{"id":27830,"date":"2020-02-03T14:10:49","date_gmt":"2020-02-03T13:10:49","guid":{"rendered":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/?p=27830"},"modified":"2020-02-04T08:22:09","modified_gmt":"2020-02-04T07:22:09","slug":"crescono-gli-infortuni-sul-lavoro-a-sud-del-lazio-uil-piu-controlli-e-piu-sanzioni","status":"publish","type":"post","link":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2020\/02\/03\/crescono-gli-infortuni-sul-lavoro-a-sud-del-lazio-uil-piu-controlli-e-piu-sanzioni\/","title":{"rendered":"Crescono gli infortuni sul lavoro a sud del Lazio. Uil: pi\u00f9 controlli e pi\u00f9 sanzioni"},"content":{"rendered":"<p>&#8220;C\u2019\u00e8 un\u2019area della nostra regione che sta diventando sempre pi\u00f9 rischiosa per i lavoratori e le lavoratrici. Quest\u2019aria \u00e8 a sud di Roma e coinvolge la provincia pontina e quella ciociara. In questa zona pi\u00f9 che altrove si sono registrate infatti le crescite percentuali pi\u00f9 elevate di infortuni sul lavoro e di malattie professionali&#8221;.<\/p>\n<h2>I numeri aumentano<\/h2>\n<p>Lo dicono in una nota congiunta <strong>Luigi Garullo e Anita Tarquini<\/strong>, rispettivamente <strong>segretari della Uil di Latina e della Uil di Frosinone<\/strong>, commentando i dati dell\u2019Inail elaborati nel 2019: rispetto al 2018 in Ciociaria gli infortuni sul lavoro<strong> sono aumentati dell\u20191,6 per cento<\/strong> (44 in pi\u00f9) pari a 2.715 mentre le malattie professionali hanno toccato quota 801 con una variazione del pi\u00f9 7,1 per cento (erano state 748 nel 2018).<\/p>\n<h2>I segretari sul mancato rispetto delle norme<\/h2>\n<p>&#8220;Cifre che fanno tremare i polsi \u2013 dicono gli esponenti della Uil \u2013 In tutto il territorio laziale nell&#8217;ultimo anno sono stati quasi 45 mila gli infortuni sul lavoro. E se la maggior parte sono avvenuti a Roma e nel suo hinterland \u2013 dato prevedibile, visto le dimensioni della citt\u00e0, della sua provincia e della forza lavoro \u2013 Gli incrementi che abbiamo rilevato nelle nostre aree confermano che per quanto riguarda il lavoro, la sua sicurezza, c\u2019\u00e8 un capitolo che deve essere aggiornato, perch\u00e9 il mancato rispetto delle regole si traduce in una violazione della libert\u00e0 per lavoratori e lavoratrici e in un aumento del rischio di perdere la vita&#8221;.<\/p>\n<p>&nbsp;<\/p>\n<figure id=\"attachment_22648\" aria-describedby=\"caption-attachment-22648\" style=\"width: 620px\" class=\"wp-caption aligncenter\"><img loading=\"lazy\" decoding=\"async\" class=\"wp-image-22648 size-full\" src=\"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2019\/11\/anita-tarquini-uil.jpg\" alt=\"anita tarquini il corriere della provincia\" width=\"620\" height=\"426\" srcset=\"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2019\/11\/anita-tarquini-uil.jpg 620w, https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2019\/11\/anita-tarquini-uil-300x206.jpg 300w, https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2019\/11\/anita-tarquini-uil-500x344.jpg 500w, https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2019\/11\/anita-tarquini-uil-130x90.jpg 130w\" sizes=\"auto, (max-width: 620px) 100vw, 620px\" \/><figcaption id=\"caption-attachment-22648\" class=\"wp-caption-text\">La segretaria territoriale della Uil Frosinone Anita Tarquini<\/figcaption><\/figure>\n<p>&nbsp;<\/p>\n<h2>Pi\u00f9 sanzioni ma meccanismi premianti per aziende virtuose<\/h2>\n<p>Sia Tarquini che Garullo sottolineano la necessit\u00e0 di &#8220;pi\u00f9 regole e controlli, pi\u00f9 sanzioni, meccanismi premianti per le aziende virtuose \u2013 concludono \u2013 perch\u00e9 nell\u2019anno appena concluso ha posto la provincia di Latina in prima posizione in termini di lutti e vite spezzate, passando infatti gli infortuni mortali da 8 nel 2018 a 14, con un indice pari a 3,7 ogni 100 mila infortuni denunciati (erano stati 2,2 l\u2019anno precedente), sottraendo cos\u00ec il primato a Rieti che fino al 2018 aveva occupato il primo posto di questa livida graduatoria e che invece ora scivola in quarta posizione. Frosinone invece \u00e8 terza, con un indice di mortalit\u00e0 pari a 2,9 pressoch\u00e9 invariato rispetto all\u2019anno precedente, in presenza di un analogo numero di vittime, pari a 8 unit\u00e0\u201d.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>&#8220;C\u2019\u00e8 un\u2019area della nostra regione che sta diventando sempre pi\u00f9 rischiosa per i lavoratori e le lavoratrici. Quest\u2019aria \u00e8 a<\/p>\n","protected":false},"author":18,"featured_media":27834,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[4,41,17],"tags":[3936,94,6743,93,8414,2481,279,8413,6007,871],"class_list":["post-27830","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-primo-piano","category-slide","category-lavoro","tag-anita-tarquini","tag-ciociaria","tag-decessi","tag-frosinone","tag-inail","tag-infortuni","tag-lavoro","tag-malattie-professionali","tag-morti-bianche","tag-uil"],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v27.8 (Yoast SEO v27.8) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Crescono gli infortuni sul lavoro a sud del Lazio. Uil: pi\u00f9 controlli e pi\u00f9 sanzioni - IlCorriereDellaProvincia.it - News h24 e notizie di approfondimento<\/title>\n<meta name=\"description\" content=\"Crescono gli infortuni sul lavoro in Ciociaria: lo evidenzia la segretaria provinciale Uil Anita Tarquini sulla base dei dati elaborati dall&#039;Inail\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2020\/02\/03\/crescono-gli-infortuni-sul-lavoro-a-sud-del-lazio-uil-piu-controlli-e-piu-sanzioni\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Crescono gli infortuni sul lavoro a sud del Lazio. Uil: pi\u00f9 controlli e pi\u00f9 sanzioni\" \/>\n<meta property=\"og:description\" content=\"Crescono gli infortuni sul lavoro in Ciociaria: lo evidenzia la segretaria provinciale Uil Anita Tarquini sulla base dei dati elaborati dall&#039;Inail\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2020\/02\/03\/crescono-gli-infortuni-sul-lavoro-a-sud-del-lazio-uil-piu-controlli-e-piu-sanzioni\/\" \/>\n<meta property=\"og:site_name\" content=\"IlCorriereDellaProvincia.it - News h24 e notizie di approfondimento\" \/>\n<meta property=\"article:author\" content=\"www.facebook.com\/tunews24\" \/>\n<meta property=\"article:published_time\" content=\"2020-02-03T13:10:49+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2020-02-04T07:22:09+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2020\/02\/infortunio-sul-lavoro-e1580735355360.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"632\" \/>\n\t<meta property=\"og:image:height\" content=\"409\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Redazione\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"Redazione\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minuti\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2020\\\/02\\\/03\\\/crescono-gli-infortuni-sul-lavoro-a-sud-del-lazio-uil-piu-controlli-e-piu-sanzioni\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2020\\\/02\\\/03\\\/crescono-gli-infortuni-sul-lavoro-a-sud-del-lazio-uil-piu-controlli-e-piu-sanzioni\\\/\"},\"author\":{\"name\":\"Redazione\",\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/#\\\/schema\\\/person\\\/6d7f0a9120d0c03d0c552e9fdf49ed7d\"},\"headline\":\"Crescono gli infortuni sul lavoro a sud del Lazio. Uil: pi\u00f9 controlli e pi\u00f9 sanzioni\",\"datePublished\":\"2020-02-03T13:10:49+00:00\",\"dateModified\":\"2020-02-04T07:22:09+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2020\\\/02\\\/03\\\/crescono-gli-infortuni-sul-lavoro-a-sud-del-lazio-uil-piu-controlli-e-piu-sanzioni\\\/\"},\"wordCount\":391,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2020\\\/02\\\/03\\\/crescono-gli-infortuni-sul-lavoro-a-sud-del-lazio-uil-piu-controlli-e-piu-sanzioni\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2020\\\/02\\\/infortunio-sul-lavoro-e1580735355360.jpg\",\"keywords\":[\"anita tarquini\",\"Ciociaria\",\"decessi\",\"Frosinone\",\"inail\",\"infortuni\",\"lavoro\",\"malattie professionali\",\"morti bianche\",\"Uil\"],\"articleSection\":[\"*PRIMO PIANO*\",\"*SLIDE*\",\"Lavoro\"],\"inLanguage\":\"it-IT\",\"copyrightYear\":\"2020\",\"copyrightHolder\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/#organization\"}},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2020\\\/02\\\/03\\\/crescono-gli-infortuni-sul-lavoro-a-sud-del-lazio-uil-piu-controlli-e-piu-sanzioni\\\/\",\"url\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2020\\\/02\\\/03\\\/crescono-gli-infortuni-sul-lavoro-a-sud-del-lazio-uil-piu-controlli-e-piu-sanzioni\\\/\",\"name\":\"Crescono gli infortuni sul lavoro a sud del Lazio. Uil: pi\u00f9 controlli e pi\u00f9 sanzioni - IlCorriereDellaProvincia.it - News h24 e notizie di approfondimento\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2020\\\/02\\\/03\\\/crescono-gli-infortuni-sul-lavoro-a-sud-del-lazio-uil-piu-controlli-e-piu-sanzioni\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2020\\\/02\\\/03\\\/crescono-gli-infortuni-sul-lavoro-a-sud-del-lazio-uil-piu-controlli-e-piu-sanzioni\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2020\\\/02\\\/infortunio-sul-lavoro-e1580735355360.jpg\",\"datePublished\":\"2020-02-03T13:10:49+00:00\",\"dateModified\":\"2020-02-04T07:22:09+00:00\",\"description\":\"Crescono gli infortuni sul lavoro in Ciociaria: lo evidenzia la segretaria provinciale Uil Anita Tarquini sulla base dei dati elaborati dall'Inail\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2020\\\/02\\\/03\\\/crescono-gli-infortuni-sul-lavoro-a-sud-del-lazio-uil-piu-controlli-e-piu-sanzioni\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2020\\\/02\\\/03\\\/crescono-gli-infortuni-sul-lavoro-a-sud-del-lazio-uil-piu-controlli-e-piu-sanzioni\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2020\\\/02\\\/03\\\/crescono-gli-infortuni-sul-lavoro-a-sud-del-lazio-uil-piu-controlli-e-piu-sanzioni\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2020\\\/02\\\/infortunio-sul-lavoro-e1580735355360.jpg\",\"contentUrl\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2020\\\/02\\\/infortunio-sul-lavoro-e1580735355360.jpg\",\"width\":632,\"height\":409,\"caption\":\"Infortunio sul lavoro\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2020\\\/02\\\/03\\\/crescono-gli-infortuni-sul-lavoro-a-sud-del-lazio-uil-piu-controlli-e-piu-sanzioni\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Crescono gli infortuni sul lavoro a sud del Lazio. Uil: pi\u00f9 controlli e pi\u00f9 sanzioni\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/#website\",\"url\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/\",\"name\":\"Il Corriere Delle Provincia\",\"description\":\"IlCorriereDellaProvincia.it, quotidiano web di politica, cronaca, inchiesta, lavoro, scuola, turismo, cultura e spettacolo, economia e finanza, salute e benessere. Approfondimenti e notizie aggiornate con foto e video della provincia di Frosinone ma anche news nazionali, dell\u2019Italia e del Mondo.\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":[\"Organization\",\"Place\"],\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/#organization\",\"name\":\"Globalpress s.r.l.\",\"url\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/\",\"logo\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2020\\\/02\\\/03\\\/crescono-gli-infortuni-sul-lavoro-a-sud-del-lazio-uil-piu-controlli-e-piu-sanzioni\\\/#local-main-organization-logo\"},\"image\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2020\\\/02\\\/03\\\/crescono-gli-infortuni-sul-lavoro-a-sud-del-lazio-uil-piu-controlli-e-piu-sanzioni\\\/#local-main-organization-logo\"},\"telephone\":[],\"openingHoursSpecification\":[{\"@type\":\"OpeningHoursSpecification\",\"dayOfWeek\":[\"Monday\",\"Tuesday\",\"Wednesday\",\"Thursday\",\"Friday\",\"Saturday\",\"Sunday\"],\"opens\":\"09:00\",\"closes\":\"17:00\"}]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/#\\\/schema\\\/person\\\/6d7f0a9120d0c03d0c552e9fdf49ed7d\",\"name\":\"Redazione\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/a40eeacccdcad861f831dde73317f63a542e738f0dc4b79b9f47062d3d4bd1d2?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/a40eeacccdcad861f831dde73317f63a542e738f0dc4b79b9f47062d3d4bd1d2?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/a40eeacccdcad861f831dde73317f63a542e738f0dc4b79b9f47062d3d4bd1d2?s=96&d=mm&r=g\",\"caption\":\"Redazione\"},\"description\":\"SEGUICI ANCHE SUI SOCIAL Facebook: TuNews24 e TuSport24 Instagram: TuNews24 e TuSport24 Youtube: TuNews24 Telegram: TuNews24 Puoi leggerci anche in formato cartaceo: il settimanale viene pubblicato e distribuito gratuitamente ogni venerd\u00ec in edicole, bar, centri commerciali e svariati esercizi. Ma \u00e8 possibile anche sfogliarlo comodamente online, cliccando su TU NEWS sfogliabile TU NEWS, PASSIONE PER L\u2019INFORMAZIONE\",\"sameAs\":[\"http:\\\/\\\/www.tunews24.it\",\"www.facebook.com\\\/tunews24\"],\"url\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/author\\\/senzafirma\\\/\"},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2020\\\/02\\\/03\\\/crescono-gli-infortuni-sul-lavoro-a-sud-del-lazio-uil-piu-controlli-e-piu-sanzioni\\\/#local-main-organization-logo\",\"url\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2022\\\/11\\\/cropped-il-corriere-della-provincia-testata-web-scontornata.png\",\"contentUrl\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2022\\\/11\\\/cropped-il-corriere-della-provincia-testata-web-scontornata.png\",\"width\":2911,\"height\":717,\"caption\":\"Globalpress s.r.l.\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Crescono gli infortuni sul lavoro a sud del Lazio. Uil: pi\u00f9 controlli e pi\u00f9 sanzioni - IlCorriereDellaProvincia.it - News h24 e notizie di approfondimento","description":"Crescono gli infortuni sul lavoro in Ciociaria: lo evidenzia la segretaria provinciale Uil Anita Tarquini sulla base dei dati elaborati dall'Inail","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2020\/02\/03\/crescono-gli-infortuni-sul-lavoro-a-sud-del-lazio-uil-piu-controlli-e-piu-sanzioni\/","og_locale":"it_IT","og_type":"article","og_title":"Crescono gli infortuni sul lavoro a sud del Lazio. Uil: pi\u00f9 controlli e pi\u00f9 sanzioni","og_description":"Crescono gli infortuni sul lavoro in Ciociaria: lo evidenzia la segretaria provinciale Uil Anita Tarquini sulla base dei dati elaborati dall'Inail","og_url":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2020\/02\/03\/crescono-gli-infortuni-sul-lavoro-a-sud-del-lazio-uil-piu-controlli-e-piu-sanzioni\/","og_site_name":"IlCorriereDellaProvincia.it - News h24 e notizie di approfondimento","article_author":"www.facebook.com\/tunews24","article_published_time":"2020-02-03T13:10:49+00:00","article_modified_time":"2020-02-04T07:22:09+00:00","og_image":[{"width":632,"height":409,"url":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2020\/02\/infortunio-sul-lavoro-e1580735355360.jpg","type":"image\/jpeg"}],"author":"Redazione","twitter_card":"summary_large_image","twitter_misc":{"Scritto da":"Redazione","Tempo di lettura stimato":"2 minuti"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2020\/02\/03\/crescono-gli-infortuni-sul-lavoro-a-sud-del-lazio-uil-piu-controlli-e-piu-sanzioni\/#article","isPartOf":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2020\/02\/03\/crescono-gli-infortuni-sul-lavoro-a-sud-del-lazio-uil-piu-controlli-e-piu-sanzioni\/"},"author":{"name":"Redazione","@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/#\/schema\/person\/6d7f0a9120d0c03d0c552e9fdf49ed7d"},"headline":"Crescono gli infortuni sul lavoro a sud del Lazio. Uil: pi\u00f9 controlli e pi\u00f9 sanzioni","datePublished":"2020-02-03T13:10:49+00:00","dateModified":"2020-02-04T07:22:09+00:00","mainEntityOfPage":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2020\/02\/03\/crescono-gli-infortuni-sul-lavoro-a-sud-del-lazio-uil-piu-controlli-e-piu-sanzioni\/"},"wordCount":391,"commentCount":0,"publisher":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/#organization"},"image":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2020\/02\/03\/crescono-gli-infortuni-sul-lavoro-a-sud-del-lazio-uil-piu-controlli-e-piu-sanzioni\/#primaryimage"},"thumbnailUrl":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2020\/02\/infortunio-sul-lavoro-e1580735355360.jpg","keywords":["anita tarquini","Ciociaria","decessi","Frosinone","inail","infortuni","lavoro","malattie professionali","morti bianche","Uil"],"articleSection":["*PRIMO PIANO*","*SLIDE*","Lavoro"],"inLanguage":"it-IT","copyrightYear":"2020","copyrightHolder":{"@id":"https:\/\/www.tunews24.it\/#organization"}},{"@type":"WebPage","@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2020\/02\/03\/crescono-gli-infortuni-sul-lavoro-a-sud-del-lazio-uil-piu-controlli-e-piu-sanzioni\/","url":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2020\/02\/03\/crescono-gli-infortuni-sul-lavoro-a-sud-del-lazio-uil-piu-controlli-e-piu-sanzioni\/","name":"Crescono gli infortuni sul lavoro a sud del Lazio. Uil: pi\u00f9 controlli e pi\u00f9 sanzioni - IlCorriereDellaProvincia.it - News h24 e notizie di approfondimento","isPartOf":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2020\/02\/03\/crescono-gli-infortuni-sul-lavoro-a-sud-del-lazio-uil-piu-controlli-e-piu-sanzioni\/#primaryimage"},"image":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2020\/02\/03\/crescono-gli-infortuni-sul-lavoro-a-sud-del-lazio-uil-piu-controlli-e-piu-sanzioni\/#primaryimage"},"thumbnailUrl":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2020\/02\/infortunio-sul-lavoro-e1580735355360.jpg","datePublished":"2020-02-03T13:10:49+00:00","dateModified":"2020-02-04T07:22:09+00:00","description":"Crescono gli infortuni sul lavoro in Ciociaria: lo evidenzia la segretaria provinciale Uil Anita Tarquini sulla base dei dati elaborati dall'Inail","breadcrumb":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2020\/02\/03\/crescono-gli-infortuni-sul-lavoro-a-sud-del-lazio-uil-piu-controlli-e-piu-sanzioni\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2020\/02\/03\/crescono-gli-infortuni-sul-lavoro-a-sud-del-lazio-uil-piu-controlli-e-piu-sanzioni\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2020\/02\/03\/crescono-gli-infortuni-sul-lavoro-a-sud-del-lazio-uil-piu-controlli-e-piu-sanzioni\/#primaryimage","url":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2020\/02\/infortunio-sul-lavoro-e1580735355360.jpg","contentUrl":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2020\/02\/infortunio-sul-lavoro-e1580735355360.jpg","width":632,"height":409,"caption":"Infortunio sul lavoro"},{"@type":"BreadcrumbList","@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2020\/02\/03\/crescono-gli-infortuni-sul-lavoro-a-sud-del-lazio-uil-piu-controlli-e-piu-sanzioni\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/"},{"@type":"ListItem","position":2,"name":"Crescono gli infortuni sul lavoro a sud del Lazio. Uil: pi\u00f9 controlli e pi\u00f9 sanzioni"}]},{"@type":"WebSite","@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/#website","url":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/","name":"Il Corriere Delle Provincia","description":"IlCorriereDellaProvincia.it, quotidiano web di politica, cronaca, inchiesta, lavoro, scuola, turismo, cultura e spettacolo, economia e finanza, salute e benessere. Approfondimenti e notizie aggiornate con foto e video della provincia di Frosinone ma anche news nazionali, dell\u2019Italia e del Mondo.","publisher":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":["Organization","Place"],"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/#organization","name":"Globalpress s.r.l.","url":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/","logo":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2020\/02\/03\/crescono-gli-infortuni-sul-lavoro-a-sud-del-lazio-uil-piu-controlli-e-piu-sanzioni\/#local-main-organization-logo"},"image":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2020\/02\/03\/crescono-gli-infortuni-sul-lavoro-a-sud-del-lazio-uil-piu-controlli-e-piu-sanzioni\/#local-main-organization-logo"},"telephone":[],"openingHoursSpecification":[{"@type":"OpeningHoursSpecification","dayOfWeek":["Monday","Tuesday","Wednesday","Thursday","Friday","Saturday","Sunday"],"opens":"09:00","closes":"17:00"}]},{"@type":"Person","@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/#\/schema\/person\/6d7f0a9120d0c03d0c552e9fdf49ed7d","name":"Redazione","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/secure.gravatar.com\/avatar\/a40eeacccdcad861f831dde73317f63a542e738f0dc4b79b9f47062d3d4bd1d2?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/a40eeacccdcad861f831dde73317f63a542e738f0dc4b79b9f47062d3d4bd1d2?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/a40eeacccdcad861f831dde73317f63a542e738f0dc4b79b9f47062d3d4bd1d2?s=96&d=mm&r=g","caption":"Redazione"},"description":"SEGUICI ANCHE SUI SOCIAL Facebook: TuNews24 e TuSport24 Instagram: TuNews24 e TuSport24 Youtube: TuNews24 Telegram: TuNews24 Puoi leggerci anche in formato cartaceo: il settimanale viene pubblicato e distribuito gratuitamente ogni venerd\u00ec in edicole, bar, centri commerciali e svariati esercizi. Ma \u00e8 possibile anche sfogliarlo comodamente online, cliccando su TU NEWS sfogliabile TU NEWS, PASSIONE PER L\u2019INFORMAZIONE","sameAs":["http:\/\/www.tunews24.it","www.facebook.com\/tunews24"],"url":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/author\/senzafirma\/"},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2020\/02\/03\/crescono-gli-infortuni-sul-lavoro-a-sud-del-lazio-uil-piu-controlli-e-piu-sanzioni\/#local-main-organization-logo","url":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2022\/11\/cropped-il-corriere-della-provincia-testata-web-scontornata.png","contentUrl":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2022\/11\/cropped-il-corriere-della-provincia-testata-web-scontornata.png","width":2911,"height":717,"caption":"Globalpress s.r.l."}]}},"_links":{"self":[{"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/posts\/27830","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/users\/18"}],"replies":[{"embeddable":true,"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/comments?post=27830"}],"version-history":[{"count":1,"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/posts\/27830\/revisions"}],"predecessor-version":[{"id":27836,"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/posts\/27830\/revisions\/27836"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/media\/27834"}],"wp:attachment":[{"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/media?parent=27830"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/categories?post=27830"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/tags?post=27830"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}