{"id":2781,"date":"2018-12-06T12:02:44","date_gmt":"2018-12-06T11:02:44","guid":{"rendered":"http:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/?p=2781"},"modified":"2018-12-06T16:30:07","modified_gmt":"2018-12-06T15:30:07","slug":"decreto-concretezza-il-no-del-senatore-ruspandini-allulteriore-burocrazia-per-comuni","status":"publish","type":"post","link":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2018\/12\/06\/decreto-concretezza-il-no-del-senatore-ruspandini-allulteriore-burocrazia-per-comuni\/","title":{"rendered":"Decreto concretezza, Ruspandini: no all&#8217;ulteriore burocrazia per i Comuni"},"content":{"rendered":"<div id=\"m_6693103366937802992mail-app-auto-signature\">\n<p dir=\"ltr\">&#8220;Siamo molto preoccupati per questo disegno di legge perch\u00e9 riteniamo che le ricadute sugli enti locali siano davvero nefaste&#8221;. Cos\u00ec il senatore di Fratelli d\u2019Italia <strong>Massimo Ruspandini<\/strong> intervenuto in aula sul<strong> decreto concretezza.<\/strong> &#8220;L\u2019Italia \u00e8 la Nazione dei mille campanili, delle mille diversit\u00e0 che si articolano, si consolidano e crescono intorno ai nostri meravigliosi comuni ed \u00e8 per questo che siamo al fianco dei sindaci e di tutti gli amministratori locali.<\/p>\n<p dir=\"ltr\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter wp-image-2785 size-full\" src=\"http:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2018\/12\/Senato_aula.jpg\" alt=\"senato il corriere della provincia frosinone ciociaria\" width=\"810\" height=\"540\" srcset=\"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2018\/12\/Senato_aula.jpg 810w, https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2018\/12\/Senato_aula-300x200.jpg 300w, https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2018\/12\/Senato_aula-768x512.jpg 768w, https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2018\/12\/Senato_aula-500x333.jpg 500w, https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2018\/12\/Senato_aula-272x182.jpg 272w\" sizes=\"auto, (max-width: 810px) 100vw, 810px\" \/><\/p>\n<p dir=\"ltr\">&#8220;Non si pu\u00f2 continuare &#8211; spiega il senatore FDI &#8211; ad affliggere i Comuni con altra burocrazia. \u00c8 necessario andare nella direzione opposta cercando di sburocratizzare il pi\u00f9 possibile i nostri enti locali, sottoposti quotidianamente a continue vessazioni che gravano fortissimamente sui bilanci comunali. Avremmo bisogno di ricambio generazionale nella pubblica amministrazione non di altra burocrazia&#8221;, conclude il senatore Ruspandini.<\/p>\n<\/div>\n<div id=\"m_6693103366937802992mail-app-auto-signature\">\n<p dir=\"ltr\">\n<\/div>\n","protected":false},"excerpt":{"rendered":"<p>&#8220;Siamo molto preoccupati per questo disegno di legge perch\u00e9 riteniamo che le ricadute sugli enti locali siano davvero nefaste&#8221;. Cos\u00ec<\/p>\n","protected":false},"author":18,"featured_media":2782,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[28],"tags":[1010,1012,1011],"class_list":["post-2781","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-politica","tag-decreto-concretezza","tag-fratelli-ditalia","tag-senatore-ruspandini"],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v27.8 (Yoast SEO v27.8) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Decreto concretezza, Ruspandini: no all&#039;ulteriore burocrazia per i Comuni - IlCorriereDellaProvincia.it - News h24 e notizie di approfondimento<\/title>\n<meta name=\"description\" content=\"&quot;Siamo molto preoccupati per questo disegno di legge perch\u00e9 riteniamo che le ricadute sugli enti locali siano davvero nefaste&quot;\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2018\/12\/06\/decreto-concretezza-il-no-del-senatore-ruspandini-allulteriore-burocrazia-per-comuni\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Decreto concretezza, Ruspandini: no all&#039;ulteriore burocrazia per i Comuni\" \/>\n<meta property=\"og:description\" content=\"&quot;Siamo molto preoccupati per questo disegno di legge perch\u00e9 riteniamo che le ricadute sugli enti locali siano davvero nefaste&quot;\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2018\/12\/06\/decreto-concretezza-il-no-del-senatore-ruspandini-allulteriore-burocrazia-per-comuni\/\" \/>\n<meta property=\"og:site_name\" content=\"IlCorriereDellaProvincia.it - News h24 e notizie di approfondimento\" \/>\n<meta property=\"article:author\" content=\"www.facebook.com\/tunews24\" \/>\n<meta property=\"article:published_time\" content=\"2018-12-06T11:02:44+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2018-12-06T15:30:07+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2018\/12\/Massimo-Ruspandini.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"670\" \/>\n\t<meta property=\"og:image:height\" content=\"400\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Redazione\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"Redazione\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2018\\\/12\\\/06\\\/decreto-concretezza-il-no-del-senatore-ruspandini-allulteriore-burocrazia-per-comuni\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2018\\\/12\\\/06\\\/decreto-concretezza-il-no-del-senatore-ruspandini-allulteriore-burocrazia-per-comuni\\\/\"},\"author\":{\"name\":\"Redazione\",\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/#\\\/schema\\\/person\\\/6d7f0a9120d0c03d0c552e9fdf49ed7d\"},\"headline\":\"Decreto concretezza, Ruspandini: no all&#8217;ulteriore burocrazia per i Comuni\",\"datePublished\":\"2018-12-06T11:02:44+00:00\",\"dateModified\":\"2018-12-06T15:30:07+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2018\\\/12\\\/06\\\/decreto-concretezza-il-no-del-senatore-ruspandini-allulteriore-burocrazia-per-comuni\\\/\"},\"wordCount\":140,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2018\\\/12\\\/06\\\/decreto-concretezza-il-no-del-senatore-ruspandini-allulteriore-burocrazia-per-comuni\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2018\\\/12\\\/Massimo-Ruspandini.jpg\",\"keywords\":[\"Decreto Concretezza\",\"Fratelli d'Italia\",\"Senatore Ruspandini\"],\"articleSection\":[\"Evidenza\"],\"inLanguage\":\"it-IT\",\"copyrightYear\":\"2018\",\"copyrightHolder\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/#organization\"}},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2018\\\/12\\\/06\\\/decreto-concretezza-il-no-del-senatore-ruspandini-allulteriore-burocrazia-per-comuni\\\/\",\"url\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2018\\\/12\\\/06\\\/decreto-concretezza-il-no-del-senatore-ruspandini-allulteriore-burocrazia-per-comuni\\\/\",\"name\":\"Decreto concretezza, Ruspandini: no all'ulteriore burocrazia per i Comuni - IlCorriereDellaProvincia.it - News h24 e notizie di approfondimento\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2018\\\/12\\\/06\\\/decreto-concretezza-il-no-del-senatore-ruspandini-allulteriore-burocrazia-per-comuni\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2018\\\/12\\\/06\\\/decreto-concretezza-il-no-del-senatore-ruspandini-allulteriore-burocrazia-per-comuni\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2018\\\/12\\\/Massimo-Ruspandini.jpg\",\"datePublished\":\"2018-12-06T11:02:44+00:00\",\"dateModified\":\"2018-12-06T15:30:07+00:00\",\"description\":\"\\\"Siamo molto preoccupati per questo disegno di legge perch\u00e9 riteniamo che le ricadute sugli enti locali siano davvero nefaste\\\"\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2018\\\/12\\\/06\\\/decreto-concretezza-il-no-del-senatore-ruspandini-allulteriore-burocrazia-per-comuni\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2018\\\/12\\\/06\\\/decreto-concretezza-il-no-del-senatore-ruspandini-allulteriore-burocrazia-per-comuni\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2018\\\/12\\\/06\\\/decreto-concretezza-il-no-del-senatore-ruspandini-allulteriore-burocrazia-per-comuni\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2018\\\/12\\\/Massimo-Ruspandini.jpg\",\"contentUrl\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2018\\\/12\\\/Massimo-Ruspandini.jpg\",\"width\":670,\"height\":400,\"caption\":\"Il senatore Massimo Ruspandini in Senato\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2018\\\/12\\\/06\\\/decreto-concretezza-il-no-del-senatore-ruspandini-allulteriore-burocrazia-per-comuni\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Decreto concretezza, Ruspandini: no all&#8217;ulteriore burocrazia per i Comuni\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/#website\",\"url\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/\",\"name\":\"Il Corriere Delle Provincia\",\"description\":\"IlCorriereDellaProvincia.it, quotidiano web di politica, cronaca, inchiesta, lavoro, scuola, turismo, cultura e spettacolo, economia e finanza, salute e benessere. Approfondimenti e notizie aggiornate con foto e video della provincia di Frosinone ma anche news nazionali, dell\u2019Italia e del Mondo.\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":[\"Organization\",\"Place\"],\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/#organization\",\"name\":\"Globalpress s.r.l.\",\"url\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/\",\"logo\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2018\\\/12\\\/06\\\/decreto-concretezza-il-no-del-senatore-ruspandini-allulteriore-burocrazia-per-comuni\\\/#local-main-organization-logo\"},\"image\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2018\\\/12\\\/06\\\/decreto-concretezza-il-no-del-senatore-ruspandini-allulteriore-burocrazia-per-comuni\\\/#local-main-organization-logo\"},\"telephone\":[],\"openingHoursSpecification\":[{\"@type\":\"OpeningHoursSpecification\",\"dayOfWeek\":[\"Monday\",\"Tuesday\",\"Wednesday\",\"Thursday\",\"Friday\",\"Saturday\",\"Sunday\"],\"opens\":\"09:00\",\"closes\":\"17:00\"}]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/#\\\/schema\\\/person\\\/6d7f0a9120d0c03d0c552e9fdf49ed7d\",\"name\":\"Redazione\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/a40eeacccdcad861f831dde73317f63a542e738f0dc4b79b9f47062d3d4bd1d2?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/a40eeacccdcad861f831dde73317f63a542e738f0dc4b79b9f47062d3d4bd1d2?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/a40eeacccdcad861f831dde73317f63a542e738f0dc4b79b9f47062d3d4bd1d2?s=96&d=mm&r=g\",\"caption\":\"Redazione\"},\"description\":\"SEGUICI ANCHE SUI SOCIAL Facebook: TuNews24 e TuSport24 Instagram: TuNews24 e TuSport24 Youtube: TuNews24 Telegram: TuNews24 Puoi leggerci anche in formato cartaceo: il settimanale viene pubblicato e distribuito gratuitamente ogni venerd\u00ec in edicole, bar, centri commerciali e svariati esercizi. Ma \u00e8 possibile anche sfogliarlo comodamente online, cliccando su TU NEWS sfogliabile TU NEWS, PASSIONE PER L\u2019INFORMAZIONE\",\"sameAs\":[\"http:\\\/\\\/www.tunews24.it\",\"www.facebook.com\\\/tunews24\"],\"url\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/author\\\/senzafirma\\\/\"},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2018\\\/12\\\/06\\\/decreto-concretezza-il-no-del-senatore-ruspandini-allulteriore-burocrazia-per-comuni\\\/#local-main-organization-logo\",\"url\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2022\\\/11\\\/cropped-il-corriere-della-provincia-testata-web-scontornata.png\",\"contentUrl\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2022\\\/11\\\/cropped-il-corriere-della-provincia-testata-web-scontornata.png\",\"width\":2911,\"height\":717,\"caption\":\"Globalpress s.r.l.\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Decreto concretezza, Ruspandini: no all'ulteriore burocrazia per i Comuni - IlCorriereDellaProvincia.it - News h24 e notizie di approfondimento","description":"\"Siamo molto preoccupati per questo disegno di legge perch\u00e9 riteniamo che le ricadute sugli enti locali siano davvero nefaste\"","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2018\/12\/06\/decreto-concretezza-il-no-del-senatore-ruspandini-allulteriore-burocrazia-per-comuni\/","og_locale":"it_IT","og_type":"article","og_title":"Decreto concretezza, Ruspandini: no all'ulteriore burocrazia per i Comuni","og_description":"\"Siamo molto preoccupati per questo disegno di legge perch\u00e9 riteniamo che le ricadute sugli enti locali siano davvero nefaste\"","og_url":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2018\/12\/06\/decreto-concretezza-il-no-del-senatore-ruspandini-allulteriore-burocrazia-per-comuni\/","og_site_name":"IlCorriereDellaProvincia.it - News h24 e notizie di approfondimento","article_author":"www.facebook.com\/tunews24","article_published_time":"2018-12-06T11:02:44+00:00","article_modified_time":"2018-12-06T15:30:07+00:00","og_image":[{"width":670,"height":400,"url":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2018\/12\/Massimo-Ruspandini.jpg","type":"image\/jpeg"}],"author":"Redazione","twitter_card":"summary_large_image","twitter_misc":{"Scritto da":"Redazione","Tempo di lettura stimato":"1 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2018\/12\/06\/decreto-concretezza-il-no-del-senatore-ruspandini-allulteriore-burocrazia-per-comuni\/#article","isPartOf":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2018\/12\/06\/decreto-concretezza-il-no-del-senatore-ruspandini-allulteriore-burocrazia-per-comuni\/"},"author":{"name":"Redazione","@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/#\/schema\/person\/6d7f0a9120d0c03d0c552e9fdf49ed7d"},"headline":"Decreto concretezza, Ruspandini: no all&#8217;ulteriore burocrazia per i Comuni","datePublished":"2018-12-06T11:02:44+00:00","dateModified":"2018-12-06T15:30:07+00:00","mainEntityOfPage":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2018\/12\/06\/decreto-concretezza-il-no-del-senatore-ruspandini-allulteriore-burocrazia-per-comuni\/"},"wordCount":140,"commentCount":0,"publisher":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/#organization"},"image":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2018\/12\/06\/decreto-concretezza-il-no-del-senatore-ruspandini-allulteriore-burocrazia-per-comuni\/#primaryimage"},"thumbnailUrl":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2018\/12\/Massimo-Ruspandini.jpg","keywords":["Decreto Concretezza","Fratelli d'Italia","Senatore Ruspandini"],"articleSection":["Evidenza"],"inLanguage":"it-IT","copyrightYear":"2018","copyrightHolder":{"@id":"https:\/\/www.tunews24.it\/#organization"}},{"@type":"WebPage","@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2018\/12\/06\/decreto-concretezza-il-no-del-senatore-ruspandini-allulteriore-burocrazia-per-comuni\/","url":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2018\/12\/06\/decreto-concretezza-il-no-del-senatore-ruspandini-allulteriore-burocrazia-per-comuni\/","name":"Decreto concretezza, Ruspandini: no all'ulteriore burocrazia per i Comuni - IlCorriereDellaProvincia.it - News h24 e notizie di approfondimento","isPartOf":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2018\/12\/06\/decreto-concretezza-il-no-del-senatore-ruspandini-allulteriore-burocrazia-per-comuni\/#primaryimage"},"image":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2018\/12\/06\/decreto-concretezza-il-no-del-senatore-ruspandini-allulteriore-burocrazia-per-comuni\/#primaryimage"},"thumbnailUrl":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2018\/12\/Massimo-Ruspandini.jpg","datePublished":"2018-12-06T11:02:44+00:00","dateModified":"2018-12-06T15:30:07+00:00","description":"\"Siamo molto preoccupati per questo disegno di legge perch\u00e9 riteniamo che le ricadute sugli enti locali siano davvero nefaste\"","breadcrumb":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2018\/12\/06\/decreto-concretezza-il-no-del-senatore-ruspandini-allulteriore-burocrazia-per-comuni\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2018\/12\/06\/decreto-concretezza-il-no-del-senatore-ruspandini-allulteriore-burocrazia-per-comuni\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2018\/12\/06\/decreto-concretezza-il-no-del-senatore-ruspandini-allulteriore-burocrazia-per-comuni\/#primaryimage","url":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2018\/12\/Massimo-Ruspandini.jpg","contentUrl":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2018\/12\/Massimo-Ruspandini.jpg","width":670,"height":400,"caption":"Il senatore Massimo Ruspandini in Senato"},{"@type":"BreadcrumbList","@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2018\/12\/06\/decreto-concretezza-il-no-del-senatore-ruspandini-allulteriore-burocrazia-per-comuni\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/"},{"@type":"ListItem","position":2,"name":"Decreto concretezza, Ruspandini: no all&#8217;ulteriore burocrazia per i Comuni"}]},{"@type":"WebSite","@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/#website","url":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/","name":"Il Corriere Delle Provincia","description":"IlCorriereDellaProvincia.it, quotidiano web di politica, cronaca, inchiesta, lavoro, scuola, turismo, cultura e spettacolo, economia e finanza, salute e benessere. Approfondimenti e notizie aggiornate con foto e video della provincia di Frosinone ma anche news nazionali, dell\u2019Italia e del Mondo.","publisher":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":["Organization","Place"],"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/#organization","name":"Globalpress s.r.l.","url":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/","logo":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2018\/12\/06\/decreto-concretezza-il-no-del-senatore-ruspandini-allulteriore-burocrazia-per-comuni\/#local-main-organization-logo"},"image":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2018\/12\/06\/decreto-concretezza-il-no-del-senatore-ruspandini-allulteriore-burocrazia-per-comuni\/#local-main-organization-logo"},"telephone":[],"openingHoursSpecification":[{"@type":"OpeningHoursSpecification","dayOfWeek":["Monday","Tuesday","Wednesday","Thursday","Friday","Saturday","Sunday"],"opens":"09:00","closes":"17:00"}]},{"@type":"Person","@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/#\/schema\/person\/6d7f0a9120d0c03d0c552e9fdf49ed7d","name":"Redazione","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/secure.gravatar.com\/avatar\/a40eeacccdcad861f831dde73317f63a542e738f0dc4b79b9f47062d3d4bd1d2?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/a40eeacccdcad861f831dde73317f63a542e738f0dc4b79b9f47062d3d4bd1d2?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/a40eeacccdcad861f831dde73317f63a542e738f0dc4b79b9f47062d3d4bd1d2?s=96&d=mm&r=g","caption":"Redazione"},"description":"SEGUICI ANCHE SUI SOCIAL Facebook: TuNews24 e TuSport24 Instagram: TuNews24 e TuSport24 Youtube: TuNews24 Telegram: TuNews24 Puoi leggerci anche in formato cartaceo: il settimanale viene pubblicato e distribuito gratuitamente ogni venerd\u00ec in edicole, bar, centri commerciali e svariati esercizi. Ma \u00e8 possibile anche sfogliarlo comodamente online, cliccando su TU NEWS sfogliabile TU NEWS, PASSIONE PER L\u2019INFORMAZIONE","sameAs":["http:\/\/www.tunews24.it","www.facebook.com\/tunews24"],"url":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/author\/senzafirma\/"},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2018\/12\/06\/decreto-concretezza-il-no-del-senatore-ruspandini-allulteriore-burocrazia-per-comuni\/#local-main-organization-logo","url":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2022\/11\/cropped-il-corriere-della-provincia-testata-web-scontornata.png","contentUrl":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2022\/11\/cropped-il-corriere-della-provincia-testata-web-scontornata.png","width":2911,"height":717,"caption":"Globalpress s.r.l."}]}},"_links":{"self":[{"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/posts\/2781","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/users\/18"}],"replies":[{"embeddable":true,"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/comments?post=2781"}],"version-history":[{"count":5,"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/posts\/2781\/revisions"}],"predecessor-version":[{"id":2815,"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/posts\/2781\/revisions\/2815"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/media\/2782"}],"wp:attachment":[{"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/media?parent=2781"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/categories?post=2781"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/tags?post=2781"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}