{"id":27802,"date":"2020-02-03T12:13:41","date_gmt":"2020-02-03T11:13:41","guid":{"rendered":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/?p=27802"},"modified":"2020-02-03T16:18:00","modified_gmt":"2020-02-03T15:18:00","slug":"incarichi-legali-alloggi-erp-e-antenne-domani-in-consiglio-a-sora","status":"publish","type":"post","link":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2020\/02\/03\/incarichi-legali-alloggi-erp-e-antenne-domani-in-consiglio-a-sora\/","title":{"rendered":"Incarichi legali, alloggi Erp e antenne: domani in Consiglio a Sora"},"content":{"rendered":"<p>Tre<strong> interrogazioni targate Cinquestelle<\/strong>, una<strong> mozione per le Marocchinate<\/strong>, la <strong>vendita degli alloggi di edilizia residenziale pubblica<\/strong> e il regolamento della Polizia locale:<strong> sei punti all&#8217;ordine del giorno<\/strong> che saranno oggetto del consiglio comunale di domani a Sora.<\/p>\n<p>La seduta \u00e8 stata convocata, <strong>per le ore 17.30 di domani, 4 febbraio<\/strong>, (in prima convocazione &#8211; in caso di mancanza del numero legale, per mercoled\u00ec 5 febbraio alle ore 18.30 in seconda convocazione) dal presidente del Consiglio, Antonio Lecce. Sei gli argomenti che saranno oggetto di dibattito per l\u2019approvazione, a cominciare da un\u2019interrogazione presentata dal consigliere grillino Fabrizio Pintori, relativa a \u2018Analisi del sistema dei controlli interni degli Enti Locali \u2013 Esercizio 2017 \u2013 Relazione 2019 della Corte dei Conti\u2019.<\/p>\n<h2>Gli altri punti<\/h2>\n<p>Altre due interrogazioni, sempre dei Cinquestelle, riguardano una l\u2019installazione dell\u2019impianto per la telefonia mobile in via Croce Branca e l\u2019altra la formazione dell\u2019elenco di professionisti legali per l\u2019affidamento di incarichi di assistenza, consulenza e svolgimento del patrocinio legale.<\/p>\n<p>&nbsp;<\/p>\n<figure id=\"attachment_5481\" aria-describedby=\"caption-attachment-5481\" style=\"width: 406px\" class=\"wp-caption aligncenter\"><img loading=\"lazy\" decoding=\"async\" class=\"wp-image-5481 size-full\" src=\"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2019\/01\/fabrizio-pintori.jpg\" alt=\"fabrizio pintori movimento cinquestelle sora il corriere della provincia\" width=\"406\" height=\"373\" srcset=\"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2019\/01\/fabrizio-pintori.jpg 406w, https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2019\/01\/fabrizio-pintori-300x276.jpg 300w\" sizes=\"auto, (max-width: 406px) 100vw, 406px\" \/><figcaption id=\"caption-attachment-5481\" class=\"wp-caption-text\">Il consigliere comunale dei Cinquestelle, Fabrizio Pintori<\/figcaption><\/figure>\n<p>&nbsp;<\/p>\n<p>In discussione anche l\u2019ordine del giorno a firma delle<strong> consigliere Maria Paola D\u2019Orazio e Serena Petricca<\/strong> riguardante l\u2019intitolazione di una strada, piazza o parco cittadino e organizzazione iniziative in ricordo delle vittime delle Marocchinate, oltre alla richiesta di istituire una \u2018Giornata della memoria per le vittime delle Marocchinate\u2019.<\/p>\n<p>Infine, la proposta del \u2018piano di vendita\u2019 degli alloggi di Edilizia Residenziale Pubblica (E.R.P.) di propriet\u00e0 del Comune di Sora, destinati all&#8217;assistenza abitativa, ai sensi del Decreto Interministeriale 24 febbraio 2015 recante \u201cProcedure di alienazione del patrimonio di Edilizia Residenziale Pubblica\u201d e il regolamento del Corpo Polizia Locale come adeguato al Regolamento regionale concernente le uniformi, i gradi, i segni distintivi, i veicoli e gli strumenti di autotutela delle Polizie Locali del Lazio.<\/p>\n<p>&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Tre interrogazioni targate Cinquestelle, una mozione per le Marocchinate, la vendita degli alloggi di edilizia residenziale pubblica e il regolamento<\/p>\n","protected":false},"author":18,"featured_media":4468,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[41],"tags":[574,94,721,724,664,93,1823,775,1687,7071,161],"class_list":["post-27802","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-slide","tag-antenne","tag-ciociaria","tag-consiglio-comunale","tag-convocazione","tag-fabrizio-pintori","tag-frosinone","tag-interrogazioni","tag-maria-paola-dorazio","tag-ordine-del-giorno","tag-serena-petricca","tag-sora"],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v27.8 (Yoast SEO v27.8) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Incarichi legali, alloggi Erp e antenne: domani in Consiglio a Sora - IlCorriereDellaProvincia.it - News h24 e notizie di approfondimento<\/title>\n<meta name=\"description\" content=\"Sei i punti all&#039;ordine del giorno che saranno discussi nel consiglio comunale di Sora convocato per domani 4 febbraio alle ore 17.30\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2020\/02\/03\/incarichi-legali-alloggi-erp-e-antenne-domani-in-consiglio-a-sora\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Incarichi legali, alloggi Erp e antenne: domani in Consiglio a Sora\" \/>\n<meta property=\"og:description\" content=\"Sei i punti all&#039;ordine del giorno che saranno discussi nel consiglio comunale di Sora convocato per domani 4 febbraio alle ore 17.30\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2020\/02\/03\/incarichi-legali-alloggi-erp-e-antenne-domani-in-consiglio-a-sora\/\" \/>\n<meta property=\"og:site_name\" content=\"IlCorriereDellaProvincia.it - News h24 e notizie di approfondimento\" \/>\n<meta property=\"article:author\" content=\"www.facebook.com\/tunews24\" \/>\n<meta property=\"article:published_time\" content=\"2020-02-03T11:13:41+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2020-02-03T15:18:00+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2019\/01\/comune-sora-e1546956010730.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"632\" \/>\n\t<meta property=\"og:image:height\" content=\"359\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Redazione\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"Redazione\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2020\\\/02\\\/03\\\/incarichi-legali-alloggi-erp-e-antenne-domani-in-consiglio-a-sora\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2020\\\/02\\\/03\\\/incarichi-legali-alloggi-erp-e-antenne-domani-in-consiglio-a-sora\\\/\"},\"author\":{\"name\":\"Redazione\",\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/#\\\/schema\\\/person\\\/6d7f0a9120d0c03d0c552e9fdf49ed7d\"},\"headline\":\"Incarichi legali, alloggi Erp e antenne: domani in Consiglio a Sora\",\"datePublished\":\"2020-02-03T11:13:41+00:00\",\"dateModified\":\"2020-02-03T15:18:00+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2020\\\/02\\\/03\\\/incarichi-legali-alloggi-erp-e-antenne-domani-in-consiglio-a-sora\\\/\"},\"wordCount\":312,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2020\\\/02\\\/03\\\/incarichi-legali-alloggi-erp-e-antenne-domani-in-consiglio-a-sora\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2019\\\/01\\\/comune-sora-e1546956010730.jpg\",\"keywords\":[\"antenne\",\"Ciociaria\",\"consiglio comunale\",\"convocazione\",\"Fabrizio Pintori\",\"Frosinone\",\"interrogazioni\",\"maria paola d'orazio\",\"ordine del giorno\",\"serena petricca\",\"sora\"],\"articleSection\":[\"*SLIDE*\"],\"inLanguage\":\"it-IT\",\"copyrightYear\":\"2020\",\"copyrightHolder\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/#organization\"}},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2020\\\/02\\\/03\\\/incarichi-legali-alloggi-erp-e-antenne-domani-in-consiglio-a-sora\\\/\",\"url\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2020\\\/02\\\/03\\\/incarichi-legali-alloggi-erp-e-antenne-domani-in-consiglio-a-sora\\\/\",\"name\":\"Incarichi legali, alloggi Erp e antenne: domani in Consiglio a Sora - IlCorriereDellaProvincia.it - News h24 e notizie di approfondimento\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2020\\\/02\\\/03\\\/incarichi-legali-alloggi-erp-e-antenne-domani-in-consiglio-a-sora\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2020\\\/02\\\/03\\\/incarichi-legali-alloggi-erp-e-antenne-domani-in-consiglio-a-sora\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2019\\\/01\\\/comune-sora-e1546956010730.jpg\",\"datePublished\":\"2020-02-03T11:13:41+00:00\",\"dateModified\":\"2020-02-03T15:18:00+00:00\",\"description\":\"Sei i punti all'ordine del giorno che saranno discussi nel consiglio comunale di Sora convocato per domani 4 febbraio alle ore 17.30\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2020\\\/02\\\/03\\\/incarichi-legali-alloggi-erp-e-antenne-domani-in-consiglio-a-sora\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2020\\\/02\\\/03\\\/incarichi-legali-alloggi-erp-e-antenne-domani-in-consiglio-a-sora\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2020\\\/02\\\/03\\\/incarichi-legali-alloggi-erp-e-antenne-domani-in-consiglio-a-sora\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2019\\\/01\\\/comune-sora-e1546956010730.jpg\",\"contentUrl\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2019\\\/01\\\/comune-sora-e1546956010730.jpg\",\"width\":632,\"height\":359,\"caption\":\"Il palazzo municipale di Sora\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2020\\\/02\\\/03\\\/incarichi-legali-alloggi-erp-e-antenne-domani-in-consiglio-a-sora\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Incarichi legali, alloggi Erp e antenne: domani in Consiglio a Sora\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/#website\",\"url\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/\",\"name\":\"Il Corriere Delle Provincia\",\"description\":\"IlCorriereDellaProvincia.it, quotidiano web di politica, cronaca, inchiesta, lavoro, scuola, turismo, cultura e spettacolo, economia e finanza, salute e benessere. Approfondimenti e notizie aggiornate con foto e video della provincia di Frosinone ma anche news nazionali, dell\u2019Italia e del Mondo.\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":[\"Organization\",\"Place\"],\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/#organization\",\"name\":\"Globalpress s.r.l.\",\"url\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/\",\"logo\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2020\\\/02\\\/03\\\/incarichi-legali-alloggi-erp-e-antenne-domani-in-consiglio-a-sora\\\/#local-main-organization-logo\"},\"image\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2020\\\/02\\\/03\\\/incarichi-legali-alloggi-erp-e-antenne-domani-in-consiglio-a-sora\\\/#local-main-organization-logo\"},\"telephone\":[],\"openingHoursSpecification\":[{\"@type\":\"OpeningHoursSpecification\",\"dayOfWeek\":[\"Monday\",\"Tuesday\",\"Wednesday\",\"Thursday\",\"Friday\",\"Saturday\",\"Sunday\"],\"opens\":\"09:00\",\"closes\":\"17:00\"}]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/#\\\/schema\\\/person\\\/6d7f0a9120d0c03d0c552e9fdf49ed7d\",\"name\":\"Redazione\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/a40eeacccdcad861f831dde73317f63a542e738f0dc4b79b9f47062d3d4bd1d2?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/a40eeacccdcad861f831dde73317f63a542e738f0dc4b79b9f47062d3d4bd1d2?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/a40eeacccdcad861f831dde73317f63a542e738f0dc4b79b9f47062d3d4bd1d2?s=96&d=mm&r=g\",\"caption\":\"Redazione\"},\"description\":\"SEGUICI ANCHE SUI SOCIAL Facebook: TuNews24 e TuSport24 Instagram: TuNews24 e TuSport24 Youtube: TuNews24 Telegram: TuNews24 Puoi leggerci anche in formato cartaceo: il settimanale viene pubblicato e distribuito gratuitamente ogni venerd\u00ec in edicole, bar, centri commerciali e svariati esercizi. Ma \u00e8 possibile anche sfogliarlo comodamente online, cliccando su TU NEWS sfogliabile TU NEWS, PASSIONE PER L\u2019INFORMAZIONE\",\"sameAs\":[\"http:\\\/\\\/www.tunews24.it\",\"www.facebook.com\\\/tunews24\"],\"url\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/author\\\/senzafirma\\\/\"},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2020\\\/02\\\/03\\\/incarichi-legali-alloggi-erp-e-antenne-domani-in-consiglio-a-sora\\\/#local-main-organization-logo\",\"url\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2022\\\/11\\\/cropped-il-corriere-della-provincia-testata-web-scontornata.png\",\"contentUrl\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2022\\\/11\\\/cropped-il-corriere-della-provincia-testata-web-scontornata.png\",\"width\":2911,\"height\":717,\"caption\":\"Globalpress s.r.l.\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Incarichi legali, alloggi Erp e antenne: domani in Consiglio a Sora - IlCorriereDellaProvincia.it - News h24 e notizie di approfondimento","description":"Sei i punti all'ordine del giorno che saranno discussi nel consiglio comunale di Sora convocato per domani 4 febbraio alle ore 17.30","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2020\/02\/03\/incarichi-legali-alloggi-erp-e-antenne-domani-in-consiglio-a-sora\/","og_locale":"it_IT","og_type":"article","og_title":"Incarichi legali, alloggi Erp e antenne: domani in Consiglio a Sora","og_description":"Sei i punti all'ordine del giorno che saranno discussi nel consiglio comunale di Sora convocato per domani 4 febbraio alle ore 17.30","og_url":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2020\/02\/03\/incarichi-legali-alloggi-erp-e-antenne-domani-in-consiglio-a-sora\/","og_site_name":"IlCorriereDellaProvincia.it - News h24 e notizie di approfondimento","article_author":"www.facebook.com\/tunews24","article_published_time":"2020-02-03T11:13:41+00:00","article_modified_time":"2020-02-03T15:18:00+00:00","og_image":[{"width":632,"height":359,"url":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2019\/01\/comune-sora-e1546956010730.jpg","type":"image\/jpeg"}],"author":"Redazione","twitter_card":"summary_large_image","twitter_misc":{"Scritto da":"Redazione","Tempo di lettura stimato":"1 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2020\/02\/03\/incarichi-legali-alloggi-erp-e-antenne-domani-in-consiglio-a-sora\/#article","isPartOf":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2020\/02\/03\/incarichi-legali-alloggi-erp-e-antenne-domani-in-consiglio-a-sora\/"},"author":{"name":"Redazione","@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/#\/schema\/person\/6d7f0a9120d0c03d0c552e9fdf49ed7d"},"headline":"Incarichi legali, alloggi Erp e antenne: domani in Consiglio a Sora","datePublished":"2020-02-03T11:13:41+00:00","dateModified":"2020-02-03T15:18:00+00:00","mainEntityOfPage":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2020\/02\/03\/incarichi-legali-alloggi-erp-e-antenne-domani-in-consiglio-a-sora\/"},"wordCount":312,"commentCount":0,"publisher":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/#organization"},"image":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2020\/02\/03\/incarichi-legali-alloggi-erp-e-antenne-domani-in-consiglio-a-sora\/#primaryimage"},"thumbnailUrl":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2019\/01\/comune-sora-e1546956010730.jpg","keywords":["antenne","Ciociaria","consiglio comunale","convocazione","Fabrizio Pintori","Frosinone","interrogazioni","maria paola d'orazio","ordine del giorno","serena petricca","sora"],"articleSection":["*SLIDE*"],"inLanguage":"it-IT","copyrightYear":"2020","copyrightHolder":{"@id":"https:\/\/www.tunews24.it\/#organization"}},{"@type":"WebPage","@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2020\/02\/03\/incarichi-legali-alloggi-erp-e-antenne-domani-in-consiglio-a-sora\/","url":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2020\/02\/03\/incarichi-legali-alloggi-erp-e-antenne-domani-in-consiglio-a-sora\/","name":"Incarichi legali, alloggi Erp e antenne: domani in Consiglio a Sora - IlCorriereDellaProvincia.it - News h24 e notizie di approfondimento","isPartOf":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2020\/02\/03\/incarichi-legali-alloggi-erp-e-antenne-domani-in-consiglio-a-sora\/#primaryimage"},"image":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2020\/02\/03\/incarichi-legali-alloggi-erp-e-antenne-domani-in-consiglio-a-sora\/#primaryimage"},"thumbnailUrl":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2019\/01\/comune-sora-e1546956010730.jpg","datePublished":"2020-02-03T11:13:41+00:00","dateModified":"2020-02-03T15:18:00+00:00","description":"Sei i punti all'ordine del giorno che saranno discussi nel consiglio comunale di Sora convocato per domani 4 febbraio alle ore 17.30","breadcrumb":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2020\/02\/03\/incarichi-legali-alloggi-erp-e-antenne-domani-in-consiglio-a-sora\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2020\/02\/03\/incarichi-legali-alloggi-erp-e-antenne-domani-in-consiglio-a-sora\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2020\/02\/03\/incarichi-legali-alloggi-erp-e-antenne-domani-in-consiglio-a-sora\/#primaryimage","url":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2019\/01\/comune-sora-e1546956010730.jpg","contentUrl":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2019\/01\/comune-sora-e1546956010730.jpg","width":632,"height":359,"caption":"Il palazzo municipale di Sora"},{"@type":"BreadcrumbList","@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2020\/02\/03\/incarichi-legali-alloggi-erp-e-antenne-domani-in-consiglio-a-sora\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/"},{"@type":"ListItem","position":2,"name":"Incarichi legali, alloggi Erp e antenne: domani in Consiglio a Sora"}]},{"@type":"WebSite","@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/#website","url":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/","name":"Il Corriere Delle Provincia","description":"IlCorriereDellaProvincia.it, quotidiano web di politica, cronaca, inchiesta, lavoro, scuola, turismo, cultura e spettacolo, economia e finanza, salute e benessere. Approfondimenti e notizie aggiornate con foto e video della provincia di Frosinone ma anche news nazionali, dell\u2019Italia e del Mondo.","publisher":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":["Organization","Place"],"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/#organization","name":"Globalpress s.r.l.","url":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/","logo":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2020\/02\/03\/incarichi-legali-alloggi-erp-e-antenne-domani-in-consiglio-a-sora\/#local-main-organization-logo"},"image":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2020\/02\/03\/incarichi-legali-alloggi-erp-e-antenne-domani-in-consiglio-a-sora\/#local-main-organization-logo"},"telephone":[],"openingHoursSpecification":[{"@type":"OpeningHoursSpecification","dayOfWeek":["Monday","Tuesday","Wednesday","Thursday","Friday","Saturday","Sunday"],"opens":"09:00","closes":"17:00"}]},{"@type":"Person","@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/#\/schema\/person\/6d7f0a9120d0c03d0c552e9fdf49ed7d","name":"Redazione","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/secure.gravatar.com\/avatar\/a40eeacccdcad861f831dde73317f63a542e738f0dc4b79b9f47062d3d4bd1d2?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/a40eeacccdcad861f831dde73317f63a542e738f0dc4b79b9f47062d3d4bd1d2?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/a40eeacccdcad861f831dde73317f63a542e738f0dc4b79b9f47062d3d4bd1d2?s=96&d=mm&r=g","caption":"Redazione"},"description":"SEGUICI ANCHE SUI SOCIAL Facebook: TuNews24 e TuSport24 Instagram: TuNews24 e TuSport24 Youtube: TuNews24 Telegram: TuNews24 Puoi leggerci anche in formato cartaceo: il settimanale viene pubblicato e distribuito gratuitamente ogni venerd\u00ec in edicole, bar, centri commerciali e svariati esercizi. Ma \u00e8 possibile anche sfogliarlo comodamente online, cliccando su TU NEWS sfogliabile TU NEWS, PASSIONE PER L\u2019INFORMAZIONE","sameAs":["http:\/\/www.tunews24.it","www.facebook.com\/tunews24"],"url":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/author\/senzafirma\/"},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2020\/02\/03\/incarichi-legali-alloggi-erp-e-antenne-domani-in-consiglio-a-sora\/#local-main-organization-logo","url":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2022\/11\/cropped-il-corriere-della-provincia-testata-web-scontornata.png","contentUrl":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2022\/11\/cropped-il-corriere-della-provincia-testata-web-scontornata.png","width":2911,"height":717,"caption":"Globalpress s.r.l."}]}},"_links":{"self":[{"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/posts\/27802","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/users\/18"}],"replies":[{"embeddable":true,"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/comments?post=27802"}],"version-history":[{"count":1,"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/posts\/27802\/revisions"}],"predecessor-version":[{"id":27806,"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/posts\/27802\/revisions\/27806"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/media\/4468"}],"wp:attachment":[{"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/media?parent=27802"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/categories?post=27802"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/tags?post=27802"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}