{"id":26635,"date":"2020-01-17T18:47:21","date_gmt":"2020-01-17T17:47:21","guid":{"rendered":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/?p=26635"},"modified":"2020-01-17T18:47:21","modified_gmt":"2020-01-17T17:47:21","slug":"delitto-mollicone-la-consigliera-simone-il-comune-si-costituisca-parte-civile","status":"publish","type":"post","link":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2020\/01\/17\/delitto-mollicone-la-consigliera-simone-il-comune-si-costituisca-parte-civile\/","title":{"rendered":"Delitto Mollicone, la consigliera Simone: il Comune si costituisca parte civile"},"content":{"rendered":"<p><strong>Una ferita aperta per tutto il paese<\/strong>. Non soltanto un femminicidio, una violenza mortale nei confronti di una giovane studentessa, una morte che dopo quasi venti anni ancora non ha trovato la giustizia che merita. Ma un\u2019onta per l\u2019intero comune, per tutta l\u2019Italia. Mentre pap\u00e0 Guglielmo lotta nel suo letto di ospedale, attaccato alla speranza di mettere la parola fine a un\u2019estenuante agonia che lo ha logorato.<\/p>\n<p>Lo scorso 15 gennaio, al tribunale di Cassino, si \u00e8 aperto il <strong>processo per la morte di Serena Mollicone<\/strong>, la diciottenne trovata cadavere nel bosco di Fonte Cupa nel giugno 2001.<\/p>\n<h2>Gli indagati<\/h2>\n<p>Devono rispondere di concorso in omicidio: <strong>l\u2019ex maresciallo dei carabinieri Franco Mottola<\/strong>, <strong>sua moglie Anna Maria<\/strong>, <strong>il figlio Marco<\/strong> e il <strong>maresciallo Vincenzo Quatrale<\/strong>. Quest\u2019ultimo \u00e8 accusato di istigazione al suicidio del brigadiere Santino Tuzi. <strong>L&#8217;appuntato Francesco Suprano<\/strong> \u00e8 accusato di favoreggiamento.<\/p>\n<h2>La proposta della Simone<\/h2>\n<p>La <strong>consigliera comunale di opposizione, capogruppo di \u2018Arce Futura\u2019, Sara Simone,<\/strong> ha inoltrato presentato oggi una<strong> mozione<\/strong>, inviata al sindaco del Comune di Arce e al presidente del Consiglio comunale, con la richiesta di\u00a0 convocazione di un consiglio comunale straordinario per deliberare la costituzione di parte civile dell\u2019ente comunale nel processo di Serena.<\/p>\n<p>&nbsp;<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter wp-image-11102 size-large\" src=\"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2019\/05\/sara-simone-arce_2-1024x624.jpg\" alt=\"Sara Simone Arce Candidato Candidata Sindaco Ciociaria Frosinone Arce Futura\" width=\"800\" height=\"488\" srcset=\"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2019\/05\/sara-simone-arce_2-1024x624.jpg 1024w, https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2019\/05\/sara-simone-arce_2-300x183.jpg 300w, https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2019\/05\/sara-simone-arce_2-768x468.jpg 768w, https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2019\/05\/sara-simone-arce_2-500x305.jpg 500w, https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2019\/05\/sara-simone-arce_2.jpg 1181w\" sizes=\"auto, (max-width: 800px) 100vw, 800px\" \/><\/p>\n<p>&nbsp;<\/p>\n<p>Osserva l\u2019avvocato Simone che &#8220;<strong>il delitto della giovane Serena Mollicone \u00e8 una ferita aperta per tutta la comunit\u00e0<\/strong>, a causa dell\u2019efferatezza dell\u2019omicidio che ha scosso e turbato gli animi e le coscienze dei cittadini arcesi, minando cos\u00ec il loro diritto soggettivo a condurre una vita serena e tranquilla nel proprio territorio. Il Comune di Arce \u2013 ha evidenziato ancora \u2013 ha subito anche un danno d\u2019immagine a seguito dell\u2019uccisione dell\u2019allora diciottenne Serena Mollicone che certamente ha aggravato l\u2019immagine di Arce. Infine \u2013 conclude la Simone \u2013 <strong>il silenzio mantenuto su questa oltraggiosa vicenda non \u00e8 pi\u00f9 tollerabile<\/strong> ed \u00e8 necessario schierare tutta l\u2019Amministrazione al fianco di Guglielmo Mollicone e di tutta la famiglia della vittima perch\u00e9 ci\u00f2 contribuir\u00e0 a dare forza a una battaglia che deve essere di tutti&#8221;.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Una ferita aperta per tutto il paese. Non soltanto un femminicidio, una violenza mortale nei confronti di una giovane studentessa,<\/p>\n","protected":false},"author":18,"featured_media":26636,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[4,2],"tags":[411,94,149,93,778,1260,3710,8173,1157,3163,728,584],"class_list":["post-26635","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-primo-piano","category-cronaca","tag-arce","tag-ciociaria","tag-comune","tag-frosinone","tag-guglielmo-mollicone","tag-indagati","tag-omicidio","tag-parte-civile","tag-processo","tag-sara-simone","tag-serena-mollicone","tag-tribunale"],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v27.8 (Yoast SEO v27.8) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Delitto Mollicone, la consigliera Simone: il Comune si costituisca parte civile - IlCorriereDellaProvincia.it - News h24 e notizie di approfondimento<\/title>\n<meta name=\"description\" content=\"La consigliera di Arce, Sara Simone, ha presentato richiesta di un consiglio comunale per costituire il Comune parte civile nel processo Mollicone\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2020\/01\/17\/delitto-mollicone-la-consigliera-simone-il-comune-si-costituisca-parte-civile\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Delitto Mollicone, la consigliera Simone: il Comune si costituisca parte civile\" \/>\n<meta property=\"og:description\" content=\"La consigliera di Arce, Sara Simone, ha presentato richiesta di un consiglio comunale per costituire il Comune parte civile nel processo Mollicone\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2020\/01\/17\/delitto-mollicone-la-consigliera-simone-il-comune-si-costituisca-parte-civile\/\" \/>\n<meta property=\"og:site_name\" content=\"IlCorriereDellaProvincia.it - News h24 e notizie di approfondimento\" \/>\n<meta property=\"article:author\" content=\"www.facebook.com\/tunews24\" \/>\n<meta property=\"article:published_time\" content=\"2020-01-17T17:47:21+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2020\/01\/guglielmo-serena-mollicone.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"700\" \/>\n\t<meta property=\"og:image:height\" content=\"410\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Redazione\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"Redazione\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minuti\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2020\\\/01\\\/17\\\/delitto-mollicone-la-consigliera-simone-il-comune-si-costituisca-parte-civile\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2020\\\/01\\\/17\\\/delitto-mollicone-la-consigliera-simone-il-comune-si-costituisca-parte-civile\\\/\"},\"author\":{\"name\":\"Redazione\",\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/#\\\/schema\\\/person\\\/6d7f0a9120d0c03d0c552e9fdf49ed7d\"},\"headline\":\"Delitto Mollicone, la consigliera Simone: il Comune si costituisca parte civile\",\"datePublished\":\"2020-01-17T17:47:21+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2020\\\/01\\\/17\\\/delitto-mollicone-la-consigliera-simone-il-comune-si-costituisca-parte-civile\\\/\"},\"wordCount\":345,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2020\\\/01\\\/17\\\/delitto-mollicone-la-consigliera-simone-il-comune-si-costituisca-parte-civile\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2020\\\/01\\\/guglielmo-serena-mollicone.jpg\",\"keywords\":[\"Arce\",\"Ciociaria\",\"comune\",\"Frosinone\",\"guglielmo mollicone\",\"Indagati\",\"omicidio\",\"parte civile\",\"Processo\",\"sara simone\",\"serena mollicone\",\"tribunale\"],\"articleSection\":[\"*PRIMO PIANO*\",\"Cronaca\"],\"inLanguage\":\"it-IT\",\"copyrightYear\":\"2020\",\"copyrightHolder\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/#organization\"}},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2020\\\/01\\\/17\\\/delitto-mollicone-la-consigliera-simone-il-comune-si-costituisca-parte-civile\\\/\",\"url\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2020\\\/01\\\/17\\\/delitto-mollicone-la-consigliera-simone-il-comune-si-costituisca-parte-civile\\\/\",\"name\":\"Delitto Mollicone, la consigliera Simone: il Comune si costituisca parte civile - IlCorriereDellaProvincia.it - News h24 e notizie di approfondimento\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2020\\\/01\\\/17\\\/delitto-mollicone-la-consigliera-simone-il-comune-si-costituisca-parte-civile\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2020\\\/01\\\/17\\\/delitto-mollicone-la-consigliera-simone-il-comune-si-costituisca-parte-civile\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2020\\\/01\\\/guglielmo-serena-mollicone.jpg\",\"datePublished\":\"2020-01-17T17:47:21+00:00\",\"description\":\"La consigliera di Arce, Sara Simone, ha presentato richiesta di un consiglio comunale per costituire il Comune parte civile nel processo Mollicone\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2020\\\/01\\\/17\\\/delitto-mollicone-la-consigliera-simone-il-comune-si-costituisca-parte-civile\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2020\\\/01\\\/17\\\/delitto-mollicone-la-consigliera-simone-il-comune-si-costituisca-parte-civile\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2020\\\/01\\\/17\\\/delitto-mollicone-la-consigliera-simone-il-comune-si-costituisca-parte-civile\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2020\\\/01\\\/guglielmo-serena-mollicone.jpg\",\"contentUrl\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2020\\\/01\\\/guglielmo-serena-mollicone.jpg\",\"width\":700,\"height\":410,\"caption\":\"Guglielmo Mollicone e sua figlia Serena, uccisa nel 2001\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2020\\\/01\\\/17\\\/delitto-mollicone-la-consigliera-simone-il-comune-si-costituisca-parte-civile\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Delitto Mollicone, la consigliera Simone: il Comune si costituisca parte civile\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/#website\",\"url\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/\",\"name\":\"Il Corriere Delle Provincia\",\"description\":\"IlCorriereDellaProvincia.it, quotidiano web di politica, cronaca, inchiesta, lavoro, scuola, turismo, cultura e spettacolo, economia e finanza, salute e benessere. Approfondimenti e notizie aggiornate con foto e video della provincia di Frosinone ma anche news nazionali, dell\u2019Italia e del Mondo.\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":[\"Organization\",\"Place\"],\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/#organization\",\"name\":\"Globalpress s.r.l.\",\"url\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/\",\"logo\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2020\\\/01\\\/17\\\/delitto-mollicone-la-consigliera-simone-il-comune-si-costituisca-parte-civile\\\/#local-main-organization-logo\"},\"image\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2020\\\/01\\\/17\\\/delitto-mollicone-la-consigliera-simone-il-comune-si-costituisca-parte-civile\\\/#local-main-organization-logo\"},\"telephone\":[],\"openingHoursSpecification\":[{\"@type\":\"OpeningHoursSpecification\",\"dayOfWeek\":[\"Monday\",\"Tuesday\",\"Wednesday\",\"Thursday\",\"Friday\",\"Saturday\",\"Sunday\"],\"opens\":\"09:00\",\"closes\":\"17:00\"}]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/#\\\/schema\\\/person\\\/6d7f0a9120d0c03d0c552e9fdf49ed7d\",\"name\":\"Redazione\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/a40eeacccdcad861f831dde73317f63a542e738f0dc4b79b9f47062d3d4bd1d2?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/a40eeacccdcad861f831dde73317f63a542e738f0dc4b79b9f47062d3d4bd1d2?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/a40eeacccdcad861f831dde73317f63a542e738f0dc4b79b9f47062d3d4bd1d2?s=96&d=mm&r=g\",\"caption\":\"Redazione\"},\"description\":\"SEGUICI ANCHE SUI SOCIAL Facebook: TuNews24 e TuSport24 Instagram: TuNews24 e TuSport24 Youtube: TuNews24 Telegram: TuNews24 Puoi leggerci anche in formato cartaceo: il settimanale viene pubblicato e distribuito gratuitamente ogni venerd\u00ec in edicole, bar, centri commerciali e svariati esercizi. Ma \u00e8 possibile anche sfogliarlo comodamente online, cliccando su TU NEWS sfogliabile TU NEWS, PASSIONE PER L\u2019INFORMAZIONE\",\"sameAs\":[\"http:\\\/\\\/www.tunews24.it\",\"www.facebook.com\\\/tunews24\"],\"url\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/author\\\/senzafirma\\\/\"},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2020\\\/01\\\/17\\\/delitto-mollicone-la-consigliera-simone-il-comune-si-costituisca-parte-civile\\\/#local-main-organization-logo\",\"url\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2022\\\/11\\\/cropped-il-corriere-della-provincia-testata-web-scontornata.png\",\"contentUrl\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2022\\\/11\\\/cropped-il-corriere-della-provincia-testata-web-scontornata.png\",\"width\":2911,\"height\":717,\"caption\":\"Globalpress s.r.l.\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Delitto Mollicone, la consigliera Simone: il Comune si costituisca parte civile - IlCorriereDellaProvincia.it - News h24 e notizie di approfondimento","description":"La consigliera di Arce, Sara Simone, ha presentato richiesta di un consiglio comunale per costituire il Comune parte civile nel processo Mollicone","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2020\/01\/17\/delitto-mollicone-la-consigliera-simone-il-comune-si-costituisca-parte-civile\/","og_locale":"it_IT","og_type":"article","og_title":"Delitto Mollicone, la consigliera Simone: il Comune si costituisca parte civile","og_description":"La consigliera di Arce, Sara Simone, ha presentato richiesta di un consiglio comunale per costituire il Comune parte civile nel processo Mollicone","og_url":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2020\/01\/17\/delitto-mollicone-la-consigliera-simone-il-comune-si-costituisca-parte-civile\/","og_site_name":"IlCorriereDellaProvincia.it - News h24 e notizie di approfondimento","article_author":"www.facebook.com\/tunews24","article_published_time":"2020-01-17T17:47:21+00:00","og_image":[{"width":700,"height":410,"url":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2020\/01\/guglielmo-serena-mollicone.jpg","type":"image\/jpeg"}],"author":"Redazione","twitter_card":"summary_large_image","twitter_misc":{"Scritto da":"Redazione","Tempo di lettura stimato":"2 minuti"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2020\/01\/17\/delitto-mollicone-la-consigliera-simone-il-comune-si-costituisca-parte-civile\/#article","isPartOf":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2020\/01\/17\/delitto-mollicone-la-consigliera-simone-il-comune-si-costituisca-parte-civile\/"},"author":{"name":"Redazione","@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/#\/schema\/person\/6d7f0a9120d0c03d0c552e9fdf49ed7d"},"headline":"Delitto Mollicone, la consigliera Simone: il Comune si costituisca parte civile","datePublished":"2020-01-17T17:47:21+00:00","mainEntityOfPage":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2020\/01\/17\/delitto-mollicone-la-consigliera-simone-il-comune-si-costituisca-parte-civile\/"},"wordCount":345,"commentCount":0,"publisher":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/#organization"},"image":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2020\/01\/17\/delitto-mollicone-la-consigliera-simone-il-comune-si-costituisca-parte-civile\/#primaryimage"},"thumbnailUrl":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2020\/01\/guglielmo-serena-mollicone.jpg","keywords":["Arce","Ciociaria","comune","Frosinone","guglielmo mollicone","Indagati","omicidio","parte civile","Processo","sara simone","serena mollicone","tribunale"],"articleSection":["*PRIMO PIANO*","Cronaca"],"inLanguage":"it-IT","copyrightYear":"2020","copyrightHolder":{"@id":"https:\/\/www.tunews24.it\/#organization"}},{"@type":"WebPage","@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2020\/01\/17\/delitto-mollicone-la-consigliera-simone-il-comune-si-costituisca-parte-civile\/","url":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2020\/01\/17\/delitto-mollicone-la-consigliera-simone-il-comune-si-costituisca-parte-civile\/","name":"Delitto Mollicone, la consigliera Simone: il Comune si costituisca parte civile - IlCorriereDellaProvincia.it - News h24 e notizie di approfondimento","isPartOf":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2020\/01\/17\/delitto-mollicone-la-consigliera-simone-il-comune-si-costituisca-parte-civile\/#primaryimage"},"image":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2020\/01\/17\/delitto-mollicone-la-consigliera-simone-il-comune-si-costituisca-parte-civile\/#primaryimage"},"thumbnailUrl":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2020\/01\/guglielmo-serena-mollicone.jpg","datePublished":"2020-01-17T17:47:21+00:00","description":"La consigliera di Arce, Sara Simone, ha presentato richiesta di un consiglio comunale per costituire il Comune parte civile nel processo Mollicone","breadcrumb":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2020\/01\/17\/delitto-mollicone-la-consigliera-simone-il-comune-si-costituisca-parte-civile\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2020\/01\/17\/delitto-mollicone-la-consigliera-simone-il-comune-si-costituisca-parte-civile\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2020\/01\/17\/delitto-mollicone-la-consigliera-simone-il-comune-si-costituisca-parte-civile\/#primaryimage","url":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2020\/01\/guglielmo-serena-mollicone.jpg","contentUrl":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2020\/01\/guglielmo-serena-mollicone.jpg","width":700,"height":410,"caption":"Guglielmo Mollicone e sua figlia Serena, uccisa nel 2001"},{"@type":"BreadcrumbList","@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2020\/01\/17\/delitto-mollicone-la-consigliera-simone-il-comune-si-costituisca-parte-civile\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/"},{"@type":"ListItem","position":2,"name":"Delitto Mollicone, la consigliera Simone: il Comune si costituisca parte civile"}]},{"@type":"WebSite","@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/#website","url":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/","name":"Il Corriere Delle Provincia","description":"IlCorriereDellaProvincia.it, quotidiano web di politica, cronaca, inchiesta, lavoro, scuola, turismo, cultura e spettacolo, economia e finanza, salute e benessere. Approfondimenti e notizie aggiornate con foto e video della provincia di Frosinone ma anche news nazionali, dell\u2019Italia e del Mondo.","publisher":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":["Organization","Place"],"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/#organization","name":"Globalpress s.r.l.","url":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/","logo":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2020\/01\/17\/delitto-mollicone-la-consigliera-simone-il-comune-si-costituisca-parte-civile\/#local-main-organization-logo"},"image":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2020\/01\/17\/delitto-mollicone-la-consigliera-simone-il-comune-si-costituisca-parte-civile\/#local-main-organization-logo"},"telephone":[],"openingHoursSpecification":[{"@type":"OpeningHoursSpecification","dayOfWeek":["Monday","Tuesday","Wednesday","Thursday","Friday","Saturday","Sunday"],"opens":"09:00","closes":"17:00"}]},{"@type":"Person","@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/#\/schema\/person\/6d7f0a9120d0c03d0c552e9fdf49ed7d","name":"Redazione","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/secure.gravatar.com\/avatar\/a40eeacccdcad861f831dde73317f63a542e738f0dc4b79b9f47062d3d4bd1d2?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/a40eeacccdcad861f831dde73317f63a542e738f0dc4b79b9f47062d3d4bd1d2?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/a40eeacccdcad861f831dde73317f63a542e738f0dc4b79b9f47062d3d4bd1d2?s=96&d=mm&r=g","caption":"Redazione"},"description":"SEGUICI ANCHE SUI SOCIAL Facebook: TuNews24 e TuSport24 Instagram: TuNews24 e TuSport24 Youtube: TuNews24 Telegram: TuNews24 Puoi leggerci anche in formato cartaceo: il settimanale viene pubblicato e distribuito gratuitamente ogni venerd\u00ec in edicole, bar, centri commerciali e svariati esercizi. Ma \u00e8 possibile anche sfogliarlo comodamente online, cliccando su TU NEWS sfogliabile TU NEWS, PASSIONE PER L\u2019INFORMAZIONE","sameAs":["http:\/\/www.tunews24.it","www.facebook.com\/tunews24"],"url":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/author\/senzafirma\/"},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2020\/01\/17\/delitto-mollicone-la-consigliera-simone-il-comune-si-costituisca-parte-civile\/#local-main-organization-logo","url":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2022\/11\/cropped-il-corriere-della-provincia-testata-web-scontornata.png","contentUrl":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2022\/11\/cropped-il-corriere-della-provincia-testata-web-scontornata.png","width":2911,"height":717,"caption":"Globalpress s.r.l."}]}},"_links":{"self":[{"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/posts\/26635","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/users\/18"}],"replies":[{"embeddable":true,"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/comments?post=26635"}],"version-history":[{"count":1,"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/posts\/26635\/revisions"}],"predecessor-version":[{"id":26637,"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/posts\/26635\/revisions\/26637"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/media\/26636"}],"wp:attachment":[{"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/media?parent=26635"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/categories?post=26635"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/tags?post=26635"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}