{"id":26257,"date":"2020-01-14T11:48:11","date_gmt":"2020-01-14T10:48:11","guid":{"rendered":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/?p=26257"},"modified":"2020-01-14T12:03:46","modified_gmt":"2020-01-14T11:03:46","slug":"a-pontecorvo-il-carnevale-2020-raddoppia","status":"publish","type":"post","link":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2020\/01\/14\/a-pontecorvo-il-carnevale-2020-raddoppia\/","title":{"rendered":"A Pontecorvo il carnevale 2020&#8230; raddoppia"},"content":{"rendered":"<p>Doppio appuntamento con la festa pi\u00f9 colorata dell&#8217;anno: <strong>a Pontecorvo torna il carnevale con la doppia sfilata<\/strong> nelle <strong>domeniche del 16 e del 23 febbraio<\/strong>. Il sindaco Rotondo parla di &#8220;impegno maggiore per sostenere l&#8217;economia cittadina e dare ossigeno al commercio locale&#8221;.<\/p>\n<h2>Le dichiarazioni dell&#8217;assessore<\/h2>\n<p>L&#8217;assessore <strong>Katiuscia Mulattieri<\/strong>, che insieme al sindaco e ai dirigenti della municipalizzata Asm ha deciso di ripristinare la formula gi\u00e0 sperimentata nel 2016\/2017 su impulso dell&#8217;assessore Moira Rotondo, si dice estremamente soddisfatta.<\/p>\n<p>&#8220;Doppia festa, per due domeniche consecutive. <strong>Il Carnevale \u00e8 il brand pi\u00f9 popolare di Pontecorvo<\/strong> e vogliamo metterne a regime tutte le potenzialit\u00e0 soprattutto per arrecare vantaggi agli operatori commerciali, baristi, ai ristoratori. Ridurre tutto a una sola domenica sarebbe come gettare al vento le opportunit\u00e0 economiche e di divertimento che invece possiamo assicurare alla citt\u00e0 in 15 giorni di attivit\u00e0 e iniziative&#8221;.<\/p>\n<h2>Carri protagonisti<\/h2>\n<p>Protagonisti delle sfilate delle domeniche 16 e 23 febbraio saranno come sempre i carri allegorici, capolavori creativit\u00e0 che sono i principali artefici del successo e della popolarit\u00e0 del Carnevale ciociaro pontecorvese.<br \/>\n&#8220;Siamo consapevoli di quanto l\u2019opera dei carristi sia funzionale alla riuscita della nostra kermesse. Non \u00e8 un caso \u2013 dice il <strong>sindaco Anselmo Rotondo<\/strong> \u2013 se gi\u00e0 in estate li abbiamo incontrati, in pi\u00f9 di una riunione, per concordare con loro la formula, il percorso, le modalit\u00e0. Al tavolo, gran bella novit\u00e0 che deve avere un seguito, c&#8217;era anche il rappresentante del gruppo di giovani di Esperia che parteciper\u00e0 alle sfilate con un proprio carro&#8221;.<\/p>\n<p>&nbsp;<\/p>\n<figure id=\"attachment_26262\" aria-describedby=\"caption-attachment-26262\" style=\"width: 632px\" class=\"wp-caption aligncenter\"><img loading=\"lazy\" decoding=\"async\" class=\"wp-image-26262 size-full\" src=\"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2020\/01\/Spiridigliozzi-Mulattieri-Rotondo-e1578999763403.jpg\" alt=\"spiridigliozzi mulattieri rotondo pontecorvo il corriere della provincia\" width=\"632\" height=\"426\" \/><figcaption id=\"caption-attachment-26262\" class=\"wp-caption-text\">Da sinistra Gaetano Spiridigliozzi, Katiuscia Mulattieri e Anselmo Rotondo<\/figcaption><\/figure>\n<p>&nbsp;<\/p>\n<p>&#8220;Abbiamo giocato d\u2019anticipo per permettere ai nostri artisti di essere da subito operativi, pianificando ogni dettaglio in un confronto improntato alla condivisione e alla trasparenza, anche finanziaria. Anzi, quest\u2019anno pi\u00f9 che nei precedenti, abbiamo chiarito subito quale fosse la disponibilit\u00e0 economica che il Comune poteva mettere in campo. Abbiamo impegnato una somma importante, con la certezza di poter disporre realmente di quelle risorse gi\u00e0 impegnate e contabilizzate in bilancio&#8221;.<\/p>\n<p>&#8220;Anche questa edizione del Carnevale sar\u00e0 archiviata con i conti in ordine, senza sorprese e senza extra spese. Abbiamo gi\u00e0 versato ai carristi \u2013 aggiunge con un pizzico di orgoglio il sindaco \u2013 il primo acconto. Il secondo sar\u00e0 liquidato prima delle sfilate. Il saldo arriver\u00e0 a bilancio approvato. <strong>Conti in ordine, trasparenza gestionale e la convinzione per cui la doppia sfilata vada istituzionalizzata<\/strong> per onorare la nostra festa pi\u00f9 popolare, ma soprattutto per garantire ai nostri commercianti occasioni ulteriori e pi\u00f9 strutturali di reddito&#8221;.<\/p>\n<h2>L&#8217;associazione &#8216;San Grimoaldo Sacerdote&#8217;<\/h2>\n<p>L&#8217;organizzazione degli eventi \u00e8 affidata all&#8217;<strong>associazione San Grimoaldo Sacerdote<\/strong>, che ha gi\u00e0 dato prova di capacit\u00e0 e competenza. Fondamentale sar\u00e0 il ruolo della Asm nella gestione degli eventi.<\/p>\n<p>&#8220;Presto pubblicheremo il programma completo dei festeggiamenti. Agli appuntamenti classici, come la gara delle mascherine, affiancheremo novit\u00e0 per offrire altre occasioni di divertimento ai tanti giovani che arriveranno a Pontecorvo nei giorni del Carnevale&#8221; dice il <strong>vicepresidente della Asm, Gaetano Spiridigliozzi<\/strong> che, su delega del presidente Gino Trotto, siede col sindaco e l\u2019assessore Mulattieri nella cabina di regia del Canevale.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Doppio appuntamento con la festa pi\u00f9 colorata dell&#8217;anno: a Pontecorvo torna il carnevale con la doppia sfilata nelle domeniche del<\/p>\n","protected":false},"author":18,"featured_media":26258,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[41,14],"tags":[2324,2517,2519,94,93,8112,733,8113],"class_list":["post-26257","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-slide","category-cultura","tag-anselmo-rotondo","tag-carnevale","tag-carri-allegorici","tag-ciociaria","tag-frosinone","tag-katiuscia-mulattieri","tag-pontecorvo","tag-sfilate"],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v27.8 (Yoast SEO v27.8) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>A Pontecorvo il carnevale 2020... raddoppia - IlCorriereDellaProvincia.it - News h24 e notizie di approfondimento<\/title>\n<meta name=\"description\" content=\"Il Carnevale 2020 a Pontecorvo raddoppia: in programma le sfilate di domenica 16 e 23 febbraio con i carri allegorici che animeranno la citt\u00e0\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2020\/01\/14\/a-pontecorvo-il-carnevale-2020-raddoppia\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"A Pontecorvo il carnevale 2020... raddoppia\" \/>\n<meta property=\"og:description\" content=\"Il Carnevale 2020 a Pontecorvo raddoppia: in programma le sfilate di domenica 16 e 23 febbraio con i carri allegorici che animeranno la citt\u00e0\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2020\/01\/14\/a-pontecorvo-il-carnevale-2020-raddoppia\/\" \/>\n<meta property=\"og:site_name\" content=\"IlCorriereDellaProvincia.it - News h24 e notizie di approfondimento\" \/>\n<meta property=\"article:author\" content=\"www.facebook.com\/tunews24\" \/>\n<meta property=\"article:published_time\" content=\"2020-01-14T10:48:11+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2020-01-14T11:03:46+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2020\/01\/carnevale-pontecorvo-e1578998845555.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"632\" \/>\n\t<meta property=\"og:image:height\" content=\"371\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Redazione\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"Redazione\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"3 minuti\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2020\\\/01\\\/14\\\/a-pontecorvo-il-carnevale-2020-raddoppia\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2020\\\/01\\\/14\\\/a-pontecorvo-il-carnevale-2020-raddoppia\\\/\"},\"author\":{\"name\":\"Redazione\",\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/#\\\/schema\\\/person\\\/6d7f0a9120d0c03d0c552e9fdf49ed7d\"},\"headline\":\"A Pontecorvo il carnevale 2020&#8230; raddoppia\",\"datePublished\":\"2020-01-14T10:48:11+00:00\",\"dateModified\":\"2020-01-14T11:03:46+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2020\\\/01\\\/14\\\/a-pontecorvo-il-carnevale-2020-raddoppia\\\/\"},\"wordCount\":517,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2020\\\/01\\\/14\\\/a-pontecorvo-il-carnevale-2020-raddoppia\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2020\\\/01\\\/carnevale-pontecorvo-e1578998845555.jpg\",\"keywords\":[\"anselmo rotondo\",\"carnevale\",\"carri allegorici\",\"Ciociaria\",\"Frosinone\",\"katiuscia mulattieri\",\"pontecorvo\",\"sfilate\"],\"articleSection\":[\"*SLIDE*\",\"Cultura e Spettacolo\"],\"inLanguage\":\"it-IT\",\"copyrightYear\":\"2020\",\"copyrightHolder\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/#organization\"}},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2020\\\/01\\\/14\\\/a-pontecorvo-il-carnevale-2020-raddoppia\\\/\",\"url\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2020\\\/01\\\/14\\\/a-pontecorvo-il-carnevale-2020-raddoppia\\\/\",\"name\":\"A Pontecorvo il carnevale 2020... raddoppia - IlCorriereDellaProvincia.it - News h24 e notizie di approfondimento\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2020\\\/01\\\/14\\\/a-pontecorvo-il-carnevale-2020-raddoppia\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2020\\\/01\\\/14\\\/a-pontecorvo-il-carnevale-2020-raddoppia\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2020\\\/01\\\/carnevale-pontecorvo-e1578998845555.jpg\",\"datePublished\":\"2020-01-14T10:48:11+00:00\",\"dateModified\":\"2020-01-14T11:03:46+00:00\",\"description\":\"Il Carnevale 2020 a Pontecorvo raddoppia: in programma le sfilate di domenica 16 e 23 febbraio con i carri allegorici che animeranno la citt\u00e0\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2020\\\/01\\\/14\\\/a-pontecorvo-il-carnevale-2020-raddoppia\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2020\\\/01\\\/14\\\/a-pontecorvo-il-carnevale-2020-raddoppia\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2020\\\/01\\\/14\\\/a-pontecorvo-il-carnevale-2020-raddoppia\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2020\\\/01\\\/carnevale-pontecorvo-e1578998845555.jpg\",\"contentUrl\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2020\\\/01\\\/carnevale-pontecorvo-e1578998845555.jpg\",\"width\":632,\"height\":371,\"caption\":\"Carro di carnevale a Pontecorvo\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2020\\\/01\\\/14\\\/a-pontecorvo-il-carnevale-2020-raddoppia\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"A Pontecorvo il carnevale 2020&#8230; raddoppia\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/#website\",\"url\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/\",\"name\":\"Il Corriere Delle Provincia\",\"description\":\"IlCorriereDellaProvincia.it, quotidiano web di politica, cronaca, inchiesta, lavoro, scuola, turismo, cultura e spettacolo, economia e finanza, salute e benessere. Approfondimenti e notizie aggiornate con foto e video della provincia di Frosinone ma anche news nazionali, dell\u2019Italia e del Mondo.\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":[\"Organization\",\"Place\"],\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/#organization\",\"name\":\"Globalpress s.r.l.\",\"url\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/\",\"logo\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2020\\\/01\\\/14\\\/a-pontecorvo-il-carnevale-2020-raddoppia\\\/#local-main-organization-logo\"},\"image\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2020\\\/01\\\/14\\\/a-pontecorvo-il-carnevale-2020-raddoppia\\\/#local-main-organization-logo\"},\"telephone\":[],\"openingHoursSpecification\":[{\"@type\":\"OpeningHoursSpecification\",\"dayOfWeek\":[\"Monday\",\"Tuesday\",\"Wednesday\",\"Thursday\",\"Friday\",\"Saturday\",\"Sunday\"],\"opens\":\"09:00\",\"closes\":\"17:00\"}]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/#\\\/schema\\\/person\\\/6d7f0a9120d0c03d0c552e9fdf49ed7d\",\"name\":\"Redazione\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/a40eeacccdcad861f831dde73317f63a542e738f0dc4b79b9f47062d3d4bd1d2?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/a40eeacccdcad861f831dde73317f63a542e738f0dc4b79b9f47062d3d4bd1d2?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/a40eeacccdcad861f831dde73317f63a542e738f0dc4b79b9f47062d3d4bd1d2?s=96&d=mm&r=g\",\"caption\":\"Redazione\"},\"description\":\"SEGUICI ANCHE SUI SOCIAL Facebook: TuNews24 e TuSport24 Instagram: TuNews24 e TuSport24 Youtube: TuNews24 Telegram: TuNews24 Puoi leggerci anche in formato cartaceo: il settimanale viene pubblicato e distribuito gratuitamente ogni venerd\u00ec in edicole, bar, centri commerciali e svariati esercizi. Ma \u00e8 possibile anche sfogliarlo comodamente online, cliccando su TU NEWS sfogliabile TU NEWS, PASSIONE PER L\u2019INFORMAZIONE\",\"sameAs\":[\"http:\\\/\\\/www.tunews24.it\",\"www.facebook.com\\\/tunews24\"],\"url\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/author\\\/senzafirma\\\/\"},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2020\\\/01\\\/14\\\/a-pontecorvo-il-carnevale-2020-raddoppia\\\/#local-main-organization-logo\",\"url\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2022\\\/11\\\/cropped-il-corriere-della-provincia-testata-web-scontornata.png\",\"contentUrl\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2022\\\/11\\\/cropped-il-corriere-della-provincia-testata-web-scontornata.png\",\"width\":2911,\"height\":717,\"caption\":\"Globalpress s.r.l.\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"A Pontecorvo il carnevale 2020... raddoppia - IlCorriereDellaProvincia.it - News h24 e notizie di approfondimento","description":"Il Carnevale 2020 a Pontecorvo raddoppia: in programma le sfilate di domenica 16 e 23 febbraio con i carri allegorici che animeranno la citt\u00e0","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2020\/01\/14\/a-pontecorvo-il-carnevale-2020-raddoppia\/","og_locale":"it_IT","og_type":"article","og_title":"A Pontecorvo il carnevale 2020... raddoppia","og_description":"Il Carnevale 2020 a Pontecorvo raddoppia: in programma le sfilate di domenica 16 e 23 febbraio con i carri allegorici che animeranno la citt\u00e0","og_url":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2020\/01\/14\/a-pontecorvo-il-carnevale-2020-raddoppia\/","og_site_name":"IlCorriereDellaProvincia.it - News h24 e notizie di approfondimento","article_author":"www.facebook.com\/tunews24","article_published_time":"2020-01-14T10:48:11+00:00","article_modified_time":"2020-01-14T11:03:46+00:00","og_image":[{"width":632,"height":371,"url":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2020\/01\/carnevale-pontecorvo-e1578998845555.jpg","type":"image\/jpeg"}],"author":"Redazione","twitter_card":"summary_large_image","twitter_misc":{"Scritto da":"Redazione","Tempo di lettura stimato":"3 minuti"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2020\/01\/14\/a-pontecorvo-il-carnevale-2020-raddoppia\/#article","isPartOf":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2020\/01\/14\/a-pontecorvo-il-carnevale-2020-raddoppia\/"},"author":{"name":"Redazione","@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/#\/schema\/person\/6d7f0a9120d0c03d0c552e9fdf49ed7d"},"headline":"A Pontecorvo il carnevale 2020&#8230; raddoppia","datePublished":"2020-01-14T10:48:11+00:00","dateModified":"2020-01-14T11:03:46+00:00","mainEntityOfPage":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2020\/01\/14\/a-pontecorvo-il-carnevale-2020-raddoppia\/"},"wordCount":517,"commentCount":0,"publisher":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/#organization"},"image":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2020\/01\/14\/a-pontecorvo-il-carnevale-2020-raddoppia\/#primaryimage"},"thumbnailUrl":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2020\/01\/carnevale-pontecorvo-e1578998845555.jpg","keywords":["anselmo rotondo","carnevale","carri allegorici","Ciociaria","Frosinone","katiuscia mulattieri","pontecorvo","sfilate"],"articleSection":["*SLIDE*","Cultura e Spettacolo"],"inLanguage":"it-IT","copyrightYear":"2020","copyrightHolder":{"@id":"https:\/\/www.tunews24.it\/#organization"}},{"@type":"WebPage","@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2020\/01\/14\/a-pontecorvo-il-carnevale-2020-raddoppia\/","url":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2020\/01\/14\/a-pontecorvo-il-carnevale-2020-raddoppia\/","name":"A Pontecorvo il carnevale 2020... raddoppia - IlCorriereDellaProvincia.it - News h24 e notizie di approfondimento","isPartOf":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2020\/01\/14\/a-pontecorvo-il-carnevale-2020-raddoppia\/#primaryimage"},"image":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2020\/01\/14\/a-pontecorvo-il-carnevale-2020-raddoppia\/#primaryimage"},"thumbnailUrl":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2020\/01\/carnevale-pontecorvo-e1578998845555.jpg","datePublished":"2020-01-14T10:48:11+00:00","dateModified":"2020-01-14T11:03:46+00:00","description":"Il Carnevale 2020 a Pontecorvo raddoppia: in programma le sfilate di domenica 16 e 23 febbraio con i carri allegorici che animeranno la citt\u00e0","breadcrumb":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2020\/01\/14\/a-pontecorvo-il-carnevale-2020-raddoppia\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2020\/01\/14\/a-pontecorvo-il-carnevale-2020-raddoppia\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2020\/01\/14\/a-pontecorvo-il-carnevale-2020-raddoppia\/#primaryimage","url":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2020\/01\/carnevale-pontecorvo-e1578998845555.jpg","contentUrl":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2020\/01\/carnevale-pontecorvo-e1578998845555.jpg","width":632,"height":371,"caption":"Carro di carnevale a Pontecorvo"},{"@type":"BreadcrumbList","@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2020\/01\/14\/a-pontecorvo-il-carnevale-2020-raddoppia\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/"},{"@type":"ListItem","position":2,"name":"A Pontecorvo il carnevale 2020&#8230; raddoppia"}]},{"@type":"WebSite","@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/#website","url":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/","name":"Il Corriere Delle Provincia","description":"IlCorriereDellaProvincia.it, quotidiano web di politica, cronaca, inchiesta, lavoro, scuola, turismo, cultura e spettacolo, economia e finanza, salute e benessere. Approfondimenti e notizie aggiornate con foto e video della provincia di Frosinone ma anche news nazionali, dell\u2019Italia e del Mondo.","publisher":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":["Organization","Place"],"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/#organization","name":"Globalpress s.r.l.","url":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/","logo":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2020\/01\/14\/a-pontecorvo-il-carnevale-2020-raddoppia\/#local-main-organization-logo"},"image":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2020\/01\/14\/a-pontecorvo-il-carnevale-2020-raddoppia\/#local-main-organization-logo"},"telephone":[],"openingHoursSpecification":[{"@type":"OpeningHoursSpecification","dayOfWeek":["Monday","Tuesday","Wednesday","Thursday","Friday","Saturday","Sunday"],"opens":"09:00","closes":"17:00"}]},{"@type":"Person","@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/#\/schema\/person\/6d7f0a9120d0c03d0c552e9fdf49ed7d","name":"Redazione","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/secure.gravatar.com\/avatar\/a40eeacccdcad861f831dde73317f63a542e738f0dc4b79b9f47062d3d4bd1d2?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/a40eeacccdcad861f831dde73317f63a542e738f0dc4b79b9f47062d3d4bd1d2?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/a40eeacccdcad861f831dde73317f63a542e738f0dc4b79b9f47062d3d4bd1d2?s=96&d=mm&r=g","caption":"Redazione"},"description":"SEGUICI ANCHE SUI SOCIAL Facebook: TuNews24 e TuSport24 Instagram: TuNews24 e TuSport24 Youtube: TuNews24 Telegram: TuNews24 Puoi leggerci anche in formato cartaceo: il settimanale viene pubblicato e distribuito gratuitamente ogni venerd\u00ec in edicole, bar, centri commerciali e svariati esercizi. Ma \u00e8 possibile anche sfogliarlo comodamente online, cliccando su TU NEWS sfogliabile TU NEWS, PASSIONE PER L\u2019INFORMAZIONE","sameAs":["http:\/\/www.tunews24.it","www.facebook.com\/tunews24"],"url":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/author\/senzafirma\/"},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2020\/01\/14\/a-pontecorvo-il-carnevale-2020-raddoppia\/#local-main-organization-logo","url":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2022\/11\/cropped-il-corriere-della-provincia-testata-web-scontornata.png","contentUrl":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2022\/11\/cropped-il-corriere-della-provincia-testata-web-scontornata.png","width":2911,"height":717,"caption":"Globalpress s.r.l."}]}},"_links":{"self":[{"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/posts\/26257","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/users\/18"}],"replies":[{"embeddable":true,"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/comments?post=26257"}],"version-history":[{"count":3,"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/posts\/26257\/revisions"}],"predecessor-version":[{"id":26264,"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/posts\/26257\/revisions\/26264"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/media\/26258"}],"wp:attachment":[{"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/media?parent=26257"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/categories?post=26257"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/tags?post=26257"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}