{"id":25832,"date":"2020-01-07T13:19:14","date_gmt":"2020-01-07T12:19:14","guid":{"rendered":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/?p=25832"},"modified":"2020-01-08T14:16:03","modified_gmt":"2020-01-08T13:16:03","slug":"litiga-con-i-genitori-assume-farmaci-e-ruba-una-macchina-denunciato","status":"publish","type":"post","link":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2020\/01\/07\/litiga-con-i-genitori-assume-farmaci-e-ruba-una-macchina-denunciato\/","title":{"rendered":"Litiga con i genitori, assume farmaci e ruba un&#8217;auto: denunciato"},"content":{"rendered":"<p>Era andato con la famiglia a <strong>Filettino<\/strong> per <strong>trascorrere le vacanze natalizie<\/strong>. Ma qualcosa \u00e8 andato storto e, dopo una violenta lite con i genitori,<strong> \u00e8 uscito di casa e ha rubato una macchina<\/strong>, poi ritrovata a Piglio.<\/p>\n<h2>I fatti<\/h2>\n<p>A finire nei guai <strong>un trentunenne di Aprilia<\/strong> che \u00e8 stato <strong>denunciato dai carabinieri di Filettino<\/strong> dopo la querela sporta da una <strong>cinquantacinquenne romana<\/strong>, vittima del furto dell&#8217;auto.<\/p>\n<p>Il giovane, infatti, dopo aver litigato con i genitori e <strong>in evidente stato di alterazione<\/strong>, <strong>dovuto all&#8217;assunzione di alcol e psicofarmaci<\/strong>, ha lasciato la casa delle vacanze e, una volta in strada, ha rubato un&#8217;auto che ha trovato aperta e con le chiavi inserite.<\/p>\n<p>La donna, una volta accortasi del furto, ha sporto denuncia ai carabinieri che hanno subito avviato le indagini: hanno rintracciato il trentunenne, e di conseguenza l&#8217;auto, nel comune di Piglio.<strong> Il giovane, in evidente stato confusionale, \u00e8 stato trasferito dal 118 all&#8217;ospedale di Subiaco<\/strong> per accertamenti e cure mentre l&#8217;auto \u00e8 stata riconsegnata alla legittima proprietaria.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Era andato con la famiglia a Filettino per trascorrere le vacanze natalizie. Ma qualcosa \u00e8 andato storto e, dopo una<\/p>\n","protected":false},"author":18,"featured_media":24792,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[2],"tags":[267,1263,90,94,245,327,93,932,345,8008,6671,8009],"class_list":["post-25832","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-cronaca","tag-alcol","tag-auto","tag-carabinieri","tag-ciociaria","tag-denuncia","tag-filettino","tag-frosinone","tag-furto","tag-ospedale","tag-piscofarmaci","tag-proprietaria","tag-subiaco"],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v27.8 (Yoast SEO v27.8) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Litiga con i genitori, assume farmaci e ruba un&#039;auto: denunciato - IlCorriereDellaProvincia.it - News h24 e notizie di approfondimento<\/title>\n<meta name=\"description\" content=\"Ha litigato con i genitori mentre erano in vacanza a Filettino. Poi, dopo aver assunto alcol e farmaci, \u00e8 sceso in strada e ha rubato un&#039;auto. Denunciato\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2020\/01\/07\/litiga-con-i-genitori-assume-farmaci-e-ruba-una-macchina-denunciato\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Litiga con i genitori, assume farmaci e ruba un&#039;auto: denunciato\" \/>\n<meta property=\"og:description\" content=\"Ha litigato con i genitori mentre erano in vacanza a Filettino. Poi, dopo aver assunto alcol e farmaci, \u00e8 sceso in strada e ha rubato un&#039;auto. Denunciato\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2020\/01\/07\/litiga-con-i-genitori-assume-farmaci-e-ruba-una-macchina-denunciato\/\" \/>\n<meta property=\"og:site_name\" content=\"IlCorriereDellaProvincia.it - News h24 e notizie di approfondimento\" \/>\n<meta property=\"article:author\" content=\"www.facebook.com\/tunews24\" \/>\n<meta property=\"article:published_time\" content=\"2020-01-07T12:19:14+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2020-01-08T13:16:03+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2019\/12\/arresto-donna-carabinieri-e1576599925701.jpeg\" \/>\n\t<meta property=\"og:image:width\" content=\"700\" \/>\n\t<meta property=\"og:image:height\" content=\"406\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Redazione\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"Redazione\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2020\\\/01\\\/07\\\/litiga-con-i-genitori-assume-farmaci-e-ruba-una-macchina-denunciato\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2020\\\/01\\\/07\\\/litiga-con-i-genitori-assume-farmaci-e-ruba-una-macchina-denunciato\\\/\"},\"author\":{\"name\":\"Redazione\",\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/#\\\/schema\\\/person\\\/6d7f0a9120d0c03d0c552e9fdf49ed7d\"},\"headline\":\"Litiga con i genitori, assume farmaci e ruba un&#8217;auto: denunciato\",\"datePublished\":\"2020-01-07T12:19:14+00:00\",\"dateModified\":\"2020-01-08T13:16:03+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2020\\\/01\\\/07\\\/litiga-con-i-genitori-assume-farmaci-e-ruba-una-macchina-denunciato\\\/\"},\"wordCount\":179,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2020\\\/01\\\/07\\\/litiga-con-i-genitori-assume-farmaci-e-ruba-una-macchina-denunciato\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2019\\\/12\\\/arresto-donna-carabinieri-e1576599925701.jpeg\",\"keywords\":[\"alcol\",\"auto\",\"carabinieri\",\"Ciociaria\",\"denuncia\",\"filettino\",\"Frosinone\",\"Furto\",\"ospedale\",\"piscofarmaci\",\"proprietaria\",\"subiaco\"],\"articleSection\":[\"Cronaca\"],\"inLanguage\":\"it-IT\",\"copyrightYear\":\"2020\",\"copyrightHolder\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/#organization\"}},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2020\\\/01\\\/07\\\/litiga-con-i-genitori-assume-farmaci-e-ruba-una-macchina-denunciato\\\/\",\"url\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2020\\\/01\\\/07\\\/litiga-con-i-genitori-assume-farmaci-e-ruba-una-macchina-denunciato\\\/\",\"name\":\"Litiga con i genitori, assume farmaci e ruba un'auto: denunciato - IlCorriereDellaProvincia.it - News h24 e notizie di approfondimento\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2020\\\/01\\\/07\\\/litiga-con-i-genitori-assume-farmaci-e-ruba-una-macchina-denunciato\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2020\\\/01\\\/07\\\/litiga-con-i-genitori-assume-farmaci-e-ruba-una-macchina-denunciato\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2019\\\/12\\\/arresto-donna-carabinieri-e1576599925701.jpeg\",\"datePublished\":\"2020-01-07T12:19:14+00:00\",\"dateModified\":\"2020-01-08T13:16:03+00:00\",\"description\":\"Ha litigato con i genitori mentre erano in vacanza a Filettino. Poi, dopo aver assunto alcol e farmaci, \u00e8 sceso in strada e ha rubato un'auto. Denunciato\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2020\\\/01\\\/07\\\/litiga-con-i-genitori-assume-farmaci-e-ruba-una-macchina-denunciato\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2020\\\/01\\\/07\\\/litiga-con-i-genitori-assume-farmaci-e-ruba-una-macchina-denunciato\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2020\\\/01\\\/07\\\/litiga-con-i-genitori-assume-farmaci-e-ruba-una-macchina-denunciato\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2019\\\/12\\\/arresto-donna-carabinieri-e1576599925701.jpeg\",\"contentUrl\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2019\\\/12\\\/arresto-donna-carabinieri-e1576599925701.jpeg\",\"width\":700,\"height\":406,\"caption\":\"Arresto carabinieri\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2020\\\/01\\\/07\\\/litiga-con-i-genitori-assume-farmaci-e-ruba-una-macchina-denunciato\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Litiga con i genitori, assume farmaci e ruba un&#8217;auto: denunciato\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/#website\",\"url\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/\",\"name\":\"Il Corriere Delle Provincia\",\"description\":\"IlCorriereDellaProvincia.it, quotidiano web di politica, cronaca, inchiesta, lavoro, scuola, turismo, cultura e spettacolo, economia e finanza, salute e benessere. Approfondimenti e notizie aggiornate con foto e video della provincia di Frosinone ma anche news nazionali, dell\u2019Italia e del Mondo.\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":[\"Organization\",\"Place\"],\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/#organization\",\"name\":\"Globalpress s.r.l.\",\"url\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/\",\"logo\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2020\\\/01\\\/07\\\/litiga-con-i-genitori-assume-farmaci-e-ruba-una-macchina-denunciato\\\/#local-main-organization-logo\"},\"image\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2020\\\/01\\\/07\\\/litiga-con-i-genitori-assume-farmaci-e-ruba-una-macchina-denunciato\\\/#local-main-organization-logo\"},\"telephone\":[],\"openingHoursSpecification\":[{\"@type\":\"OpeningHoursSpecification\",\"dayOfWeek\":[\"Monday\",\"Tuesday\",\"Wednesday\",\"Thursday\",\"Friday\",\"Saturday\",\"Sunday\"],\"opens\":\"09:00\",\"closes\":\"17:00\"}]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/#\\\/schema\\\/person\\\/6d7f0a9120d0c03d0c552e9fdf49ed7d\",\"name\":\"Redazione\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/a40eeacccdcad861f831dde73317f63a542e738f0dc4b79b9f47062d3d4bd1d2?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/a40eeacccdcad861f831dde73317f63a542e738f0dc4b79b9f47062d3d4bd1d2?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/a40eeacccdcad861f831dde73317f63a542e738f0dc4b79b9f47062d3d4bd1d2?s=96&d=mm&r=g\",\"caption\":\"Redazione\"},\"description\":\"SEGUICI ANCHE SUI SOCIAL Facebook: TuNews24 e TuSport24 Instagram: TuNews24 e TuSport24 Youtube: TuNews24 Telegram: TuNews24 Puoi leggerci anche in formato cartaceo: il settimanale viene pubblicato e distribuito gratuitamente ogni venerd\u00ec in edicole, bar, centri commerciali e svariati esercizi. Ma \u00e8 possibile anche sfogliarlo comodamente online, cliccando su TU NEWS sfogliabile TU NEWS, PASSIONE PER L\u2019INFORMAZIONE\",\"sameAs\":[\"http:\\\/\\\/www.tunews24.it\",\"www.facebook.com\\\/tunews24\"],\"url\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/author\\\/senzafirma\\\/\"},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2020\\\/01\\\/07\\\/litiga-con-i-genitori-assume-farmaci-e-ruba-una-macchina-denunciato\\\/#local-main-organization-logo\",\"url\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2022\\\/11\\\/cropped-il-corriere-della-provincia-testata-web-scontornata.png\",\"contentUrl\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2022\\\/11\\\/cropped-il-corriere-della-provincia-testata-web-scontornata.png\",\"width\":2911,\"height\":717,\"caption\":\"Globalpress s.r.l.\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Litiga con i genitori, assume farmaci e ruba un'auto: denunciato - IlCorriereDellaProvincia.it - News h24 e notizie di approfondimento","description":"Ha litigato con i genitori mentre erano in vacanza a Filettino. Poi, dopo aver assunto alcol e farmaci, \u00e8 sceso in strada e ha rubato un'auto. Denunciato","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2020\/01\/07\/litiga-con-i-genitori-assume-farmaci-e-ruba-una-macchina-denunciato\/","og_locale":"it_IT","og_type":"article","og_title":"Litiga con i genitori, assume farmaci e ruba un'auto: denunciato","og_description":"Ha litigato con i genitori mentre erano in vacanza a Filettino. Poi, dopo aver assunto alcol e farmaci, \u00e8 sceso in strada e ha rubato un'auto. Denunciato","og_url":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2020\/01\/07\/litiga-con-i-genitori-assume-farmaci-e-ruba-una-macchina-denunciato\/","og_site_name":"IlCorriereDellaProvincia.it - News h24 e notizie di approfondimento","article_author":"www.facebook.com\/tunews24","article_published_time":"2020-01-07T12:19:14+00:00","article_modified_time":"2020-01-08T13:16:03+00:00","og_image":[{"width":700,"height":406,"url":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2019\/12\/arresto-donna-carabinieri-e1576599925701.jpeg","type":"image\/jpeg"}],"author":"Redazione","twitter_card":"summary_large_image","twitter_misc":{"Scritto da":"Redazione","Tempo di lettura stimato":"1 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2020\/01\/07\/litiga-con-i-genitori-assume-farmaci-e-ruba-una-macchina-denunciato\/#article","isPartOf":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2020\/01\/07\/litiga-con-i-genitori-assume-farmaci-e-ruba-una-macchina-denunciato\/"},"author":{"name":"Redazione","@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/#\/schema\/person\/6d7f0a9120d0c03d0c552e9fdf49ed7d"},"headline":"Litiga con i genitori, assume farmaci e ruba un&#8217;auto: denunciato","datePublished":"2020-01-07T12:19:14+00:00","dateModified":"2020-01-08T13:16:03+00:00","mainEntityOfPage":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2020\/01\/07\/litiga-con-i-genitori-assume-farmaci-e-ruba-una-macchina-denunciato\/"},"wordCount":179,"commentCount":0,"publisher":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/#organization"},"image":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2020\/01\/07\/litiga-con-i-genitori-assume-farmaci-e-ruba-una-macchina-denunciato\/#primaryimage"},"thumbnailUrl":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2019\/12\/arresto-donna-carabinieri-e1576599925701.jpeg","keywords":["alcol","auto","carabinieri","Ciociaria","denuncia","filettino","Frosinone","Furto","ospedale","piscofarmaci","proprietaria","subiaco"],"articleSection":["Cronaca"],"inLanguage":"it-IT","copyrightYear":"2020","copyrightHolder":{"@id":"https:\/\/www.tunews24.it\/#organization"}},{"@type":"WebPage","@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2020\/01\/07\/litiga-con-i-genitori-assume-farmaci-e-ruba-una-macchina-denunciato\/","url":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2020\/01\/07\/litiga-con-i-genitori-assume-farmaci-e-ruba-una-macchina-denunciato\/","name":"Litiga con i genitori, assume farmaci e ruba un'auto: denunciato - IlCorriereDellaProvincia.it - News h24 e notizie di approfondimento","isPartOf":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2020\/01\/07\/litiga-con-i-genitori-assume-farmaci-e-ruba-una-macchina-denunciato\/#primaryimage"},"image":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2020\/01\/07\/litiga-con-i-genitori-assume-farmaci-e-ruba-una-macchina-denunciato\/#primaryimage"},"thumbnailUrl":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2019\/12\/arresto-donna-carabinieri-e1576599925701.jpeg","datePublished":"2020-01-07T12:19:14+00:00","dateModified":"2020-01-08T13:16:03+00:00","description":"Ha litigato con i genitori mentre erano in vacanza a Filettino. Poi, dopo aver assunto alcol e farmaci, \u00e8 sceso in strada e ha rubato un'auto. Denunciato","breadcrumb":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2020\/01\/07\/litiga-con-i-genitori-assume-farmaci-e-ruba-una-macchina-denunciato\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2020\/01\/07\/litiga-con-i-genitori-assume-farmaci-e-ruba-una-macchina-denunciato\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2020\/01\/07\/litiga-con-i-genitori-assume-farmaci-e-ruba-una-macchina-denunciato\/#primaryimage","url":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2019\/12\/arresto-donna-carabinieri-e1576599925701.jpeg","contentUrl":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2019\/12\/arresto-donna-carabinieri-e1576599925701.jpeg","width":700,"height":406,"caption":"Arresto carabinieri"},{"@type":"BreadcrumbList","@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2020\/01\/07\/litiga-con-i-genitori-assume-farmaci-e-ruba-una-macchina-denunciato\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/"},{"@type":"ListItem","position":2,"name":"Litiga con i genitori, assume farmaci e ruba un&#8217;auto: denunciato"}]},{"@type":"WebSite","@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/#website","url":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/","name":"Il Corriere Delle Provincia","description":"IlCorriereDellaProvincia.it, quotidiano web di politica, cronaca, inchiesta, lavoro, scuola, turismo, cultura e spettacolo, economia e finanza, salute e benessere. Approfondimenti e notizie aggiornate con foto e video della provincia di Frosinone ma anche news nazionali, dell\u2019Italia e del Mondo.","publisher":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":["Organization","Place"],"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/#organization","name":"Globalpress s.r.l.","url":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/","logo":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2020\/01\/07\/litiga-con-i-genitori-assume-farmaci-e-ruba-una-macchina-denunciato\/#local-main-organization-logo"},"image":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2020\/01\/07\/litiga-con-i-genitori-assume-farmaci-e-ruba-una-macchina-denunciato\/#local-main-organization-logo"},"telephone":[],"openingHoursSpecification":[{"@type":"OpeningHoursSpecification","dayOfWeek":["Monday","Tuesday","Wednesday","Thursday","Friday","Saturday","Sunday"],"opens":"09:00","closes":"17:00"}]},{"@type":"Person","@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/#\/schema\/person\/6d7f0a9120d0c03d0c552e9fdf49ed7d","name":"Redazione","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/secure.gravatar.com\/avatar\/a40eeacccdcad861f831dde73317f63a542e738f0dc4b79b9f47062d3d4bd1d2?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/a40eeacccdcad861f831dde73317f63a542e738f0dc4b79b9f47062d3d4bd1d2?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/a40eeacccdcad861f831dde73317f63a542e738f0dc4b79b9f47062d3d4bd1d2?s=96&d=mm&r=g","caption":"Redazione"},"description":"SEGUICI ANCHE SUI SOCIAL Facebook: TuNews24 e TuSport24 Instagram: TuNews24 e TuSport24 Youtube: TuNews24 Telegram: TuNews24 Puoi leggerci anche in formato cartaceo: il settimanale viene pubblicato e distribuito gratuitamente ogni venerd\u00ec in edicole, bar, centri commerciali e svariati esercizi. Ma \u00e8 possibile anche sfogliarlo comodamente online, cliccando su TU NEWS sfogliabile TU NEWS, PASSIONE PER L\u2019INFORMAZIONE","sameAs":["http:\/\/www.tunews24.it","www.facebook.com\/tunews24"],"url":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/author\/senzafirma\/"},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2020\/01\/07\/litiga-con-i-genitori-assume-farmaci-e-ruba-una-macchina-denunciato\/#local-main-organization-logo","url":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2022\/11\/cropped-il-corriere-della-provincia-testata-web-scontornata.png","contentUrl":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2022\/11\/cropped-il-corriere-della-provincia-testata-web-scontornata.png","width":2911,"height":717,"caption":"Globalpress s.r.l."}]}},"_links":{"self":[{"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/posts\/25832","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/users\/18"}],"replies":[{"embeddable":true,"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/comments?post=25832"}],"version-history":[{"count":2,"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/posts\/25832\/revisions"}],"predecessor-version":[{"id":25834,"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/posts\/25832\/revisions\/25834"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/media\/24792"}],"wp:attachment":[{"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/media?parent=25832"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/categories?post=25832"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/tags?post=25832"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}