{"id":25821,"date":"2020-01-07T11:00:02","date_gmt":"2020-01-07T10:00:02","guid":{"rendered":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/?p=25821"},"modified":"2020-01-07T11:00:02","modified_gmt":"2020-01-07T10:00:02","slug":"caos-barelle-allo-spaziani-e-ambulanze-bloccate-appello-di-quadrini-a-lorusso","status":"publish","type":"post","link":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2020\/01\/07\/caos-barelle-allo-spaziani-e-ambulanze-bloccate-appello-di-quadrini-a-lorusso\/","title":{"rendered":"Caos barelle allo &#8216;Spaziani&#8217; e ambulanze bloccate: appello di Quadrini a Lorusso"},"content":{"rendered":"<p lang=\"it-IT\">Un&#8217;emergenza ciclica che, a quanto pare, continua anche nel nuovo anno. \u00c8 quella delle <strong>ambulanze ferme nei Pronto Soccorso<\/strong> a causa della<strong> mancanza di posti letto delle strutture ospedaliere<\/strong> che costringono i pazienti a restare per ore sulle barelle del 118.<\/p>\n<p lang=\"it-IT\"><span lang=\"it-IT\">Una criticit\u00e0 purtroppo cronica che si \u00e8 verificata anche<strong> nei giorni scorsi a Frosinone<\/strong>: all&#8217;ospedale &#8216;Fabrizio Spaziani&#8217;<strong> sono rimaste ferme fino a 15 ambulanze<\/strong><\/span><span style=\"font-size: medium\">. <\/span><\/p>\n<h2>Disagi e costi per la collettivit\u00e0<\/h2>\n<p lang=\"it-IT\"><span style=\"font-size: medium\">Il disagio, fanno sapere alcuni operatori sanitari, determina ogni volta la drastica riduzione del gi\u00e0 esiguo numero di ambulanze di soccorso avanzato e ritardi dei soccorsi su patologie tempo-dipendenti, comportando, inoltre, difficolt\u00e0 e rallentamenti nella gestione dei soccorsi per la centrale operativa del 118.<\/span><\/p>\n<p lang=\"it-IT\">\n<p lang=\"it-IT\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter wp-image-4020 size-full\" src=\"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2018\/12\/posti-letto-ospedale-e1546167235638.jpg\" alt=\"\" width=\"632\" height=\"351\" \/><\/p>\n<p lang=\"it-IT\">\n<p>Ma non solo: la carenza di mezzi di soccorso &#8216;operativi&#8217; determinata dal blocco delle barelle costa alle casse pubbliche cifre piuttosto importanti; lo scorso anno l\u2019attivazione di ambulanze &#8216;spot&#8217; (autoambulanze occasionali, che entrano in servizio a chiamata, giorno per giorno) \u00e8 costata 6 milioni e 394 mila euro, pari a una media di 17.517 euro al giorno, come quantificato dalla stessa Ares 118 nel suo bilancio consuntivo.<\/p>\n<h2>L&#8217;intervento di Quadrini<\/h2>\n<p>Sulla questione, tra gli altri interventi, si registra oggi quello del <strong>consigliere provinciale e vicecoordinatore regionale di FI, Gianluca Quadrini<\/strong>, che parla di &#8220;quadro sanitario critico&#8221; in provincia di Frosinone, dove \u00e8 necessaria una concreta soluzione per il bene della comunit\u00e0.<\/p>\n<p>&nbsp;<\/p>\n<figure id=\"attachment_4901\" aria-describedby=\"caption-attachment-4901\" style=\"width: 531px\" class=\"wp-caption aligncenter\"><img loading=\"lazy\" decoding=\"async\" class=\"wp-image-4901 size-full\" src=\"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2019\/01\/gianluca-quadrini.jpg\" alt=\"consigliere gianluca quadrini frosinone il corriere della provincia\" width=\"531\" height=\"370\" srcset=\"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2019\/01\/gianluca-quadrini.jpg 531w, https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2019\/01\/gianluca-quadrini-300x209.jpg 300w, https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2019\/01\/gianluca-quadrini-500x348.jpg 500w, https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2019\/01\/gianluca-quadrini-392x272.jpg 392w, https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2019\/01\/gianluca-quadrini-130x90.jpg 130w\" sizes=\"auto, (max-width: 531px) 100vw, 531px\" \/><figcaption id=\"caption-attachment-4901\" class=\"wp-caption-text\">Il consigliere provinciale e vice coordinatore regionale di FI Gianluca Quadrini<\/figcaption><\/figure>\n<p>&nbsp;<\/p>\n<p>&#8220;La logica dell&#8217;emergenza sanitaria in Ciociaria \u2013 sottolinea &#8211; \u00e8 diventata intollerabile e i cittadini sono davvero stanchi.<strong> Il problema della carenza delle lettighe va avanti da tempo<\/strong> e nel 2020 non \u00e8 pi\u00f9 tollerabile. Faccio appello alla sensibilit\u00e0 del direttore generale Asl, il dottor Stefano Lorusso, affinch\u00e8 si possa porre fine all&#8217;annoso problema&#8221;.<\/p>\n<h2>Prime misure contro l&#8217;emergenza<\/h2>\n<p class=\"western\"><span style=\"font-size: medium\">Intanto, la direzione aziendale della Asl provinciale sta provando a correre ai ripari con una manovra &#8216;salva-barelle&#8217; e il direttore Asl di Frosinone Lorusso ha reso noto di <strong>aver proceduto a bandire una gara per l\u2019acquisto di 68 nuovi letti<\/strong> di cui dotare il pronto soccorso dello Spaziani per evitare di trattenere quelli delle ambulanze. <\/span><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Un&#8217;emergenza ciclica che, a quanto pare, continua anche nel nuovo anno. \u00c8 quella delle ambulanze ferme nei Pronto Soccorso a<\/p>\n","protected":false},"author":18,"featured_media":9372,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[41,11],"tags":[261,782,1582,94,1902,93,1251,8003,774,107,484,5394],"class_list":["post-25821","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-slide","category-salute","tag-261","tag-ambulanze","tag-barelle","tag-ciociaria","tag-direttore-generale","tag-frosinone","tag-gianluca-quadrini","tag-lettighe","tag-pronto-soccorso","tag-sanita","tag-spaziani","tag-stefano-lorusso"],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v27.8 (Yoast SEO v27.8) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Caos barelle allo &#039;Spaziani&#039; e ambulanze bloccate: appello di Quadrini a Lorusso - IlCorriereDellaProvincia.it - News h24 e notizie di approfondimento<\/title>\n<meta name=\"description\" content=\"Ambulanze bloccate perch\u00e9 prive di barelle a causa della mancanza di posti letto negli ospedali: Gianluca Quadrini fa appello al dg Asl Lorusso\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2020\/01\/07\/caos-barelle-allo-spaziani-e-ambulanze-bloccate-appello-di-quadrini-a-lorusso\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Caos barelle allo &#039;Spaziani&#039; e ambulanze bloccate: appello di Quadrini a Lorusso\" \/>\n<meta property=\"og:description\" content=\"Ambulanze bloccate perch\u00e9 prive di barelle a causa della mancanza di posti letto negli ospedali: Gianluca Quadrini fa appello al dg Asl Lorusso\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2020\/01\/07\/caos-barelle-allo-spaziani-e-ambulanze-bloccate-appello-di-quadrini-a-lorusso\/\" \/>\n<meta property=\"og:site_name\" content=\"IlCorriereDellaProvincia.it - News h24 e notizie di approfondimento\" \/>\n<meta property=\"article:author\" content=\"www.facebook.com\/tunews24\" \/>\n<meta property=\"article:published_time\" content=\"2020-01-07T10:00:02+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2019\/04\/ambulanze-pronto-soccorso.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"620\" \/>\n\t<meta property=\"og:image:height\" content=\"339\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Redazione\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"Redazione\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minuti\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2020\\\/01\\\/07\\\/caos-barelle-allo-spaziani-e-ambulanze-bloccate-appello-di-quadrini-a-lorusso\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2020\\\/01\\\/07\\\/caos-barelle-allo-spaziani-e-ambulanze-bloccate-appello-di-quadrini-a-lorusso\\\/\"},\"author\":{\"name\":\"Redazione\",\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/#\\\/schema\\\/person\\\/6d7f0a9120d0c03d0c552e9fdf49ed7d\"},\"headline\":\"Caos barelle allo &#8216;Spaziani&#8217; e ambulanze bloccate: appello di Quadrini a Lorusso\",\"datePublished\":\"2020-01-07T10:00:02+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2020\\\/01\\\/07\\\/caos-barelle-allo-spaziani-e-ambulanze-bloccate-appello-di-quadrini-a-lorusso\\\/\"},\"wordCount\":363,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2020\\\/01\\\/07\\\/caos-barelle-allo-spaziani-e-ambulanze-bloccate-appello-di-quadrini-a-lorusso\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2019\\\/04\\\/ambulanze-pronto-soccorso.jpg\",\"keywords\":[\"118\",\"ambulanze\",\"barelle\",\"Ciociaria\",\"direttore generale\",\"Frosinone\",\"Gianluca Quadrini\",\"lettighe\",\"pronto soccorso\",\"Sanit\u00e0\",\"spaziani\",\"Stefano Lorusso\"],\"articleSection\":[\"*SLIDE*\",\"Salute e Benessere\"],\"inLanguage\":\"it-IT\",\"copyrightYear\":\"2020\",\"copyrightHolder\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/#organization\"}},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2020\\\/01\\\/07\\\/caos-barelle-allo-spaziani-e-ambulanze-bloccate-appello-di-quadrini-a-lorusso\\\/\",\"url\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2020\\\/01\\\/07\\\/caos-barelle-allo-spaziani-e-ambulanze-bloccate-appello-di-quadrini-a-lorusso\\\/\",\"name\":\"Caos barelle allo 'Spaziani' e ambulanze bloccate: appello di Quadrini a Lorusso - IlCorriereDellaProvincia.it - News h24 e notizie di approfondimento\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2020\\\/01\\\/07\\\/caos-barelle-allo-spaziani-e-ambulanze-bloccate-appello-di-quadrini-a-lorusso\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2020\\\/01\\\/07\\\/caos-barelle-allo-spaziani-e-ambulanze-bloccate-appello-di-quadrini-a-lorusso\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2019\\\/04\\\/ambulanze-pronto-soccorso.jpg\",\"datePublished\":\"2020-01-07T10:00:02+00:00\",\"description\":\"Ambulanze bloccate perch\u00e9 prive di barelle a causa della mancanza di posti letto negli ospedali: Gianluca Quadrini fa appello al dg Asl Lorusso\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2020\\\/01\\\/07\\\/caos-barelle-allo-spaziani-e-ambulanze-bloccate-appello-di-quadrini-a-lorusso\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2020\\\/01\\\/07\\\/caos-barelle-allo-spaziani-e-ambulanze-bloccate-appello-di-quadrini-a-lorusso\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2020\\\/01\\\/07\\\/caos-barelle-allo-spaziani-e-ambulanze-bloccate-appello-di-quadrini-a-lorusso\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2019\\\/04\\\/ambulanze-pronto-soccorso.jpg\",\"contentUrl\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2019\\\/04\\\/ambulanze-pronto-soccorso.jpg\",\"width\":620,\"height\":339,\"caption\":\"Le ambulanze al Pronto soccorso dell'ospedale 'Fabrizio Spaziani' di Frosinone\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2020\\\/01\\\/07\\\/caos-barelle-allo-spaziani-e-ambulanze-bloccate-appello-di-quadrini-a-lorusso\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Caos barelle allo &#8216;Spaziani&#8217; e ambulanze bloccate: appello di Quadrini a Lorusso\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/#website\",\"url\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/\",\"name\":\"Il Corriere Delle Provincia\",\"description\":\"IlCorriereDellaProvincia.it, quotidiano web di politica, cronaca, inchiesta, lavoro, scuola, turismo, cultura e spettacolo, economia e finanza, salute e benessere. Approfondimenti e notizie aggiornate con foto e video della provincia di Frosinone ma anche news nazionali, dell\u2019Italia e del Mondo.\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":[\"Organization\",\"Place\"],\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/#organization\",\"name\":\"Globalpress s.r.l.\",\"url\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/\",\"logo\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2020\\\/01\\\/07\\\/caos-barelle-allo-spaziani-e-ambulanze-bloccate-appello-di-quadrini-a-lorusso\\\/#local-main-organization-logo\"},\"image\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2020\\\/01\\\/07\\\/caos-barelle-allo-spaziani-e-ambulanze-bloccate-appello-di-quadrini-a-lorusso\\\/#local-main-organization-logo\"},\"telephone\":[],\"openingHoursSpecification\":[{\"@type\":\"OpeningHoursSpecification\",\"dayOfWeek\":[\"Monday\",\"Tuesday\",\"Wednesday\",\"Thursday\",\"Friday\",\"Saturday\",\"Sunday\"],\"opens\":\"09:00\",\"closes\":\"17:00\"}]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/#\\\/schema\\\/person\\\/6d7f0a9120d0c03d0c552e9fdf49ed7d\",\"name\":\"Redazione\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/a40eeacccdcad861f831dde73317f63a542e738f0dc4b79b9f47062d3d4bd1d2?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/a40eeacccdcad861f831dde73317f63a542e738f0dc4b79b9f47062d3d4bd1d2?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/a40eeacccdcad861f831dde73317f63a542e738f0dc4b79b9f47062d3d4bd1d2?s=96&d=mm&r=g\",\"caption\":\"Redazione\"},\"description\":\"SEGUICI ANCHE SUI SOCIAL Facebook: TuNews24 e TuSport24 Instagram: TuNews24 e TuSport24 Youtube: TuNews24 Telegram: TuNews24 Puoi leggerci anche in formato cartaceo: il settimanale viene pubblicato e distribuito gratuitamente ogni venerd\u00ec in edicole, bar, centri commerciali e svariati esercizi. Ma \u00e8 possibile anche sfogliarlo comodamente online, cliccando su TU NEWS sfogliabile TU NEWS, PASSIONE PER L\u2019INFORMAZIONE\",\"sameAs\":[\"http:\\\/\\\/www.tunews24.it\",\"www.facebook.com\\\/tunews24\"],\"url\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/author\\\/senzafirma\\\/\"},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2020\\\/01\\\/07\\\/caos-barelle-allo-spaziani-e-ambulanze-bloccate-appello-di-quadrini-a-lorusso\\\/#local-main-organization-logo\",\"url\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2022\\\/11\\\/cropped-il-corriere-della-provincia-testata-web-scontornata.png\",\"contentUrl\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2022\\\/11\\\/cropped-il-corriere-della-provincia-testata-web-scontornata.png\",\"width\":2911,\"height\":717,\"caption\":\"Globalpress s.r.l.\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Caos barelle allo 'Spaziani' e ambulanze bloccate: appello di Quadrini a Lorusso - IlCorriereDellaProvincia.it - News h24 e notizie di approfondimento","description":"Ambulanze bloccate perch\u00e9 prive di barelle a causa della mancanza di posti letto negli ospedali: Gianluca Quadrini fa appello al dg Asl Lorusso","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2020\/01\/07\/caos-barelle-allo-spaziani-e-ambulanze-bloccate-appello-di-quadrini-a-lorusso\/","og_locale":"it_IT","og_type":"article","og_title":"Caos barelle allo 'Spaziani' e ambulanze bloccate: appello di Quadrini a Lorusso","og_description":"Ambulanze bloccate perch\u00e9 prive di barelle a causa della mancanza di posti letto negli ospedali: Gianluca Quadrini fa appello al dg Asl Lorusso","og_url":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2020\/01\/07\/caos-barelle-allo-spaziani-e-ambulanze-bloccate-appello-di-quadrini-a-lorusso\/","og_site_name":"IlCorriereDellaProvincia.it - News h24 e notizie di approfondimento","article_author":"www.facebook.com\/tunews24","article_published_time":"2020-01-07T10:00:02+00:00","og_image":[{"width":620,"height":339,"url":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2019\/04\/ambulanze-pronto-soccorso.jpg","type":"image\/jpeg"}],"author":"Redazione","twitter_card":"summary_large_image","twitter_misc":{"Scritto da":"Redazione","Tempo di lettura stimato":"2 minuti"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2020\/01\/07\/caos-barelle-allo-spaziani-e-ambulanze-bloccate-appello-di-quadrini-a-lorusso\/#article","isPartOf":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2020\/01\/07\/caos-barelle-allo-spaziani-e-ambulanze-bloccate-appello-di-quadrini-a-lorusso\/"},"author":{"name":"Redazione","@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/#\/schema\/person\/6d7f0a9120d0c03d0c552e9fdf49ed7d"},"headline":"Caos barelle allo &#8216;Spaziani&#8217; e ambulanze bloccate: appello di Quadrini a Lorusso","datePublished":"2020-01-07T10:00:02+00:00","mainEntityOfPage":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2020\/01\/07\/caos-barelle-allo-spaziani-e-ambulanze-bloccate-appello-di-quadrini-a-lorusso\/"},"wordCount":363,"commentCount":0,"publisher":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/#organization"},"image":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2020\/01\/07\/caos-barelle-allo-spaziani-e-ambulanze-bloccate-appello-di-quadrini-a-lorusso\/#primaryimage"},"thumbnailUrl":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2019\/04\/ambulanze-pronto-soccorso.jpg","keywords":["118","ambulanze","barelle","Ciociaria","direttore generale","Frosinone","Gianluca Quadrini","lettighe","pronto soccorso","Sanit\u00e0","spaziani","Stefano Lorusso"],"articleSection":["*SLIDE*","Salute e Benessere"],"inLanguage":"it-IT","copyrightYear":"2020","copyrightHolder":{"@id":"https:\/\/www.tunews24.it\/#organization"}},{"@type":"WebPage","@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2020\/01\/07\/caos-barelle-allo-spaziani-e-ambulanze-bloccate-appello-di-quadrini-a-lorusso\/","url":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2020\/01\/07\/caos-barelle-allo-spaziani-e-ambulanze-bloccate-appello-di-quadrini-a-lorusso\/","name":"Caos barelle allo 'Spaziani' e ambulanze bloccate: appello di Quadrini a Lorusso - IlCorriereDellaProvincia.it - News h24 e notizie di approfondimento","isPartOf":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2020\/01\/07\/caos-barelle-allo-spaziani-e-ambulanze-bloccate-appello-di-quadrini-a-lorusso\/#primaryimage"},"image":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2020\/01\/07\/caos-barelle-allo-spaziani-e-ambulanze-bloccate-appello-di-quadrini-a-lorusso\/#primaryimage"},"thumbnailUrl":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2019\/04\/ambulanze-pronto-soccorso.jpg","datePublished":"2020-01-07T10:00:02+00:00","description":"Ambulanze bloccate perch\u00e9 prive di barelle a causa della mancanza di posti letto negli ospedali: Gianluca Quadrini fa appello al dg Asl Lorusso","breadcrumb":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2020\/01\/07\/caos-barelle-allo-spaziani-e-ambulanze-bloccate-appello-di-quadrini-a-lorusso\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2020\/01\/07\/caos-barelle-allo-spaziani-e-ambulanze-bloccate-appello-di-quadrini-a-lorusso\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2020\/01\/07\/caos-barelle-allo-spaziani-e-ambulanze-bloccate-appello-di-quadrini-a-lorusso\/#primaryimage","url":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2019\/04\/ambulanze-pronto-soccorso.jpg","contentUrl":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2019\/04\/ambulanze-pronto-soccorso.jpg","width":620,"height":339,"caption":"Le ambulanze al Pronto soccorso dell'ospedale 'Fabrizio Spaziani' di Frosinone"},{"@type":"BreadcrumbList","@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2020\/01\/07\/caos-barelle-allo-spaziani-e-ambulanze-bloccate-appello-di-quadrini-a-lorusso\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/"},{"@type":"ListItem","position":2,"name":"Caos barelle allo &#8216;Spaziani&#8217; e ambulanze bloccate: appello di Quadrini a Lorusso"}]},{"@type":"WebSite","@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/#website","url":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/","name":"Il Corriere Delle Provincia","description":"IlCorriereDellaProvincia.it, quotidiano web di politica, cronaca, inchiesta, lavoro, scuola, turismo, cultura e spettacolo, economia e finanza, salute e benessere. Approfondimenti e notizie aggiornate con foto e video della provincia di Frosinone ma anche news nazionali, dell\u2019Italia e del Mondo.","publisher":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":["Organization","Place"],"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/#organization","name":"Globalpress s.r.l.","url":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/","logo":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2020\/01\/07\/caos-barelle-allo-spaziani-e-ambulanze-bloccate-appello-di-quadrini-a-lorusso\/#local-main-organization-logo"},"image":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2020\/01\/07\/caos-barelle-allo-spaziani-e-ambulanze-bloccate-appello-di-quadrini-a-lorusso\/#local-main-organization-logo"},"telephone":[],"openingHoursSpecification":[{"@type":"OpeningHoursSpecification","dayOfWeek":["Monday","Tuesday","Wednesday","Thursday","Friday","Saturday","Sunday"],"opens":"09:00","closes":"17:00"}]},{"@type":"Person","@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/#\/schema\/person\/6d7f0a9120d0c03d0c552e9fdf49ed7d","name":"Redazione","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/secure.gravatar.com\/avatar\/a40eeacccdcad861f831dde73317f63a542e738f0dc4b79b9f47062d3d4bd1d2?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/a40eeacccdcad861f831dde73317f63a542e738f0dc4b79b9f47062d3d4bd1d2?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/a40eeacccdcad861f831dde73317f63a542e738f0dc4b79b9f47062d3d4bd1d2?s=96&d=mm&r=g","caption":"Redazione"},"description":"SEGUICI ANCHE SUI SOCIAL Facebook: TuNews24 e TuSport24 Instagram: TuNews24 e TuSport24 Youtube: TuNews24 Telegram: TuNews24 Puoi leggerci anche in formato cartaceo: il settimanale viene pubblicato e distribuito gratuitamente ogni venerd\u00ec in edicole, bar, centri commerciali e svariati esercizi. Ma \u00e8 possibile anche sfogliarlo comodamente online, cliccando su TU NEWS sfogliabile TU NEWS, PASSIONE PER L\u2019INFORMAZIONE","sameAs":["http:\/\/www.tunews24.it","www.facebook.com\/tunews24"],"url":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/author\/senzafirma\/"},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2020\/01\/07\/caos-barelle-allo-spaziani-e-ambulanze-bloccate-appello-di-quadrini-a-lorusso\/#local-main-organization-logo","url":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2022\/11\/cropped-il-corriere-della-provincia-testata-web-scontornata.png","contentUrl":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2022\/11\/cropped-il-corriere-della-provincia-testata-web-scontornata.png","width":2911,"height":717,"caption":"Globalpress s.r.l."}]}},"_links":{"self":[{"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/posts\/25821","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/users\/18"}],"replies":[{"embeddable":true,"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/comments?post=25821"}],"version-history":[{"count":1,"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/posts\/25821\/revisions"}],"predecessor-version":[{"id":25822,"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/posts\/25821\/revisions\/25822"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/media\/9372"}],"wp:attachment":[{"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/media?parent=25821"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/categories?post=25821"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/tags?post=25821"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}