{"id":25720,"date":"2020-01-04T11:06:55","date_gmt":"2020-01-04T10:06:55","guid":{"rendered":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/?p=25720"},"modified":"2020-01-05T09:34:21","modified_gmt":"2020-01-05T08:34:21","slug":"fca-ciacciarelli-2019-annus-horribilis-servono-maggiori-garanzie","status":"publish","type":"post","link":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2020\/01\/04\/fca-ciacciarelli-2019-annus-horribilis-servono-maggiori-garanzie\/","title":{"rendered":"Fca, Ciacciarelli: &#8220;2019  annus horribilis. Servono maggiori garanzie&#8221;"},"content":{"rendered":"<div dir=\"auto\">\u201c<strong>Il 2019 \u00e8 stato un anno pessimo in cui si \u00e8 registrato il record di cassa integrazione<\/strong>. La pi\u00f9 grande azienda del Lazio Meridionale, la Fiat Chrysler sta chiudendo l\u2019anno con ben 110 giorni di stop produttivo&#8221;.\u00a0<strong>Cos\u00ec il consigliere regionale del Lazio Pasquale Ciacciarelli.<\/strong><\/div>\n<div dir=\"auto\"><\/div>\n<div dir=\"auto\"><img loading=\"lazy\" decoding=\"async\" class=\"wp-image-1470 aligncenter\" src=\"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2018\/11\/fca-cassino.jpg\" alt=\"Fca cassino alfa romeo fiat frosinone regione lazio ciociaria il corriere della provincia manley\" width=\"632\" height=\"346\" srcset=\"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2018\/11\/fca-cassino.jpg 990w, https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2018\/11\/fca-cassino-300x164.jpg 300w, https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2018\/11\/fca-cassino-768x420.jpg 768w, https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2018\/11\/fca-cassino-500x274.jpg 500w\" sizes=\"auto, (max-width: 632px) 100vw, 632px\" \/><\/div>\n<h2><\/h2>\n<h2>L&#8217;intervento<\/h2>\n<div dir=\"auto\">&#8220;Un annus horribilis per il colosso italiano, che, secondo le stime, dovrebbe ricorrere alla cassa integrazione anche nel 2020.<strong> Tutto ci\u00f2 crea un\u2019atmosfera tutt\u2019altro che positiva<\/strong> in vista del futuro. Per questi motivi, bene la fusione con PSA, ma tenere la barra dritta sugli obiettivi da raggiungere, primo tra tutti la salvaguardia del lavoro nel Lazio.\u00a0 Penso alle migliaia di operai che anche quest\u2019anno mangeranno un panettone amaro, in un clima di costante incertezza. Durante tutti questi mesi del 2019 mi sono battuto pi\u00f9 volte allo scopo di tutelare il loro posto di lavoro. Il 2020 deve dare maggiori risposte a tutti loro.\u00a0<strong> Hochiesto un incontro ai vertici FCA,<\/strong> scrivendogli una lettera, alla quale, per\u00f2, ancora non ho ricevuto rispost<strong style=\"line-height: 1.5\">\u00a0<\/strong><span style=\"line-height: 1.5\">a. Zingaretti, come volevasi dimostrare, non ha mosso un dito. Ho dovuto scrivere io ai vertici FCA per conoscere le loro intenzioni sul futuro del sito di Piedimonte San Germano, estremamente strategico per l\u2019intero Lazio Meridionale, e volano di sviluppo irrinunciabile per il nostro territorio. Auguro alla nostra regione di poter tornare presto alle urne ed avere un presidente degno di questo nome!&#8221;.\u00a0<\/span><\/div>\n<div dir=\"auto\"><\/div>\n<div dir=\"auto\"><\/div>\n","protected":false},"excerpt":{"rendered":"<p>\u201cIl 2019 \u00e8 stato un anno pessimo in cui si \u00e8 registrato il record di cassa integrazione. La pi\u00f9 grande<\/p>\n","protected":false},"author":18,"featured_media":21598,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[28,17],"tags":[216,94,554,2048,93,1336,194,7758,562,104],"class_list":["post-25720","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-politica","category-lavoro","tag-cassino","tag-ciociaria","tag-fca","tag-fiat","tag-frosinone","tag-pasquale-ciacciarelli","tag-piedimonte-san-germano","tag-psa","tag-regione-lazio","tag-zingaretti"],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v27.8 (Yoast SEO v27.8) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Fca, Ciacciarelli: &quot;2019 annus horribilis. Servono maggiori garanzie&quot; - IlCorriereDellaProvincia.it - News h24 e notizie di approfondimento<\/title>\n<meta name=\"description\" content=\"Il 2019 \u00e8 stato un anno pessimo in cui si \u00e8 registrato il record di cassa integrazione. Il consigliere regionale ha chiesto un incontro con Fca\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2020\/01\/04\/fca-ciacciarelli-2019-annus-horribilis-servono-maggiori-garanzie\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Fca, Ciacciarelli: &quot;2019 annus horribilis. Servono maggiori garanzie&quot;\" \/>\n<meta property=\"og:description\" content=\"Il 2019 \u00e8 stato un anno pessimo in cui si \u00e8 registrato il record di cassa integrazione. Il consigliere regionale ha chiesto un incontro con Fca\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2020\/01\/04\/fca-ciacciarelli-2019-annus-horribilis-servono-maggiori-garanzie\/\" \/>\n<meta property=\"og:site_name\" content=\"IlCorriereDellaProvincia.it - News h24 e notizie di approfondimento\" \/>\n<meta property=\"article:author\" content=\"www.facebook.com\/tunews24\" \/>\n<meta property=\"article:published_time\" content=\"2020-01-04T10:06:55+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2020-01-05T08:34:21+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2019\/11\/Ciacciarelli-Regione-Lazio.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"4032\" \/>\n\t<meta property=\"og:image:height\" content=\"3024\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Redazione\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"Redazione\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2020\\\/01\\\/04\\\/fca-ciacciarelli-2019-annus-horribilis-servono-maggiori-garanzie\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2020\\\/01\\\/04\\\/fca-ciacciarelli-2019-annus-horribilis-servono-maggiori-garanzie\\\/\"},\"author\":{\"name\":\"Redazione\",\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/#\\\/schema\\\/person\\\/6d7f0a9120d0c03d0c552e9fdf49ed7d\"},\"headline\":\"Fca, Ciacciarelli: &#8220;2019 annus horribilis. Servono maggiori garanzie&#8221;\",\"datePublished\":\"2020-01-04T10:06:55+00:00\",\"dateModified\":\"2020-01-05T08:34:21+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2020\\\/01\\\/04\\\/fca-ciacciarelli-2019-annus-horribilis-servono-maggiori-garanzie\\\/\"},\"wordCount\":235,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2020\\\/01\\\/04\\\/fca-ciacciarelli-2019-annus-horribilis-servono-maggiori-garanzie\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2019\\\/11\\\/Ciacciarelli-Regione-Lazio.jpg\",\"keywords\":[\"Cassino\",\"Ciociaria\",\"Fca\",\"fiat\",\"Frosinone\",\"pasquale ciacciarelli\",\"piedimonte san germano\",\"psa\",\"regione lazio\",\"zingaretti\"],\"articleSection\":[\"Evidenza\",\"Lavoro\"],\"inLanguage\":\"it-IT\",\"copyrightYear\":\"2020\",\"copyrightHolder\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/#organization\"}},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2020\\\/01\\\/04\\\/fca-ciacciarelli-2019-annus-horribilis-servono-maggiori-garanzie\\\/\",\"url\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2020\\\/01\\\/04\\\/fca-ciacciarelli-2019-annus-horribilis-servono-maggiori-garanzie\\\/\",\"name\":\"Fca, Ciacciarelli: \\\"2019 annus horribilis. Servono maggiori garanzie\\\" - IlCorriereDellaProvincia.it - News h24 e notizie di approfondimento\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2020\\\/01\\\/04\\\/fca-ciacciarelli-2019-annus-horribilis-servono-maggiori-garanzie\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2020\\\/01\\\/04\\\/fca-ciacciarelli-2019-annus-horribilis-servono-maggiori-garanzie\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2019\\\/11\\\/Ciacciarelli-Regione-Lazio.jpg\",\"datePublished\":\"2020-01-04T10:06:55+00:00\",\"dateModified\":\"2020-01-05T08:34:21+00:00\",\"description\":\"Il 2019 \u00e8 stato un anno pessimo in cui si \u00e8 registrato il record di cassa integrazione. Il consigliere regionale ha chiesto un incontro con Fca\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2020\\\/01\\\/04\\\/fca-ciacciarelli-2019-annus-horribilis-servono-maggiori-garanzie\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2020\\\/01\\\/04\\\/fca-ciacciarelli-2019-annus-horribilis-servono-maggiori-garanzie\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2020\\\/01\\\/04\\\/fca-ciacciarelli-2019-annus-horribilis-servono-maggiori-garanzie\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2019\\\/11\\\/Ciacciarelli-Regione-Lazio.jpg\",\"contentUrl\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2019\\\/11\\\/Ciacciarelli-Regione-Lazio.jpg\",\"width\":4032,\"height\":3024,\"caption\":\"Il consigliere regionale Pasquale Ciacciarelli\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2020\\\/01\\\/04\\\/fca-ciacciarelli-2019-annus-horribilis-servono-maggiori-garanzie\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Fca, Ciacciarelli: &#8220;2019 annus horribilis. Servono maggiori garanzie&#8221;\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/#website\",\"url\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/\",\"name\":\"Il Corriere Delle Provincia\",\"description\":\"IlCorriereDellaProvincia.it, quotidiano web di politica, cronaca, inchiesta, lavoro, scuola, turismo, cultura e spettacolo, economia e finanza, salute e benessere. Approfondimenti e notizie aggiornate con foto e video della provincia di Frosinone ma anche news nazionali, dell\u2019Italia e del Mondo.\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":[\"Organization\",\"Place\"],\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/#organization\",\"name\":\"Globalpress s.r.l.\",\"url\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/\",\"logo\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2020\\\/01\\\/04\\\/fca-ciacciarelli-2019-annus-horribilis-servono-maggiori-garanzie\\\/#local-main-organization-logo\"},\"image\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2020\\\/01\\\/04\\\/fca-ciacciarelli-2019-annus-horribilis-servono-maggiori-garanzie\\\/#local-main-organization-logo\"},\"telephone\":[],\"openingHoursSpecification\":[{\"@type\":\"OpeningHoursSpecification\",\"dayOfWeek\":[\"Monday\",\"Tuesday\",\"Wednesday\",\"Thursday\",\"Friday\",\"Saturday\",\"Sunday\"],\"opens\":\"09:00\",\"closes\":\"17:00\"}]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/#\\\/schema\\\/person\\\/6d7f0a9120d0c03d0c552e9fdf49ed7d\",\"name\":\"Redazione\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/a40eeacccdcad861f831dde73317f63a542e738f0dc4b79b9f47062d3d4bd1d2?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/a40eeacccdcad861f831dde73317f63a542e738f0dc4b79b9f47062d3d4bd1d2?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/a40eeacccdcad861f831dde73317f63a542e738f0dc4b79b9f47062d3d4bd1d2?s=96&d=mm&r=g\",\"caption\":\"Redazione\"},\"description\":\"SEGUICI ANCHE SUI SOCIAL Facebook: TuNews24 e TuSport24 Instagram: TuNews24 e TuSport24 Youtube: TuNews24 Telegram: TuNews24 Puoi leggerci anche in formato cartaceo: il settimanale viene pubblicato e distribuito gratuitamente ogni venerd\u00ec in edicole, bar, centri commerciali e svariati esercizi. Ma \u00e8 possibile anche sfogliarlo comodamente online, cliccando su TU NEWS sfogliabile TU NEWS, PASSIONE PER L\u2019INFORMAZIONE\",\"sameAs\":[\"http:\\\/\\\/www.tunews24.it\",\"www.facebook.com\\\/tunews24\"],\"url\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/author\\\/senzafirma\\\/\"},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2020\\\/01\\\/04\\\/fca-ciacciarelli-2019-annus-horribilis-servono-maggiori-garanzie\\\/#local-main-organization-logo\",\"url\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2022\\\/11\\\/cropped-il-corriere-della-provincia-testata-web-scontornata.png\",\"contentUrl\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2022\\\/11\\\/cropped-il-corriere-della-provincia-testata-web-scontornata.png\",\"width\":2911,\"height\":717,\"caption\":\"Globalpress s.r.l.\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Fca, Ciacciarelli: \"2019 annus horribilis. Servono maggiori garanzie\" - IlCorriereDellaProvincia.it - News h24 e notizie di approfondimento","description":"Il 2019 \u00e8 stato un anno pessimo in cui si \u00e8 registrato il record di cassa integrazione. Il consigliere regionale ha chiesto un incontro con Fca","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2020\/01\/04\/fca-ciacciarelli-2019-annus-horribilis-servono-maggiori-garanzie\/","og_locale":"it_IT","og_type":"article","og_title":"Fca, Ciacciarelli: \"2019 annus horribilis. Servono maggiori garanzie\"","og_description":"Il 2019 \u00e8 stato un anno pessimo in cui si \u00e8 registrato il record di cassa integrazione. Il consigliere regionale ha chiesto un incontro con Fca","og_url":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2020\/01\/04\/fca-ciacciarelli-2019-annus-horribilis-servono-maggiori-garanzie\/","og_site_name":"IlCorriereDellaProvincia.it - News h24 e notizie di approfondimento","article_author":"www.facebook.com\/tunews24","article_published_time":"2020-01-04T10:06:55+00:00","article_modified_time":"2020-01-05T08:34:21+00:00","og_image":[{"width":4032,"height":3024,"url":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2019\/11\/Ciacciarelli-Regione-Lazio.jpg","type":"image\/jpeg"}],"author":"Redazione","twitter_card":"summary_large_image","twitter_misc":{"Scritto da":"Redazione","Tempo di lettura stimato":"1 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2020\/01\/04\/fca-ciacciarelli-2019-annus-horribilis-servono-maggiori-garanzie\/#article","isPartOf":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2020\/01\/04\/fca-ciacciarelli-2019-annus-horribilis-servono-maggiori-garanzie\/"},"author":{"name":"Redazione","@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/#\/schema\/person\/6d7f0a9120d0c03d0c552e9fdf49ed7d"},"headline":"Fca, Ciacciarelli: &#8220;2019 annus horribilis. Servono maggiori garanzie&#8221;","datePublished":"2020-01-04T10:06:55+00:00","dateModified":"2020-01-05T08:34:21+00:00","mainEntityOfPage":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2020\/01\/04\/fca-ciacciarelli-2019-annus-horribilis-servono-maggiori-garanzie\/"},"wordCount":235,"commentCount":0,"publisher":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/#organization"},"image":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2020\/01\/04\/fca-ciacciarelli-2019-annus-horribilis-servono-maggiori-garanzie\/#primaryimage"},"thumbnailUrl":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2019\/11\/Ciacciarelli-Regione-Lazio.jpg","keywords":["Cassino","Ciociaria","Fca","fiat","Frosinone","pasquale ciacciarelli","piedimonte san germano","psa","regione lazio","zingaretti"],"articleSection":["Evidenza","Lavoro"],"inLanguage":"it-IT","copyrightYear":"2020","copyrightHolder":{"@id":"https:\/\/www.tunews24.it\/#organization"}},{"@type":"WebPage","@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2020\/01\/04\/fca-ciacciarelli-2019-annus-horribilis-servono-maggiori-garanzie\/","url":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2020\/01\/04\/fca-ciacciarelli-2019-annus-horribilis-servono-maggiori-garanzie\/","name":"Fca, Ciacciarelli: \"2019 annus horribilis. Servono maggiori garanzie\" - IlCorriereDellaProvincia.it - News h24 e notizie di approfondimento","isPartOf":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2020\/01\/04\/fca-ciacciarelli-2019-annus-horribilis-servono-maggiori-garanzie\/#primaryimage"},"image":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2020\/01\/04\/fca-ciacciarelli-2019-annus-horribilis-servono-maggiori-garanzie\/#primaryimage"},"thumbnailUrl":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2019\/11\/Ciacciarelli-Regione-Lazio.jpg","datePublished":"2020-01-04T10:06:55+00:00","dateModified":"2020-01-05T08:34:21+00:00","description":"Il 2019 \u00e8 stato un anno pessimo in cui si \u00e8 registrato il record di cassa integrazione. Il consigliere regionale ha chiesto un incontro con Fca","breadcrumb":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2020\/01\/04\/fca-ciacciarelli-2019-annus-horribilis-servono-maggiori-garanzie\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2020\/01\/04\/fca-ciacciarelli-2019-annus-horribilis-servono-maggiori-garanzie\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2020\/01\/04\/fca-ciacciarelli-2019-annus-horribilis-servono-maggiori-garanzie\/#primaryimage","url":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2019\/11\/Ciacciarelli-Regione-Lazio.jpg","contentUrl":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2019\/11\/Ciacciarelli-Regione-Lazio.jpg","width":4032,"height":3024,"caption":"Il consigliere regionale Pasquale Ciacciarelli"},{"@type":"BreadcrumbList","@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2020\/01\/04\/fca-ciacciarelli-2019-annus-horribilis-servono-maggiori-garanzie\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/"},{"@type":"ListItem","position":2,"name":"Fca, Ciacciarelli: &#8220;2019 annus horribilis. Servono maggiori garanzie&#8221;"}]},{"@type":"WebSite","@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/#website","url":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/","name":"Il Corriere Delle Provincia","description":"IlCorriereDellaProvincia.it, quotidiano web di politica, cronaca, inchiesta, lavoro, scuola, turismo, cultura e spettacolo, economia e finanza, salute e benessere. Approfondimenti e notizie aggiornate con foto e video della provincia di Frosinone ma anche news nazionali, dell\u2019Italia e del Mondo.","publisher":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":["Organization","Place"],"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/#organization","name":"Globalpress s.r.l.","url":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/","logo":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2020\/01\/04\/fca-ciacciarelli-2019-annus-horribilis-servono-maggiori-garanzie\/#local-main-organization-logo"},"image":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2020\/01\/04\/fca-ciacciarelli-2019-annus-horribilis-servono-maggiori-garanzie\/#local-main-organization-logo"},"telephone":[],"openingHoursSpecification":[{"@type":"OpeningHoursSpecification","dayOfWeek":["Monday","Tuesday","Wednesday","Thursday","Friday","Saturday","Sunday"],"opens":"09:00","closes":"17:00"}]},{"@type":"Person","@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/#\/schema\/person\/6d7f0a9120d0c03d0c552e9fdf49ed7d","name":"Redazione","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/secure.gravatar.com\/avatar\/a40eeacccdcad861f831dde73317f63a542e738f0dc4b79b9f47062d3d4bd1d2?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/a40eeacccdcad861f831dde73317f63a542e738f0dc4b79b9f47062d3d4bd1d2?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/a40eeacccdcad861f831dde73317f63a542e738f0dc4b79b9f47062d3d4bd1d2?s=96&d=mm&r=g","caption":"Redazione"},"description":"SEGUICI ANCHE SUI SOCIAL Facebook: TuNews24 e TuSport24 Instagram: TuNews24 e TuSport24 Youtube: TuNews24 Telegram: TuNews24 Puoi leggerci anche in formato cartaceo: il settimanale viene pubblicato e distribuito gratuitamente ogni venerd\u00ec in edicole, bar, centri commerciali e svariati esercizi. Ma \u00e8 possibile anche sfogliarlo comodamente online, cliccando su TU NEWS sfogliabile TU NEWS, PASSIONE PER L\u2019INFORMAZIONE","sameAs":["http:\/\/www.tunews24.it","www.facebook.com\/tunews24"],"url":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/author\/senzafirma\/"},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2020\/01\/04\/fca-ciacciarelli-2019-annus-horribilis-servono-maggiori-garanzie\/#local-main-organization-logo","url":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2022\/11\/cropped-il-corriere-della-provincia-testata-web-scontornata.png","contentUrl":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2022\/11\/cropped-il-corriere-della-provincia-testata-web-scontornata.png","width":2911,"height":717,"caption":"Globalpress s.r.l."}]}},"_links":{"self":[{"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/posts\/25720","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/users\/18"}],"replies":[{"embeddable":true,"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/comments?post=25720"}],"version-history":[{"count":1,"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/posts\/25720\/revisions"}],"predecessor-version":[{"id":25721,"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/posts\/25720\/revisions\/25721"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/media\/21598"}],"wp:attachment":[{"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/media?parent=25720"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/categories?post=25720"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/tags?post=25720"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}