{"id":25710,"date":"2020-01-04T10:18:13","date_gmt":"2020-01-04T09:18:13","guid":{"rendered":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/?p=25710"},"modified":"2020-01-04T10:18:13","modified_gmt":"2020-01-04T09:18:13","slug":"ferentino-weekend-ll-natale-delle-meraviglie-pompeo","status":"publish","type":"post","link":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2020\/01\/04\/ferentino-weekend-ll-natale-delle-meraviglie-pompeo\/","title":{"rendered":"Ferentino, ultimo weekend con &#8216;ll Natale delle Meraviglie&#8217;"},"content":{"rendered":"<p><strong>Laboratori creativi, giochi, animazione per i piccoli.<\/strong> Ma anche musica e un festival artistico a chiudere le festivit\u00e0 del 2019 con un programma ricco di eventi che ha scandito i giorni di festa e regalato alla cittadinanza, oltre che a visitatori e turisti, tanti appuntamenti e bei momenti di condivisione.<\/p>\n<h2><\/h2>\n<h2>Gli appuntamenti<\/h2>\n<p>Gli ultimi eventi sono in calendario per domenica 5 e luned\u00ec 6 gennaio, giorno dell\u2019Epifania, in cui cala il sipario sulle festivit\u00e0 natalizie.\u00a0Per <strong>domenica 5 gennaio<\/strong>, dalle ore 10, \u00e8 previsto in piazza Matteotti il laboratorio creativo \u2018La mia calza\u2019, con truccabimbi e baby dance a cura delle associazioni \u2018I Carillon\u2019 e \u2018L\u2019Airone\u2019, che continueranno le loro attivit\u00e0 anche nella mattinata del 6 gennaio. Sempre domenica mattina, in piazza, andranno in scena i festeggiamenti per il 25\u00b0esimo anniversario del MotoClub Ferentino, mentre nel pomeriggio ancora divertimento per i bambini con il Clown Skarabokkio.<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter wp-image-25712\" src=\"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2020\/01\/Moto-Club-Ferentino.jpg\" alt=\"moto club ferentino\" width=\"632\" height=\"896\" srcset=\"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2020\/01\/Moto-Club-Ferentino.jpg 448w, https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2020\/01\/Moto-Club-Ferentino-212x300.jpg 212w\" sizes=\"auto, (max-width: 632px) 100vw, 632px\" \/><\/p>\n<p>&nbsp;<\/p>\n<p><strong>Alle ore 18, invece, nella chiesa di San Francesc<\/strong>o, si svolger\u00e0 l\u2019esibizione del coro di voci bianche \u2018Liet Armonia\u2019, diretto da Katia Sacchetti, con la banda giovanile \u2018Citt\u00e0 di Ferentino\u2019 del direttore Luigi Bartolini.<\/p>\n<p>&nbsp;<\/p>\n<p><strong>Luned\u00ec 6 gennaio<\/strong>, invece, a partire dalle 10.30, l\u2019arrivo della Befana in piazza Matteotti anche con il carro dell\u2019associazione \u2018Castello delle vigne\u2019: saranno distribuite calze e dolciumi a tutti i bambini presenti, mentre, a chiusura di tutte le manifestazioni, un festival artistico dell\u2019Epifania al Centro Polivalente dalle ore 15.<\/p>\n<p>&nbsp;<\/p>\n<figure id=\"attachment_2437\" aria-describedby=\"caption-attachment-2437\" style=\"width: 632px\" class=\"wp-caption aligncenter\"><img loading=\"lazy\" decoding=\"async\" class=\"wp-image-2437 size-full\" src=\"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2018\/11\/pompeo-natale-ferentino-e1543518957575.jpg\" alt=\"natale ferentino comune iniziative programma calendario pompeo ferentino frosinone ciociaria\" width=\"632\" height=\"474\" \/><figcaption id=\"caption-attachment-2437\" class=\"wp-caption-text\">Un momento della conferenza di presentazione del programma natalizio a Ferentino<\/figcaption><\/figure>\n<h2>Gli interventi<\/h2>\n<p>\u201c<em>Con questi ultimi appuntamenti<\/em> \u2013<strong> commentano il sindaco Antonio Pompeo e gli assessori Vittori, Schietroma e Di Marco<\/strong> \u2013 <em>si chiude \u2018Il Natale delle Meraviglie\u2019 2019 che ci ha regalato tanti momenti indimenticabili, in una citt\u00e0 vestita a festa grazie allo splendido spettacolo delle luminarie \u2018Incanti di Natale\u2019. Siamo molto soddisfatti della partecipazione calorosa, da parte di cittadini e turisti, ai vari eventi che hanno scandito queste giornate di festa e che ci hanno permesso di mostrare il volto accogliente e coinvolgente della nostra citt\u00e0. L\u2019anno 2020 \u2013 <\/em>concludono &#8211; <em>ci vedr\u00e0 ancora pi\u00f9 impegnati e motivati a creare occasioni e momenti di svago e condivisione non soltanto per la nostra cittadinanza ma anche per chi, venendo dai paesi limitrofi o da fuori provincia, voglia apprezzare le nostre bellezze e la nostra gente\u201d.\u00a0<\/em><\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter wp-image-25711\" src=\"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2020\/01\/Locandina-eventi-Epifania.jpg\" alt=\"\" width=\"632\" height=\"965\" srcset=\"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2020\/01\/Locandina-eventi-Epifania.jpg 440w, https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2020\/01\/Locandina-eventi-Epifania-196x300.jpg 196w\" sizes=\"auto, (max-width: 632px) 100vw, 632px\" \/><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Laboratori creativi, giochi, animazione per i piccoli. Ma anche musica e un festival artistico a chiudere le festivit\u00e0 del 2019<\/p>\n","protected":false},"author":18,"featured_media":25711,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[4,14],"tags":[842,1462,94,7962,92,93,7963,7512,7015,1938],"class_list":["post-25710","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-primo-piano","category-cultura","tag-antonio-pompeo","tag-befana","tag-ciociaria","tag-di-marco","tag-ferentino","tag-frosinone","tag-motoclub","tag-natale-delle-meraviglie","tag-schietroma","tag-vittori"],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v27.8 (Yoast SEO v27.8) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Ferentino, ultimo weekend con &#039;ll Natale delle Meraviglie&#039; - IlCorriereDellaProvincia.it - News h24 e notizie di approfondimento<\/title>\n<meta name=\"description\" content=\"Gli ultimi eventi sono in calendario per domenica 5 e luned\u00ec 6 gennaio, giorno dell\u2019Epifania, in cui cala il sipario sulle festivit\u00e0 natalizie.\u00a0\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2020\/01\/04\/ferentino-weekend-ll-natale-delle-meraviglie-pompeo\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Ferentino, ultimo weekend con &#039;ll Natale delle Meraviglie&#039;\" \/>\n<meta property=\"og:description\" content=\"Gli ultimi eventi sono in calendario per domenica 5 e luned\u00ec 6 gennaio, giorno dell\u2019Epifania, in cui cala il sipario sulle festivit\u00e0 natalizie.\u00a0\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2020\/01\/04\/ferentino-weekend-ll-natale-delle-meraviglie-pompeo\/\" \/>\n<meta property=\"og:site_name\" content=\"IlCorriereDellaProvincia.it - News h24 e notizie di approfondimento\" \/>\n<meta property=\"article:author\" content=\"www.facebook.com\/tunews24\" \/>\n<meta property=\"article:published_time\" content=\"2020-01-04T09:18:13+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2020\/01\/Locandina-eventi-Epifania.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"440\" \/>\n\t<meta property=\"og:image:height\" content=\"672\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Redazione\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"Redazione\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minuti\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2020\\\/01\\\/04\\\/ferentino-weekend-ll-natale-delle-meraviglie-pompeo\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2020\\\/01\\\/04\\\/ferentino-weekend-ll-natale-delle-meraviglie-pompeo\\\/\"},\"author\":{\"name\":\"Redazione\",\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/#\\\/schema\\\/person\\\/6d7f0a9120d0c03d0c552e9fdf49ed7d\"},\"headline\":\"Ferentino, ultimo weekend con &#8216;ll Natale delle Meraviglie&#8217;\",\"datePublished\":\"2020-01-04T09:18:13+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2020\\\/01\\\/04\\\/ferentino-weekend-ll-natale-delle-meraviglie-pompeo\\\/\"},\"wordCount\":384,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2020\\\/01\\\/04\\\/ferentino-weekend-ll-natale-delle-meraviglie-pompeo\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2020\\\/01\\\/Locandina-eventi-Epifania.jpg\",\"keywords\":[\"antonio pompeo\",\"befana\",\"Ciociaria\",\"di marco\",\"ferentino\",\"Frosinone\",\"motoclub\",\"natale delle meraviglie\",\"Schietroma\",\"vittori\"],\"articleSection\":[\"*PRIMO PIANO*\",\"Cultura e Spettacolo\"],\"inLanguage\":\"it-IT\",\"copyrightYear\":\"2020\",\"copyrightHolder\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/#organization\"}},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2020\\\/01\\\/04\\\/ferentino-weekend-ll-natale-delle-meraviglie-pompeo\\\/\",\"url\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2020\\\/01\\\/04\\\/ferentino-weekend-ll-natale-delle-meraviglie-pompeo\\\/\",\"name\":\"Ferentino, ultimo weekend con 'll Natale delle Meraviglie' - IlCorriereDellaProvincia.it - News h24 e notizie di approfondimento\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2020\\\/01\\\/04\\\/ferentino-weekend-ll-natale-delle-meraviglie-pompeo\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2020\\\/01\\\/04\\\/ferentino-weekend-ll-natale-delle-meraviglie-pompeo\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2020\\\/01\\\/Locandina-eventi-Epifania.jpg\",\"datePublished\":\"2020-01-04T09:18:13+00:00\",\"description\":\"Gli ultimi eventi sono in calendario per domenica 5 e luned\u00ec 6 gennaio, giorno dell\u2019Epifania, in cui cala il sipario sulle festivit\u00e0 natalizie.\u00a0\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2020\\\/01\\\/04\\\/ferentino-weekend-ll-natale-delle-meraviglie-pompeo\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2020\\\/01\\\/04\\\/ferentino-weekend-ll-natale-delle-meraviglie-pompeo\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2020\\\/01\\\/04\\\/ferentino-weekend-ll-natale-delle-meraviglie-pompeo\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2020\\\/01\\\/Locandina-eventi-Epifania.jpg\",\"contentUrl\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2020\\\/01\\\/Locandina-eventi-Epifania.jpg\",\"width\":440,\"height\":672},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2020\\\/01\\\/04\\\/ferentino-weekend-ll-natale-delle-meraviglie-pompeo\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Ferentino, ultimo weekend con &#8216;ll Natale delle Meraviglie&#8217;\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/#website\",\"url\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/\",\"name\":\"Il Corriere Delle Provincia\",\"description\":\"IlCorriereDellaProvincia.it, quotidiano web di politica, cronaca, inchiesta, lavoro, scuola, turismo, cultura e spettacolo, economia e finanza, salute e benessere. Approfondimenti e notizie aggiornate con foto e video della provincia di Frosinone ma anche news nazionali, dell\u2019Italia e del Mondo.\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":[\"Organization\",\"Place\"],\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/#organization\",\"name\":\"Globalpress s.r.l.\",\"url\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/\",\"logo\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2020\\\/01\\\/04\\\/ferentino-weekend-ll-natale-delle-meraviglie-pompeo\\\/#local-main-organization-logo\"},\"image\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2020\\\/01\\\/04\\\/ferentino-weekend-ll-natale-delle-meraviglie-pompeo\\\/#local-main-organization-logo\"},\"telephone\":[],\"openingHoursSpecification\":[{\"@type\":\"OpeningHoursSpecification\",\"dayOfWeek\":[\"Monday\",\"Tuesday\",\"Wednesday\",\"Thursday\",\"Friday\",\"Saturday\",\"Sunday\"],\"opens\":\"09:00\",\"closes\":\"17:00\"}]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/#\\\/schema\\\/person\\\/6d7f0a9120d0c03d0c552e9fdf49ed7d\",\"name\":\"Redazione\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/a40eeacccdcad861f831dde73317f63a542e738f0dc4b79b9f47062d3d4bd1d2?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/a40eeacccdcad861f831dde73317f63a542e738f0dc4b79b9f47062d3d4bd1d2?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/a40eeacccdcad861f831dde73317f63a542e738f0dc4b79b9f47062d3d4bd1d2?s=96&d=mm&r=g\",\"caption\":\"Redazione\"},\"description\":\"SEGUICI ANCHE SUI SOCIAL Facebook: TuNews24 e TuSport24 Instagram: TuNews24 e TuSport24 Youtube: TuNews24 Telegram: TuNews24 Puoi leggerci anche in formato cartaceo: il settimanale viene pubblicato e distribuito gratuitamente ogni venerd\u00ec in edicole, bar, centri commerciali e svariati esercizi. Ma \u00e8 possibile anche sfogliarlo comodamente online, cliccando su TU NEWS sfogliabile TU NEWS, PASSIONE PER L\u2019INFORMAZIONE\",\"sameAs\":[\"http:\\\/\\\/www.tunews24.it\",\"www.facebook.com\\\/tunews24\"],\"url\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/author\\\/senzafirma\\\/\"},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2020\\\/01\\\/04\\\/ferentino-weekend-ll-natale-delle-meraviglie-pompeo\\\/#local-main-organization-logo\",\"url\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2022\\\/11\\\/cropped-il-corriere-della-provincia-testata-web-scontornata.png\",\"contentUrl\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2022\\\/11\\\/cropped-il-corriere-della-provincia-testata-web-scontornata.png\",\"width\":2911,\"height\":717,\"caption\":\"Globalpress s.r.l.\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Ferentino, ultimo weekend con 'll Natale delle Meraviglie' - IlCorriereDellaProvincia.it - News h24 e notizie di approfondimento","description":"Gli ultimi eventi sono in calendario per domenica 5 e luned\u00ec 6 gennaio, giorno dell\u2019Epifania, in cui cala il sipario sulle festivit\u00e0 natalizie.\u00a0","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2020\/01\/04\/ferentino-weekend-ll-natale-delle-meraviglie-pompeo\/","og_locale":"it_IT","og_type":"article","og_title":"Ferentino, ultimo weekend con 'll Natale delle Meraviglie'","og_description":"Gli ultimi eventi sono in calendario per domenica 5 e luned\u00ec 6 gennaio, giorno dell\u2019Epifania, in cui cala il sipario sulle festivit\u00e0 natalizie.\u00a0","og_url":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2020\/01\/04\/ferentino-weekend-ll-natale-delle-meraviglie-pompeo\/","og_site_name":"IlCorriereDellaProvincia.it - News h24 e notizie di approfondimento","article_author":"www.facebook.com\/tunews24","article_published_time":"2020-01-04T09:18:13+00:00","og_image":[{"width":440,"height":672,"url":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2020\/01\/Locandina-eventi-Epifania.jpg","type":"image\/jpeg"}],"author":"Redazione","twitter_card":"summary_large_image","twitter_misc":{"Scritto da":"Redazione","Tempo di lettura stimato":"2 minuti"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2020\/01\/04\/ferentino-weekend-ll-natale-delle-meraviglie-pompeo\/#article","isPartOf":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2020\/01\/04\/ferentino-weekend-ll-natale-delle-meraviglie-pompeo\/"},"author":{"name":"Redazione","@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/#\/schema\/person\/6d7f0a9120d0c03d0c552e9fdf49ed7d"},"headline":"Ferentino, ultimo weekend con &#8216;ll Natale delle Meraviglie&#8217;","datePublished":"2020-01-04T09:18:13+00:00","mainEntityOfPage":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2020\/01\/04\/ferentino-weekend-ll-natale-delle-meraviglie-pompeo\/"},"wordCount":384,"commentCount":0,"publisher":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/#organization"},"image":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2020\/01\/04\/ferentino-weekend-ll-natale-delle-meraviglie-pompeo\/#primaryimage"},"thumbnailUrl":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2020\/01\/Locandina-eventi-Epifania.jpg","keywords":["antonio pompeo","befana","Ciociaria","di marco","ferentino","Frosinone","motoclub","natale delle meraviglie","Schietroma","vittori"],"articleSection":["*PRIMO PIANO*","Cultura e Spettacolo"],"inLanguage":"it-IT","copyrightYear":"2020","copyrightHolder":{"@id":"https:\/\/www.tunews24.it\/#organization"}},{"@type":"WebPage","@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2020\/01\/04\/ferentino-weekend-ll-natale-delle-meraviglie-pompeo\/","url":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2020\/01\/04\/ferentino-weekend-ll-natale-delle-meraviglie-pompeo\/","name":"Ferentino, ultimo weekend con 'll Natale delle Meraviglie' - IlCorriereDellaProvincia.it - News h24 e notizie di approfondimento","isPartOf":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2020\/01\/04\/ferentino-weekend-ll-natale-delle-meraviglie-pompeo\/#primaryimage"},"image":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2020\/01\/04\/ferentino-weekend-ll-natale-delle-meraviglie-pompeo\/#primaryimage"},"thumbnailUrl":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2020\/01\/Locandina-eventi-Epifania.jpg","datePublished":"2020-01-04T09:18:13+00:00","description":"Gli ultimi eventi sono in calendario per domenica 5 e luned\u00ec 6 gennaio, giorno dell\u2019Epifania, in cui cala il sipario sulle festivit\u00e0 natalizie.\u00a0","breadcrumb":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2020\/01\/04\/ferentino-weekend-ll-natale-delle-meraviglie-pompeo\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2020\/01\/04\/ferentino-weekend-ll-natale-delle-meraviglie-pompeo\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2020\/01\/04\/ferentino-weekend-ll-natale-delle-meraviglie-pompeo\/#primaryimage","url":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2020\/01\/Locandina-eventi-Epifania.jpg","contentUrl":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2020\/01\/Locandina-eventi-Epifania.jpg","width":440,"height":672},{"@type":"BreadcrumbList","@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2020\/01\/04\/ferentino-weekend-ll-natale-delle-meraviglie-pompeo\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/"},{"@type":"ListItem","position":2,"name":"Ferentino, ultimo weekend con &#8216;ll Natale delle Meraviglie&#8217;"}]},{"@type":"WebSite","@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/#website","url":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/","name":"Il Corriere Delle Provincia","description":"IlCorriereDellaProvincia.it, quotidiano web di politica, cronaca, inchiesta, lavoro, scuola, turismo, cultura e spettacolo, economia e finanza, salute e benessere. Approfondimenti e notizie aggiornate con foto e video della provincia di Frosinone ma anche news nazionali, dell\u2019Italia e del Mondo.","publisher":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":["Organization","Place"],"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/#organization","name":"Globalpress s.r.l.","url":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/","logo":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2020\/01\/04\/ferentino-weekend-ll-natale-delle-meraviglie-pompeo\/#local-main-organization-logo"},"image":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2020\/01\/04\/ferentino-weekend-ll-natale-delle-meraviglie-pompeo\/#local-main-organization-logo"},"telephone":[],"openingHoursSpecification":[{"@type":"OpeningHoursSpecification","dayOfWeek":["Monday","Tuesday","Wednesday","Thursday","Friday","Saturday","Sunday"],"opens":"09:00","closes":"17:00"}]},{"@type":"Person","@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/#\/schema\/person\/6d7f0a9120d0c03d0c552e9fdf49ed7d","name":"Redazione","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/secure.gravatar.com\/avatar\/a40eeacccdcad861f831dde73317f63a542e738f0dc4b79b9f47062d3d4bd1d2?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/a40eeacccdcad861f831dde73317f63a542e738f0dc4b79b9f47062d3d4bd1d2?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/a40eeacccdcad861f831dde73317f63a542e738f0dc4b79b9f47062d3d4bd1d2?s=96&d=mm&r=g","caption":"Redazione"},"description":"SEGUICI ANCHE SUI SOCIAL Facebook: TuNews24 e TuSport24 Instagram: TuNews24 e TuSport24 Youtube: TuNews24 Telegram: TuNews24 Puoi leggerci anche in formato cartaceo: il settimanale viene pubblicato e distribuito gratuitamente ogni venerd\u00ec in edicole, bar, centri commerciali e svariati esercizi. Ma \u00e8 possibile anche sfogliarlo comodamente online, cliccando su TU NEWS sfogliabile TU NEWS, PASSIONE PER L\u2019INFORMAZIONE","sameAs":["http:\/\/www.tunews24.it","www.facebook.com\/tunews24"],"url":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/author\/senzafirma\/"},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2020\/01\/04\/ferentino-weekend-ll-natale-delle-meraviglie-pompeo\/#local-main-organization-logo","url":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2022\/11\/cropped-il-corriere-della-provincia-testata-web-scontornata.png","contentUrl":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2022\/11\/cropped-il-corriere-della-provincia-testata-web-scontornata.png","width":2911,"height":717,"caption":"Globalpress s.r.l."}]}},"_links":{"self":[{"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/posts\/25710","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/users\/18"}],"replies":[{"embeddable":true,"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/comments?post=25710"}],"version-history":[{"count":1,"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/posts\/25710\/revisions"}],"predecessor-version":[{"id":25713,"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/posts\/25710\/revisions\/25713"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/media\/25711"}],"wp:attachment":[{"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/media?parent=25710"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/categories?post=25710"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/tags?post=25710"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}