{"id":25600,"date":"2019-12-31T17:08:33","date_gmt":"2019-12-31T16:08:33","guid":{"rendered":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/?p=25600"},"modified":"2019-12-31T17:08:33","modified_gmt":"2019-12-31T16:08:33","slug":"fiuggi-il-2020-inizia-in-piazza-con-i-capitani-coraggiosi","status":"publish","type":"post","link":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2019\/12\/31\/fiuggi-il-2020-inizia-in-piazza-con-i-capitani-coraggiosi\/","title":{"rendered":"Fiuggi: il 2020 inizia in piazza con &#8216;I Capitani Coraggiosi&#8217;"},"content":{"rendered":"<p>Grande attesa per il <strong>concerto<\/strong> di domani, <strong>1\u00b0 gennaio 2020<\/strong>, nella citt\u00e0 termale. Per l\u2019occasione si esibir\u00e0 il gruppo <strong>&#8216;I Capitani Coraggiosi&#8217;<\/strong>, una band di alto livello composta da ben dodici elementi che render\u00e0 omaggio ai grandi nomi della musica italiana.<\/p>\n<p>Saranno riproposti i <strong>successi indimenticabili<\/strong> di artisti del calibro di <strong>Umberto Tozzi e Gianni Morandi<\/strong>, con testi e musiche originali che hanno fatto la storia della musica del Belpaese.<\/p>\n<p><strong>L\u2019appuntamento \u00e8 alle ore 17<\/strong> nella centralissima<strong> piazza Spada<\/strong> a Fiuggi fonte.<\/p>\n<h2>Le parole dell&#8217;assessore Girolami<\/h2>\n<p>&#8220;Come assessore al turismo \u2013 ha spiegato<strong> Simona Girolami<\/strong> \u2013 sono lieta di invitare tutta la cittadinanza, i nostri ospiti villeggianti e tutti gli amanti della bella musica a un appuntamento di grande impatto emotivo. Sul palco salir\u00e0 <strong>una band che non ha bisogno di presentazioni<\/strong> per i grandi successi ottenuti in tutta Italia&#8221;.<\/p>\n<p>&#8220;Ascoltare, cantare e rivivere tutti insieme un pomeriggio all&#8217;insegna di canzoni indimenticabili, a firma di Tozzi e Morandi, sar\u00e0 l\u2019occasione per festeggiare insieme l\u2019inizio del nuovo anno&#8221;.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Grande attesa per il concerto di domani, 1\u00b0 gennaio 2020, nella citt\u00e0 termale. Per l\u2019occasione si esibir\u00e0 il gruppo &#8216;I<\/p>\n","protected":false},"author":18,"featured_media":25601,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[4,14],"tags":[1453,94,1089,217,93,7917,4566,7777,7916],"class_list":["post-25600","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-primo-piano","category-cultura","tag-capodanno","tag-ciociaria","tag-concerto","tag-fiuggi","tag-frosinone","tag-gianni-morandi","tag-piazza-spada","tag-simona-girolami","tag-umberto-tozzi"],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v27.8 (Yoast SEO v27.8) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Fiuggi: il 2020 inizia in piazza con &#039;I Capitani Coraggiosi&#039; - IlCorriereDellaProvincia.it - News h24 e notizie di approfondimento<\/title>\n<meta name=\"description\" content=\"Cresce l&#039;attesa per il concerto del 1\u00b0 gennaio in piazza Spada a Fiuggi. Per l&#039;occasione si esibir\u00e0 la band de &#039;I Capitani Coraggiosi&#039;\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2019\/12\/31\/fiuggi-il-2020-inizia-in-piazza-con-i-capitani-coraggiosi\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Fiuggi: il 2020 inizia in piazza con &#039;I Capitani Coraggiosi&#039;\" \/>\n<meta property=\"og:description\" content=\"Cresce l&#039;attesa per il concerto del 1\u00b0 gennaio in piazza Spada a Fiuggi. Per l&#039;occasione si esibir\u00e0 la band de &#039;I Capitani Coraggiosi&#039;\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2019\/12\/31\/fiuggi-il-2020-inizia-in-piazza-con-i-capitani-coraggiosi\/\" \/>\n<meta property=\"og:site_name\" content=\"IlCorriereDellaProvincia.it - News h24 e notizie di approfondimento\" \/>\n<meta property=\"article:author\" content=\"www.facebook.com\/tunews24\" \/>\n<meta property=\"article:published_time\" content=\"2019-12-31T16:08:33+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2019\/12\/piazza-spada-fiuggi-e1577808064338.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"632\" \/>\n\t<meta property=\"og:image:height\" content=\"382\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Redazione\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"Redazione\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2019\\\/12\\\/31\\\/fiuggi-il-2020-inizia-in-piazza-con-i-capitani-coraggiosi\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2019\\\/12\\\/31\\\/fiuggi-il-2020-inizia-in-piazza-con-i-capitani-coraggiosi\\\/\"},\"author\":{\"name\":\"Redazione\",\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/#\\\/schema\\\/person\\\/6d7f0a9120d0c03d0c552e9fdf49ed7d\"},\"headline\":\"Fiuggi: il 2020 inizia in piazza con &#8216;I Capitani Coraggiosi&#8217;\",\"datePublished\":\"2019-12-31T16:08:33+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2019\\\/12\\\/31\\\/fiuggi-il-2020-inizia-in-piazza-con-i-capitani-coraggiosi\\\/\"},\"wordCount\":176,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2019\\\/12\\\/31\\\/fiuggi-il-2020-inizia-in-piazza-con-i-capitani-coraggiosi\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2019\\\/12\\\/piazza-spada-fiuggi-e1577808064338.jpg\",\"keywords\":[\"capodanno\",\"Ciociaria\",\"concerto\",\"Fiuggi\",\"Frosinone\",\"gianni morandi\",\"piazza spada\",\"Simona Girolami\",\"umberto tozzi\"],\"articleSection\":[\"*PRIMO PIANO*\",\"Cultura e Spettacolo\"],\"inLanguage\":\"it-IT\",\"copyrightYear\":\"2019\",\"copyrightHolder\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/#organization\"}},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2019\\\/12\\\/31\\\/fiuggi-il-2020-inizia-in-piazza-con-i-capitani-coraggiosi\\\/\",\"url\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2019\\\/12\\\/31\\\/fiuggi-il-2020-inizia-in-piazza-con-i-capitani-coraggiosi\\\/\",\"name\":\"Fiuggi: il 2020 inizia in piazza con 'I Capitani Coraggiosi' - IlCorriereDellaProvincia.it - News h24 e notizie di approfondimento\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2019\\\/12\\\/31\\\/fiuggi-il-2020-inizia-in-piazza-con-i-capitani-coraggiosi\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2019\\\/12\\\/31\\\/fiuggi-il-2020-inizia-in-piazza-con-i-capitani-coraggiosi\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2019\\\/12\\\/piazza-spada-fiuggi-e1577808064338.jpg\",\"datePublished\":\"2019-12-31T16:08:33+00:00\",\"description\":\"Cresce l'attesa per il concerto del 1\u00b0 gennaio in piazza Spada a Fiuggi. Per l'occasione si esibir\u00e0 la band de 'I Capitani Coraggiosi'\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2019\\\/12\\\/31\\\/fiuggi-il-2020-inizia-in-piazza-con-i-capitani-coraggiosi\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2019\\\/12\\\/31\\\/fiuggi-il-2020-inizia-in-piazza-con-i-capitani-coraggiosi\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2019\\\/12\\\/31\\\/fiuggi-il-2020-inizia-in-piazza-con-i-capitani-coraggiosi\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2019\\\/12\\\/piazza-spada-fiuggi-e1577808064338.jpg\",\"contentUrl\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2019\\\/12\\\/piazza-spada-fiuggi-e1577808064338.jpg\",\"width\":632,\"height\":382,\"caption\":\"Piazza Spada a Fiuggi\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2019\\\/12\\\/31\\\/fiuggi-il-2020-inizia-in-piazza-con-i-capitani-coraggiosi\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Fiuggi: il 2020 inizia in piazza con &#8216;I Capitani Coraggiosi&#8217;\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/#website\",\"url\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/\",\"name\":\"Il Corriere Delle Provincia\",\"description\":\"IlCorriereDellaProvincia.it, quotidiano web di politica, cronaca, inchiesta, lavoro, scuola, turismo, cultura e spettacolo, economia e finanza, salute e benessere. Approfondimenti e notizie aggiornate con foto e video della provincia di Frosinone ma anche news nazionali, dell\u2019Italia e del Mondo.\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":[\"Organization\",\"Place\"],\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/#organization\",\"name\":\"Globalpress s.r.l.\",\"url\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/\",\"logo\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2019\\\/12\\\/31\\\/fiuggi-il-2020-inizia-in-piazza-con-i-capitani-coraggiosi\\\/#local-main-organization-logo\"},\"image\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2019\\\/12\\\/31\\\/fiuggi-il-2020-inizia-in-piazza-con-i-capitani-coraggiosi\\\/#local-main-organization-logo\"},\"telephone\":[],\"openingHoursSpecification\":[{\"@type\":\"OpeningHoursSpecification\",\"dayOfWeek\":[\"Monday\",\"Tuesday\",\"Wednesday\",\"Thursday\",\"Friday\",\"Saturday\",\"Sunday\"],\"opens\":\"09:00\",\"closes\":\"17:00\"}]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/#\\\/schema\\\/person\\\/6d7f0a9120d0c03d0c552e9fdf49ed7d\",\"name\":\"Redazione\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/a40eeacccdcad861f831dde73317f63a542e738f0dc4b79b9f47062d3d4bd1d2?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/a40eeacccdcad861f831dde73317f63a542e738f0dc4b79b9f47062d3d4bd1d2?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/a40eeacccdcad861f831dde73317f63a542e738f0dc4b79b9f47062d3d4bd1d2?s=96&d=mm&r=g\",\"caption\":\"Redazione\"},\"description\":\"SEGUICI ANCHE SUI SOCIAL Facebook: TuNews24 e TuSport24 Instagram: TuNews24 e TuSport24 Youtube: TuNews24 Telegram: TuNews24 Puoi leggerci anche in formato cartaceo: il settimanale viene pubblicato e distribuito gratuitamente ogni venerd\u00ec in edicole, bar, centri commerciali e svariati esercizi. Ma \u00e8 possibile anche sfogliarlo comodamente online, cliccando su TU NEWS sfogliabile TU NEWS, PASSIONE PER L\u2019INFORMAZIONE\",\"sameAs\":[\"http:\\\/\\\/www.tunews24.it\",\"www.facebook.com\\\/tunews24\"],\"url\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/author\\\/senzafirma\\\/\"},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2019\\\/12\\\/31\\\/fiuggi-il-2020-inizia-in-piazza-con-i-capitani-coraggiosi\\\/#local-main-organization-logo\",\"url\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2022\\\/11\\\/cropped-il-corriere-della-provincia-testata-web-scontornata.png\",\"contentUrl\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2022\\\/11\\\/cropped-il-corriere-della-provincia-testata-web-scontornata.png\",\"width\":2911,\"height\":717,\"caption\":\"Globalpress s.r.l.\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Fiuggi: il 2020 inizia in piazza con 'I Capitani Coraggiosi' - IlCorriereDellaProvincia.it - News h24 e notizie di approfondimento","description":"Cresce l'attesa per il concerto del 1\u00b0 gennaio in piazza Spada a Fiuggi. Per l'occasione si esibir\u00e0 la band de 'I Capitani Coraggiosi'","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2019\/12\/31\/fiuggi-il-2020-inizia-in-piazza-con-i-capitani-coraggiosi\/","og_locale":"it_IT","og_type":"article","og_title":"Fiuggi: il 2020 inizia in piazza con 'I Capitani Coraggiosi'","og_description":"Cresce l'attesa per il concerto del 1\u00b0 gennaio in piazza Spada a Fiuggi. Per l'occasione si esibir\u00e0 la band de 'I Capitani Coraggiosi'","og_url":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2019\/12\/31\/fiuggi-il-2020-inizia-in-piazza-con-i-capitani-coraggiosi\/","og_site_name":"IlCorriereDellaProvincia.it - News h24 e notizie di approfondimento","article_author":"www.facebook.com\/tunews24","article_published_time":"2019-12-31T16:08:33+00:00","og_image":[{"width":632,"height":382,"url":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2019\/12\/piazza-spada-fiuggi-e1577808064338.jpg","type":"image\/jpeg"}],"author":"Redazione","twitter_card":"summary_large_image","twitter_misc":{"Scritto da":"Redazione","Tempo di lettura stimato":"1 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2019\/12\/31\/fiuggi-il-2020-inizia-in-piazza-con-i-capitani-coraggiosi\/#article","isPartOf":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2019\/12\/31\/fiuggi-il-2020-inizia-in-piazza-con-i-capitani-coraggiosi\/"},"author":{"name":"Redazione","@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/#\/schema\/person\/6d7f0a9120d0c03d0c552e9fdf49ed7d"},"headline":"Fiuggi: il 2020 inizia in piazza con &#8216;I Capitani Coraggiosi&#8217;","datePublished":"2019-12-31T16:08:33+00:00","mainEntityOfPage":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2019\/12\/31\/fiuggi-il-2020-inizia-in-piazza-con-i-capitani-coraggiosi\/"},"wordCount":176,"commentCount":0,"publisher":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/#organization"},"image":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2019\/12\/31\/fiuggi-il-2020-inizia-in-piazza-con-i-capitani-coraggiosi\/#primaryimage"},"thumbnailUrl":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2019\/12\/piazza-spada-fiuggi-e1577808064338.jpg","keywords":["capodanno","Ciociaria","concerto","Fiuggi","Frosinone","gianni morandi","piazza spada","Simona Girolami","umberto tozzi"],"articleSection":["*PRIMO PIANO*","Cultura e Spettacolo"],"inLanguage":"it-IT","copyrightYear":"2019","copyrightHolder":{"@id":"https:\/\/www.tunews24.it\/#organization"}},{"@type":"WebPage","@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2019\/12\/31\/fiuggi-il-2020-inizia-in-piazza-con-i-capitani-coraggiosi\/","url":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2019\/12\/31\/fiuggi-il-2020-inizia-in-piazza-con-i-capitani-coraggiosi\/","name":"Fiuggi: il 2020 inizia in piazza con 'I Capitani Coraggiosi' - IlCorriereDellaProvincia.it - News h24 e notizie di approfondimento","isPartOf":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2019\/12\/31\/fiuggi-il-2020-inizia-in-piazza-con-i-capitani-coraggiosi\/#primaryimage"},"image":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2019\/12\/31\/fiuggi-il-2020-inizia-in-piazza-con-i-capitani-coraggiosi\/#primaryimage"},"thumbnailUrl":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2019\/12\/piazza-spada-fiuggi-e1577808064338.jpg","datePublished":"2019-12-31T16:08:33+00:00","description":"Cresce l'attesa per il concerto del 1\u00b0 gennaio in piazza Spada a Fiuggi. Per l'occasione si esibir\u00e0 la band de 'I Capitani Coraggiosi'","breadcrumb":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2019\/12\/31\/fiuggi-il-2020-inizia-in-piazza-con-i-capitani-coraggiosi\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2019\/12\/31\/fiuggi-il-2020-inizia-in-piazza-con-i-capitani-coraggiosi\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2019\/12\/31\/fiuggi-il-2020-inizia-in-piazza-con-i-capitani-coraggiosi\/#primaryimage","url":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2019\/12\/piazza-spada-fiuggi-e1577808064338.jpg","contentUrl":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2019\/12\/piazza-spada-fiuggi-e1577808064338.jpg","width":632,"height":382,"caption":"Piazza Spada a Fiuggi"},{"@type":"BreadcrumbList","@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2019\/12\/31\/fiuggi-il-2020-inizia-in-piazza-con-i-capitani-coraggiosi\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/"},{"@type":"ListItem","position":2,"name":"Fiuggi: il 2020 inizia in piazza con &#8216;I Capitani Coraggiosi&#8217;"}]},{"@type":"WebSite","@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/#website","url":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/","name":"Il Corriere Delle Provincia","description":"IlCorriereDellaProvincia.it, quotidiano web di politica, cronaca, inchiesta, lavoro, scuola, turismo, cultura e spettacolo, economia e finanza, salute e benessere. Approfondimenti e notizie aggiornate con foto e video della provincia di Frosinone ma anche news nazionali, dell\u2019Italia e del Mondo.","publisher":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":["Organization","Place"],"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/#organization","name":"Globalpress s.r.l.","url":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/","logo":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2019\/12\/31\/fiuggi-il-2020-inizia-in-piazza-con-i-capitani-coraggiosi\/#local-main-organization-logo"},"image":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2019\/12\/31\/fiuggi-il-2020-inizia-in-piazza-con-i-capitani-coraggiosi\/#local-main-organization-logo"},"telephone":[],"openingHoursSpecification":[{"@type":"OpeningHoursSpecification","dayOfWeek":["Monday","Tuesday","Wednesday","Thursday","Friday","Saturday","Sunday"],"opens":"09:00","closes":"17:00"}]},{"@type":"Person","@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/#\/schema\/person\/6d7f0a9120d0c03d0c552e9fdf49ed7d","name":"Redazione","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/secure.gravatar.com\/avatar\/a40eeacccdcad861f831dde73317f63a542e738f0dc4b79b9f47062d3d4bd1d2?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/a40eeacccdcad861f831dde73317f63a542e738f0dc4b79b9f47062d3d4bd1d2?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/a40eeacccdcad861f831dde73317f63a542e738f0dc4b79b9f47062d3d4bd1d2?s=96&d=mm&r=g","caption":"Redazione"},"description":"SEGUICI ANCHE SUI SOCIAL Facebook: TuNews24 e TuSport24 Instagram: TuNews24 e TuSport24 Youtube: TuNews24 Telegram: TuNews24 Puoi leggerci anche in formato cartaceo: il settimanale viene pubblicato e distribuito gratuitamente ogni venerd\u00ec in edicole, bar, centri commerciali e svariati esercizi. Ma \u00e8 possibile anche sfogliarlo comodamente online, cliccando su TU NEWS sfogliabile TU NEWS, PASSIONE PER L\u2019INFORMAZIONE","sameAs":["http:\/\/www.tunews24.it","www.facebook.com\/tunews24"],"url":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/author\/senzafirma\/"},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2019\/12\/31\/fiuggi-il-2020-inizia-in-piazza-con-i-capitani-coraggiosi\/#local-main-organization-logo","url":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2022\/11\/cropped-il-corriere-della-provincia-testata-web-scontornata.png","contentUrl":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2022\/11\/cropped-il-corriere-della-provincia-testata-web-scontornata.png","width":2911,"height":717,"caption":"Globalpress s.r.l."}]}},"_links":{"self":[{"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/posts\/25600","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/users\/18"}],"replies":[{"embeddable":true,"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/comments?post=25600"}],"version-history":[{"count":1,"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/posts\/25600\/revisions"}],"predecessor-version":[{"id":25602,"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/posts\/25600\/revisions\/25602"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/media\/25601"}],"wp:attachment":[{"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/media?parent=25600"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/categories?post=25600"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/tags?post=25600"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}