{"id":25261,"date":"2019-12-25T09:27:01","date_gmt":"2019-12-25T08:27:01","guid":{"rendered":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/?p=25261"},"modified":"2019-12-25T09:35:38","modified_gmt":"2019-12-25T08:35:38","slug":"serena-viselli-fdi-ceprano-giorgia-meloni-frosinone","status":"publish","type":"post","link":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2019\/12\/25\/serena-viselli-fdi-ceprano-giorgia-meloni-frosinone\/","title":{"rendered":"Serena Viselli aderisce a FdI. Venerdi la presentazione"},"content":{"rendered":"<div dir=\"auto\"><strong>Serena Viselli, ex sindaco di Ceprano<\/strong>, ha aderito a Fratelli d&#8217;I&#8217;italia. Venerd\u00ec<strong>\u00a0l&#8217;ufficializzazione<\/strong> nel corso di una conferenza stampa che si terr\u00e0 nella sede del partito di Giorgia Meloni, in piazzale Europa a Frosinone.<strong> L&#8217;incontro \u00e8 fissato per le 11,30. \u00a0<\/strong><\/div>\n<h2><\/h2>\n<h2>La decisione<\/h2>\n<div dir=\"auto\">&#8220;La Viselli, attualmente consigliere comunale di opposizione, ha spiegato che la sua decisione si basa sul fatto che si\u00a0<strong>\u00a0riconosce profondamente in quanto dice e soprattutto fa l\u2019Onorevole Giorgia Meloni: &#8220;<\/strong>donna preparatissima in ogni materia &#8211; ha scritto sulla sua pagina facebook &#8211; e sempre attenta a tutti gli scenari nazionali ed internazionali. \u00a0<span class=\"text_exposed_show\">Lei fa la politica vera, quella che non c&#8217;\u00e8 pi\u00f9, quella di chi sa perch\u00e9 \u00e8 l\u00ec e perch\u00e9 parla. Di chi fa nel presente guardando 100 o 200 anni pi\u00f9 in l\u00e0. Come lei, sono una donna che proviene dal territorio e da una lunga militanza.\u00a0Come lei ci ho sempre messo la faccia. <strong>\u00a0Come lei non ho paura di portare avanti i miei ideali nel pieno e totale rispetto della democrazia e con immenso amore per la mia citt\u00e0 e per l\u2019Italia<\/strong>&#8220;.<\/span><\/div>\n","protected":false},"excerpt":{"rendered":"<p>Serena Viselli, ex sindaco di Ceprano, ha aderito a Fratelli d&#8217;I&#8217;italia. Venerd\u00ec\u00a0l&#8217;ufficializzazione nel corso di una conferenza stampa che si<\/p>\n","protected":false},"author":18,"featured_media":25262,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[28],"tags":[3558,247,94,2961,1012,93,3559,3902],"class_list":["post-25261","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-politica","tag-adesione","tag-ceprano","tag-ciociaria","tag-fdi","tag-fratelli-ditalia","tag-frosinone","tag-giorgia-meloni","tag-serena-viselli"],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v27.8 (Yoast SEO v27.8) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Serena Viselli aderisce a FdI. Venerdi la presentazione - IlCorriereDellaProvincia.it - News h24 e notizie di approfondimento<\/title>\n<meta name=\"description\" content=\"Nel corso di una conferenza stampa che si terr\u00e0 nella sede del partito di Giorgia Meloni, in piazzale Europa a Frosinone. L&#039;incontro \u00e8 fissato per le 11,30. \u00a0\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2019\/12\/25\/serena-viselli-fdi-ceprano-giorgia-meloni-frosinone\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Serena Viselli aderisce a FdI. Venerdi la presentazione\" \/>\n<meta property=\"og:description\" content=\"Nel corso di una conferenza stampa che si terr\u00e0 nella sede del partito di Giorgia Meloni, in piazzale Europa a Frosinone. L&#039;incontro \u00e8 fissato per le 11,30. \u00a0\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2019\/12\/25\/serena-viselli-fdi-ceprano-giorgia-meloni-frosinone\/\" \/>\n<meta property=\"og:site_name\" content=\"IlCorriereDellaProvincia.it - News h24 e notizie di approfondimento\" \/>\n<meta property=\"article:author\" content=\"www.facebook.com\/tunews24\" \/>\n<meta property=\"article:published_time\" content=\"2019-12-25T08:27:01+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2019-12-25T08:35:38+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2019\/12\/serena-viselli.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"480\" \/>\n\t<meta property=\"og:image:height\" content=\"360\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Redazione\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"Redazione\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2019\\\/12\\\/25\\\/serena-viselli-fdi-ceprano-giorgia-meloni-frosinone\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2019\\\/12\\\/25\\\/serena-viselli-fdi-ceprano-giorgia-meloni-frosinone\\\/\"},\"author\":{\"name\":\"Redazione\",\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/#\\\/schema\\\/person\\\/6d7f0a9120d0c03d0c552e9fdf49ed7d\"},\"headline\":\"Serena Viselli aderisce a FdI. Venerdi la presentazione\",\"datePublished\":\"2019-12-25T08:27:01+00:00\",\"dateModified\":\"2019-12-25T08:35:38+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2019\\\/12\\\/25\\\/serena-viselli-fdi-ceprano-giorgia-meloni-frosinone\\\/\"},\"wordCount\":188,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2019\\\/12\\\/25\\\/serena-viselli-fdi-ceprano-giorgia-meloni-frosinone\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2019\\\/12\\\/serena-viselli.jpg\",\"keywords\":[\"adesione\",\"ceprano\",\"Ciociaria\",\"fdI\",\"Fratelli d'Italia\",\"Frosinone\",\"giorgia meloni\",\"Serena Viselli\"],\"articleSection\":[\"Evidenza\"],\"inLanguage\":\"it-IT\",\"copyrightYear\":\"2019\",\"copyrightHolder\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/#organization\"}},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2019\\\/12\\\/25\\\/serena-viselli-fdi-ceprano-giorgia-meloni-frosinone\\\/\",\"url\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2019\\\/12\\\/25\\\/serena-viselli-fdi-ceprano-giorgia-meloni-frosinone\\\/\",\"name\":\"Serena Viselli aderisce a FdI. Venerdi la presentazione - IlCorriereDellaProvincia.it - News h24 e notizie di approfondimento\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2019\\\/12\\\/25\\\/serena-viselli-fdi-ceprano-giorgia-meloni-frosinone\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2019\\\/12\\\/25\\\/serena-viselli-fdi-ceprano-giorgia-meloni-frosinone\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2019\\\/12\\\/serena-viselli.jpg\",\"datePublished\":\"2019-12-25T08:27:01+00:00\",\"dateModified\":\"2019-12-25T08:35:38+00:00\",\"description\":\"Nel corso di una conferenza stampa che si terr\u00e0 nella sede del partito di Giorgia Meloni, in piazzale Europa a Frosinone. L'incontro \u00e8 fissato per le 11,30. \u00a0\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2019\\\/12\\\/25\\\/serena-viselli-fdi-ceprano-giorgia-meloni-frosinone\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2019\\\/12\\\/25\\\/serena-viselli-fdi-ceprano-giorgia-meloni-frosinone\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2019\\\/12\\\/25\\\/serena-viselli-fdi-ceprano-giorgia-meloni-frosinone\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2019\\\/12\\\/serena-viselli.jpg\",\"contentUrl\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2019\\\/12\\\/serena-viselli.jpg\",\"width\":480,\"height\":360,\"caption\":\"serena viselli ceprano fdi frosinone ciociaria\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2019\\\/12\\\/25\\\/serena-viselli-fdi-ceprano-giorgia-meloni-frosinone\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Serena Viselli aderisce a FdI. Venerdi la presentazione\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/#website\",\"url\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/\",\"name\":\"Il Corriere Delle Provincia\",\"description\":\"IlCorriereDellaProvincia.it, quotidiano web di politica, cronaca, inchiesta, lavoro, scuola, turismo, cultura e spettacolo, economia e finanza, salute e benessere. Approfondimenti e notizie aggiornate con foto e video della provincia di Frosinone ma anche news nazionali, dell\u2019Italia e del Mondo.\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":[\"Organization\",\"Place\"],\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/#organization\",\"name\":\"Globalpress s.r.l.\",\"url\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/\",\"logo\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2019\\\/12\\\/25\\\/serena-viselli-fdi-ceprano-giorgia-meloni-frosinone\\\/#local-main-organization-logo\"},\"image\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2019\\\/12\\\/25\\\/serena-viselli-fdi-ceprano-giorgia-meloni-frosinone\\\/#local-main-organization-logo\"},\"telephone\":[],\"openingHoursSpecification\":[{\"@type\":\"OpeningHoursSpecification\",\"dayOfWeek\":[\"Monday\",\"Tuesday\",\"Wednesday\",\"Thursday\",\"Friday\",\"Saturday\",\"Sunday\"],\"opens\":\"09:00\",\"closes\":\"17:00\"}]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/#\\\/schema\\\/person\\\/6d7f0a9120d0c03d0c552e9fdf49ed7d\",\"name\":\"Redazione\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/a40eeacccdcad861f831dde73317f63a542e738f0dc4b79b9f47062d3d4bd1d2?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/a40eeacccdcad861f831dde73317f63a542e738f0dc4b79b9f47062d3d4bd1d2?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/a40eeacccdcad861f831dde73317f63a542e738f0dc4b79b9f47062d3d4bd1d2?s=96&d=mm&r=g\",\"caption\":\"Redazione\"},\"description\":\"SEGUICI ANCHE SUI SOCIAL Facebook: TuNews24 e TuSport24 Instagram: TuNews24 e TuSport24 Youtube: TuNews24 Telegram: TuNews24 Puoi leggerci anche in formato cartaceo: il settimanale viene pubblicato e distribuito gratuitamente ogni venerd\u00ec in edicole, bar, centri commerciali e svariati esercizi. Ma \u00e8 possibile anche sfogliarlo comodamente online, cliccando su TU NEWS sfogliabile TU NEWS, PASSIONE PER L\u2019INFORMAZIONE\",\"sameAs\":[\"http:\\\/\\\/www.tunews24.it\",\"www.facebook.com\\\/tunews24\"],\"url\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/author\\\/senzafirma\\\/\"},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2019\\\/12\\\/25\\\/serena-viselli-fdi-ceprano-giorgia-meloni-frosinone\\\/#local-main-organization-logo\",\"url\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2022\\\/11\\\/cropped-il-corriere-della-provincia-testata-web-scontornata.png\",\"contentUrl\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2022\\\/11\\\/cropped-il-corriere-della-provincia-testata-web-scontornata.png\",\"width\":2911,\"height\":717,\"caption\":\"Globalpress s.r.l.\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Serena Viselli aderisce a FdI. Venerdi la presentazione - IlCorriereDellaProvincia.it - News h24 e notizie di approfondimento","description":"Nel corso di una conferenza stampa che si terr\u00e0 nella sede del partito di Giorgia Meloni, in piazzale Europa a Frosinone. L'incontro \u00e8 fissato per le 11,30. \u00a0","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2019\/12\/25\/serena-viselli-fdi-ceprano-giorgia-meloni-frosinone\/","og_locale":"it_IT","og_type":"article","og_title":"Serena Viselli aderisce a FdI. Venerdi la presentazione","og_description":"Nel corso di una conferenza stampa che si terr\u00e0 nella sede del partito di Giorgia Meloni, in piazzale Europa a Frosinone. L'incontro \u00e8 fissato per le 11,30. \u00a0","og_url":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2019\/12\/25\/serena-viselli-fdi-ceprano-giorgia-meloni-frosinone\/","og_site_name":"IlCorriereDellaProvincia.it - News h24 e notizie di approfondimento","article_author":"www.facebook.com\/tunews24","article_published_time":"2019-12-25T08:27:01+00:00","article_modified_time":"2019-12-25T08:35:38+00:00","og_image":[{"width":480,"height":360,"url":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2019\/12\/serena-viselli.jpg","type":"image\/jpeg"}],"author":"Redazione","twitter_card":"summary_large_image","twitter_misc":{"Scritto da":"Redazione","Tempo di lettura stimato":"1 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2019\/12\/25\/serena-viselli-fdi-ceprano-giorgia-meloni-frosinone\/#article","isPartOf":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2019\/12\/25\/serena-viselli-fdi-ceprano-giorgia-meloni-frosinone\/"},"author":{"name":"Redazione","@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/#\/schema\/person\/6d7f0a9120d0c03d0c552e9fdf49ed7d"},"headline":"Serena Viselli aderisce a FdI. Venerdi la presentazione","datePublished":"2019-12-25T08:27:01+00:00","dateModified":"2019-12-25T08:35:38+00:00","mainEntityOfPage":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2019\/12\/25\/serena-viselli-fdi-ceprano-giorgia-meloni-frosinone\/"},"wordCount":188,"commentCount":0,"publisher":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/#organization"},"image":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2019\/12\/25\/serena-viselli-fdi-ceprano-giorgia-meloni-frosinone\/#primaryimage"},"thumbnailUrl":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2019\/12\/serena-viselli.jpg","keywords":["adesione","ceprano","Ciociaria","fdI","Fratelli d'Italia","Frosinone","giorgia meloni","Serena Viselli"],"articleSection":["Evidenza"],"inLanguage":"it-IT","copyrightYear":"2019","copyrightHolder":{"@id":"https:\/\/www.tunews24.it\/#organization"}},{"@type":"WebPage","@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2019\/12\/25\/serena-viselli-fdi-ceprano-giorgia-meloni-frosinone\/","url":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2019\/12\/25\/serena-viselli-fdi-ceprano-giorgia-meloni-frosinone\/","name":"Serena Viselli aderisce a FdI. Venerdi la presentazione - IlCorriereDellaProvincia.it - News h24 e notizie di approfondimento","isPartOf":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2019\/12\/25\/serena-viselli-fdi-ceprano-giorgia-meloni-frosinone\/#primaryimage"},"image":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2019\/12\/25\/serena-viselli-fdi-ceprano-giorgia-meloni-frosinone\/#primaryimage"},"thumbnailUrl":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2019\/12\/serena-viselli.jpg","datePublished":"2019-12-25T08:27:01+00:00","dateModified":"2019-12-25T08:35:38+00:00","description":"Nel corso di una conferenza stampa che si terr\u00e0 nella sede del partito di Giorgia Meloni, in piazzale Europa a Frosinone. L'incontro \u00e8 fissato per le 11,30. \u00a0","breadcrumb":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2019\/12\/25\/serena-viselli-fdi-ceprano-giorgia-meloni-frosinone\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2019\/12\/25\/serena-viselli-fdi-ceprano-giorgia-meloni-frosinone\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2019\/12\/25\/serena-viselli-fdi-ceprano-giorgia-meloni-frosinone\/#primaryimage","url":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2019\/12\/serena-viselli.jpg","contentUrl":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2019\/12\/serena-viselli.jpg","width":480,"height":360,"caption":"serena viselli ceprano fdi frosinone ciociaria"},{"@type":"BreadcrumbList","@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2019\/12\/25\/serena-viselli-fdi-ceprano-giorgia-meloni-frosinone\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/"},{"@type":"ListItem","position":2,"name":"Serena Viselli aderisce a FdI. Venerdi la presentazione"}]},{"@type":"WebSite","@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/#website","url":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/","name":"Il Corriere Delle Provincia","description":"IlCorriereDellaProvincia.it, quotidiano web di politica, cronaca, inchiesta, lavoro, scuola, turismo, cultura e spettacolo, economia e finanza, salute e benessere. Approfondimenti e notizie aggiornate con foto e video della provincia di Frosinone ma anche news nazionali, dell\u2019Italia e del Mondo.","publisher":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":["Organization","Place"],"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/#organization","name":"Globalpress s.r.l.","url":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/","logo":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2019\/12\/25\/serena-viselli-fdi-ceprano-giorgia-meloni-frosinone\/#local-main-organization-logo"},"image":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2019\/12\/25\/serena-viselli-fdi-ceprano-giorgia-meloni-frosinone\/#local-main-organization-logo"},"telephone":[],"openingHoursSpecification":[{"@type":"OpeningHoursSpecification","dayOfWeek":["Monday","Tuesday","Wednesday","Thursday","Friday","Saturday","Sunday"],"opens":"09:00","closes":"17:00"}]},{"@type":"Person","@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/#\/schema\/person\/6d7f0a9120d0c03d0c552e9fdf49ed7d","name":"Redazione","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/secure.gravatar.com\/avatar\/a40eeacccdcad861f831dde73317f63a542e738f0dc4b79b9f47062d3d4bd1d2?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/a40eeacccdcad861f831dde73317f63a542e738f0dc4b79b9f47062d3d4bd1d2?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/a40eeacccdcad861f831dde73317f63a542e738f0dc4b79b9f47062d3d4bd1d2?s=96&d=mm&r=g","caption":"Redazione"},"description":"SEGUICI ANCHE SUI SOCIAL Facebook: TuNews24 e TuSport24 Instagram: TuNews24 e TuSport24 Youtube: TuNews24 Telegram: TuNews24 Puoi leggerci anche in formato cartaceo: il settimanale viene pubblicato e distribuito gratuitamente ogni venerd\u00ec in edicole, bar, centri commerciali e svariati esercizi. Ma \u00e8 possibile anche sfogliarlo comodamente online, cliccando su TU NEWS sfogliabile TU NEWS, PASSIONE PER L\u2019INFORMAZIONE","sameAs":["http:\/\/www.tunews24.it","www.facebook.com\/tunews24"],"url":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/author\/senzafirma\/"},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2019\/12\/25\/serena-viselli-fdi-ceprano-giorgia-meloni-frosinone\/#local-main-organization-logo","url":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2022\/11\/cropped-il-corriere-della-provincia-testata-web-scontornata.png","contentUrl":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2022\/11\/cropped-il-corriere-della-provincia-testata-web-scontornata.png","width":2911,"height":717,"caption":"Globalpress s.r.l."}]}},"_links":{"self":[{"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/posts\/25261","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/users\/18"}],"replies":[{"embeddable":true,"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/comments?post=25261"}],"version-history":[{"count":5,"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/posts\/25261\/revisions"}],"predecessor-version":[{"id":25267,"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/posts\/25261\/revisions\/25267"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/media\/25262"}],"wp:attachment":[{"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/media?parent=25261"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/categories?post=25261"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/tags?post=25261"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}