{"id":25113,"date":"2019-12-22T10:22:29","date_gmt":"2019-12-22T09:22:29","guid":{"rendered":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/?p=25113"},"modified":"2019-12-23T17:14:09","modified_gmt":"2019-12-23T16:14:09","slug":"frosinone-rigenerazione-urbana-pratiche-per-10-milioni-di-euro","status":"publish","type":"post","link":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2019\/12\/22\/frosinone-rigenerazione-urbana-pratiche-per-10-milioni-di-euro\/","title":{"rendered":"Frosinone, rigenerazione urbana: pratiche per 10 milioni di euro"},"content":{"rendered":"<p><strong>L&#8217;ufficio urbanistica del Comune di Frosinone<\/strong> sta completando le procedure per l&#8217;affidamento, entro la prossima settimana, degli incarichi relativi alla complessa articolazione della rigenerazione urbana, che interesser\u00e0, secondo le stime, circa 2\/3.000 immobili presenti all&#8217;interno del territorio comunale, con un introito potenziale di circa 10 milioni di euro.<\/p>\n<p>&nbsp;<\/p>\n<h2><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter wp-image-25115\" src=\"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2019\/12\/frosinone-via-moro.jpg\" alt=\"\" width=\"632\" height=\"422\" srcset=\"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2019\/12\/frosinone-via-moro.jpg 562w, https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2019\/12\/frosinone-via-moro-300x200.jpg 300w, https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2019\/12\/frosinone-via-moro-500x334.jpg 500w, https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2019\/12\/frosinone-via-moro-272x182.jpg 272w\" sizes=\"auto, (max-width: 632px) 100vw, 632px\" \/><\/h2>\n<h2><\/h2>\n<h2>La decisione<\/h2>\n<p><strong>La procedura attivata prevede una prima fase di studio preliminare per l&#8217;individuazione degli ambiti e delle tipologie di intervento<\/strong> che dovr\u00e0, poi, essere sottoposta al vaglio sia delle associazioni professionali e di categoria, sia della Giunta e del Consiglio comunale, permettendo il recupero, a fini edilizi, di una vasta parte del territorio urbano e della stessa periferia contigua al centro cittadino.<\/p>\n<figure id=\"attachment_25042\" aria-describedby=\"caption-attachment-25042\" style=\"width: 632px\" class=\"wp-caption aligncenter\"><img loading=\"lazy\" decoding=\"async\" class=\"wp-image-25042\" src=\"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2019\/12\/nicola-ottaviani.jpg\" alt=\"Nicola Ottaviani sindaco frosinone ciociaria\" width=\"632\" height=\"474\" srcset=\"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2019\/12\/nicola-ottaviani.jpg 1521w, https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2019\/12\/nicola-ottaviani-300x225.jpg 300w, https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2019\/12\/nicola-ottaviani-768x576.jpg 768w, https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2019\/12\/nicola-ottaviani-1024x768.jpg 1024w, https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2019\/12\/nicola-ottaviani-500x375.jpg 500w\" sizes=\"auto, (max-width: 632px) 100vw, 632px\" \/><figcaption id=\"caption-attachment-25042\" class=\"wp-caption-text\">Nicola Ottaviani<\/figcaption><\/figure>\n<h2><\/h2>\n<h2>L&#8217;intervento del sindaco<\/h2>\n<p>&#8220;La rigenerazione urbana che sta per partire <strong>&#8211; ha dichiarato il sindaco di Frosinone, Nicola Ottaviani<\/strong> &#8211; \u00e8 sicuramente la novit\u00e0 ed opportunit\u00e0 urbanistica pi\u00f9 importante dall\u2019approvazione del Piano Regolatore Generale, datato circa mezzo secolo, ad oggi, soprattutto perch\u00e9 permetter\u00e0 il recupero delle enormi volumetrie gi\u00e0 esistenti, con l&#8217;adeguamento ad una realt\u00e0 socio-economica mutata, attraverso cambi di destinazione d&#8217;uso o la definitiva sistemazione degli abusi edilizi ereditati dai decenni passati. Proprio per questo motivo, dopo l&#8217;assegnazione degli iniziali incarichi di studio e di valutazione, sar\u00e0 necessario fissare riunioni di carattere quasi settimanale da parte della commissione urbanistica, allargata agli esperti e agli stakeholder del territorio, per utilizzare al meglio le potenzialit\u00e0 di uno strumento sicuramente utile ed agevole&#8221;.<\/p>\n<h2><\/h2>\n<h2>L&#8217;obiettivo<\/h2>\n<p>&#8220;<strong>Dopo il pronunciamento che sar\u00e0 effettuato da parte del Consiglio comunale, si dovr\u00e0 procedere nei due\/tre anni successivi alla istruttoria<\/strong> delle singole pratiche, per evitare di dirottare le risorse e le intenzioni di quanti vogliono investire sul capoluogo verso altre direzioni o paralleli geografici. Del resto, la rigenerazione del tessuto urbanistico passa anche per l&#8217;armonizzazione del recupero delle volumetrie preesistenti, che dovranno essere integrate all&#8217;interno di un\u00a0contesto nel quale il verde, gli standard pubblici ed i servizi di interesse collettivo, dovranno essere disegnati dall&#8217;ente comunale, in funzione dell&#8217;interesse generale&#8221;.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>L&#8217;ufficio urbanistica del Comune di Frosinone sta completando le procedure per l&#8217;affidamento, entro la prossima settimana, degli incarichi relativi alla<\/p>\n","protected":false},"author":18,"featured_media":25114,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[4,2236],"tags":[94,788,93,639,3091],"class_list":["post-25113","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-primo-piano","category-attualita","tag-ciociaria","tag-edilizia","tag-frosinone","tag-nicola-ottaviani","tag-rigenerazione-urbana"],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v27.8 (Yoast SEO v27.8) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Frosinone, rigenerazione urbana: pratiche per 10 milioni di euro - IlCorriereDellaProvincia.it - News h24 e notizie di approfondimento<\/title>\n<meta name=\"description\" content=\"La procedura attivata prevede una prima fase di studio preliminare per l&#039;individuazione degli ambiti e delle tipologie di intervento\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2019\/12\/22\/frosinone-rigenerazione-urbana-pratiche-per-10-milioni-di-euro\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Frosinone, rigenerazione urbana: pratiche per 10 milioni di euro\" \/>\n<meta property=\"og:description\" content=\"La procedura attivata prevede una prima fase di studio preliminare per l&#039;individuazione degli ambiti e delle tipologie di intervento\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2019\/12\/22\/frosinone-rigenerazione-urbana-pratiche-per-10-milioni-di-euro\/\" \/>\n<meta property=\"og:site_name\" content=\"IlCorriereDellaProvincia.it - News h24 e notizie di approfondimento\" \/>\n<meta property=\"article:author\" content=\"www.facebook.com\/tunews24\" \/>\n<meta property=\"article:published_time\" content=\"2019-12-22T09:22:29+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2019-12-23T16:14:09+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2019\/12\/frosinone-bassa.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"787\" \/>\n\t<meta property=\"og:image:height\" content=\"525\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Redazione\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"Redazione\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minuti\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2019\\\/12\\\/22\\\/frosinone-rigenerazione-urbana-pratiche-per-10-milioni-di-euro\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2019\\\/12\\\/22\\\/frosinone-rigenerazione-urbana-pratiche-per-10-milioni-di-euro\\\/\"},\"author\":{\"name\":\"Redazione\",\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/#\\\/schema\\\/person\\\/6d7f0a9120d0c03d0c552e9fdf49ed7d\"},\"headline\":\"Frosinone, rigenerazione urbana: pratiche per 10 milioni di euro\",\"datePublished\":\"2019-12-22T09:22:29+00:00\",\"dateModified\":\"2019-12-23T16:14:09+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2019\\\/12\\\/22\\\/frosinone-rigenerazione-urbana-pratiche-per-10-milioni-di-euro\\\/\"},\"wordCount\":353,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2019\\\/12\\\/22\\\/frosinone-rigenerazione-urbana-pratiche-per-10-milioni-di-euro\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2019\\\/12\\\/frosinone-bassa.jpg\",\"keywords\":[\"Ciociaria\",\"edilizia\",\"Frosinone\",\"nicola ottaviani\",\"rigenerazione urbana\"],\"articleSection\":[\"*PRIMO PIANO*\",\"Attualit\u00e0\"],\"inLanguage\":\"it-IT\",\"copyrightYear\":\"2019\",\"copyrightHolder\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/#organization\"}},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2019\\\/12\\\/22\\\/frosinone-rigenerazione-urbana-pratiche-per-10-milioni-di-euro\\\/\",\"url\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2019\\\/12\\\/22\\\/frosinone-rigenerazione-urbana-pratiche-per-10-milioni-di-euro\\\/\",\"name\":\"Frosinone, rigenerazione urbana: pratiche per 10 milioni di euro - IlCorriereDellaProvincia.it - News h24 e notizie di approfondimento\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2019\\\/12\\\/22\\\/frosinone-rigenerazione-urbana-pratiche-per-10-milioni-di-euro\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2019\\\/12\\\/22\\\/frosinone-rigenerazione-urbana-pratiche-per-10-milioni-di-euro\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2019\\\/12\\\/frosinone-bassa.jpg\",\"datePublished\":\"2019-12-22T09:22:29+00:00\",\"dateModified\":\"2019-12-23T16:14:09+00:00\",\"description\":\"La procedura attivata prevede una prima fase di studio preliminare per l'individuazione degli ambiti e delle tipologie di intervento\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2019\\\/12\\\/22\\\/frosinone-rigenerazione-urbana-pratiche-per-10-milioni-di-euro\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2019\\\/12\\\/22\\\/frosinone-rigenerazione-urbana-pratiche-per-10-milioni-di-euro\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2019\\\/12\\\/22\\\/frosinone-rigenerazione-urbana-pratiche-per-10-milioni-di-euro\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2019\\\/12\\\/frosinone-bassa.jpg\",\"contentUrl\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2019\\\/12\\\/frosinone-bassa.jpg\",\"width\":787,\"height\":525,\"caption\":\"frosinone ciociaria edilizia\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2019\\\/12\\\/22\\\/frosinone-rigenerazione-urbana-pratiche-per-10-milioni-di-euro\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Frosinone, rigenerazione urbana: pratiche per 10 milioni di euro\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/#website\",\"url\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/\",\"name\":\"Il Corriere Delle Provincia\",\"description\":\"IlCorriereDellaProvincia.it, quotidiano web di politica, cronaca, inchiesta, lavoro, scuola, turismo, cultura e spettacolo, economia e finanza, salute e benessere. Approfondimenti e notizie aggiornate con foto e video della provincia di Frosinone ma anche news nazionali, dell\u2019Italia e del Mondo.\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":[\"Organization\",\"Place\"],\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/#organization\",\"name\":\"Globalpress s.r.l.\",\"url\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/\",\"logo\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2019\\\/12\\\/22\\\/frosinone-rigenerazione-urbana-pratiche-per-10-milioni-di-euro\\\/#local-main-organization-logo\"},\"image\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2019\\\/12\\\/22\\\/frosinone-rigenerazione-urbana-pratiche-per-10-milioni-di-euro\\\/#local-main-organization-logo\"},\"telephone\":[],\"openingHoursSpecification\":[{\"@type\":\"OpeningHoursSpecification\",\"dayOfWeek\":[\"Monday\",\"Tuesday\",\"Wednesday\",\"Thursday\",\"Friday\",\"Saturday\",\"Sunday\"],\"opens\":\"09:00\",\"closes\":\"17:00\"}]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/#\\\/schema\\\/person\\\/6d7f0a9120d0c03d0c552e9fdf49ed7d\",\"name\":\"Redazione\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/a40eeacccdcad861f831dde73317f63a542e738f0dc4b79b9f47062d3d4bd1d2?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/a40eeacccdcad861f831dde73317f63a542e738f0dc4b79b9f47062d3d4bd1d2?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/a40eeacccdcad861f831dde73317f63a542e738f0dc4b79b9f47062d3d4bd1d2?s=96&d=mm&r=g\",\"caption\":\"Redazione\"},\"description\":\"SEGUICI ANCHE SUI SOCIAL Facebook: TuNews24 e TuSport24 Instagram: TuNews24 e TuSport24 Youtube: TuNews24 Telegram: TuNews24 Puoi leggerci anche in formato cartaceo: il settimanale viene pubblicato e distribuito gratuitamente ogni venerd\u00ec in edicole, bar, centri commerciali e svariati esercizi. Ma \u00e8 possibile anche sfogliarlo comodamente online, cliccando su TU NEWS sfogliabile TU NEWS, PASSIONE PER L\u2019INFORMAZIONE\",\"sameAs\":[\"http:\\\/\\\/www.tunews24.it\",\"www.facebook.com\\\/tunews24\"],\"url\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/author\\\/senzafirma\\\/\"},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2019\\\/12\\\/22\\\/frosinone-rigenerazione-urbana-pratiche-per-10-milioni-di-euro\\\/#local-main-organization-logo\",\"url\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2022\\\/11\\\/cropped-il-corriere-della-provincia-testata-web-scontornata.png\",\"contentUrl\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2022\\\/11\\\/cropped-il-corriere-della-provincia-testata-web-scontornata.png\",\"width\":2911,\"height\":717,\"caption\":\"Globalpress s.r.l.\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Frosinone, rigenerazione urbana: pratiche per 10 milioni di euro - IlCorriereDellaProvincia.it - News h24 e notizie di approfondimento","description":"La procedura attivata prevede una prima fase di studio preliminare per l'individuazione degli ambiti e delle tipologie di intervento","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2019\/12\/22\/frosinone-rigenerazione-urbana-pratiche-per-10-milioni-di-euro\/","og_locale":"it_IT","og_type":"article","og_title":"Frosinone, rigenerazione urbana: pratiche per 10 milioni di euro","og_description":"La procedura attivata prevede una prima fase di studio preliminare per l'individuazione degli ambiti e delle tipologie di intervento","og_url":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2019\/12\/22\/frosinone-rigenerazione-urbana-pratiche-per-10-milioni-di-euro\/","og_site_name":"IlCorriereDellaProvincia.it - News h24 e notizie di approfondimento","article_author":"www.facebook.com\/tunews24","article_published_time":"2019-12-22T09:22:29+00:00","article_modified_time":"2019-12-23T16:14:09+00:00","og_image":[{"width":787,"height":525,"url":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2019\/12\/frosinone-bassa.jpg","type":"image\/jpeg"}],"author":"Redazione","twitter_card":"summary_large_image","twitter_misc":{"Scritto da":"Redazione","Tempo di lettura stimato":"2 minuti"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2019\/12\/22\/frosinone-rigenerazione-urbana-pratiche-per-10-milioni-di-euro\/#article","isPartOf":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2019\/12\/22\/frosinone-rigenerazione-urbana-pratiche-per-10-milioni-di-euro\/"},"author":{"name":"Redazione","@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/#\/schema\/person\/6d7f0a9120d0c03d0c552e9fdf49ed7d"},"headline":"Frosinone, rigenerazione urbana: pratiche per 10 milioni di euro","datePublished":"2019-12-22T09:22:29+00:00","dateModified":"2019-12-23T16:14:09+00:00","mainEntityOfPage":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2019\/12\/22\/frosinone-rigenerazione-urbana-pratiche-per-10-milioni-di-euro\/"},"wordCount":353,"commentCount":0,"publisher":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/#organization"},"image":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2019\/12\/22\/frosinone-rigenerazione-urbana-pratiche-per-10-milioni-di-euro\/#primaryimage"},"thumbnailUrl":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2019\/12\/frosinone-bassa.jpg","keywords":["Ciociaria","edilizia","Frosinone","nicola ottaviani","rigenerazione urbana"],"articleSection":["*PRIMO PIANO*","Attualit\u00e0"],"inLanguage":"it-IT","copyrightYear":"2019","copyrightHolder":{"@id":"https:\/\/www.tunews24.it\/#organization"}},{"@type":"WebPage","@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2019\/12\/22\/frosinone-rigenerazione-urbana-pratiche-per-10-milioni-di-euro\/","url":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2019\/12\/22\/frosinone-rigenerazione-urbana-pratiche-per-10-milioni-di-euro\/","name":"Frosinone, rigenerazione urbana: pratiche per 10 milioni di euro - IlCorriereDellaProvincia.it - News h24 e notizie di approfondimento","isPartOf":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2019\/12\/22\/frosinone-rigenerazione-urbana-pratiche-per-10-milioni-di-euro\/#primaryimage"},"image":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2019\/12\/22\/frosinone-rigenerazione-urbana-pratiche-per-10-milioni-di-euro\/#primaryimage"},"thumbnailUrl":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2019\/12\/frosinone-bassa.jpg","datePublished":"2019-12-22T09:22:29+00:00","dateModified":"2019-12-23T16:14:09+00:00","description":"La procedura attivata prevede una prima fase di studio preliminare per l'individuazione degli ambiti e delle tipologie di intervento","breadcrumb":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2019\/12\/22\/frosinone-rigenerazione-urbana-pratiche-per-10-milioni-di-euro\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2019\/12\/22\/frosinone-rigenerazione-urbana-pratiche-per-10-milioni-di-euro\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2019\/12\/22\/frosinone-rigenerazione-urbana-pratiche-per-10-milioni-di-euro\/#primaryimage","url":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2019\/12\/frosinone-bassa.jpg","contentUrl":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2019\/12\/frosinone-bassa.jpg","width":787,"height":525,"caption":"frosinone ciociaria edilizia"},{"@type":"BreadcrumbList","@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2019\/12\/22\/frosinone-rigenerazione-urbana-pratiche-per-10-milioni-di-euro\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/"},{"@type":"ListItem","position":2,"name":"Frosinone, rigenerazione urbana: pratiche per 10 milioni di euro"}]},{"@type":"WebSite","@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/#website","url":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/","name":"Il Corriere Delle Provincia","description":"IlCorriereDellaProvincia.it, quotidiano web di politica, cronaca, inchiesta, lavoro, scuola, turismo, cultura e spettacolo, economia e finanza, salute e benessere. Approfondimenti e notizie aggiornate con foto e video della provincia di Frosinone ma anche news nazionali, dell\u2019Italia e del Mondo.","publisher":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":["Organization","Place"],"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/#organization","name":"Globalpress s.r.l.","url":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/","logo":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2019\/12\/22\/frosinone-rigenerazione-urbana-pratiche-per-10-milioni-di-euro\/#local-main-organization-logo"},"image":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2019\/12\/22\/frosinone-rigenerazione-urbana-pratiche-per-10-milioni-di-euro\/#local-main-organization-logo"},"telephone":[],"openingHoursSpecification":[{"@type":"OpeningHoursSpecification","dayOfWeek":["Monday","Tuesday","Wednesday","Thursday","Friday","Saturday","Sunday"],"opens":"09:00","closes":"17:00"}]},{"@type":"Person","@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/#\/schema\/person\/6d7f0a9120d0c03d0c552e9fdf49ed7d","name":"Redazione","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/secure.gravatar.com\/avatar\/a40eeacccdcad861f831dde73317f63a542e738f0dc4b79b9f47062d3d4bd1d2?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/a40eeacccdcad861f831dde73317f63a542e738f0dc4b79b9f47062d3d4bd1d2?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/a40eeacccdcad861f831dde73317f63a542e738f0dc4b79b9f47062d3d4bd1d2?s=96&d=mm&r=g","caption":"Redazione"},"description":"SEGUICI ANCHE SUI SOCIAL Facebook: TuNews24 e TuSport24 Instagram: TuNews24 e TuSport24 Youtube: TuNews24 Telegram: TuNews24 Puoi leggerci anche in formato cartaceo: il settimanale viene pubblicato e distribuito gratuitamente ogni venerd\u00ec in edicole, bar, centri commerciali e svariati esercizi. Ma \u00e8 possibile anche sfogliarlo comodamente online, cliccando su TU NEWS sfogliabile TU NEWS, PASSIONE PER L\u2019INFORMAZIONE","sameAs":["http:\/\/www.tunews24.it","www.facebook.com\/tunews24"],"url":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/author\/senzafirma\/"},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2019\/12\/22\/frosinone-rigenerazione-urbana-pratiche-per-10-milioni-di-euro\/#local-main-organization-logo","url":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2022\/11\/cropped-il-corriere-della-provincia-testata-web-scontornata.png","contentUrl":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2022\/11\/cropped-il-corriere-della-provincia-testata-web-scontornata.png","width":2911,"height":717,"caption":"Globalpress s.r.l."}]}},"_links":{"self":[{"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/posts\/25113","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/users\/18"}],"replies":[{"embeddable":true,"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/comments?post=25113"}],"version-history":[{"count":1,"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/posts\/25113\/revisions"}],"predecessor-version":[{"id":25116,"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/posts\/25113\/revisions\/25116"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/media\/25114"}],"wp:attachment":[{"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/media?parent=25113"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/categories?post=25113"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/tags?post=25113"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}