{"id":2501,"date":"2018-12-01T11:00:17","date_gmt":"2018-12-01T10:00:17","guid":{"rendered":"http:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/?p=2501"},"modified":"2018-12-02T08:17:02","modified_gmt":"2018-12-02T07:17:02","slug":"frosinone-maglia-nera-per-emissioni-inquinanti","status":"publish","type":"post","link":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2018\/12\/01\/frosinone-maglia-nera-per-emissioni-inquinanti\/","title":{"rendered":"Frosinone maglia nera per emissioni inquinanti"},"content":{"rendered":"<p>\u00c8 una fotografia impietosa, quella scattata dal Rapporto sullo stato delle Province del Lazio, realizzato da Eures ricerche economiche e sociali in collaborazione con Upi Lazio, e presentato nella sede Anci Nazionale.<\/p>\n<p>&#8220;Nonostante la significativa riduzione dei rifiuti solidi urbani (-9,9 per cento nel Lazio e -7,5 per cento in Italia tra il 2007 e il 2016), il Lazio &#8211; evidenzia lo studio &#8211; continua a produrre oltre 3 milioni di tonnellate di rifiuti l\u2019anno, pari a 513 Kg pro-capite (a fronte di 497 Kg in Italia). A livello provinciale tuttavia soltanto Roma (543 Kg, che sale a 588 Kg nel solo comune di Roma) e Latina (503 kg di rifiuti pro-capite) superano la media nazionale, mentre le altre province registrano valori molto inferiori, pari a 421 Kg a Rieti, 416 Kg a Viterbo e<strong> 356 Kg a Frosinone<\/strong>&#8220;.<\/p>\n<h2>Differenziata tra luci e ombre<\/h2>\n<p>&#8220;Pur in presenza di un forte aumento della raccolta (+78,7 per cento rispetto al 2013 e +13 per cento rispetto al 2015), nel Lazio soltanto il 42,9 per cento dei rifiuti viene differenziato (1,28 milioni di tonnellate in valori assoluti, pari a 217 kg per abitante), a fronte del 52,5 per cento in Italia (261 kg pro capite). \u00c8<strong> Rieti a presentare le maggiori criticit\u00e0<\/strong>, con una percentuale pari ad appena il 33,5 per cento (22,2 mila tonnellate, pari a 141 kg per abitante);<strong> seguita da Frosinone<\/strong> (41,8 per cento; 74,9 mila tonnellate, pari a 152 kg in valori pro capite), dall\u2019area metropolitana di Roma (42,3 per cento; 1 milione di tonnellate, 230 kg di rifiuti differenziati per abitante), dalla provincia di Latina (42,7 per cento; 120,9 mila tonnellate, 210 kg per abitante) e da quella di Viterbo (48,1 per cento; 63,9 mila tonnellate, 200 kg pro capite)&#8221;.<\/p>\n<h3>Nel capolugo auto vecchie e inquinanti<\/h3>\n<p>&#8220;Nel 2017 &#8211; secondo i ricercatori Eures &#8211; si contano nel Lazio 63,8 auto ogni 100 abitanti, un risultato in linea alla media nazionale (63,7) e che sale a 75,2 se si considerano anche i motocicli (74,8 in Italia). Tra le province, \u00e8 l&#8217;area metropolitana di Roma a registrare l\u2019incidenza pi\u00f9 bassa, con 62 autoveicoli ogni 100 abitanti, che scendono a 61,4 considerando solo comune di Roma. Sul fronte opposto<strong> Frosinone,<\/strong> con 72,2 autovetture ogni 100 abitanti, <strong>detiene il record negativo<\/strong>, seguita da Viterbo (71,8), Rieti (70,3) e Latina (63,9 auto ogni 100 abitanti). \u00c8 inoltre sempre Frosinone a detenere il parco veicolare pi\u00f9 vecchio e inquinante, con il 48,8 per cento delle auto omologate Euro 0, 1, 2 o 3 (a fronte di una media regionale del 38,5 per cento), seguita da Viterbo (43 per cento), Rieti (46,3 per cento), Latina (42,5 per cento) e Roma (36 per cento). Coerentemente l\u2019incidenza pi\u00f9 bassa delle auto \u201cEuro 6\u201d (12,4 per cento nel Lazio) si registra nella provincia di Frosinone (8 per cento), seguita da Rieti (8,6 per cento), Latina (9,4 per cento) e Viterbo (9,8 per cento), mentre nell\u2019area metropolitana di Roma (13,8 per cento) la loro diffusione risulta superiore a quella mediamente rilevata in Italia (13,5 per cento).<\/p>\n<h3>Pm 10 alle stelle<\/h3>\n<p>&#8220;Frosinone ottiene il <strong>record negativo<\/strong> anche in termini di superamenti dei valori limite di <strong>Pm10<\/strong> (fissati dalla normativa europea come non pi\u00f9 di 35 superamenti della soglia di 50 \u00b5g\/m\u00b3 in un anno) rilevati delle centraline presenti nel Lazio; nel 2017 il numero maggiore di sforamenti si registra infatti nella Valle del Sacco, e in particolare nelle centraline di Frosinone Scalo (93 superamenti), Ceccano (89) e Colleferro (40); nell\u2019agglomerato di Roma, pur registrandosi valori medi spesso vicini alla soglia limite, in tutte le centraline il numero dei superamenti \u00e8 inferiore a 35. La situazione migliore si registra invece nella zona appenninica e nell\u2019area litoranea, dove circa la met\u00e0 delle centraline non ha registrato alcun superamento del valore soglia&#8221;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>\u00c8 una fotografia impietosa, quella scattata dal Rapporto sullo stato delle Province del Lazio, realizzato da Eures ricerche economiche e<\/p>\n","protected":false},"author":3,"featured_media":2508,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[41,2,1],"tags":[921,321,920,93,922],"class_list":["post-2501","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-slide","category-cronaca","category-news","tag-auto-vecchie","tag-differenziata","tag-eures","tag-frosinone","tag-smog"],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v27.8 (Yoast SEO v27.8) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Frosinone maglia nera per emissioni inquinanti - IlCorriereDellaProvincia.it - News h24 e notizie di approfondimento<\/title>\n<meta name=\"description\" content=\"\u00c8 una fotografia impietosa, qualla scattata dal Rapporto sullo stato delle Province del Lazio, realizzato da Eures ricerche economiche e sociali.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2018\/12\/01\/frosinone-maglia-nera-per-emissioni-inquinanti\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Frosinone maglia nera per emissioni inquinanti\" \/>\n<meta property=\"og:description\" content=\"\u00c8 una fotografia impietosa, qualla scattata dal Rapporto sullo stato delle Province del Lazio, realizzato da Eures ricerche economiche e sociali.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2018\/12\/01\/frosinone-maglia-nera-per-emissioni-inquinanti\/\" \/>\n<meta property=\"og:site_name\" content=\"IlCorriereDellaProvincia.it - News h24 e notizie di approfondimento\" \/>\n<meta property=\"article:author\" content=\"http:\/\/www.facebook.com\/TuNews24\" \/>\n<meta property=\"article:published_time\" content=\"2018-12-01T10:00:17+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2018-12-02T07:17:02+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2018\/11\/auto-inquinanti.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"2912\" \/>\n\t<meta property=\"og:image:height\" content=\"1696\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Gianluca Trento\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"Gianluca Trento\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"3 minuti\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2018\\\/12\\\/01\\\/frosinone-maglia-nera-per-emissioni-inquinanti\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2018\\\/12\\\/01\\\/frosinone-maglia-nera-per-emissioni-inquinanti\\\/\"},\"author\":{\"name\":\"Gianluca Trento\",\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/#\\\/schema\\\/person\\\/61ad8468fc64fa3e36d950057c9c2cbd\"},\"headline\":\"Frosinone maglia nera per emissioni inquinanti\",\"datePublished\":\"2018-12-01T10:00:17+00:00\",\"dateModified\":\"2018-12-02T07:17:02+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2018\\\/12\\\/01\\\/frosinone-maglia-nera-per-emissioni-inquinanti\\\/\"},\"wordCount\":563,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2018\\\/12\\\/01\\\/frosinone-maglia-nera-per-emissioni-inquinanti\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2018\\\/11\\\/auto-inquinanti.jpg\",\"keywords\":[\"Auto vecchie\",\"differenziata\",\"Eures\",\"Frosinone\",\"Smog\"],\"articleSection\":[\"*SLIDE*\",\"Cronaca\",\"News\"],\"inLanguage\":\"it-IT\",\"copyrightYear\":\"2018\",\"copyrightHolder\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/#organization\"}},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2018\\\/12\\\/01\\\/frosinone-maglia-nera-per-emissioni-inquinanti\\\/\",\"url\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2018\\\/12\\\/01\\\/frosinone-maglia-nera-per-emissioni-inquinanti\\\/\",\"name\":\"Frosinone maglia nera per emissioni inquinanti - IlCorriereDellaProvincia.it - News h24 e notizie di approfondimento\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2018\\\/12\\\/01\\\/frosinone-maglia-nera-per-emissioni-inquinanti\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2018\\\/12\\\/01\\\/frosinone-maglia-nera-per-emissioni-inquinanti\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2018\\\/11\\\/auto-inquinanti.jpg\",\"datePublished\":\"2018-12-01T10:00:17+00:00\",\"dateModified\":\"2018-12-02T07:17:02+00:00\",\"description\":\"\u00c8 una fotografia impietosa, qualla scattata dal Rapporto sullo stato delle Province del Lazio, realizzato da Eures ricerche economiche e sociali.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2018\\\/12\\\/01\\\/frosinone-maglia-nera-per-emissioni-inquinanti\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2018\\\/12\\\/01\\\/frosinone-maglia-nera-per-emissioni-inquinanti\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2018\\\/12\\\/01\\\/frosinone-maglia-nera-per-emissioni-inquinanti\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2018\\\/11\\\/auto-inquinanti.jpg\",\"contentUrl\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2018\\\/11\\\/auto-inquinanti.jpg\",\"width\":2912,\"height\":1696,\"caption\":\"traffic\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2018\\\/12\\\/01\\\/frosinone-maglia-nera-per-emissioni-inquinanti\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Frosinone maglia nera per emissioni inquinanti\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/#website\",\"url\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/\",\"name\":\"Il Corriere Delle Provincia\",\"description\":\"IlCorriereDellaProvincia.it, quotidiano web di politica, cronaca, inchiesta, lavoro, scuola, turismo, cultura e spettacolo, economia e finanza, salute e benessere. Approfondimenti e notizie aggiornate con foto e video della provincia di Frosinone ma anche news nazionali, dell\u2019Italia e del Mondo.\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":[\"Organization\",\"Place\"],\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/#organization\",\"name\":\"Globalpress s.r.l.\",\"url\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/\",\"logo\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2018\\\/12\\\/01\\\/frosinone-maglia-nera-per-emissioni-inquinanti\\\/#local-main-organization-logo\"},\"image\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2018\\\/12\\\/01\\\/frosinone-maglia-nera-per-emissioni-inquinanti\\\/#local-main-organization-logo\"},\"telephone\":[],\"openingHoursSpecification\":[{\"@type\":\"OpeningHoursSpecification\",\"dayOfWeek\":[\"Monday\",\"Tuesday\",\"Wednesday\",\"Thursday\",\"Friday\",\"Saturday\",\"Sunday\"],\"opens\":\"09:00\",\"closes\":\"17:00\"}]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/#\\\/schema\\\/person\\\/61ad8468fc64fa3e36d950057c9c2cbd\",\"name\":\"Gianluca Trento\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/8c3ab5f4c6ed6f32f95ece33488c4ec55733fd2c584ad602d0b29746892705ab?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/8c3ab5f4c6ed6f32f95ece33488c4ec55733fd2c584ad602d0b29746892705ab?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/8c3ab5f4c6ed6f32f95ece33488c4ec55733fd2c584ad602d0b29746892705ab?s=96&d=mm&r=g\",\"caption\":\"Gianluca Trento\"},\"description\":\"Giornalista dei quotidiani online \\\"LaProvinciaQuotidiano.it\\\" e \\\"TuNews24.it\\\" e del settimanale cartaceo \\\"Tu News\\\". In passato \u00e8 stato anche Direttore Editoriale de \\\"La Provincia\\\", Direttore Responsabile del quotidiano \\\"Ciociaria Oggi\\\", Condirettore de \\\"Il quotidiano della Ciociaria\\\", giornalista di \\\"Paese Sera\\\", del settimanale \\\"L\u2019Inchiesta\\\" e del quotidiano online \\\"Il Corriere della Provincia\\\".\",\"sameAs\":[\"https:\\\/\\\/www.tunews24.it\",\"http:\\\/\\\/www.facebook.com\\\/TuNews24\"],\"url\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/author\\\/gianluca\\\/\"},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2018\\\/12\\\/01\\\/frosinone-maglia-nera-per-emissioni-inquinanti\\\/#local-main-organization-logo\",\"url\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2022\\\/11\\\/cropped-il-corriere-della-provincia-testata-web-scontornata.png\",\"contentUrl\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2022\\\/11\\\/cropped-il-corriere-della-provincia-testata-web-scontornata.png\",\"width\":2911,\"height\":717,\"caption\":\"Globalpress s.r.l.\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Frosinone maglia nera per emissioni inquinanti - IlCorriereDellaProvincia.it - News h24 e notizie di approfondimento","description":"\u00c8 una fotografia impietosa, qualla scattata dal Rapporto sullo stato delle Province del Lazio, realizzato da Eures ricerche economiche e sociali.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2018\/12\/01\/frosinone-maglia-nera-per-emissioni-inquinanti\/","og_locale":"it_IT","og_type":"article","og_title":"Frosinone maglia nera per emissioni inquinanti","og_description":"\u00c8 una fotografia impietosa, qualla scattata dal Rapporto sullo stato delle Province del Lazio, realizzato da Eures ricerche economiche e sociali.","og_url":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2018\/12\/01\/frosinone-maglia-nera-per-emissioni-inquinanti\/","og_site_name":"IlCorriereDellaProvincia.it - News h24 e notizie di approfondimento","article_author":"http:\/\/www.facebook.com\/TuNews24","article_published_time":"2018-12-01T10:00:17+00:00","article_modified_time":"2018-12-02T07:17:02+00:00","og_image":[{"width":2912,"height":1696,"url":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2018\/11\/auto-inquinanti.jpg","type":"image\/jpeg"}],"author":"Gianluca Trento","twitter_card":"summary_large_image","twitter_misc":{"Scritto da":"Gianluca Trento","Tempo di lettura stimato":"3 minuti"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2018\/12\/01\/frosinone-maglia-nera-per-emissioni-inquinanti\/#article","isPartOf":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2018\/12\/01\/frosinone-maglia-nera-per-emissioni-inquinanti\/"},"author":{"name":"Gianluca Trento","@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/#\/schema\/person\/61ad8468fc64fa3e36d950057c9c2cbd"},"headline":"Frosinone maglia nera per emissioni inquinanti","datePublished":"2018-12-01T10:00:17+00:00","dateModified":"2018-12-02T07:17:02+00:00","mainEntityOfPage":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2018\/12\/01\/frosinone-maglia-nera-per-emissioni-inquinanti\/"},"wordCount":563,"commentCount":0,"publisher":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/#organization"},"image":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2018\/12\/01\/frosinone-maglia-nera-per-emissioni-inquinanti\/#primaryimage"},"thumbnailUrl":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2018\/11\/auto-inquinanti.jpg","keywords":["Auto vecchie","differenziata","Eures","Frosinone","Smog"],"articleSection":["*SLIDE*","Cronaca","News"],"inLanguage":"it-IT","copyrightYear":"2018","copyrightHolder":{"@id":"https:\/\/www.tunews24.it\/#organization"}},{"@type":"WebPage","@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2018\/12\/01\/frosinone-maglia-nera-per-emissioni-inquinanti\/","url":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2018\/12\/01\/frosinone-maglia-nera-per-emissioni-inquinanti\/","name":"Frosinone maglia nera per emissioni inquinanti - IlCorriereDellaProvincia.it - News h24 e notizie di approfondimento","isPartOf":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2018\/12\/01\/frosinone-maglia-nera-per-emissioni-inquinanti\/#primaryimage"},"image":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2018\/12\/01\/frosinone-maglia-nera-per-emissioni-inquinanti\/#primaryimage"},"thumbnailUrl":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2018\/11\/auto-inquinanti.jpg","datePublished":"2018-12-01T10:00:17+00:00","dateModified":"2018-12-02T07:17:02+00:00","description":"\u00c8 una fotografia impietosa, qualla scattata dal Rapporto sullo stato delle Province del Lazio, realizzato da Eures ricerche economiche e sociali.","breadcrumb":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2018\/12\/01\/frosinone-maglia-nera-per-emissioni-inquinanti\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2018\/12\/01\/frosinone-maglia-nera-per-emissioni-inquinanti\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2018\/12\/01\/frosinone-maglia-nera-per-emissioni-inquinanti\/#primaryimage","url":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2018\/11\/auto-inquinanti.jpg","contentUrl":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2018\/11\/auto-inquinanti.jpg","width":2912,"height":1696,"caption":"traffic"},{"@type":"BreadcrumbList","@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2018\/12\/01\/frosinone-maglia-nera-per-emissioni-inquinanti\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/"},{"@type":"ListItem","position":2,"name":"Frosinone maglia nera per emissioni inquinanti"}]},{"@type":"WebSite","@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/#website","url":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/","name":"Il Corriere Delle Provincia","description":"IlCorriereDellaProvincia.it, quotidiano web di politica, cronaca, inchiesta, lavoro, scuola, turismo, cultura e spettacolo, economia e finanza, salute e benessere. Approfondimenti e notizie aggiornate con foto e video della provincia di Frosinone ma anche news nazionali, dell\u2019Italia e del Mondo.","publisher":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":["Organization","Place"],"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/#organization","name":"Globalpress s.r.l.","url":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/","logo":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2018\/12\/01\/frosinone-maglia-nera-per-emissioni-inquinanti\/#local-main-organization-logo"},"image":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2018\/12\/01\/frosinone-maglia-nera-per-emissioni-inquinanti\/#local-main-organization-logo"},"telephone":[],"openingHoursSpecification":[{"@type":"OpeningHoursSpecification","dayOfWeek":["Monday","Tuesday","Wednesday","Thursday","Friday","Saturday","Sunday"],"opens":"09:00","closes":"17:00"}]},{"@type":"Person","@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/#\/schema\/person\/61ad8468fc64fa3e36d950057c9c2cbd","name":"Gianluca Trento","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/secure.gravatar.com\/avatar\/8c3ab5f4c6ed6f32f95ece33488c4ec55733fd2c584ad602d0b29746892705ab?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/8c3ab5f4c6ed6f32f95ece33488c4ec55733fd2c584ad602d0b29746892705ab?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/8c3ab5f4c6ed6f32f95ece33488c4ec55733fd2c584ad602d0b29746892705ab?s=96&d=mm&r=g","caption":"Gianluca Trento"},"description":"Giornalista dei quotidiani online \"LaProvinciaQuotidiano.it\" e \"TuNews24.it\" e del settimanale cartaceo \"Tu News\". In passato \u00e8 stato anche Direttore Editoriale de \"La Provincia\", Direttore Responsabile del quotidiano \"Ciociaria Oggi\", Condirettore de \"Il quotidiano della Ciociaria\", giornalista di \"Paese Sera\", del settimanale \"L\u2019Inchiesta\" e del quotidiano online \"Il Corriere della Provincia\".","sameAs":["https:\/\/www.tunews24.it","http:\/\/www.facebook.com\/TuNews24"],"url":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/author\/gianluca\/"},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2018\/12\/01\/frosinone-maglia-nera-per-emissioni-inquinanti\/#local-main-organization-logo","url":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2022\/11\/cropped-il-corriere-della-provincia-testata-web-scontornata.png","contentUrl":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2022\/11\/cropped-il-corriere-della-provincia-testata-web-scontornata.png","width":2911,"height":717,"caption":"Globalpress s.r.l."}]}},"_links":{"self":[{"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/posts\/2501","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/comments?post=2501"}],"version-history":[{"count":4,"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/posts\/2501\/revisions"}],"predecessor-version":[{"id":2518,"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/posts\/2501\/revisions\/2518"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/media\/2508"}],"wp:attachment":[{"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/media?parent=2501"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/categories?post=2501"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/tags?post=2501"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}