{"id":24567,"date":"2019-12-14T14:56:22","date_gmt":"2019-12-14T13:56:22","guid":{"rendered":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/?p=24567"},"modified":"2019-12-14T14:57:19","modified_gmt":"2019-12-14T13:57:19","slug":"fanno-acquisti-i-con-soldi-falsi-a-sora-e-isola-del-liri-arrestati","status":"publish","type":"post","link":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2019\/12\/14\/fanno-acquisti-i-con-soldi-falsi-a-sora-e-isola-del-liri-arrestati\/","title":{"rendered":"Fanno acquisti i con soldi falsi a Sora e Isola del Liri, finiscono in manette"},"content":{"rendered":"<p><strong>Hanno pagato gli acquisti effettuati all\u2019interno di un noto esercizio commerciale di Isola del Liri<\/strong> con banconote da euro 20 palesemente contraffatte. Poi si sono allontanati a bordo di una utilitaria di colore bianco. Il commerciante, accortosi\u00a0 del raggiro, ha contattato il 112.<\/p>\n<h2><\/h2>\n<h2>L&#8217;operazione<\/h2>\n<p>Gli uomini dell\u2019Arma, dopo pochi minuti, hanno individuato l\u2019autovettura. La coppia, una volta bloccata, \u00e8 stata sottoposta a perquisizione. I <strong>carabinieri, all\u2019interno del portellone del bagagliaio del mezzo, hanno scovato un pacchetto<\/strong>, confezionato con carta d\u2019alluminio, <strong>contenente \u00a083 banconote false<\/strong>, tutte del taglio di \u00a020 euro, per un valore nominale complessivo di 1.660 euro.<\/p>\n<h2><\/h2>\n<h2>La ricostruzione<\/h2>\n<p><strong>Anche attraverso la visione dei filmati dell\u2019impianto di videosorveglianza<\/strong> dell\u2019esercizio commerciale, i militari sono riusciti ad identificare, con certezza, i due fermati quali autori della spendita delle banconote contraffatte. Le successive indagini, tramite l\u2019acquisizione di informazioni testimoniali, hanno permesso di verificare che i d<strong>ue avevano effettuato ulteriori acquisti, sempre mediante banconote contraffatte da 20 euro presso altre due attivit\u00e0 commerciali di Sora. <\/strong>Al termine delle formalit\u00e0 di rito, i due sono stati rinchiusi nella Casa circondariale di Cassino<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Hanno pagato gli acquisti effettuati all\u2019interno di un noto esercizio commerciale di Isola del Liri con banconote da euro 20<\/p>\n","protected":false},"author":18,"featured_media":24568,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[41],"tags":[440,90,6144,93,260,1273,161],"class_list":["post-24567","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-slide","tag-arresti","tag-carabinieri","tag-ciociria","tag-frosinone","tag-isola-del-liri","tag-soldi-falsi","tag-sora"],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v27.8 (Yoast SEO v27.8) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Fanno acquisti i con soldi falsi a Sora e Isola del Liri, finiscono in manette - IlCorriereDellaProvincia.it - News h24 e notizie di approfondimento<\/title>\n<meta name=\"description\" content=\"Gli uomini dell\u2019Arma, dopo pochi minuti, hanno individuato l\u2019autovettura. La coppia, una volta bloccata, \u00e8 stata sottoposta a perquisizione\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2019\/12\/14\/fanno-acquisti-i-con-soldi-falsi-a-sora-e-isola-del-liri-arrestati\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Fanno acquisti i con soldi falsi a Sora e Isola del Liri, finiscono in manette\" \/>\n<meta property=\"og:description\" content=\"Gli uomini dell\u2019Arma, dopo pochi minuti, hanno individuato l\u2019autovettura. La coppia, una volta bloccata, \u00e8 stata sottoposta a perquisizione\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2019\/12\/14\/fanno-acquisti-i-con-soldi-falsi-a-sora-e-isola-del-liri-arrestati\/\" \/>\n<meta property=\"og:site_name\" content=\"IlCorriereDellaProvincia.it - News h24 e notizie di approfondimento\" \/>\n<meta property=\"article:author\" content=\"www.facebook.com\/tunews24\" \/>\n<meta property=\"article:published_time\" content=\"2019-12-14T13:56:22+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2019-12-14T13:57:19+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2019\/12\/soldi-falsi-carabinieri.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"692\" \/>\n\t<meta property=\"og:image:height\" content=\"476\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Redazione\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"Redazione\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2019\\\/12\\\/14\\\/fanno-acquisti-i-con-soldi-falsi-a-sora-e-isola-del-liri-arrestati\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2019\\\/12\\\/14\\\/fanno-acquisti-i-con-soldi-falsi-a-sora-e-isola-del-liri-arrestati\\\/\"},\"author\":{\"name\":\"Redazione\",\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/#\\\/schema\\\/person\\\/6d7f0a9120d0c03d0c552e9fdf49ed7d\"},\"headline\":\"Fanno acquisti i con soldi falsi a Sora e Isola del Liri, finiscono in manette\",\"datePublished\":\"2019-12-14T13:56:22+00:00\",\"dateModified\":\"2019-12-14T13:57:19+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2019\\\/12\\\/14\\\/fanno-acquisti-i-con-soldi-falsi-a-sora-e-isola-del-liri-arrestati\\\/\"},\"wordCount\":195,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2019\\\/12\\\/14\\\/fanno-acquisti-i-con-soldi-falsi-a-sora-e-isola-del-liri-arrestati\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2019\\\/12\\\/soldi-falsi-carabinieri.jpg\",\"keywords\":[\"arresti\",\"carabinieri\",\"Ciociria\",\"Frosinone\",\"isola del liri\",\"soldi falsi\",\"sora\"],\"articleSection\":[\"*SLIDE*\"],\"inLanguage\":\"it-IT\",\"copyrightYear\":\"2019\",\"copyrightHolder\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/#organization\"}},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2019\\\/12\\\/14\\\/fanno-acquisti-i-con-soldi-falsi-a-sora-e-isola-del-liri-arrestati\\\/\",\"url\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2019\\\/12\\\/14\\\/fanno-acquisti-i-con-soldi-falsi-a-sora-e-isola-del-liri-arrestati\\\/\",\"name\":\"Fanno acquisti i con soldi falsi a Sora e Isola del Liri, finiscono in manette - IlCorriereDellaProvincia.it - News h24 e notizie di approfondimento\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2019\\\/12\\\/14\\\/fanno-acquisti-i-con-soldi-falsi-a-sora-e-isola-del-liri-arrestati\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2019\\\/12\\\/14\\\/fanno-acquisti-i-con-soldi-falsi-a-sora-e-isola-del-liri-arrestati\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2019\\\/12\\\/soldi-falsi-carabinieri.jpg\",\"datePublished\":\"2019-12-14T13:56:22+00:00\",\"dateModified\":\"2019-12-14T13:57:19+00:00\",\"description\":\"Gli uomini dell\u2019Arma, dopo pochi minuti, hanno individuato l\u2019autovettura. La coppia, una volta bloccata, \u00e8 stata sottoposta a perquisizione\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2019\\\/12\\\/14\\\/fanno-acquisti-i-con-soldi-falsi-a-sora-e-isola-del-liri-arrestati\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2019\\\/12\\\/14\\\/fanno-acquisti-i-con-soldi-falsi-a-sora-e-isola-del-liri-arrestati\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2019\\\/12\\\/14\\\/fanno-acquisti-i-con-soldi-falsi-a-sora-e-isola-del-liri-arrestati\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2019\\\/12\\\/soldi-falsi-carabinieri.jpg\",\"contentUrl\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2019\\\/12\\\/soldi-falsi-carabinieri.jpg\",\"width\":692,\"height\":476,\"caption\":\"smart\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2019\\\/12\\\/14\\\/fanno-acquisti-i-con-soldi-falsi-a-sora-e-isola-del-liri-arrestati\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Fanno acquisti i con soldi falsi a Sora e Isola del Liri, finiscono in manette\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/#website\",\"url\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/\",\"name\":\"Il Corriere Delle Provincia\",\"description\":\"IlCorriereDellaProvincia.it, quotidiano web di politica, cronaca, inchiesta, lavoro, scuola, turismo, cultura e spettacolo, economia e finanza, salute e benessere. Approfondimenti e notizie aggiornate con foto e video della provincia di Frosinone ma anche news nazionali, dell\u2019Italia e del Mondo.\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":[\"Organization\",\"Place\"],\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/#organization\",\"name\":\"Globalpress s.r.l.\",\"url\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/\",\"logo\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2019\\\/12\\\/14\\\/fanno-acquisti-i-con-soldi-falsi-a-sora-e-isola-del-liri-arrestati\\\/#local-main-organization-logo\"},\"image\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2019\\\/12\\\/14\\\/fanno-acquisti-i-con-soldi-falsi-a-sora-e-isola-del-liri-arrestati\\\/#local-main-organization-logo\"},\"telephone\":[],\"openingHoursSpecification\":[{\"@type\":\"OpeningHoursSpecification\",\"dayOfWeek\":[\"Monday\",\"Tuesday\",\"Wednesday\",\"Thursday\",\"Friday\",\"Saturday\",\"Sunday\"],\"opens\":\"09:00\",\"closes\":\"17:00\"}]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/#\\\/schema\\\/person\\\/6d7f0a9120d0c03d0c552e9fdf49ed7d\",\"name\":\"Redazione\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/a40eeacccdcad861f831dde73317f63a542e738f0dc4b79b9f47062d3d4bd1d2?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/a40eeacccdcad861f831dde73317f63a542e738f0dc4b79b9f47062d3d4bd1d2?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/a40eeacccdcad861f831dde73317f63a542e738f0dc4b79b9f47062d3d4bd1d2?s=96&d=mm&r=g\",\"caption\":\"Redazione\"},\"description\":\"SEGUICI ANCHE SUI SOCIAL Facebook: TuNews24 e TuSport24 Instagram: TuNews24 e TuSport24 Youtube: TuNews24 Telegram: TuNews24 Puoi leggerci anche in formato cartaceo: il settimanale viene pubblicato e distribuito gratuitamente ogni venerd\u00ec in edicole, bar, centri commerciali e svariati esercizi. Ma \u00e8 possibile anche sfogliarlo comodamente online, cliccando su TU NEWS sfogliabile TU NEWS, PASSIONE PER L\u2019INFORMAZIONE\",\"sameAs\":[\"http:\\\/\\\/www.tunews24.it\",\"www.facebook.com\\\/tunews24\"],\"url\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/author\\\/senzafirma\\\/\"},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2019\\\/12\\\/14\\\/fanno-acquisti-i-con-soldi-falsi-a-sora-e-isola-del-liri-arrestati\\\/#local-main-organization-logo\",\"url\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2022\\\/11\\\/cropped-il-corriere-della-provincia-testata-web-scontornata.png\",\"contentUrl\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2022\\\/11\\\/cropped-il-corriere-della-provincia-testata-web-scontornata.png\",\"width\":2911,\"height\":717,\"caption\":\"Globalpress s.r.l.\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Fanno acquisti i con soldi falsi a Sora e Isola del Liri, finiscono in manette - IlCorriereDellaProvincia.it - News h24 e notizie di approfondimento","description":"Gli uomini dell\u2019Arma, dopo pochi minuti, hanno individuato l\u2019autovettura. La coppia, una volta bloccata, \u00e8 stata sottoposta a perquisizione","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2019\/12\/14\/fanno-acquisti-i-con-soldi-falsi-a-sora-e-isola-del-liri-arrestati\/","og_locale":"it_IT","og_type":"article","og_title":"Fanno acquisti i con soldi falsi a Sora e Isola del Liri, finiscono in manette","og_description":"Gli uomini dell\u2019Arma, dopo pochi minuti, hanno individuato l\u2019autovettura. La coppia, una volta bloccata, \u00e8 stata sottoposta a perquisizione","og_url":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2019\/12\/14\/fanno-acquisti-i-con-soldi-falsi-a-sora-e-isola-del-liri-arrestati\/","og_site_name":"IlCorriereDellaProvincia.it - News h24 e notizie di approfondimento","article_author":"www.facebook.com\/tunews24","article_published_time":"2019-12-14T13:56:22+00:00","article_modified_time":"2019-12-14T13:57:19+00:00","og_image":[{"width":692,"height":476,"url":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2019\/12\/soldi-falsi-carabinieri.jpg","type":"image\/jpeg"}],"author":"Redazione","twitter_card":"summary_large_image","twitter_misc":{"Scritto da":"Redazione","Tempo di lettura stimato":"1 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2019\/12\/14\/fanno-acquisti-i-con-soldi-falsi-a-sora-e-isola-del-liri-arrestati\/#article","isPartOf":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2019\/12\/14\/fanno-acquisti-i-con-soldi-falsi-a-sora-e-isola-del-liri-arrestati\/"},"author":{"name":"Redazione","@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/#\/schema\/person\/6d7f0a9120d0c03d0c552e9fdf49ed7d"},"headline":"Fanno acquisti i con soldi falsi a Sora e Isola del Liri, finiscono in manette","datePublished":"2019-12-14T13:56:22+00:00","dateModified":"2019-12-14T13:57:19+00:00","mainEntityOfPage":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2019\/12\/14\/fanno-acquisti-i-con-soldi-falsi-a-sora-e-isola-del-liri-arrestati\/"},"wordCount":195,"commentCount":0,"publisher":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/#organization"},"image":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2019\/12\/14\/fanno-acquisti-i-con-soldi-falsi-a-sora-e-isola-del-liri-arrestati\/#primaryimage"},"thumbnailUrl":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2019\/12\/soldi-falsi-carabinieri.jpg","keywords":["arresti","carabinieri","Ciociria","Frosinone","isola del liri","soldi falsi","sora"],"articleSection":["*SLIDE*"],"inLanguage":"it-IT","copyrightYear":"2019","copyrightHolder":{"@id":"https:\/\/www.tunews24.it\/#organization"}},{"@type":"WebPage","@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2019\/12\/14\/fanno-acquisti-i-con-soldi-falsi-a-sora-e-isola-del-liri-arrestati\/","url":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2019\/12\/14\/fanno-acquisti-i-con-soldi-falsi-a-sora-e-isola-del-liri-arrestati\/","name":"Fanno acquisti i con soldi falsi a Sora e Isola del Liri, finiscono in manette - IlCorriereDellaProvincia.it - News h24 e notizie di approfondimento","isPartOf":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2019\/12\/14\/fanno-acquisti-i-con-soldi-falsi-a-sora-e-isola-del-liri-arrestati\/#primaryimage"},"image":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2019\/12\/14\/fanno-acquisti-i-con-soldi-falsi-a-sora-e-isola-del-liri-arrestati\/#primaryimage"},"thumbnailUrl":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2019\/12\/soldi-falsi-carabinieri.jpg","datePublished":"2019-12-14T13:56:22+00:00","dateModified":"2019-12-14T13:57:19+00:00","description":"Gli uomini dell\u2019Arma, dopo pochi minuti, hanno individuato l\u2019autovettura. La coppia, una volta bloccata, \u00e8 stata sottoposta a perquisizione","breadcrumb":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2019\/12\/14\/fanno-acquisti-i-con-soldi-falsi-a-sora-e-isola-del-liri-arrestati\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2019\/12\/14\/fanno-acquisti-i-con-soldi-falsi-a-sora-e-isola-del-liri-arrestati\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2019\/12\/14\/fanno-acquisti-i-con-soldi-falsi-a-sora-e-isola-del-liri-arrestati\/#primaryimage","url":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2019\/12\/soldi-falsi-carabinieri.jpg","contentUrl":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2019\/12\/soldi-falsi-carabinieri.jpg","width":692,"height":476,"caption":"smart"},{"@type":"BreadcrumbList","@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2019\/12\/14\/fanno-acquisti-i-con-soldi-falsi-a-sora-e-isola-del-liri-arrestati\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/"},{"@type":"ListItem","position":2,"name":"Fanno acquisti i con soldi falsi a Sora e Isola del Liri, finiscono in manette"}]},{"@type":"WebSite","@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/#website","url":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/","name":"Il Corriere Delle Provincia","description":"IlCorriereDellaProvincia.it, quotidiano web di politica, cronaca, inchiesta, lavoro, scuola, turismo, cultura e spettacolo, economia e finanza, salute e benessere. Approfondimenti e notizie aggiornate con foto e video della provincia di Frosinone ma anche news nazionali, dell\u2019Italia e del Mondo.","publisher":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":["Organization","Place"],"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/#organization","name":"Globalpress s.r.l.","url":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/","logo":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2019\/12\/14\/fanno-acquisti-i-con-soldi-falsi-a-sora-e-isola-del-liri-arrestati\/#local-main-organization-logo"},"image":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2019\/12\/14\/fanno-acquisti-i-con-soldi-falsi-a-sora-e-isola-del-liri-arrestati\/#local-main-organization-logo"},"telephone":[],"openingHoursSpecification":[{"@type":"OpeningHoursSpecification","dayOfWeek":["Monday","Tuesday","Wednesday","Thursday","Friday","Saturday","Sunday"],"opens":"09:00","closes":"17:00"}]},{"@type":"Person","@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/#\/schema\/person\/6d7f0a9120d0c03d0c552e9fdf49ed7d","name":"Redazione","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/secure.gravatar.com\/avatar\/a40eeacccdcad861f831dde73317f63a542e738f0dc4b79b9f47062d3d4bd1d2?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/a40eeacccdcad861f831dde73317f63a542e738f0dc4b79b9f47062d3d4bd1d2?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/a40eeacccdcad861f831dde73317f63a542e738f0dc4b79b9f47062d3d4bd1d2?s=96&d=mm&r=g","caption":"Redazione"},"description":"SEGUICI ANCHE SUI SOCIAL Facebook: TuNews24 e TuSport24 Instagram: TuNews24 e TuSport24 Youtube: TuNews24 Telegram: TuNews24 Puoi leggerci anche in formato cartaceo: il settimanale viene pubblicato e distribuito gratuitamente ogni venerd\u00ec in edicole, bar, centri commerciali e svariati esercizi. Ma \u00e8 possibile anche sfogliarlo comodamente online, cliccando su TU NEWS sfogliabile TU NEWS, PASSIONE PER L\u2019INFORMAZIONE","sameAs":["http:\/\/www.tunews24.it","www.facebook.com\/tunews24"],"url":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/author\/senzafirma\/"},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2019\/12\/14\/fanno-acquisti-i-con-soldi-falsi-a-sora-e-isola-del-liri-arrestati\/#local-main-organization-logo","url":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2022\/11\/cropped-il-corriere-della-provincia-testata-web-scontornata.png","contentUrl":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2022\/11\/cropped-il-corriere-della-provincia-testata-web-scontornata.png","width":2911,"height":717,"caption":"Globalpress s.r.l."}]}},"_links":{"self":[{"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/posts\/24567","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/users\/18"}],"replies":[{"embeddable":true,"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/comments?post=24567"}],"version-history":[{"count":3,"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/posts\/24567\/revisions"}],"predecessor-version":[{"id":24571,"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/posts\/24567\/revisions\/24571"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/media\/24568"}],"wp:attachment":[{"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/media?parent=24567"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/categories?post=24567"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/tags?post=24567"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}