{"id":2450,"date":"2018-11-30T11:18:45","date_gmt":"2018-11-30T10:18:45","guid":{"rendered":"http:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/?p=2450"},"modified":"2018-11-30T11:18:45","modified_gmt":"2018-11-30T10:18:45","slug":"qualita-dellaria-indoor-de-angelis-ripartire-dalle-scuole-per-creare-una-nuova-e-necessaria-consapevolezza","status":"publish","type":"post","link":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2018\/11\/30\/qualita-dellaria-indoor-de-angelis-ripartire-dalle-scuole-per-creare-una-nuova-e-necessaria-consapevolezza\/","title":{"rendered":"\u201cQualit\u00e0 dell\u2019aria indoor\u201d, De Angelis: ripartire dalle scuole per creare una nuova e necessaria consapevolezza"},"content":{"rendered":"<p>&#8220;Bisogna ripartire dalle scuole perch\u00e9 \u00e8 da l\u00ec che si pu\u00f2 sviluppare una nuova e necessaria consapevolezza su tematiche emergenti come questa&#8221;. Cos\u00ec <strong>Francesco De Angelis,<\/strong> presidente del Consorzio per lo Sviluppo Industriale Frosinone, intervenendo al convegno \u201cQualit\u00e0 dell\u2019aria indoor. Nuovi scenari nornativi\u201d, che si \u00e8 svolto\u00a0 nella sala conferenze dello stadio Benito Stirpe.<\/p>\n<p>L\u2019iniziativa, promossa dalla GWA, azienda specializzata nel trattamento dell\u2019acqua e dell\u2019aria, ha ottenuto il patrocinio dell\u2019Associazione italiana igienisti sistemi aeraulici, del Consiglio regionale del Lazio, della Asl di Frosinone, di Unindustria, dell\u2019universit\u00e0 di Cassino e della Federlazio, oltre al contributo di Sabiana, azienda specializzata nella climatizzazione.<\/p>\n<p>&#8220;Il tema dell\u2019ambiente \u2013 ha aggiunto il numero uno del\u2019Asi \u2013 deve assolutamente rappresentare una priorit\u00e0. Lo \u00e8 sicuramente per noi, che da sempre scommettiamo su uno sviluppo sostenibile per tutelare i cittadini. I dati preoccupanti illustrati oggi, secondo i quali la qualit\u00e0 dell\u2019aria negli ambienti chiusi \u00e8 dannosa per la salute umana,\u00a0 devono portarci a capovolgere la scaletta degli interventi perch\u00e9 non si pu\u00f2 pi\u00f9 soprassedere su un problema tanto serio e che, proprio per questo, deve assolutamente trovare delle risposte. Da questo punto di vista il mio plauso non pu\u00f2 che andare alla Regione Lazio che sta predisponendo il testo di un apposito regolamento con il quale questa materia verr\u00e0 disciplinata. La preoccupazione \u00e8 tanta, ma sono certo che il lavoro di squadra avviato da realt\u00e0 importanti come quelle qui presenti sapr\u00e0 dare i propri frutti&#8221;.<\/p>\n<p>&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>&#8220;Bisogna ripartire dalle scuole perch\u00e9 \u00e8 da l\u00ec che si pu\u00f2 sviluppare una nuova e necessaria consapevolezza su tematiche emergenti<\/p>\n","protected":false},"author":3,"featured_media":2453,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[5],"tags":[],"class_list":["post-2450","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-economia"],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v27.8 (Yoast SEO v27.8) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>\u201cQualit\u00e0 dell\u2019aria indoor\u201d, De Angelis: ripartire dalle scuole per creare una nuova e necessaria consapevolezza - IlCorriereDellaProvincia.it - News h24 e notizie di approfondimento<\/title>\n<meta name=\"description\" content=\"L\u2019iniziativa, promossa dalla GWA, azienda specializzata nel trattamento dell\u2019acqua e dell\u2019aria, ha ottenuto il patrocinio dell\u2019Associazione igienisti.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2018\/11\/30\/qualita-dellaria-indoor-de-angelis-ripartire-dalle-scuole-per-creare-una-nuova-e-necessaria-consapevolezza\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"\u201cQualit\u00e0 dell\u2019aria indoor\u201d, De Angelis: ripartire dalle scuole per creare una nuova e necessaria consapevolezza\" \/>\n<meta property=\"og:description\" content=\"L\u2019iniziativa, promossa dalla GWA, azienda specializzata nel trattamento dell\u2019acqua e dell\u2019aria, ha ottenuto il patrocinio dell\u2019Associazione igienisti.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2018\/11\/30\/qualita-dellaria-indoor-de-angelis-ripartire-dalle-scuole-per-creare-una-nuova-e-necessaria-consapevolezza\/\" \/>\n<meta property=\"og:site_name\" content=\"IlCorriereDellaProvincia.it - News h24 e notizie di approfondimento\" \/>\n<meta property=\"article:author\" content=\"http:\/\/www.facebook.com\/TuNews24\" \/>\n<meta property=\"article:published_time\" content=\"2018-11-30T10:18:45+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2018\/11\/qualit\u00e0-aria-de-angelis.png\" \/>\n\t<meta property=\"og:image:width\" content=\"686\" \/>\n\t<meta property=\"og:image:height\" content=\"391\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"Gianluca Trento\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"Gianluca Trento\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2018\\\/11\\\/30\\\/qualita-dellaria-indoor-de-angelis-ripartire-dalle-scuole-per-creare-una-nuova-e-necessaria-consapevolezza\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2018\\\/11\\\/30\\\/qualita-dellaria-indoor-de-angelis-ripartire-dalle-scuole-per-creare-una-nuova-e-necessaria-consapevolezza\\\/\"},\"author\":{\"name\":\"Gianluca Trento\",\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/#\\\/schema\\\/person\\\/61ad8468fc64fa3e36d950057c9c2cbd\"},\"headline\":\"\u201cQualit\u00e0 dell\u2019aria indoor\u201d, De Angelis: ripartire dalle scuole per creare una nuova e necessaria consapevolezza\",\"datePublished\":\"2018-11-30T10:18:45+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2018\\\/11\\\/30\\\/qualita-dellaria-indoor-de-angelis-ripartire-dalle-scuole-per-creare-una-nuova-e-necessaria-consapevolezza\\\/\"},\"wordCount\":257,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2018\\\/11\\\/30\\\/qualita-dellaria-indoor-de-angelis-ripartire-dalle-scuole-per-creare-una-nuova-e-necessaria-consapevolezza\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2018\\\/11\\\/qualit\u00e0-aria-de-angelis.png\",\"articleSection\":[\"Economia e Finanza\"],\"inLanguage\":\"it-IT\",\"copyrightYear\":\"2018\",\"copyrightHolder\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/#organization\"}},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2018\\\/11\\\/30\\\/qualita-dellaria-indoor-de-angelis-ripartire-dalle-scuole-per-creare-una-nuova-e-necessaria-consapevolezza\\\/\",\"url\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2018\\\/11\\\/30\\\/qualita-dellaria-indoor-de-angelis-ripartire-dalle-scuole-per-creare-una-nuova-e-necessaria-consapevolezza\\\/\",\"name\":\"\u201cQualit\u00e0 dell\u2019aria indoor\u201d, De Angelis: ripartire dalle scuole per creare una nuova e necessaria consapevolezza - IlCorriereDellaProvincia.it - News h24 e notizie di approfondimento\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2018\\\/11\\\/30\\\/qualita-dellaria-indoor-de-angelis-ripartire-dalle-scuole-per-creare-una-nuova-e-necessaria-consapevolezza\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2018\\\/11\\\/30\\\/qualita-dellaria-indoor-de-angelis-ripartire-dalle-scuole-per-creare-una-nuova-e-necessaria-consapevolezza\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2018\\\/11\\\/qualit\u00e0-aria-de-angelis.png\",\"datePublished\":\"2018-11-30T10:18:45+00:00\",\"description\":\"L\u2019iniziativa, promossa dalla GWA, azienda specializzata nel trattamento dell\u2019acqua e dell\u2019aria, ha ottenuto il patrocinio dell\u2019Associazione igienisti.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2018\\\/11\\\/30\\\/qualita-dellaria-indoor-de-angelis-ripartire-dalle-scuole-per-creare-una-nuova-e-necessaria-consapevolezza\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2018\\\/11\\\/30\\\/qualita-dellaria-indoor-de-angelis-ripartire-dalle-scuole-per-creare-una-nuova-e-necessaria-consapevolezza\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2018\\\/11\\\/30\\\/qualita-dellaria-indoor-de-angelis-ripartire-dalle-scuole-per-creare-una-nuova-e-necessaria-consapevolezza\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2018\\\/11\\\/qualit\u00e0-aria-de-angelis.png\",\"contentUrl\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2018\\\/11\\\/qualit\u00e0-aria-de-angelis.png\",\"width\":686,\"height\":391,\"caption\":\"de angelis frosinone asi ciociaria qualit\u00e0 aria\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2018\\\/11\\\/30\\\/qualita-dellaria-indoor-de-angelis-ripartire-dalle-scuole-per-creare-una-nuova-e-necessaria-consapevolezza\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"\u201cQualit\u00e0 dell\u2019aria indoor\u201d, De Angelis: ripartire dalle scuole per creare una nuova e necessaria consapevolezza\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/#website\",\"url\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/\",\"name\":\"Il Corriere Delle Provincia\",\"description\":\"IlCorriereDellaProvincia.it, quotidiano web di politica, cronaca, inchiesta, lavoro, scuola, turismo, cultura e spettacolo, economia e finanza, salute e benessere. Approfondimenti e notizie aggiornate con foto e video della provincia di Frosinone ma anche news nazionali, dell\u2019Italia e del Mondo.\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":[\"Organization\",\"Place\"],\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/#organization\",\"name\":\"Globalpress s.r.l.\",\"url\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/\",\"logo\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2018\\\/11\\\/30\\\/qualita-dellaria-indoor-de-angelis-ripartire-dalle-scuole-per-creare-una-nuova-e-necessaria-consapevolezza\\\/#local-main-organization-logo\"},\"image\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2018\\\/11\\\/30\\\/qualita-dellaria-indoor-de-angelis-ripartire-dalle-scuole-per-creare-una-nuova-e-necessaria-consapevolezza\\\/#local-main-organization-logo\"},\"telephone\":[],\"openingHoursSpecification\":[{\"@type\":\"OpeningHoursSpecification\",\"dayOfWeek\":[\"Monday\",\"Tuesday\",\"Wednesday\",\"Thursday\",\"Friday\",\"Saturday\",\"Sunday\"],\"opens\":\"09:00\",\"closes\":\"17:00\"}]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/#\\\/schema\\\/person\\\/61ad8468fc64fa3e36d950057c9c2cbd\",\"name\":\"Gianluca Trento\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/8c3ab5f4c6ed6f32f95ece33488c4ec55733fd2c584ad602d0b29746892705ab?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/8c3ab5f4c6ed6f32f95ece33488c4ec55733fd2c584ad602d0b29746892705ab?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/8c3ab5f4c6ed6f32f95ece33488c4ec55733fd2c584ad602d0b29746892705ab?s=96&d=mm&r=g\",\"caption\":\"Gianluca Trento\"},\"description\":\"Giornalista dei quotidiani online \\\"LaProvinciaQuotidiano.it\\\" e \\\"TuNews24.it\\\" e del settimanale cartaceo \\\"Tu News\\\". In passato \u00e8 stato anche Direttore Editoriale de \\\"La Provincia\\\", Direttore Responsabile del quotidiano \\\"Ciociaria Oggi\\\", Condirettore de \\\"Il quotidiano della Ciociaria\\\", giornalista di \\\"Paese Sera\\\", del settimanale \\\"L\u2019Inchiesta\\\" e del quotidiano online \\\"Il Corriere della Provincia\\\".\",\"sameAs\":[\"https:\\\/\\\/www.tunews24.it\",\"http:\\\/\\\/www.facebook.com\\\/TuNews24\"],\"url\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/author\\\/gianluca\\\/\"},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2018\\\/11\\\/30\\\/qualita-dellaria-indoor-de-angelis-ripartire-dalle-scuole-per-creare-una-nuova-e-necessaria-consapevolezza\\\/#local-main-organization-logo\",\"url\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2022\\\/11\\\/cropped-il-corriere-della-provincia-testata-web-scontornata.png\",\"contentUrl\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2022\\\/11\\\/cropped-il-corriere-della-provincia-testata-web-scontornata.png\",\"width\":2911,\"height\":717,\"caption\":\"Globalpress s.r.l.\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"\u201cQualit\u00e0 dell\u2019aria indoor\u201d, De Angelis: ripartire dalle scuole per creare una nuova e necessaria consapevolezza - IlCorriereDellaProvincia.it - News h24 e notizie di approfondimento","description":"L\u2019iniziativa, promossa dalla GWA, azienda specializzata nel trattamento dell\u2019acqua e dell\u2019aria, ha ottenuto il patrocinio dell\u2019Associazione igienisti.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2018\/11\/30\/qualita-dellaria-indoor-de-angelis-ripartire-dalle-scuole-per-creare-una-nuova-e-necessaria-consapevolezza\/","og_locale":"it_IT","og_type":"article","og_title":"\u201cQualit\u00e0 dell\u2019aria indoor\u201d, De Angelis: ripartire dalle scuole per creare una nuova e necessaria consapevolezza","og_description":"L\u2019iniziativa, promossa dalla GWA, azienda specializzata nel trattamento dell\u2019acqua e dell\u2019aria, ha ottenuto il patrocinio dell\u2019Associazione igienisti.","og_url":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2018\/11\/30\/qualita-dellaria-indoor-de-angelis-ripartire-dalle-scuole-per-creare-una-nuova-e-necessaria-consapevolezza\/","og_site_name":"IlCorriereDellaProvincia.it - News h24 e notizie di approfondimento","article_author":"http:\/\/www.facebook.com\/TuNews24","article_published_time":"2018-11-30T10:18:45+00:00","og_image":[{"width":686,"height":391,"url":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2018\/11\/qualit\u00e0-aria-de-angelis.png","type":"image\/png"}],"author":"Gianluca Trento","twitter_card":"summary_large_image","twitter_misc":{"Scritto da":"Gianluca Trento","Tempo di lettura stimato":"1 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2018\/11\/30\/qualita-dellaria-indoor-de-angelis-ripartire-dalle-scuole-per-creare-una-nuova-e-necessaria-consapevolezza\/#article","isPartOf":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2018\/11\/30\/qualita-dellaria-indoor-de-angelis-ripartire-dalle-scuole-per-creare-una-nuova-e-necessaria-consapevolezza\/"},"author":{"name":"Gianluca Trento","@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/#\/schema\/person\/61ad8468fc64fa3e36d950057c9c2cbd"},"headline":"\u201cQualit\u00e0 dell\u2019aria indoor\u201d, De Angelis: ripartire dalle scuole per creare una nuova e necessaria consapevolezza","datePublished":"2018-11-30T10:18:45+00:00","mainEntityOfPage":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2018\/11\/30\/qualita-dellaria-indoor-de-angelis-ripartire-dalle-scuole-per-creare-una-nuova-e-necessaria-consapevolezza\/"},"wordCount":257,"commentCount":0,"publisher":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/#organization"},"image":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2018\/11\/30\/qualita-dellaria-indoor-de-angelis-ripartire-dalle-scuole-per-creare-una-nuova-e-necessaria-consapevolezza\/#primaryimage"},"thumbnailUrl":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2018\/11\/qualit\u00e0-aria-de-angelis.png","articleSection":["Economia e Finanza"],"inLanguage":"it-IT","copyrightYear":"2018","copyrightHolder":{"@id":"https:\/\/www.tunews24.it\/#organization"}},{"@type":"WebPage","@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2018\/11\/30\/qualita-dellaria-indoor-de-angelis-ripartire-dalle-scuole-per-creare-una-nuova-e-necessaria-consapevolezza\/","url":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2018\/11\/30\/qualita-dellaria-indoor-de-angelis-ripartire-dalle-scuole-per-creare-una-nuova-e-necessaria-consapevolezza\/","name":"\u201cQualit\u00e0 dell\u2019aria indoor\u201d, De Angelis: ripartire dalle scuole per creare una nuova e necessaria consapevolezza - IlCorriereDellaProvincia.it - News h24 e notizie di approfondimento","isPartOf":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2018\/11\/30\/qualita-dellaria-indoor-de-angelis-ripartire-dalle-scuole-per-creare-una-nuova-e-necessaria-consapevolezza\/#primaryimage"},"image":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2018\/11\/30\/qualita-dellaria-indoor-de-angelis-ripartire-dalle-scuole-per-creare-una-nuova-e-necessaria-consapevolezza\/#primaryimage"},"thumbnailUrl":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2018\/11\/qualit\u00e0-aria-de-angelis.png","datePublished":"2018-11-30T10:18:45+00:00","description":"L\u2019iniziativa, promossa dalla GWA, azienda specializzata nel trattamento dell\u2019acqua e dell\u2019aria, ha ottenuto il patrocinio dell\u2019Associazione igienisti.","breadcrumb":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2018\/11\/30\/qualita-dellaria-indoor-de-angelis-ripartire-dalle-scuole-per-creare-una-nuova-e-necessaria-consapevolezza\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2018\/11\/30\/qualita-dellaria-indoor-de-angelis-ripartire-dalle-scuole-per-creare-una-nuova-e-necessaria-consapevolezza\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2018\/11\/30\/qualita-dellaria-indoor-de-angelis-ripartire-dalle-scuole-per-creare-una-nuova-e-necessaria-consapevolezza\/#primaryimage","url":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2018\/11\/qualit\u00e0-aria-de-angelis.png","contentUrl":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2018\/11\/qualit\u00e0-aria-de-angelis.png","width":686,"height":391,"caption":"de angelis frosinone asi ciociaria qualit\u00e0 aria"},{"@type":"BreadcrumbList","@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2018\/11\/30\/qualita-dellaria-indoor-de-angelis-ripartire-dalle-scuole-per-creare-una-nuova-e-necessaria-consapevolezza\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/"},{"@type":"ListItem","position":2,"name":"\u201cQualit\u00e0 dell\u2019aria indoor\u201d, De Angelis: ripartire dalle scuole per creare una nuova e necessaria consapevolezza"}]},{"@type":"WebSite","@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/#website","url":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/","name":"Il Corriere Delle Provincia","description":"IlCorriereDellaProvincia.it, quotidiano web di politica, cronaca, inchiesta, lavoro, scuola, turismo, cultura e spettacolo, economia e finanza, salute e benessere. Approfondimenti e notizie aggiornate con foto e video della provincia di Frosinone ma anche news nazionali, dell\u2019Italia e del Mondo.","publisher":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":["Organization","Place"],"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/#organization","name":"Globalpress s.r.l.","url":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/","logo":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2018\/11\/30\/qualita-dellaria-indoor-de-angelis-ripartire-dalle-scuole-per-creare-una-nuova-e-necessaria-consapevolezza\/#local-main-organization-logo"},"image":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2018\/11\/30\/qualita-dellaria-indoor-de-angelis-ripartire-dalle-scuole-per-creare-una-nuova-e-necessaria-consapevolezza\/#local-main-organization-logo"},"telephone":[],"openingHoursSpecification":[{"@type":"OpeningHoursSpecification","dayOfWeek":["Monday","Tuesday","Wednesday","Thursday","Friday","Saturday","Sunday"],"opens":"09:00","closes":"17:00"}]},{"@type":"Person","@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/#\/schema\/person\/61ad8468fc64fa3e36d950057c9c2cbd","name":"Gianluca Trento","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/secure.gravatar.com\/avatar\/8c3ab5f4c6ed6f32f95ece33488c4ec55733fd2c584ad602d0b29746892705ab?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/8c3ab5f4c6ed6f32f95ece33488c4ec55733fd2c584ad602d0b29746892705ab?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/8c3ab5f4c6ed6f32f95ece33488c4ec55733fd2c584ad602d0b29746892705ab?s=96&d=mm&r=g","caption":"Gianluca Trento"},"description":"Giornalista dei quotidiani online \"LaProvinciaQuotidiano.it\" e \"TuNews24.it\" e del settimanale cartaceo \"Tu News\". In passato \u00e8 stato anche Direttore Editoriale de \"La Provincia\", Direttore Responsabile del quotidiano \"Ciociaria Oggi\", Condirettore de \"Il quotidiano della Ciociaria\", giornalista di \"Paese Sera\", del settimanale \"L\u2019Inchiesta\" e del quotidiano online \"Il Corriere della Provincia\".","sameAs":["https:\/\/www.tunews24.it","http:\/\/www.facebook.com\/TuNews24"],"url":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/author\/gianluca\/"},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2018\/11\/30\/qualita-dellaria-indoor-de-angelis-ripartire-dalle-scuole-per-creare-una-nuova-e-necessaria-consapevolezza\/#local-main-organization-logo","url":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2022\/11\/cropped-il-corriere-della-provincia-testata-web-scontornata.png","contentUrl":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2022\/11\/cropped-il-corriere-della-provincia-testata-web-scontornata.png","width":2911,"height":717,"caption":"Globalpress s.r.l."}]}},"_links":{"self":[{"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/posts\/2450","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/comments?post=2450"}],"version-history":[{"count":2,"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/posts\/2450\/revisions"}],"predecessor-version":[{"id":2455,"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/posts\/2450\/revisions\/2455"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/media\/2453"}],"wp:attachment":[{"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/media?parent=2450"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/categories?post=2450"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/tags?post=2450"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}