{"id":2427,"date":"2018-11-30T11:00:51","date_gmt":"2018-11-30T10:00:51","guid":{"rendered":"http:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/?p=2427"},"modified":"2018-11-29T20:02:07","modified_gmt":"2018-11-29T19:02:07","slug":"piu-libri-piu-liberi-2018-la-fiera-della-piccola-editoria","status":"publish","type":"post","link":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2018\/11\/30\/piu-libri-piu-liberi-2018-la-fiera-della-piccola-editoria\/","title":{"rendered":"Pi\u00f9 libri pi\u00f9 liberi 2018: la fiera della piccola editoria"},"content":{"rendered":"<p>Dal <strong>5 al 9 dicembre<\/strong> torna \u201cPi\u00f9 Libri pi\u00f9 Liberi\u201d, <strong>fiera della piccola e media editoria<\/strong>, ospitata presso il Roma Convention Center \u2013 La Nuvola all\u2019Eur.<br \/>\nLa Regione Lazio sostiene con convinzione la Fiera dell\u2019editoria indipendente sin dalla sua prima edizione, sia per dare supporto a un settore economico che nel Lazio vede <strong>300 case editrici<\/strong> che impiegano <strong>pi\u00f9 di 1200 addetti<\/strong>, sia per promuovere la lettura, in calo negli ultimi anni.<\/p>\n<h2>La novit\u00e0 del 2018<\/h2>\n<p>Quest\u2019anno oltre al programma di iniziative, la Regione introduce un\u2019eccezionale novit\u00e0: un <strong>&#8216;buono libro&#8217;<\/strong> destinato a <strong>10.000 studenti<\/strong> delle scuole primarie e secondarie, grazie al quale ogni alunno che visiter\u00e0 la fiera con la classe avr\u00e0 a disposizione <strong>10 euro da spendere per acquistare un libro<\/strong> tra gli editori presenti.<\/p>\n<p>L\u2019iniziativa vuole essere un concreto invito alla lettura e un modo per contrastare il dato negativo riferito alla lettura nel Paese, anche se secondo i <strong>dati Istat<\/strong> il numero di lettori nel Lazio \u00e8 pi\u00f9 alto della media nazionale. Resta, comunque, il fatto che una famiglia italiana su dieci non ha nemmeno un libro in casa.<\/p>\n<p>Vista la grande rilevanza culturale del progetto, la Consigliera delegata all\u2019Istruzione del Comune di Sora, <strong>Floriana De Donatis<\/strong> desidera promuovere le adesioni degli istituti scolastici cittadini. Per prenotare la visita e ottenere il buono per i ragazzi, le scuole interessate dovranno compilare il modulo disponibile su https:\/\/plpl.it\/scuole\/e inviarlo a scuola@plpl.it.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Dal 5 al 9 dicembre torna \u201cPi\u00f9 Libri pi\u00f9 Liberi\u201d, fiera della piccola e media editoria, ospitata presso il Roma<\/p>\n","protected":false},"author":7,"featured_media":2430,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[4,38],"tags":[896,899,94,276,93,898,895,897,129,161],"class_list":["post-2427","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-primo-piano","category-scuola","tag-bonus-libri","tag-case-editrici","tag-ciociaria","tag-fiera","tag-frosinone","tag-lettura","tag-libri","tag-piccola-e-media-editoria","tag-scuole","tag-sora"],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v27.8 (Yoast SEO v27.8) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Pi\u00f9 libri pi\u00f9 liberi 2018: la fiera della piccola editoria - IlCorriereDellaProvincia.it - News h24 e notizie di approfondimento<\/title>\n<meta name=\"description\" content=\"La consigliera delegata all&#039;Istruzione del Comune di Sora, Floriana De Donatis, invita le scuole della citt\u00e0 ad aderire alla fiera &#039;Pi\u00f9 libri pi\u00f9 liberi&#039;.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2018\/11\/30\/piu-libri-piu-liberi-2018-la-fiera-della-piccola-editoria\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Pi\u00f9 libri pi\u00f9 liberi 2018: la fiera della piccola editoria\" \/>\n<meta property=\"og:description\" content=\"La consigliera delegata all&#039;Istruzione del Comune di Sora, Floriana De Donatis, invita le scuole della citt\u00e0 ad aderire alla fiera &#039;Pi\u00f9 libri pi\u00f9 liberi&#039;.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2018\/11\/30\/piu-libri-piu-liberi-2018-la-fiera-della-piccola-editoria\/\" \/>\n<meta property=\"og:site_name\" content=\"IlCorriereDellaProvincia.it - News h24 e notizie di approfondimento\" \/>\n<meta property=\"article:author\" content=\"http:\/\/www.facebook.com\/tunews24\" \/>\n<meta property=\"article:published_time\" content=\"2018-11-30T10:00:51+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2018\/11\/fiera-editoria-roma-e1543517962578.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"632\" \/>\n\t<meta property=\"og:image:height\" content=\"366\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Giulia Abbruzzese\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"Giulia Abbruzzese\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2018\\\/11\\\/30\\\/piu-libri-piu-liberi-2018-la-fiera-della-piccola-editoria\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2018\\\/11\\\/30\\\/piu-libri-piu-liberi-2018-la-fiera-della-piccola-editoria\\\/\"},\"author\":{\"name\":\"Giulia Abbruzzese\",\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/#\\\/schema\\\/person\\\/58bf90a6d70d54d2f0db83bc3d580351\"},\"headline\":\"Pi\u00f9 libri pi\u00f9 liberi 2018: la fiera della piccola editoria\",\"datePublished\":\"2018-11-30T10:00:51+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2018\\\/11\\\/30\\\/piu-libri-piu-liberi-2018-la-fiera-della-piccola-editoria\\\/\"},\"wordCount\":244,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2018\\\/11\\\/30\\\/piu-libri-piu-liberi-2018-la-fiera-della-piccola-editoria\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2018\\\/11\\\/fiera-editoria-roma-e1543517962578.jpg\",\"keywords\":[\"bonus libri\",\"case editrici\",\"Ciociaria\",\"fiera\",\"Frosinone\",\"lettura\",\"libri\",\"piccola e media editoria\",\"scuole\",\"sora\"],\"articleSection\":[\"*PRIMO PIANO*\",\"Scuola\"],\"inLanguage\":\"it-IT\",\"copyrightYear\":\"2018\",\"copyrightHolder\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/#organization\"}},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2018\\\/11\\\/30\\\/piu-libri-piu-liberi-2018-la-fiera-della-piccola-editoria\\\/\",\"url\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2018\\\/11\\\/30\\\/piu-libri-piu-liberi-2018-la-fiera-della-piccola-editoria\\\/\",\"name\":\"Pi\u00f9 libri pi\u00f9 liberi 2018: la fiera della piccola editoria - IlCorriereDellaProvincia.it - News h24 e notizie di approfondimento\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2018\\\/11\\\/30\\\/piu-libri-piu-liberi-2018-la-fiera-della-piccola-editoria\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2018\\\/11\\\/30\\\/piu-libri-piu-liberi-2018-la-fiera-della-piccola-editoria\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2018\\\/11\\\/fiera-editoria-roma-e1543517962578.jpg\",\"datePublished\":\"2018-11-30T10:00:51+00:00\",\"description\":\"La consigliera delegata all'Istruzione del Comune di Sora, Floriana De Donatis, invita le scuole della citt\u00e0 ad aderire alla fiera 'Pi\u00f9 libri pi\u00f9 liberi'.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2018\\\/11\\\/30\\\/piu-libri-piu-liberi-2018-la-fiera-della-piccola-editoria\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2018\\\/11\\\/30\\\/piu-libri-piu-liberi-2018-la-fiera-della-piccola-editoria\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2018\\\/11\\\/30\\\/piu-libri-piu-liberi-2018-la-fiera-della-piccola-editoria\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2018\\\/11\\\/fiera-editoria-roma-e1543517962578.jpg\",\"contentUrl\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2018\\\/11\\\/fiera-editoria-roma-e1543517962578.jpg\",\"width\":632,\"height\":366,\"caption\":\"La fiera della piccola e media editoria\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2018\\\/11\\\/30\\\/piu-libri-piu-liberi-2018-la-fiera-della-piccola-editoria\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Pi\u00f9 libri pi\u00f9 liberi 2018: la fiera della piccola editoria\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/#website\",\"url\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/\",\"name\":\"Il Corriere Delle Provincia\",\"description\":\"IlCorriereDellaProvincia.it, quotidiano web di politica, cronaca, inchiesta, lavoro, scuola, turismo, cultura e spettacolo, economia e finanza, salute e benessere. Approfondimenti e notizie aggiornate con foto e video della provincia di Frosinone ma anche news nazionali, dell\u2019Italia e del Mondo.\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":[\"Organization\",\"Place\"],\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/#organization\",\"name\":\"Globalpress s.r.l.\",\"url\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/\",\"logo\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2018\\\/11\\\/30\\\/piu-libri-piu-liberi-2018-la-fiera-della-piccola-editoria\\\/#local-main-organization-logo\"},\"image\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2018\\\/11\\\/30\\\/piu-libri-piu-liberi-2018-la-fiera-della-piccola-editoria\\\/#local-main-organization-logo\"},\"telephone\":[],\"openingHoursSpecification\":[{\"@type\":\"OpeningHoursSpecification\",\"dayOfWeek\":[\"Monday\",\"Tuesday\",\"Wednesday\",\"Thursday\",\"Friday\",\"Saturday\",\"Sunday\"],\"opens\":\"09:00\",\"closes\":\"17:00\"}]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/#\\\/schema\\\/person\\\/58bf90a6d70d54d2f0db83bc3d580351\",\"name\":\"Giulia Abbruzzese\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/ff9b2f7c2c6d1751e3de0056e95b7af4a6c366bf539cdd639aac86cd1908507f?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/ff9b2f7c2c6d1751e3de0056e95b7af4a6c366bf539cdd639aac86cd1908507f?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/ff9b2f7c2c6d1751e3de0056e95b7af4a6c366bf539cdd639aac86cd1908507f?s=96&d=mm&r=g\",\"caption\":\"Giulia Abbruzzese\"},\"description\":\"Giornalista dei quotidiani online \\\"Il Corriere della Provincia\\\" e \\\"TuNews24.it\\\" e del settimanale \\\"Tu News\\\", ha collaborato anche con il mensile \\\"Qui Magazine\\\" oltre che con il settimanale \\\"Qui Sette\\\"; \u00e8 stata inoltre Caposervizio del quotidiano \\\"\u2018Ciociaria Oggi\\\" e Caporedattore de \\\"Il quotidiano della Ciociaria\\\". Collabora con la rivista \\\"Chic Style\\\".\",\"sameAs\":[\"http:\\\/\\\/www.tunews24.it\",\"http:\\\/\\\/www.facebook.com\\\/tunews24\"],\"url\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/author\\\/giulia-abbruzzese\\\/\"},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2018\\\/11\\\/30\\\/piu-libri-piu-liberi-2018-la-fiera-della-piccola-editoria\\\/#local-main-organization-logo\",\"url\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2022\\\/11\\\/cropped-il-corriere-della-provincia-testata-web-scontornata.png\",\"contentUrl\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2022\\\/11\\\/cropped-il-corriere-della-provincia-testata-web-scontornata.png\",\"width\":2911,\"height\":717,\"caption\":\"Globalpress s.r.l.\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Pi\u00f9 libri pi\u00f9 liberi 2018: la fiera della piccola editoria - IlCorriereDellaProvincia.it - News h24 e notizie di approfondimento","description":"La consigliera delegata all'Istruzione del Comune di Sora, Floriana De Donatis, invita le scuole della citt\u00e0 ad aderire alla fiera 'Pi\u00f9 libri pi\u00f9 liberi'.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2018\/11\/30\/piu-libri-piu-liberi-2018-la-fiera-della-piccola-editoria\/","og_locale":"it_IT","og_type":"article","og_title":"Pi\u00f9 libri pi\u00f9 liberi 2018: la fiera della piccola editoria","og_description":"La consigliera delegata all'Istruzione del Comune di Sora, Floriana De Donatis, invita le scuole della citt\u00e0 ad aderire alla fiera 'Pi\u00f9 libri pi\u00f9 liberi'.","og_url":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2018\/11\/30\/piu-libri-piu-liberi-2018-la-fiera-della-piccola-editoria\/","og_site_name":"IlCorriereDellaProvincia.it - News h24 e notizie di approfondimento","article_author":"http:\/\/www.facebook.com\/tunews24","article_published_time":"2018-11-30T10:00:51+00:00","og_image":[{"width":632,"height":366,"url":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2018\/11\/fiera-editoria-roma-e1543517962578.jpg","type":"image\/jpeg"}],"author":"Giulia Abbruzzese","twitter_card":"summary_large_image","twitter_misc":{"Scritto da":"Giulia Abbruzzese","Tempo di lettura stimato":"1 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2018\/11\/30\/piu-libri-piu-liberi-2018-la-fiera-della-piccola-editoria\/#article","isPartOf":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2018\/11\/30\/piu-libri-piu-liberi-2018-la-fiera-della-piccola-editoria\/"},"author":{"name":"Giulia Abbruzzese","@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/#\/schema\/person\/58bf90a6d70d54d2f0db83bc3d580351"},"headline":"Pi\u00f9 libri pi\u00f9 liberi 2018: la fiera della piccola editoria","datePublished":"2018-11-30T10:00:51+00:00","mainEntityOfPage":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2018\/11\/30\/piu-libri-piu-liberi-2018-la-fiera-della-piccola-editoria\/"},"wordCount":244,"commentCount":0,"publisher":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/#organization"},"image":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2018\/11\/30\/piu-libri-piu-liberi-2018-la-fiera-della-piccola-editoria\/#primaryimage"},"thumbnailUrl":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2018\/11\/fiera-editoria-roma-e1543517962578.jpg","keywords":["bonus libri","case editrici","Ciociaria","fiera","Frosinone","lettura","libri","piccola e media editoria","scuole","sora"],"articleSection":["*PRIMO PIANO*","Scuola"],"inLanguage":"it-IT","copyrightYear":"2018","copyrightHolder":{"@id":"https:\/\/www.tunews24.it\/#organization"}},{"@type":"WebPage","@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2018\/11\/30\/piu-libri-piu-liberi-2018-la-fiera-della-piccola-editoria\/","url":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2018\/11\/30\/piu-libri-piu-liberi-2018-la-fiera-della-piccola-editoria\/","name":"Pi\u00f9 libri pi\u00f9 liberi 2018: la fiera della piccola editoria - IlCorriereDellaProvincia.it - News h24 e notizie di approfondimento","isPartOf":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2018\/11\/30\/piu-libri-piu-liberi-2018-la-fiera-della-piccola-editoria\/#primaryimage"},"image":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2018\/11\/30\/piu-libri-piu-liberi-2018-la-fiera-della-piccola-editoria\/#primaryimage"},"thumbnailUrl":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2018\/11\/fiera-editoria-roma-e1543517962578.jpg","datePublished":"2018-11-30T10:00:51+00:00","description":"La consigliera delegata all'Istruzione del Comune di Sora, Floriana De Donatis, invita le scuole della citt\u00e0 ad aderire alla fiera 'Pi\u00f9 libri pi\u00f9 liberi'.","breadcrumb":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2018\/11\/30\/piu-libri-piu-liberi-2018-la-fiera-della-piccola-editoria\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2018\/11\/30\/piu-libri-piu-liberi-2018-la-fiera-della-piccola-editoria\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2018\/11\/30\/piu-libri-piu-liberi-2018-la-fiera-della-piccola-editoria\/#primaryimage","url":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2018\/11\/fiera-editoria-roma-e1543517962578.jpg","contentUrl":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2018\/11\/fiera-editoria-roma-e1543517962578.jpg","width":632,"height":366,"caption":"La fiera della piccola e media editoria"},{"@type":"BreadcrumbList","@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2018\/11\/30\/piu-libri-piu-liberi-2018-la-fiera-della-piccola-editoria\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/"},{"@type":"ListItem","position":2,"name":"Pi\u00f9 libri pi\u00f9 liberi 2018: la fiera della piccola editoria"}]},{"@type":"WebSite","@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/#website","url":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/","name":"Il Corriere Delle Provincia","description":"IlCorriereDellaProvincia.it, quotidiano web di politica, cronaca, inchiesta, lavoro, scuola, turismo, cultura e spettacolo, economia e finanza, salute e benessere. Approfondimenti e notizie aggiornate con foto e video della provincia di Frosinone ma anche news nazionali, dell\u2019Italia e del Mondo.","publisher":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":["Organization","Place"],"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/#organization","name":"Globalpress s.r.l.","url":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/","logo":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2018\/11\/30\/piu-libri-piu-liberi-2018-la-fiera-della-piccola-editoria\/#local-main-organization-logo"},"image":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2018\/11\/30\/piu-libri-piu-liberi-2018-la-fiera-della-piccola-editoria\/#local-main-organization-logo"},"telephone":[],"openingHoursSpecification":[{"@type":"OpeningHoursSpecification","dayOfWeek":["Monday","Tuesday","Wednesday","Thursday","Friday","Saturday","Sunday"],"opens":"09:00","closes":"17:00"}]},{"@type":"Person","@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/#\/schema\/person\/58bf90a6d70d54d2f0db83bc3d580351","name":"Giulia Abbruzzese","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/secure.gravatar.com\/avatar\/ff9b2f7c2c6d1751e3de0056e95b7af4a6c366bf539cdd639aac86cd1908507f?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/ff9b2f7c2c6d1751e3de0056e95b7af4a6c366bf539cdd639aac86cd1908507f?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/ff9b2f7c2c6d1751e3de0056e95b7af4a6c366bf539cdd639aac86cd1908507f?s=96&d=mm&r=g","caption":"Giulia Abbruzzese"},"description":"Giornalista dei quotidiani online \"Il Corriere della Provincia\" e \"TuNews24.it\" e del settimanale \"Tu News\", ha collaborato anche con il mensile \"Qui Magazine\" oltre che con il settimanale \"Qui Sette\"; \u00e8 stata inoltre Caposervizio del quotidiano \"\u2018Ciociaria Oggi\" e Caporedattore de \"Il quotidiano della Ciociaria\". Collabora con la rivista \"Chic Style\".","sameAs":["http:\/\/www.tunews24.it","http:\/\/www.facebook.com\/tunews24"],"url":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/author\/giulia-abbruzzese\/"},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2018\/11\/30\/piu-libri-piu-liberi-2018-la-fiera-della-piccola-editoria\/#local-main-organization-logo","url":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2022\/11\/cropped-il-corriere-della-provincia-testata-web-scontornata.png","contentUrl":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2022\/11\/cropped-il-corriere-della-provincia-testata-web-scontornata.png","width":2911,"height":717,"caption":"Globalpress s.r.l."}]}},"_links":{"self":[{"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/posts\/2427","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/users\/7"}],"replies":[{"embeddable":true,"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/comments?post=2427"}],"version-history":[{"count":1,"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/posts\/2427\/revisions"}],"predecessor-version":[{"id":2433,"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/posts\/2427\/revisions\/2433"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/media\/2430"}],"wp:attachment":[{"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/media?parent=2427"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/categories?post=2427"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/tags?post=2427"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}