{"id":23732,"date":"2019-12-03T16:54:01","date_gmt":"2019-12-03T15:54:01","guid":{"rendered":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/?p=23732"},"modified":"2019-12-04T14:02:05","modified_gmt":"2019-12-04T13:02:05","slug":"beni-confiscati-alla-criminalita-ferentino-casa-famiglia-disabili","status":"publish","type":"post","link":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2019\/12\/03\/beni-confiscati-alla-criminalita-ferentino-casa-famiglia-disabili\/","title":{"rendered":"Ferentino, una casa famiglia per disabili nell&#8217;immobile confiscato alla criminalit\u00e0"},"content":{"rendered":"<p><strong>L&#8217;Area Affari Generali, Sicurezza Integrata e Beni Confiscati alla mafia<\/strong> della Direzione Regionale Affari Costituzionali ha comunicato al Comune di Ferentino l&#8217;ammissione al finanziamento per gli intervent manutenzione straordinaria degli immobili situati in localit\u00e0 &#8216;Fossa della Penna&#8217;.<\/p>\n<h2><\/h2>\n<h2>Al via i lavori<\/h2>\n<p>Si tratta, in particolare, di un <strong>complesso immobiliare, confiscato alla criminalit\u00e0 organizzata,<\/strong> secondo quanto previsto dalla Legge regionale 15\/2001 e dalla Dgr 621\/2019, che ora, grazie al finanziamento accordato dalla Regione Lazio di 64.829 euro, sar\u00e0 oggetto di lavori di recupero ai fini del suo riutilizzo. Una bella notizia per il Comune di Ferentino, ammesso al finanziamento regionale.<\/p>\n<h2><\/h2>\n<h2>L&#8217;obiettivo<\/h2>\n<p>Il complesso immobiliare di via Forma Coperta sar\u00e0 utilizzato com<strong>e casa-famiglia per disabili<\/strong>: un risultato che premia il costante impegno dell&#8217;Amministrazione comunale nel rispondere ai bisogni della comunit\u00e0 e alla crescente domanda delle famiglie.<\/p>\n<figure id=\"attachment_11881\" aria-describedby=\"caption-attachment-11881\" style=\"width: 632px\" class=\"wp-caption aligncenter\"><img loading=\"lazy\" decoding=\"async\" class=\"size-full wp-image-11881\" src=\"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2019\/05\/antonio-pompeo-sindaco-ferentino-e1561993822743.jpg\" alt=\"antonio pompeo sindaco ferentino\" width=\"632\" height=\"484\" \/><figcaption id=\"caption-attachment-11881\" class=\"wp-caption-text\">Il sindaco di Ferentino Antonio Pompeo<\/figcaption><\/figure>\n<h2><\/h2>\n<h2>Le parole del sindaco e dell&#8217;assessore<\/h2>\n<p>&#8220;Accogliamo questa notizia con grande soddisfazione \u2013 \u00e8 il commento del sindaco <strong>Antonio Pompeo e del vicesindaco e assessore ai Servizi Sociali, Luigi Vittori<\/strong> \u2013 non solo perch\u00e9 simbolicamente convertire un bene della mafia in un punto di riferimento per la collettivit\u00e0 e le emergenze sociali \u00e8 una vittoria della legalit\u00e0 sul crimine, ma anche perch\u00e9, grazie al lavoro dei nostri uffici e all&#8217;impegno costante dell&#8217;Amministrazione, possiamo dare risposte concrete alle esigenze dei cittadini. E, in questo caso, alle fasce deboli e alle persone con disabilit\u00e0, che potranno contare su una nuova struttura di riferimento. Ringraziamo, quindi, la Regione Lazio \u2013 concludono Pompeo e Vittori \u2013 per il contributo e ci impegneremo, come sempre, affinch\u00e9 l&#8217;iter possa concludersi entro tempi certi e rapidi&#8221;.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>L&#8217;Area Affari Generali, Sicurezza Integrata e Beni Confiscati alla mafia della Direzione Regionale Affari Costituzionali ha comunicato al Comune di<\/p>\n","protected":false},"author":18,"featured_media":20241,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[41,2236],"tags":[842,7435,5762,2467,92,4719],"class_list":["post-23732","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-slide","category-attualita","tag-antonio-pompeo","tag-bene-confiscato","tag-casa-famiglia","tag-criminalita","tag-ferentino","tag-luigi-vittori"],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v27.8 (Yoast SEO v27.8) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Ferentino, una casa famiglia per disabili nell&#039;immobile confiscato alla criminalit\u00e0 - IlCorriereDellaProvincia.it - News h24 e notizie di approfondimento<\/title>\n<meta name=\"description\" content=\"Un risultato che premia il costante impegno dell&#039;Amministrazione comunale nel rispondere ai bisogni della comunit\u00e0 e alla crescente domanda delle famiglie.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2019\/12\/03\/beni-confiscati-alla-criminalita-ferentino-casa-famiglia-disabili\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Ferentino, una casa famiglia per disabili nell&#039;immobile confiscato alla criminalit\u00e0\" \/>\n<meta property=\"og:description\" content=\"Un risultato che premia il costante impegno dell&#039;Amministrazione comunale nel rispondere ai bisogni della comunit\u00e0 e alla crescente domanda delle famiglie.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2019\/12\/03\/beni-confiscati-alla-criminalita-ferentino-casa-famiglia-disabili\/\" \/>\n<meta property=\"og:site_name\" content=\"IlCorriereDellaProvincia.it - News h24 e notizie di approfondimento\" \/>\n<meta property=\"article:author\" content=\"www.facebook.com\/tunews24\" \/>\n<meta property=\"article:published_time\" content=\"2019-12-03T15:54:01+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2019-12-04T13:02:05+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2019\/10\/piazza-matteotti-ferentino-e1571153718888.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"632\" \/>\n\t<meta property=\"og:image:height\" content=\"474\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Redazione\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"Redazione\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2019\\\/12\\\/03\\\/beni-confiscati-alla-criminalita-ferentino-casa-famiglia-disabili\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2019\\\/12\\\/03\\\/beni-confiscati-alla-criminalita-ferentino-casa-famiglia-disabili\\\/\"},\"author\":{\"name\":\"Redazione\",\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/#\\\/schema\\\/person\\\/6d7f0a9120d0c03d0c552e9fdf49ed7d\"},\"headline\":\"Ferentino, una casa famiglia per disabili nell&#8217;immobile confiscato alla criminalit\u00e0\",\"datePublished\":\"2019-12-03T15:54:01+00:00\",\"dateModified\":\"2019-12-04T13:02:05+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2019\\\/12\\\/03\\\/beni-confiscati-alla-criminalita-ferentino-casa-famiglia-disabili\\\/\"},\"wordCount\":286,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2019\\\/12\\\/03\\\/beni-confiscati-alla-criminalita-ferentino-casa-famiglia-disabili\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2019\\\/10\\\/piazza-matteotti-ferentino-e1571153718888.jpg\",\"keywords\":[\"antonio pompeo\",\"bene confiscato\",\"casa famiglia\",\"criminalit\u00e0\",\"ferentino\",\"luigi vittori\"],\"articleSection\":[\"*SLIDE*\",\"Attualit\u00e0\"],\"inLanguage\":\"it-IT\",\"copyrightYear\":\"2019\",\"copyrightHolder\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/#organization\"}},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2019\\\/12\\\/03\\\/beni-confiscati-alla-criminalita-ferentino-casa-famiglia-disabili\\\/\",\"url\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2019\\\/12\\\/03\\\/beni-confiscati-alla-criminalita-ferentino-casa-famiglia-disabili\\\/\",\"name\":\"Ferentino, una casa famiglia per disabili nell'immobile confiscato alla criminalit\u00e0 - IlCorriereDellaProvincia.it - News h24 e notizie di approfondimento\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2019\\\/12\\\/03\\\/beni-confiscati-alla-criminalita-ferentino-casa-famiglia-disabili\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2019\\\/12\\\/03\\\/beni-confiscati-alla-criminalita-ferentino-casa-famiglia-disabili\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2019\\\/10\\\/piazza-matteotti-ferentino-e1571153718888.jpg\",\"datePublished\":\"2019-12-03T15:54:01+00:00\",\"dateModified\":\"2019-12-04T13:02:05+00:00\",\"description\":\"Un risultato che premia il costante impegno dell'Amministrazione comunale nel rispondere ai bisogni della comunit\u00e0 e alla crescente domanda delle famiglie.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2019\\\/12\\\/03\\\/beni-confiscati-alla-criminalita-ferentino-casa-famiglia-disabili\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2019\\\/12\\\/03\\\/beni-confiscati-alla-criminalita-ferentino-casa-famiglia-disabili\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2019\\\/12\\\/03\\\/beni-confiscati-alla-criminalita-ferentino-casa-famiglia-disabili\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2019\\\/10\\\/piazza-matteotti-ferentino-e1571153718888.jpg\",\"contentUrl\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2019\\\/10\\\/piazza-matteotti-ferentino-e1571153718888.jpg\",\"width\":632,\"height\":474,\"caption\":\"Piazza Matteotti a Ferentino\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2019\\\/12\\\/03\\\/beni-confiscati-alla-criminalita-ferentino-casa-famiglia-disabili\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Ferentino, una casa famiglia per disabili nell&#8217;immobile confiscato alla criminalit\u00e0\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/#website\",\"url\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/\",\"name\":\"Il Corriere Delle Provincia\",\"description\":\"IlCorriereDellaProvincia.it, quotidiano web di politica, cronaca, inchiesta, lavoro, scuola, turismo, cultura e spettacolo, economia e finanza, salute e benessere. Approfondimenti e notizie aggiornate con foto e video della provincia di Frosinone ma anche news nazionali, dell\u2019Italia e del Mondo.\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":[\"Organization\",\"Place\"],\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/#organization\",\"name\":\"Globalpress s.r.l.\",\"url\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/\",\"logo\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2019\\\/12\\\/03\\\/beni-confiscati-alla-criminalita-ferentino-casa-famiglia-disabili\\\/#local-main-organization-logo\"},\"image\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2019\\\/12\\\/03\\\/beni-confiscati-alla-criminalita-ferentino-casa-famiglia-disabili\\\/#local-main-organization-logo\"},\"telephone\":[],\"openingHoursSpecification\":[{\"@type\":\"OpeningHoursSpecification\",\"dayOfWeek\":[\"Monday\",\"Tuesday\",\"Wednesday\",\"Thursday\",\"Friday\",\"Saturday\",\"Sunday\"],\"opens\":\"09:00\",\"closes\":\"17:00\"}]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/#\\\/schema\\\/person\\\/6d7f0a9120d0c03d0c552e9fdf49ed7d\",\"name\":\"Redazione\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/a40eeacccdcad861f831dde73317f63a542e738f0dc4b79b9f47062d3d4bd1d2?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/a40eeacccdcad861f831dde73317f63a542e738f0dc4b79b9f47062d3d4bd1d2?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/a40eeacccdcad861f831dde73317f63a542e738f0dc4b79b9f47062d3d4bd1d2?s=96&d=mm&r=g\",\"caption\":\"Redazione\"},\"description\":\"SEGUICI ANCHE SUI SOCIAL Facebook: TuNews24 e TuSport24 Instagram: TuNews24 e TuSport24 Youtube: TuNews24 Telegram: TuNews24 Puoi leggerci anche in formato cartaceo: il settimanale viene pubblicato e distribuito gratuitamente ogni venerd\u00ec in edicole, bar, centri commerciali e svariati esercizi. Ma \u00e8 possibile anche sfogliarlo comodamente online, cliccando su TU NEWS sfogliabile TU NEWS, PASSIONE PER L\u2019INFORMAZIONE\",\"sameAs\":[\"http:\\\/\\\/www.tunews24.it\",\"www.facebook.com\\\/tunews24\"],\"url\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/author\\\/senzafirma\\\/\"},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2019\\\/12\\\/03\\\/beni-confiscati-alla-criminalita-ferentino-casa-famiglia-disabili\\\/#local-main-organization-logo\",\"url\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2022\\\/11\\\/cropped-il-corriere-della-provincia-testata-web-scontornata.png\",\"contentUrl\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2022\\\/11\\\/cropped-il-corriere-della-provincia-testata-web-scontornata.png\",\"width\":2911,\"height\":717,\"caption\":\"Globalpress s.r.l.\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Ferentino, una casa famiglia per disabili nell'immobile confiscato alla criminalit\u00e0 - IlCorriereDellaProvincia.it - News h24 e notizie di approfondimento","description":"Un risultato che premia il costante impegno dell'Amministrazione comunale nel rispondere ai bisogni della comunit\u00e0 e alla crescente domanda delle famiglie.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2019\/12\/03\/beni-confiscati-alla-criminalita-ferentino-casa-famiglia-disabili\/","og_locale":"it_IT","og_type":"article","og_title":"Ferentino, una casa famiglia per disabili nell'immobile confiscato alla criminalit\u00e0","og_description":"Un risultato che premia il costante impegno dell'Amministrazione comunale nel rispondere ai bisogni della comunit\u00e0 e alla crescente domanda delle famiglie.","og_url":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2019\/12\/03\/beni-confiscati-alla-criminalita-ferentino-casa-famiglia-disabili\/","og_site_name":"IlCorriereDellaProvincia.it - News h24 e notizie di approfondimento","article_author":"www.facebook.com\/tunews24","article_published_time":"2019-12-03T15:54:01+00:00","article_modified_time":"2019-12-04T13:02:05+00:00","og_image":[{"width":632,"height":474,"url":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2019\/10\/piazza-matteotti-ferentino-e1571153718888.jpg","type":"image\/jpeg"}],"author":"Redazione","twitter_card":"summary_large_image","twitter_misc":{"Scritto da":"Redazione","Tempo di lettura stimato":"1 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2019\/12\/03\/beni-confiscati-alla-criminalita-ferentino-casa-famiglia-disabili\/#article","isPartOf":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2019\/12\/03\/beni-confiscati-alla-criminalita-ferentino-casa-famiglia-disabili\/"},"author":{"name":"Redazione","@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/#\/schema\/person\/6d7f0a9120d0c03d0c552e9fdf49ed7d"},"headline":"Ferentino, una casa famiglia per disabili nell&#8217;immobile confiscato alla criminalit\u00e0","datePublished":"2019-12-03T15:54:01+00:00","dateModified":"2019-12-04T13:02:05+00:00","mainEntityOfPage":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2019\/12\/03\/beni-confiscati-alla-criminalita-ferentino-casa-famiglia-disabili\/"},"wordCount":286,"commentCount":0,"publisher":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/#organization"},"image":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2019\/12\/03\/beni-confiscati-alla-criminalita-ferentino-casa-famiglia-disabili\/#primaryimage"},"thumbnailUrl":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2019\/10\/piazza-matteotti-ferentino-e1571153718888.jpg","keywords":["antonio pompeo","bene confiscato","casa famiglia","criminalit\u00e0","ferentino","luigi vittori"],"articleSection":["*SLIDE*","Attualit\u00e0"],"inLanguage":"it-IT","copyrightYear":"2019","copyrightHolder":{"@id":"https:\/\/www.tunews24.it\/#organization"}},{"@type":"WebPage","@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2019\/12\/03\/beni-confiscati-alla-criminalita-ferentino-casa-famiglia-disabili\/","url":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2019\/12\/03\/beni-confiscati-alla-criminalita-ferentino-casa-famiglia-disabili\/","name":"Ferentino, una casa famiglia per disabili nell'immobile confiscato alla criminalit\u00e0 - IlCorriereDellaProvincia.it - News h24 e notizie di approfondimento","isPartOf":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2019\/12\/03\/beni-confiscati-alla-criminalita-ferentino-casa-famiglia-disabili\/#primaryimage"},"image":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2019\/12\/03\/beni-confiscati-alla-criminalita-ferentino-casa-famiglia-disabili\/#primaryimage"},"thumbnailUrl":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2019\/10\/piazza-matteotti-ferentino-e1571153718888.jpg","datePublished":"2019-12-03T15:54:01+00:00","dateModified":"2019-12-04T13:02:05+00:00","description":"Un risultato che premia il costante impegno dell'Amministrazione comunale nel rispondere ai bisogni della comunit\u00e0 e alla crescente domanda delle famiglie.","breadcrumb":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2019\/12\/03\/beni-confiscati-alla-criminalita-ferentino-casa-famiglia-disabili\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2019\/12\/03\/beni-confiscati-alla-criminalita-ferentino-casa-famiglia-disabili\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2019\/12\/03\/beni-confiscati-alla-criminalita-ferentino-casa-famiglia-disabili\/#primaryimage","url":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2019\/10\/piazza-matteotti-ferentino-e1571153718888.jpg","contentUrl":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2019\/10\/piazza-matteotti-ferentino-e1571153718888.jpg","width":632,"height":474,"caption":"Piazza Matteotti a Ferentino"},{"@type":"BreadcrumbList","@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2019\/12\/03\/beni-confiscati-alla-criminalita-ferentino-casa-famiglia-disabili\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/"},{"@type":"ListItem","position":2,"name":"Ferentino, una casa famiglia per disabili nell&#8217;immobile confiscato alla criminalit\u00e0"}]},{"@type":"WebSite","@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/#website","url":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/","name":"Il Corriere Delle Provincia","description":"IlCorriereDellaProvincia.it, quotidiano web di politica, cronaca, inchiesta, lavoro, scuola, turismo, cultura e spettacolo, economia e finanza, salute e benessere. Approfondimenti e notizie aggiornate con foto e video della provincia di Frosinone ma anche news nazionali, dell\u2019Italia e del Mondo.","publisher":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":["Organization","Place"],"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/#organization","name":"Globalpress s.r.l.","url":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/","logo":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2019\/12\/03\/beni-confiscati-alla-criminalita-ferentino-casa-famiglia-disabili\/#local-main-organization-logo"},"image":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2019\/12\/03\/beni-confiscati-alla-criminalita-ferentino-casa-famiglia-disabili\/#local-main-organization-logo"},"telephone":[],"openingHoursSpecification":[{"@type":"OpeningHoursSpecification","dayOfWeek":["Monday","Tuesday","Wednesday","Thursday","Friday","Saturday","Sunday"],"opens":"09:00","closes":"17:00"}]},{"@type":"Person","@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/#\/schema\/person\/6d7f0a9120d0c03d0c552e9fdf49ed7d","name":"Redazione","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/secure.gravatar.com\/avatar\/a40eeacccdcad861f831dde73317f63a542e738f0dc4b79b9f47062d3d4bd1d2?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/a40eeacccdcad861f831dde73317f63a542e738f0dc4b79b9f47062d3d4bd1d2?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/a40eeacccdcad861f831dde73317f63a542e738f0dc4b79b9f47062d3d4bd1d2?s=96&d=mm&r=g","caption":"Redazione"},"description":"SEGUICI ANCHE SUI SOCIAL Facebook: TuNews24 e TuSport24 Instagram: TuNews24 e TuSport24 Youtube: TuNews24 Telegram: TuNews24 Puoi leggerci anche in formato cartaceo: il settimanale viene pubblicato e distribuito gratuitamente ogni venerd\u00ec in edicole, bar, centri commerciali e svariati esercizi. Ma \u00e8 possibile anche sfogliarlo comodamente online, cliccando su TU NEWS sfogliabile TU NEWS, PASSIONE PER L\u2019INFORMAZIONE","sameAs":["http:\/\/www.tunews24.it","www.facebook.com\/tunews24"],"url":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/author\/senzafirma\/"},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2019\/12\/03\/beni-confiscati-alla-criminalita-ferentino-casa-famiglia-disabili\/#local-main-organization-logo","url":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2022\/11\/cropped-il-corriere-della-provincia-testata-web-scontornata.png","contentUrl":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2022\/11\/cropped-il-corriere-della-provincia-testata-web-scontornata.png","width":2911,"height":717,"caption":"Globalpress s.r.l."}]}},"_links":{"self":[{"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/posts\/23732","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/users\/18"}],"replies":[{"embeddable":true,"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/comments?post=23732"}],"version-history":[{"count":1,"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/posts\/23732\/revisions"}],"predecessor-version":[{"id":23737,"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/posts\/23732\/revisions\/23737"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/media\/20241"}],"wp:attachment":[{"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/media?parent=23732"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/categories?post=23732"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/tags?post=23732"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}