{"id":23430,"date":"2019-11-29T08:34:08","date_gmt":"2019-11-29T07:34:08","guid":{"rendered":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/?p=23430"},"modified":"2019-11-29T18:25:17","modified_gmt":"2019-11-29T17:25:17","slug":"ferentino-primi-passi-per-la-bonifica-dei-siti-inquinati-nellarea-della-valle-del-sacco","status":"publish","type":"post","link":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2019\/11\/29\/ferentino-primi-passi-per-la-bonifica-dei-siti-inquinati-nellarea-della-valle-del-sacco\/","title":{"rendered":"Ferentino, primi passi per la bonifica dei siti inquinati nell&#8217;area della Valle del Sacco"},"content":{"rendered":"<p align=\"JUSTIFY\"><strong>Messa in sicurezza, bonifica e recupero delle aree inquinate<\/strong> incluse nel perimetro del S.I.N. (Sito di Interesse Nazionale) del Bacino del fiume Sacco che ricadono in territorio di Ferentino: il prossimo 14 gennaio, alle ore 9.30, si terr\u00e0 una riunione in Comune con i proprietari delle aree agricole ripariali.<\/p>\n<figure id=\"attachment_11881\" aria-describedby=\"caption-attachment-11881\" style=\"width: 632px\" class=\"wp-caption aligncenter\"><img loading=\"lazy\" decoding=\"async\" class=\"size-full wp-image-11881\" src=\"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2019\/05\/antonio-pompeo-sindaco-ferentino-e1561993822743.jpg\" alt=\"antonio pompeo sindaco ferentino\" width=\"632\" height=\"484\" \/><figcaption id=\"caption-attachment-11881\" class=\"wp-caption-text\">Il sindaco di Ferentino Antonio Pompeo<\/figcaption><\/figure>\n<h2 align=\"JUSTIFY\"><\/h2>\n<h2 align=\"JUSTIFY\">La decisione<\/h2>\n<p align=\"JUSTIFY\">Si tratta dei primi passi per procedere alla bonifica delle zone inquinate, che rientrano nel perimetro della Valle del Sacco e che interessano diversi comuni, tra cui anche quello di Ferentino. La Regione Lazio, a tal proposito, ha informato l&#8217;Ente di piazza Matteotti che t<strong>ra gli interventi prioritari da effettuare c&#8217;\u00e8 la caratterizzazione delle aree agricole ripariali del fiume Sacco<\/strong>, finalizzata a verificare l&#8217;eventuale permanenza di agenti inquinanti che ne comportarono l&#8217;interdizione nella fase di emergenza.<\/p>\n<p align=\"JUSTIFY\">Ora, in collaborazione con Arpa, Istituto Superiore di Sanit\u00e0, Servizio Sanitario Nazionale, Istituto Zooprofilattico Nazionale e Asl, la Regione Lazio proceder\u00e0, nei prossimi mesi, a prelevare campioni di terreno e di prodotti vegetali in vari punti dell&#8217;area e chiede la collaborazione dei proprietari per effettuare agevolmente queste operazioni.<\/p>\n<h2 align=\"JUSTIFY\">L&#8217;intervento<\/h2>\n<p align=\"JUSTIFY\">&#8220;<i>Si tratta<\/i>\u00a0\u2013 sottolinea il sindaco di Ferentino, Antonio Pompeo \u2013\u00a0<i>di <strong>un primo e importantissimo passo verso la bonifica e la messa in sicurezza di un&#8217;area<\/strong> che, purtroppo, rappresenta l&#8217;esempio pi\u00f9 drammatico di come l&#8217;inquinamento possa mettere in ginocchio un intero territorio, minare la salute della popolazione che lo abita, frenare lo sviluppo e la crescita economica, provocare un disastro ambientale di proporzioni spaventose. Ecco perch\u00e9 &#8211;\u00a0<\/i>conclude Pompeo &#8211;\u00a0<i>daremo tutto il nostro contributo, iniziando da questa riunione con i proprietari dei terreni, che saranno oggetto di verifica e prelievi, affinch\u00e9 il percorso sia il pi\u00f9 rapido ed efficace possibile<\/i>&#8220;.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Messa in sicurezza, bonifica e recupero delle aree inquinate incluse nel perimetro del S.I.N. (Sito di Interesse Nazionale) del Bacino<\/p>\n","protected":false},"author":18,"featured_media":20241,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[41,2236],"tags":[842,7444,537,94,92,93,7443,809],"class_list":["post-23430","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-slide","category-attualita","tag-antonio-pompeo","tag-aree-agricole","tag-bonifica","tag-ciociaria","tag-ferentino","tag-frosinone","tag-siti-inquinati","tag-valle-del-sacco"],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v27.8 (Yoast SEO v27.8) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Ferentino, primi passi per la bonifica dei siti inquinati nell&#039;area della Valle del Sacco - IlCorriereDellaProvincia.it - News h24 e notizie di approfondimento<\/title>\n<meta name=\"description\" content=\"Si proceder\u00e0 in collaborazione con Arpa, Istituto Superiore di Sanit\u00e0, Servizio Sanitario Nazionale, Istituto Zooprofilattico Nazionale e Asl\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2019\/11\/29\/ferentino-primi-passi-per-la-bonifica-dei-siti-inquinati-nellarea-della-valle-del-sacco\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Ferentino, primi passi per la bonifica dei siti inquinati nell&#039;area della Valle del Sacco\" \/>\n<meta property=\"og:description\" content=\"Si proceder\u00e0 in collaborazione con Arpa, Istituto Superiore di Sanit\u00e0, Servizio Sanitario Nazionale, Istituto Zooprofilattico Nazionale e Asl\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2019\/11\/29\/ferentino-primi-passi-per-la-bonifica-dei-siti-inquinati-nellarea-della-valle-del-sacco\/\" \/>\n<meta property=\"og:site_name\" content=\"IlCorriereDellaProvincia.it - News h24 e notizie di approfondimento\" \/>\n<meta property=\"article:author\" content=\"www.facebook.com\/tunews24\" \/>\n<meta property=\"article:published_time\" content=\"2019-11-29T07:34:08+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2019-11-29T17:25:17+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2019\/10\/piazza-matteotti-ferentino-e1571153718888.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"632\" \/>\n\t<meta property=\"og:image:height\" content=\"474\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Redazione\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"Redazione\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2019\\\/11\\\/29\\\/ferentino-primi-passi-per-la-bonifica-dei-siti-inquinati-nellarea-della-valle-del-sacco\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2019\\\/11\\\/29\\\/ferentino-primi-passi-per-la-bonifica-dei-siti-inquinati-nellarea-della-valle-del-sacco\\\/\"},\"author\":{\"name\":\"Redazione\",\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/#\\\/schema\\\/person\\\/6d7f0a9120d0c03d0c552e9fdf49ed7d\"},\"headline\":\"Ferentino, primi passi per la bonifica dei siti inquinati nell&#8217;area della Valle del Sacco\",\"datePublished\":\"2019-11-29T07:34:08+00:00\",\"dateModified\":\"2019-11-29T17:25:17+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2019\\\/11\\\/29\\\/ferentino-primi-passi-per-la-bonifica-dei-siti-inquinati-nellarea-della-valle-del-sacco\\\/\"},\"wordCount\":312,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2019\\\/11\\\/29\\\/ferentino-primi-passi-per-la-bonifica-dei-siti-inquinati-nellarea-della-valle-del-sacco\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2019\\\/10\\\/piazza-matteotti-ferentino-e1571153718888.jpg\",\"keywords\":[\"antonio pompeo\",\"aree agricole\",\"bonifica\",\"Ciociaria\",\"ferentino\",\"Frosinone\",\"siti inquinati\",\"valle del sacco\"],\"articleSection\":[\"*SLIDE*\",\"Attualit\u00e0\"],\"inLanguage\":\"it-IT\",\"copyrightYear\":\"2019\",\"copyrightHolder\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/#organization\"}},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2019\\\/11\\\/29\\\/ferentino-primi-passi-per-la-bonifica-dei-siti-inquinati-nellarea-della-valle-del-sacco\\\/\",\"url\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2019\\\/11\\\/29\\\/ferentino-primi-passi-per-la-bonifica-dei-siti-inquinati-nellarea-della-valle-del-sacco\\\/\",\"name\":\"Ferentino, primi passi per la bonifica dei siti inquinati nell'area della Valle del Sacco - IlCorriereDellaProvincia.it - News h24 e notizie di approfondimento\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2019\\\/11\\\/29\\\/ferentino-primi-passi-per-la-bonifica-dei-siti-inquinati-nellarea-della-valle-del-sacco\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2019\\\/11\\\/29\\\/ferentino-primi-passi-per-la-bonifica-dei-siti-inquinati-nellarea-della-valle-del-sacco\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2019\\\/10\\\/piazza-matteotti-ferentino-e1571153718888.jpg\",\"datePublished\":\"2019-11-29T07:34:08+00:00\",\"dateModified\":\"2019-11-29T17:25:17+00:00\",\"description\":\"Si proceder\u00e0 in collaborazione con Arpa, Istituto Superiore di Sanit\u00e0, Servizio Sanitario Nazionale, Istituto Zooprofilattico Nazionale e Asl\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2019\\\/11\\\/29\\\/ferentino-primi-passi-per-la-bonifica-dei-siti-inquinati-nellarea-della-valle-del-sacco\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2019\\\/11\\\/29\\\/ferentino-primi-passi-per-la-bonifica-dei-siti-inquinati-nellarea-della-valle-del-sacco\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2019\\\/11\\\/29\\\/ferentino-primi-passi-per-la-bonifica-dei-siti-inquinati-nellarea-della-valle-del-sacco\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2019\\\/10\\\/piazza-matteotti-ferentino-e1571153718888.jpg\",\"contentUrl\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2019\\\/10\\\/piazza-matteotti-ferentino-e1571153718888.jpg\",\"width\":632,\"height\":474,\"caption\":\"Piazza Matteotti a Ferentino\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2019\\\/11\\\/29\\\/ferentino-primi-passi-per-la-bonifica-dei-siti-inquinati-nellarea-della-valle-del-sacco\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Ferentino, primi passi per la bonifica dei siti inquinati nell&#8217;area della Valle del Sacco\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/#website\",\"url\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/\",\"name\":\"Il Corriere Delle Provincia\",\"description\":\"IlCorriereDellaProvincia.it, quotidiano web di politica, cronaca, inchiesta, lavoro, scuola, turismo, cultura e spettacolo, economia e finanza, salute e benessere. Approfondimenti e notizie aggiornate con foto e video della provincia di Frosinone ma anche news nazionali, dell\u2019Italia e del Mondo.\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":[\"Organization\",\"Place\"],\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/#organization\",\"name\":\"Globalpress s.r.l.\",\"url\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/\",\"logo\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2019\\\/11\\\/29\\\/ferentino-primi-passi-per-la-bonifica-dei-siti-inquinati-nellarea-della-valle-del-sacco\\\/#local-main-organization-logo\"},\"image\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2019\\\/11\\\/29\\\/ferentino-primi-passi-per-la-bonifica-dei-siti-inquinati-nellarea-della-valle-del-sacco\\\/#local-main-organization-logo\"},\"telephone\":[],\"openingHoursSpecification\":[{\"@type\":\"OpeningHoursSpecification\",\"dayOfWeek\":[\"Monday\",\"Tuesday\",\"Wednesday\",\"Thursday\",\"Friday\",\"Saturday\",\"Sunday\"],\"opens\":\"09:00\",\"closes\":\"17:00\"}]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/#\\\/schema\\\/person\\\/6d7f0a9120d0c03d0c552e9fdf49ed7d\",\"name\":\"Redazione\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/a40eeacccdcad861f831dde73317f63a542e738f0dc4b79b9f47062d3d4bd1d2?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/a40eeacccdcad861f831dde73317f63a542e738f0dc4b79b9f47062d3d4bd1d2?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/a40eeacccdcad861f831dde73317f63a542e738f0dc4b79b9f47062d3d4bd1d2?s=96&d=mm&r=g\",\"caption\":\"Redazione\"},\"description\":\"SEGUICI ANCHE SUI SOCIAL Facebook: TuNews24 e TuSport24 Instagram: TuNews24 e TuSport24 Youtube: TuNews24 Telegram: TuNews24 Puoi leggerci anche in formato cartaceo: il settimanale viene pubblicato e distribuito gratuitamente ogni venerd\u00ec in edicole, bar, centri commerciali e svariati esercizi. Ma \u00e8 possibile anche sfogliarlo comodamente online, cliccando su TU NEWS sfogliabile TU NEWS, PASSIONE PER L\u2019INFORMAZIONE\",\"sameAs\":[\"http:\\\/\\\/www.tunews24.it\",\"www.facebook.com\\\/tunews24\"],\"url\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/author\\\/senzafirma\\\/\"},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2019\\\/11\\\/29\\\/ferentino-primi-passi-per-la-bonifica-dei-siti-inquinati-nellarea-della-valle-del-sacco\\\/#local-main-organization-logo\",\"url\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2022\\\/11\\\/cropped-il-corriere-della-provincia-testata-web-scontornata.png\",\"contentUrl\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2022\\\/11\\\/cropped-il-corriere-della-provincia-testata-web-scontornata.png\",\"width\":2911,\"height\":717,\"caption\":\"Globalpress s.r.l.\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Ferentino, primi passi per la bonifica dei siti inquinati nell'area della Valle del Sacco - IlCorriereDellaProvincia.it - News h24 e notizie di approfondimento","description":"Si proceder\u00e0 in collaborazione con Arpa, Istituto Superiore di Sanit\u00e0, Servizio Sanitario Nazionale, Istituto Zooprofilattico Nazionale e Asl","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2019\/11\/29\/ferentino-primi-passi-per-la-bonifica-dei-siti-inquinati-nellarea-della-valle-del-sacco\/","og_locale":"it_IT","og_type":"article","og_title":"Ferentino, primi passi per la bonifica dei siti inquinati nell'area della Valle del Sacco","og_description":"Si proceder\u00e0 in collaborazione con Arpa, Istituto Superiore di Sanit\u00e0, Servizio Sanitario Nazionale, Istituto Zooprofilattico Nazionale e Asl","og_url":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2019\/11\/29\/ferentino-primi-passi-per-la-bonifica-dei-siti-inquinati-nellarea-della-valle-del-sacco\/","og_site_name":"IlCorriereDellaProvincia.it - News h24 e notizie di approfondimento","article_author":"www.facebook.com\/tunews24","article_published_time":"2019-11-29T07:34:08+00:00","article_modified_time":"2019-11-29T17:25:17+00:00","og_image":[{"width":632,"height":474,"url":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2019\/10\/piazza-matteotti-ferentino-e1571153718888.jpg","type":"image\/jpeg"}],"author":"Redazione","twitter_card":"summary_large_image","twitter_misc":{"Scritto da":"Redazione","Tempo di lettura stimato":"1 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2019\/11\/29\/ferentino-primi-passi-per-la-bonifica-dei-siti-inquinati-nellarea-della-valle-del-sacco\/#article","isPartOf":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2019\/11\/29\/ferentino-primi-passi-per-la-bonifica-dei-siti-inquinati-nellarea-della-valle-del-sacco\/"},"author":{"name":"Redazione","@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/#\/schema\/person\/6d7f0a9120d0c03d0c552e9fdf49ed7d"},"headline":"Ferentino, primi passi per la bonifica dei siti inquinati nell&#8217;area della Valle del Sacco","datePublished":"2019-11-29T07:34:08+00:00","dateModified":"2019-11-29T17:25:17+00:00","mainEntityOfPage":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2019\/11\/29\/ferentino-primi-passi-per-la-bonifica-dei-siti-inquinati-nellarea-della-valle-del-sacco\/"},"wordCount":312,"commentCount":0,"publisher":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/#organization"},"image":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2019\/11\/29\/ferentino-primi-passi-per-la-bonifica-dei-siti-inquinati-nellarea-della-valle-del-sacco\/#primaryimage"},"thumbnailUrl":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2019\/10\/piazza-matteotti-ferentino-e1571153718888.jpg","keywords":["antonio pompeo","aree agricole","bonifica","Ciociaria","ferentino","Frosinone","siti inquinati","valle del sacco"],"articleSection":["*SLIDE*","Attualit\u00e0"],"inLanguage":"it-IT","copyrightYear":"2019","copyrightHolder":{"@id":"https:\/\/www.tunews24.it\/#organization"}},{"@type":"WebPage","@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2019\/11\/29\/ferentino-primi-passi-per-la-bonifica-dei-siti-inquinati-nellarea-della-valle-del-sacco\/","url":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2019\/11\/29\/ferentino-primi-passi-per-la-bonifica-dei-siti-inquinati-nellarea-della-valle-del-sacco\/","name":"Ferentino, primi passi per la bonifica dei siti inquinati nell'area della Valle del Sacco - IlCorriereDellaProvincia.it - News h24 e notizie di approfondimento","isPartOf":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2019\/11\/29\/ferentino-primi-passi-per-la-bonifica-dei-siti-inquinati-nellarea-della-valle-del-sacco\/#primaryimage"},"image":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2019\/11\/29\/ferentino-primi-passi-per-la-bonifica-dei-siti-inquinati-nellarea-della-valle-del-sacco\/#primaryimage"},"thumbnailUrl":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2019\/10\/piazza-matteotti-ferentino-e1571153718888.jpg","datePublished":"2019-11-29T07:34:08+00:00","dateModified":"2019-11-29T17:25:17+00:00","description":"Si proceder\u00e0 in collaborazione con Arpa, Istituto Superiore di Sanit\u00e0, Servizio Sanitario Nazionale, Istituto Zooprofilattico Nazionale e Asl","breadcrumb":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2019\/11\/29\/ferentino-primi-passi-per-la-bonifica-dei-siti-inquinati-nellarea-della-valle-del-sacco\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2019\/11\/29\/ferentino-primi-passi-per-la-bonifica-dei-siti-inquinati-nellarea-della-valle-del-sacco\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2019\/11\/29\/ferentino-primi-passi-per-la-bonifica-dei-siti-inquinati-nellarea-della-valle-del-sacco\/#primaryimage","url":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2019\/10\/piazza-matteotti-ferentino-e1571153718888.jpg","contentUrl":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2019\/10\/piazza-matteotti-ferentino-e1571153718888.jpg","width":632,"height":474,"caption":"Piazza Matteotti a Ferentino"},{"@type":"BreadcrumbList","@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2019\/11\/29\/ferentino-primi-passi-per-la-bonifica-dei-siti-inquinati-nellarea-della-valle-del-sacco\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/"},{"@type":"ListItem","position":2,"name":"Ferentino, primi passi per la bonifica dei siti inquinati nell&#8217;area della Valle del Sacco"}]},{"@type":"WebSite","@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/#website","url":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/","name":"Il Corriere Delle Provincia","description":"IlCorriereDellaProvincia.it, quotidiano web di politica, cronaca, inchiesta, lavoro, scuola, turismo, cultura e spettacolo, economia e finanza, salute e benessere. Approfondimenti e notizie aggiornate con foto e video della provincia di Frosinone ma anche news nazionali, dell\u2019Italia e del Mondo.","publisher":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":["Organization","Place"],"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/#organization","name":"Globalpress s.r.l.","url":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/","logo":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2019\/11\/29\/ferentino-primi-passi-per-la-bonifica-dei-siti-inquinati-nellarea-della-valle-del-sacco\/#local-main-organization-logo"},"image":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2019\/11\/29\/ferentino-primi-passi-per-la-bonifica-dei-siti-inquinati-nellarea-della-valle-del-sacco\/#local-main-organization-logo"},"telephone":[],"openingHoursSpecification":[{"@type":"OpeningHoursSpecification","dayOfWeek":["Monday","Tuesday","Wednesday","Thursday","Friday","Saturday","Sunday"],"opens":"09:00","closes":"17:00"}]},{"@type":"Person","@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/#\/schema\/person\/6d7f0a9120d0c03d0c552e9fdf49ed7d","name":"Redazione","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/secure.gravatar.com\/avatar\/a40eeacccdcad861f831dde73317f63a542e738f0dc4b79b9f47062d3d4bd1d2?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/a40eeacccdcad861f831dde73317f63a542e738f0dc4b79b9f47062d3d4bd1d2?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/a40eeacccdcad861f831dde73317f63a542e738f0dc4b79b9f47062d3d4bd1d2?s=96&d=mm&r=g","caption":"Redazione"},"description":"SEGUICI ANCHE SUI SOCIAL Facebook: TuNews24 e TuSport24 Instagram: TuNews24 e TuSport24 Youtube: TuNews24 Telegram: TuNews24 Puoi leggerci anche in formato cartaceo: il settimanale viene pubblicato e distribuito gratuitamente ogni venerd\u00ec in edicole, bar, centri commerciali e svariati esercizi. Ma \u00e8 possibile anche sfogliarlo comodamente online, cliccando su TU NEWS sfogliabile TU NEWS, PASSIONE PER L\u2019INFORMAZIONE","sameAs":["http:\/\/www.tunews24.it","www.facebook.com\/tunews24"],"url":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/author\/senzafirma\/"},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2019\/11\/29\/ferentino-primi-passi-per-la-bonifica-dei-siti-inquinati-nellarea-della-valle-del-sacco\/#local-main-organization-logo","url":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2022\/11\/cropped-il-corriere-della-provincia-testata-web-scontornata.png","contentUrl":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2022\/11\/cropped-il-corriere-della-provincia-testata-web-scontornata.png","width":2911,"height":717,"caption":"Globalpress s.r.l."}]}},"_links":{"self":[{"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/posts\/23430","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/users\/18"}],"replies":[{"embeddable":true,"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/comments?post=23430"}],"version-history":[{"count":3,"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/posts\/23430\/revisions"}],"predecessor-version":[{"id":23433,"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/posts\/23430\/revisions\/23433"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/media\/20241"}],"wp:attachment":[{"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/media?parent=23430"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/categories?post=23430"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/tags?post=23430"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}