{"id":23328,"date":"2019-11-27T14:29:33","date_gmt":"2019-11-27T13:29:33","guid":{"rendered":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/?p=23328"},"modified":"2019-11-27T14:48:27","modified_gmt":"2019-11-27T13:48:27","slug":"un-maxi-finanziamento-per-la-condotta-idrica-supino-morolo","status":"publish","type":"post","link":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2019\/11\/27\/un-maxi-finanziamento-per-la-condotta-idrica-supino-morolo\/","title":{"rendered":"Un maxi-finanziamento per la condotta idrica Supino-Morolo"},"content":{"rendered":"<p><strong>Quasi quattro milioni e mezzo di euro<\/strong> per la sostituzione di un tratto della condotta idrica adduttrice \u2018Supino-Morolo\u2019. La realizzazione dell\u2019importante opera,<strong> l\u2019unica finanziata nel Lazio, \u2013 Ambito Territoriale ottimale 5<\/strong> &#8211; \u00e8 ricompresa nel primo stralcio del Piano nazionale degli interventi nel settore idrico &#8211; sezione acquedotti, varato dal Governo a fine dello scorso settembre.<\/p>\n<h2>Risultato importante: unica opera finanziata per l&#8217;Ato 5<\/h2>\n<p>Il finanziamento, completamente a fondo perduto, consentir\u00e0 la realizzazione dell\u2019opera al di fuori delle regole tariffarie e quindi senza alcun ulteriore peso sulle bollette pagate dai cittadini. Un risultato che \u00e8 stato possibile raggiungere solo grazie alla <strong>collaborazione instaurata tra Autorit\u00e0 d\u2019ambito, Segreteria tecnico-operativa, e gestore del servizio idrico Acea Ato 5<\/strong>, che hanno agito in modo compatto.<\/p>\n<p>&nbsp;<\/p>\n<figure id=\"attachment_23330\" aria-describedby=\"caption-attachment-23330\" style=\"width: 632px\" class=\"wp-caption aligncenter\"><img loading=\"lazy\" decoding=\"async\" class=\"wp-image-23330 size-full\" src=\"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2019\/11\/riunione-pompeo-acea-otuc-e1574858637736.jpg\" alt=\"provincia otuc il corriere della provincia\" width=\"632\" height=\"391\" \/><figcaption id=\"caption-attachment-23330\" class=\"wp-caption-text\">Riunione in Provincia con Acea Ato 5 e Otuc<\/figcaption><\/figure>\n<p>&nbsp;<\/p>\n<p>La sistemazione dell\u2019adduttrice Supino-Morolo \u00e8 stata inserita dall\u2019Arera tra gli interventi (in tutto 26) ritenuti prioritari e strategici al fine di raggiungere adeguati livelli di qualit\u00e0 tecnica, ivi compreso l\u2019obiettivo di riduzione della dispersione delle risorse idriche ed \u00e8 tra i primi in Italia che sar\u00e0 realizzato.<\/p>\n<h2>Il commento del presidente Pompeo<\/h2>\n<p>&#8220;Un risultato che certamente premia un lavoro condiviso tra gli enti coinvolti \u2013 \u00e8 il commento del <strong>presidente Antonio Pompeo<\/strong> \u2013 e testimonia, fattivamente, che quando si mette in campo un\u2019azione sinergica si riescono a centrare obiettivi anche importanti che, come in questo caso, non sono affatto scontati&#8221;.<\/p>\n<h2>Quattro gli interventi in tutto il Lazio<\/h2>\n<p>Sono in tutto quattro gli interventi con livello di priorit\u00e0 alto che l\u2019Arera ha individuato nell\u2019intero Lazio e tutti e quattro interessano l\u2019Ato 5 di Frosinone.<\/p>\n<p>Oltre alla sostituzione dell\u2019adduttrice Supino-Morolo gi\u00e0 finanziata con il primo stralcio del piano nazionale, vi sono anche <strong>il rifacimento della condotta adduttrice Colle Roanzo-Colle Cottorino<\/strong> per un importo di oltre 9,2 milioni di euro; la rifunzionalizzazione, ottimizzazione e messa in sicurezza della captazione \u2018Jermalle\u2019 <strong>in territorio del Comune di Falvaterra<\/strong> e la messa in funzione del pozzo<strong> in localit\u00e0 Giardino<\/strong> tra i comuni di Arce e Rocca d\u2019Arce.<\/p>\n<p>Questi ultimi due interventi, <strong>per un importo totale di 860.000 euro<\/strong>, sono stati inseriti, lo scorso ottobre, tra quelli il cui importo potrebbe essere interamente finanziato a valle del gi\u00e0 previsto aggiornamento tariffario.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Quasi quattro milioni e mezzo di euro per la sostituzione di un tratto della condotta idrica adduttrice \u2018Supino-Morolo\u2019. La realizzazione<\/p>\n","protected":false},"author":18,"featured_media":23329,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[4,2236],"tags":[1329,7412,7411,7410,5766,94,5612,837,93,616,227,1751,981],"class_list":["post-23328","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-primo-piano","category-attualita","tag-acea-ato-5","tag-adduttrice","tag-ambito-territoriale","tag-arera","tag-ato5","tag-ciociaria","tag-condotta-idrica","tag-finanziamento","tag-frosinone","tag-interventi","tag-lavori","tag-morolo","tag-supino"],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v27.8 (Yoast SEO v27.8) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Un maxi-finanziamento per la condotta idrica Supino-Morolo - IlCorriereDellaProvincia.it - News h24 e notizie di approfondimento<\/title>\n<meta name=\"description\" content=\"Quattro milioni e mezzo di euro per la sostituzione di un tratto della condotta idrica adduttrice \u2018Supino-Morolo\u2019: unico intervento finanziato per l&#039;Ato 5\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2019\/11\/27\/un-maxi-finanziamento-per-la-condotta-idrica-supino-morolo\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Un maxi-finanziamento per la condotta idrica Supino-Morolo\" \/>\n<meta property=\"og:description\" content=\"Quattro milioni e mezzo di euro per la sostituzione di un tratto della condotta idrica adduttrice \u2018Supino-Morolo\u2019: unico intervento finanziato per l&#039;Ato 5\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2019\/11\/27\/un-maxi-finanziamento-per-la-condotta-idrica-supino-morolo\/\" \/>\n<meta property=\"og:site_name\" content=\"IlCorriereDellaProvincia.it - News h24 e notizie di approfondimento\" \/>\n<meta property=\"article:author\" content=\"www.facebook.com\/tunews24\" \/>\n<meta property=\"article:published_time\" content=\"2019-11-27T13:29:33+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2019-11-27T13:48:27+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2019\/11\/lavori-condotta-idrica.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"683\" \/>\n\t<meta property=\"og:image:height\" content=\"459\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Redazione\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"Redazione\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minuti\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2019\\\/11\\\/27\\\/un-maxi-finanziamento-per-la-condotta-idrica-supino-morolo\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2019\\\/11\\\/27\\\/un-maxi-finanziamento-per-la-condotta-idrica-supino-morolo\\\/\"},\"author\":{\"name\":\"Redazione\",\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/#\\\/schema\\\/person\\\/6d7f0a9120d0c03d0c552e9fdf49ed7d\"},\"headline\":\"Un maxi-finanziamento per la condotta idrica Supino-Morolo\",\"datePublished\":\"2019-11-27T13:29:33+00:00\",\"dateModified\":\"2019-11-27T13:48:27+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2019\\\/11\\\/27\\\/un-maxi-finanziamento-per-la-condotta-idrica-supino-morolo\\\/\"},\"wordCount\":379,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2019\\\/11\\\/27\\\/un-maxi-finanziamento-per-la-condotta-idrica-supino-morolo\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2019\\\/11\\\/lavori-condotta-idrica.jpg\",\"keywords\":[\"acea ato 5\",\"adduttrice\",\"ambito territoriale\",\"arera\",\"ato5\",\"Ciociaria\",\"condotta idrica\",\"finanziamento\",\"Frosinone\",\"interventi\",\"lavori\",\"morolo\",\"Supino\"],\"articleSection\":[\"*PRIMO PIANO*\",\"Attualit\u00e0\"],\"inLanguage\":\"it-IT\",\"copyrightYear\":\"2019\",\"copyrightHolder\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/#organization\"}},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2019\\\/11\\\/27\\\/un-maxi-finanziamento-per-la-condotta-idrica-supino-morolo\\\/\",\"url\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2019\\\/11\\\/27\\\/un-maxi-finanziamento-per-la-condotta-idrica-supino-morolo\\\/\",\"name\":\"Un maxi-finanziamento per la condotta idrica Supino-Morolo - IlCorriereDellaProvincia.it - News h24 e notizie di approfondimento\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2019\\\/11\\\/27\\\/un-maxi-finanziamento-per-la-condotta-idrica-supino-morolo\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2019\\\/11\\\/27\\\/un-maxi-finanziamento-per-la-condotta-idrica-supino-morolo\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2019\\\/11\\\/lavori-condotta-idrica.jpg\",\"datePublished\":\"2019-11-27T13:29:33+00:00\",\"dateModified\":\"2019-11-27T13:48:27+00:00\",\"description\":\"Quattro milioni e mezzo di euro per la sostituzione di un tratto della condotta idrica adduttrice \u2018Supino-Morolo\u2019: unico intervento finanziato per l'Ato 5\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2019\\\/11\\\/27\\\/un-maxi-finanziamento-per-la-condotta-idrica-supino-morolo\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2019\\\/11\\\/27\\\/un-maxi-finanziamento-per-la-condotta-idrica-supino-morolo\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2019\\\/11\\\/27\\\/un-maxi-finanziamento-per-la-condotta-idrica-supino-morolo\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2019\\\/11\\\/lavori-condotta-idrica.jpg\",\"contentUrl\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2019\\\/11\\\/lavori-condotta-idrica.jpg\",\"width\":683,\"height\":459,\"caption\":\"Lavori condotta idrica\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2019\\\/11\\\/27\\\/un-maxi-finanziamento-per-la-condotta-idrica-supino-morolo\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Un maxi-finanziamento per la condotta idrica Supino-Morolo\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/#website\",\"url\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/\",\"name\":\"Il Corriere Delle Provincia\",\"description\":\"IlCorriereDellaProvincia.it, quotidiano web di politica, cronaca, inchiesta, lavoro, scuola, turismo, cultura e spettacolo, economia e finanza, salute e benessere. Approfondimenti e notizie aggiornate con foto e video della provincia di Frosinone ma anche news nazionali, dell\u2019Italia e del Mondo.\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":[\"Organization\",\"Place\"],\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/#organization\",\"name\":\"Globalpress s.r.l.\",\"url\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/\",\"logo\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2019\\\/11\\\/27\\\/un-maxi-finanziamento-per-la-condotta-idrica-supino-morolo\\\/#local-main-organization-logo\"},\"image\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2019\\\/11\\\/27\\\/un-maxi-finanziamento-per-la-condotta-idrica-supino-morolo\\\/#local-main-organization-logo\"},\"telephone\":[],\"openingHoursSpecification\":[{\"@type\":\"OpeningHoursSpecification\",\"dayOfWeek\":[\"Monday\",\"Tuesday\",\"Wednesday\",\"Thursday\",\"Friday\",\"Saturday\",\"Sunday\"],\"opens\":\"09:00\",\"closes\":\"17:00\"}]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/#\\\/schema\\\/person\\\/6d7f0a9120d0c03d0c552e9fdf49ed7d\",\"name\":\"Redazione\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/a40eeacccdcad861f831dde73317f63a542e738f0dc4b79b9f47062d3d4bd1d2?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/a40eeacccdcad861f831dde73317f63a542e738f0dc4b79b9f47062d3d4bd1d2?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/a40eeacccdcad861f831dde73317f63a542e738f0dc4b79b9f47062d3d4bd1d2?s=96&d=mm&r=g\",\"caption\":\"Redazione\"},\"description\":\"SEGUICI ANCHE SUI SOCIAL Facebook: TuNews24 e TuSport24 Instagram: TuNews24 e TuSport24 Youtube: TuNews24 Telegram: TuNews24 Puoi leggerci anche in formato cartaceo: il settimanale viene pubblicato e distribuito gratuitamente ogni venerd\u00ec in edicole, bar, centri commerciali e svariati esercizi. Ma \u00e8 possibile anche sfogliarlo comodamente online, cliccando su TU NEWS sfogliabile TU NEWS, PASSIONE PER L\u2019INFORMAZIONE\",\"sameAs\":[\"http:\\\/\\\/www.tunews24.it\",\"www.facebook.com\\\/tunews24\"],\"url\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/author\\\/senzafirma\\\/\"},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2019\\\/11\\\/27\\\/un-maxi-finanziamento-per-la-condotta-idrica-supino-morolo\\\/#local-main-organization-logo\",\"url\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2022\\\/11\\\/cropped-il-corriere-della-provincia-testata-web-scontornata.png\",\"contentUrl\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2022\\\/11\\\/cropped-il-corriere-della-provincia-testata-web-scontornata.png\",\"width\":2911,\"height\":717,\"caption\":\"Globalpress s.r.l.\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Un maxi-finanziamento per la condotta idrica Supino-Morolo - IlCorriereDellaProvincia.it - News h24 e notizie di approfondimento","description":"Quattro milioni e mezzo di euro per la sostituzione di un tratto della condotta idrica adduttrice \u2018Supino-Morolo\u2019: unico intervento finanziato per l'Ato 5","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2019\/11\/27\/un-maxi-finanziamento-per-la-condotta-idrica-supino-morolo\/","og_locale":"it_IT","og_type":"article","og_title":"Un maxi-finanziamento per la condotta idrica Supino-Morolo","og_description":"Quattro milioni e mezzo di euro per la sostituzione di un tratto della condotta idrica adduttrice \u2018Supino-Morolo\u2019: unico intervento finanziato per l'Ato 5","og_url":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2019\/11\/27\/un-maxi-finanziamento-per-la-condotta-idrica-supino-morolo\/","og_site_name":"IlCorriereDellaProvincia.it - News h24 e notizie di approfondimento","article_author":"www.facebook.com\/tunews24","article_published_time":"2019-11-27T13:29:33+00:00","article_modified_time":"2019-11-27T13:48:27+00:00","og_image":[{"width":683,"height":459,"url":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2019\/11\/lavori-condotta-idrica.jpg","type":"image\/jpeg"}],"author":"Redazione","twitter_card":"summary_large_image","twitter_misc":{"Scritto da":"Redazione","Tempo di lettura stimato":"2 minuti"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2019\/11\/27\/un-maxi-finanziamento-per-la-condotta-idrica-supino-morolo\/#article","isPartOf":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2019\/11\/27\/un-maxi-finanziamento-per-la-condotta-idrica-supino-morolo\/"},"author":{"name":"Redazione","@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/#\/schema\/person\/6d7f0a9120d0c03d0c552e9fdf49ed7d"},"headline":"Un maxi-finanziamento per la condotta idrica Supino-Morolo","datePublished":"2019-11-27T13:29:33+00:00","dateModified":"2019-11-27T13:48:27+00:00","mainEntityOfPage":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2019\/11\/27\/un-maxi-finanziamento-per-la-condotta-idrica-supino-morolo\/"},"wordCount":379,"commentCount":0,"publisher":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/#organization"},"image":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2019\/11\/27\/un-maxi-finanziamento-per-la-condotta-idrica-supino-morolo\/#primaryimage"},"thumbnailUrl":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2019\/11\/lavori-condotta-idrica.jpg","keywords":["acea ato 5","adduttrice","ambito territoriale","arera","ato5","Ciociaria","condotta idrica","finanziamento","Frosinone","interventi","lavori","morolo","Supino"],"articleSection":["*PRIMO PIANO*","Attualit\u00e0"],"inLanguage":"it-IT","copyrightYear":"2019","copyrightHolder":{"@id":"https:\/\/www.tunews24.it\/#organization"}},{"@type":"WebPage","@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2019\/11\/27\/un-maxi-finanziamento-per-la-condotta-idrica-supino-morolo\/","url":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2019\/11\/27\/un-maxi-finanziamento-per-la-condotta-idrica-supino-morolo\/","name":"Un maxi-finanziamento per la condotta idrica Supino-Morolo - IlCorriereDellaProvincia.it - News h24 e notizie di approfondimento","isPartOf":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2019\/11\/27\/un-maxi-finanziamento-per-la-condotta-idrica-supino-morolo\/#primaryimage"},"image":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2019\/11\/27\/un-maxi-finanziamento-per-la-condotta-idrica-supino-morolo\/#primaryimage"},"thumbnailUrl":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2019\/11\/lavori-condotta-idrica.jpg","datePublished":"2019-11-27T13:29:33+00:00","dateModified":"2019-11-27T13:48:27+00:00","description":"Quattro milioni e mezzo di euro per la sostituzione di un tratto della condotta idrica adduttrice \u2018Supino-Morolo\u2019: unico intervento finanziato per l'Ato 5","breadcrumb":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2019\/11\/27\/un-maxi-finanziamento-per-la-condotta-idrica-supino-morolo\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2019\/11\/27\/un-maxi-finanziamento-per-la-condotta-idrica-supino-morolo\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2019\/11\/27\/un-maxi-finanziamento-per-la-condotta-idrica-supino-morolo\/#primaryimage","url":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2019\/11\/lavori-condotta-idrica.jpg","contentUrl":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2019\/11\/lavori-condotta-idrica.jpg","width":683,"height":459,"caption":"Lavori condotta idrica"},{"@type":"BreadcrumbList","@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2019\/11\/27\/un-maxi-finanziamento-per-la-condotta-idrica-supino-morolo\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/"},{"@type":"ListItem","position":2,"name":"Un maxi-finanziamento per la condotta idrica Supino-Morolo"}]},{"@type":"WebSite","@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/#website","url":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/","name":"Il Corriere Delle Provincia","description":"IlCorriereDellaProvincia.it, quotidiano web di politica, cronaca, inchiesta, lavoro, scuola, turismo, cultura e spettacolo, economia e finanza, salute e benessere. Approfondimenti e notizie aggiornate con foto e video della provincia di Frosinone ma anche news nazionali, dell\u2019Italia e del Mondo.","publisher":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":["Organization","Place"],"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/#organization","name":"Globalpress s.r.l.","url":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/","logo":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2019\/11\/27\/un-maxi-finanziamento-per-la-condotta-idrica-supino-morolo\/#local-main-organization-logo"},"image":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2019\/11\/27\/un-maxi-finanziamento-per-la-condotta-idrica-supino-morolo\/#local-main-organization-logo"},"telephone":[],"openingHoursSpecification":[{"@type":"OpeningHoursSpecification","dayOfWeek":["Monday","Tuesday","Wednesday","Thursday","Friday","Saturday","Sunday"],"opens":"09:00","closes":"17:00"}]},{"@type":"Person","@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/#\/schema\/person\/6d7f0a9120d0c03d0c552e9fdf49ed7d","name":"Redazione","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/secure.gravatar.com\/avatar\/a40eeacccdcad861f831dde73317f63a542e738f0dc4b79b9f47062d3d4bd1d2?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/a40eeacccdcad861f831dde73317f63a542e738f0dc4b79b9f47062d3d4bd1d2?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/a40eeacccdcad861f831dde73317f63a542e738f0dc4b79b9f47062d3d4bd1d2?s=96&d=mm&r=g","caption":"Redazione"},"description":"SEGUICI ANCHE SUI SOCIAL Facebook: TuNews24 e TuSport24 Instagram: TuNews24 e TuSport24 Youtube: TuNews24 Telegram: TuNews24 Puoi leggerci anche in formato cartaceo: il settimanale viene pubblicato e distribuito gratuitamente ogni venerd\u00ec in edicole, bar, centri commerciali e svariati esercizi. Ma \u00e8 possibile anche sfogliarlo comodamente online, cliccando su TU NEWS sfogliabile TU NEWS, PASSIONE PER L\u2019INFORMAZIONE","sameAs":["http:\/\/www.tunews24.it","www.facebook.com\/tunews24"],"url":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/author\/senzafirma\/"},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2019\/11\/27\/un-maxi-finanziamento-per-la-condotta-idrica-supino-morolo\/#local-main-organization-logo","url":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2022\/11\/cropped-il-corriere-della-provincia-testata-web-scontornata.png","contentUrl":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2022\/11\/cropped-il-corriere-della-provincia-testata-web-scontornata.png","width":2911,"height":717,"caption":"Globalpress s.r.l."}]}},"_links":{"self":[{"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/posts\/23328","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/users\/18"}],"replies":[{"embeddable":true,"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/comments?post=23328"}],"version-history":[{"count":1,"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/posts\/23328\/revisions"}],"predecessor-version":[{"id":23333,"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/posts\/23328\/revisions\/23333"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/media\/23329"}],"wp:attachment":[{"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/media?parent=23328"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/categories?post=23328"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/tags?post=23328"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}