{"id":22966,"date":"2019-11-22T17:20:35","date_gmt":"2019-11-22T16:20:35","guid":{"rendered":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/?p=22966"},"modified":"2019-11-22T18:58:01","modified_gmt":"2019-11-22T17:58:01","slug":"serrone-festa-per-i-vini-cesanese-dogc-medaglia-doro-e-dei-prodotti-locali","status":"publish","type":"post","link":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2019\/11\/22\/serrone-festa-per-i-vini-cesanese-dogc-medaglia-doro-e-dei-prodotti-locali\/","title":{"rendered":"Serrone, festa per i vini Cesanese Dogc medaglia d\u2019oro e i prodotti locali"},"content":{"rendered":"<p>Ci sar\u00e0 una serata di grande prestigio per <b>La Festa delle Medaglie D\u2019oro<\/b> dei due vini Cesanese <b>Nero Scalambra 2016<\/b> della cantina di <b>Mario Terenzi<\/b> e <b>Vajo Scuro 2016<\/b> di <b>Giovanni Terenzi.<\/b> Etichette DOCG riserva premiate tra tremila concorrenti dall\u2019Associazione internazionale \u201cCitt\u00e0 del Vino\u201d. Due premi che certificano l\u2019eccellenza del vino prodotto nel nord della Ciociaria, pi\u00f9 segnatamente a Serrone, visto che gi\u00e0 facevano parte delle 23 eccellenze italiane delle D.O.C.G.<\/p>\n<h2><\/h2>\n<h2>L&#8217;appuntamento<\/h2>\n<p>L\u2019associazione culturale Rocca D\u2019oro con il suo presidente, il collega <b>Giancarlo Flavi<\/b> e la giuria del Premio con il presidente generale Carlo Felice Corsetti, hanno deciso all\u2019unanimit\u00e0 di assegnare anche a loro il <b>Premio Internazionale Professionalit\u00e0 30ma edizione<\/b> la prestigiosa stampa dell\u2019artista francece <b>Jaklin Nakash De Blanck<\/b> con l\u2019annullo postale del 30 giugno scorso che raffigura la Pace nel Mondo. Perch\u00e9 il vino se degustato porta veramente la Pace ed \u00e8 questa l\u2019occasione per presentare le due etichette premiate alla qualificata platea di giornalisti dell\u2019Arga (Associazione Regionale Giornalisti Agricoli).<\/p>\n<p>Sar\u00e0 questo l\u2019evento, organizzato insieme all\u2019amministrazione comunale ed alla Pro Loco, per conoscere le propriet\u00e0 organolettiche di questo vino illustrate dal Prof. Giovanni Amati ed dal giornalista Roberto Ambrogi (pres. Arga Lazio). Il cesanese sar\u00e0 abbinato alla Pasta De.C.O. \u201cle patacche\u201d che saranno preparate dallo chef del ristorante IL San Michele, alle \u201cciammelle serronesi\u201d ne dolci ne salate buone con tutto, alla salamella serronese al prosciutto cotto al miele con le erbe di Monte Scalambra della Norcineria Minori di Serrone ed a altre specialit\u00e0 del paese.<\/p>\n<p><strong>La serata si svolger\u00e0 sabato 23 alle ore 19,30<\/strong> prima per\u00f2 i giornalisti andranno a visitare il museo dei costumi di teatro di Bice Minori, il museo della \u201cCasa di una volta\u201d e il museo del cittadino onorario Cardinale Dario Castrillon Hoyos che ha donato alla parrocchia di San Pietro anche un Cristo ligneo e il suo altare personale. Poi ci sar\u00e0 la serata di degustazione degli eccellenti prodotti locali.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Ci sar\u00e0 una serata di grande prestigio per La Festa delle Medaglie D\u2019oro dei due vini Cesanese Nero Scalambra 2016<\/p>\n","protected":false},"author":18,"featured_media":22967,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[2236],"tags":[493,7343,7344,7345,5094,2402],"class_list":["post-22966","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-attualita","tag-cesanese","tag-flavi","tag-giovanni-terenzi","tag-mario-terenzi","tag-rocca-doro","tag-serrone"],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v27.8 (Yoast SEO v27.8) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Serrone, festa per i vini Cesanese Dogc medaglia d\u2019oro e i prodotti locali - IlCorriereDellaProvincia.it - News h24 e notizie di approfondimento<\/title>\n<meta name=\"description\" content=\"La Festa delle Medaglie D\u2019oro dei due vini Cesanese Nero Scalambra 2016 della cantina di Mario Terenzi e Vajo Scuro 2016 di Giovanni Terenzi.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2019\/11\/22\/serrone-festa-per-i-vini-cesanese-dogc-medaglia-doro-e-dei-prodotti-locali\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Serrone, festa per i vini Cesanese Dogc medaglia d\u2019oro e i prodotti locali\" \/>\n<meta property=\"og:description\" content=\"La Festa delle Medaglie D\u2019oro dei due vini Cesanese Nero Scalambra 2016 della cantina di Mario Terenzi e Vajo Scuro 2016 di Giovanni Terenzi.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2019\/11\/22\/serrone-festa-per-i-vini-cesanese-dogc-medaglia-doro-e-dei-prodotti-locali\/\" \/>\n<meta property=\"og:site_name\" content=\"IlCorriereDellaProvincia.it - News h24 e notizie di approfondimento\" \/>\n<meta property=\"article:author\" content=\"www.facebook.com\/tunews24\" \/>\n<meta property=\"article:published_time\" content=\"2019-11-22T16:20:35+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2019-11-22T17:58:01+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2019\/11\/Vino.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"780\" \/>\n\t<meta property=\"og:image:height\" content=\"422\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Redazione\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"Redazione\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minuti\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2019\\\/11\\\/22\\\/serrone-festa-per-i-vini-cesanese-dogc-medaglia-doro-e-dei-prodotti-locali\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2019\\\/11\\\/22\\\/serrone-festa-per-i-vini-cesanese-dogc-medaglia-doro-e-dei-prodotti-locali\\\/\"},\"author\":{\"name\":\"Redazione\",\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/#\\\/schema\\\/person\\\/6d7f0a9120d0c03d0c552e9fdf49ed7d\"},\"headline\":\"Serrone, festa per i vini Cesanese Dogc medaglia d\u2019oro e i prodotti locali\",\"datePublished\":\"2019-11-22T16:20:35+00:00\",\"dateModified\":\"2019-11-22T17:58:01+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2019\\\/11\\\/22\\\/serrone-festa-per-i-vini-cesanese-dogc-medaglia-doro-e-dei-prodotti-locali\\\/\"},\"wordCount\":342,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2019\\\/11\\\/22\\\/serrone-festa-per-i-vini-cesanese-dogc-medaglia-doro-e-dei-prodotti-locali\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2019\\\/11\\\/Vino.jpg\",\"keywords\":[\"cesanese\",\"flavi\",\"Giovanni terenzi\",\"mario Terenzi\",\"Rocca d'oro\",\"serrone\"],\"articleSection\":[\"Attualit\u00e0\"],\"inLanguage\":\"it-IT\",\"copyrightYear\":\"2019\",\"copyrightHolder\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/#organization\"}},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2019\\\/11\\\/22\\\/serrone-festa-per-i-vini-cesanese-dogc-medaglia-doro-e-dei-prodotti-locali\\\/\",\"url\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2019\\\/11\\\/22\\\/serrone-festa-per-i-vini-cesanese-dogc-medaglia-doro-e-dei-prodotti-locali\\\/\",\"name\":\"Serrone, festa per i vini Cesanese Dogc medaglia d\u2019oro e i prodotti locali - IlCorriereDellaProvincia.it - News h24 e notizie di approfondimento\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2019\\\/11\\\/22\\\/serrone-festa-per-i-vini-cesanese-dogc-medaglia-doro-e-dei-prodotti-locali\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2019\\\/11\\\/22\\\/serrone-festa-per-i-vini-cesanese-dogc-medaglia-doro-e-dei-prodotti-locali\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2019\\\/11\\\/Vino.jpg\",\"datePublished\":\"2019-11-22T16:20:35+00:00\",\"dateModified\":\"2019-11-22T17:58:01+00:00\",\"description\":\"La Festa delle Medaglie D\u2019oro dei due vini Cesanese Nero Scalambra 2016 della cantina di Mario Terenzi e Vajo Scuro 2016 di Giovanni Terenzi.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2019\\\/11\\\/22\\\/serrone-festa-per-i-vini-cesanese-dogc-medaglia-doro-e-dei-prodotti-locali\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2019\\\/11\\\/22\\\/serrone-festa-per-i-vini-cesanese-dogc-medaglia-doro-e-dei-prodotti-locali\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2019\\\/11\\\/22\\\/serrone-festa-per-i-vini-cesanese-dogc-medaglia-doro-e-dei-prodotti-locali\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2019\\\/11\\\/Vino.jpg\",\"contentUrl\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2019\\\/11\\\/Vino.jpg\",\"width\":780,\"height\":422},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2019\\\/11\\\/22\\\/serrone-festa-per-i-vini-cesanese-dogc-medaglia-doro-e-dei-prodotti-locali\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Serrone, festa per i vini Cesanese Dogc medaglia d\u2019oro e i prodotti locali\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/#website\",\"url\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/\",\"name\":\"Il Corriere Delle Provincia\",\"description\":\"IlCorriereDellaProvincia.it, quotidiano web di politica, cronaca, inchiesta, lavoro, scuola, turismo, cultura e spettacolo, economia e finanza, salute e benessere. Approfondimenti e notizie aggiornate con foto e video della provincia di Frosinone ma anche news nazionali, dell\u2019Italia e del Mondo.\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":[\"Organization\",\"Place\"],\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/#organization\",\"name\":\"Globalpress s.r.l.\",\"url\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/\",\"logo\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2019\\\/11\\\/22\\\/serrone-festa-per-i-vini-cesanese-dogc-medaglia-doro-e-dei-prodotti-locali\\\/#local-main-organization-logo\"},\"image\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2019\\\/11\\\/22\\\/serrone-festa-per-i-vini-cesanese-dogc-medaglia-doro-e-dei-prodotti-locali\\\/#local-main-organization-logo\"},\"telephone\":[],\"openingHoursSpecification\":[{\"@type\":\"OpeningHoursSpecification\",\"dayOfWeek\":[\"Monday\",\"Tuesday\",\"Wednesday\",\"Thursday\",\"Friday\",\"Saturday\",\"Sunday\"],\"opens\":\"09:00\",\"closes\":\"17:00\"}]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/#\\\/schema\\\/person\\\/6d7f0a9120d0c03d0c552e9fdf49ed7d\",\"name\":\"Redazione\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/a40eeacccdcad861f831dde73317f63a542e738f0dc4b79b9f47062d3d4bd1d2?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/a40eeacccdcad861f831dde73317f63a542e738f0dc4b79b9f47062d3d4bd1d2?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/a40eeacccdcad861f831dde73317f63a542e738f0dc4b79b9f47062d3d4bd1d2?s=96&d=mm&r=g\",\"caption\":\"Redazione\"},\"description\":\"SEGUICI ANCHE SUI SOCIAL Facebook: TuNews24 e TuSport24 Instagram: TuNews24 e TuSport24 Youtube: TuNews24 Telegram: TuNews24 Puoi leggerci anche in formato cartaceo: il settimanale viene pubblicato e distribuito gratuitamente ogni venerd\u00ec in edicole, bar, centri commerciali e svariati esercizi. Ma \u00e8 possibile anche sfogliarlo comodamente online, cliccando su TU NEWS sfogliabile TU NEWS, PASSIONE PER L\u2019INFORMAZIONE\",\"sameAs\":[\"http:\\\/\\\/www.tunews24.it\",\"www.facebook.com\\\/tunews24\"],\"url\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/author\\\/senzafirma\\\/\"},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2019\\\/11\\\/22\\\/serrone-festa-per-i-vini-cesanese-dogc-medaglia-doro-e-dei-prodotti-locali\\\/#local-main-organization-logo\",\"url\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2022\\\/11\\\/cropped-il-corriere-della-provincia-testata-web-scontornata.png\",\"contentUrl\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2022\\\/11\\\/cropped-il-corriere-della-provincia-testata-web-scontornata.png\",\"width\":2911,\"height\":717,\"caption\":\"Globalpress s.r.l.\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Serrone, festa per i vini Cesanese Dogc medaglia d\u2019oro e i prodotti locali - IlCorriereDellaProvincia.it - News h24 e notizie di approfondimento","description":"La Festa delle Medaglie D\u2019oro dei due vini Cesanese Nero Scalambra 2016 della cantina di Mario Terenzi e Vajo Scuro 2016 di Giovanni Terenzi.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2019\/11\/22\/serrone-festa-per-i-vini-cesanese-dogc-medaglia-doro-e-dei-prodotti-locali\/","og_locale":"it_IT","og_type":"article","og_title":"Serrone, festa per i vini Cesanese Dogc medaglia d\u2019oro e i prodotti locali","og_description":"La Festa delle Medaglie D\u2019oro dei due vini Cesanese Nero Scalambra 2016 della cantina di Mario Terenzi e Vajo Scuro 2016 di Giovanni Terenzi.","og_url":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2019\/11\/22\/serrone-festa-per-i-vini-cesanese-dogc-medaglia-doro-e-dei-prodotti-locali\/","og_site_name":"IlCorriereDellaProvincia.it - News h24 e notizie di approfondimento","article_author":"www.facebook.com\/tunews24","article_published_time":"2019-11-22T16:20:35+00:00","article_modified_time":"2019-11-22T17:58:01+00:00","og_image":[{"width":780,"height":422,"url":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2019\/11\/Vino.jpg","type":"image\/jpeg"}],"author":"Redazione","twitter_card":"summary_large_image","twitter_misc":{"Scritto da":"Redazione","Tempo di lettura stimato":"2 minuti"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2019\/11\/22\/serrone-festa-per-i-vini-cesanese-dogc-medaglia-doro-e-dei-prodotti-locali\/#article","isPartOf":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2019\/11\/22\/serrone-festa-per-i-vini-cesanese-dogc-medaglia-doro-e-dei-prodotti-locali\/"},"author":{"name":"Redazione","@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/#\/schema\/person\/6d7f0a9120d0c03d0c552e9fdf49ed7d"},"headline":"Serrone, festa per i vini Cesanese Dogc medaglia d\u2019oro e i prodotti locali","datePublished":"2019-11-22T16:20:35+00:00","dateModified":"2019-11-22T17:58:01+00:00","mainEntityOfPage":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2019\/11\/22\/serrone-festa-per-i-vini-cesanese-dogc-medaglia-doro-e-dei-prodotti-locali\/"},"wordCount":342,"commentCount":0,"publisher":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/#organization"},"image":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2019\/11\/22\/serrone-festa-per-i-vini-cesanese-dogc-medaglia-doro-e-dei-prodotti-locali\/#primaryimage"},"thumbnailUrl":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2019\/11\/Vino.jpg","keywords":["cesanese","flavi","Giovanni terenzi","mario Terenzi","Rocca d'oro","serrone"],"articleSection":["Attualit\u00e0"],"inLanguage":"it-IT","copyrightYear":"2019","copyrightHolder":{"@id":"https:\/\/www.tunews24.it\/#organization"}},{"@type":"WebPage","@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2019\/11\/22\/serrone-festa-per-i-vini-cesanese-dogc-medaglia-doro-e-dei-prodotti-locali\/","url":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2019\/11\/22\/serrone-festa-per-i-vini-cesanese-dogc-medaglia-doro-e-dei-prodotti-locali\/","name":"Serrone, festa per i vini Cesanese Dogc medaglia d\u2019oro e i prodotti locali - IlCorriereDellaProvincia.it - News h24 e notizie di approfondimento","isPartOf":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2019\/11\/22\/serrone-festa-per-i-vini-cesanese-dogc-medaglia-doro-e-dei-prodotti-locali\/#primaryimage"},"image":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2019\/11\/22\/serrone-festa-per-i-vini-cesanese-dogc-medaglia-doro-e-dei-prodotti-locali\/#primaryimage"},"thumbnailUrl":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2019\/11\/Vino.jpg","datePublished":"2019-11-22T16:20:35+00:00","dateModified":"2019-11-22T17:58:01+00:00","description":"La Festa delle Medaglie D\u2019oro dei due vini Cesanese Nero Scalambra 2016 della cantina di Mario Terenzi e Vajo Scuro 2016 di Giovanni Terenzi.","breadcrumb":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2019\/11\/22\/serrone-festa-per-i-vini-cesanese-dogc-medaglia-doro-e-dei-prodotti-locali\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2019\/11\/22\/serrone-festa-per-i-vini-cesanese-dogc-medaglia-doro-e-dei-prodotti-locali\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2019\/11\/22\/serrone-festa-per-i-vini-cesanese-dogc-medaglia-doro-e-dei-prodotti-locali\/#primaryimage","url":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2019\/11\/Vino.jpg","contentUrl":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2019\/11\/Vino.jpg","width":780,"height":422},{"@type":"BreadcrumbList","@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2019\/11\/22\/serrone-festa-per-i-vini-cesanese-dogc-medaglia-doro-e-dei-prodotti-locali\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/"},{"@type":"ListItem","position":2,"name":"Serrone, festa per i vini Cesanese Dogc medaglia d\u2019oro e i prodotti locali"}]},{"@type":"WebSite","@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/#website","url":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/","name":"Il Corriere Delle Provincia","description":"IlCorriereDellaProvincia.it, quotidiano web di politica, cronaca, inchiesta, lavoro, scuola, turismo, cultura e spettacolo, economia e finanza, salute e benessere. Approfondimenti e notizie aggiornate con foto e video della provincia di Frosinone ma anche news nazionali, dell\u2019Italia e del Mondo.","publisher":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":["Organization","Place"],"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/#organization","name":"Globalpress s.r.l.","url":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/","logo":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2019\/11\/22\/serrone-festa-per-i-vini-cesanese-dogc-medaglia-doro-e-dei-prodotti-locali\/#local-main-organization-logo"},"image":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2019\/11\/22\/serrone-festa-per-i-vini-cesanese-dogc-medaglia-doro-e-dei-prodotti-locali\/#local-main-organization-logo"},"telephone":[],"openingHoursSpecification":[{"@type":"OpeningHoursSpecification","dayOfWeek":["Monday","Tuesday","Wednesday","Thursday","Friday","Saturday","Sunday"],"opens":"09:00","closes":"17:00"}]},{"@type":"Person","@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/#\/schema\/person\/6d7f0a9120d0c03d0c552e9fdf49ed7d","name":"Redazione","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/secure.gravatar.com\/avatar\/a40eeacccdcad861f831dde73317f63a542e738f0dc4b79b9f47062d3d4bd1d2?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/a40eeacccdcad861f831dde73317f63a542e738f0dc4b79b9f47062d3d4bd1d2?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/a40eeacccdcad861f831dde73317f63a542e738f0dc4b79b9f47062d3d4bd1d2?s=96&d=mm&r=g","caption":"Redazione"},"description":"SEGUICI ANCHE SUI SOCIAL Facebook: TuNews24 e TuSport24 Instagram: TuNews24 e TuSport24 Youtube: TuNews24 Telegram: TuNews24 Puoi leggerci anche in formato cartaceo: il settimanale viene pubblicato e distribuito gratuitamente ogni venerd\u00ec in edicole, bar, centri commerciali e svariati esercizi. Ma \u00e8 possibile anche sfogliarlo comodamente online, cliccando su TU NEWS sfogliabile TU NEWS, PASSIONE PER L\u2019INFORMAZIONE","sameAs":["http:\/\/www.tunews24.it","www.facebook.com\/tunews24"],"url":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/author\/senzafirma\/"},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2019\/11\/22\/serrone-festa-per-i-vini-cesanese-dogc-medaglia-doro-e-dei-prodotti-locali\/#local-main-organization-logo","url":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2022\/11\/cropped-il-corriere-della-provincia-testata-web-scontornata.png","contentUrl":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2022\/11\/cropped-il-corriere-della-provincia-testata-web-scontornata.png","width":2911,"height":717,"caption":"Globalpress s.r.l."}]}},"_links":{"self":[{"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/posts\/22966","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/users\/18"}],"replies":[{"embeddable":true,"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/comments?post=22966"}],"version-history":[{"count":4,"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/posts\/22966\/revisions"}],"predecessor-version":[{"id":22983,"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/posts\/22966\/revisions\/22983"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/media\/22967"}],"wp:attachment":[{"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/media?parent=22966"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/categories?post=22966"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/tags?post=22966"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}