{"id":22953,"date":"2019-11-22T18:43:00","date_gmt":"2019-11-22T17:43:00","guid":{"rendered":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/?p=22953"},"modified":"2019-11-22T18:49:28","modified_gmt":"2019-11-22T17:49:28","slug":"frosinone-unindustria-camera-di-commercio","status":"publish","type":"post","link":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2019\/11\/22\/frosinone-unindustria-camera-di-commercio\/","title":{"rendered":"Autisti per aziende di trasporto, progetto di Camera di Commercio, Unindustria e Orienta"},"content":{"rendered":"<p><strong>La Camera di Commercio, Unindustria ed Orienta spa<\/strong>, agenzia per il lavoro associata ad Unindustria e con il contributo del Consorzio per lo Sviluppo Industriale di Frosinone, stanno per avviare \u00a0un primo corso di formazione per soddisfare il fabbisogno formativo delle Imprese di autotrasporto merci e persone nel reperimento di autisti in possesso dei requisiti di legge.<\/p>\n<p>&nbsp;<\/p>\n<p style=\"text-align: center;\"><iframe loading=\"lazy\" src=\"\/\/www.youtube.com\/embed\/LQ_QHzUOrFE\" width=\"560\" height=\"315\" frameborder=\"0\" allowfullscreen=\"allowfullscreen\"><\/iframe><\/p>\n<p>&nbsp;<\/p>\n<h2>L&#8217;obiettivo<\/h2>\n<p><strong>Una recente ricerca sull&#8217;autotrasporto<\/strong> europeo ha evidenziato, infatti, la forte carenza di autisti di veicoli industriali dovuta ad una serie di fattori come: cambio generazionale, la delocalizzazione di molte imprese occidentali verso paesi dell\u2019Est, costi elevati per il conseguimento delle patenti.<\/p>\n<p>La progettualit\u00e0 della Camera di Commercio, Unindustria Frosinone e Orienta <strong>mira a creare professionalit\u00e0 al servizio delle imprese<\/strong> ed una sicura prospettiva occupazionale ai partecipanti, selezionati prioritariamente tra inoccupati e disoccupati under 45, che aderiranno al percorso formativo.\u00a0\u00a0 Il percorso prevede la formazione per il conseguimento della patente per dieci autisti nel settore trasporto persone e dieci autisti per il settore trasporto merci.<\/p>\n<h2>Le aziende coinvolte<\/h2>\n<p>Al progetto hanno aderito e dato la disponibilit\u00e0 ad assumere gli autisti una volta formati sono, per il trasporto persone Cialone Tour Spa, Iannucci Autotrasporti Sas, Reali Tours Srl;\u00a0 per il trasporto merci: Turriziani Trasporti Srl, Pigliacelli, Schietroma Trasporti\u00a0 e\u00a0 La Marra Srl.\u00a0 Le patenti che verranno rilasciate sono la C la CQC, la E e la ADR per il trasporto merci. La selezione delle candidature verr\u00e0 interamente gestita da Orienta.<\/p>\n<p>&nbsp;<\/p>\n<h2><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter wp-image-22955\" src=\"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2019\/11\/unindustria-ricci.jpg\" alt=\"\" width=\"632\" height=\"356\" srcset=\"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2019\/11\/unindustria-ricci.jpg 1008w, https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2019\/11\/unindustria-ricci-300x169.jpg 300w, https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2019\/11\/unindustria-ricci-768x432.jpg 768w, https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2019\/11\/unindustria-ricci-500x281.jpg 500w\" sizes=\"auto, (max-width: 632px) 100vw, 632px\" \/><\/h2>\n<h2><\/h2>\n<h2>L&#8217;intervento di Turriziani<\/h2>\n<p>\u201cTale iniziativa \u00e8 nata da un fabbisogno emerso dalle aziende di autotrasporto che hanno sempre maggiori difficolt\u00e0 nel reperire gli autisti \u2013 dichiara il Presidente di Unindustria Frosinone <strong>Giovanni Turriziani<\/strong> \u2013 per questo motivo insieme alla Camera di Commercio abbiamo voluto avviare questo progetto formativo. La nostra associazione, del resto, sempre pi\u00f9 attenta alle reali esigenze delle aziende, sta prestando ultimamente una sempre maggiore attenzione anche alla formazione del personale, cos\u00ec come dimostrato recentemente anche con il corso ITS. Auspichiamo con questa iniziativa di poter dare un altro piccolo contributo per la creazione di altri posti di lavoro in provincia di Frosinone, dove l\u2019esigenza di incontro tra domanda ed offerta \u00e8 sempre pi\u00f9 evidente\u201d.<\/p>\n<h2><\/h2>\n<h2>L&#8217;analisi di Pigliacelli<\/h2>\n<p>\u201cE\u2019 molto importante la sinergia tra pubblico e privato attivata con questo progetto \u2013 dichiara il Presidente della Camera di Commercio di Frosinone <strong>Marcello Pigliacelli<\/strong> \u2013 Tutto ci\u00f2 dimostra che quando la finalit\u00e0 di una progettualit\u00e0 \u00e8 nobile, \u00e8 fondamentale la collaborazione. In questo caso vogliamo dare l\u2019opportunit\u00e0 a persone disoccupate o comunque uscite temporaneamente dal mondo del lavoro di potersi formare ed avere cos\u00ec un nuovo impiego.<\/p>\n<p>&#8220;<strong>Altro valore aggiunto del progetto<\/strong> \u00e8 che con esso vogliamo creare un link tra il mondo della formazione e quello del lavoro ed in questo caso vogliamo dare l\u2019opportunit\u00e0 a persone anche un po\u2019 pi\u00f9 avanti con gli anni di poter essere reimpiegate. Le aziende partecipanti, infatti, hanno assunto l\u2019impegno di occupare il capitale umano che verr\u00e0 formato, e questa \u00e8 una cosa di estrema importanza per il mondo del lavoro del nostro territorio\u201d.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>La Camera di Commercio, Unindustria ed Orienta spa, agenzia per il lavoro associata ad Unindustria e con il contributo del<\/p>\n","protected":false},"author":18,"featured_media":22954,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[4,5],"tags":[7302,7336,1013,93,1023,7337,2126,7341,7340,7338,7339,170],"class_list":["post-22953","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-primo-piano","category-economia","tag-autisti","tag-cailone-tour","tag-camera-di-commercio","tag-frosinone","tag-giovanni-turriziani","tag-iannucci-autotrasporti-sas","tag-marcello-pigliacelli","tag-orienta","tag-patenti","tag-reali-tours-srl","tag-schietroma-trasporti-e-la-marra-srl","tag-unindustria"],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v27.8 (Yoast SEO v27.8) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Autisti per aziende di trasporto, progetto di Camera di Commercio, Unindustria e Orienta - IlCorriereDellaProvincia.it - News h24 e notizie di approfondimento<\/title>\n<meta name=\"description\" content=\"La progettualit\u00e0 della Camera di Commercio, Unindustria Frosinone e Orienta mira a creare professionalit\u00e0 al servizio delle imprese\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2019\/11\/22\/frosinone-unindustria-camera-di-commercio\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Autisti per aziende di trasporto, progetto di Camera di Commercio, Unindustria e Orienta\" \/>\n<meta property=\"og:description\" content=\"La progettualit\u00e0 della Camera di Commercio, Unindustria Frosinone e Orienta mira a creare professionalit\u00e0 al servizio delle imprese\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2019\/11\/22\/frosinone-unindustria-camera-di-commercio\/\" \/>\n<meta property=\"og:site_name\" content=\"IlCorriereDellaProvincia.it - News h24 e notizie di approfondimento\" \/>\n<meta property=\"article:author\" content=\"www.facebook.com\/tunews24\" \/>\n<meta property=\"article:published_time\" content=\"2019-11-22T17:43:00+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2019-11-22T17:49:28+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2019\/11\/Unindustria-Pigliacelli-Turriziani-1.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1008\" \/>\n\t<meta property=\"og:image:height\" content=\"567\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Redazione\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"Redazione\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minuti\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2019\\\/11\\\/22\\\/frosinone-unindustria-camera-di-commercio\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2019\\\/11\\\/22\\\/frosinone-unindustria-camera-di-commercio\\\/\"},\"author\":{\"name\":\"Redazione\",\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/#\\\/schema\\\/person\\\/6d7f0a9120d0c03d0c552e9fdf49ed7d\"},\"headline\":\"Autisti per aziende di trasporto, progetto di Camera di Commercio, Unindustria e Orienta\",\"datePublished\":\"2019-11-22T17:43:00+00:00\",\"dateModified\":\"2019-11-22T17:49:28+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2019\\\/11\\\/22\\\/frosinone-unindustria-camera-di-commercio\\\/\"},\"wordCount\":512,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2019\\\/11\\\/22\\\/frosinone-unindustria-camera-di-commercio\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2019\\\/11\\\/Unindustria-Pigliacelli-Turriziani-1.jpg\",\"keywords\":[\"autisti\",\"Cailone tour\",\"Camera di Commercio\",\"Frosinone\",\"giovanni turriziani\",\"Iannucci Autotrasporti Sas\",\"marcello pigliacelli\",\"orienta\",\"patenti\",\"Reali Tours Srl\",\"Schietroma Trasporti e La Marra Srl\",\"Unindustria\"],\"articleSection\":[\"*PRIMO PIANO*\",\"Economia e Finanza\"],\"inLanguage\":\"it-IT\",\"copyrightYear\":\"2019\",\"copyrightHolder\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/#organization\"}},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2019\\\/11\\\/22\\\/frosinone-unindustria-camera-di-commercio\\\/\",\"url\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2019\\\/11\\\/22\\\/frosinone-unindustria-camera-di-commercio\\\/\",\"name\":\"Autisti per aziende di trasporto, progetto di Camera di Commercio, Unindustria e Orienta - IlCorriereDellaProvincia.it - News h24 e notizie di approfondimento\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2019\\\/11\\\/22\\\/frosinone-unindustria-camera-di-commercio\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2019\\\/11\\\/22\\\/frosinone-unindustria-camera-di-commercio\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2019\\\/11\\\/Unindustria-Pigliacelli-Turriziani-1.jpg\",\"datePublished\":\"2019-11-22T17:43:00+00:00\",\"dateModified\":\"2019-11-22T17:49:28+00:00\",\"description\":\"La progettualit\u00e0 della Camera di Commercio, Unindustria Frosinone e Orienta mira a creare professionalit\u00e0 al servizio delle imprese\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2019\\\/11\\\/22\\\/frosinone-unindustria-camera-di-commercio\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2019\\\/11\\\/22\\\/frosinone-unindustria-camera-di-commercio\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2019\\\/11\\\/22\\\/frosinone-unindustria-camera-di-commercio\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2019\\\/11\\\/Unindustria-Pigliacelli-Turriziani-1.jpg\",\"contentUrl\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2019\\\/11\\\/Unindustria-Pigliacelli-Turriziani-1.jpg\",\"width\":1008,\"height\":567},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2019\\\/11\\\/22\\\/frosinone-unindustria-camera-di-commercio\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Autisti per aziende di trasporto, progetto di Camera di Commercio, Unindustria e Orienta\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/#website\",\"url\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/\",\"name\":\"Il Corriere Delle Provincia\",\"description\":\"IlCorriereDellaProvincia.it, quotidiano web di politica, cronaca, inchiesta, lavoro, scuola, turismo, cultura e spettacolo, economia e finanza, salute e benessere. Approfondimenti e notizie aggiornate con foto e video della provincia di Frosinone ma anche news nazionali, dell\u2019Italia e del Mondo.\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":[\"Organization\",\"Place\"],\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/#organization\",\"name\":\"Globalpress s.r.l.\",\"url\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/\",\"logo\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2019\\\/11\\\/22\\\/frosinone-unindustria-camera-di-commercio\\\/#local-main-organization-logo\"},\"image\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2019\\\/11\\\/22\\\/frosinone-unindustria-camera-di-commercio\\\/#local-main-organization-logo\"},\"telephone\":[],\"openingHoursSpecification\":[{\"@type\":\"OpeningHoursSpecification\",\"dayOfWeek\":[\"Monday\",\"Tuesday\",\"Wednesday\",\"Thursday\",\"Friday\",\"Saturday\",\"Sunday\"],\"opens\":\"09:00\",\"closes\":\"17:00\"}]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/#\\\/schema\\\/person\\\/6d7f0a9120d0c03d0c552e9fdf49ed7d\",\"name\":\"Redazione\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/a40eeacccdcad861f831dde73317f63a542e738f0dc4b79b9f47062d3d4bd1d2?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/a40eeacccdcad861f831dde73317f63a542e738f0dc4b79b9f47062d3d4bd1d2?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/a40eeacccdcad861f831dde73317f63a542e738f0dc4b79b9f47062d3d4bd1d2?s=96&d=mm&r=g\",\"caption\":\"Redazione\"},\"description\":\"SEGUICI ANCHE SUI SOCIAL Facebook: TuNews24 e TuSport24 Instagram: TuNews24 e TuSport24 Youtube: TuNews24 Telegram: TuNews24 Puoi leggerci anche in formato cartaceo: il settimanale viene pubblicato e distribuito gratuitamente ogni venerd\u00ec in edicole, bar, centri commerciali e svariati esercizi. Ma \u00e8 possibile anche sfogliarlo comodamente online, cliccando su TU NEWS sfogliabile TU NEWS, PASSIONE PER L\u2019INFORMAZIONE\",\"sameAs\":[\"http:\\\/\\\/www.tunews24.it\",\"www.facebook.com\\\/tunews24\"],\"url\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/author\\\/senzafirma\\\/\"},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2019\\\/11\\\/22\\\/frosinone-unindustria-camera-di-commercio\\\/#local-main-organization-logo\",\"url\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2022\\\/11\\\/cropped-il-corriere-della-provincia-testata-web-scontornata.png\",\"contentUrl\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2022\\\/11\\\/cropped-il-corriere-della-provincia-testata-web-scontornata.png\",\"width\":2911,\"height\":717,\"caption\":\"Globalpress s.r.l.\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Autisti per aziende di trasporto, progetto di Camera di Commercio, Unindustria e Orienta - IlCorriereDellaProvincia.it - News h24 e notizie di approfondimento","description":"La progettualit\u00e0 della Camera di Commercio, Unindustria Frosinone e Orienta mira a creare professionalit\u00e0 al servizio delle imprese","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2019\/11\/22\/frosinone-unindustria-camera-di-commercio\/","og_locale":"it_IT","og_type":"article","og_title":"Autisti per aziende di trasporto, progetto di Camera di Commercio, Unindustria e Orienta","og_description":"La progettualit\u00e0 della Camera di Commercio, Unindustria Frosinone e Orienta mira a creare professionalit\u00e0 al servizio delle imprese","og_url":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2019\/11\/22\/frosinone-unindustria-camera-di-commercio\/","og_site_name":"IlCorriereDellaProvincia.it - News h24 e notizie di approfondimento","article_author":"www.facebook.com\/tunews24","article_published_time":"2019-11-22T17:43:00+00:00","article_modified_time":"2019-11-22T17:49:28+00:00","og_image":[{"width":1008,"height":567,"url":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2019\/11\/Unindustria-Pigliacelli-Turriziani-1.jpg","type":"image\/jpeg"}],"author":"Redazione","twitter_card":"summary_large_image","twitter_misc":{"Scritto da":"Redazione","Tempo di lettura stimato":"2 minuti"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2019\/11\/22\/frosinone-unindustria-camera-di-commercio\/#article","isPartOf":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2019\/11\/22\/frosinone-unindustria-camera-di-commercio\/"},"author":{"name":"Redazione","@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/#\/schema\/person\/6d7f0a9120d0c03d0c552e9fdf49ed7d"},"headline":"Autisti per aziende di trasporto, progetto di Camera di Commercio, Unindustria e Orienta","datePublished":"2019-11-22T17:43:00+00:00","dateModified":"2019-11-22T17:49:28+00:00","mainEntityOfPage":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2019\/11\/22\/frosinone-unindustria-camera-di-commercio\/"},"wordCount":512,"commentCount":0,"publisher":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/#organization"},"image":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2019\/11\/22\/frosinone-unindustria-camera-di-commercio\/#primaryimage"},"thumbnailUrl":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2019\/11\/Unindustria-Pigliacelli-Turriziani-1.jpg","keywords":["autisti","Cailone tour","Camera di Commercio","Frosinone","giovanni turriziani","Iannucci Autotrasporti Sas","marcello pigliacelli","orienta","patenti","Reali Tours Srl","Schietroma Trasporti e La Marra Srl","Unindustria"],"articleSection":["*PRIMO PIANO*","Economia e Finanza"],"inLanguage":"it-IT","copyrightYear":"2019","copyrightHolder":{"@id":"https:\/\/www.tunews24.it\/#organization"}},{"@type":"WebPage","@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2019\/11\/22\/frosinone-unindustria-camera-di-commercio\/","url":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2019\/11\/22\/frosinone-unindustria-camera-di-commercio\/","name":"Autisti per aziende di trasporto, progetto di Camera di Commercio, Unindustria e Orienta - IlCorriereDellaProvincia.it - News h24 e notizie di approfondimento","isPartOf":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2019\/11\/22\/frosinone-unindustria-camera-di-commercio\/#primaryimage"},"image":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2019\/11\/22\/frosinone-unindustria-camera-di-commercio\/#primaryimage"},"thumbnailUrl":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2019\/11\/Unindustria-Pigliacelli-Turriziani-1.jpg","datePublished":"2019-11-22T17:43:00+00:00","dateModified":"2019-11-22T17:49:28+00:00","description":"La progettualit\u00e0 della Camera di Commercio, Unindustria Frosinone e Orienta mira a creare professionalit\u00e0 al servizio delle imprese","breadcrumb":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2019\/11\/22\/frosinone-unindustria-camera-di-commercio\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2019\/11\/22\/frosinone-unindustria-camera-di-commercio\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2019\/11\/22\/frosinone-unindustria-camera-di-commercio\/#primaryimage","url":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2019\/11\/Unindustria-Pigliacelli-Turriziani-1.jpg","contentUrl":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2019\/11\/Unindustria-Pigliacelli-Turriziani-1.jpg","width":1008,"height":567},{"@type":"BreadcrumbList","@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2019\/11\/22\/frosinone-unindustria-camera-di-commercio\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/"},{"@type":"ListItem","position":2,"name":"Autisti per aziende di trasporto, progetto di Camera di Commercio, Unindustria e Orienta"}]},{"@type":"WebSite","@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/#website","url":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/","name":"Il Corriere Delle Provincia","description":"IlCorriereDellaProvincia.it, quotidiano web di politica, cronaca, inchiesta, lavoro, scuola, turismo, cultura e spettacolo, economia e finanza, salute e benessere. Approfondimenti e notizie aggiornate con foto e video della provincia di Frosinone ma anche news nazionali, dell\u2019Italia e del Mondo.","publisher":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":["Organization","Place"],"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/#organization","name":"Globalpress s.r.l.","url":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/","logo":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2019\/11\/22\/frosinone-unindustria-camera-di-commercio\/#local-main-organization-logo"},"image":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2019\/11\/22\/frosinone-unindustria-camera-di-commercio\/#local-main-organization-logo"},"telephone":[],"openingHoursSpecification":[{"@type":"OpeningHoursSpecification","dayOfWeek":["Monday","Tuesday","Wednesday","Thursday","Friday","Saturday","Sunday"],"opens":"09:00","closes":"17:00"}]},{"@type":"Person","@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/#\/schema\/person\/6d7f0a9120d0c03d0c552e9fdf49ed7d","name":"Redazione","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/secure.gravatar.com\/avatar\/a40eeacccdcad861f831dde73317f63a542e738f0dc4b79b9f47062d3d4bd1d2?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/a40eeacccdcad861f831dde73317f63a542e738f0dc4b79b9f47062d3d4bd1d2?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/a40eeacccdcad861f831dde73317f63a542e738f0dc4b79b9f47062d3d4bd1d2?s=96&d=mm&r=g","caption":"Redazione"},"description":"SEGUICI ANCHE SUI SOCIAL Facebook: TuNews24 e TuSport24 Instagram: TuNews24 e TuSport24 Youtube: TuNews24 Telegram: TuNews24 Puoi leggerci anche in formato cartaceo: il settimanale viene pubblicato e distribuito gratuitamente ogni venerd\u00ec in edicole, bar, centri commerciali e svariati esercizi. Ma \u00e8 possibile anche sfogliarlo comodamente online, cliccando su TU NEWS sfogliabile TU NEWS, PASSIONE PER L\u2019INFORMAZIONE","sameAs":["http:\/\/www.tunews24.it","www.facebook.com\/tunews24"],"url":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/author\/senzafirma\/"},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2019\/11\/22\/frosinone-unindustria-camera-di-commercio\/#local-main-organization-logo","url":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2022\/11\/cropped-il-corriere-della-provincia-testata-web-scontornata.png","contentUrl":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2022\/11\/cropped-il-corriere-della-provincia-testata-web-scontornata.png","width":2911,"height":717,"caption":"Globalpress s.r.l."}]}},"_links":{"self":[{"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/posts\/22953","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/users\/18"}],"replies":[{"embeddable":true,"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/comments?post=22953"}],"version-history":[{"count":5,"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/posts\/22953\/revisions"}],"predecessor-version":[{"id":22982,"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/posts\/22953\/revisions\/22982"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/media\/22954"}],"wp:attachment":[{"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/media?parent=22953"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/categories?post=22953"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/tags?post=22953"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}