{"id":22927,"date":"2019-11-22T13:11:32","date_gmt":"2019-11-22T12:11:32","guid":{"rendered":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/?p=22927"},"modified":"2019-11-23T16:33:58","modified_gmt":"2019-11-23T15:33:58","slug":"magliocchetti-sulla-moschea-servono-equilibrio-e-buon-senso","status":"publish","type":"post","link":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2019\/11\/22\/magliocchetti-sulla-moschea-servono-equilibrio-e-buon-senso\/","title":{"rendered":"Moschea, Magliocchetti: usare equilibrio e buon senso"},"content":{"rendered":"<p>A gettare acqua sulla vicenda &#8216;infuocata&#8217; della Moschea \u00e8 il <strong>consigliere comunale di Frosinone<\/strong>, <strong>Danilo Magliocchetti<\/strong>, che invita tutti a non fare del sensazionalismo, &#8220;perch\u00e9 <strong>si corre il rischio di ingenerare solo equivoci<\/strong>, confusione e di conseguenza ingiustificabile allarme&#8221;.<\/p>\n<h2>La posizione di Magliocchetti<\/h2>\n<p>&#8220;Sono tanti gli interessi e i diritti da tutelare, in questa come in tutte le pratiche urbanistiche. <strong>Bisogna tutelare<\/strong>, in primo luogo, <strong>l\u2019amministrazione comunale<\/strong>, senza esporla a rischi inutili e onerosi. <strong>Bisogna tutelare i residenti<\/strong> coinvolti nell\u2019intervento urbanistico, affinch\u00e9 non abbiano ogni possibile eventuale nocumento. <strong>Bisogna tutelare il diritto del consigliere comunale<\/strong> di esercitare il proprio ruolo di controllo e stimolo. <strong>Bisogna tutelare<\/strong>, infine,<strong> il diritto di chiunque voglia presentare una pratica urbanistica<\/strong>, ovviamente che sia conforme a tutti i requisiti di legge e agli standard&#8221;.<\/p>\n<h2>L&#8217;invito<\/h2>\n<p>&#8220;Nella vicenda della cosiddetta Moschea \u2013 sottolinea il consigliere &#8211; siamo ancora nella fase istruttoria e nessun atto, di nessun genere, men che meno autorizzativo, \u00e8 stato fino ad ora rilasciato dall\u2019amministrazione comunale che, evidentemente, ancora non si \u00e8 espressa sull\u2019istanza specifica e sulla eventuale localizzazione&#8221;.<\/p>\n<p>&nbsp;<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter wp-image-10393 size-full\" src=\"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2019\/04\/moschea-Frosinone-il-corriere-della-provincia.jpg\" alt=\"moschea Frosinone il corriere della provincia ciociaria\" width=\"755\" height=\"408\" srcset=\"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2019\/04\/moschea-Frosinone-il-corriere-della-provincia.jpg 755w, https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2019\/04\/moschea-Frosinone-il-corriere-della-provincia-300x162.jpg 300w, https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2019\/04\/moschea-Frosinone-il-corriere-della-provincia-500x270.jpg 500w\" sizes=\"auto, (max-width: 755px) 100vw, 755px\" \/><\/p>\n<p>&nbsp;<\/p>\n<p>&#8220;Quando la pratica sar\u00e0 perfezionata, acquisito il parere della o delle commissioni competenti, ed eventualmente portata all\u2019attenzione del Consiglio Comunale, quello sar\u00e0 il luogo deputato per il confronto sul tema, anche duro, tra i Consiglieri, per esprimere pareri, valutazioni o eventuali proposte alternative, senza arroccarsi e cntestardirsi su posizioni preconcette. Allo stato esistono, comunque, altre tre o quattro possibili soluzioni&#8221;.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>A gettare acqua sulla vicenda &#8216;infuocata&#8217; della Moschea \u00e8 il consigliere comunale di Frosinone, Danilo Magliocchetti, che invita tutti a<\/p>\n","protected":false},"author":18,"featured_media":11211,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[4,2236],"tags":[5363,94,858,93,3952,7332],"class_list":["post-22927","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-primo-piano","category-attualita","tag-autorizzazioni","tag-ciociaria","tag-danilo-magliocchetti","tag-frosinone","tag-moschea","tag-pratica-urbanistica"],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v27.8 (Yoast SEO v27.8) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Moschea, Magliocchetti: usare equilibrio e buon senso - IlCorriereDellaProvincia.it - News h24 e notizie di approfondimento<\/title>\n<meta name=\"description\" content=\"Sulla Moschea il consigliere comunale Danilo Magliocchetti invita a usare senso di responsabilit\u00e0, equilibrio e buon senso e a non fare allarmismi\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2019\/11\/22\/magliocchetti-sulla-moschea-servono-equilibrio-e-buon-senso\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Moschea, Magliocchetti: usare equilibrio e buon senso\" \/>\n<meta property=\"og:description\" content=\"Sulla Moschea il consigliere comunale Danilo Magliocchetti invita a usare senso di responsabilit\u00e0, equilibrio e buon senso e a non fare allarmismi\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2019\/11\/22\/magliocchetti-sulla-moschea-servono-equilibrio-e-buon-senso\/\" \/>\n<meta property=\"og:site_name\" content=\"IlCorriereDellaProvincia.it - News h24 e notizie di approfondimento\" \/>\n<meta property=\"article:author\" content=\"www.facebook.com\/tunews24\" \/>\n<meta property=\"article:published_time\" content=\"2019-11-22T12:11:32+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2019-11-23T15:33:58+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2019\/05\/danilo-magliocchetti-frosinone-e1557501019998.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"632\" \/>\n\t<meta property=\"og:image:height\" content=\"426\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Redazione\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"Redazione\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2019\\\/11\\\/22\\\/magliocchetti-sulla-moschea-servono-equilibrio-e-buon-senso\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2019\\\/11\\\/22\\\/magliocchetti-sulla-moschea-servono-equilibrio-e-buon-senso\\\/\"},\"author\":{\"name\":\"Redazione\",\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/#\\\/schema\\\/person\\\/6d7f0a9120d0c03d0c552e9fdf49ed7d\"},\"headline\":\"Moschea, Magliocchetti: usare equilibrio e buon senso\",\"datePublished\":\"2019-11-22T12:11:32+00:00\",\"dateModified\":\"2019-11-23T15:33:58+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2019\\\/11\\\/22\\\/magliocchetti-sulla-moschea-servono-equilibrio-e-buon-senso\\\/\"},\"wordCount\":247,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2019\\\/11\\\/22\\\/magliocchetti-sulla-moschea-servono-equilibrio-e-buon-senso\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2019\\\/05\\\/danilo-magliocchetti-frosinone-e1557501019998.jpg\",\"keywords\":[\"autorizzazioni\",\"Ciociaria\",\"danilo magliocchetti\",\"Frosinone\",\"Moschea\",\"pratica urbanistica\"],\"articleSection\":[\"*PRIMO PIANO*\",\"Attualit\u00e0\"],\"inLanguage\":\"it-IT\",\"copyrightYear\":\"2019\",\"copyrightHolder\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/#organization\"}},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2019\\\/11\\\/22\\\/magliocchetti-sulla-moschea-servono-equilibrio-e-buon-senso\\\/\",\"url\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2019\\\/11\\\/22\\\/magliocchetti-sulla-moschea-servono-equilibrio-e-buon-senso\\\/\",\"name\":\"Moschea, Magliocchetti: usare equilibrio e buon senso - IlCorriereDellaProvincia.it - News h24 e notizie di approfondimento\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2019\\\/11\\\/22\\\/magliocchetti-sulla-moschea-servono-equilibrio-e-buon-senso\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2019\\\/11\\\/22\\\/magliocchetti-sulla-moschea-servono-equilibrio-e-buon-senso\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2019\\\/05\\\/danilo-magliocchetti-frosinone-e1557501019998.jpg\",\"datePublished\":\"2019-11-22T12:11:32+00:00\",\"dateModified\":\"2019-11-23T15:33:58+00:00\",\"description\":\"Sulla Moschea il consigliere comunale Danilo Magliocchetti invita a usare senso di responsabilit\u00e0, equilibrio e buon senso e a non fare allarmismi\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2019\\\/11\\\/22\\\/magliocchetti-sulla-moschea-servono-equilibrio-e-buon-senso\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2019\\\/11\\\/22\\\/magliocchetti-sulla-moschea-servono-equilibrio-e-buon-senso\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2019\\\/11\\\/22\\\/magliocchetti-sulla-moschea-servono-equilibrio-e-buon-senso\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2019\\\/05\\\/danilo-magliocchetti-frosinone-e1557501019998.jpg\",\"contentUrl\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2019\\\/05\\\/danilo-magliocchetti-frosinone-e1557501019998.jpg\",\"width\":632,\"height\":426,\"caption\":\"Il capogruppo di FI al consiglio comunale di Frosinone Danilo Magliocchetti\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2019\\\/11\\\/22\\\/magliocchetti-sulla-moschea-servono-equilibrio-e-buon-senso\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Moschea, Magliocchetti: usare equilibrio e buon senso\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/#website\",\"url\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/\",\"name\":\"Il Corriere Delle Provincia\",\"description\":\"IlCorriereDellaProvincia.it, quotidiano web di politica, cronaca, inchiesta, lavoro, scuola, turismo, cultura e spettacolo, economia e finanza, salute e benessere. Approfondimenti e notizie aggiornate con foto e video della provincia di Frosinone ma anche news nazionali, dell\u2019Italia e del Mondo.\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":[\"Organization\",\"Place\"],\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/#organization\",\"name\":\"Globalpress s.r.l.\",\"url\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/\",\"logo\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2019\\\/11\\\/22\\\/magliocchetti-sulla-moschea-servono-equilibrio-e-buon-senso\\\/#local-main-organization-logo\"},\"image\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2019\\\/11\\\/22\\\/magliocchetti-sulla-moschea-servono-equilibrio-e-buon-senso\\\/#local-main-organization-logo\"},\"telephone\":[],\"openingHoursSpecification\":[{\"@type\":\"OpeningHoursSpecification\",\"dayOfWeek\":[\"Monday\",\"Tuesday\",\"Wednesday\",\"Thursday\",\"Friday\",\"Saturday\",\"Sunday\"],\"opens\":\"09:00\",\"closes\":\"17:00\"}]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/#\\\/schema\\\/person\\\/6d7f0a9120d0c03d0c552e9fdf49ed7d\",\"name\":\"Redazione\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/a40eeacccdcad861f831dde73317f63a542e738f0dc4b79b9f47062d3d4bd1d2?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/a40eeacccdcad861f831dde73317f63a542e738f0dc4b79b9f47062d3d4bd1d2?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/a40eeacccdcad861f831dde73317f63a542e738f0dc4b79b9f47062d3d4bd1d2?s=96&d=mm&r=g\",\"caption\":\"Redazione\"},\"description\":\"SEGUICI ANCHE SUI SOCIAL Facebook: TuNews24 e TuSport24 Instagram: TuNews24 e TuSport24 Youtube: TuNews24 Telegram: TuNews24 Puoi leggerci anche in formato cartaceo: il settimanale viene pubblicato e distribuito gratuitamente ogni venerd\u00ec in edicole, bar, centri commerciali e svariati esercizi. Ma \u00e8 possibile anche sfogliarlo comodamente online, cliccando su TU NEWS sfogliabile TU NEWS, PASSIONE PER L\u2019INFORMAZIONE\",\"sameAs\":[\"http:\\\/\\\/www.tunews24.it\",\"www.facebook.com\\\/tunews24\"],\"url\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/author\\\/senzafirma\\\/\"},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2019\\\/11\\\/22\\\/magliocchetti-sulla-moschea-servono-equilibrio-e-buon-senso\\\/#local-main-organization-logo\",\"url\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2022\\\/11\\\/cropped-il-corriere-della-provincia-testata-web-scontornata.png\",\"contentUrl\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2022\\\/11\\\/cropped-il-corriere-della-provincia-testata-web-scontornata.png\",\"width\":2911,\"height\":717,\"caption\":\"Globalpress s.r.l.\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Moschea, Magliocchetti: usare equilibrio e buon senso - IlCorriereDellaProvincia.it - News h24 e notizie di approfondimento","description":"Sulla Moschea il consigliere comunale Danilo Magliocchetti invita a usare senso di responsabilit\u00e0, equilibrio e buon senso e a non fare allarmismi","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2019\/11\/22\/magliocchetti-sulla-moschea-servono-equilibrio-e-buon-senso\/","og_locale":"it_IT","og_type":"article","og_title":"Moschea, Magliocchetti: usare equilibrio e buon senso","og_description":"Sulla Moschea il consigliere comunale Danilo Magliocchetti invita a usare senso di responsabilit\u00e0, equilibrio e buon senso e a non fare allarmismi","og_url":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2019\/11\/22\/magliocchetti-sulla-moschea-servono-equilibrio-e-buon-senso\/","og_site_name":"IlCorriereDellaProvincia.it - News h24 e notizie di approfondimento","article_author":"www.facebook.com\/tunews24","article_published_time":"2019-11-22T12:11:32+00:00","article_modified_time":"2019-11-23T15:33:58+00:00","og_image":[{"width":632,"height":426,"url":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2019\/05\/danilo-magliocchetti-frosinone-e1557501019998.jpg","type":"image\/jpeg"}],"author":"Redazione","twitter_card":"summary_large_image","twitter_misc":{"Scritto da":"Redazione","Tempo di lettura stimato":"1 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2019\/11\/22\/magliocchetti-sulla-moschea-servono-equilibrio-e-buon-senso\/#article","isPartOf":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2019\/11\/22\/magliocchetti-sulla-moschea-servono-equilibrio-e-buon-senso\/"},"author":{"name":"Redazione","@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/#\/schema\/person\/6d7f0a9120d0c03d0c552e9fdf49ed7d"},"headline":"Moschea, Magliocchetti: usare equilibrio e buon senso","datePublished":"2019-11-22T12:11:32+00:00","dateModified":"2019-11-23T15:33:58+00:00","mainEntityOfPage":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2019\/11\/22\/magliocchetti-sulla-moschea-servono-equilibrio-e-buon-senso\/"},"wordCount":247,"commentCount":0,"publisher":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/#organization"},"image":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2019\/11\/22\/magliocchetti-sulla-moschea-servono-equilibrio-e-buon-senso\/#primaryimage"},"thumbnailUrl":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2019\/05\/danilo-magliocchetti-frosinone-e1557501019998.jpg","keywords":["autorizzazioni","Ciociaria","danilo magliocchetti","Frosinone","Moschea","pratica urbanistica"],"articleSection":["*PRIMO PIANO*","Attualit\u00e0"],"inLanguage":"it-IT","copyrightYear":"2019","copyrightHolder":{"@id":"https:\/\/www.tunews24.it\/#organization"}},{"@type":"WebPage","@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2019\/11\/22\/magliocchetti-sulla-moschea-servono-equilibrio-e-buon-senso\/","url":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2019\/11\/22\/magliocchetti-sulla-moschea-servono-equilibrio-e-buon-senso\/","name":"Moschea, Magliocchetti: usare equilibrio e buon senso - IlCorriereDellaProvincia.it - News h24 e notizie di approfondimento","isPartOf":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2019\/11\/22\/magliocchetti-sulla-moschea-servono-equilibrio-e-buon-senso\/#primaryimage"},"image":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2019\/11\/22\/magliocchetti-sulla-moschea-servono-equilibrio-e-buon-senso\/#primaryimage"},"thumbnailUrl":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2019\/05\/danilo-magliocchetti-frosinone-e1557501019998.jpg","datePublished":"2019-11-22T12:11:32+00:00","dateModified":"2019-11-23T15:33:58+00:00","description":"Sulla Moschea il consigliere comunale Danilo Magliocchetti invita a usare senso di responsabilit\u00e0, equilibrio e buon senso e a non fare allarmismi","breadcrumb":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2019\/11\/22\/magliocchetti-sulla-moschea-servono-equilibrio-e-buon-senso\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2019\/11\/22\/magliocchetti-sulla-moschea-servono-equilibrio-e-buon-senso\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2019\/11\/22\/magliocchetti-sulla-moschea-servono-equilibrio-e-buon-senso\/#primaryimage","url":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2019\/05\/danilo-magliocchetti-frosinone-e1557501019998.jpg","contentUrl":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2019\/05\/danilo-magliocchetti-frosinone-e1557501019998.jpg","width":632,"height":426,"caption":"Il capogruppo di FI al consiglio comunale di Frosinone Danilo Magliocchetti"},{"@type":"BreadcrumbList","@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2019\/11\/22\/magliocchetti-sulla-moschea-servono-equilibrio-e-buon-senso\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/"},{"@type":"ListItem","position":2,"name":"Moschea, Magliocchetti: usare equilibrio e buon senso"}]},{"@type":"WebSite","@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/#website","url":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/","name":"Il Corriere Delle Provincia","description":"IlCorriereDellaProvincia.it, quotidiano web di politica, cronaca, inchiesta, lavoro, scuola, turismo, cultura e spettacolo, economia e finanza, salute e benessere. Approfondimenti e notizie aggiornate con foto e video della provincia di Frosinone ma anche news nazionali, dell\u2019Italia e del Mondo.","publisher":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":["Organization","Place"],"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/#organization","name":"Globalpress s.r.l.","url":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/","logo":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2019\/11\/22\/magliocchetti-sulla-moschea-servono-equilibrio-e-buon-senso\/#local-main-organization-logo"},"image":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2019\/11\/22\/magliocchetti-sulla-moschea-servono-equilibrio-e-buon-senso\/#local-main-organization-logo"},"telephone":[],"openingHoursSpecification":[{"@type":"OpeningHoursSpecification","dayOfWeek":["Monday","Tuesday","Wednesday","Thursday","Friday","Saturday","Sunday"],"opens":"09:00","closes":"17:00"}]},{"@type":"Person","@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/#\/schema\/person\/6d7f0a9120d0c03d0c552e9fdf49ed7d","name":"Redazione","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/secure.gravatar.com\/avatar\/a40eeacccdcad861f831dde73317f63a542e738f0dc4b79b9f47062d3d4bd1d2?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/a40eeacccdcad861f831dde73317f63a542e738f0dc4b79b9f47062d3d4bd1d2?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/a40eeacccdcad861f831dde73317f63a542e738f0dc4b79b9f47062d3d4bd1d2?s=96&d=mm&r=g","caption":"Redazione"},"description":"SEGUICI ANCHE SUI SOCIAL Facebook: TuNews24 e TuSport24 Instagram: TuNews24 e TuSport24 Youtube: TuNews24 Telegram: TuNews24 Puoi leggerci anche in formato cartaceo: il settimanale viene pubblicato e distribuito gratuitamente ogni venerd\u00ec in edicole, bar, centri commerciali e svariati esercizi. Ma \u00e8 possibile anche sfogliarlo comodamente online, cliccando su TU NEWS sfogliabile TU NEWS, PASSIONE PER L\u2019INFORMAZIONE","sameAs":["http:\/\/www.tunews24.it","www.facebook.com\/tunews24"],"url":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/author\/senzafirma\/"},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2019\/11\/22\/magliocchetti-sulla-moschea-servono-equilibrio-e-buon-senso\/#local-main-organization-logo","url":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2022\/11\/cropped-il-corriere-della-provincia-testata-web-scontornata.png","contentUrl":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2022\/11\/cropped-il-corriere-della-provincia-testata-web-scontornata.png","width":2911,"height":717,"caption":"Globalpress s.r.l."}]}},"_links":{"self":[{"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/posts\/22927","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/users\/18"}],"replies":[{"embeddable":true,"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/comments?post=22927"}],"version-history":[{"count":2,"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/posts\/22927\/revisions"}],"predecessor-version":[{"id":22929,"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/posts\/22927\/revisions\/22929"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/media\/11211"}],"wp:attachment":[{"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/media?parent=22927"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/categories?post=22927"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/tags?post=22927"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}