{"id":22699,"date":"2019-11-19T17:09:44","date_gmt":"2019-11-19T16:09:44","guid":{"rendered":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/?p=22699"},"modified":"2019-11-20T17:25:55","modified_gmt":"2019-11-20T16:25:55","slug":"quello-del-pd-non-sara-un-congresso-farsa-la-replica-della-battisti","status":"publish","type":"post","link":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2019\/11\/19\/quello-del-pd-non-sara-un-congresso-farsa-la-replica-della-battisti\/","title":{"rendered":"&#8220;Quello del Pd non sar\u00e0 un congresso farsa&#8221;. La replica della Battisti"},"content":{"rendered":"<div id=\":w5\" class=\"a3s aXjCH \">\n<div>\n<div id=\"m_7240216394562269916mail-app-auto-signature\"><strong>Sara Battisti \u00e8 una che ha coraggio da vendere,<\/strong> e nelle battaglie che porta avanti ci mette sempre la faccia. Ed \u00e8 per questo che <strong>pubblico interamente<\/strong>, a differenza di quanto farebbero altri, una sua riflessione in risposta al mio articolo che descrive il dualismo che c&#8217;\u00e8 tra Francesco De Angelis e Antonio Pompeo nella gestione del Pd.<\/div>\n<div><\/div>\n<div>E anche se il consigliere regionale mi accusa di aver dato una visione distorta del partito, non faccio davvero nessuna fatica, in virt\u00f9 di quello che dovrebbe essere il plurialismo dell&#8217;informazione (che in questa provincia in pochi portano avanti) a concedere tutto lo spazio che chiede. Oggi e sempre&#8230; Ma non solo a lei. A chiunque.<\/div>\n<div><\/div>\n<div><strong>Peccato, per\u00f2, vista la grande stima che io personalmente nutro per Sara Battisti<\/strong>, che la stessa nota non l&#8217;abbia inviata anche a coloro che ogni giorno alimentano lo scontro tra i due esponenti del Pd.\u00a0 A chi li fa apparire, cos\u00ec come ho fatto io, gli unici padroni di un partito che, come sostiene il consigliere regionale, \u00e8 davvero molto di pi\u00f9 del<strong> &#8216;resti, non resti, me ne vado, te ne vai&#8217;.\u00a0 Quello che serve ai Dem, me lo conceda consigliere, \u00e8 una stagione nuova e un segretario che faccia il segretario, <\/strong>cos\u00ec come \u00e8 sempre avvenuto a livello nazionale, nella migliore <strong>tradizione storica dei partiti di sinistra<\/strong><\/div>\n<div><\/div>\n<\/div>\n<div><\/div>\n<div>\n<div><strong><img loading=\"lazy\" decoding=\"async\" class=\"wp-image-5074 aligncenter\" src=\"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2019\/01\/sara-battisti.jpg\" alt=\"sara battisti il corriere della provincia regione lazio frosinone ciociaria\" width=\"632\" height=\"359\" srcset=\"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2019\/01\/sara-battisti.jpg 860w, https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2019\/01\/sara-battisti-300x170.jpg 300w, https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2019\/01\/sara-battisti-768x436.jpg 768w, https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2019\/01\/sara-battisti-500x284.jpg 500w\" sizes=\"auto, (max-width: 632px) 100vw, 632px\" \/><\/strong><\/div>\n<div>\n<h2><\/h2>\n<h2>L&#8217;intervento<\/h2>\n<p dir=\"ltr\">&#8220;Ho avuto modo di leggere il suo breve articolo che descrive l\u2019attuale situazione del PD in Provincia di Frosinone e delle presunte modalit\u00e0 di azione di alcuni suoi esponenti . Premetto che non sono solita interloquire con un giornalista a seguito di una sua riflessione ma mi corre d\u2019obbligo, data l\u2019immagine distorta che viene restituita del mio partito dal suo articolo. <strong>Ho grande stima di Francesco De Angelis e di Antonio Pompeo. Conosco entrambi da tempo e riconosco ad entrambi le funzioni che svolgono sia all\u2019interno del PD<\/strong>, sia a alla guida di enti importanti per il territorio. Il PD per\u00f2 \u00e8 tanto altro. Ci sono i nostri amministratori locali, i nostri dirigenti, la rete di iscritti e simpatizzanti, i Giovani Democratici.<\/p>\n<p>&nbsp;<\/p>\n<h2>L&#8217;analisi<\/h2>\n<p dir=\"ltr\"><strong>A De Angelis va dato sicuramente atto che negli ultimi anni si \u00e8 fatto garante di un equilibrio<\/strong> che ha portato ad una fase di condivisione, ha avuto la lungimiranza di far crescere nuova classe dirigente e di metterla a disposizione delle Istituzioni. Questo vale per la sottoscritta, per il Presidente del Consiglio Regionale, Mauro Buschini, per il Presidente della Provincia, Antonio Pompeo.<\/p>\n<p>&nbsp;<\/p>\n<h2>&#8220;Sceglieremo liberi da vincoli&#8221;<\/h2>\n<p dir=\"ltr\">&#8220;Quello che pi\u00f9 mi lascia pensare della sua riflessione, per\u00f2, \u00e8 l\u2019idea che un partito politico come il PD, erede delle tradizioni dei grandi partiti di massa in Italia, possa mai immaginare di celebrare un &#8216;congresso farsa&#8217;. <strong>Forse questo stile pu\u00f2 appartenere alla destra, ai partiti leaderistici, a quelli che si autodeterminano attraverso piattaforme online non si sa bene gestite da chi e come, non vale certo per noi.\u00a0<\/strong><\/p>\n<p dir=\"ltr\"><strong>Celebreremo un Congresso,<\/strong> chiamando i nostri iscritti a scegliere il nuovo gruppo dirigente sulla base delle proposte politiche che verranno presentate, lo faremo come gi\u00e0 detto da De Angelis,<strong> liberi da vincoli, caminetti, tavoli<\/strong>. E questa linea non \u00e8 di certo casuale.\u00a0 \u00c8 valutata sulla base di errori commessi in passato figli delle storture del PD, per costruire il nuovo partito cos\u00ec come ha annunciato Zingaretti a Bologna. Lo faremo il congresso dando la possibilit\u00e0, soprattutto alle nuove generazioni, di impegnarsi per costruire una comunit\u00e0 politica che risponda alle esigenze dei pi\u00f9 deboli, chiedendo a loro di mettere a disposizione tempo, impegno e soprattutto passione, come abbiamo visto fare dai giovani bolognesi che hanno dato il via al movimento delle &#8216;sardine'&#8221;.<\/p>\n<p>&nbsp;<\/p>\n<h2>Sguardo al futuro<\/h2>\n<p dir=\"ltr\">&#8220;<strong>Lo faremo soprattutto per immaginare un nuovo sviluppo territoriale anche a seguito della classifica annuale di ItaliaOggi e Universit\u00e0 La Sapienza, che vede la Provincia di Frosinone tra le ultime posizioni. Per investire su industria 4.0, per garantire servizi essenziali ai cittadini,<\/strong> per lavorare su nuovo asset di sviluppo come quello legato al Turismo, a tutela dell\u2019ambiente, per la giustizia sociale.\u00a0 Per questo un congresso non pu\u00f2 e non sar\u00e0 mai una farsa per noi, ma sempre una grande opportunit\u00e0 di svolta&#8221;.<\/p>\n<p dir=\"ltr\">\n<\/div>\n<p dir=\"ltr\"><strong>LEGGI ANCHE: <a href=\"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2019\/11\/19\/de-angelis-pompeo-e-linutile-congresso-del-pd\/\">De Angelis, Pompeo e l\u2019inutile congresso del Pd<\/a><\/strong><\/p>\n<\/div>\n<\/div>\n","protected":false},"excerpt":{"rendered":"<p>Sara Battisti \u00e8 una che ha coraggio da vendere, e nelle battaglie che porta avanti ci mette sempre la faccia.<\/p>\n","protected":false},"author":3,"featured_media":13241,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[28],"tags":[842,507,969,98,1721,97],"class_list":["post-22699","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-politica","tag-antonio-pompeo","tag-congresso","tag-francesco-de-angelis","tag-pd","tag-sara-battisti","tag-segreteria"],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v27.8 (Yoast SEO v27.8) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>&quot;Quello del Pd non sar\u00e0 un congresso farsa&quot;. La replica della Battisti - IlCorriereDellaProvincia.it - News h24 e notizie di approfondimento<\/title>\n<meta name=\"description\" content=\"Il consigliere regionale del Partito Democratico intereviene in merito al nostro articolo sul dualismo tra Pomeo e De Angelis\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2019\/11\/19\/quello-del-pd-non-sara-un-congresso-farsa-la-replica-della-battisti\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"&quot;Quello del Pd non sar\u00e0 un congresso farsa&quot;. La replica della Battisti\" \/>\n<meta property=\"og:description\" content=\"Il consigliere regionale del Partito Democratico intereviene in merito al nostro articolo sul dualismo tra Pomeo e De Angelis\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2019\/11\/19\/quello-del-pd-non-sara-un-congresso-farsa-la-replica-della-battisti\/\" \/>\n<meta property=\"og:site_name\" content=\"IlCorriereDellaProvincia.it - News h24 e notizie di approfondimento\" \/>\n<meta property=\"article:author\" content=\"http:\/\/www.facebook.com\/TuNews24\" \/>\n<meta property=\"article:published_time\" content=\"2019-11-19T16:09:44+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2019-11-20T16:25:55+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2019\/06\/conferenza-stampa-Pd-e1560859598231.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"632\" \/>\n\t<meta property=\"og:image:height\" content=\"337\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Gianluca Trento\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"Gianluca Trento\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"3 minuti\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2019\\\/11\\\/19\\\/quello-del-pd-non-sara-un-congresso-farsa-la-replica-della-battisti\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2019\\\/11\\\/19\\\/quello-del-pd-non-sara-un-congresso-farsa-la-replica-della-battisti\\\/\"},\"author\":{\"name\":\"Gianluca Trento\",\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/#\\\/schema\\\/person\\\/61ad8468fc64fa3e36d950057c9c2cbd\"},\"headline\":\"&#8220;Quello del Pd non sar\u00e0 un congresso farsa&#8221;. La replica della Battisti\",\"datePublished\":\"2019-11-19T16:09:44+00:00\",\"dateModified\":\"2019-11-20T16:25:55+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2019\\\/11\\\/19\\\/quello-del-pd-non-sara-un-congresso-farsa-la-replica-della-battisti\\\/\"},\"wordCount\":712,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2019\\\/11\\\/19\\\/quello-del-pd-non-sara-un-congresso-farsa-la-replica-della-battisti\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2019\\\/06\\\/conferenza-stampa-Pd-e1560859598231.jpg\",\"keywords\":[\"antonio pompeo\",\"congresso\",\"francesco de angelis\",\"Pd\",\"Sara Battisti\",\"Segreteria\"],\"articleSection\":[\"Evidenza\"],\"inLanguage\":\"it-IT\",\"copyrightYear\":\"2019\",\"copyrightHolder\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/#organization\"}},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2019\\\/11\\\/19\\\/quello-del-pd-non-sara-un-congresso-farsa-la-replica-della-battisti\\\/\",\"url\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2019\\\/11\\\/19\\\/quello-del-pd-non-sara-un-congresso-farsa-la-replica-della-battisti\\\/\",\"name\":\"\\\"Quello del Pd non sar\u00e0 un congresso farsa\\\". La replica della Battisti - IlCorriereDellaProvincia.it - News h24 e notizie di approfondimento\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2019\\\/11\\\/19\\\/quello-del-pd-non-sara-un-congresso-farsa-la-replica-della-battisti\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2019\\\/11\\\/19\\\/quello-del-pd-non-sara-un-congresso-farsa-la-replica-della-battisti\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2019\\\/06\\\/conferenza-stampa-Pd-e1560859598231.jpg\",\"datePublished\":\"2019-11-19T16:09:44+00:00\",\"dateModified\":\"2019-11-20T16:25:55+00:00\",\"description\":\"Il consigliere regionale del Partito Democratico intereviene in merito al nostro articolo sul dualismo tra Pomeo e De Angelis\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2019\\\/11\\\/19\\\/quello-del-pd-non-sara-un-congresso-farsa-la-replica-della-battisti\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2019\\\/11\\\/19\\\/quello-del-pd-non-sara-un-congresso-farsa-la-replica-della-battisti\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2019\\\/11\\\/19\\\/quello-del-pd-non-sara-un-congresso-farsa-la-replica-della-battisti\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2019\\\/06\\\/conferenza-stampa-Pd-e1560859598231.jpg\",\"contentUrl\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2019\\\/06\\\/conferenza-stampa-Pd-e1560859598231.jpg\",\"width\":632,\"height\":337,\"caption\":\"Un momento della conferenza stampa di questa mattina alla Federazione provinciale del Pd\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2019\\\/11\\\/19\\\/quello-del-pd-non-sara-un-congresso-farsa-la-replica-della-battisti\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"&#8220;Quello del Pd non sar\u00e0 un congresso farsa&#8221;. La replica della Battisti\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/#website\",\"url\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/\",\"name\":\"Il Corriere Delle Provincia\",\"description\":\"IlCorriereDellaProvincia.it, quotidiano web di politica, cronaca, inchiesta, lavoro, scuola, turismo, cultura e spettacolo, economia e finanza, salute e benessere. Approfondimenti e notizie aggiornate con foto e video della provincia di Frosinone ma anche news nazionali, dell\u2019Italia e del Mondo.\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":[\"Organization\",\"Place\"],\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/#organization\",\"name\":\"Globalpress s.r.l.\",\"url\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/\",\"logo\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2019\\\/11\\\/19\\\/quello-del-pd-non-sara-un-congresso-farsa-la-replica-della-battisti\\\/#local-main-organization-logo\"},\"image\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2019\\\/11\\\/19\\\/quello-del-pd-non-sara-un-congresso-farsa-la-replica-della-battisti\\\/#local-main-organization-logo\"},\"telephone\":[],\"openingHoursSpecification\":[{\"@type\":\"OpeningHoursSpecification\",\"dayOfWeek\":[\"Monday\",\"Tuesday\",\"Wednesday\",\"Thursday\",\"Friday\",\"Saturday\",\"Sunday\"],\"opens\":\"09:00\",\"closes\":\"17:00\"}]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/#\\\/schema\\\/person\\\/61ad8468fc64fa3e36d950057c9c2cbd\",\"name\":\"Gianluca Trento\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/8c3ab5f4c6ed6f32f95ece33488c4ec55733fd2c584ad602d0b29746892705ab?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/8c3ab5f4c6ed6f32f95ece33488c4ec55733fd2c584ad602d0b29746892705ab?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/8c3ab5f4c6ed6f32f95ece33488c4ec55733fd2c584ad602d0b29746892705ab?s=96&d=mm&r=g\",\"caption\":\"Gianluca Trento\"},\"description\":\"Giornalista dei quotidiani online \\\"LaProvinciaQuotidiano.it\\\" e \\\"TuNews24.it\\\" e del settimanale cartaceo \\\"Tu News\\\". In passato \u00e8 stato anche Direttore Editoriale de \\\"La Provincia\\\", Direttore Responsabile del quotidiano \\\"Ciociaria Oggi\\\", Condirettore de \\\"Il quotidiano della Ciociaria\\\", giornalista di \\\"Paese Sera\\\", del settimanale \\\"L\u2019Inchiesta\\\" e del quotidiano online \\\"Il Corriere della Provincia\\\".\",\"sameAs\":[\"https:\\\/\\\/www.tunews24.it\",\"http:\\\/\\\/www.facebook.com\\\/TuNews24\"],\"url\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/author\\\/gianluca\\\/\"},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2019\\\/11\\\/19\\\/quello-del-pd-non-sara-un-congresso-farsa-la-replica-della-battisti\\\/#local-main-organization-logo\",\"url\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2022\\\/11\\\/cropped-il-corriere-della-provincia-testata-web-scontornata.png\",\"contentUrl\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2022\\\/11\\\/cropped-il-corriere-della-provincia-testata-web-scontornata.png\",\"width\":2911,\"height\":717,\"caption\":\"Globalpress s.r.l.\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"\"Quello del Pd non sar\u00e0 un congresso farsa\". La replica della Battisti - IlCorriereDellaProvincia.it - News h24 e notizie di approfondimento","description":"Il consigliere regionale del Partito Democratico intereviene in merito al nostro articolo sul dualismo tra Pomeo e De Angelis","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2019\/11\/19\/quello-del-pd-non-sara-un-congresso-farsa-la-replica-della-battisti\/","og_locale":"it_IT","og_type":"article","og_title":"\"Quello del Pd non sar\u00e0 un congresso farsa\". La replica della Battisti","og_description":"Il consigliere regionale del Partito Democratico intereviene in merito al nostro articolo sul dualismo tra Pomeo e De Angelis","og_url":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2019\/11\/19\/quello-del-pd-non-sara-un-congresso-farsa-la-replica-della-battisti\/","og_site_name":"IlCorriereDellaProvincia.it - News h24 e notizie di approfondimento","article_author":"http:\/\/www.facebook.com\/TuNews24","article_published_time":"2019-11-19T16:09:44+00:00","article_modified_time":"2019-11-20T16:25:55+00:00","og_image":[{"width":632,"height":337,"url":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2019\/06\/conferenza-stampa-Pd-e1560859598231.jpg","type":"image\/jpeg"}],"author":"Gianluca Trento","twitter_card":"summary_large_image","twitter_misc":{"Scritto da":"Gianluca Trento","Tempo di lettura stimato":"3 minuti"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2019\/11\/19\/quello-del-pd-non-sara-un-congresso-farsa-la-replica-della-battisti\/#article","isPartOf":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2019\/11\/19\/quello-del-pd-non-sara-un-congresso-farsa-la-replica-della-battisti\/"},"author":{"name":"Gianluca Trento","@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/#\/schema\/person\/61ad8468fc64fa3e36d950057c9c2cbd"},"headline":"&#8220;Quello del Pd non sar\u00e0 un congresso farsa&#8221;. La replica della Battisti","datePublished":"2019-11-19T16:09:44+00:00","dateModified":"2019-11-20T16:25:55+00:00","mainEntityOfPage":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2019\/11\/19\/quello-del-pd-non-sara-un-congresso-farsa-la-replica-della-battisti\/"},"wordCount":712,"commentCount":0,"publisher":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/#organization"},"image":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2019\/11\/19\/quello-del-pd-non-sara-un-congresso-farsa-la-replica-della-battisti\/#primaryimage"},"thumbnailUrl":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2019\/06\/conferenza-stampa-Pd-e1560859598231.jpg","keywords":["antonio pompeo","congresso","francesco de angelis","Pd","Sara Battisti","Segreteria"],"articleSection":["Evidenza"],"inLanguage":"it-IT","copyrightYear":"2019","copyrightHolder":{"@id":"https:\/\/www.tunews24.it\/#organization"}},{"@type":"WebPage","@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2019\/11\/19\/quello-del-pd-non-sara-un-congresso-farsa-la-replica-della-battisti\/","url":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2019\/11\/19\/quello-del-pd-non-sara-un-congresso-farsa-la-replica-della-battisti\/","name":"\"Quello del Pd non sar\u00e0 un congresso farsa\". La replica della Battisti - IlCorriereDellaProvincia.it - News h24 e notizie di approfondimento","isPartOf":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2019\/11\/19\/quello-del-pd-non-sara-un-congresso-farsa-la-replica-della-battisti\/#primaryimage"},"image":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2019\/11\/19\/quello-del-pd-non-sara-un-congresso-farsa-la-replica-della-battisti\/#primaryimage"},"thumbnailUrl":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2019\/06\/conferenza-stampa-Pd-e1560859598231.jpg","datePublished":"2019-11-19T16:09:44+00:00","dateModified":"2019-11-20T16:25:55+00:00","description":"Il consigliere regionale del Partito Democratico intereviene in merito al nostro articolo sul dualismo tra Pomeo e De Angelis","breadcrumb":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2019\/11\/19\/quello-del-pd-non-sara-un-congresso-farsa-la-replica-della-battisti\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2019\/11\/19\/quello-del-pd-non-sara-un-congresso-farsa-la-replica-della-battisti\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2019\/11\/19\/quello-del-pd-non-sara-un-congresso-farsa-la-replica-della-battisti\/#primaryimage","url":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2019\/06\/conferenza-stampa-Pd-e1560859598231.jpg","contentUrl":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2019\/06\/conferenza-stampa-Pd-e1560859598231.jpg","width":632,"height":337,"caption":"Un momento della conferenza stampa di questa mattina alla Federazione provinciale del Pd"},{"@type":"BreadcrumbList","@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2019\/11\/19\/quello-del-pd-non-sara-un-congresso-farsa-la-replica-della-battisti\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/"},{"@type":"ListItem","position":2,"name":"&#8220;Quello del Pd non sar\u00e0 un congresso farsa&#8221;. La replica della Battisti"}]},{"@type":"WebSite","@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/#website","url":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/","name":"Il Corriere Delle Provincia","description":"IlCorriereDellaProvincia.it, quotidiano web di politica, cronaca, inchiesta, lavoro, scuola, turismo, cultura e spettacolo, economia e finanza, salute e benessere. Approfondimenti e notizie aggiornate con foto e video della provincia di Frosinone ma anche news nazionali, dell\u2019Italia e del Mondo.","publisher":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":["Organization","Place"],"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/#organization","name":"Globalpress s.r.l.","url":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/","logo":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2019\/11\/19\/quello-del-pd-non-sara-un-congresso-farsa-la-replica-della-battisti\/#local-main-organization-logo"},"image":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2019\/11\/19\/quello-del-pd-non-sara-un-congresso-farsa-la-replica-della-battisti\/#local-main-organization-logo"},"telephone":[],"openingHoursSpecification":[{"@type":"OpeningHoursSpecification","dayOfWeek":["Monday","Tuesday","Wednesday","Thursday","Friday","Saturday","Sunday"],"opens":"09:00","closes":"17:00"}]},{"@type":"Person","@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/#\/schema\/person\/61ad8468fc64fa3e36d950057c9c2cbd","name":"Gianluca Trento","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/secure.gravatar.com\/avatar\/8c3ab5f4c6ed6f32f95ece33488c4ec55733fd2c584ad602d0b29746892705ab?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/8c3ab5f4c6ed6f32f95ece33488c4ec55733fd2c584ad602d0b29746892705ab?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/8c3ab5f4c6ed6f32f95ece33488c4ec55733fd2c584ad602d0b29746892705ab?s=96&d=mm&r=g","caption":"Gianluca Trento"},"description":"Giornalista dei quotidiani online \"LaProvinciaQuotidiano.it\" e \"TuNews24.it\" e del settimanale cartaceo \"Tu News\". In passato \u00e8 stato anche Direttore Editoriale de \"La Provincia\", Direttore Responsabile del quotidiano \"Ciociaria Oggi\", Condirettore de \"Il quotidiano della Ciociaria\", giornalista di \"Paese Sera\", del settimanale \"L\u2019Inchiesta\" e del quotidiano online \"Il Corriere della Provincia\".","sameAs":["https:\/\/www.tunews24.it","http:\/\/www.facebook.com\/TuNews24"],"url":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/author\/gianluca\/"},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2019\/11\/19\/quello-del-pd-non-sara-un-congresso-farsa-la-replica-della-battisti\/#local-main-organization-logo","url":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2022\/11\/cropped-il-corriere-della-provincia-testata-web-scontornata.png","contentUrl":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2022\/11\/cropped-il-corriere-della-provincia-testata-web-scontornata.png","width":2911,"height":717,"caption":"Globalpress s.r.l."}]}},"_links":{"self":[{"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/posts\/22699","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/comments?post=22699"}],"version-history":[{"count":10,"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/posts\/22699\/revisions"}],"predecessor-version":[{"id":22713,"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/posts\/22699\/revisions\/22713"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/media\/13241"}],"wp:attachment":[{"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/media?parent=22699"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/categories?post=22699"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/tags?post=22699"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}