{"id":22422,"date":"2019-11-17T11:03:57","date_gmt":"2019-11-17T10:03:57","guid":{"rendered":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/?p=22422"},"modified":"2019-11-17T11:07:16","modified_gmt":"2019-11-17T10:07:16","slug":"fiuggi-cine-regio-assemblea-sovena","status":"publish","type":"post","link":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2019\/11\/17\/fiuggi-cine-regio-assemblea-sovena\/","title":{"rendered":"Il &#8216;Cine-Regio annual meeting&#8217; a Fiuggi dal 18 al 20 novembre"},"content":{"rendered":"<p><strong>L\u2019Assemblea annuale di Cine-Regio,<\/strong> il network europeo dei Fondi regionali per il\u00a0cinema e l\u2019audiovisivo, che coinvolge circa 50 fondi europei, <strong>si terr\u00e0 quest\u2019anno dal 18\u00a0al 20 novembre nel Lazio, a Fiugg<\/strong>i. Il network Cine-Regio, attivo dal 2005, svolge\u00a0attivit\u00e0 di studio e ricerca sui temi dell\u2019audiovisivo oltre che attivit\u00e0 con le principali\u00a0istituzioni europee sul tema dei supporti e fondi nel campo dell\u2019audiovisivo.<\/p>\n<h2><img loading=\"lazy\" decoding=\"async\" class=\"size-full wp-image-22425 aligncenter\" src=\"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2019\/11\/Roma-Lazio-Film-Commission-696x390.jpg\" alt=\"\" width=\"696\" height=\"390\" srcset=\"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2019\/11\/Roma-Lazio-Film-Commission-696x390.jpg 696w, https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2019\/11\/Roma-Lazio-Film-Commission-696x390-300x168.jpg 300w, https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2019\/11\/Roma-Lazio-Film-Commission-696x390-500x280.jpg 500w\" sizes=\"auto, (max-width: 696px) 100vw, 696px\" \/><\/h2>\n<h2><\/h2>\n<h2>L\u2019iniziativa<\/h2>\n<p>Cine-Regio annual meeting, Fiuggi 18-20 novembre 2019 \u00e8<strong> realizzata da\u00a0Roma Lazio Film Commission in collaborazione con Regione Lazio e Ass.For.SEO\u00a0<\/strong>nell\u2019ambito della Sovvenzione Globale MOViE UP 2020 della Regione Lazio, a valere\u00a0sul Programma Operativo del Fondo Sociale Europeo 2014\u20132020, finalizzata allo\u00a0sviluppo e consolidamento delle competenze degli operatori per l\u2019innovazione e\u00a0l\u2019internazionalizzazione del settore audiovisivo.<\/p>\n<p>L\u2019Assemblea annuale \u00e8 l\u2019occasione per i direttori e i rappresentanti dei Fondi Regionali\u00a0europei per il cinema e l\u2019audiovisivo associati al Network Cine-Regio di confrontarsi sui\u00a0punti di maggiore attualit\u00e0 relativi ai fondi a supporto degli operatori del settore cinema\u00a0e audiovisivo.<\/p>\n<p>Roma Lazio Film Commission, attiva per lo sviluppo della coproduzione, oltre a\u00a0promuovere Lazio Cinema International, strumento della Regione Lazio dedicato alla\u00a0coproduzione, attivo da quattro anni, \u00e8 impegnata nello sviluppo di accordi internazionali\u00a0che possano aprire nuove strade ai produttori del Lazio, come \u00e8 avvenuto con le attivit\u00e0\u00a0realizzate con i paesi dei Balcani, con il recente accordo siglato con la Rabinovich\u00a0Foundation di Israele e ora con il Belgio, che vede nella regione della Vallonia\u00a0potenzialit\u00e0 di sviluppo comune.<\/p>\n<p><strong>Gli oltre 40 partecipanti saranno ospitati presso l\u2019Hotel Ambasciatori di Fiuggi<\/strong>, dove si\u00a0svolgeranno anche tutte le sessioni assembleari e di training per i partecipanti di Cine-\u00a0Regio.<\/p>\n<h2>L&#8217;appuntamento<\/h2>\n<p>Il 18 novembre alle 18.30 si svolger\u00e0 la conferenza stampa di presentazione\u00a0dell\u2019Assemblea annuale Cine-Regio, presso la Sala Consiliare del Municipio di Fiuggi,\u00a0alla presenza dei Direttori dei Fondi Europei per il Cinema e con gli interventi di <strong>Sara\u00a0Battisti-Consigliere Regionale del Lazio, Alioska Baccarini, sindaco di Fiuggi,\u00a0Charlotte Applegren- Segretario Generale Cine-Regio e Cristina Priarone-Direttore\u00a0<\/strong><strong>Generale di Roma Lazio Film Commission.<\/strong><\/p>\n<p>&nbsp;<\/p>\n<figure id=\"attachment_5194\" aria-describedby=\"caption-attachment-5194\" style=\"width: 632px\" class=\"wp-caption aligncenter\"><img loading=\"lazy\" decoding=\"async\" class=\"wp-image-5194\" src=\"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2019\/01\/Buschini-Battisti-2.jpg\" alt=\"Mauro Buschini e Sara Battisti frosinone il corriere della provincia ciociaria frosinone regione lazio\" width=\"632\" height=\"356\" srcset=\"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2019\/01\/Buschini-Battisti-2.jpg 1000w, https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2019\/01\/Buschini-Battisti-2-300x169.jpg 300w, https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2019\/01\/Buschini-Battisti-2-768x433.jpg 768w, https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2019\/01\/Buschini-Battisti-2-500x282.jpg 500w\" sizes=\"auto, (max-width: 632px) 100vw, 632px\" \/><figcaption id=\"caption-attachment-5194\" class=\"wp-caption-text\">Mauro Buschini e Sara Battisti<\/figcaption><\/figure>\n<h2><\/h2>\n<h2>Serata di Gala<\/h2>\n<p>Il 19 novembre, al termine dei lavori, si svolger\u00e0 una serata di gala <strong>presso l\u2019Istituto\u00a0Alberghiero di Fiuggi<\/strong>, alla presenza dei rappresentanti istituzionali, Albino Ruberti-Capo\u00a0di Gabinetto della Regione Lazio, Mauro Buschini-Presidente del Consiglio Regionale<strong>,\u00a0<\/strong>Sara Battisti-Consigliere Regionale del Lazio, Luciano Sovena-Presidente di Roma Lazio\u00a0Film Commission, di produttori italiani e di tutti i partecipanti all\u2019Assemblea Cine-Regio.<\/p>\n<p>&nbsp;<\/p>\n<figure id=\"attachment_22423\" aria-describedby=\"caption-attachment-22423\" style=\"width: 632px\" class=\"wp-caption aligncenter\"><img loading=\"lazy\" decoding=\"async\" class=\"wp-image-22423\" src=\"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2019\/11\/luciano-sovena.jpg\" alt=\"\" width=\"632\" height=\"355\" srcset=\"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2019\/11\/luciano-sovena.jpg 850w, https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2019\/11\/luciano-sovena-300x169.jpg 300w, https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2019\/11\/luciano-sovena-768x432.jpg 768w, https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2019\/11\/luciano-sovena-500x281.jpg 500w\" sizes=\"auto, (max-width: 632px) 100vw, 632px\" \/><figcaption id=\"caption-attachment-22423\" class=\"wp-caption-text\">Luciano Sovena<\/figcaption><\/figure>\n<h2><\/h2>\n<h2>L&#8217;obiettivo<\/h2>\n<p>La serata del 19 novembre sar\u00e0 anche l\u2019occasione per la<strong> firma del protocollo di intesa<\/strong>\u00a0\u201cRegional Development and Co-Production Agreement\u201d fra Wallimage, Fondo della\u00a0Vallonia in Belgio, Roma Lazio Film Commission e Ass.For.SEO, alla presenza di Paolo\u00a0Luci-Presidente Ass.For.SEO, Philippe Reynaert- Direttore Generale Wallimage,\u00a0Luciano Sovena-Presidente Roma Lazio Film Commission. Il protocollo mira allo\u00a0sviluppo di iniziative comuni per il settore cinematografico e audiovisivo, in particolare\u00a0nell\u2019ambito della coproduzione, che Film Commission da sempre considera leva di\u00a0sviluppo per tutto il settore.<\/p>\n<p><strong>La cena sar\u00e0 arricchita dallo spettacolo \u201cSolo Anna\u201d dedicato ad Anna Magnani<\/strong>, di e\u00a0con Lidia Vitale.\u00a0Il 20 novembre i membri Cineregio parteciperanno al Location Tour sul territorio con la\u00a0visita di Anagni, dove potranno ammirare le bellezze della Cattedrale, visitare il museo e\u00a0conoscere le vicende storiche del luogo.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>L\u2019Assemblea annuale di Cine-Regio, il network europeo dei Fondi regionali per il\u00a0cinema e l\u2019audiovisivo, che coinvolge circa 50 fondi europei,<\/p>\n","protected":false},"author":18,"featured_media":4692,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[4,14],"tags":[6279,7257,217,7259,1388,1721,7258],"class_list":["post-22422","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-primo-piano","category-cultura","tag-albino-ruberti","tag-cine-regio","tag-fiuggi","tag-luciano-sovena","tag-mauro-buschini","tag-sara-battisti","tag-sovena"],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v27.8 (Yoast SEO v27.8) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Il &#039;Cine-Regio annual meeting&#039; a Fiuggi dal 18 al 20 novembre - IlCorriereDellaProvincia.it - News h24 e notizie di approfondimento<\/title>\n<meta name=\"description\" content=\"Cine-Regio annual meeting, Fiuggi 18-20 novembre 2019 \u00e8 realizzata da\u00a0Roma Lazio Film Commission in collaborazione con Regione Lazio e Ass.For.SEO\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2019\/11\/17\/fiuggi-cine-regio-assemblea-sovena\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Il &#039;Cine-Regio annual meeting&#039; a Fiuggi dal 18 al 20 novembre\" \/>\n<meta property=\"og:description\" content=\"Cine-Regio annual meeting, Fiuggi 18-20 novembre 2019 \u00e8 realizzata da\u00a0Roma Lazio Film Commission in collaborazione con Regione Lazio e Ass.For.SEO\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2019\/11\/17\/fiuggi-cine-regio-assemblea-sovena\/\" \/>\n<meta property=\"og:site_name\" content=\"IlCorriereDellaProvincia.it - News h24 e notizie di approfondimento\" \/>\n<meta property=\"article:author\" content=\"www.facebook.com\/tunews24\" \/>\n<meta property=\"article:published_time\" content=\"2019-11-17T10:03:57+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2019-11-17T10:07:16+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2019\/01\/teatro-comunale-fiuggi.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"640\" \/>\n\t<meta property=\"og:image:height\" content=\"480\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Redazione\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"Redazione\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"3 minuti\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2019\\\/11\\\/17\\\/fiuggi-cine-regio-assemblea-sovena\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2019\\\/11\\\/17\\\/fiuggi-cine-regio-assemblea-sovena\\\/\"},\"author\":{\"name\":\"Redazione\",\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/#\\\/schema\\\/person\\\/6d7f0a9120d0c03d0c552e9fdf49ed7d\"},\"headline\":\"Il &#8216;Cine-Regio annual meeting&#8217; a Fiuggi dal 18 al 20 novembre\",\"datePublished\":\"2019-11-17T10:03:57+00:00\",\"dateModified\":\"2019-11-17T10:07:16+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2019\\\/11\\\/17\\\/fiuggi-cine-regio-assemblea-sovena\\\/\"},\"wordCount\":572,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2019\\\/11\\\/17\\\/fiuggi-cine-regio-assemblea-sovena\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2019\\\/01\\\/teatro-comunale-fiuggi.jpg\",\"keywords\":[\"albino ruberti\",\"cine-regio\",\"Fiuggi\",\"Luciano Sovena\",\"mauro buschini\",\"Sara Battisti\",\"Sovena\"],\"articleSection\":[\"*PRIMO PIANO*\",\"Cultura e Spettacolo\"],\"inLanguage\":\"it-IT\",\"copyrightYear\":\"2019\",\"copyrightHolder\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/#organization\"}},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2019\\\/11\\\/17\\\/fiuggi-cine-regio-assemblea-sovena\\\/\",\"url\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2019\\\/11\\\/17\\\/fiuggi-cine-regio-assemblea-sovena\\\/\",\"name\":\"Il 'Cine-Regio annual meeting' a Fiuggi dal 18 al 20 novembre - IlCorriereDellaProvincia.it - News h24 e notizie di approfondimento\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2019\\\/11\\\/17\\\/fiuggi-cine-regio-assemblea-sovena\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2019\\\/11\\\/17\\\/fiuggi-cine-regio-assemblea-sovena\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2019\\\/01\\\/teatro-comunale-fiuggi.jpg\",\"datePublished\":\"2019-11-17T10:03:57+00:00\",\"dateModified\":\"2019-11-17T10:07:16+00:00\",\"description\":\"Cine-Regio annual meeting, Fiuggi 18-20 novembre 2019 \u00e8 realizzata da\u00a0Roma Lazio Film Commission in collaborazione con Regione Lazio e Ass.For.SEO\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2019\\\/11\\\/17\\\/fiuggi-cine-regio-assemblea-sovena\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2019\\\/11\\\/17\\\/fiuggi-cine-regio-assemblea-sovena\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2019\\\/11\\\/17\\\/fiuggi-cine-regio-assemblea-sovena\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2019\\\/01\\\/teatro-comunale-fiuggi.jpg\",\"contentUrl\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2019\\\/01\\\/teatro-comunale-fiuggi.jpg\",\"width\":640,\"height\":480,\"caption\":\"Il teatro comunale di Fiuggi in piazza Trento e Trieste\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2019\\\/11\\\/17\\\/fiuggi-cine-regio-assemblea-sovena\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Il &#8216;Cine-Regio annual meeting&#8217; a Fiuggi dal 18 al 20 novembre\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/#website\",\"url\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/\",\"name\":\"Il Corriere Delle Provincia\",\"description\":\"IlCorriereDellaProvincia.it, quotidiano web di politica, cronaca, inchiesta, lavoro, scuola, turismo, cultura e spettacolo, economia e finanza, salute e benessere. Approfondimenti e notizie aggiornate con foto e video della provincia di Frosinone ma anche news nazionali, dell\u2019Italia e del Mondo.\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":[\"Organization\",\"Place\"],\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/#organization\",\"name\":\"Globalpress s.r.l.\",\"url\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/\",\"logo\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2019\\\/11\\\/17\\\/fiuggi-cine-regio-assemblea-sovena\\\/#local-main-organization-logo\"},\"image\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2019\\\/11\\\/17\\\/fiuggi-cine-regio-assemblea-sovena\\\/#local-main-organization-logo\"},\"telephone\":[],\"openingHoursSpecification\":[{\"@type\":\"OpeningHoursSpecification\",\"dayOfWeek\":[\"Monday\",\"Tuesday\",\"Wednesday\",\"Thursday\",\"Friday\",\"Saturday\",\"Sunday\"],\"opens\":\"09:00\",\"closes\":\"17:00\"}]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/#\\\/schema\\\/person\\\/6d7f0a9120d0c03d0c552e9fdf49ed7d\",\"name\":\"Redazione\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/a40eeacccdcad861f831dde73317f63a542e738f0dc4b79b9f47062d3d4bd1d2?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/a40eeacccdcad861f831dde73317f63a542e738f0dc4b79b9f47062d3d4bd1d2?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/a40eeacccdcad861f831dde73317f63a542e738f0dc4b79b9f47062d3d4bd1d2?s=96&d=mm&r=g\",\"caption\":\"Redazione\"},\"description\":\"SEGUICI ANCHE SUI SOCIAL Facebook: TuNews24 e TuSport24 Instagram: TuNews24 e TuSport24 Youtube: TuNews24 Telegram: TuNews24 Puoi leggerci anche in formato cartaceo: il settimanale viene pubblicato e distribuito gratuitamente ogni venerd\u00ec in edicole, bar, centri commerciali e svariati esercizi. Ma \u00e8 possibile anche sfogliarlo comodamente online, cliccando su TU NEWS sfogliabile TU NEWS, PASSIONE PER L\u2019INFORMAZIONE\",\"sameAs\":[\"http:\\\/\\\/www.tunews24.it\",\"www.facebook.com\\\/tunews24\"],\"url\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/author\\\/senzafirma\\\/\"},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2019\\\/11\\\/17\\\/fiuggi-cine-regio-assemblea-sovena\\\/#local-main-organization-logo\",\"url\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2022\\\/11\\\/cropped-il-corriere-della-provincia-testata-web-scontornata.png\",\"contentUrl\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2022\\\/11\\\/cropped-il-corriere-della-provincia-testata-web-scontornata.png\",\"width\":2911,\"height\":717,\"caption\":\"Globalpress s.r.l.\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Il 'Cine-Regio annual meeting' a Fiuggi dal 18 al 20 novembre - IlCorriereDellaProvincia.it - News h24 e notizie di approfondimento","description":"Cine-Regio annual meeting, Fiuggi 18-20 novembre 2019 \u00e8 realizzata da\u00a0Roma Lazio Film Commission in collaborazione con Regione Lazio e Ass.For.SEO","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2019\/11\/17\/fiuggi-cine-regio-assemblea-sovena\/","og_locale":"it_IT","og_type":"article","og_title":"Il 'Cine-Regio annual meeting' a Fiuggi dal 18 al 20 novembre","og_description":"Cine-Regio annual meeting, Fiuggi 18-20 novembre 2019 \u00e8 realizzata da\u00a0Roma Lazio Film Commission in collaborazione con Regione Lazio e Ass.For.SEO","og_url":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2019\/11\/17\/fiuggi-cine-regio-assemblea-sovena\/","og_site_name":"IlCorriereDellaProvincia.it - News h24 e notizie di approfondimento","article_author":"www.facebook.com\/tunews24","article_published_time":"2019-11-17T10:03:57+00:00","article_modified_time":"2019-11-17T10:07:16+00:00","og_image":[{"width":640,"height":480,"url":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2019\/01\/teatro-comunale-fiuggi.jpg","type":"image\/jpeg"}],"author":"Redazione","twitter_card":"summary_large_image","twitter_misc":{"Scritto da":"Redazione","Tempo di lettura stimato":"3 minuti"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2019\/11\/17\/fiuggi-cine-regio-assemblea-sovena\/#article","isPartOf":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2019\/11\/17\/fiuggi-cine-regio-assemblea-sovena\/"},"author":{"name":"Redazione","@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/#\/schema\/person\/6d7f0a9120d0c03d0c552e9fdf49ed7d"},"headline":"Il &#8216;Cine-Regio annual meeting&#8217; a Fiuggi dal 18 al 20 novembre","datePublished":"2019-11-17T10:03:57+00:00","dateModified":"2019-11-17T10:07:16+00:00","mainEntityOfPage":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2019\/11\/17\/fiuggi-cine-regio-assemblea-sovena\/"},"wordCount":572,"commentCount":0,"publisher":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/#organization"},"image":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2019\/11\/17\/fiuggi-cine-regio-assemblea-sovena\/#primaryimage"},"thumbnailUrl":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2019\/01\/teatro-comunale-fiuggi.jpg","keywords":["albino ruberti","cine-regio","Fiuggi","Luciano Sovena","mauro buschini","Sara Battisti","Sovena"],"articleSection":["*PRIMO PIANO*","Cultura e Spettacolo"],"inLanguage":"it-IT","copyrightYear":"2019","copyrightHolder":{"@id":"https:\/\/www.tunews24.it\/#organization"}},{"@type":"WebPage","@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2019\/11\/17\/fiuggi-cine-regio-assemblea-sovena\/","url":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2019\/11\/17\/fiuggi-cine-regio-assemblea-sovena\/","name":"Il 'Cine-Regio annual meeting' a Fiuggi dal 18 al 20 novembre - IlCorriereDellaProvincia.it - News h24 e notizie di approfondimento","isPartOf":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2019\/11\/17\/fiuggi-cine-regio-assemblea-sovena\/#primaryimage"},"image":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2019\/11\/17\/fiuggi-cine-regio-assemblea-sovena\/#primaryimage"},"thumbnailUrl":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2019\/01\/teatro-comunale-fiuggi.jpg","datePublished":"2019-11-17T10:03:57+00:00","dateModified":"2019-11-17T10:07:16+00:00","description":"Cine-Regio annual meeting, Fiuggi 18-20 novembre 2019 \u00e8 realizzata da\u00a0Roma Lazio Film Commission in collaborazione con Regione Lazio e Ass.For.SEO","breadcrumb":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2019\/11\/17\/fiuggi-cine-regio-assemblea-sovena\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2019\/11\/17\/fiuggi-cine-regio-assemblea-sovena\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2019\/11\/17\/fiuggi-cine-regio-assemblea-sovena\/#primaryimage","url":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2019\/01\/teatro-comunale-fiuggi.jpg","contentUrl":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2019\/01\/teatro-comunale-fiuggi.jpg","width":640,"height":480,"caption":"Il teatro comunale di Fiuggi in piazza Trento e Trieste"},{"@type":"BreadcrumbList","@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2019\/11\/17\/fiuggi-cine-regio-assemblea-sovena\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/"},{"@type":"ListItem","position":2,"name":"Il &#8216;Cine-Regio annual meeting&#8217; a Fiuggi dal 18 al 20 novembre"}]},{"@type":"WebSite","@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/#website","url":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/","name":"Il Corriere Delle Provincia","description":"IlCorriereDellaProvincia.it, quotidiano web di politica, cronaca, inchiesta, lavoro, scuola, turismo, cultura e spettacolo, economia e finanza, salute e benessere. Approfondimenti e notizie aggiornate con foto e video della provincia di Frosinone ma anche news nazionali, dell\u2019Italia e del Mondo.","publisher":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":["Organization","Place"],"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/#organization","name":"Globalpress s.r.l.","url":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/","logo":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2019\/11\/17\/fiuggi-cine-regio-assemblea-sovena\/#local-main-organization-logo"},"image":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2019\/11\/17\/fiuggi-cine-regio-assemblea-sovena\/#local-main-organization-logo"},"telephone":[],"openingHoursSpecification":[{"@type":"OpeningHoursSpecification","dayOfWeek":["Monday","Tuesday","Wednesday","Thursday","Friday","Saturday","Sunday"],"opens":"09:00","closes":"17:00"}]},{"@type":"Person","@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/#\/schema\/person\/6d7f0a9120d0c03d0c552e9fdf49ed7d","name":"Redazione","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/secure.gravatar.com\/avatar\/a40eeacccdcad861f831dde73317f63a542e738f0dc4b79b9f47062d3d4bd1d2?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/a40eeacccdcad861f831dde73317f63a542e738f0dc4b79b9f47062d3d4bd1d2?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/a40eeacccdcad861f831dde73317f63a542e738f0dc4b79b9f47062d3d4bd1d2?s=96&d=mm&r=g","caption":"Redazione"},"description":"SEGUICI ANCHE SUI SOCIAL Facebook: TuNews24 e TuSport24 Instagram: TuNews24 e TuSport24 Youtube: TuNews24 Telegram: TuNews24 Puoi leggerci anche in formato cartaceo: il settimanale viene pubblicato e distribuito gratuitamente ogni venerd\u00ec in edicole, bar, centri commerciali e svariati esercizi. Ma \u00e8 possibile anche sfogliarlo comodamente online, cliccando su TU NEWS sfogliabile TU NEWS, PASSIONE PER L\u2019INFORMAZIONE","sameAs":["http:\/\/www.tunews24.it","www.facebook.com\/tunews24"],"url":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/author\/senzafirma\/"},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2019\/11\/17\/fiuggi-cine-regio-assemblea-sovena\/#local-main-organization-logo","url":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2022\/11\/cropped-il-corriere-della-provincia-testata-web-scontornata.png","contentUrl":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2022\/11\/cropped-il-corriere-della-provincia-testata-web-scontornata.png","width":2911,"height":717,"caption":"Globalpress s.r.l."}]}},"_links":{"self":[{"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/posts\/22422","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/users\/18"}],"replies":[{"embeddable":true,"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/comments?post=22422"}],"version-history":[{"count":4,"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/posts\/22422\/revisions"}],"predecessor-version":[{"id":22429,"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/posts\/22422\/revisions\/22429"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/media\/4692"}],"wp:attachment":[{"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/media?parent=22422"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/categories?post=22422"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/tags?post=22422"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}