{"id":21895,"date":"2019-11-10T13:29:00","date_gmt":"2019-11-10T12:29:00","guid":{"rendered":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/?p=21895"},"modified":"2019-11-10T13:29:00","modified_gmt":"2019-11-10T12:29:00","slug":"provincia-controlli-post-terremoto-nelle-scuole-ecco-cosa-e-emerso","status":"publish","type":"post","link":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2019\/11\/10\/provincia-controlli-post-terremoto-nelle-scuole-ecco-cosa-e-emerso\/","title":{"rendered":"Provincia, controlli post-terremoto nelle scuole. Ecco cosa \u00e8 emerso"},"content":{"rendered":"<p><strong>Sono terminate nella mattinata odierna le ispezioni<\/strong> visive nelle strutture che ospitano gli istituti di istruzione di secondo grado della provincia di Frosinone.<\/p>\n<p>L&#8217;Amministrazione provinciale ha chiesto e ottenuto la <strong>collaborazione e il supporto dell&#8217;Ordine degli Ingegneri e di quello degli Architetti<\/strong>, per completare in tempi rapidi le verifiche in tutte le strutture del territorio che ospitano scuole superiori.<\/p>\n<h2>Le risultanze delle ispezioni<\/h2>\n<p>Dai controlli \u00e8 emerso che il sisma del 7 novembre scorso, e le altre scosse dei giorni seguenti, non hanno provocato danni o situazioni di rischio negli stabili.<\/p>\n<p><strong>Unico caso<\/strong>, che per\u00f2 non riguarda l&#8217;aspetto strutturale, <strong>\u00e8 quello di due aule dell&#8217;Istituto &#8216;Cesare Baronio&#8217; di Sora<\/strong> per un problema legato a un tramezzo, del quale la dirigente scolastica era gi\u00e0 a conoscenza: per questa ragione entrambe le aree dovranno restare interdette all&#8217;utilizzo, s\u00ec da permettere l&#8217;intervento di ripristino delle normali condizioni di sicurezza.<\/p>\n<p>A conclusione delle ispezioni, dunque, e in considerazione dell&#8217;esito negativo per quanto concerne situazioni di pericolo o rischio, da domani le lezioni potranno riprendere regolarmente in tutti gli istituti superiori del territorio provinciale.<\/p>\n<h2>I ringraziamenti di Pompeo e Quadrini<\/h2>\n<p>&#8220;Un doveroso ringraziamento \u2013 commentano il <strong>presidente Antonio Pompeo<\/strong> e il <strong>consigliere provinciale delegato all&#8217;Edilizia scolastica, Massimiliano Quadrini<\/strong> \u2013 va all&#8217;Ordine degli Ingegneri e degli Architetti per il loro preziosissimo lavoro di supporto nelle operazioni ispettive sulle scuole: in questo modo, \u00e8 stato possibile verificare, in tempi rapidi, la sussistenza delle condizioni di sicurezza necessarie per permettere la riapertura di tutti i plessi&#8221;.<\/p>\n<p>&nbsp;<\/p>\n<figure id=\"attachment_21896\" aria-describedby=\"caption-attachment-21896\" style=\"width: 643px\" class=\"wp-caption aligncenter\"><img loading=\"lazy\" decoding=\"async\" class=\"wp-image-21896 size-full\" src=\"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2019\/11\/Pompeo-Quadrini.jpg\" alt=\"scuole controlli provincia terremoto pompeo quadrini il corriere \" width=\"643\" height=\"633\" srcset=\"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2019\/11\/Pompeo-Quadrini.jpg 643w, https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2019\/11\/Pompeo-Quadrini-300x295.jpg 300w, https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2019\/11\/Pompeo-Quadrini-500x492.jpg 500w\" sizes=\"auto, (max-width: 643px) 100vw, 643px\" \/><figcaption id=\"caption-attachment-21896\" class=\"wp-caption-text\">Il presidente Antonio Pompeo e il consigliere delegato all&#8217;Edilizia scolastica Massimiliano Quadrini<\/figcaption><\/figure>\n<p>&nbsp;<\/p>\n<p>&#8220;Chiaramente ringraziamo anche i nostri funzionari e i tecnici che hanno coordinato le attivit\u00e0 e reso possibile il completamento del lavoro nella giornata di oggi. Garantire scuole sicure ai nostri ragazzi \u2013 concludono \u2013 \u00e8 da sempre una delle priorit\u00e0 della nostra agenda e in una situazione di particolare criticit\u00e0, come questa, diventa il dovere primario di qualsiasi amministrazione&#8221;.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Sono terminate nella mattinata odierna le ispezioni visive nelle strutture che ospitano gli istituti di istruzione di secondo grado della<\/p>\n","protected":false},"author":18,"featured_media":21898,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[41,2236],"tags":[842,5193,94,209,93,5192,1292,1775,83,129,116,379,973],"class_list":["post-21895","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-slide","category-attualita","tag-antonio-pompeo","tag-architetti","tag-ciociaria","tag-controlli","tag-frosinone","tag-ingegneri","tag-istituti-superiori","tag-massimiliano-quadrini","tag-provincia","tag-scuole","tag-sicurezza","tag-studenti","tag-terremoto"],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v27.8 (Yoast SEO v27.8) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Provincia, controlli post-terremoto nelle scuole. Ecco cosa \u00e8 emerso - IlCorriereDellaProvincia.it - News h24 e notizie di approfondimento<\/title>\n<meta name=\"description\" content=\"Sono terminati questa mattina i controlli di Provincia, Ordine degli ingegneri e degli architetti nelle scuole del territorio dopo il terremoto\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2019\/11\/10\/provincia-controlli-post-terremoto-nelle-scuole-ecco-cosa-e-emerso\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Provincia, controlli post-terremoto nelle scuole. Ecco cosa \u00e8 emerso\" \/>\n<meta property=\"og:description\" content=\"Sono terminati questa mattina i controlli di Provincia, Ordine degli ingegneri e degli architetti nelle scuole del territorio dopo il terremoto\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2019\/11\/10\/provincia-controlli-post-terremoto-nelle-scuole-ecco-cosa-e-emerso\/\" \/>\n<meta property=\"og:site_name\" content=\"IlCorriereDellaProvincia.it - News h24 e notizie di approfondimento\" \/>\n<meta property=\"article:author\" content=\"www.facebook.com\/tunews24\" \/>\n<meta property=\"article:published_time\" content=\"2019-11-10T12:29:00+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2019\/11\/controlli-terremoto-scuole-e1573388891325.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"638\" \/>\n\t<meta property=\"og:image:height\" content=\"376\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Redazione\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"Redazione\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minuti\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2019\\\/11\\\/10\\\/provincia-controlli-post-terremoto-nelle-scuole-ecco-cosa-e-emerso\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2019\\\/11\\\/10\\\/provincia-controlli-post-terremoto-nelle-scuole-ecco-cosa-e-emerso\\\/\"},\"author\":{\"name\":\"Redazione\",\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/#\\\/schema\\\/person\\\/6d7f0a9120d0c03d0c552e9fdf49ed7d\"},\"headline\":\"Provincia, controlli post-terremoto nelle scuole. Ecco cosa \u00e8 emerso\",\"datePublished\":\"2019-11-10T12:29:00+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2019\\\/11\\\/10\\\/provincia-controlli-post-terremoto-nelle-scuole-ecco-cosa-e-emerso\\\/\"},\"wordCount\":337,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2019\\\/11\\\/10\\\/provincia-controlli-post-terremoto-nelle-scuole-ecco-cosa-e-emerso\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2019\\\/11\\\/controlli-terremoto-scuole-e1573388891325.jpg\",\"keywords\":[\"antonio pompeo\",\"architetti\",\"Ciociaria\",\"controlli\",\"Frosinone\",\"ingegneri\",\"istituti superiori\",\"massimiliano quadrini\",\"provincia\",\"scuole\",\"sicurezza\",\"studenti\",\"terremoto\"],\"articleSection\":[\"*SLIDE*\",\"Attualit\u00e0\"],\"inLanguage\":\"it-IT\",\"copyrightYear\":\"2019\",\"copyrightHolder\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/#organization\"}},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2019\\\/11\\\/10\\\/provincia-controlli-post-terremoto-nelle-scuole-ecco-cosa-e-emerso\\\/\",\"url\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2019\\\/11\\\/10\\\/provincia-controlli-post-terremoto-nelle-scuole-ecco-cosa-e-emerso\\\/\",\"name\":\"Provincia, controlli post-terremoto nelle scuole. Ecco cosa \u00e8 emerso - IlCorriereDellaProvincia.it - News h24 e notizie di approfondimento\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2019\\\/11\\\/10\\\/provincia-controlli-post-terremoto-nelle-scuole-ecco-cosa-e-emerso\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2019\\\/11\\\/10\\\/provincia-controlli-post-terremoto-nelle-scuole-ecco-cosa-e-emerso\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2019\\\/11\\\/controlli-terremoto-scuole-e1573388891325.jpg\",\"datePublished\":\"2019-11-10T12:29:00+00:00\",\"description\":\"Sono terminati questa mattina i controlli di Provincia, Ordine degli ingegneri e degli architetti nelle scuole del territorio dopo il terremoto\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2019\\\/11\\\/10\\\/provincia-controlli-post-terremoto-nelle-scuole-ecco-cosa-e-emerso\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2019\\\/11\\\/10\\\/provincia-controlli-post-terremoto-nelle-scuole-ecco-cosa-e-emerso\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2019\\\/11\\\/10\\\/provincia-controlli-post-terremoto-nelle-scuole-ecco-cosa-e-emerso\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2019\\\/11\\\/controlli-terremoto-scuole-e1573388891325.jpg\",\"contentUrl\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2019\\\/11\\\/controlli-terremoto-scuole-e1573388891325.jpg\",\"width\":638,\"height\":376,\"caption\":\"Controlli post-terremoto nelle scuole\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2019\\\/11\\\/10\\\/provincia-controlli-post-terremoto-nelle-scuole-ecco-cosa-e-emerso\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Provincia, controlli post-terremoto nelle scuole. Ecco cosa \u00e8 emerso\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/#website\",\"url\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/\",\"name\":\"Il Corriere Delle Provincia\",\"description\":\"IlCorriereDellaProvincia.it, quotidiano web di politica, cronaca, inchiesta, lavoro, scuola, turismo, cultura e spettacolo, economia e finanza, salute e benessere. Approfondimenti e notizie aggiornate con foto e video della provincia di Frosinone ma anche news nazionali, dell\u2019Italia e del Mondo.\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":[\"Organization\",\"Place\"],\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/#organization\",\"name\":\"Globalpress s.r.l.\",\"url\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/\",\"logo\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2019\\\/11\\\/10\\\/provincia-controlli-post-terremoto-nelle-scuole-ecco-cosa-e-emerso\\\/#local-main-organization-logo\"},\"image\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2019\\\/11\\\/10\\\/provincia-controlli-post-terremoto-nelle-scuole-ecco-cosa-e-emerso\\\/#local-main-organization-logo\"},\"telephone\":[],\"openingHoursSpecification\":[{\"@type\":\"OpeningHoursSpecification\",\"dayOfWeek\":[\"Monday\",\"Tuesday\",\"Wednesday\",\"Thursday\",\"Friday\",\"Saturday\",\"Sunday\"],\"opens\":\"09:00\",\"closes\":\"17:00\"}]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/#\\\/schema\\\/person\\\/6d7f0a9120d0c03d0c552e9fdf49ed7d\",\"name\":\"Redazione\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/a40eeacccdcad861f831dde73317f63a542e738f0dc4b79b9f47062d3d4bd1d2?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/a40eeacccdcad861f831dde73317f63a542e738f0dc4b79b9f47062d3d4bd1d2?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/a40eeacccdcad861f831dde73317f63a542e738f0dc4b79b9f47062d3d4bd1d2?s=96&d=mm&r=g\",\"caption\":\"Redazione\"},\"description\":\"SEGUICI ANCHE SUI SOCIAL Facebook: TuNews24 e TuSport24 Instagram: TuNews24 e TuSport24 Youtube: TuNews24 Telegram: TuNews24 Puoi leggerci anche in formato cartaceo: il settimanale viene pubblicato e distribuito gratuitamente ogni venerd\u00ec in edicole, bar, centri commerciali e svariati esercizi. Ma \u00e8 possibile anche sfogliarlo comodamente online, cliccando su TU NEWS sfogliabile TU NEWS, PASSIONE PER L\u2019INFORMAZIONE\",\"sameAs\":[\"http:\\\/\\\/www.tunews24.it\",\"www.facebook.com\\\/tunews24\"],\"url\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/author\\\/senzafirma\\\/\"},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2019\\\/11\\\/10\\\/provincia-controlli-post-terremoto-nelle-scuole-ecco-cosa-e-emerso\\\/#local-main-organization-logo\",\"url\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2022\\\/11\\\/cropped-il-corriere-della-provincia-testata-web-scontornata.png\",\"contentUrl\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2022\\\/11\\\/cropped-il-corriere-della-provincia-testata-web-scontornata.png\",\"width\":2911,\"height\":717,\"caption\":\"Globalpress s.r.l.\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Provincia, controlli post-terremoto nelle scuole. Ecco cosa \u00e8 emerso - IlCorriereDellaProvincia.it - News h24 e notizie di approfondimento","description":"Sono terminati questa mattina i controlli di Provincia, Ordine degli ingegneri e degli architetti nelle scuole del territorio dopo il terremoto","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2019\/11\/10\/provincia-controlli-post-terremoto-nelle-scuole-ecco-cosa-e-emerso\/","og_locale":"it_IT","og_type":"article","og_title":"Provincia, controlli post-terremoto nelle scuole. Ecco cosa \u00e8 emerso","og_description":"Sono terminati questa mattina i controlli di Provincia, Ordine degli ingegneri e degli architetti nelle scuole del territorio dopo il terremoto","og_url":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2019\/11\/10\/provincia-controlli-post-terremoto-nelle-scuole-ecco-cosa-e-emerso\/","og_site_name":"IlCorriereDellaProvincia.it - News h24 e notizie di approfondimento","article_author":"www.facebook.com\/tunews24","article_published_time":"2019-11-10T12:29:00+00:00","og_image":[{"width":638,"height":376,"url":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2019\/11\/controlli-terremoto-scuole-e1573388891325.jpg","type":"image\/jpeg"}],"author":"Redazione","twitter_card":"summary_large_image","twitter_misc":{"Scritto da":"Redazione","Tempo di lettura stimato":"2 minuti"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2019\/11\/10\/provincia-controlli-post-terremoto-nelle-scuole-ecco-cosa-e-emerso\/#article","isPartOf":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2019\/11\/10\/provincia-controlli-post-terremoto-nelle-scuole-ecco-cosa-e-emerso\/"},"author":{"name":"Redazione","@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/#\/schema\/person\/6d7f0a9120d0c03d0c552e9fdf49ed7d"},"headline":"Provincia, controlli post-terremoto nelle scuole. Ecco cosa \u00e8 emerso","datePublished":"2019-11-10T12:29:00+00:00","mainEntityOfPage":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2019\/11\/10\/provincia-controlli-post-terremoto-nelle-scuole-ecco-cosa-e-emerso\/"},"wordCount":337,"commentCount":0,"publisher":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/#organization"},"image":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2019\/11\/10\/provincia-controlli-post-terremoto-nelle-scuole-ecco-cosa-e-emerso\/#primaryimage"},"thumbnailUrl":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2019\/11\/controlli-terremoto-scuole-e1573388891325.jpg","keywords":["antonio pompeo","architetti","Ciociaria","controlli","Frosinone","ingegneri","istituti superiori","massimiliano quadrini","provincia","scuole","sicurezza","studenti","terremoto"],"articleSection":["*SLIDE*","Attualit\u00e0"],"inLanguage":"it-IT","copyrightYear":"2019","copyrightHolder":{"@id":"https:\/\/www.tunews24.it\/#organization"}},{"@type":"WebPage","@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2019\/11\/10\/provincia-controlli-post-terremoto-nelle-scuole-ecco-cosa-e-emerso\/","url":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2019\/11\/10\/provincia-controlli-post-terremoto-nelle-scuole-ecco-cosa-e-emerso\/","name":"Provincia, controlli post-terremoto nelle scuole. Ecco cosa \u00e8 emerso - IlCorriereDellaProvincia.it - News h24 e notizie di approfondimento","isPartOf":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2019\/11\/10\/provincia-controlli-post-terremoto-nelle-scuole-ecco-cosa-e-emerso\/#primaryimage"},"image":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2019\/11\/10\/provincia-controlli-post-terremoto-nelle-scuole-ecco-cosa-e-emerso\/#primaryimage"},"thumbnailUrl":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2019\/11\/controlli-terremoto-scuole-e1573388891325.jpg","datePublished":"2019-11-10T12:29:00+00:00","description":"Sono terminati questa mattina i controlli di Provincia, Ordine degli ingegneri e degli architetti nelle scuole del territorio dopo il terremoto","breadcrumb":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2019\/11\/10\/provincia-controlli-post-terremoto-nelle-scuole-ecco-cosa-e-emerso\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2019\/11\/10\/provincia-controlli-post-terremoto-nelle-scuole-ecco-cosa-e-emerso\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2019\/11\/10\/provincia-controlli-post-terremoto-nelle-scuole-ecco-cosa-e-emerso\/#primaryimage","url":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2019\/11\/controlli-terremoto-scuole-e1573388891325.jpg","contentUrl":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2019\/11\/controlli-terremoto-scuole-e1573388891325.jpg","width":638,"height":376,"caption":"Controlli post-terremoto nelle scuole"},{"@type":"BreadcrumbList","@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2019\/11\/10\/provincia-controlli-post-terremoto-nelle-scuole-ecco-cosa-e-emerso\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/"},{"@type":"ListItem","position":2,"name":"Provincia, controlli post-terremoto nelle scuole. Ecco cosa \u00e8 emerso"}]},{"@type":"WebSite","@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/#website","url":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/","name":"Il Corriere Delle Provincia","description":"IlCorriereDellaProvincia.it, quotidiano web di politica, cronaca, inchiesta, lavoro, scuola, turismo, cultura e spettacolo, economia e finanza, salute e benessere. Approfondimenti e notizie aggiornate con foto e video della provincia di Frosinone ma anche news nazionali, dell\u2019Italia e del Mondo.","publisher":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":["Organization","Place"],"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/#organization","name":"Globalpress s.r.l.","url":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/","logo":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2019\/11\/10\/provincia-controlli-post-terremoto-nelle-scuole-ecco-cosa-e-emerso\/#local-main-organization-logo"},"image":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2019\/11\/10\/provincia-controlli-post-terremoto-nelle-scuole-ecco-cosa-e-emerso\/#local-main-organization-logo"},"telephone":[],"openingHoursSpecification":[{"@type":"OpeningHoursSpecification","dayOfWeek":["Monday","Tuesday","Wednesday","Thursday","Friday","Saturday","Sunday"],"opens":"09:00","closes":"17:00"}]},{"@type":"Person","@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/#\/schema\/person\/6d7f0a9120d0c03d0c552e9fdf49ed7d","name":"Redazione","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/secure.gravatar.com\/avatar\/a40eeacccdcad861f831dde73317f63a542e738f0dc4b79b9f47062d3d4bd1d2?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/a40eeacccdcad861f831dde73317f63a542e738f0dc4b79b9f47062d3d4bd1d2?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/a40eeacccdcad861f831dde73317f63a542e738f0dc4b79b9f47062d3d4bd1d2?s=96&d=mm&r=g","caption":"Redazione"},"description":"SEGUICI ANCHE SUI SOCIAL Facebook: TuNews24 e TuSport24 Instagram: TuNews24 e TuSport24 Youtube: TuNews24 Telegram: TuNews24 Puoi leggerci anche in formato cartaceo: il settimanale viene pubblicato e distribuito gratuitamente ogni venerd\u00ec in edicole, bar, centri commerciali e svariati esercizi. Ma \u00e8 possibile anche sfogliarlo comodamente online, cliccando su TU NEWS sfogliabile TU NEWS, PASSIONE PER L\u2019INFORMAZIONE","sameAs":["http:\/\/www.tunews24.it","www.facebook.com\/tunews24"],"url":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/author\/senzafirma\/"},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2019\/11\/10\/provincia-controlli-post-terremoto-nelle-scuole-ecco-cosa-e-emerso\/#local-main-organization-logo","url":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2022\/11\/cropped-il-corriere-della-provincia-testata-web-scontornata.png","contentUrl":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2022\/11\/cropped-il-corriere-della-provincia-testata-web-scontornata.png","width":2911,"height":717,"caption":"Globalpress s.r.l."}]}},"_links":{"self":[{"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/posts\/21895","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/users\/18"}],"replies":[{"embeddable":true,"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/comments?post=21895"}],"version-history":[{"count":1,"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/posts\/21895\/revisions"}],"predecessor-version":[{"id":21899,"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/posts\/21895\/revisions\/21899"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/media\/21898"}],"wp:attachment":[{"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/media?parent=21895"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/categories?post=21895"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/tags?post=21895"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}