{"id":21853,"date":"2019-11-09T20:28:37","date_gmt":"2019-11-09T19:28:37","guid":{"rendered":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/?p=21853"},"modified":"2019-11-09T20:28:37","modified_gmt":"2019-11-09T19:28:37","slug":"pofi-anche-il-vice-di-ciccone-aderisce-a-cambiamo","status":"publish","type":"post","link":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2019\/11\/09\/pofi-anche-il-vice-di-ciccone-aderisce-a-cambiamo\/","title":{"rendered":"Pofi: anche il vice di Ciccone aderisce a &#8216;Cambiamo&#8217;"},"content":{"rendered":"<p>Anche il vice di <strong>Tommaso Ciccone, sindaco di Pofi<\/strong> e responsabile provinciale di &#8216;Cambiamo&#8217;, lascia la maglia azzurra per seguire il movimento di Giovanni Toti.<\/p>\n<p>Lo comunica in una nota, in cui parla di &#8220;<strong>scelta importante e difficile<\/strong> per garantire ai cittadini una politica nuova, vera e vicina alle esigenze degli stessi&#8221;.<\/p>\n<h2>Le parole di Piero De Nardis<\/h2>\n<p>&#8220;Allora insieme a tanti amici \u2013 dice il numero due di Ciccone &#8211; abbiamo condiviso in pieno il progetto &#8216;Cambiamo&#8217; del governatore ligure Giovanni Toti,<strong> un progetto equilibrato<\/strong>, attento ai temi che sono passati in seconda linea. Lascio dunque Forza Italia, per ripartire dalla base e non dai nominati, per garantire a ogni singola persona di conoscere chi va a votare&#8221;.<\/p>\n<p>&nbsp;<\/p>\n<figure id=\"attachment_21854\" aria-describedby=\"caption-attachment-21854\" style=\"width: 494px\" class=\"wp-caption aligncenter\"><img loading=\"lazy\" decoding=\"async\" class=\"wp-image-21854 size-full\" src=\"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2019\/11\/de-nardis-vice-sindaco-pofi.jpg\" alt=\"piero de nardis vicesindaco pofi il corriere della provincia\" width=\"494\" height=\"655\" srcset=\"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2019\/11\/de-nardis-vice-sindaco-pofi.jpg 494w, https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2019\/11\/de-nardis-vice-sindaco-pofi-226x300.jpg 226w\" sizes=\"auto, (max-width: 494px) 100vw, 494px\" \/><figcaption id=\"caption-attachment-21854\" class=\"wp-caption-text\">Piero De Nardis, vicesindaco di Pofi<\/figcaption><\/figure>\n<p>&nbsp;<\/p>\n<p>&#8220;Sono gi\u00e0 a lavoro \u2013 conclude De Nardis &#8211; per dare il mio contributo al radicamento del partito ed avvicinare i cittadini, ai quali voglio trasmettere l&#8217;entusiasmo che si respira nel panorama politico nazionale nel centrodestra. Insieme possiamo farcela&#8221;.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Anche il vice di Tommaso Ciccone, sindaco di Pofi e responsabile provinciale di &#8216;Cambiamo&#8217;, lascia la maglia azzurra per seguire<\/p>\n","protected":false},"author":18,"featured_media":21855,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[28],"tags":[5738,94,93,7141,328,362,2927,5121],"class_list":["post-21853","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-politica","tag-cambiamo","tag-ciociaria","tag-frosinone","tag-piero-de-nardis","tag-pofi","tag-progetto","tag-tommaso-ciccone","tag-vicesindaco"],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v27.8 (Yoast SEO v27.8) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Pofi: anche il vice di Ciccone aderisce a &#039;Cambiamo&#039; - IlCorriereDellaProvincia.it - News h24 e notizie di approfondimento<\/title>\n<meta name=\"description\" content=\"Il vicesindaco di Pofi, Piero De Nardis, ha lasciato Forza Italia e ha aderito a &#039;Cambiamo&#039;, il movimento di Giovanni Toti. Lo comunica in una nota\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2019\/11\/09\/pofi-anche-il-vice-di-ciccone-aderisce-a-cambiamo\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Pofi: anche il vice di Ciccone aderisce a &#039;Cambiamo&#039;\" \/>\n<meta property=\"og:description\" content=\"Il vicesindaco di Pofi, Piero De Nardis, ha lasciato Forza Italia e ha aderito a &#039;Cambiamo&#039;, il movimento di Giovanni Toti. Lo comunica in una nota\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2019\/11\/09\/pofi-anche-il-vice-di-ciccone-aderisce-a-cambiamo\/\" \/>\n<meta property=\"og:site_name\" content=\"IlCorriereDellaProvincia.it - News h24 e notizie di approfondimento\" \/>\n<meta property=\"article:author\" content=\"www.facebook.com\/tunews24\" \/>\n<meta property=\"article:published_time\" content=\"2019-11-09T19:28:37+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2019\/11\/piero-de-nardis-pofi-e1573327654359.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"632\" \/>\n\t<meta property=\"og:image:height\" content=\"450\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Redazione\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"Redazione\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2019\\\/11\\\/09\\\/pofi-anche-il-vice-di-ciccone-aderisce-a-cambiamo\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2019\\\/11\\\/09\\\/pofi-anche-il-vice-di-ciccone-aderisce-a-cambiamo\\\/\"},\"author\":{\"name\":\"Redazione\",\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/#\\\/schema\\\/person\\\/6d7f0a9120d0c03d0c552e9fdf49ed7d\"},\"headline\":\"Pofi: anche il vice di Ciccone aderisce a &#8216;Cambiamo&#8217;\",\"datePublished\":\"2019-11-09T19:28:37+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2019\\\/11\\\/09\\\/pofi-anche-il-vice-di-ciccone-aderisce-a-cambiamo\\\/\"},\"wordCount\":181,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2019\\\/11\\\/09\\\/pofi-anche-il-vice-di-ciccone-aderisce-a-cambiamo\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2019\\\/11\\\/piero-de-nardis-pofi-e1573327654359.jpg\",\"keywords\":[\"cambiamo\",\"Ciociaria\",\"Frosinone\",\"piero de nardis\",\"pofi\",\"progetto\",\"Tommaso Ciccone\",\"vicesindaco\"],\"articleSection\":[\"Evidenza\"],\"inLanguage\":\"it-IT\",\"copyrightYear\":\"2019\",\"copyrightHolder\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/#organization\"}},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2019\\\/11\\\/09\\\/pofi-anche-il-vice-di-ciccone-aderisce-a-cambiamo\\\/\",\"url\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2019\\\/11\\\/09\\\/pofi-anche-il-vice-di-ciccone-aderisce-a-cambiamo\\\/\",\"name\":\"Pofi: anche il vice di Ciccone aderisce a 'Cambiamo' - IlCorriereDellaProvincia.it - News h24 e notizie di approfondimento\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2019\\\/11\\\/09\\\/pofi-anche-il-vice-di-ciccone-aderisce-a-cambiamo\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2019\\\/11\\\/09\\\/pofi-anche-il-vice-di-ciccone-aderisce-a-cambiamo\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2019\\\/11\\\/piero-de-nardis-pofi-e1573327654359.jpg\",\"datePublished\":\"2019-11-09T19:28:37+00:00\",\"description\":\"Il vicesindaco di Pofi, Piero De Nardis, ha lasciato Forza Italia e ha aderito a 'Cambiamo', il movimento di Giovanni Toti. Lo comunica in una nota\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2019\\\/11\\\/09\\\/pofi-anche-il-vice-di-ciccone-aderisce-a-cambiamo\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2019\\\/11\\\/09\\\/pofi-anche-il-vice-di-ciccone-aderisce-a-cambiamo\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2019\\\/11\\\/09\\\/pofi-anche-il-vice-di-ciccone-aderisce-a-cambiamo\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2019\\\/11\\\/piero-de-nardis-pofi-e1573327654359.jpg\",\"contentUrl\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2019\\\/11\\\/piero-de-nardis-pofi-e1573327654359.jpg\",\"width\":632,\"height\":450,\"caption\":\"Il vicesindaco di Pofi Piero De Nardis\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2019\\\/11\\\/09\\\/pofi-anche-il-vice-di-ciccone-aderisce-a-cambiamo\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Pofi: anche il vice di Ciccone aderisce a &#8216;Cambiamo&#8217;\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/#website\",\"url\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/\",\"name\":\"Il Corriere Delle Provincia\",\"description\":\"IlCorriereDellaProvincia.it, quotidiano web di politica, cronaca, inchiesta, lavoro, scuola, turismo, cultura e spettacolo, economia e finanza, salute e benessere. Approfondimenti e notizie aggiornate con foto e video della provincia di Frosinone ma anche news nazionali, dell\u2019Italia e del Mondo.\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":[\"Organization\",\"Place\"],\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/#organization\",\"name\":\"Globalpress s.r.l.\",\"url\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/\",\"logo\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2019\\\/11\\\/09\\\/pofi-anche-il-vice-di-ciccone-aderisce-a-cambiamo\\\/#local-main-organization-logo\"},\"image\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2019\\\/11\\\/09\\\/pofi-anche-il-vice-di-ciccone-aderisce-a-cambiamo\\\/#local-main-organization-logo\"},\"telephone\":[],\"openingHoursSpecification\":[{\"@type\":\"OpeningHoursSpecification\",\"dayOfWeek\":[\"Monday\",\"Tuesday\",\"Wednesday\",\"Thursday\",\"Friday\",\"Saturday\",\"Sunday\"],\"opens\":\"09:00\",\"closes\":\"17:00\"}]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/#\\\/schema\\\/person\\\/6d7f0a9120d0c03d0c552e9fdf49ed7d\",\"name\":\"Redazione\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/a40eeacccdcad861f831dde73317f63a542e738f0dc4b79b9f47062d3d4bd1d2?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/a40eeacccdcad861f831dde73317f63a542e738f0dc4b79b9f47062d3d4bd1d2?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/a40eeacccdcad861f831dde73317f63a542e738f0dc4b79b9f47062d3d4bd1d2?s=96&d=mm&r=g\",\"caption\":\"Redazione\"},\"description\":\"SEGUICI ANCHE SUI SOCIAL Facebook: TuNews24 e TuSport24 Instagram: TuNews24 e TuSport24 Youtube: TuNews24 Telegram: TuNews24 Puoi leggerci anche in formato cartaceo: il settimanale viene pubblicato e distribuito gratuitamente ogni venerd\u00ec in edicole, bar, centri commerciali e svariati esercizi. Ma \u00e8 possibile anche sfogliarlo comodamente online, cliccando su TU NEWS sfogliabile TU NEWS, PASSIONE PER L\u2019INFORMAZIONE\",\"sameAs\":[\"http:\\\/\\\/www.tunews24.it\",\"www.facebook.com\\\/tunews24\"],\"url\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/author\\\/senzafirma\\\/\"},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2019\\\/11\\\/09\\\/pofi-anche-il-vice-di-ciccone-aderisce-a-cambiamo\\\/#local-main-organization-logo\",\"url\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2022\\\/11\\\/cropped-il-corriere-della-provincia-testata-web-scontornata.png\",\"contentUrl\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2022\\\/11\\\/cropped-il-corriere-della-provincia-testata-web-scontornata.png\",\"width\":2911,\"height\":717,\"caption\":\"Globalpress s.r.l.\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Pofi: anche il vice di Ciccone aderisce a 'Cambiamo' - IlCorriereDellaProvincia.it - News h24 e notizie di approfondimento","description":"Il vicesindaco di Pofi, Piero De Nardis, ha lasciato Forza Italia e ha aderito a 'Cambiamo', il movimento di Giovanni Toti. Lo comunica in una nota","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2019\/11\/09\/pofi-anche-il-vice-di-ciccone-aderisce-a-cambiamo\/","og_locale":"it_IT","og_type":"article","og_title":"Pofi: anche il vice di Ciccone aderisce a 'Cambiamo'","og_description":"Il vicesindaco di Pofi, Piero De Nardis, ha lasciato Forza Italia e ha aderito a 'Cambiamo', il movimento di Giovanni Toti. Lo comunica in una nota","og_url":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2019\/11\/09\/pofi-anche-il-vice-di-ciccone-aderisce-a-cambiamo\/","og_site_name":"IlCorriereDellaProvincia.it - News h24 e notizie di approfondimento","article_author":"www.facebook.com\/tunews24","article_published_time":"2019-11-09T19:28:37+00:00","og_image":[{"width":632,"height":450,"url":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2019\/11\/piero-de-nardis-pofi-e1573327654359.jpg","type":"image\/jpeg"}],"author":"Redazione","twitter_card":"summary_large_image","twitter_misc":{"Scritto da":"Redazione","Tempo di lettura stimato":"1 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2019\/11\/09\/pofi-anche-il-vice-di-ciccone-aderisce-a-cambiamo\/#article","isPartOf":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2019\/11\/09\/pofi-anche-il-vice-di-ciccone-aderisce-a-cambiamo\/"},"author":{"name":"Redazione","@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/#\/schema\/person\/6d7f0a9120d0c03d0c552e9fdf49ed7d"},"headline":"Pofi: anche il vice di Ciccone aderisce a &#8216;Cambiamo&#8217;","datePublished":"2019-11-09T19:28:37+00:00","mainEntityOfPage":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2019\/11\/09\/pofi-anche-il-vice-di-ciccone-aderisce-a-cambiamo\/"},"wordCount":181,"commentCount":0,"publisher":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/#organization"},"image":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2019\/11\/09\/pofi-anche-il-vice-di-ciccone-aderisce-a-cambiamo\/#primaryimage"},"thumbnailUrl":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2019\/11\/piero-de-nardis-pofi-e1573327654359.jpg","keywords":["cambiamo","Ciociaria","Frosinone","piero de nardis","pofi","progetto","Tommaso Ciccone","vicesindaco"],"articleSection":["Evidenza"],"inLanguage":"it-IT","copyrightYear":"2019","copyrightHolder":{"@id":"https:\/\/www.tunews24.it\/#organization"}},{"@type":"WebPage","@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2019\/11\/09\/pofi-anche-il-vice-di-ciccone-aderisce-a-cambiamo\/","url":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2019\/11\/09\/pofi-anche-il-vice-di-ciccone-aderisce-a-cambiamo\/","name":"Pofi: anche il vice di Ciccone aderisce a 'Cambiamo' - IlCorriereDellaProvincia.it - News h24 e notizie di approfondimento","isPartOf":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2019\/11\/09\/pofi-anche-il-vice-di-ciccone-aderisce-a-cambiamo\/#primaryimage"},"image":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2019\/11\/09\/pofi-anche-il-vice-di-ciccone-aderisce-a-cambiamo\/#primaryimage"},"thumbnailUrl":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2019\/11\/piero-de-nardis-pofi-e1573327654359.jpg","datePublished":"2019-11-09T19:28:37+00:00","description":"Il vicesindaco di Pofi, Piero De Nardis, ha lasciato Forza Italia e ha aderito a 'Cambiamo', il movimento di Giovanni Toti. Lo comunica in una nota","breadcrumb":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2019\/11\/09\/pofi-anche-il-vice-di-ciccone-aderisce-a-cambiamo\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2019\/11\/09\/pofi-anche-il-vice-di-ciccone-aderisce-a-cambiamo\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2019\/11\/09\/pofi-anche-il-vice-di-ciccone-aderisce-a-cambiamo\/#primaryimage","url":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2019\/11\/piero-de-nardis-pofi-e1573327654359.jpg","contentUrl":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2019\/11\/piero-de-nardis-pofi-e1573327654359.jpg","width":632,"height":450,"caption":"Il vicesindaco di Pofi Piero De Nardis"},{"@type":"BreadcrumbList","@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2019\/11\/09\/pofi-anche-il-vice-di-ciccone-aderisce-a-cambiamo\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/"},{"@type":"ListItem","position":2,"name":"Pofi: anche il vice di Ciccone aderisce a &#8216;Cambiamo&#8217;"}]},{"@type":"WebSite","@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/#website","url":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/","name":"Il Corriere Delle Provincia","description":"IlCorriereDellaProvincia.it, quotidiano web di politica, cronaca, inchiesta, lavoro, scuola, turismo, cultura e spettacolo, economia e finanza, salute e benessere. Approfondimenti e notizie aggiornate con foto e video della provincia di Frosinone ma anche news nazionali, dell\u2019Italia e del Mondo.","publisher":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":["Organization","Place"],"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/#organization","name":"Globalpress s.r.l.","url":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/","logo":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2019\/11\/09\/pofi-anche-il-vice-di-ciccone-aderisce-a-cambiamo\/#local-main-organization-logo"},"image":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2019\/11\/09\/pofi-anche-il-vice-di-ciccone-aderisce-a-cambiamo\/#local-main-organization-logo"},"telephone":[],"openingHoursSpecification":[{"@type":"OpeningHoursSpecification","dayOfWeek":["Monday","Tuesday","Wednesday","Thursday","Friday","Saturday","Sunday"],"opens":"09:00","closes":"17:00"}]},{"@type":"Person","@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/#\/schema\/person\/6d7f0a9120d0c03d0c552e9fdf49ed7d","name":"Redazione","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/secure.gravatar.com\/avatar\/a40eeacccdcad861f831dde73317f63a542e738f0dc4b79b9f47062d3d4bd1d2?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/a40eeacccdcad861f831dde73317f63a542e738f0dc4b79b9f47062d3d4bd1d2?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/a40eeacccdcad861f831dde73317f63a542e738f0dc4b79b9f47062d3d4bd1d2?s=96&d=mm&r=g","caption":"Redazione"},"description":"SEGUICI ANCHE SUI SOCIAL Facebook: TuNews24 e TuSport24 Instagram: TuNews24 e TuSport24 Youtube: TuNews24 Telegram: TuNews24 Puoi leggerci anche in formato cartaceo: il settimanale viene pubblicato e distribuito gratuitamente ogni venerd\u00ec in edicole, bar, centri commerciali e svariati esercizi. Ma \u00e8 possibile anche sfogliarlo comodamente online, cliccando su TU NEWS sfogliabile TU NEWS, PASSIONE PER L\u2019INFORMAZIONE","sameAs":["http:\/\/www.tunews24.it","www.facebook.com\/tunews24"],"url":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/author\/senzafirma\/"},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2019\/11\/09\/pofi-anche-il-vice-di-ciccone-aderisce-a-cambiamo\/#local-main-organization-logo","url":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2022\/11\/cropped-il-corriere-della-provincia-testata-web-scontornata.png","contentUrl":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2022\/11\/cropped-il-corriere-della-provincia-testata-web-scontornata.png","width":2911,"height":717,"caption":"Globalpress s.r.l."}]}},"_links":{"self":[{"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/posts\/21853","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/users\/18"}],"replies":[{"embeddable":true,"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/comments?post=21853"}],"version-history":[{"count":1,"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/posts\/21853\/revisions"}],"predecessor-version":[{"id":21856,"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/posts\/21853\/revisions\/21856"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/media\/21855"}],"wp:attachment":[{"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/media?parent=21853"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/categories?post=21853"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/tags?post=21853"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}