{"id":21811,"date":"2019-11-09T10:21:35","date_gmt":"2019-11-09T09:21:35","guid":{"rendered":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/?p=21811"},"modified":"2019-11-10T20:32:25","modified_gmt":"2019-11-10T19:32:25","slug":"cinghiali-coldiretti-manifestazione-roma-frosinone","status":"publish","type":"post","link":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2019\/11\/09\/cinghiali-coldiretti-manifestazione-roma-frosinone\/","title":{"rendered":"#Bastacinghiali, Coldiretti Frosinone in piazza a Roma"},"content":{"rendered":"<p><strong>L\u2019emergenza cinghiali \u00e8 arrivata a Piazza Montecitorio.<\/strong> Migliaia tra agricoltori, allevatori, cittadini,\u00a0esponenti istituzionali ,ambientalisti , sindacalisti e associazioni \u00a0da tutte le regioni\u00a0d\u2019Italia . \u00c8 stata la pi\u00f9 grande manifestazione mai realizzata prima a Roma contro l\u2019invasione dei cinghiali\u00a0e degli animali selvatici. <strong>C&#8217;era anche una folta delegazione della provincia di Frosinone.<\/strong><\/p>\n<p>&nbsp;<\/p>\n<h2><\/h2>\n<h2><img loading=\"lazy\" decoding=\"async\" class=\"wp-image-21815 aligncenter\" src=\"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2019\/11\/cinghiali-coldiretti.jpg\" alt=\"cinghiali emergenza coldiretti\" width=\"632\" height=\"474\" srcset=\"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2019\/11\/cinghiali-coldiretti.jpg 1024w, https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2019\/11\/cinghiali-coldiretti-300x225.jpg 300w, https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2019\/11\/cinghiali-coldiretti-768x576.jpg 768w, https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2019\/11\/cinghiali-coldiretti-500x375.jpg 500w\" sizes=\"auto, (max-width: 632px) 100vw, 632px\" \/><\/h2>\n<h2><\/h2>\n<h2>Le parole di Prandini<\/h2>\n<p>\u2018\u2019Ormai la maggioranza degli italiani considera l\u2019eccessiva presenza degli animali selvatici come\u00a0una vera e propria emergenza che incide sulla sicurezza delle persone oltre che sull\u2019economia e\u00a0sul lavoro, specie nelle zone pi\u00f9 svantaggiate\u201d<strong> ha denunciato il presidente di Coldiretti<\/strong> Ettore\u00a0Prandini .\u00a0Per sensibilizzare l\u2019opinione pubblica sulla gravit\u00e0 del problema , gli agricoltori della Coldiretti\u00a0hanno provocatoriamente portato in piazza Montecitorio un pentolone gigante di polenta e\u00a0spezzatino di cinghiale, oltre a cartelli con le foto degli incidenti provocati sulle strade e dei danni\u00a0nelle campagne.\u00a0Non solo , nella moltitudine di persone davanti al Parlamento protagonisti sono stati i cartelli con le\u00a0scritte &#8216;Difendiamo il nostro territorio&#8217; , &#8216;Basta danni , basta paura, fate qualcosa. Adesso&#8217;, &#8216;Il\u00a0cinghiale ci piace , ma solo con la polenta&#8217; e #bastacinghiali che ben hanno esemplificato lo spirito\u00a0della giornata .<\/p>\n<h2><img loading=\"lazy\" decoding=\"async\" class=\"wp-image-21813 aligncenter\" src=\"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2019\/11\/picchi-coldiretti-scaccia.jpg\" alt=\"picchi coldiretti scaccia cinghiali\" width=\"632\" height=\"474\" srcset=\"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2019\/11\/picchi-coldiretti-scaccia.jpg 1600w, https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2019\/11\/picchi-coldiretti-scaccia-300x225.jpg 300w, https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2019\/11\/picchi-coldiretti-scaccia-768x576.jpg 768w, https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2019\/11\/picchi-coldiretti-scaccia-1024x768.jpg 1024w, https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2019\/11\/picchi-coldiretti-scaccia-500x375.jpg 500w\" sizes=\"auto, (max-width: 632px) 100vw, 632px\" \/><\/h2>\n<h2><\/h2>\n<h2>La Ciociaria in prima linea<\/h2>\n<p><strong>Coldiretti Frosinone ha voluto esserci portando con s\u00e9 grazie al Comune di Frosinone il gonfalone\u00a0<\/strong><strong>della citt\u00e0<\/strong> , nonch\u00e9 numerosi esponenti delle istituzioni locali ,<strong> in foto assieme al direttore Carlo\u00a0<\/strong><strong>Picchi e al segretario di zona Lucrezia Scaccia. \u00a0<\/strong><\/p>\n<h2><\/h2>\n<h2>L&#8217;intervento di Picchi<\/h2>\n<p>\u2018\u2019Davanti ad una tale emergenza , estesa a livello nazionale , che sta provocando abbandono delle\u00a0aree interne, problemi sociali, economici e ambientali con inevitabili riflessi sul paesaggio e sulle\u00a0produzioni , con incursioni dei cinghiali anche all\u2019interno delle citt\u00e0 che minacciano la sicurezza\u00a0delle persone , abbiamo voluto dimostrare ancora una volta ai cittadini , e non solo agli agricoltori ,\u00a0che le loro preoccupazioni sono le nostre preoccupazioni \u2018\u2019 <strong>ha dichiarato Carlo Picchi , direttore\u00a0<\/strong><strong>provinciale di Coldiretti Frosinone<\/strong> chiarendo l\u2019importanza di agire in modo concertato tra Ministeri \u00a0Regioni, Province e Comuni .<\/p>\n<h2><img loading=\"lazy\" decoding=\"async\" class=\"wp-image-21816 aligncenter\" src=\"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2019\/11\/coldiretti-difendiamo-territorio.jpg\" alt=\"\" width=\"632\" height=\"474\" srcset=\"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2019\/11\/coldiretti-difendiamo-territorio.jpg 960w, https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2019\/11\/coldiretti-difendiamo-territorio-300x225.jpg 300w, https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2019\/11\/coldiretti-difendiamo-territorio-768x576.jpg 768w, https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2019\/11\/coldiretti-difendiamo-territorio-500x375.jpg 500w\" sizes=\"auto, (max-width: 632px) 100vw, 632px\" \/><\/h2>\n<h2><\/h2>\n<h2>Le problematiche<\/h2>\n<p><strong>Dati Coldiretti alla mano in Italia ci sono diecimila incidenti stradali all\u2019anno causati da animali\u00a0selvatici<\/strong> . Nei primi nove mesi del 2019 sono stati 13 i morti . Ma si tratta solo della punta\u00a0dell\u2019iceberg perch\u00e9 molti non denunciano , scoraggiati dalle lungaggini burocratiche e dalle\u00a0condizioni poste dalle assicurazioni .\u00a0Per non parlare poi dei rischi connessi all\u2019agroalimentare. Proprio nei comuni sotto i 5mila abitanti\u00a0si concentra il 92 % delle produzioni tipiche nazionali : 270 dei 293 prodotti a denominazione di\u00a0origine DOP e IGP italiani riconosciuti dall\u2019 UE tra formaggi, oli extravergine di oliva, salumi e\u00a0prodotti a base di carne, vini, panetteria e pasticceria.\u00a0Un patrimonio conservato nel tempo dalle 279mila imprese agricole dei piccoli comuni , un tesoro\u00a0messo a rischio dall\u2019avanzata dei cinghiali , che sempre pi\u00f9 spesso in queste aree si spingono fin\u00a0dentro i cortili e sugli usci delle case, scorrazzando per le vie dei paesi o sui campi, nelle stalle e\u00a0nelle aziende agricole.<\/p>\n<h2><\/h2>\n<h2>Le parole di Savone<\/h2>\n<p>&#8220;Serve responsabilit\u00e0 nella difesa degli allevamenti, dei pastori e allevatori che \u2013<strong> ha sottolineato\u00a0<\/strong><strong>Vinicio Savo, presidente provinciale Coldiretti Frosinone<\/strong> \u2013 con coraggio continuano a presidiare\u00a0anche i territori pi\u00f9 isolati e a garantire la bellezza del paesaggio e il futuro del Made in Italy\u00a0agroalimentare. \u2018\u2019 Servono azioni concrete , misure efficaci \u2018\u2019 .<\/p>\n<h2><\/h2>\n<h2>L&#8217;appello al Governo<\/h2>\n<p>A conclusione della manifestazione , Prandini ha illustrato ai rappresentanti del Governo e del\u00a0Parlamento di tutti gli schieramenti presenti un pacchetto di misure da tradurre in un emendamento\u00a0alla legge di Bilancio. Il fine \u00e8 quello di semplificare le norme che consentano alle regioni <strong>di\u00a0mettere a punto piani per il contenimento dei cinghiali e della fauna selvatica<\/strong>. La norma che\u00a0assegna la competenza alle Regioni \u2013 ha detto il presidente di Coldiretti &#8211; \u00e8 fondamentale per dare\u00a0certezze alle imprese agricole e garantire il futuro agli agricoltori. Si deve andare oltre alla caccia\u00a0per dare risposte strutturali che consentano di ripristinare l\u2019equilibrio ambientale. Apprezziamo gli\u00a0impegni assunti dai parlamentari di tutti gli schieramenti nel sottolineare pero\u2019 che se le\u00a0commissioni parlamentari, dall\u2019Agricoltura all\u2019ambiente e alle Finanze, non voteranno il\u00a0provvedimento torneremo in piazza ma questa volta &#8211; ha concluso Prandini &#8211; non in modo cos\u00ec\u00a0pacifico perch\u00e9 siamo esasperati\u201d.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>L\u2019emergenza cinghiali \u00e8 arrivata a Piazza Montecitorio. Migliaia tra agricoltori, allevatori, cittadini,\u00a0esponenti istituzionali ,ambientalisti , sindacalisti e associazioni \u00a0da tutte<\/p>\n","protected":false},"author":18,"featured_media":21812,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[4,2236],"tags":[7128,2027,1375,2552,7130,7129,1898,277,1643],"class_list":["post-21811","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-primo-piano","category-attualita","tag-bastacinghiali","tag-carlo-picchi","tag-coldiretti","tag-emergenza","tag-ettore-prandini","tag-lucrezia-scaccia","tag-manifestazione","tag-roma","tag-vinicio-savone"],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v27.8 (Yoast SEO v27.8) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>#Bastacinghiali, Coldiretti Frosinone in piazza a Roma - IlCorriereDellaProvincia.it - News h24 e notizie di approfondimento<\/title>\n<meta name=\"description\" content=\"Frosinone ha voluto esserci portando con s\u00e9 grazie il gonfalonedella citt\u00e0. Presenti il direttore picchi e il presidente Savone\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2019\/11\/09\/cinghiali-coldiretti-manifestazione-roma-frosinone\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"#Bastacinghiali, Coldiretti Frosinone in piazza a Roma\" \/>\n<meta property=\"og:description\" content=\"Frosinone ha voluto esserci portando con s\u00e9 grazie il gonfalonedella citt\u00e0. Presenti il direttore picchi e il presidente Savone\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2019\/11\/09\/cinghiali-coldiretti-manifestazione-roma-frosinone\/\" \/>\n<meta property=\"og:site_name\" content=\"IlCorriereDellaProvincia.it - News h24 e notizie di approfondimento\" \/>\n<meta property=\"article:author\" content=\"www.facebook.com\/tunews24\" \/>\n<meta property=\"article:published_time\" content=\"2019-11-09T09:21:35+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2019-11-10T19:32:25+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2019\/11\/coldiretti-frosinone.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1600\" \/>\n\t<meta property=\"og:image:height\" content=\"1200\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Redazione\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"Redazione\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"3 minuti\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2019\\\/11\\\/09\\\/cinghiali-coldiretti-manifestazione-roma-frosinone\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2019\\\/11\\\/09\\\/cinghiali-coldiretti-manifestazione-roma-frosinone\\\/\"},\"author\":{\"name\":\"Redazione\",\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/#\\\/schema\\\/person\\\/6d7f0a9120d0c03d0c552e9fdf49ed7d\"},\"headline\":\"#Bastacinghiali, Coldiretti Frosinone in piazza a Roma\",\"datePublished\":\"2019-11-09T09:21:35+00:00\",\"dateModified\":\"2019-11-10T19:32:25+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2019\\\/11\\\/09\\\/cinghiali-coldiretti-manifestazione-roma-frosinone\\\/\"},\"wordCount\":698,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2019\\\/11\\\/09\\\/cinghiali-coldiretti-manifestazione-roma-frosinone\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2019\\\/11\\\/coldiretti-frosinone.jpg\",\"keywords\":[\"#Bastacinghiali\",\"carlo picchi\",\"coldiretti\",\"emergenza\",\"ettore prandini\",\"lucrezia scaccia\",\"manifestazione\",\"roma\",\"vinicio savone\"],\"articleSection\":[\"*PRIMO PIANO*\",\"Attualit\u00e0\"],\"inLanguage\":\"it-IT\",\"copyrightYear\":\"2019\",\"copyrightHolder\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/#organization\"}},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2019\\\/11\\\/09\\\/cinghiali-coldiretti-manifestazione-roma-frosinone\\\/\",\"url\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2019\\\/11\\\/09\\\/cinghiali-coldiretti-manifestazione-roma-frosinone\\\/\",\"name\":\"#Bastacinghiali, Coldiretti Frosinone in piazza a Roma - IlCorriereDellaProvincia.it - News h24 e notizie di approfondimento\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2019\\\/11\\\/09\\\/cinghiali-coldiretti-manifestazione-roma-frosinone\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2019\\\/11\\\/09\\\/cinghiali-coldiretti-manifestazione-roma-frosinone\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2019\\\/11\\\/coldiretti-frosinone.jpg\",\"datePublished\":\"2019-11-09T09:21:35+00:00\",\"dateModified\":\"2019-11-10T19:32:25+00:00\",\"description\":\"Frosinone ha voluto esserci portando con s\u00e9 grazie il gonfalonedella citt\u00e0. Presenti il direttore picchi e il presidente Savone\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2019\\\/11\\\/09\\\/cinghiali-coldiretti-manifestazione-roma-frosinone\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2019\\\/11\\\/09\\\/cinghiali-coldiretti-manifestazione-roma-frosinone\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2019\\\/11\\\/09\\\/cinghiali-coldiretti-manifestazione-roma-frosinone\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2019\\\/11\\\/coldiretti-frosinone.jpg\",\"contentUrl\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2019\\\/11\\\/coldiretti-frosinone.jpg\",\"width\":1600,\"height\":1200,\"caption\":\"coldiretti frosinone cinghiali picchi savone scaccia\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2019\\\/11\\\/09\\\/cinghiali-coldiretti-manifestazione-roma-frosinone\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"#Bastacinghiali, Coldiretti Frosinone in piazza a Roma\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/#website\",\"url\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/\",\"name\":\"Il Corriere Delle Provincia\",\"description\":\"IlCorriereDellaProvincia.it, quotidiano web di politica, cronaca, inchiesta, lavoro, scuola, turismo, cultura e spettacolo, economia e finanza, salute e benessere. Approfondimenti e notizie aggiornate con foto e video della provincia di Frosinone ma anche news nazionali, dell\u2019Italia e del Mondo.\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":[\"Organization\",\"Place\"],\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/#organization\",\"name\":\"Globalpress s.r.l.\",\"url\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/\",\"logo\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2019\\\/11\\\/09\\\/cinghiali-coldiretti-manifestazione-roma-frosinone\\\/#local-main-organization-logo\"},\"image\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2019\\\/11\\\/09\\\/cinghiali-coldiretti-manifestazione-roma-frosinone\\\/#local-main-organization-logo\"},\"telephone\":[],\"openingHoursSpecification\":[{\"@type\":\"OpeningHoursSpecification\",\"dayOfWeek\":[\"Monday\",\"Tuesday\",\"Wednesday\",\"Thursday\",\"Friday\",\"Saturday\",\"Sunday\"],\"opens\":\"09:00\",\"closes\":\"17:00\"}]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/#\\\/schema\\\/person\\\/6d7f0a9120d0c03d0c552e9fdf49ed7d\",\"name\":\"Redazione\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/a40eeacccdcad861f831dde73317f63a542e738f0dc4b79b9f47062d3d4bd1d2?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/a40eeacccdcad861f831dde73317f63a542e738f0dc4b79b9f47062d3d4bd1d2?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/a40eeacccdcad861f831dde73317f63a542e738f0dc4b79b9f47062d3d4bd1d2?s=96&d=mm&r=g\",\"caption\":\"Redazione\"},\"description\":\"SEGUICI ANCHE SUI SOCIAL Facebook: TuNews24 e TuSport24 Instagram: TuNews24 e TuSport24 Youtube: TuNews24 Telegram: TuNews24 Puoi leggerci anche in formato cartaceo: il settimanale viene pubblicato e distribuito gratuitamente ogni venerd\u00ec in edicole, bar, centri commerciali e svariati esercizi. Ma \u00e8 possibile anche sfogliarlo comodamente online, cliccando su TU NEWS sfogliabile TU NEWS, PASSIONE PER L\u2019INFORMAZIONE\",\"sameAs\":[\"http:\\\/\\\/www.tunews24.it\",\"www.facebook.com\\\/tunews24\"],\"url\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/author\\\/senzafirma\\\/\"},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2019\\\/11\\\/09\\\/cinghiali-coldiretti-manifestazione-roma-frosinone\\\/#local-main-organization-logo\",\"url\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2022\\\/11\\\/cropped-il-corriere-della-provincia-testata-web-scontornata.png\",\"contentUrl\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2022\\\/11\\\/cropped-il-corriere-della-provincia-testata-web-scontornata.png\",\"width\":2911,\"height\":717,\"caption\":\"Globalpress s.r.l.\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"#Bastacinghiali, Coldiretti Frosinone in piazza a Roma - IlCorriereDellaProvincia.it - News h24 e notizie di approfondimento","description":"Frosinone ha voluto esserci portando con s\u00e9 grazie il gonfalonedella citt\u00e0. Presenti il direttore picchi e il presidente Savone","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2019\/11\/09\/cinghiali-coldiretti-manifestazione-roma-frosinone\/","og_locale":"it_IT","og_type":"article","og_title":"#Bastacinghiali, Coldiretti Frosinone in piazza a Roma","og_description":"Frosinone ha voluto esserci portando con s\u00e9 grazie il gonfalonedella citt\u00e0. Presenti il direttore picchi e il presidente Savone","og_url":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2019\/11\/09\/cinghiali-coldiretti-manifestazione-roma-frosinone\/","og_site_name":"IlCorriereDellaProvincia.it - News h24 e notizie di approfondimento","article_author":"www.facebook.com\/tunews24","article_published_time":"2019-11-09T09:21:35+00:00","article_modified_time":"2019-11-10T19:32:25+00:00","og_image":[{"width":1600,"height":1200,"url":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2019\/11\/coldiretti-frosinone.jpg","type":"image\/jpeg"}],"author":"Redazione","twitter_card":"summary_large_image","twitter_misc":{"Scritto da":"Redazione","Tempo di lettura stimato":"3 minuti"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2019\/11\/09\/cinghiali-coldiretti-manifestazione-roma-frosinone\/#article","isPartOf":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2019\/11\/09\/cinghiali-coldiretti-manifestazione-roma-frosinone\/"},"author":{"name":"Redazione","@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/#\/schema\/person\/6d7f0a9120d0c03d0c552e9fdf49ed7d"},"headline":"#Bastacinghiali, Coldiretti Frosinone in piazza a Roma","datePublished":"2019-11-09T09:21:35+00:00","dateModified":"2019-11-10T19:32:25+00:00","mainEntityOfPage":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2019\/11\/09\/cinghiali-coldiretti-manifestazione-roma-frosinone\/"},"wordCount":698,"commentCount":0,"publisher":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/#organization"},"image":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2019\/11\/09\/cinghiali-coldiretti-manifestazione-roma-frosinone\/#primaryimage"},"thumbnailUrl":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2019\/11\/coldiretti-frosinone.jpg","keywords":["#Bastacinghiali","carlo picchi","coldiretti","emergenza","ettore prandini","lucrezia scaccia","manifestazione","roma","vinicio savone"],"articleSection":["*PRIMO PIANO*","Attualit\u00e0"],"inLanguage":"it-IT","copyrightYear":"2019","copyrightHolder":{"@id":"https:\/\/www.tunews24.it\/#organization"}},{"@type":"WebPage","@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2019\/11\/09\/cinghiali-coldiretti-manifestazione-roma-frosinone\/","url":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2019\/11\/09\/cinghiali-coldiretti-manifestazione-roma-frosinone\/","name":"#Bastacinghiali, Coldiretti Frosinone in piazza a Roma - IlCorriereDellaProvincia.it - News h24 e notizie di approfondimento","isPartOf":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2019\/11\/09\/cinghiali-coldiretti-manifestazione-roma-frosinone\/#primaryimage"},"image":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2019\/11\/09\/cinghiali-coldiretti-manifestazione-roma-frosinone\/#primaryimage"},"thumbnailUrl":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2019\/11\/coldiretti-frosinone.jpg","datePublished":"2019-11-09T09:21:35+00:00","dateModified":"2019-11-10T19:32:25+00:00","description":"Frosinone ha voluto esserci portando con s\u00e9 grazie il gonfalonedella citt\u00e0. Presenti il direttore picchi e il presidente Savone","breadcrumb":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2019\/11\/09\/cinghiali-coldiretti-manifestazione-roma-frosinone\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2019\/11\/09\/cinghiali-coldiretti-manifestazione-roma-frosinone\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2019\/11\/09\/cinghiali-coldiretti-manifestazione-roma-frosinone\/#primaryimage","url":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2019\/11\/coldiretti-frosinone.jpg","contentUrl":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2019\/11\/coldiretti-frosinone.jpg","width":1600,"height":1200,"caption":"coldiretti frosinone cinghiali picchi savone scaccia"},{"@type":"BreadcrumbList","@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2019\/11\/09\/cinghiali-coldiretti-manifestazione-roma-frosinone\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/"},{"@type":"ListItem","position":2,"name":"#Bastacinghiali, Coldiretti Frosinone in piazza a Roma"}]},{"@type":"WebSite","@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/#website","url":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/","name":"Il Corriere Delle Provincia","description":"IlCorriereDellaProvincia.it, quotidiano web di politica, cronaca, inchiesta, lavoro, scuola, turismo, cultura e spettacolo, economia e finanza, salute e benessere. Approfondimenti e notizie aggiornate con foto e video della provincia di Frosinone ma anche news nazionali, dell\u2019Italia e del Mondo.","publisher":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":["Organization","Place"],"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/#organization","name":"Globalpress s.r.l.","url":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/","logo":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2019\/11\/09\/cinghiali-coldiretti-manifestazione-roma-frosinone\/#local-main-organization-logo"},"image":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2019\/11\/09\/cinghiali-coldiretti-manifestazione-roma-frosinone\/#local-main-organization-logo"},"telephone":[],"openingHoursSpecification":[{"@type":"OpeningHoursSpecification","dayOfWeek":["Monday","Tuesday","Wednesday","Thursday","Friday","Saturday","Sunday"],"opens":"09:00","closes":"17:00"}]},{"@type":"Person","@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/#\/schema\/person\/6d7f0a9120d0c03d0c552e9fdf49ed7d","name":"Redazione","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/secure.gravatar.com\/avatar\/a40eeacccdcad861f831dde73317f63a542e738f0dc4b79b9f47062d3d4bd1d2?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/a40eeacccdcad861f831dde73317f63a542e738f0dc4b79b9f47062d3d4bd1d2?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/a40eeacccdcad861f831dde73317f63a542e738f0dc4b79b9f47062d3d4bd1d2?s=96&d=mm&r=g","caption":"Redazione"},"description":"SEGUICI ANCHE SUI SOCIAL Facebook: TuNews24 e TuSport24 Instagram: TuNews24 e TuSport24 Youtube: TuNews24 Telegram: TuNews24 Puoi leggerci anche in formato cartaceo: il settimanale viene pubblicato e distribuito gratuitamente ogni venerd\u00ec in edicole, bar, centri commerciali e svariati esercizi. Ma \u00e8 possibile anche sfogliarlo comodamente online, cliccando su TU NEWS sfogliabile TU NEWS, PASSIONE PER L\u2019INFORMAZIONE","sameAs":["http:\/\/www.tunews24.it","www.facebook.com\/tunews24"],"url":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/author\/senzafirma\/"},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2019\/11\/09\/cinghiali-coldiretti-manifestazione-roma-frosinone\/#local-main-organization-logo","url":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2022\/11\/cropped-il-corriere-della-provincia-testata-web-scontornata.png","contentUrl":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2022\/11\/cropped-il-corriere-della-provincia-testata-web-scontornata.png","width":2911,"height":717,"caption":"Globalpress s.r.l."}]}},"_links":{"self":[{"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/posts\/21811","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/users\/18"}],"replies":[{"embeddable":true,"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/comments?post=21811"}],"version-history":[{"count":3,"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/posts\/21811\/revisions"}],"predecessor-version":[{"id":21819,"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/posts\/21811\/revisions\/21819"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/media\/21812"}],"wp:attachment":[{"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/media?parent=21811"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/categories?post=21811"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/tags?post=21811"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}