{"id":21788,"date":"2019-11-08T18:52:32","date_gmt":"2019-11-08T17:52:32","guid":{"rendered":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/?p=21788"},"modified":"2019-11-09T17:42:55","modified_gmt":"2019-11-09T16:42:55","slug":"frosinone-da-lunedi-targhe-alterne-e-stop-fino-a-euro-3","status":"publish","type":"post","link":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2019\/11\/08\/frosinone-da-lunedi-targhe-alterne-e-stop-fino-a-euro-3\/","title":{"rendered":"Frosinone, da luned\u00ec targhe alterne e stop fino a euro 3"},"content":{"rendered":"<p><strong>La Giunta Ottaviani ha deliberato<\/strong>, nella seduta settimanale, i provvedimenti per il risanamento della qualit\u00e0 dell\u2019aria, tra i quali gli interventi programmatici per la limitazione del traffico veicolare, per l\u2019anno 2019\/2020.<\/p>\n<h2><\/h2>\n<h2>Domeniche ecologiche e blocchi<\/h2>\n<p>Tra questi, \u00a0oltre all\u2019istituzione delle domeniche ecologiche <strong>(previste per le giornate del 17 e 24 novembre 2019, del 12 gennaio e del 16 febbraio 2020)<\/strong>, rientra l\u2019istituzione della circolazione a targhe alterne per i veicoli alimentati a benzina (con omologazione di categoria superiore ad euro 2) e diesel (con omologazione di categoria superiore a euro 3), dall\u201911 novembre 2019 al 27 marzo 2020, dalle 8.30 alle 13:00 e dalle 14:30 alle 22:00, <strong>per le giornate di luned\u00ec<\/strong> (circolazione consentita ai veicoli con targa dispari)<strong> e venerd\u00ec<\/strong> (circolazione consentita ai veicoli con targa pari).\u00a0In deroga, potranno circolare i veicoli a basso impatto ambientale, ovvero elettrici, ibridi, a metano, gpl e diesel dotati di filtro antiparticolato (FAP) con\u00a0omologazione di categoria superiore a euro 3; saranno esentati dai divieti i veicoli adibiti a pubblici servizi, a servizio di persone invalide quelli comunque autorizzati per esigenze speciali.<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"wp-image-21792 aligncenter\" src=\"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2019\/11\/smog-auto.jpg\" alt=\"\" width=\"632\" height=\"395\" srcset=\"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2019\/11\/smog-auto.jpg 712w, https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2019\/11\/smog-auto-300x188.jpg 300w, https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2019\/11\/smog-auto-500x313.jpg 500w\" sizes=\"auto, (max-width: 632px) 100vw, 632px\" \/><\/p>\n<h2><\/h2>\n<h2>Le strade interessate<\/h2>\n<div dir=\"ltr\">\n<p><strong>Gli interventi programmati per la limitazione del traffico veicolare avverranno nell&#8217;area urbana circoscritta dalle seguenti strade<\/strong>: da via Tiburtina, piazza Madonna della Neve, via Madonna della Neve, via Marco Tullio Cicerone (da incrocio con via Madonna della Neve), viale Volsci, via Simoncelli, via Vado del Tufo, viale Europa, via Marittima (da incrocio viale Europa), via Puccini, via Pasta, via Pier Luigi da Palestrina, via san Giuliano, via Vivaldi, via Verdi (da incrocio via Vivaldi), viale America Latina, via Marconi, via Fosse Ardeatine, via san Gerardo (senso unico in discesa), via don Buttarazzi, via Ferrarelli (da incrocio via don Buttarazzi), via Caio Mario, via Maria (da incrocio via Caio Mario) fino all&#8217;incrocio con via Tiburtina;\u00a0 limitatamente al tratto stradale di via Sacra Famiglia, uscita obbligata su via Pasta (sottopasso ferroviario); limitatamente a via Mascagni, \u00e8 vietato il transito sul tratto di piazza Pertini e di via Monteverdi in direzione piazza Kambo. Su tali strade la circolazione non \u00e8 assoggettata a restrizioni ed \u00e8 comunque consentito l&#8217;accesso di tutti i tipi di veicoli per raggiungere la pi\u00f9 vicina area destinata a parcheggio (da cui sar\u00e0 quindi possibile recarsi presso le varie zone del centro urbano mediante i servizi di trasporto pubblico), come piazza Salvo D&#8217;Acquisto, piazza Falcone e Borsellino (antistante la villa comunale), piazza Martiri delle Foibe (parcheggio Questura, in via Vado del Tufo).<\/p>\n<\/div>\n<h2><\/h2>\n<h2>Le interdizioni<\/h2>\n<div dir=\"ltr\">\n<p><strong>Dall\u2019 11 novembre 2019 al 31 marzo 2020<\/strong>, dalle ore 00,00 alle ore 24,00, \u00e8 prevista l\u2019interdizione della circolazione<strong> nelle zone sopra richiamate<\/strong> dei veicoli ad accensione spontanea (diesel) \u201cEuro 3\u201d. Sino al 31\/12\/2020 sono esentati i veicoli delle categorie innanzi specificati se di propriet\u00e0 di cittadini residenti a Frosinone, che possano dimostrare di non essere proprietari o di non avere familiari conviventi proprietari di autoveicoli ad accensione spontanea (diesel) superiori alla categoria \u201cEuro 3\u201d. Saranno altres\u00ec esentati dal divieto i veicoli adibiti a pubblici servizi, a servizio di persone invalide e quelli comunque autorizzati per esigenze speciali.<\/p>\n<p>&nbsp;<\/p>\n<p><strong>Dall\u2019 11 novembre 2019 al 31 marzo 2020,<\/strong> dalle ore 00,00 alle ore 24,00, \u00e8 istituita l\u2019interdizione della circolazione nelle zone sopra menzionate dei veicoli ad accensione comandata (benzina) \u201cEuro 2\u201d. <strong>Sino al 31\/12\/2020<\/strong> sono esentati i veicoli delle categorie innanzi specificati se di propriet\u00e0 di cittadini residenti a Frosinone, che possano dimostrare di non essere proprietari o di non avere familiari conviventi proprietari di autoveicoli ad accensione comandata (benzina) superiori alla categoria \u201cEuro 2\u201d. Saranno altres\u00ec esentati dai divieti i veicoli adibiti a pubblici servizi, a servizio di persone invalide e quelli comunque autorizzati per esigenze speciali.<\/p>\n<h2><\/h2>\n<h2>Stop ai mezzi pesanti<\/h2>\n<p>Prevista inoltre l\u2019Interdizione della circolazione nel centro urbano ai <strong>veicoli con massa complessiva superiore a 3,5 t.<\/strong>, dall\u201911 novembre 2019 al 31 marzo 2020, nelle fasce orarie dalle 7,30 alle 14,00 e dalle 16,30 alle 18,00 ad eccezione dei veicoli adibiti a pubblici servizi.<\/p>\n<p><strong>Istituito, nel medesimo periodo, l\u2019obbligo di spegnimento dei motori per i veicoli merci<\/strong> nella fase di carico\/scarico e per quelli adibiti al trasporto pubblico nelle aree di sosta e nei nodi di scambio.<\/p>\n<h2>Vietato accendere fuochi<\/h2>\n<p><strong>Dal 7 gennaio al 31 marzo 2020<\/strong> \u00e8 vietato accendere fuochi e\/o fal\u00f2, anche connessi all\u2019ordinaria pratica agricola, con la sola eccezione dei tralci di vite sottoposti ad abbruciamento con finalit\u00e0 antiparassitarie.<\/p>\n<p>&nbsp;<\/p>\n<h2>Norme sul riscaldamento<\/h2>\n<p>Dal\u201911 novembre 2019 al 31 marzo 2020, <strong>i limiti massimi di temperatura in ambiente chiuso dovranno essere pari a 20 C\u00b0<\/strong> in edifici ad uso residenziale, commerciale, direzionale o sedi di attivit\u00e0 sportive, ricreative e scolastiche; <strong>di 18 C\u00b0, invece, in edifici ad uso industriale, artigianale ed assimilabili.<\/strong> Per gli impianti di riscaldamento alimentati a gasolio o nafta, prevista la riduzione di due ore del periodo di accensione rispetto a quelli consentiti dalle norme del Decreto Presidente della Repubblica n. 412 del 1993. \u00c8 vietato, nello stesso periodo, l\u2019 uso di legna da ardere o biomasse per alimentare impianti di riscaldamento con potenza superiore a 35 KW, qualora esista la possibilit\u00e0 di utilizzare combustibili gassosi o GPL, con estensione della prescrizione di utilizzo di camini aperti e chiusi, stufe a legna, pellet e a biomassa in generale su tutto il territorio comunale, anche in tutte le abitazioni e alle attivit\u00e0 produttive provviste di rete del gas metano e di bomboloni GPL.<\/p>\n<p><strong>Il provvedimento \u00e8 valido sia per le utenze domestiche che per le attivit\u00e0 economiche e produttive<\/strong> solo per il riscaldamento degli ambienti. L\u2019Amministrazione si riserva, infine, il potere di intervenire con provvedimenti di interdizione del traffico veicolare, per singole zone o per l\u2019intero territorio comunale, nel caso di superamento dei limiti legali in materia di PM 10, PM 2,5 ed altre polveri sottili.<\/p>\n<\/div>\n","protected":false},"excerpt":{"rendered":"<p>La Giunta Ottaviani ha deliberato, nella seduta settimanale, i provvedimenti per il risanamento della qualit\u00e0 dell\u2019aria, tra i quali gli<\/p>\n","protected":false},"author":18,"featured_media":21789,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[4,2236],"tags":[7120,2087,2137,93,639,7121,922,526,461],"class_list":["post-21788","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-primo-piano","category-attualita","tag-cirocolazione","tag-domeniche-ecologiche","tag-euro-3","tag-frosinone","tag-nicola-ottaviani","tag-riscaldamenti","tag-smog","tag-targhe-alterne","tag-traffico"],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v27.8 (Yoast SEO v27.8) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Frosinone, da luned\u00ec targhe alterne e stop fino a euro 3 - IlCorriereDellaProvincia.it - News h24 e notizie di approfondimento<\/title>\n<meta name=\"description\" content=\"La giunta Ottaviani ha emanato una serie di divieti anche per quel che concerne l&#039;accensione dei fuochi e degli impianti di riscaldamento\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2019\/11\/08\/frosinone-da-lunedi-targhe-alterne-e-stop-fino-a-euro-3\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Frosinone, da luned\u00ec targhe alterne e stop fino a euro 3\" \/>\n<meta property=\"og:description\" content=\"La giunta Ottaviani ha emanato una serie di divieti anche per quel che concerne l&#039;accensione dei fuochi e degli impianti di riscaldamento\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2019\/11\/08\/frosinone-da-lunedi-targhe-alterne-e-stop-fino-a-euro-3\/\" \/>\n<meta property=\"og:site_name\" content=\"IlCorriereDellaProvincia.it - News h24 e notizie di approfondimento\" \/>\n<meta property=\"article:author\" content=\"www.facebook.com\/tunews24\" \/>\n<meta property=\"article:published_time\" content=\"2019-11-08T17:52:32+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2019-11-09T16:42:55+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2019\/11\/targhe-alterne.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"728\" \/>\n\t<meta property=\"og:image:height\" content=\"405\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Redazione\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"Redazione\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"4 minuti\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2019\\\/11\\\/08\\\/frosinone-da-lunedi-targhe-alterne-e-stop-fino-a-euro-3\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2019\\\/11\\\/08\\\/frosinone-da-lunedi-targhe-alterne-e-stop-fino-a-euro-3\\\/\"},\"author\":{\"name\":\"Redazione\",\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/#\\\/schema\\\/person\\\/6d7f0a9120d0c03d0c552e9fdf49ed7d\"},\"headline\":\"Frosinone, da luned\u00ec targhe alterne e stop fino a euro 3\",\"datePublished\":\"2019-11-08T17:52:32+00:00\",\"dateModified\":\"2019-11-09T16:42:55+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2019\\\/11\\\/08\\\/frosinone-da-lunedi-targhe-alterne-e-stop-fino-a-euro-3\\\/\"},\"wordCount\":911,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2019\\\/11\\\/08\\\/frosinone-da-lunedi-targhe-alterne-e-stop-fino-a-euro-3\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2019\\\/11\\\/targhe-alterne.jpg\",\"keywords\":[\"cirocolazione\",\"domeniche ecologiche\",\"euro 3\",\"Frosinone\",\"nicola ottaviani\",\"riscaldamenti\",\"Smog\",\"targhe alterne\",\"traffico\"],\"articleSection\":[\"*PRIMO PIANO*\",\"Attualit\u00e0\"],\"inLanguage\":\"it-IT\",\"copyrightYear\":\"2019\",\"copyrightHolder\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/#organization\"}},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2019\\\/11\\\/08\\\/frosinone-da-lunedi-targhe-alterne-e-stop-fino-a-euro-3\\\/\",\"url\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2019\\\/11\\\/08\\\/frosinone-da-lunedi-targhe-alterne-e-stop-fino-a-euro-3\\\/\",\"name\":\"Frosinone, da luned\u00ec targhe alterne e stop fino a euro 3 - IlCorriereDellaProvincia.it - News h24 e notizie di approfondimento\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2019\\\/11\\\/08\\\/frosinone-da-lunedi-targhe-alterne-e-stop-fino-a-euro-3\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2019\\\/11\\\/08\\\/frosinone-da-lunedi-targhe-alterne-e-stop-fino-a-euro-3\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2019\\\/11\\\/targhe-alterne.jpg\",\"datePublished\":\"2019-11-08T17:52:32+00:00\",\"dateModified\":\"2019-11-09T16:42:55+00:00\",\"description\":\"La giunta Ottaviani ha emanato una serie di divieti anche per quel che concerne l'accensione dei fuochi e degli impianti di riscaldamento\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2019\\\/11\\\/08\\\/frosinone-da-lunedi-targhe-alterne-e-stop-fino-a-euro-3\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2019\\\/11\\\/08\\\/frosinone-da-lunedi-targhe-alterne-e-stop-fino-a-euro-3\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2019\\\/11\\\/08\\\/frosinone-da-lunedi-targhe-alterne-e-stop-fino-a-euro-3\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2019\\\/11\\\/targhe-alterne.jpg\",\"contentUrl\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2019\\\/11\\\/targhe-alterne.jpg\",\"width\":728,\"height\":405,\"caption\":\"targhe alterne\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2019\\\/11\\\/08\\\/frosinone-da-lunedi-targhe-alterne-e-stop-fino-a-euro-3\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Frosinone, da luned\u00ec targhe alterne e stop fino a euro 3\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/#website\",\"url\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/\",\"name\":\"Il Corriere Delle Provincia\",\"description\":\"IlCorriereDellaProvincia.it, quotidiano web di politica, cronaca, inchiesta, lavoro, scuola, turismo, cultura e spettacolo, economia e finanza, salute e benessere. Approfondimenti e notizie aggiornate con foto e video della provincia di Frosinone ma anche news nazionali, dell\u2019Italia e del Mondo.\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":[\"Organization\",\"Place\"],\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/#organization\",\"name\":\"Globalpress s.r.l.\",\"url\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/\",\"logo\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2019\\\/11\\\/08\\\/frosinone-da-lunedi-targhe-alterne-e-stop-fino-a-euro-3\\\/#local-main-organization-logo\"},\"image\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2019\\\/11\\\/08\\\/frosinone-da-lunedi-targhe-alterne-e-stop-fino-a-euro-3\\\/#local-main-organization-logo\"},\"telephone\":[],\"openingHoursSpecification\":[{\"@type\":\"OpeningHoursSpecification\",\"dayOfWeek\":[\"Monday\",\"Tuesday\",\"Wednesday\",\"Thursday\",\"Friday\",\"Saturday\",\"Sunday\"],\"opens\":\"09:00\",\"closes\":\"17:00\"}]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/#\\\/schema\\\/person\\\/6d7f0a9120d0c03d0c552e9fdf49ed7d\",\"name\":\"Redazione\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/a40eeacccdcad861f831dde73317f63a542e738f0dc4b79b9f47062d3d4bd1d2?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/a40eeacccdcad861f831dde73317f63a542e738f0dc4b79b9f47062d3d4bd1d2?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/a40eeacccdcad861f831dde73317f63a542e738f0dc4b79b9f47062d3d4bd1d2?s=96&d=mm&r=g\",\"caption\":\"Redazione\"},\"description\":\"SEGUICI ANCHE SUI SOCIAL Facebook: TuNews24 e TuSport24 Instagram: TuNews24 e TuSport24 Youtube: TuNews24 Telegram: TuNews24 Puoi leggerci anche in formato cartaceo: il settimanale viene pubblicato e distribuito gratuitamente ogni venerd\u00ec in edicole, bar, centri commerciali e svariati esercizi. Ma \u00e8 possibile anche sfogliarlo comodamente online, cliccando su TU NEWS sfogliabile TU NEWS, PASSIONE PER L\u2019INFORMAZIONE\",\"sameAs\":[\"http:\\\/\\\/www.tunews24.it\",\"www.facebook.com\\\/tunews24\"],\"url\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/author\\\/senzafirma\\\/\"},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2019\\\/11\\\/08\\\/frosinone-da-lunedi-targhe-alterne-e-stop-fino-a-euro-3\\\/#local-main-organization-logo\",\"url\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2022\\\/11\\\/cropped-il-corriere-della-provincia-testata-web-scontornata.png\",\"contentUrl\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2022\\\/11\\\/cropped-il-corriere-della-provincia-testata-web-scontornata.png\",\"width\":2911,\"height\":717,\"caption\":\"Globalpress s.r.l.\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Frosinone, da luned\u00ec targhe alterne e stop fino a euro 3 - IlCorriereDellaProvincia.it - News h24 e notizie di approfondimento","description":"La giunta Ottaviani ha emanato una serie di divieti anche per quel che concerne l'accensione dei fuochi e degli impianti di riscaldamento","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2019\/11\/08\/frosinone-da-lunedi-targhe-alterne-e-stop-fino-a-euro-3\/","og_locale":"it_IT","og_type":"article","og_title":"Frosinone, da luned\u00ec targhe alterne e stop fino a euro 3","og_description":"La giunta Ottaviani ha emanato una serie di divieti anche per quel che concerne l'accensione dei fuochi e degli impianti di riscaldamento","og_url":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2019\/11\/08\/frosinone-da-lunedi-targhe-alterne-e-stop-fino-a-euro-3\/","og_site_name":"IlCorriereDellaProvincia.it - News h24 e notizie di approfondimento","article_author":"www.facebook.com\/tunews24","article_published_time":"2019-11-08T17:52:32+00:00","article_modified_time":"2019-11-09T16:42:55+00:00","og_image":[{"width":728,"height":405,"url":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2019\/11\/targhe-alterne.jpg","type":"image\/jpeg"}],"author":"Redazione","twitter_card":"summary_large_image","twitter_misc":{"Scritto da":"Redazione","Tempo di lettura stimato":"4 minuti"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2019\/11\/08\/frosinone-da-lunedi-targhe-alterne-e-stop-fino-a-euro-3\/#article","isPartOf":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2019\/11\/08\/frosinone-da-lunedi-targhe-alterne-e-stop-fino-a-euro-3\/"},"author":{"name":"Redazione","@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/#\/schema\/person\/6d7f0a9120d0c03d0c552e9fdf49ed7d"},"headline":"Frosinone, da luned\u00ec targhe alterne e stop fino a euro 3","datePublished":"2019-11-08T17:52:32+00:00","dateModified":"2019-11-09T16:42:55+00:00","mainEntityOfPage":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2019\/11\/08\/frosinone-da-lunedi-targhe-alterne-e-stop-fino-a-euro-3\/"},"wordCount":911,"commentCount":0,"publisher":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/#organization"},"image":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2019\/11\/08\/frosinone-da-lunedi-targhe-alterne-e-stop-fino-a-euro-3\/#primaryimage"},"thumbnailUrl":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2019\/11\/targhe-alterne.jpg","keywords":["cirocolazione","domeniche ecologiche","euro 3","Frosinone","nicola ottaviani","riscaldamenti","Smog","targhe alterne","traffico"],"articleSection":["*PRIMO PIANO*","Attualit\u00e0"],"inLanguage":"it-IT","copyrightYear":"2019","copyrightHolder":{"@id":"https:\/\/www.tunews24.it\/#organization"}},{"@type":"WebPage","@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2019\/11\/08\/frosinone-da-lunedi-targhe-alterne-e-stop-fino-a-euro-3\/","url":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2019\/11\/08\/frosinone-da-lunedi-targhe-alterne-e-stop-fino-a-euro-3\/","name":"Frosinone, da luned\u00ec targhe alterne e stop fino a euro 3 - IlCorriereDellaProvincia.it - News h24 e notizie di approfondimento","isPartOf":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2019\/11\/08\/frosinone-da-lunedi-targhe-alterne-e-stop-fino-a-euro-3\/#primaryimage"},"image":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2019\/11\/08\/frosinone-da-lunedi-targhe-alterne-e-stop-fino-a-euro-3\/#primaryimage"},"thumbnailUrl":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2019\/11\/targhe-alterne.jpg","datePublished":"2019-11-08T17:52:32+00:00","dateModified":"2019-11-09T16:42:55+00:00","description":"La giunta Ottaviani ha emanato una serie di divieti anche per quel che concerne l'accensione dei fuochi e degli impianti di riscaldamento","breadcrumb":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2019\/11\/08\/frosinone-da-lunedi-targhe-alterne-e-stop-fino-a-euro-3\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2019\/11\/08\/frosinone-da-lunedi-targhe-alterne-e-stop-fino-a-euro-3\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2019\/11\/08\/frosinone-da-lunedi-targhe-alterne-e-stop-fino-a-euro-3\/#primaryimage","url":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2019\/11\/targhe-alterne.jpg","contentUrl":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2019\/11\/targhe-alterne.jpg","width":728,"height":405,"caption":"targhe alterne"},{"@type":"BreadcrumbList","@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2019\/11\/08\/frosinone-da-lunedi-targhe-alterne-e-stop-fino-a-euro-3\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/"},{"@type":"ListItem","position":2,"name":"Frosinone, da luned\u00ec targhe alterne e stop fino a euro 3"}]},{"@type":"WebSite","@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/#website","url":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/","name":"Il Corriere Delle Provincia","description":"IlCorriereDellaProvincia.it, quotidiano web di politica, cronaca, inchiesta, lavoro, scuola, turismo, cultura e spettacolo, economia e finanza, salute e benessere. Approfondimenti e notizie aggiornate con foto e video della provincia di Frosinone ma anche news nazionali, dell\u2019Italia e del Mondo.","publisher":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":["Organization","Place"],"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/#organization","name":"Globalpress s.r.l.","url":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/","logo":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2019\/11\/08\/frosinone-da-lunedi-targhe-alterne-e-stop-fino-a-euro-3\/#local-main-organization-logo"},"image":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2019\/11\/08\/frosinone-da-lunedi-targhe-alterne-e-stop-fino-a-euro-3\/#local-main-organization-logo"},"telephone":[],"openingHoursSpecification":[{"@type":"OpeningHoursSpecification","dayOfWeek":["Monday","Tuesday","Wednesday","Thursday","Friday","Saturday","Sunday"],"opens":"09:00","closes":"17:00"}]},{"@type":"Person","@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/#\/schema\/person\/6d7f0a9120d0c03d0c552e9fdf49ed7d","name":"Redazione","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/secure.gravatar.com\/avatar\/a40eeacccdcad861f831dde73317f63a542e738f0dc4b79b9f47062d3d4bd1d2?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/a40eeacccdcad861f831dde73317f63a542e738f0dc4b79b9f47062d3d4bd1d2?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/a40eeacccdcad861f831dde73317f63a542e738f0dc4b79b9f47062d3d4bd1d2?s=96&d=mm&r=g","caption":"Redazione"},"description":"SEGUICI ANCHE SUI SOCIAL Facebook: TuNews24 e TuSport24 Instagram: TuNews24 e TuSport24 Youtube: TuNews24 Telegram: TuNews24 Puoi leggerci anche in formato cartaceo: il settimanale viene pubblicato e distribuito gratuitamente ogni venerd\u00ec in edicole, bar, centri commerciali e svariati esercizi. Ma \u00e8 possibile anche sfogliarlo comodamente online, cliccando su TU NEWS sfogliabile TU NEWS, PASSIONE PER L\u2019INFORMAZIONE","sameAs":["http:\/\/www.tunews24.it","www.facebook.com\/tunews24"],"url":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/author\/senzafirma\/"},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2019\/11\/08\/frosinone-da-lunedi-targhe-alterne-e-stop-fino-a-euro-3\/#local-main-organization-logo","url":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2022\/11\/cropped-il-corriere-della-provincia-testata-web-scontornata.png","contentUrl":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2022\/11\/cropped-il-corriere-della-provincia-testata-web-scontornata.png","width":2911,"height":717,"caption":"Globalpress s.r.l."}]}},"_links":{"self":[{"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/posts\/21788","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/users\/18"}],"replies":[{"embeddable":true,"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/comments?post=21788"}],"version-history":[{"count":3,"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/posts\/21788\/revisions"}],"predecessor-version":[{"id":21795,"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/posts\/21788\/revisions\/21795"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/media\/21789"}],"wp:attachment":[{"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/media?parent=21788"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/categories?post=21788"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/tags?post=21788"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}