{"id":21739,"date":"2019-11-08T14:46:56","date_gmt":"2019-11-08T13:46:56","guid":{"rendered":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/?p=21739"},"modified":"2019-11-08T16:16:52","modified_gmt":"2019-11-08T15:16:52","slug":"ferentino-ambiente-e-scuole-le-priorita-della-giunta-pompeo","status":"publish","type":"post","link":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2019\/11\/08\/ferentino-ambiente-e-scuole-le-priorita-della-giunta-pompeo\/","title":{"rendered":"Ferentino, ambiente e scuole le priorit\u00e0 della giunta Pompeo"},"content":{"rendered":"<p><strong>Il rispetto e la salvaguardia dell&#8217;ambiente,<\/strong> la manutenzione e la sicurezza delle scuole sono da sempre priorit\u00e0 nell&#8217;agenda dell&#8217;Amministrazione comunale di Ferentino, guidata dal sindaco Antonio Pompeo.<\/p>\n<h2><\/h2>\n<h2>Gli obiettivi<\/h2>\n<p>E anche l\u2019ultimo progetto, che riguarda un intervento di efficientamento energetico del &#8216;Plesso Scuola Capoluogo&#8217;, facente parte dell&#8217;Istituto Comprensivo 1, va esattamente in questa direzione. I lavori, che saranno realizzati grazie a un finanziamento di 130.000 euro, interamente erogato dal Ministero dello Sviluppo Economico nell&#8217;ambito del D.L. 34\/2019 &#8216;Misure urgenti di crescita economica e per la risoluzione di specifiche situazioni di crisi&#8217;, sono stati consegnati alla ditta incaricata.<\/p>\n<p>Tra gli obiettivi che saranno centrati con la realizzazione di questi lavori ci sono<strong> l&#8217;aumento del comfort abitativo della struttura, che ospita la scuola dell&#8217;infanzia e materna; il miglioramento delle prestazioni energetiche dell&#8217;edificio e, di conseguenza, la riduzione del tasso di CO2 nell&#8217;atmosfera.<\/strong><\/p>\n<p>In particolare, si tratta di opere di coibentazione del solaio di copertura dell&#8217;edificio che consentiranno di &#8216;impermeabilizzare&#8217; lo stabile e preservarlo da umidit\u00e0 e possibili infiltrazioni dovute alle avverse condizioni climatiche.<\/p>\n<h2><\/h2>\n<h2>Le parole del sindaco e dell&#8217;assessore<\/h2>\n<p>&#8220;L\u2019amministrazione comunale\u00a0\u2013<strong> sottolineano il sindaco Antonio Pompeo e l&#8217;assessore all&#8217;Istruzione e all&#8217;Ambiente, Evelina Di Marco<\/strong> \u2013\u00a0punta in maniera decisa sull&#8217;efficientamento energetico delle strutture, perch\u00e9 ci permette di avviare interventi che riqualificano gli immobili e li adeguano alle ultime normative, con un notevole risparmio sui consumi e le spese, contribuendo direttamente alla tutela dell\u2019ambiente. Un esempio di come il Comune punti continuamente sull&#8217;educazione e sul futuro dei giovani che saranno i cittadini di domani&#8221;.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Il rispetto e la salvaguardia dell&#8217;ambiente, la manutenzione e la sicurezza delle scuole sono da sempre priorit\u00e0 nell&#8217;agenda dell&#8217;Amministrazione comunale<\/p>\n","protected":false},"author":18,"featured_media":21586,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[28,38],"tags":[842,3452,92,129],"class_list":["post-21739","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-politica","category-scuola","tag-antonio-pompeo","tag-evelina-di-marco","tag-ferentino","tag-scuole"],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v27.8 (Yoast SEO v27.8) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Ferentino, ambiente e scuole le priorit\u00e0 della giunta Pompeo - IlCorriereDellaProvincia.it - News h24 e notizie di approfondimento<\/title>\n<meta name=\"description\" content=\"Aumento del comfort abitativo della struttura, che ospita la scuola dell&#039;infanzia e materna; il miglioramento delle prestazioni energetiche dell&#039;edificio\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2019\/11\/08\/ferentino-ambiente-e-scuole-le-priorita-della-giunta-pompeo\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Ferentino, ambiente e scuole le priorit\u00e0 della giunta Pompeo\" \/>\n<meta property=\"og:description\" content=\"Aumento del comfort abitativo della struttura, che ospita la scuola dell&#039;infanzia e materna; il miglioramento delle prestazioni energetiche dell&#039;edificio\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2019\/11\/08\/ferentino-ambiente-e-scuole-le-priorita-della-giunta-pompeo\/\" \/>\n<meta property=\"og:site_name\" content=\"IlCorriereDellaProvincia.it - News h24 e notizie di approfondimento\" \/>\n<meta property=\"article:author\" content=\"www.facebook.com\/tunews24\" \/>\n<meta property=\"article:published_time\" content=\"2019-11-08T13:46:56+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2019-11-08T15:16:52+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2019\/11\/antonio-pompeo-e1573057821875.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"632\" \/>\n\t<meta property=\"og:image:height\" content=\"422\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Redazione\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"Redazione\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2019\\\/11\\\/08\\\/ferentino-ambiente-e-scuole-le-priorita-della-giunta-pompeo\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2019\\\/11\\\/08\\\/ferentino-ambiente-e-scuole-le-priorita-della-giunta-pompeo\\\/\"},\"author\":{\"name\":\"Redazione\",\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/#\\\/schema\\\/person\\\/6d7f0a9120d0c03d0c552e9fdf49ed7d\"},\"headline\":\"Ferentino, ambiente e scuole le priorit\u00e0 della giunta Pompeo\",\"datePublished\":\"2019-11-08T13:46:56+00:00\",\"dateModified\":\"2019-11-08T15:16:52+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2019\\\/11\\\/08\\\/ferentino-ambiente-e-scuole-le-priorita-della-giunta-pompeo\\\/\"},\"wordCount\":276,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2019\\\/11\\\/08\\\/ferentino-ambiente-e-scuole-le-priorita-della-giunta-pompeo\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2019\\\/11\\\/antonio-pompeo-e1573057821875.jpg\",\"keywords\":[\"antonio pompeo\",\"Evelina Di Marco\",\"ferentino\",\"scuole\"],\"articleSection\":[\"Evidenza\",\"Scuola\"],\"inLanguage\":\"it-IT\",\"copyrightYear\":\"2019\",\"copyrightHolder\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/#organization\"}},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2019\\\/11\\\/08\\\/ferentino-ambiente-e-scuole-le-priorita-della-giunta-pompeo\\\/\",\"url\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2019\\\/11\\\/08\\\/ferentino-ambiente-e-scuole-le-priorita-della-giunta-pompeo\\\/\",\"name\":\"Ferentino, ambiente e scuole le priorit\u00e0 della giunta Pompeo - IlCorriereDellaProvincia.it - News h24 e notizie di approfondimento\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2019\\\/11\\\/08\\\/ferentino-ambiente-e-scuole-le-priorita-della-giunta-pompeo\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2019\\\/11\\\/08\\\/ferentino-ambiente-e-scuole-le-priorita-della-giunta-pompeo\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2019\\\/11\\\/antonio-pompeo-e1573057821875.jpg\",\"datePublished\":\"2019-11-08T13:46:56+00:00\",\"dateModified\":\"2019-11-08T15:16:52+00:00\",\"description\":\"Aumento del comfort abitativo della struttura, che ospita la scuola dell'infanzia e materna; il miglioramento delle prestazioni energetiche dell'edificio\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2019\\\/11\\\/08\\\/ferentino-ambiente-e-scuole-le-priorita-della-giunta-pompeo\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2019\\\/11\\\/08\\\/ferentino-ambiente-e-scuole-le-priorita-della-giunta-pompeo\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2019\\\/11\\\/08\\\/ferentino-ambiente-e-scuole-le-priorita-della-giunta-pompeo\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2019\\\/11\\\/antonio-pompeo-e1573057821875.jpg\",\"contentUrl\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2019\\\/11\\\/antonio-pompeo-e1573057821875.jpg\",\"width\":632,\"height\":422,\"caption\":\"Il presidente della Provincia di Frosinone e presidente di Upi Lazio, Antonio Pompeo\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2019\\\/11\\\/08\\\/ferentino-ambiente-e-scuole-le-priorita-della-giunta-pompeo\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Ferentino, ambiente e scuole le priorit\u00e0 della giunta Pompeo\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/#website\",\"url\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/\",\"name\":\"Il Corriere Delle Provincia\",\"description\":\"IlCorriereDellaProvincia.it, quotidiano web di politica, cronaca, inchiesta, lavoro, scuola, turismo, cultura e spettacolo, economia e finanza, salute e benessere. Approfondimenti e notizie aggiornate con foto e video della provincia di Frosinone ma anche news nazionali, dell\u2019Italia e del Mondo.\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":[\"Organization\",\"Place\"],\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/#organization\",\"name\":\"Globalpress s.r.l.\",\"url\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/\",\"logo\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2019\\\/11\\\/08\\\/ferentino-ambiente-e-scuole-le-priorita-della-giunta-pompeo\\\/#local-main-organization-logo\"},\"image\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2019\\\/11\\\/08\\\/ferentino-ambiente-e-scuole-le-priorita-della-giunta-pompeo\\\/#local-main-organization-logo\"},\"telephone\":[],\"openingHoursSpecification\":[{\"@type\":\"OpeningHoursSpecification\",\"dayOfWeek\":[\"Monday\",\"Tuesday\",\"Wednesday\",\"Thursday\",\"Friday\",\"Saturday\",\"Sunday\"],\"opens\":\"09:00\",\"closes\":\"17:00\"}]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/#\\\/schema\\\/person\\\/6d7f0a9120d0c03d0c552e9fdf49ed7d\",\"name\":\"Redazione\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/a40eeacccdcad861f831dde73317f63a542e738f0dc4b79b9f47062d3d4bd1d2?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/a40eeacccdcad861f831dde73317f63a542e738f0dc4b79b9f47062d3d4bd1d2?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/a40eeacccdcad861f831dde73317f63a542e738f0dc4b79b9f47062d3d4bd1d2?s=96&d=mm&r=g\",\"caption\":\"Redazione\"},\"description\":\"SEGUICI ANCHE SUI SOCIAL Facebook: TuNews24 e TuSport24 Instagram: TuNews24 e TuSport24 Youtube: TuNews24 Telegram: TuNews24 Puoi leggerci anche in formato cartaceo: il settimanale viene pubblicato e distribuito gratuitamente ogni venerd\u00ec in edicole, bar, centri commerciali e svariati esercizi. Ma \u00e8 possibile anche sfogliarlo comodamente online, cliccando su TU NEWS sfogliabile TU NEWS, PASSIONE PER L\u2019INFORMAZIONE\",\"sameAs\":[\"http:\\\/\\\/www.tunews24.it\",\"www.facebook.com\\\/tunews24\"],\"url\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/author\\\/senzafirma\\\/\"},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2019\\\/11\\\/08\\\/ferentino-ambiente-e-scuole-le-priorita-della-giunta-pompeo\\\/#local-main-organization-logo\",\"url\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2022\\\/11\\\/cropped-il-corriere-della-provincia-testata-web-scontornata.png\",\"contentUrl\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2022\\\/11\\\/cropped-il-corriere-della-provincia-testata-web-scontornata.png\",\"width\":2911,\"height\":717,\"caption\":\"Globalpress s.r.l.\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Ferentino, ambiente e scuole le priorit\u00e0 della giunta Pompeo - IlCorriereDellaProvincia.it - News h24 e notizie di approfondimento","description":"Aumento del comfort abitativo della struttura, che ospita la scuola dell'infanzia e materna; il miglioramento delle prestazioni energetiche dell'edificio","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2019\/11\/08\/ferentino-ambiente-e-scuole-le-priorita-della-giunta-pompeo\/","og_locale":"it_IT","og_type":"article","og_title":"Ferentino, ambiente e scuole le priorit\u00e0 della giunta Pompeo","og_description":"Aumento del comfort abitativo della struttura, che ospita la scuola dell'infanzia e materna; il miglioramento delle prestazioni energetiche dell'edificio","og_url":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2019\/11\/08\/ferentino-ambiente-e-scuole-le-priorita-della-giunta-pompeo\/","og_site_name":"IlCorriereDellaProvincia.it - News h24 e notizie di approfondimento","article_author":"www.facebook.com\/tunews24","article_published_time":"2019-11-08T13:46:56+00:00","article_modified_time":"2019-11-08T15:16:52+00:00","og_image":[{"width":632,"height":422,"url":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2019\/11\/antonio-pompeo-e1573057821875.jpg","type":"image\/jpeg"}],"author":"Redazione","twitter_card":"summary_large_image","twitter_misc":{"Scritto da":"Redazione","Tempo di lettura stimato":"1 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2019\/11\/08\/ferentino-ambiente-e-scuole-le-priorita-della-giunta-pompeo\/#article","isPartOf":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2019\/11\/08\/ferentino-ambiente-e-scuole-le-priorita-della-giunta-pompeo\/"},"author":{"name":"Redazione","@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/#\/schema\/person\/6d7f0a9120d0c03d0c552e9fdf49ed7d"},"headline":"Ferentino, ambiente e scuole le priorit\u00e0 della giunta Pompeo","datePublished":"2019-11-08T13:46:56+00:00","dateModified":"2019-11-08T15:16:52+00:00","mainEntityOfPage":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2019\/11\/08\/ferentino-ambiente-e-scuole-le-priorita-della-giunta-pompeo\/"},"wordCount":276,"commentCount":0,"publisher":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/#organization"},"image":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2019\/11\/08\/ferentino-ambiente-e-scuole-le-priorita-della-giunta-pompeo\/#primaryimage"},"thumbnailUrl":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2019\/11\/antonio-pompeo-e1573057821875.jpg","keywords":["antonio pompeo","Evelina Di Marco","ferentino","scuole"],"articleSection":["Evidenza","Scuola"],"inLanguage":"it-IT","copyrightYear":"2019","copyrightHolder":{"@id":"https:\/\/www.tunews24.it\/#organization"}},{"@type":"WebPage","@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2019\/11\/08\/ferentino-ambiente-e-scuole-le-priorita-della-giunta-pompeo\/","url":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2019\/11\/08\/ferentino-ambiente-e-scuole-le-priorita-della-giunta-pompeo\/","name":"Ferentino, ambiente e scuole le priorit\u00e0 della giunta Pompeo - IlCorriereDellaProvincia.it - News h24 e notizie di approfondimento","isPartOf":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2019\/11\/08\/ferentino-ambiente-e-scuole-le-priorita-della-giunta-pompeo\/#primaryimage"},"image":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2019\/11\/08\/ferentino-ambiente-e-scuole-le-priorita-della-giunta-pompeo\/#primaryimage"},"thumbnailUrl":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2019\/11\/antonio-pompeo-e1573057821875.jpg","datePublished":"2019-11-08T13:46:56+00:00","dateModified":"2019-11-08T15:16:52+00:00","description":"Aumento del comfort abitativo della struttura, che ospita la scuola dell'infanzia e materna; il miglioramento delle prestazioni energetiche dell'edificio","breadcrumb":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2019\/11\/08\/ferentino-ambiente-e-scuole-le-priorita-della-giunta-pompeo\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2019\/11\/08\/ferentino-ambiente-e-scuole-le-priorita-della-giunta-pompeo\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2019\/11\/08\/ferentino-ambiente-e-scuole-le-priorita-della-giunta-pompeo\/#primaryimage","url":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2019\/11\/antonio-pompeo-e1573057821875.jpg","contentUrl":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2019\/11\/antonio-pompeo-e1573057821875.jpg","width":632,"height":422,"caption":"Il presidente della Provincia di Frosinone e presidente di Upi Lazio, Antonio Pompeo"},{"@type":"BreadcrumbList","@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2019\/11\/08\/ferentino-ambiente-e-scuole-le-priorita-della-giunta-pompeo\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/"},{"@type":"ListItem","position":2,"name":"Ferentino, ambiente e scuole le priorit\u00e0 della giunta Pompeo"}]},{"@type":"WebSite","@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/#website","url":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/","name":"Il Corriere Delle Provincia","description":"IlCorriereDellaProvincia.it, quotidiano web di politica, cronaca, inchiesta, lavoro, scuola, turismo, cultura e spettacolo, economia e finanza, salute e benessere. Approfondimenti e notizie aggiornate con foto e video della provincia di Frosinone ma anche news nazionali, dell\u2019Italia e del Mondo.","publisher":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":["Organization","Place"],"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/#organization","name":"Globalpress s.r.l.","url":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/","logo":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2019\/11\/08\/ferentino-ambiente-e-scuole-le-priorita-della-giunta-pompeo\/#local-main-organization-logo"},"image":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2019\/11\/08\/ferentino-ambiente-e-scuole-le-priorita-della-giunta-pompeo\/#local-main-organization-logo"},"telephone":[],"openingHoursSpecification":[{"@type":"OpeningHoursSpecification","dayOfWeek":["Monday","Tuesday","Wednesday","Thursday","Friday","Saturday","Sunday"],"opens":"09:00","closes":"17:00"}]},{"@type":"Person","@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/#\/schema\/person\/6d7f0a9120d0c03d0c552e9fdf49ed7d","name":"Redazione","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/secure.gravatar.com\/avatar\/a40eeacccdcad861f831dde73317f63a542e738f0dc4b79b9f47062d3d4bd1d2?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/a40eeacccdcad861f831dde73317f63a542e738f0dc4b79b9f47062d3d4bd1d2?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/a40eeacccdcad861f831dde73317f63a542e738f0dc4b79b9f47062d3d4bd1d2?s=96&d=mm&r=g","caption":"Redazione"},"description":"SEGUICI ANCHE SUI SOCIAL Facebook: TuNews24 e TuSport24 Instagram: TuNews24 e TuSport24 Youtube: TuNews24 Telegram: TuNews24 Puoi leggerci anche in formato cartaceo: il settimanale viene pubblicato e distribuito gratuitamente ogni venerd\u00ec in edicole, bar, centri commerciali e svariati esercizi. Ma \u00e8 possibile anche sfogliarlo comodamente online, cliccando su TU NEWS sfogliabile TU NEWS, PASSIONE PER L\u2019INFORMAZIONE","sameAs":["http:\/\/www.tunews24.it","www.facebook.com\/tunews24"],"url":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/author\/senzafirma\/"},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2019\/11\/08\/ferentino-ambiente-e-scuole-le-priorita-della-giunta-pompeo\/#local-main-organization-logo","url":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2022\/11\/cropped-il-corriere-della-provincia-testata-web-scontornata.png","contentUrl":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2022\/11\/cropped-il-corriere-della-provincia-testata-web-scontornata.png","width":2911,"height":717,"caption":"Globalpress s.r.l."}]}},"_links":{"self":[{"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/posts\/21739","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/users\/18"}],"replies":[{"embeddable":true,"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/comments?post=21739"}],"version-history":[{"count":4,"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/posts\/21739\/revisions"}],"predecessor-version":[{"id":21743,"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/posts\/21739\/revisions\/21743"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/media\/21586"}],"wp:attachment":[{"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/media?parent=21739"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/categories?post=21739"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/tags?post=21739"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}