{"id":21727,"date":"2019-11-08T14:13:48","date_gmt":"2019-11-08T13:13:48","guid":{"rendered":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/?p=21727"},"modified":"2019-11-09T09:30:32","modified_gmt":"2019-11-09T08:30:32","slug":"anagni-vicolo-san-michele-e-piazza-innocenzo-iii-al-via-la-riqualificazione","status":"publish","type":"post","link":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2019\/11\/08\/anagni-vicolo-san-michele-e-piazza-innocenzo-iii-al-via-la-riqualificazione\/","title":{"rendered":"Anagni, vicolo San Michele e Piazza Innocenzo III: al via la riqualificazione"},"content":{"rendered":"<p><strong>Una Giunta particolarmente importante per la citt\u00e0 di Anagni quella di ieri mattina<\/strong>. Infatti \u00e8 stato approvato il progetto esecutivo per i lavori di manutenzione straordinaria dell&#8217;area adiacente Piazza Innocenzo III. Interessate dagli interventi di manutenzione saranno Vicolo San Michele e Piazza Innocenzo III con l&#8217;area sottostante.<\/p>\n<h2><\/h2>\n<h2>Le opere<\/h2>\n<p>I lavori prevedono la <strong>riparazione del muro di sostegno di Vicolo San Michele<\/strong> in due momenti: nella prima fase verranno rimosse le attuali puntellature e la rete metallica di protezione cos\u00ec da poter poi procedere alla esecuzione delle sottofondazioni, alla riparazione della fogna, all&#8217;eliminazione delle lesioni presenti, al restauro di paramento e copertina<strong> per poi ripristinare la superficie di sanpietrini.<\/strong> Nella seconda fase invece l&#8217;intervento centrale riguarder\u00e0 la realizzazione di una nuova fognatura. Spazio anche alle scalinate e murature superiori che saranno riportate a conveniente decoro.<\/p>\n<p><strong>A Piazza Innocenzo III e nell&#8217;area sottostante verr\u00e0 invece sostituita l&#8217;attuale pavimentazione con l&#8217;installazione di nuovi sanpietrini<\/strong> e blocchi in pietra lavica nella zona sottostante. Nell&#8217;ambito di questi importanti interventi \u00e8 prevista anche la realizzazione di servizi igienici semi-automatici cos\u00ec da poter rispondere alle richieste di cittadini e turisti di potenziare il servizio di bagni pubblici nelle vicinanze dei principali monumenti della citt\u00e0.<\/p>\n<p>&nbsp;<\/p>\n<figure id=\"attachment_7459\" aria-describedby=\"caption-attachment-7459\" style=\"width: 632px\" class=\"wp-caption aligncenter\"><img loading=\"lazy\" decoding=\"async\" class=\"wp-image-7459\" src=\"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2019\/03\/Daniele-Natalia-2.jpg\" alt=\"daniele natalia sindaco di anagni\" width=\"632\" height=\"540\" srcset=\"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2019\/03\/Daniele-Natalia-2.jpg 468w, https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2019\/03\/Daniele-Natalia-2-300x256.jpg 300w\" sizes=\"auto, (max-width: 632px) 100vw, 632px\" \/><figcaption id=\"caption-attachment-7459\" class=\"wp-caption-text\">Il sindaco di Anagni Daniele Natalia<\/figcaption><\/figure>\n<p>&nbsp;<\/p>\n<h2>Le parole del sindaco<\/h2>\n<p>&#8220;L&#8217;anno scorso, al momento del mio insediamento &#8211; ha affermato Daniele Natalia &#8211; informai assessori e consiglieri della mia intenzione di trovare una soluzione nel pi\u00f9 breve tempo possibile alla annosa questioni di Vicolo San Michele, colpevolmente abbandonato a s\u00e9 stesso nel corso degli anni, e dell&#8217;area sottostante Piazza Innocenzo III che \u00e8 stata, finora, un pessimo biglietto da visita per la nostra citt\u00e0. Una amministrazione che funziona e che ama Anagni aveva l&#8217;obbligo di mettere mano a due dei dossier pi\u00f9 importanti, la nostra ha preso di petto la situazione e di questo non posso che essere estremamente soddisfatto&#8221;.<\/p>\n<p>&nbsp;<\/p>\n<figure id=\"attachment_21729\" aria-describedby=\"caption-attachment-21729\" style=\"width: 632px\" class=\"wp-caption aligncenter\"><img loading=\"lazy\" decoding=\"async\" class=\"wp-image-21729\" src=\"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2019\/11\/cardinali-alessandro.jpg\" alt=\"\" width=\"632\" height=\"675\" srcset=\"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2019\/11\/cardinali-alessandro.jpg 365w, https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2019\/11\/cardinali-alessandro-281x300.jpg 281w\" sizes=\"auto, (max-width: 632px) 100vw, 632px\" \/><figcaption id=\"caption-attachment-21729\" class=\"wp-caption-text\">Alessandro Cardinali<\/figcaption><\/figure>\n<p>&nbsp;<\/p>\n<h2>L&#8217;intervento di Cardinali<\/h2>\n<p><strong>Sulla stessa linea d&#8217;onda il consigliere comunale subdelegato alla Manutenzione<\/strong> Alessandro Cardinali (FdI): &#8220;Consci del fatto che i residenti di Vicolo San Michele aspettavano da ormai troppo tempo di essere ascoltati dagli enti pubblici, ci siamo attivati per trovare finalmente una soluzione. La situazione di questo storico vicolo era indecente, uno schiaffo per la citt\u00e0, \u00e8 per questo che questi lavori sono stati programmati ed approvati dalla Giunta, per rispondere ai bisogni dei cittadini e per fare del decoro, della pulizia e della bellezza una cartina al tornasole per il nostro centro storico&#8221;.<\/p>\n<p><strong>I lavori di Vicolo San Michele e Piazza Innocenzo III approvati<\/strong> fanno parte di una pi\u00f9 ampia programmazione di interventi di manutenzione straordinaria promossi dall&#8217;amministrazione del sindaco Daniele Natalia e rispondono anche all&#8217;esigenza politica di rispettare il programma elettorale della coalizione di governo.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Una Giunta particolarmente importante per la citt\u00e0 di Anagni quella di ieri mattina. Infatti \u00e8 stato approvato il progetto esecutivo<\/p>\n","protected":false},"author":18,"featured_media":21728,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[2236],"tags":[5160,441,7102,7104,7103],"class_list":["post-21727","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-attualita","tag-alessandro-cardinali","tag-anagni","tag-daniele-datalia","tag-piazza-innocenzo-iii","tag-vicolo-san-michele"],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v27.8 (Yoast SEO v27.8) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Anagni, vicolo San Michele e Piazza Innocenzo III: al via la riqualificazione - IlCorriereDellaProvincia.it - News h24 e notizie di approfondimento<\/title>\n<meta name=\"description\" content=\"le oper fanno parte di una pi\u00f9 ampia programmazione di interventi di manutenzione straordinaria promossi dall&#039;amministrazione del sindaco Daniele Natalia\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2019\/11\/08\/anagni-vicolo-san-michele-e-piazza-innocenzo-iii-al-via-la-riqualificazione\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Anagni, vicolo San Michele e Piazza Innocenzo III: al via la riqualificazione\" \/>\n<meta property=\"og:description\" content=\"le oper fanno parte di una pi\u00f9 ampia programmazione di interventi di manutenzione straordinaria promossi dall&#039;amministrazione del sindaco Daniele Natalia\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2019\/11\/08\/anagni-vicolo-san-michele-e-piazza-innocenzo-iii-al-via-la-riqualificazione\/\" \/>\n<meta property=\"og:site_name\" content=\"IlCorriereDellaProvincia.it - News h24 e notizie di approfondimento\" \/>\n<meta property=\"article:author\" content=\"www.facebook.com\/tunews24\" \/>\n<meta property=\"article:published_time\" content=\"2019-11-08T13:13:48+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2019-11-09T08:30:32+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2019\/11\/anagni.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"800\" \/>\n\t<meta property=\"og:image:height\" content=\"548\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Redazione\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"Redazione\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minuti\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2019\\\/11\\\/08\\\/anagni-vicolo-san-michele-e-piazza-innocenzo-iii-al-via-la-riqualificazione\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2019\\\/11\\\/08\\\/anagni-vicolo-san-michele-e-piazza-innocenzo-iii-al-via-la-riqualificazione\\\/\"},\"author\":{\"name\":\"Redazione\",\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/#\\\/schema\\\/person\\\/6d7f0a9120d0c03d0c552e9fdf49ed7d\"},\"headline\":\"Anagni, vicolo San Michele e Piazza Innocenzo III: al via la riqualificazione\",\"datePublished\":\"2019-11-08T13:13:48+00:00\",\"dateModified\":\"2019-11-09T08:30:32+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2019\\\/11\\\/08\\\/anagni-vicolo-san-michele-e-piazza-innocenzo-iii-al-via-la-riqualificazione\\\/\"},\"wordCount\":490,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2019\\\/11\\\/08\\\/anagni-vicolo-san-michele-e-piazza-innocenzo-iii-al-via-la-riqualificazione\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2019\\\/11\\\/anagni.jpg\",\"keywords\":[\"alessandro cardinali\",\"anagni\",\"daniele datalia\",\"piazza innocenzo iii\",\"vicolo san michele\"],\"articleSection\":[\"Attualit\u00e0\"],\"inLanguage\":\"it-IT\",\"copyrightYear\":\"2019\",\"copyrightHolder\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/#organization\"}},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2019\\\/11\\\/08\\\/anagni-vicolo-san-michele-e-piazza-innocenzo-iii-al-via-la-riqualificazione\\\/\",\"url\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2019\\\/11\\\/08\\\/anagni-vicolo-san-michele-e-piazza-innocenzo-iii-al-via-la-riqualificazione\\\/\",\"name\":\"Anagni, vicolo San Michele e Piazza Innocenzo III: al via la riqualificazione - IlCorriereDellaProvincia.it - News h24 e notizie di approfondimento\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2019\\\/11\\\/08\\\/anagni-vicolo-san-michele-e-piazza-innocenzo-iii-al-via-la-riqualificazione\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2019\\\/11\\\/08\\\/anagni-vicolo-san-michele-e-piazza-innocenzo-iii-al-via-la-riqualificazione\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2019\\\/11\\\/anagni.jpg\",\"datePublished\":\"2019-11-08T13:13:48+00:00\",\"dateModified\":\"2019-11-09T08:30:32+00:00\",\"description\":\"le oper fanno parte di una pi\u00f9 ampia programmazione di interventi di manutenzione straordinaria promossi dall'amministrazione del sindaco Daniele Natalia\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2019\\\/11\\\/08\\\/anagni-vicolo-san-michele-e-piazza-innocenzo-iii-al-via-la-riqualificazione\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2019\\\/11\\\/08\\\/anagni-vicolo-san-michele-e-piazza-innocenzo-iii-al-via-la-riqualificazione\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2019\\\/11\\\/08\\\/anagni-vicolo-san-michele-e-piazza-innocenzo-iii-al-via-la-riqualificazione\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2019\\\/11\\\/anagni.jpg\",\"contentUrl\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2019\\\/11\\\/anagni.jpg\",\"width\":800,\"height\":548,\"caption\":\"anagni\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2019\\\/11\\\/08\\\/anagni-vicolo-san-michele-e-piazza-innocenzo-iii-al-via-la-riqualificazione\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Anagni, vicolo San Michele e Piazza Innocenzo III: al via la riqualificazione\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/#website\",\"url\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/\",\"name\":\"Il Corriere Delle Provincia\",\"description\":\"IlCorriereDellaProvincia.it, quotidiano web di politica, cronaca, inchiesta, lavoro, scuola, turismo, cultura e spettacolo, economia e finanza, salute e benessere. Approfondimenti e notizie aggiornate con foto e video della provincia di Frosinone ma anche news nazionali, dell\u2019Italia e del Mondo.\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":[\"Organization\",\"Place\"],\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/#organization\",\"name\":\"Globalpress s.r.l.\",\"url\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/\",\"logo\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2019\\\/11\\\/08\\\/anagni-vicolo-san-michele-e-piazza-innocenzo-iii-al-via-la-riqualificazione\\\/#local-main-organization-logo\"},\"image\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2019\\\/11\\\/08\\\/anagni-vicolo-san-michele-e-piazza-innocenzo-iii-al-via-la-riqualificazione\\\/#local-main-organization-logo\"},\"telephone\":[],\"openingHoursSpecification\":[{\"@type\":\"OpeningHoursSpecification\",\"dayOfWeek\":[\"Monday\",\"Tuesday\",\"Wednesday\",\"Thursday\",\"Friday\",\"Saturday\",\"Sunday\"],\"opens\":\"09:00\",\"closes\":\"17:00\"}]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/#\\\/schema\\\/person\\\/6d7f0a9120d0c03d0c552e9fdf49ed7d\",\"name\":\"Redazione\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/a40eeacccdcad861f831dde73317f63a542e738f0dc4b79b9f47062d3d4bd1d2?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/a40eeacccdcad861f831dde73317f63a542e738f0dc4b79b9f47062d3d4bd1d2?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/a40eeacccdcad861f831dde73317f63a542e738f0dc4b79b9f47062d3d4bd1d2?s=96&d=mm&r=g\",\"caption\":\"Redazione\"},\"description\":\"SEGUICI ANCHE SUI SOCIAL Facebook: TuNews24 e TuSport24 Instagram: TuNews24 e TuSport24 Youtube: TuNews24 Telegram: TuNews24 Puoi leggerci anche in formato cartaceo: il settimanale viene pubblicato e distribuito gratuitamente ogni venerd\u00ec in edicole, bar, centri commerciali e svariati esercizi. Ma \u00e8 possibile anche sfogliarlo comodamente online, cliccando su TU NEWS sfogliabile TU NEWS, PASSIONE PER L\u2019INFORMAZIONE\",\"sameAs\":[\"http:\\\/\\\/www.tunews24.it\",\"www.facebook.com\\\/tunews24\"],\"url\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/author\\\/senzafirma\\\/\"},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2019\\\/11\\\/08\\\/anagni-vicolo-san-michele-e-piazza-innocenzo-iii-al-via-la-riqualificazione\\\/#local-main-organization-logo\",\"url\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2022\\\/11\\\/cropped-il-corriere-della-provincia-testata-web-scontornata.png\",\"contentUrl\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2022\\\/11\\\/cropped-il-corriere-della-provincia-testata-web-scontornata.png\",\"width\":2911,\"height\":717,\"caption\":\"Globalpress s.r.l.\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Anagni, vicolo San Michele e Piazza Innocenzo III: al via la riqualificazione - IlCorriereDellaProvincia.it - News h24 e notizie di approfondimento","description":"le oper fanno parte di una pi\u00f9 ampia programmazione di interventi di manutenzione straordinaria promossi dall'amministrazione del sindaco Daniele Natalia","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2019\/11\/08\/anagni-vicolo-san-michele-e-piazza-innocenzo-iii-al-via-la-riqualificazione\/","og_locale":"it_IT","og_type":"article","og_title":"Anagni, vicolo San Michele e Piazza Innocenzo III: al via la riqualificazione","og_description":"le oper fanno parte di una pi\u00f9 ampia programmazione di interventi di manutenzione straordinaria promossi dall'amministrazione del sindaco Daniele Natalia","og_url":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2019\/11\/08\/anagni-vicolo-san-michele-e-piazza-innocenzo-iii-al-via-la-riqualificazione\/","og_site_name":"IlCorriereDellaProvincia.it - News h24 e notizie di approfondimento","article_author":"www.facebook.com\/tunews24","article_published_time":"2019-11-08T13:13:48+00:00","article_modified_time":"2019-11-09T08:30:32+00:00","og_image":[{"width":800,"height":548,"url":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2019\/11\/anagni.jpg","type":"image\/jpeg"}],"author":"Redazione","twitter_card":"summary_large_image","twitter_misc":{"Scritto da":"Redazione","Tempo di lettura stimato":"2 minuti"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2019\/11\/08\/anagni-vicolo-san-michele-e-piazza-innocenzo-iii-al-via-la-riqualificazione\/#article","isPartOf":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2019\/11\/08\/anagni-vicolo-san-michele-e-piazza-innocenzo-iii-al-via-la-riqualificazione\/"},"author":{"name":"Redazione","@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/#\/schema\/person\/6d7f0a9120d0c03d0c552e9fdf49ed7d"},"headline":"Anagni, vicolo San Michele e Piazza Innocenzo III: al via la riqualificazione","datePublished":"2019-11-08T13:13:48+00:00","dateModified":"2019-11-09T08:30:32+00:00","mainEntityOfPage":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2019\/11\/08\/anagni-vicolo-san-michele-e-piazza-innocenzo-iii-al-via-la-riqualificazione\/"},"wordCount":490,"commentCount":0,"publisher":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/#organization"},"image":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2019\/11\/08\/anagni-vicolo-san-michele-e-piazza-innocenzo-iii-al-via-la-riqualificazione\/#primaryimage"},"thumbnailUrl":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2019\/11\/anagni.jpg","keywords":["alessandro cardinali","anagni","daniele datalia","piazza innocenzo iii","vicolo san michele"],"articleSection":["Attualit\u00e0"],"inLanguage":"it-IT","copyrightYear":"2019","copyrightHolder":{"@id":"https:\/\/www.tunews24.it\/#organization"}},{"@type":"WebPage","@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2019\/11\/08\/anagni-vicolo-san-michele-e-piazza-innocenzo-iii-al-via-la-riqualificazione\/","url":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2019\/11\/08\/anagni-vicolo-san-michele-e-piazza-innocenzo-iii-al-via-la-riqualificazione\/","name":"Anagni, vicolo San Michele e Piazza Innocenzo III: al via la riqualificazione - IlCorriereDellaProvincia.it - News h24 e notizie di approfondimento","isPartOf":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2019\/11\/08\/anagni-vicolo-san-michele-e-piazza-innocenzo-iii-al-via-la-riqualificazione\/#primaryimage"},"image":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2019\/11\/08\/anagni-vicolo-san-michele-e-piazza-innocenzo-iii-al-via-la-riqualificazione\/#primaryimage"},"thumbnailUrl":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2019\/11\/anagni.jpg","datePublished":"2019-11-08T13:13:48+00:00","dateModified":"2019-11-09T08:30:32+00:00","description":"le oper fanno parte di una pi\u00f9 ampia programmazione di interventi di manutenzione straordinaria promossi dall'amministrazione del sindaco Daniele Natalia","breadcrumb":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2019\/11\/08\/anagni-vicolo-san-michele-e-piazza-innocenzo-iii-al-via-la-riqualificazione\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2019\/11\/08\/anagni-vicolo-san-michele-e-piazza-innocenzo-iii-al-via-la-riqualificazione\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2019\/11\/08\/anagni-vicolo-san-michele-e-piazza-innocenzo-iii-al-via-la-riqualificazione\/#primaryimage","url":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2019\/11\/anagni.jpg","contentUrl":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2019\/11\/anagni.jpg","width":800,"height":548,"caption":"anagni"},{"@type":"BreadcrumbList","@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2019\/11\/08\/anagni-vicolo-san-michele-e-piazza-innocenzo-iii-al-via-la-riqualificazione\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/"},{"@type":"ListItem","position":2,"name":"Anagni, vicolo San Michele e Piazza Innocenzo III: al via la riqualificazione"}]},{"@type":"WebSite","@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/#website","url":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/","name":"Il Corriere Delle Provincia","description":"IlCorriereDellaProvincia.it, quotidiano web di politica, cronaca, inchiesta, lavoro, scuola, turismo, cultura e spettacolo, economia e finanza, salute e benessere. Approfondimenti e notizie aggiornate con foto e video della provincia di Frosinone ma anche news nazionali, dell\u2019Italia e del Mondo.","publisher":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":["Organization","Place"],"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/#organization","name":"Globalpress s.r.l.","url":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/","logo":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2019\/11\/08\/anagni-vicolo-san-michele-e-piazza-innocenzo-iii-al-via-la-riqualificazione\/#local-main-organization-logo"},"image":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2019\/11\/08\/anagni-vicolo-san-michele-e-piazza-innocenzo-iii-al-via-la-riqualificazione\/#local-main-organization-logo"},"telephone":[],"openingHoursSpecification":[{"@type":"OpeningHoursSpecification","dayOfWeek":["Monday","Tuesday","Wednesday","Thursday","Friday","Saturday","Sunday"],"opens":"09:00","closes":"17:00"}]},{"@type":"Person","@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/#\/schema\/person\/6d7f0a9120d0c03d0c552e9fdf49ed7d","name":"Redazione","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/secure.gravatar.com\/avatar\/a40eeacccdcad861f831dde73317f63a542e738f0dc4b79b9f47062d3d4bd1d2?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/a40eeacccdcad861f831dde73317f63a542e738f0dc4b79b9f47062d3d4bd1d2?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/a40eeacccdcad861f831dde73317f63a542e738f0dc4b79b9f47062d3d4bd1d2?s=96&d=mm&r=g","caption":"Redazione"},"description":"SEGUICI ANCHE SUI SOCIAL Facebook: TuNews24 e TuSport24 Instagram: TuNews24 e TuSport24 Youtube: TuNews24 Telegram: TuNews24 Puoi leggerci anche in formato cartaceo: il settimanale viene pubblicato e distribuito gratuitamente ogni venerd\u00ec in edicole, bar, centri commerciali e svariati esercizi. Ma \u00e8 possibile anche sfogliarlo comodamente online, cliccando su TU NEWS sfogliabile TU NEWS, PASSIONE PER L\u2019INFORMAZIONE","sameAs":["http:\/\/www.tunews24.it","www.facebook.com\/tunews24"],"url":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/author\/senzafirma\/"},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2019\/11\/08\/anagni-vicolo-san-michele-e-piazza-innocenzo-iii-al-via-la-riqualificazione\/#local-main-organization-logo","url":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2022\/11\/cropped-il-corriere-della-provincia-testata-web-scontornata.png","contentUrl":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2022\/11\/cropped-il-corriere-della-provincia-testata-web-scontornata.png","width":2911,"height":717,"caption":"Globalpress s.r.l."}]}},"_links":{"self":[{"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/posts\/21727","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/users\/18"}],"replies":[{"embeddable":true,"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/comments?post=21727"}],"version-history":[{"count":1,"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/posts\/21727\/revisions"}],"predecessor-version":[{"id":21730,"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/posts\/21727\/revisions\/21730"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/media\/21728"}],"wp:attachment":[{"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/media?parent=21727"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/categories?post=21727"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/tags?post=21727"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}