{"id":20740,"date":"2019-10-23T16:40:00","date_gmt":"2019-10-23T14:40:00","guid":{"rendered":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/?p=20740"},"modified":"2019-10-23T16:40:00","modified_gmt":"2019-10-23T14:40:00","slug":"morto-lo-scienziato-lelio-orci-era-di-san-giovanni-incarico","status":"publish","type":"post","link":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2019\/10\/23\/morto-lo-scienziato-lelio-orci-era-di-san-giovanni-incarico\/","title":{"rendered":"Morto lo scienziato Lelio Orci. Era di San Giovanni Incarico"},"content":{"rendered":"<p>Noto in tutto il mondo per le sue scoperte nel settore della biologia cellulare e in particolare del diabete: <strong>\u00e8 morto ieri sera, a Ginevra, il professor Lelio Orci<\/strong>, scienziato italiano che per lungo tempo \u00e8 stato Direttore del Dipartimento di Morfologia dell\u2019Universit\u00e0 di Ginevra. <strong>Era originario di San Giovanni Incarico.<\/strong><\/p>\n<p>&nbsp;<\/p>\n<figure id=\"attachment_20741\" aria-describedby=\"caption-attachment-20741\" style=\"width: 200px\" class=\"wp-caption aligncenter\"><img loading=\"lazy\" decoding=\"async\" class=\"wp-image-20741 size-full\" src=\"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2019\/10\/lelio-orci.jpg\" alt=\"lelio orci san giovanni incarico il corriere della provincia\" width=\"200\" height=\"245\" \/><figcaption id=\"caption-attachment-20741\" class=\"wp-caption-text\">Lo scienziato Lelio Orci<\/figcaption><\/figure>\n<p>&nbsp;<\/p>\n<p>Dal 1984, la collaborazione tra Lelio Orci, <strong>James Rothman e Randy Sheckman<\/strong> negli studi sul cosiddetto &#8216;traffico delle vescicole&#8217; (uno dei principali sistemi di trasporto delle proteine all\u2019interno delle cellule) ha portato gli stessi J. Rothman e R. Schekman ad ottenere nel 2013 il Premio Nobel per la Medicina, insieme a Thomas C. S\u00fcdhof.<\/p>\n<p>&nbsp;<\/p>\n<figure id=\"attachment_20742\" aria-describedby=\"caption-attachment-20742\" style=\"width: 632px\" class=\"wp-caption aligncenter\"><img loading=\"lazy\" decoding=\"async\" class=\"wp-image-20742 size-full\" src=\"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2019\/10\/Rothman-Schekman-Nobel-e1571841389323.jpg\" alt=\"vincitori premio nobel il corriere della provincia\" width=\"632\" height=\"347\" \/><figcaption id=\"caption-attachment-20742\" class=\"wp-caption-text\">Rothman e Schekman vincitori del Nobel nel 2013<\/figcaption><\/figure>\n<p>&nbsp;<\/p>\n<h2>Le origini ciociare<\/h2>\n<p>Il professor Orci aveva 82 anni. <strong>Era nato nel 1937 a San Giovanni Incarico<\/strong> e la sua famiglia viveva a Ceprano e lui ha frequentato la scuola media e il Liceo scientifico \u201cG. Sulpicio\u201d a Veroli (citt\u00e0 che nel 2001 gli ha dato la cittadinanza onoraria).<\/p>\n<p>Nel 1964 si era laureato con lode in Medicina, all\u2019Universit\u00e0 &#8216;La Sapienza&#8217; di Roma. Due anni dopo, si era trasferito all\u2019Universit\u00e0 di Ginevra ottenendo la cattedra di Istologia ed Embriologia. Dal 1976 al 2002 \u00e8 stato direttore del Dipartimento di Morfologia nella stessa universit\u00e0, da cui ha anche ricevuto la laurea honoris causa.<\/p>\n<h2>Le ricerche sul diabete<\/h2>\n<p>Per le sue ricerche &#8211; in particolare, quelle pionieristiche sull\u2019architettura e la funzione dei cosiddetti &#8216;Isolotti di Langerhans&#8217;, aree del pancreas dove si produce l\u2019insulina &#8211; gli \u00e8 stata insignita l\u2019onorificenza di Commendatore dell\u2019Ordine al merito della Repubblica italiana.<\/p>\n<p><strong>Ha ottenuto numerosi premi e riconoscimenti in varie parti del mondo<\/strong> (ad esempio, il King Faisal International Prize for Medicine, considerato il Nobel del mondo arabo), lauree honoris causa in varie universit\u00e0 (Padova, Lovanio, Montreal, ecc.), ed era membro \u2013 fra le altre &#8211; della prestigiosa National Academy of Sciences degli Stati Uniti, dell\u2019Accademia Europea delle Scienze, dell\u2019Accademia dei Lincei e dell\u2019Accademia di Scienze mediche della Svizzera.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Noto in tutto il mondo per le sue scoperte nel settore della biologia cellulare e in particolare del diabete: \u00e8<\/p>\n","protected":false},"author":18,"featured_media":20743,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[4,2236],"tags":[94,6827,93,6828,6825,6829,1600,6826],"class_list":["post-20740","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-primo-piano","category-attualita","tag-ciociaria","tag-diabete","tag-frosinone","tag-ginevra","tag-lelio-orci","tag-premio-nobel","tag-san-giovanni-incarico","tag-scienziato"],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v27.8 (Yoast SEO v27.8) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Morto lo scienziato Lelio Orci. Era di San Giovanni Incarico - IlCorriereDellaProvincia.it - News h24 e notizie di approfondimento<\/title>\n<meta name=\"description\" content=\"Morto ieri, a Ginevra, lo scienziato Lelio Orci, famoso in tutto il mondo per le sue scoperte sul diabete. Era originario di San Giovanni Incarico\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2019\/10\/23\/morto-lo-scienziato-lelio-orci-era-di-san-giovanni-incarico\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Morto lo scienziato Lelio Orci. Era di San Giovanni Incarico\" \/>\n<meta property=\"og:description\" content=\"Morto ieri, a Ginevra, lo scienziato Lelio Orci, famoso in tutto il mondo per le sue scoperte sul diabete. Era originario di San Giovanni Incarico\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2019\/10\/23\/morto-lo-scienziato-lelio-orci-era-di-san-giovanni-incarico\/\" \/>\n<meta property=\"og:site_name\" content=\"IlCorriereDellaProvincia.it - News h24 e notizie di approfondimento\" \/>\n<meta property=\"article:author\" content=\"www.facebook.com\/tunews24\" \/>\n<meta property=\"article:published_time\" content=\"2019-10-23T14:40:00+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2019\/10\/universit\u00e0-ginevra.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"590\" \/>\n\t<meta property=\"og:image:height\" content=\"400\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Redazione\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"Redazione\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minuti\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2019\\\/10\\\/23\\\/morto-lo-scienziato-lelio-orci-era-di-san-giovanni-incarico\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2019\\\/10\\\/23\\\/morto-lo-scienziato-lelio-orci-era-di-san-giovanni-incarico\\\/\"},\"author\":{\"name\":\"Redazione\",\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/#\\\/schema\\\/person\\\/6d7f0a9120d0c03d0c552e9fdf49ed7d\"},\"headline\":\"Morto lo scienziato Lelio Orci. Era di San Giovanni Incarico\",\"datePublished\":\"2019-10-23T14:40:00+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2019\\\/10\\\/23\\\/morto-lo-scienziato-lelio-orci-era-di-san-giovanni-incarico\\\/\"},\"wordCount\":355,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2019\\\/10\\\/23\\\/morto-lo-scienziato-lelio-orci-era-di-san-giovanni-incarico\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2019\\\/10\\\/universit\u00e0-ginevra.jpg\",\"keywords\":[\"Ciociaria\",\"diabete\",\"Frosinone\",\"ginevra\",\"lelio orci\",\"premio nobel\",\"San Giovanni Incarico\",\"scienziato\"],\"articleSection\":[\"*PRIMO PIANO*\",\"Attualit\u00e0\"],\"inLanguage\":\"it-IT\",\"copyrightYear\":\"2019\",\"copyrightHolder\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/#organization\"}},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2019\\\/10\\\/23\\\/morto-lo-scienziato-lelio-orci-era-di-san-giovanni-incarico\\\/\",\"url\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2019\\\/10\\\/23\\\/morto-lo-scienziato-lelio-orci-era-di-san-giovanni-incarico\\\/\",\"name\":\"Morto lo scienziato Lelio Orci. Era di San Giovanni Incarico - IlCorriereDellaProvincia.it - News h24 e notizie di approfondimento\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2019\\\/10\\\/23\\\/morto-lo-scienziato-lelio-orci-era-di-san-giovanni-incarico\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2019\\\/10\\\/23\\\/morto-lo-scienziato-lelio-orci-era-di-san-giovanni-incarico\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2019\\\/10\\\/universit\u00e0-ginevra.jpg\",\"datePublished\":\"2019-10-23T14:40:00+00:00\",\"description\":\"Morto ieri, a Ginevra, lo scienziato Lelio Orci, famoso in tutto il mondo per le sue scoperte sul diabete. Era originario di San Giovanni Incarico\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2019\\\/10\\\/23\\\/morto-lo-scienziato-lelio-orci-era-di-san-giovanni-incarico\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2019\\\/10\\\/23\\\/morto-lo-scienziato-lelio-orci-era-di-san-giovanni-incarico\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2019\\\/10\\\/23\\\/morto-lo-scienziato-lelio-orci-era-di-san-giovanni-incarico\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2019\\\/10\\\/universit\u00e0-ginevra.jpg\",\"contentUrl\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2019\\\/10\\\/universit\u00e0-ginevra.jpg\",\"width\":590,\"height\":400,\"caption\":\"L'Universit\u00e0 di Ginevra\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2019\\\/10\\\/23\\\/morto-lo-scienziato-lelio-orci-era-di-san-giovanni-incarico\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Morto lo scienziato Lelio Orci. Era di San Giovanni Incarico\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/#website\",\"url\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/\",\"name\":\"Il Corriere Delle Provincia\",\"description\":\"IlCorriereDellaProvincia.it, quotidiano web di politica, cronaca, inchiesta, lavoro, scuola, turismo, cultura e spettacolo, economia e finanza, salute e benessere. Approfondimenti e notizie aggiornate con foto e video della provincia di Frosinone ma anche news nazionali, dell\u2019Italia e del Mondo.\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":[\"Organization\",\"Place\"],\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/#organization\",\"name\":\"Globalpress s.r.l.\",\"url\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/\",\"logo\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2019\\\/10\\\/23\\\/morto-lo-scienziato-lelio-orci-era-di-san-giovanni-incarico\\\/#local-main-organization-logo\"},\"image\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2019\\\/10\\\/23\\\/morto-lo-scienziato-lelio-orci-era-di-san-giovanni-incarico\\\/#local-main-organization-logo\"},\"telephone\":[],\"openingHoursSpecification\":[{\"@type\":\"OpeningHoursSpecification\",\"dayOfWeek\":[\"Monday\",\"Tuesday\",\"Wednesday\",\"Thursday\",\"Friday\",\"Saturday\",\"Sunday\"],\"opens\":\"09:00\",\"closes\":\"17:00\"}]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/#\\\/schema\\\/person\\\/6d7f0a9120d0c03d0c552e9fdf49ed7d\",\"name\":\"Redazione\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/a40eeacccdcad861f831dde73317f63a542e738f0dc4b79b9f47062d3d4bd1d2?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/a40eeacccdcad861f831dde73317f63a542e738f0dc4b79b9f47062d3d4bd1d2?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/a40eeacccdcad861f831dde73317f63a542e738f0dc4b79b9f47062d3d4bd1d2?s=96&d=mm&r=g\",\"caption\":\"Redazione\"},\"description\":\"SEGUICI ANCHE SUI SOCIAL Facebook: TuNews24 e TuSport24 Instagram: TuNews24 e TuSport24 Youtube: TuNews24 Telegram: TuNews24 Puoi leggerci anche in formato cartaceo: il settimanale viene pubblicato e distribuito gratuitamente ogni venerd\u00ec in edicole, bar, centri commerciali e svariati esercizi. Ma \u00e8 possibile anche sfogliarlo comodamente online, cliccando su TU NEWS sfogliabile TU NEWS, PASSIONE PER L\u2019INFORMAZIONE\",\"sameAs\":[\"http:\\\/\\\/www.tunews24.it\",\"www.facebook.com\\\/tunews24\"],\"url\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/author\\\/senzafirma\\\/\"},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2019\\\/10\\\/23\\\/morto-lo-scienziato-lelio-orci-era-di-san-giovanni-incarico\\\/#local-main-organization-logo\",\"url\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2022\\\/11\\\/cropped-il-corriere-della-provincia-testata-web-scontornata.png\",\"contentUrl\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2022\\\/11\\\/cropped-il-corriere-della-provincia-testata-web-scontornata.png\",\"width\":2911,\"height\":717,\"caption\":\"Globalpress s.r.l.\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Morto lo scienziato Lelio Orci. Era di San Giovanni Incarico - IlCorriereDellaProvincia.it - News h24 e notizie di approfondimento","description":"Morto ieri, a Ginevra, lo scienziato Lelio Orci, famoso in tutto il mondo per le sue scoperte sul diabete. Era originario di San Giovanni Incarico","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2019\/10\/23\/morto-lo-scienziato-lelio-orci-era-di-san-giovanni-incarico\/","og_locale":"it_IT","og_type":"article","og_title":"Morto lo scienziato Lelio Orci. Era di San Giovanni Incarico","og_description":"Morto ieri, a Ginevra, lo scienziato Lelio Orci, famoso in tutto il mondo per le sue scoperte sul diabete. Era originario di San Giovanni Incarico","og_url":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2019\/10\/23\/morto-lo-scienziato-lelio-orci-era-di-san-giovanni-incarico\/","og_site_name":"IlCorriereDellaProvincia.it - News h24 e notizie di approfondimento","article_author":"www.facebook.com\/tunews24","article_published_time":"2019-10-23T14:40:00+00:00","og_image":[{"width":590,"height":400,"url":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2019\/10\/universit\u00e0-ginevra.jpg","type":"image\/jpeg"}],"author":"Redazione","twitter_card":"summary_large_image","twitter_misc":{"Scritto da":"Redazione","Tempo di lettura stimato":"2 minuti"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2019\/10\/23\/morto-lo-scienziato-lelio-orci-era-di-san-giovanni-incarico\/#article","isPartOf":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2019\/10\/23\/morto-lo-scienziato-lelio-orci-era-di-san-giovanni-incarico\/"},"author":{"name":"Redazione","@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/#\/schema\/person\/6d7f0a9120d0c03d0c552e9fdf49ed7d"},"headline":"Morto lo scienziato Lelio Orci. Era di San Giovanni Incarico","datePublished":"2019-10-23T14:40:00+00:00","mainEntityOfPage":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2019\/10\/23\/morto-lo-scienziato-lelio-orci-era-di-san-giovanni-incarico\/"},"wordCount":355,"commentCount":0,"publisher":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/#organization"},"image":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2019\/10\/23\/morto-lo-scienziato-lelio-orci-era-di-san-giovanni-incarico\/#primaryimage"},"thumbnailUrl":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2019\/10\/universit\u00e0-ginevra.jpg","keywords":["Ciociaria","diabete","Frosinone","ginevra","lelio orci","premio nobel","San Giovanni Incarico","scienziato"],"articleSection":["*PRIMO PIANO*","Attualit\u00e0"],"inLanguage":"it-IT","copyrightYear":"2019","copyrightHolder":{"@id":"https:\/\/www.tunews24.it\/#organization"}},{"@type":"WebPage","@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2019\/10\/23\/morto-lo-scienziato-lelio-orci-era-di-san-giovanni-incarico\/","url":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2019\/10\/23\/morto-lo-scienziato-lelio-orci-era-di-san-giovanni-incarico\/","name":"Morto lo scienziato Lelio Orci. Era di San Giovanni Incarico - IlCorriereDellaProvincia.it - News h24 e notizie di approfondimento","isPartOf":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2019\/10\/23\/morto-lo-scienziato-lelio-orci-era-di-san-giovanni-incarico\/#primaryimage"},"image":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2019\/10\/23\/morto-lo-scienziato-lelio-orci-era-di-san-giovanni-incarico\/#primaryimage"},"thumbnailUrl":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2019\/10\/universit\u00e0-ginevra.jpg","datePublished":"2019-10-23T14:40:00+00:00","description":"Morto ieri, a Ginevra, lo scienziato Lelio Orci, famoso in tutto il mondo per le sue scoperte sul diabete. Era originario di San Giovanni Incarico","breadcrumb":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2019\/10\/23\/morto-lo-scienziato-lelio-orci-era-di-san-giovanni-incarico\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2019\/10\/23\/morto-lo-scienziato-lelio-orci-era-di-san-giovanni-incarico\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2019\/10\/23\/morto-lo-scienziato-lelio-orci-era-di-san-giovanni-incarico\/#primaryimage","url":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2019\/10\/universit\u00e0-ginevra.jpg","contentUrl":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2019\/10\/universit\u00e0-ginevra.jpg","width":590,"height":400,"caption":"L'Universit\u00e0 di Ginevra"},{"@type":"BreadcrumbList","@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2019\/10\/23\/morto-lo-scienziato-lelio-orci-era-di-san-giovanni-incarico\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/"},{"@type":"ListItem","position":2,"name":"Morto lo scienziato Lelio Orci. Era di San Giovanni Incarico"}]},{"@type":"WebSite","@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/#website","url":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/","name":"Il Corriere Delle Provincia","description":"IlCorriereDellaProvincia.it, quotidiano web di politica, cronaca, inchiesta, lavoro, scuola, turismo, cultura e spettacolo, economia e finanza, salute e benessere. Approfondimenti e notizie aggiornate con foto e video della provincia di Frosinone ma anche news nazionali, dell\u2019Italia e del Mondo.","publisher":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":["Organization","Place"],"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/#organization","name":"Globalpress s.r.l.","url":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/","logo":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2019\/10\/23\/morto-lo-scienziato-lelio-orci-era-di-san-giovanni-incarico\/#local-main-organization-logo"},"image":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2019\/10\/23\/morto-lo-scienziato-lelio-orci-era-di-san-giovanni-incarico\/#local-main-organization-logo"},"telephone":[],"openingHoursSpecification":[{"@type":"OpeningHoursSpecification","dayOfWeek":["Monday","Tuesday","Wednesday","Thursday","Friday","Saturday","Sunday"],"opens":"09:00","closes":"17:00"}]},{"@type":"Person","@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/#\/schema\/person\/6d7f0a9120d0c03d0c552e9fdf49ed7d","name":"Redazione","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/secure.gravatar.com\/avatar\/a40eeacccdcad861f831dde73317f63a542e738f0dc4b79b9f47062d3d4bd1d2?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/a40eeacccdcad861f831dde73317f63a542e738f0dc4b79b9f47062d3d4bd1d2?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/a40eeacccdcad861f831dde73317f63a542e738f0dc4b79b9f47062d3d4bd1d2?s=96&d=mm&r=g","caption":"Redazione"},"description":"SEGUICI ANCHE SUI SOCIAL Facebook: TuNews24 e TuSport24 Instagram: TuNews24 e TuSport24 Youtube: TuNews24 Telegram: TuNews24 Puoi leggerci anche in formato cartaceo: il settimanale viene pubblicato e distribuito gratuitamente ogni venerd\u00ec in edicole, bar, centri commerciali e svariati esercizi. Ma \u00e8 possibile anche sfogliarlo comodamente online, cliccando su TU NEWS sfogliabile TU NEWS, PASSIONE PER L\u2019INFORMAZIONE","sameAs":["http:\/\/www.tunews24.it","www.facebook.com\/tunews24"],"url":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/author\/senzafirma\/"},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2019\/10\/23\/morto-lo-scienziato-lelio-orci-era-di-san-giovanni-incarico\/#local-main-organization-logo","url":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2022\/11\/cropped-il-corriere-della-provincia-testata-web-scontornata.png","contentUrl":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2022\/11\/cropped-il-corriere-della-provincia-testata-web-scontornata.png","width":2911,"height":717,"caption":"Globalpress s.r.l."}]}},"_links":{"self":[{"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/posts\/20740","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/users\/18"}],"replies":[{"embeddable":true,"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/comments?post=20740"}],"version-history":[{"count":1,"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/posts\/20740\/revisions"}],"predecessor-version":[{"id":20744,"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/posts\/20740\/revisions\/20744"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/media\/20743"}],"wp:attachment":[{"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/media?parent=20740"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/categories?post=20740"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/tags?post=20740"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}