{"id":20732,"date":"2019-10-23T16:06:12","date_gmt":"2019-10-23T14:06:12","guid":{"rendered":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/?p=20732"},"modified":"2019-10-24T15:39:54","modified_gmt":"2019-10-24T13:39:54","slug":"pronto-soccorso-dello-spaziani-intasato-ciacciarelli-bisogna-aprirne-uno-ad-anagni","status":"publish","type":"post","link":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2019\/10\/23\/pronto-soccorso-dello-spaziani-intasato-ciacciarelli-bisogna-aprirne-uno-ad-anagni\/","title":{"rendered":"Pronto soccorso dello &#8216;Spaziani&#8217; intasato, Ciacciarelli: &#8220;Bisogna aprirne uno ad Anagni&#8221;."},"content":{"rendered":"<div dir=\"auto\"><\/div>\n<div dir=\"auto\"><strong>\u201cIl pronto soccorso dell\u2019ospedale Fabrizio Spaziani di Frosinone \u00e8 sempre pi\u00f9 intasato<\/strong>. Sono innumerevoli le segnalazioni che ricevo quotidianamente dai cittadini&#8221;. Cos\u00ec il consigliere regionale del Lazio<strong> Pasquale Ciacciarelli,<\/strong> Cambiamo\/ Laboratorio Lazio per il Cambiamento.<\/div>\n<h2><\/h2>\n<h2>L&#8217;intervento<\/h2>\n<div dir=\"auto\">&#8220;Si rende sempre pi\u00f9 necessario, quindi,<strong> un intervento volto a potenziare l\u2019offerta del territorio<\/strong> provinciale ed a sollevare il pronto soccorso di Frosinone dall\u2019eccessivo numero di richieste attraverso il potenziamento della struttura anagnina. La sanit\u00e0 regionale \u2013 evidenzia il presidente della V Commissione Cultura, Spettacolo, Sport e Turismo della Regione Lazio \u2013 continua a distinguersi per carenze che finiscono per screditare il servizio pubblico agli occhi dei cittadini&#8221;.<\/div>\n<h2><\/h2>\n<h2>L&#8217;affondo<\/h2>\n<div dir=\"auto\">&#8220;Le criticit\u00e0 legate al sovraffollamento dei pronto soccorso e alla carenza dei posti letto \u2013 rincara il consigliere regionale \u2013 non sono affatto circoscritte alla capitale:<strong> bisogna risolvere il problema delle urgenze soprattutto nell\u2019area nord della provincia di Frosinone<\/strong> che vede un bacino di utenza molto ampio che non pu\u00f2 essere riversato esclusivamente sull\u2019ospedale \u2018Fabrizio Spaziani\u2019 di Frosinone; per tutti questi motivi si rende indispensabile il rilancio dell\u2019ospedale di Anagni&#8221;.<\/div>\n<div dir=\"auto\"><\/div>\n<div dir=\"auto\">&#8220;\u00c8 stata <strong>una delle questioni di primaria importanza che ho sottoposto al neo manager<\/strong> Asl Frosinone Lorusso, e vigiler\u00f2 affinch\u00e9 si dia il giusto peso alla cosa. Basta aspettare ogni volta le tragedie. La situazione \u00e8 davvero emergenziale e richiede un intervento immediato e mirato.\u201d<\/div>\n<div dir=\"auto\"><\/div>\n<div dir=\"auto\"><\/div>\n<div dir=\"auto\"><\/div>\n<div dir=\"auto\"><\/div>\n","protected":false},"excerpt":{"rendered":"<p>\u201cIl pronto soccorso dell\u2019ospedale Fabrizio Spaziani di Frosinone \u00e8 sempre pi\u00f9 intasato. Sono innumerevoli le segnalazioni che ricevo quotidianamente dai<\/p>\n","protected":false},"author":18,"featured_media":15899,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[4,11],"tags":[441,216,94,93,1415,1336,774],"class_list":["post-20732","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-primo-piano","category-salute","tag-anagni","tag-cassino","tag-ciociaria","tag-frosinone","tag-ospedale-spaziani","tag-pasquale-ciacciarelli","tag-pronto-soccorso"],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v27.8 (Yoast SEO v27.8) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Pronto soccorso dello &#039;Spaziani&#039; intasato, Ciacciarelli: &quot;Bisogna aprirne uno ad Anagni&quot;. - IlCorriereDellaProvincia.it - News h24 e notizie di approfondimento<\/title>\n<meta name=\"description\" content=\"Le criticit\u00e0 legate al sovraffollamento dei pronto soccorso e alla carenza dei posti letto \u2013 rin non sono affatto circoscritte alla capitale\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2019\/10\/23\/pronto-soccorso-dello-spaziani-intasato-ciacciarelli-bisogna-aprirne-uno-ad-anagni\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Pronto soccorso dello &#039;Spaziani&#039; intasato, Ciacciarelli: &quot;Bisogna aprirne uno ad Anagni&quot;.\" \/>\n<meta property=\"og:description\" content=\"Le criticit\u00e0 legate al sovraffollamento dei pronto soccorso e alla carenza dei posti letto \u2013 rin non sono affatto circoscritte alla capitale\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2019\/10\/23\/pronto-soccorso-dello-spaziani-intasato-ciacciarelli-bisogna-aprirne-uno-ad-anagni\/\" \/>\n<meta property=\"og:site_name\" content=\"IlCorriereDellaProvincia.it - News h24 e notizie di approfondimento\" \/>\n<meta property=\"article:author\" content=\"www.facebook.com\/tunews24\" \/>\n<meta property=\"article:published_time\" content=\"2019-10-23T14:06:12+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2019-10-24T13:39:54+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2019\/07\/pasquale-ciacciarelli-consigliere-regionale-il-corriere-della-provincia-e1566288502603.jpeg\" \/>\n\t<meta property=\"og:image:width\" content=\"632\" \/>\n\t<meta property=\"og:image:height\" content=\"414\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Redazione\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"Redazione\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2019\\\/10\\\/23\\\/pronto-soccorso-dello-spaziani-intasato-ciacciarelli-bisogna-aprirne-uno-ad-anagni\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2019\\\/10\\\/23\\\/pronto-soccorso-dello-spaziani-intasato-ciacciarelli-bisogna-aprirne-uno-ad-anagni\\\/\"},\"author\":{\"name\":\"Redazione\",\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/#\\\/schema\\\/person\\\/6d7f0a9120d0c03d0c552e9fdf49ed7d\"},\"headline\":\"Pronto soccorso dello &#8216;Spaziani&#8217; intasato, Ciacciarelli: &#8220;Bisogna aprirne uno ad Anagni&#8221;.\",\"datePublished\":\"2019-10-23T14:06:12+00:00\",\"dateModified\":\"2019-10-24T13:39:54+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2019\\\/10\\\/23\\\/pronto-soccorso-dello-spaziani-intasato-ciacciarelli-bisogna-aprirne-uno-ad-anagni\\\/\"},\"wordCount\":232,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2019\\\/10\\\/23\\\/pronto-soccorso-dello-spaziani-intasato-ciacciarelli-bisogna-aprirne-uno-ad-anagni\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2019\\\/07\\\/pasquale-ciacciarelli-consigliere-regionale-il-corriere-della-provincia-e1566288502603.jpeg\",\"keywords\":[\"anagni\",\"Cassino\",\"Ciociaria\",\"Frosinone\",\"ospedale spaziani\",\"pasquale ciacciarelli\",\"pronto soccorso\"],\"articleSection\":[\"*PRIMO PIANO*\",\"Salute e Benessere\"],\"inLanguage\":\"it-IT\",\"copyrightYear\":\"2019\",\"copyrightHolder\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/#organization\"}},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2019\\\/10\\\/23\\\/pronto-soccorso-dello-spaziani-intasato-ciacciarelli-bisogna-aprirne-uno-ad-anagni\\\/\",\"url\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2019\\\/10\\\/23\\\/pronto-soccorso-dello-spaziani-intasato-ciacciarelli-bisogna-aprirne-uno-ad-anagni\\\/\",\"name\":\"Pronto soccorso dello 'Spaziani' intasato, Ciacciarelli: \\\"Bisogna aprirne uno ad Anagni\\\". - IlCorriereDellaProvincia.it - News h24 e notizie di approfondimento\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2019\\\/10\\\/23\\\/pronto-soccorso-dello-spaziani-intasato-ciacciarelli-bisogna-aprirne-uno-ad-anagni\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2019\\\/10\\\/23\\\/pronto-soccorso-dello-spaziani-intasato-ciacciarelli-bisogna-aprirne-uno-ad-anagni\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2019\\\/07\\\/pasquale-ciacciarelli-consigliere-regionale-il-corriere-della-provincia-e1566288502603.jpeg\",\"datePublished\":\"2019-10-23T14:06:12+00:00\",\"dateModified\":\"2019-10-24T13:39:54+00:00\",\"description\":\"Le criticit\u00e0 legate al sovraffollamento dei pronto soccorso e alla carenza dei posti letto \u2013 rin non sono affatto circoscritte alla capitale\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2019\\\/10\\\/23\\\/pronto-soccorso-dello-spaziani-intasato-ciacciarelli-bisogna-aprirne-uno-ad-anagni\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2019\\\/10\\\/23\\\/pronto-soccorso-dello-spaziani-intasato-ciacciarelli-bisogna-aprirne-uno-ad-anagni\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2019\\\/10\\\/23\\\/pronto-soccorso-dello-spaziani-intasato-ciacciarelli-bisogna-aprirne-uno-ad-anagni\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2019\\\/07\\\/pasquale-ciacciarelli-consigliere-regionale-il-corriere-della-provincia-e1566288502603.jpeg\",\"contentUrl\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2019\\\/07\\\/pasquale-ciacciarelli-consigliere-regionale-il-corriere-della-provincia-e1566288502603.jpeg\",\"width\":632,\"height\":414,\"caption\":\"Il consigliere regionale Pasquale Ciacciarelli\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2019\\\/10\\\/23\\\/pronto-soccorso-dello-spaziani-intasato-ciacciarelli-bisogna-aprirne-uno-ad-anagni\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Pronto soccorso dello &#8216;Spaziani&#8217; intasato, Ciacciarelli: &#8220;Bisogna aprirne uno ad Anagni&#8221;.\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/#website\",\"url\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/\",\"name\":\"Il Corriere Delle Provincia\",\"description\":\"IlCorriereDellaProvincia.it, quotidiano web di politica, cronaca, inchiesta, lavoro, scuola, turismo, cultura e spettacolo, economia e finanza, salute e benessere. Approfondimenti e notizie aggiornate con foto e video della provincia di Frosinone ma anche news nazionali, dell\u2019Italia e del Mondo.\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":[\"Organization\",\"Place\"],\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/#organization\",\"name\":\"Globalpress s.r.l.\",\"url\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/\",\"logo\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2019\\\/10\\\/23\\\/pronto-soccorso-dello-spaziani-intasato-ciacciarelli-bisogna-aprirne-uno-ad-anagni\\\/#local-main-organization-logo\"},\"image\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2019\\\/10\\\/23\\\/pronto-soccorso-dello-spaziani-intasato-ciacciarelli-bisogna-aprirne-uno-ad-anagni\\\/#local-main-organization-logo\"},\"telephone\":[],\"openingHoursSpecification\":[{\"@type\":\"OpeningHoursSpecification\",\"dayOfWeek\":[\"Monday\",\"Tuesday\",\"Wednesday\",\"Thursday\",\"Friday\",\"Saturday\",\"Sunday\"],\"opens\":\"09:00\",\"closes\":\"17:00\"}]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/#\\\/schema\\\/person\\\/6d7f0a9120d0c03d0c552e9fdf49ed7d\",\"name\":\"Redazione\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/a40eeacccdcad861f831dde73317f63a542e738f0dc4b79b9f47062d3d4bd1d2?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/a40eeacccdcad861f831dde73317f63a542e738f0dc4b79b9f47062d3d4bd1d2?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/a40eeacccdcad861f831dde73317f63a542e738f0dc4b79b9f47062d3d4bd1d2?s=96&d=mm&r=g\",\"caption\":\"Redazione\"},\"description\":\"SEGUICI ANCHE SUI SOCIAL Facebook: TuNews24 e TuSport24 Instagram: TuNews24 e TuSport24 Youtube: TuNews24 Telegram: TuNews24 Puoi leggerci anche in formato cartaceo: il settimanale viene pubblicato e distribuito gratuitamente ogni venerd\u00ec in edicole, bar, centri commerciali e svariati esercizi. Ma \u00e8 possibile anche sfogliarlo comodamente online, cliccando su TU NEWS sfogliabile TU NEWS, PASSIONE PER L\u2019INFORMAZIONE\",\"sameAs\":[\"http:\\\/\\\/www.tunews24.it\",\"www.facebook.com\\\/tunews24\"],\"url\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/author\\\/senzafirma\\\/\"},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2019\\\/10\\\/23\\\/pronto-soccorso-dello-spaziani-intasato-ciacciarelli-bisogna-aprirne-uno-ad-anagni\\\/#local-main-organization-logo\",\"url\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2022\\\/11\\\/cropped-il-corriere-della-provincia-testata-web-scontornata.png\",\"contentUrl\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2022\\\/11\\\/cropped-il-corriere-della-provincia-testata-web-scontornata.png\",\"width\":2911,\"height\":717,\"caption\":\"Globalpress s.r.l.\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Pronto soccorso dello 'Spaziani' intasato, Ciacciarelli: \"Bisogna aprirne uno ad Anagni\". - IlCorriereDellaProvincia.it - News h24 e notizie di approfondimento","description":"Le criticit\u00e0 legate al sovraffollamento dei pronto soccorso e alla carenza dei posti letto \u2013 rin non sono affatto circoscritte alla capitale","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2019\/10\/23\/pronto-soccorso-dello-spaziani-intasato-ciacciarelli-bisogna-aprirne-uno-ad-anagni\/","og_locale":"it_IT","og_type":"article","og_title":"Pronto soccorso dello 'Spaziani' intasato, Ciacciarelli: \"Bisogna aprirne uno ad Anagni\".","og_description":"Le criticit\u00e0 legate al sovraffollamento dei pronto soccorso e alla carenza dei posti letto \u2013 rin non sono affatto circoscritte alla capitale","og_url":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2019\/10\/23\/pronto-soccorso-dello-spaziani-intasato-ciacciarelli-bisogna-aprirne-uno-ad-anagni\/","og_site_name":"IlCorriereDellaProvincia.it - News h24 e notizie di approfondimento","article_author":"www.facebook.com\/tunews24","article_published_time":"2019-10-23T14:06:12+00:00","article_modified_time":"2019-10-24T13:39:54+00:00","og_image":[{"width":632,"height":414,"url":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2019\/07\/pasquale-ciacciarelli-consigliere-regionale-il-corriere-della-provincia-e1566288502603.jpeg","type":"image\/jpeg"}],"author":"Redazione","twitter_card":"summary_large_image","twitter_misc":{"Scritto da":"Redazione","Tempo di lettura stimato":"1 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2019\/10\/23\/pronto-soccorso-dello-spaziani-intasato-ciacciarelli-bisogna-aprirne-uno-ad-anagni\/#article","isPartOf":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2019\/10\/23\/pronto-soccorso-dello-spaziani-intasato-ciacciarelli-bisogna-aprirne-uno-ad-anagni\/"},"author":{"name":"Redazione","@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/#\/schema\/person\/6d7f0a9120d0c03d0c552e9fdf49ed7d"},"headline":"Pronto soccorso dello &#8216;Spaziani&#8217; intasato, Ciacciarelli: &#8220;Bisogna aprirne uno ad Anagni&#8221;.","datePublished":"2019-10-23T14:06:12+00:00","dateModified":"2019-10-24T13:39:54+00:00","mainEntityOfPage":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2019\/10\/23\/pronto-soccorso-dello-spaziani-intasato-ciacciarelli-bisogna-aprirne-uno-ad-anagni\/"},"wordCount":232,"commentCount":0,"publisher":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/#organization"},"image":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2019\/10\/23\/pronto-soccorso-dello-spaziani-intasato-ciacciarelli-bisogna-aprirne-uno-ad-anagni\/#primaryimage"},"thumbnailUrl":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2019\/07\/pasquale-ciacciarelli-consigliere-regionale-il-corriere-della-provincia-e1566288502603.jpeg","keywords":["anagni","Cassino","Ciociaria","Frosinone","ospedale spaziani","pasquale ciacciarelli","pronto soccorso"],"articleSection":["*PRIMO PIANO*","Salute e Benessere"],"inLanguage":"it-IT","copyrightYear":"2019","copyrightHolder":{"@id":"https:\/\/www.tunews24.it\/#organization"}},{"@type":"WebPage","@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2019\/10\/23\/pronto-soccorso-dello-spaziani-intasato-ciacciarelli-bisogna-aprirne-uno-ad-anagni\/","url":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2019\/10\/23\/pronto-soccorso-dello-spaziani-intasato-ciacciarelli-bisogna-aprirne-uno-ad-anagni\/","name":"Pronto soccorso dello 'Spaziani' intasato, Ciacciarelli: \"Bisogna aprirne uno ad Anagni\". - IlCorriereDellaProvincia.it - News h24 e notizie di approfondimento","isPartOf":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2019\/10\/23\/pronto-soccorso-dello-spaziani-intasato-ciacciarelli-bisogna-aprirne-uno-ad-anagni\/#primaryimage"},"image":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2019\/10\/23\/pronto-soccorso-dello-spaziani-intasato-ciacciarelli-bisogna-aprirne-uno-ad-anagni\/#primaryimage"},"thumbnailUrl":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2019\/07\/pasquale-ciacciarelli-consigliere-regionale-il-corriere-della-provincia-e1566288502603.jpeg","datePublished":"2019-10-23T14:06:12+00:00","dateModified":"2019-10-24T13:39:54+00:00","description":"Le criticit\u00e0 legate al sovraffollamento dei pronto soccorso e alla carenza dei posti letto \u2013 rin non sono affatto circoscritte alla capitale","breadcrumb":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2019\/10\/23\/pronto-soccorso-dello-spaziani-intasato-ciacciarelli-bisogna-aprirne-uno-ad-anagni\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2019\/10\/23\/pronto-soccorso-dello-spaziani-intasato-ciacciarelli-bisogna-aprirne-uno-ad-anagni\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2019\/10\/23\/pronto-soccorso-dello-spaziani-intasato-ciacciarelli-bisogna-aprirne-uno-ad-anagni\/#primaryimage","url":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2019\/07\/pasquale-ciacciarelli-consigliere-regionale-il-corriere-della-provincia-e1566288502603.jpeg","contentUrl":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2019\/07\/pasquale-ciacciarelli-consigliere-regionale-il-corriere-della-provincia-e1566288502603.jpeg","width":632,"height":414,"caption":"Il consigliere regionale Pasquale Ciacciarelli"},{"@type":"BreadcrumbList","@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2019\/10\/23\/pronto-soccorso-dello-spaziani-intasato-ciacciarelli-bisogna-aprirne-uno-ad-anagni\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/"},{"@type":"ListItem","position":2,"name":"Pronto soccorso dello &#8216;Spaziani&#8217; intasato, Ciacciarelli: &#8220;Bisogna aprirne uno ad Anagni&#8221;."}]},{"@type":"WebSite","@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/#website","url":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/","name":"Il Corriere Delle Provincia","description":"IlCorriereDellaProvincia.it, quotidiano web di politica, cronaca, inchiesta, lavoro, scuola, turismo, cultura e spettacolo, economia e finanza, salute e benessere. Approfondimenti e notizie aggiornate con foto e video della provincia di Frosinone ma anche news nazionali, dell\u2019Italia e del Mondo.","publisher":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":["Organization","Place"],"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/#organization","name":"Globalpress s.r.l.","url":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/","logo":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2019\/10\/23\/pronto-soccorso-dello-spaziani-intasato-ciacciarelli-bisogna-aprirne-uno-ad-anagni\/#local-main-organization-logo"},"image":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2019\/10\/23\/pronto-soccorso-dello-spaziani-intasato-ciacciarelli-bisogna-aprirne-uno-ad-anagni\/#local-main-organization-logo"},"telephone":[],"openingHoursSpecification":[{"@type":"OpeningHoursSpecification","dayOfWeek":["Monday","Tuesday","Wednesday","Thursday","Friday","Saturday","Sunday"],"opens":"09:00","closes":"17:00"}]},{"@type":"Person","@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/#\/schema\/person\/6d7f0a9120d0c03d0c552e9fdf49ed7d","name":"Redazione","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/secure.gravatar.com\/avatar\/a40eeacccdcad861f831dde73317f63a542e738f0dc4b79b9f47062d3d4bd1d2?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/a40eeacccdcad861f831dde73317f63a542e738f0dc4b79b9f47062d3d4bd1d2?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/a40eeacccdcad861f831dde73317f63a542e738f0dc4b79b9f47062d3d4bd1d2?s=96&d=mm&r=g","caption":"Redazione"},"description":"SEGUICI ANCHE SUI SOCIAL Facebook: TuNews24 e TuSport24 Instagram: TuNews24 e TuSport24 Youtube: TuNews24 Telegram: TuNews24 Puoi leggerci anche in formato cartaceo: il settimanale viene pubblicato e distribuito gratuitamente ogni venerd\u00ec in edicole, bar, centri commerciali e svariati esercizi. Ma \u00e8 possibile anche sfogliarlo comodamente online, cliccando su TU NEWS sfogliabile TU NEWS, PASSIONE PER L\u2019INFORMAZIONE","sameAs":["http:\/\/www.tunews24.it","www.facebook.com\/tunews24"],"url":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/author\/senzafirma\/"},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2019\/10\/23\/pronto-soccorso-dello-spaziani-intasato-ciacciarelli-bisogna-aprirne-uno-ad-anagni\/#local-main-organization-logo","url":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2022\/11\/cropped-il-corriere-della-provincia-testata-web-scontornata.png","contentUrl":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2022\/11\/cropped-il-corriere-della-provincia-testata-web-scontornata.png","width":2911,"height":717,"caption":"Globalpress s.r.l."}]}},"_links":{"self":[{"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/posts\/20732","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/users\/18"}],"replies":[{"embeddable":true,"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/comments?post=20732"}],"version-history":[{"count":2,"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/posts\/20732\/revisions"}],"predecessor-version":[{"id":20734,"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/posts\/20732\/revisions\/20734"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/media\/15899"}],"wp:attachment":[{"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/media?parent=20732"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/categories?post=20732"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/tags?post=20732"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}