{"id":20568,"date":"2019-10-21T12:05:21","date_gmt":"2019-10-21T10:05:21","guid":{"rendered":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/?p=20568"},"modified":"2019-10-22T18:05:26","modified_gmt":"2019-10-22T16:05:26","slug":"fratelli-ditalia-sempre-piu-nella-bufera-spaccature-anche-ad-anagni","status":"publish","type":"post","link":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2019\/10\/21\/fratelli-ditalia-sempre-piu-nella-bufera-spaccature-anche-ad-anagni\/","title":{"rendered":"Fratelli d&#8217;Italia sempre pi\u00f9 nella bufera. Spaccature anche ad Anagni"},"content":{"rendered":"<p><strong> Fratelli d&#8217;Italia Anagni risponde al consigliere Gianluigi Ferretti<\/strong> dopo il duro attacco mosso da quest&#8217;ultimo contro l&#8217;amministrazione Natalia in una conferenza stampa. Ma quello che emerge \u00e8 un partito spaccato a livello provinciale.<\/p>\n<h2><\/h2>\n<h2>L&#8217;intervento<\/h2>\n<p>&#8220;Ferretti \u00e8 solito evitare il confronto &#8211; dichiarano i consiglieri del partito della fiamma, Riccardo Ambrosetti (capogruppo), Alessandro Cardinali e Davide Salvati insieme all&#8217;assessore Jessica Chiarelli &#8211;\u00a0 lanciando attacchi aggressivi e poi trincerandosi dietro la definizione di &#8216;tecnico&#8217;, ma con questa storia della responsabilit\u00e0 e della competenza tecnica potr\u00e0 prendere in giro i suoi accoliti ed i suoi burattinai, di certo non noi. Diciamo questo innanzitutto perch\u00e9 sarebbe opportuno che Ferretti, se vuole continuare ad attaccare l&#8217;amministrazione comunale di Anagni<strong>, si dimettesse seduta stante dal gruppo consiliare di FdI a Palazzo Gramsci<\/strong> visto che, fino a prova contraria, FdI ad Anagni \u00e8 il gruppo preponderante della maggioranza e sostiene a spada tratta il sindaco Daniele Natalia&#8221;.<\/p>\n<p>&#8220;L&#8217;unica voce ufficiale ed autorevole di FdI ad Anagni &#8211; aggiungono &#8211; \u00e8 rappresentata dai consiglieri comunali &#8211; tra cui il segretario cittadino &#8211; e dall&#8217;assessore di riferimento. Altri, a cominciare da Ferretti, non possono intestarsi nulla a nome di FdI, al di l\u00e0 di fantomatiche \u201cscalate\u201d al partito e di articoli di stampa palesemente telecomandati. La leadership politica del segretario Ambrosetti \u00e8 incontestata dal circolo anagnino e dai veri attivisti di Fratelli d\u2019Italia&#8221;.<\/p>\n<h2><\/h2>\n<h2>FdI non \u00e8 un taxi<\/h2>\n<p>&#8220;Sarebbe opportuno da parte di Ferretti, noto trasformista, avere un minimo di dignit\u00e0 e smetterla di servire pi\u00f9 padroni contemporaneamente: o si sta in FdI e si collabora o si obbedisce agli apprendisti stregoni del &#8216;civismo d&#8217;interesse&#8217;. Delle due l&#8217;una; due piedi in una scarpa da chi <strong>\u00e8 stato prima sponsor di Bassetta e poi alleato di Casapound, fino a riciclarsi in Provincia con FdI<\/strong> non \u00e8 una posizione che possiamo accettare. Perch\u00e9 Ferretti pu\u00f2 permettersi questo tipo di esternazioni da consigliere provinciale di FdI senza nemmeno avere una tessera in tasca &#8211; ed aver sdegnosamente respinto l&#8217;ipotesi in Consiglio Comunale come se i partiti fossero solo dei &#8216;taxi&#8217; &#8211; e sedere impunemente tra i banchi dell&#8217;opposizione accanto alla sinistra politica e civica? Lui non vede contraddizione nella linea che porta avanti ma questo solo perch\u00e9 \u00e8 un camaleonte della politica, abituato a salire sul carro del vincitore, peccato per lui per\u00f2, sempre in ritardo, proprio come il suo mentore della societ\u00e0 civile anagnina. Forse anche per questo avr\u00e0 trasformato il suo desiderio recondito di fare l\u2019assessore in una presunta offerta da parte di qualcuno della maggioranza. Un\u2019offerta del genere \u2013 che sappiamo per certo non esserci mai stata \u2013 non \u00e8 arrivata da Fratelli d\u2019Italia Anagni che considera Ferretti come un avversario e non come un compagno di strada&#8221;.<\/p>\n<h2>L&#8217;affondo<\/h2>\n<p>&#8220;Basteranno due esempi &#8211; concludono &#8211; per dimostrare quanto Ferretti sia lontano da FdI e quanto poco dunque possa permettersi di parlare a nome del partito: su un tema d&#8217;importanza nazionale come l&#8217;immigrazione egli ha una visione legata al sistema affaristico delle cooperative di gestione; sul piano locale accetta senza troppi complimenti il consociativismo con il Partito Democratico strizzando l&#8217;occhio alle sinistre pur di mantenersi ben saldo sulla poltrona. Chiediamo a nome di Fratelli d&#8217;Italia Anagni, a scanso di equivoci, l&#8217;espulsione immediata di Gianluigi Ferretti dal gruppo consiliare di FdI alla Provincia&#8221;.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Fratelli d&#8217;Italia Anagni risponde al consigliere Gianluigi Ferretti dopo il duro attacco mosso da quest&#8217;ultimo contro l&#8217;amministrazione Natalia in una<\/p>\n","protected":false},"author":18,"featured_media":20569,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[41,28],"tags":[5160,5135,1012,6771,3675],"class_list":["post-20568","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-slide","category-politica","tag-alessandro-cardinali","tag-davide-salvati","tag-fratelli-ditalia","tag-gianluigi-ferretti","tag-riccardo-ambrosetti"],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v27.8 (Yoast SEO v27.8) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Fratelli d&#039;Italia sempre pi\u00f9 nella bufera. Spaccature anche ad Anagni - IlCorriereDellaProvincia.it - News h24 e notizie di approfondimento<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2019\/10\/21\/fratelli-ditalia-sempre-piu-nella-bufera-spaccature-anche-ad-anagni\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Fratelli d&#039;Italia sempre pi\u00f9 nella bufera. Spaccature anche ad Anagni\" \/>\n<meta property=\"og:description\" content=\"Fratelli d&#8217;Italia Anagni risponde al consigliere Gianluigi Ferretti dopo il duro attacco mosso da quest&#8217;ultimo contro l&#8217;amministrazione Natalia in una\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2019\/10\/21\/fratelli-ditalia-sempre-piu-nella-bufera-spaccature-anche-ad-anagni\/\" \/>\n<meta property=\"og:site_name\" content=\"IlCorriereDellaProvincia.it - News h24 e notizie di approfondimento\" \/>\n<meta property=\"article:author\" content=\"www.facebook.com\/tunews24\" \/>\n<meta property=\"article:published_time\" content=\"2019-10-21T10:05:21+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2019-10-22T16:05:26+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2019\/10\/natalia-e-ambrosetti-680x365_c.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"680\" \/>\n\t<meta property=\"og:image:height\" content=\"365\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Redazione\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"Redazione\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"3 minuti\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2019\\\/10\\\/21\\\/fratelli-ditalia-sempre-piu-nella-bufera-spaccature-anche-ad-anagni\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2019\\\/10\\\/21\\\/fratelli-ditalia-sempre-piu-nella-bufera-spaccature-anche-ad-anagni\\\/\"},\"author\":{\"name\":\"Redazione\",\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/#\\\/schema\\\/person\\\/6d7f0a9120d0c03d0c552e9fdf49ed7d\"},\"headline\":\"Fratelli d&#8217;Italia sempre pi\u00f9 nella bufera. Spaccature anche ad Anagni\",\"datePublished\":\"2019-10-21T10:05:21+00:00\",\"dateModified\":\"2019-10-22T16:05:26+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2019\\\/10\\\/21\\\/fratelli-ditalia-sempre-piu-nella-bufera-spaccature-anche-ad-anagni\\\/\"},\"wordCount\":563,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2019\\\/10\\\/21\\\/fratelli-ditalia-sempre-piu-nella-bufera-spaccature-anche-ad-anagni\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2019\\\/10\\\/natalia-e-ambrosetti-680x365_c.jpg\",\"keywords\":[\"alessandro cardinali\",\"Davide Salvati\",\"Fratelli d'Italia\",\"Gianluigi Ferretti\",\"riccardo ambrosetti\"],\"articleSection\":[\"*SLIDE*\",\"Evidenza\"],\"inLanguage\":\"it-IT\",\"copyrightYear\":\"2019\",\"copyrightHolder\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/#organization\"}},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2019\\\/10\\\/21\\\/fratelli-ditalia-sempre-piu-nella-bufera-spaccature-anche-ad-anagni\\\/\",\"url\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2019\\\/10\\\/21\\\/fratelli-ditalia-sempre-piu-nella-bufera-spaccature-anche-ad-anagni\\\/\",\"name\":\"Fratelli d'Italia sempre pi\u00f9 nella bufera. Spaccature anche ad Anagni - IlCorriereDellaProvincia.it - News h24 e notizie di approfondimento\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2019\\\/10\\\/21\\\/fratelli-ditalia-sempre-piu-nella-bufera-spaccature-anche-ad-anagni\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2019\\\/10\\\/21\\\/fratelli-ditalia-sempre-piu-nella-bufera-spaccature-anche-ad-anagni\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2019\\\/10\\\/natalia-e-ambrosetti-680x365_c.jpg\",\"datePublished\":\"2019-10-21T10:05:21+00:00\",\"dateModified\":\"2019-10-22T16:05:26+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2019\\\/10\\\/21\\\/fratelli-ditalia-sempre-piu-nella-bufera-spaccature-anche-ad-anagni\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2019\\\/10\\\/21\\\/fratelli-ditalia-sempre-piu-nella-bufera-spaccature-anche-ad-anagni\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2019\\\/10\\\/21\\\/fratelli-ditalia-sempre-piu-nella-bufera-spaccature-anche-ad-anagni\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2019\\\/10\\\/natalia-e-ambrosetti-680x365_c.jpg\",\"contentUrl\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2019\\\/10\\\/natalia-e-ambrosetti-680x365_c.jpg\",\"width\":680,\"height\":365},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2019\\\/10\\\/21\\\/fratelli-ditalia-sempre-piu-nella-bufera-spaccature-anche-ad-anagni\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Fratelli d&#8217;Italia sempre pi\u00f9 nella bufera. Spaccature anche ad Anagni\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/#website\",\"url\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/\",\"name\":\"Il Corriere Delle Provincia\",\"description\":\"IlCorriereDellaProvincia.it, quotidiano web di politica, cronaca, inchiesta, lavoro, scuola, turismo, cultura e spettacolo, economia e finanza, salute e benessere. Approfondimenti e notizie aggiornate con foto e video della provincia di Frosinone ma anche news nazionali, dell\u2019Italia e del Mondo.\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":[\"Organization\",\"Place\"],\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/#organization\",\"name\":\"Globalpress s.r.l.\",\"url\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/\",\"logo\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2019\\\/10\\\/21\\\/fratelli-ditalia-sempre-piu-nella-bufera-spaccature-anche-ad-anagni\\\/#local-main-organization-logo\"},\"image\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2019\\\/10\\\/21\\\/fratelli-ditalia-sempre-piu-nella-bufera-spaccature-anche-ad-anagni\\\/#local-main-organization-logo\"},\"telephone\":[],\"openingHoursSpecification\":[{\"@type\":\"OpeningHoursSpecification\",\"dayOfWeek\":[\"Monday\",\"Tuesday\",\"Wednesday\",\"Thursday\",\"Friday\",\"Saturday\",\"Sunday\"],\"opens\":\"09:00\",\"closes\":\"17:00\"}]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/#\\\/schema\\\/person\\\/6d7f0a9120d0c03d0c552e9fdf49ed7d\",\"name\":\"Redazione\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/a40eeacccdcad861f831dde73317f63a542e738f0dc4b79b9f47062d3d4bd1d2?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/a40eeacccdcad861f831dde73317f63a542e738f0dc4b79b9f47062d3d4bd1d2?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/a40eeacccdcad861f831dde73317f63a542e738f0dc4b79b9f47062d3d4bd1d2?s=96&d=mm&r=g\",\"caption\":\"Redazione\"},\"description\":\"SEGUICI ANCHE SUI SOCIAL Facebook: TuNews24 e TuSport24 Instagram: TuNews24 e TuSport24 Youtube: TuNews24 Telegram: TuNews24 Puoi leggerci anche in formato cartaceo: il settimanale viene pubblicato e distribuito gratuitamente ogni venerd\u00ec in edicole, bar, centri commerciali e svariati esercizi. Ma \u00e8 possibile anche sfogliarlo comodamente online, cliccando su TU NEWS sfogliabile TU NEWS, PASSIONE PER L\u2019INFORMAZIONE\",\"sameAs\":[\"http:\\\/\\\/www.tunews24.it\",\"www.facebook.com\\\/tunews24\"],\"url\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/author\\\/senzafirma\\\/\"},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2019\\\/10\\\/21\\\/fratelli-ditalia-sempre-piu-nella-bufera-spaccature-anche-ad-anagni\\\/#local-main-organization-logo\",\"url\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2022\\\/11\\\/cropped-il-corriere-della-provincia-testata-web-scontornata.png\",\"contentUrl\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2022\\\/11\\\/cropped-il-corriere-della-provincia-testata-web-scontornata.png\",\"width\":2911,\"height\":717,\"caption\":\"Globalpress s.r.l.\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Fratelli d'Italia sempre pi\u00f9 nella bufera. Spaccature anche ad Anagni - IlCorriereDellaProvincia.it - News h24 e notizie di approfondimento","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2019\/10\/21\/fratelli-ditalia-sempre-piu-nella-bufera-spaccature-anche-ad-anagni\/","og_locale":"it_IT","og_type":"article","og_title":"Fratelli d'Italia sempre pi\u00f9 nella bufera. Spaccature anche ad Anagni","og_description":"Fratelli d&#8217;Italia Anagni risponde al consigliere Gianluigi Ferretti dopo il duro attacco mosso da quest&#8217;ultimo contro l&#8217;amministrazione Natalia in una","og_url":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2019\/10\/21\/fratelli-ditalia-sempre-piu-nella-bufera-spaccature-anche-ad-anagni\/","og_site_name":"IlCorriereDellaProvincia.it - News h24 e notizie di approfondimento","article_author":"www.facebook.com\/tunews24","article_published_time":"2019-10-21T10:05:21+00:00","article_modified_time":"2019-10-22T16:05:26+00:00","og_image":[{"width":680,"height":365,"url":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2019\/10\/natalia-e-ambrosetti-680x365_c.jpg","type":"image\/jpeg"}],"author":"Redazione","twitter_card":"summary_large_image","twitter_misc":{"Scritto da":"Redazione","Tempo di lettura stimato":"3 minuti"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2019\/10\/21\/fratelli-ditalia-sempre-piu-nella-bufera-spaccature-anche-ad-anagni\/#article","isPartOf":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2019\/10\/21\/fratelli-ditalia-sempre-piu-nella-bufera-spaccature-anche-ad-anagni\/"},"author":{"name":"Redazione","@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/#\/schema\/person\/6d7f0a9120d0c03d0c552e9fdf49ed7d"},"headline":"Fratelli d&#8217;Italia sempre pi\u00f9 nella bufera. Spaccature anche ad Anagni","datePublished":"2019-10-21T10:05:21+00:00","dateModified":"2019-10-22T16:05:26+00:00","mainEntityOfPage":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2019\/10\/21\/fratelli-ditalia-sempre-piu-nella-bufera-spaccature-anche-ad-anagni\/"},"wordCount":563,"commentCount":0,"publisher":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/#organization"},"image":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2019\/10\/21\/fratelli-ditalia-sempre-piu-nella-bufera-spaccature-anche-ad-anagni\/#primaryimage"},"thumbnailUrl":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2019\/10\/natalia-e-ambrosetti-680x365_c.jpg","keywords":["alessandro cardinali","Davide Salvati","Fratelli d'Italia","Gianluigi Ferretti","riccardo ambrosetti"],"articleSection":["*SLIDE*","Evidenza"],"inLanguage":"it-IT","copyrightYear":"2019","copyrightHolder":{"@id":"https:\/\/www.tunews24.it\/#organization"}},{"@type":"WebPage","@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2019\/10\/21\/fratelli-ditalia-sempre-piu-nella-bufera-spaccature-anche-ad-anagni\/","url":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2019\/10\/21\/fratelli-ditalia-sempre-piu-nella-bufera-spaccature-anche-ad-anagni\/","name":"Fratelli d'Italia sempre pi\u00f9 nella bufera. Spaccature anche ad Anagni - IlCorriereDellaProvincia.it - News h24 e notizie di approfondimento","isPartOf":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2019\/10\/21\/fratelli-ditalia-sempre-piu-nella-bufera-spaccature-anche-ad-anagni\/#primaryimage"},"image":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2019\/10\/21\/fratelli-ditalia-sempre-piu-nella-bufera-spaccature-anche-ad-anagni\/#primaryimage"},"thumbnailUrl":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2019\/10\/natalia-e-ambrosetti-680x365_c.jpg","datePublished":"2019-10-21T10:05:21+00:00","dateModified":"2019-10-22T16:05:26+00:00","breadcrumb":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2019\/10\/21\/fratelli-ditalia-sempre-piu-nella-bufera-spaccature-anche-ad-anagni\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2019\/10\/21\/fratelli-ditalia-sempre-piu-nella-bufera-spaccature-anche-ad-anagni\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2019\/10\/21\/fratelli-ditalia-sempre-piu-nella-bufera-spaccature-anche-ad-anagni\/#primaryimage","url":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2019\/10\/natalia-e-ambrosetti-680x365_c.jpg","contentUrl":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2019\/10\/natalia-e-ambrosetti-680x365_c.jpg","width":680,"height":365},{"@type":"BreadcrumbList","@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2019\/10\/21\/fratelli-ditalia-sempre-piu-nella-bufera-spaccature-anche-ad-anagni\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/"},{"@type":"ListItem","position":2,"name":"Fratelli d&#8217;Italia sempre pi\u00f9 nella bufera. Spaccature anche ad Anagni"}]},{"@type":"WebSite","@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/#website","url":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/","name":"Il Corriere Delle Provincia","description":"IlCorriereDellaProvincia.it, quotidiano web di politica, cronaca, inchiesta, lavoro, scuola, turismo, cultura e spettacolo, economia e finanza, salute e benessere. Approfondimenti e notizie aggiornate con foto e video della provincia di Frosinone ma anche news nazionali, dell\u2019Italia e del Mondo.","publisher":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":["Organization","Place"],"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/#organization","name":"Globalpress s.r.l.","url":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/","logo":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2019\/10\/21\/fratelli-ditalia-sempre-piu-nella-bufera-spaccature-anche-ad-anagni\/#local-main-organization-logo"},"image":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2019\/10\/21\/fratelli-ditalia-sempre-piu-nella-bufera-spaccature-anche-ad-anagni\/#local-main-organization-logo"},"telephone":[],"openingHoursSpecification":[{"@type":"OpeningHoursSpecification","dayOfWeek":["Monday","Tuesday","Wednesday","Thursday","Friday","Saturday","Sunday"],"opens":"09:00","closes":"17:00"}]},{"@type":"Person","@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/#\/schema\/person\/6d7f0a9120d0c03d0c552e9fdf49ed7d","name":"Redazione","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/secure.gravatar.com\/avatar\/a40eeacccdcad861f831dde73317f63a542e738f0dc4b79b9f47062d3d4bd1d2?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/a40eeacccdcad861f831dde73317f63a542e738f0dc4b79b9f47062d3d4bd1d2?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/a40eeacccdcad861f831dde73317f63a542e738f0dc4b79b9f47062d3d4bd1d2?s=96&d=mm&r=g","caption":"Redazione"},"description":"SEGUICI ANCHE SUI SOCIAL Facebook: TuNews24 e TuSport24 Instagram: TuNews24 e TuSport24 Youtube: TuNews24 Telegram: TuNews24 Puoi leggerci anche in formato cartaceo: il settimanale viene pubblicato e distribuito gratuitamente ogni venerd\u00ec in edicole, bar, centri commerciali e svariati esercizi. Ma \u00e8 possibile anche sfogliarlo comodamente online, cliccando su TU NEWS sfogliabile TU NEWS, PASSIONE PER L\u2019INFORMAZIONE","sameAs":["http:\/\/www.tunews24.it","www.facebook.com\/tunews24"],"url":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/author\/senzafirma\/"},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2019\/10\/21\/fratelli-ditalia-sempre-piu-nella-bufera-spaccature-anche-ad-anagni\/#local-main-organization-logo","url":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2022\/11\/cropped-il-corriere-della-provincia-testata-web-scontornata.png","contentUrl":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2022\/11\/cropped-il-corriere-della-provincia-testata-web-scontornata.png","width":2911,"height":717,"caption":"Globalpress s.r.l."}]}},"_links":{"self":[{"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/posts\/20568","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/users\/18"}],"replies":[{"embeddable":true,"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/comments?post=20568"}],"version-history":[{"count":3,"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/posts\/20568\/revisions"}],"predecessor-version":[{"id":20573,"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/posts\/20568\/revisions\/20573"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/media\/20569"}],"wp:attachment":[{"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/media?parent=20568"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/categories?post=20568"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/tags?post=20568"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}