{"id":20499,"date":"2019-10-19T15:26:01","date_gmt":"2019-10-19T13:26:01","guid":{"rendered":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/?p=20499"},"modified":"2019-10-21T14:44:16","modified_gmt":"2019-10-21T12:44:16","slug":"incendio-saf-san-giovanni-incarico-fallone-migliorelli","status":"publish","type":"post","link":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2019\/10\/19\/incendio-saf-san-giovanni-incarico-fallone-migliorelli\/","title":{"rendered":"San Giovanni Incarico, la Saf finanzia il rimboschimento del Colle della Guardia"},"content":{"rendered":"<p><strong>La presidenza e il CdA<\/strong> hanno accolto la richiesta del sindaco Paolo Fallone, firmando un accordo in virt\u00f9 del quale la Societ\u00e0 Ambiente Frosinone sosterr\u00e0 l\u2019investimento \u2013\u00a0 spesa complessiva di 50.000 euro \u2013 per fornire al Comune gli alberi necessari a ricostituire il patrimonio boschivo del Colle della Guardia, il pi\u00f9 rappresentativo <strong>simbolo della fede cristiana della comunit\u00e0 sangiovannese distrutto da un incendio<\/strong> nel 2017.<\/p>\n<h2>L&#8217;intesa<\/h2>\n<p>La firma dell\u2019accordo cade proprio mentre la Regione Lazio presenta la campagna Ossigeno promossa dall\u2019amministrazione Zingaretti, che prevede la piantumazione sul territorio regionale di 6 milioni di alberi, uno per ogni abitante, perch\u00e9 il Lazio diventi sempre pi\u00f9 green. Sulla base di uno studio, la messa a dimora di 6 milioni di nuovi alberi consentir\u00e0 l\u2019assimilazione e la compensazione di <a href=\"tel:240000\" target=\"_blank\" rel=\"noopener\">240.000<\/a> tonnellate annue di anidride carbonica.<\/p>\n<h2><\/h2>\n<h2>Le parole di Migliorelli<\/h2>\n<p>\u201cLa nostra decisione \u2013<strong> spiega il presidente<\/strong> Lucio Migliorelli \u2013 va nella direzione del sostegno alla crescita della sostenibilit\u00e0 ambientale e del continuo miglioramento degli standard della qualit\u00e0 dell\u2019aria nei comuni, in particolare in quelli confinanti con il nostro impianto i quali proprio perch\u00e9 confinanti, come nel caso di San Giovanni, non hanno diritto a benefit di alcun genere. Un obiettivo che Saf perfeziona mese dopo mese grazie alla diminuzione del numero dei viaggi dei mezzi in entrata e in uscita e grazie al calo delle ore di lavorazione, combinazione di fattori che ha gi\u00e0 favorito negli ultimi due anni un significativo abbattimento delle emissioni in atmosfera. Questo accordo permetter\u00e0 al Comune di San Giovanni di ricomporre il patrimonio naturale pi\u00f9 caro alla comunit\u00e0 locale\u201d.<\/p>\n<p>&nbsp;<\/p>\n<figure id=\"attachment_5654\" aria-describedby=\"caption-attachment-5654\" style=\"width: 632px\" class=\"wp-caption aligncenter\"><img loading=\"lazy\" decoding=\"async\" class=\"size-full wp-image-5654\" src=\"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2019\/01\/Paolo-Fallone-680x365_c-e1563374715519.jpg\" alt=\"Paolo Fallone sindaco San Giovanni Incarico il corriere della provincia\" width=\"632\" height=\"339\" \/><figcaption id=\"caption-attachment-5654\" class=\"wp-caption-text\">Il sindaco di San Giovanni Incarico Paolo Fallone<\/figcaption><\/figure>\n<h2><\/h2>\n<h2>L&#8217;intervento di Fallone<\/h2>\n<p><strong>\u201c\u00c8 la prima volta che Saf riconosce una forma di ristoro al nostro Comune<\/strong>, che tra tutti \u00e8 quello che subisce i maggiori disagi derivanti dalla presenza dell\u2019impianto. \u00c8 emblematico che questo contributo, per il quale ringrazio il presidente, il CdA, la Regione Lazio e i Comuni soci, sia finalizzato a perseguire obiettivi di salvaguardia e miglioramento dell\u2019ambiente. \u00c8 l\u2019inizio di un nuovo capitolo \u2013 <strong>commenta Paolo Fallone, sindaco di San Giovanni<\/strong> \u2013 nella storia dei rapporti tra i due enti. Confidando sulla disponibilit\u00e0 al dialogo del presidente e del consiglio d\u2019amministrazione intavoler\u00f2 una trattativa per chiedere il riconoscimento di benefici diretti a favore dei miei concittadini, ad esempio uno sgravio sulla tassa rifiuti. Da oggi, con ancora pi\u00f9 convinzione di ieri, il nostro Comune sosterr\u00e0 il nuovo corso della Saf verso l\u2019economia circolare del rifiuto, augurandoci tempi brevi nel processo di radicale e innovativa trasformazione dell\u2019impianto da Tmb a Fabbrica dei Materiali\u201d.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>La presidenza e il CdA hanno accolto la richiesta del sindaco Paolo Fallone, firmando un accordo in virt\u00f9 del quale<\/p>\n","protected":false},"author":18,"featured_media":15158,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[4,2236],"tags":[6750,804,6748,6749,1601,1600],"class_list":["post-20499","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-primo-piano","category-attualita","tag-colle-della-guardia","tag-fallone","tag-migliorelli","tag-rimboschimento","tag-saf","tag-san-giovanni-incarico"],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v27.8 (Yoast SEO v27.8) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>San Giovanni Incarico, la Saf finanzia il rimboschimento del Colle della Guardia - IlCorriereDellaProvincia.it - News h24 e notizie di approfondimento<\/title>\n<meta name=\"description\" content=\"La firma dell\u2019accordo cade proprio mentre la Regione Lazio presenta la campagna Ossigeno promossa dall\u2019amministrazione Zingaretti\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2019\/10\/19\/incendio-saf-san-giovanni-incarico-fallone-migliorelli\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"San Giovanni Incarico, la Saf finanzia il rimboschimento del Colle della Guardia\" \/>\n<meta property=\"og:description\" content=\"La firma dell\u2019accordo cade proprio mentre la Regione Lazio presenta la campagna Ossigeno promossa dall\u2019amministrazione Zingaretti\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2019\/10\/19\/incendio-saf-san-giovanni-incarico-fallone-migliorelli\/\" \/>\n<meta property=\"og:site_name\" content=\"IlCorriereDellaProvincia.it - News h24 e notizie di approfondimento\" \/>\n<meta property=\"article:author\" content=\"www.facebook.com\/tunews24\" \/>\n<meta property=\"article:published_time\" content=\"2019-10-19T13:26:01+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2019-10-21T12:44:16+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2019\/07\/lucio-migliorelli.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"838\" \/>\n\t<meta property=\"og:image:height\" content=\"543\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Redazione\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"Redazione\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minuti\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2019\\\/10\\\/19\\\/incendio-saf-san-giovanni-incarico-fallone-migliorelli\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2019\\\/10\\\/19\\\/incendio-saf-san-giovanni-incarico-fallone-migliorelli\\\/\"},\"author\":{\"name\":\"Redazione\",\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/#\\\/schema\\\/person\\\/6d7f0a9120d0c03d0c552e9fdf49ed7d\"},\"headline\":\"San Giovanni Incarico, la Saf finanzia il rimboschimento del Colle della Guardia\",\"datePublished\":\"2019-10-19T13:26:01+00:00\",\"dateModified\":\"2019-10-21T12:44:16+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2019\\\/10\\\/19\\\/incendio-saf-san-giovanni-incarico-fallone-migliorelli\\\/\"},\"wordCount\":443,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2019\\\/10\\\/19\\\/incendio-saf-san-giovanni-incarico-fallone-migliorelli\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2019\\\/07\\\/lucio-migliorelli.jpg\",\"keywords\":[\"colle della guardia\",\"Fallone\",\"Migliorelli\",\"rimboschimento\",\"Saf\",\"San Giovanni Incarico\"],\"articleSection\":[\"*PRIMO PIANO*\",\"Attualit\u00e0\"],\"inLanguage\":\"it-IT\",\"copyrightYear\":\"2019\",\"copyrightHolder\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/#organization\"}},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2019\\\/10\\\/19\\\/incendio-saf-san-giovanni-incarico-fallone-migliorelli\\\/\",\"url\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2019\\\/10\\\/19\\\/incendio-saf-san-giovanni-incarico-fallone-migliorelli\\\/\",\"name\":\"San Giovanni Incarico, la Saf finanzia il rimboschimento del Colle della Guardia - IlCorriereDellaProvincia.it - News h24 e notizie di approfondimento\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2019\\\/10\\\/19\\\/incendio-saf-san-giovanni-incarico-fallone-migliorelli\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2019\\\/10\\\/19\\\/incendio-saf-san-giovanni-incarico-fallone-migliorelli\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2019\\\/07\\\/lucio-migliorelli.jpg\",\"datePublished\":\"2019-10-19T13:26:01+00:00\",\"dateModified\":\"2019-10-21T12:44:16+00:00\",\"description\":\"La firma dell\u2019accordo cade proprio mentre la Regione Lazio presenta la campagna Ossigeno promossa dall\u2019amministrazione Zingaretti\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2019\\\/10\\\/19\\\/incendio-saf-san-giovanni-incarico-fallone-migliorelli\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2019\\\/10\\\/19\\\/incendio-saf-san-giovanni-incarico-fallone-migliorelli\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2019\\\/10\\\/19\\\/incendio-saf-san-giovanni-incarico-fallone-migliorelli\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2019\\\/07\\\/lucio-migliorelli.jpg\",\"contentUrl\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2019\\\/07\\\/lucio-migliorelli.jpg\",\"width\":838,\"height\":543,\"caption\":\"Lucio Migliorelli\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2019\\\/10\\\/19\\\/incendio-saf-san-giovanni-incarico-fallone-migliorelli\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"San Giovanni Incarico, la Saf finanzia il rimboschimento del Colle della Guardia\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/#website\",\"url\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/\",\"name\":\"Il Corriere Delle Provincia\",\"description\":\"IlCorriereDellaProvincia.it, quotidiano web di politica, cronaca, inchiesta, lavoro, scuola, turismo, cultura e spettacolo, economia e finanza, salute e benessere. Approfondimenti e notizie aggiornate con foto e video della provincia di Frosinone ma anche news nazionali, dell\u2019Italia e del Mondo.\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":[\"Organization\",\"Place\"],\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/#organization\",\"name\":\"Globalpress s.r.l.\",\"url\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/\",\"logo\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2019\\\/10\\\/19\\\/incendio-saf-san-giovanni-incarico-fallone-migliorelli\\\/#local-main-organization-logo\"},\"image\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2019\\\/10\\\/19\\\/incendio-saf-san-giovanni-incarico-fallone-migliorelli\\\/#local-main-organization-logo\"},\"telephone\":[],\"openingHoursSpecification\":[{\"@type\":\"OpeningHoursSpecification\",\"dayOfWeek\":[\"Monday\",\"Tuesday\",\"Wednesday\",\"Thursday\",\"Friday\",\"Saturday\",\"Sunday\"],\"opens\":\"09:00\",\"closes\":\"17:00\"}]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/#\\\/schema\\\/person\\\/6d7f0a9120d0c03d0c552e9fdf49ed7d\",\"name\":\"Redazione\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/a40eeacccdcad861f831dde73317f63a542e738f0dc4b79b9f47062d3d4bd1d2?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/a40eeacccdcad861f831dde73317f63a542e738f0dc4b79b9f47062d3d4bd1d2?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/a40eeacccdcad861f831dde73317f63a542e738f0dc4b79b9f47062d3d4bd1d2?s=96&d=mm&r=g\",\"caption\":\"Redazione\"},\"description\":\"SEGUICI ANCHE SUI SOCIAL Facebook: TuNews24 e TuSport24 Instagram: TuNews24 e TuSport24 Youtube: TuNews24 Telegram: TuNews24 Puoi leggerci anche in formato cartaceo: il settimanale viene pubblicato e distribuito gratuitamente ogni venerd\u00ec in edicole, bar, centri commerciali e svariati esercizi. Ma \u00e8 possibile anche sfogliarlo comodamente online, cliccando su TU NEWS sfogliabile TU NEWS, PASSIONE PER L\u2019INFORMAZIONE\",\"sameAs\":[\"http:\\\/\\\/www.tunews24.it\",\"www.facebook.com\\\/tunews24\"],\"url\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/author\\\/senzafirma\\\/\"},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2019\\\/10\\\/19\\\/incendio-saf-san-giovanni-incarico-fallone-migliorelli\\\/#local-main-organization-logo\",\"url\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2022\\\/11\\\/cropped-il-corriere-della-provincia-testata-web-scontornata.png\",\"contentUrl\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2022\\\/11\\\/cropped-il-corriere-della-provincia-testata-web-scontornata.png\",\"width\":2911,\"height\":717,\"caption\":\"Globalpress s.r.l.\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"San Giovanni Incarico, la Saf finanzia il rimboschimento del Colle della Guardia - IlCorriereDellaProvincia.it - News h24 e notizie di approfondimento","description":"La firma dell\u2019accordo cade proprio mentre la Regione Lazio presenta la campagna Ossigeno promossa dall\u2019amministrazione Zingaretti","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2019\/10\/19\/incendio-saf-san-giovanni-incarico-fallone-migliorelli\/","og_locale":"it_IT","og_type":"article","og_title":"San Giovanni Incarico, la Saf finanzia il rimboschimento del Colle della Guardia","og_description":"La firma dell\u2019accordo cade proprio mentre la Regione Lazio presenta la campagna Ossigeno promossa dall\u2019amministrazione Zingaretti","og_url":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2019\/10\/19\/incendio-saf-san-giovanni-incarico-fallone-migliorelli\/","og_site_name":"IlCorriereDellaProvincia.it - News h24 e notizie di approfondimento","article_author":"www.facebook.com\/tunews24","article_published_time":"2019-10-19T13:26:01+00:00","article_modified_time":"2019-10-21T12:44:16+00:00","og_image":[{"width":838,"height":543,"url":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2019\/07\/lucio-migliorelli.jpg","type":"image\/jpeg"}],"author":"Redazione","twitter_card":"summary_large_image","twitter_misc":{"Scritto da":"Redazione","Tempo di lettura stimato":"2 minuti"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2019\/10\/19\/incendio-saf-san-giovanni-incarico-fallone-migliorelli\/#article","isPartOf":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2019\/10\/19\/incendio-saf-san-giovanni-incarico-fallone-migliorelli\/"},"author":{"name":"Redazione","@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/#\/schema\/person\/6d7f0a9120d0c03d0c552e9fdf49ed7d"},"headline":"San Giovanni Incarico, la Saf finanzia il rimboschimento del Colle della Guardia","datePublished":"2019-10-19T13:26:01+00:00","dateModified":"2019-10-21T12:44:16+00:00","mainEntityOfPage":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2019\/10\/19\/incendio-saf-san-giovanni-incarico-fallone-migliorelli\/"},"wordCount":443,"commentCount":0,"publisher":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/#organization"},"image":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2019\/10\/19\/incendio-saf-san-giovanni-incarico-fallone-migliorelli\/#primaryimage"},"thumbnailUrl":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2019\/07\/lucio-migliorelli.jpg","keywords":["colle della guardia","Fallone","Migliorelli","rimboschimento","Saf","San Giovanni Incarico"],"articleSection":["*PRIMO PIANO*","Attualit\u00e0"],"inLanguage":"it-IT","copyrightYear":"2019","copyrightHolder":{"@id":"https:\/\/www.tunews24.it\/#organization"}},{"@type":"WebPage","@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2019\/10\/19\/incendio-saf-san-giovanni-incarico-fallone-migliorelli\/","url":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2019\/10\/19\/incendio-saf-san-giovanni-incarico-fallone-migliorelli\/","name":"San Giovanni Incarico, la Saf finanzia il rimboschimento del Colle della Guardia - IlCorriereDellaProvincia.it - News h24 e notizie di approfondimento","isPartOf":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2019\/10\/19\/incendio-saf-san-giovanni-incarico-fallone-migliorelli\/#primaryimage"},"image":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2019\/10\/19\/incendio-saf-san-giovanni-incarico-fallone-migliorelli\/#primaryimage"},"thumbnailUrl":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2019\/07\/lucio-migliorelli.jpg","datePublished":"2019-10-19T13:26:01+00:00","dateModified":"2019-10-21T12:44:16+00:00","description":"La firma dell\u2019accordo cade proprio mentre la Regione Lazio presenta la campagna Ossigeno promossa dall\u2019amministrazione Zingaretti","breadcrumb":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2019\/10\/19\/incendio-saf-san-giovanni-incarico-fallone-migliorelli\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2019\/10\/19\/incendio-saf-san-giovanni-incarico-fallone-migliorelli\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2019\/10\/19\/incendio-saf-san-giovanni-incarico-fallone-migliorelli\/#primaryimage","url":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2019\/07\/lucio-migliorelli.jpg","contentUrl":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2019\/07\/lucio-migliorelli.jpg","width":838,"height":543,"caption":"Lucio Migliorelli"},{"@type":"BreadcrumbList","@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2019\/10\/19\/incendio-saf-san-giovanni-incarico-fallone-migliorelli\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/"},{"@type":"ListItem","position":2,"name":"San Giovanni Incarico, la Saf finanzia il rimboschimento del Colle della Guardia"}]},{"@type":"WebSite","@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/#website","url":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/","name":"Il Corriere Delle Provincia","description":"IlCorriereDellaProvincia.it, quotidiano web di politica, cronaca, inchiesta, lavoro, scuola, turismo, cultura e spettacolo, economia e finanza, salute e benessere. Approfondimenti e notizie aggiornate con foto e video della provincia di Frosinone ma anche news nazionali, dell\u2019Italia e del Mondo.","publisher":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":["Organization","Place"],"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/#organization","name":"Globalpress s.r.l.","url":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/","logo":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2019\/10\/19\/incendio-saf-san-giovanni-incarico-fallone-migliorelli\/#local-main-organization-logo"},"image":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2019\/10\/19\/incendio-saf-san-giovanni-incarico-fallone-migliorelli\/#local-main-organization-logo"},"telephone":[],"openingHoursSpecification":[{"@type":"OpeningHoursSpecification","dayOfWeek":["Monday","Tuesday","Wednesday","Thursday","Friday","Saturday","Sunday"],"opens":"09:00","closes":"17:00"}]},{"@type":"Person","@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/#\/schema\/person\/6d7f0a9120d0c03d0c552e9fdf49ed7d","name":"Redazione","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/secure.gravatar.com\/avatar\/a40eeacccdcad861f831dde73317f63a542e738f0dc4b79b9f47062d3d4bd1d2?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/a40eeacccdcad861f831dde73317f63a542e738f0dc4b79b9f47062d3d4bd1d2?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/a40eeacccdcad861f831dde73317f63a542e738f0dc4b79b9f47062d3d4bd1d2?s=96&d=mm&r=g","caption":"Redazione"},"description":"SEGUICI ANCHE SUI SOCIAL Facebook: TuNews24 e TuSport24 Instagram: TuNews24 e TuSport24 Youtube: TuNews24 Telegram: TuNews24 Puoi leggerci anche in formato cartaceo: il settimanale viene pubblicato e distribuito gratuitamente ogni venerd\u00ec in edicole, bar, centri commerciali e svariati esercizi. Ma \u00e8 possibile anche sfogliarlo comodamente online, cliccando su TU NEWS sfogliabile TU NEWS, PASSIONE PER L\u2019INFORMAZIONE","sameAs":["http:\/\/www.tunews24.it","www.facebook.com\/tunews24"],"url":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/author\/senzafirma\/"},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2019\/10\/19\/incendio-saf-san-giovanni-incarico-fallone-migliorelli\/#local-main-organization-logo","url":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2022\/11\/cropped-il-corriere-della-provincia-testata-web-scontornata.png","contentUrl":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2022\/11\/cropped-il-corriere-della-provincia-testata-web-scontornata.png","width":2911,"height":717,"caption":"Globalpress s.r.l."}]}},"_links":{"self":[{"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/posts\/20499","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/users\/18"}],"replies":[{"embeddable":true,"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/comments?post=20499"}],"version-history":[{"count":2,"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/posts\/20499\/revisions"}],"predecessor-version":[{"id":20501,"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/posts\/20499\/revisions\/20501"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/media\/15158"}],"wp:attachment":[{"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/media?parent=20499"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/categories?post=20499"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/tags?post=20499"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}