{"id":20470,"date":"2019-10-19T08:26:03","date_gmt":"2019-10-19T06:26:03","guid":{"rendered":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/?p=20470"},"modified":"2019-10-19T14:42:32","modified_gmt":"2019-10-19T12:42:32","slug":"revenge-porn-sara-battisti-regione-lazio-legge","status":"publish","type":"post","link":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2019\/10\/19\/revenge-porn-sara-battisti-regione-lazio-legge\/","title":{"rendered":"Revenge Porn, l&#8217;iniziativa di Sara Battisti per contrastare il fenomeno"},"content":{"rendered":"<p><strong>Revenge Porn, Sara Battisti prosegue la sua battaglia<\/strong>. Il consigliere regionale del Pd, proprio in questi giorni, ha presentato\u00a0all&#8217;XI Commissione la proposta di legge sul contrasto a tale fenomeno: &#8220;\u00c8 stato fatto il primo passo &#8211; spiega &#8211; per la definitiva approvazione da parte del\u00a0Consiglio Regionale. Si tratta di una legge molto importante, che qualificherebbe la\u00a0Regione Lazio come capofila per una battaglia di diritti che interessa tutti&#8221;.<\/p>\n<h2><\/h2>\n<h2>L&#8217;iniziativa<\/h2>\n<p>&#8220;Avevo gi\u00e0 depositato la proposto di legge nel marzo del 2019 &#8211; fa notare &#8211; \u00a0nelle more del dibattito in Parlamento\u00a0sull\u2019emendamento al DDL &#8216;Codice Rosso&#8217; che poi ha, di fatto, istituzionalizzato la\u00a0condivisione di video e immagini sessualmente espliciti come reato ai sensi dell\u2019art.\u00a0612 ter del codice penale. La mia proposta, per\u00f2, afferisce t<strong>ematiche diverse\u00a0rispetto a quelle della mera statuizione del reato<\/strong>&#8220;.<\/p>\n<h2><\/h2>\n<h2>L&#8217;obiettivo<\/h2>\n<p>&#8220;Nella proposta &#8211; argomenta Sara Battisti &#8211;<strong> voglio dare\u00a0strumenti alle vittime per difendersi in tribunale e per ricevere un adeguato\u00a0sostegno psicologico<\/strong>, tramite contributi per i soggetti del terzo settore che svolgono\u00a0attivit\u00e0 di assistenza legale e psicologica.\u00a0Un altro tema che ho affrontato nell\u2019articolato riguarda il reinserimento sociale e\u00a0lavorativo delle vittime. Come abbiamo purtroppo letto nelle cronache, chi subisce\u00a0questo tipo di reato, spesso \u00e8 costretto a cambiare casa, lavoro, finanche citt\u00e0\u00a0perch\u00e9 additato pubblicamente ed umiliato: ancora oggi le vittime di reati che\u00a0afferiscono la sfera sessuale, si sentono colpevoli e sono costrette a nascondersi,\u00a0anzich\u00e9 venire aiutate. Per questo occorre un grande lavoro culturale da parte delle\u00a0istituzioni, \u00e8 necessario che muti l\u2019humus in cui alberga l\u2019umiliazione per le vittime\u00a0ed emerga, invece, la loro voglia di giustizia sociale e la loro richiesta di aiuto senza\u00a0sentirsi sotto giudizio&#8221;.<\/p>\n<h2><\/h2>\n<h2>Puntare sulla sensibilizzazione<\/h2>\n<p>&#8220;Infine, ma probabilmente nel medio e lungo termine si tratta dell\u2019aspetto pi\u00f9\u00a0importante della mia proposta, ho voluto inserire il tema della sensibilizzazione\u00a0verso i sentimenti che riguardano la sfera dell\u2019affettivit\u00e0 e della sessualit\u00e0, anche e\u00a0soprattutto nelle scuole. Per questo, ho inserito tra gli interventi apposite campagne\u00a0di informazione in merito a questo reato affinch\u00e9 vengano proposti, anche da parte\u00a0dei media e new media, modelli positivi nelle relazioni intime.\u00a0Ci tengo a ringraziare &#8211; conclude il consigliere regionale &#8211; i numerosi colleghi di maggioranza che hanno, da subito,\u00a0sposato la mia battaglia a sostegno delle vittime di questo reato particolarmente\u00a0esecrabile: <strong>credo che le istituzioni non possano pensare che la sola formalizzazione\u00a0del reato sia sufficiente a scoraggiare il fenomeno<\/strong> che ha causato conseguenze\u00a0spesso estreme anche tra i giovanissimi.\u00a0Ora abbiamo il dovere di fornire strumenti concreti per far emergere i tanti casi\u00a0sommersi e inascoltati ed aiutare concretamente le vittime\u201d.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Revenge Porn, Sara Battisti prosegue la sua battaglia. Il consigliere regionale del Pd, proprio in questi giorni, ha presentato\u00a0all&#8217;XI Commissione<\/p>\n","protected":false},"author":18,"featured_media":5074,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[28],"tags":[6734,93,1946,562,6733,1721],"class_list":["post-20470","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-politica","tag-contrasto","tag-frosinone","tag-legge","tag-regione-lazio","tag-revenge-porn","tag-sara-battisti"],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v27.8 (Yoast SEO v27.8) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Revenge Porn, l&#039;iniziativa di Sara Battisti per contrastare il fenomeno - IlCorriereDellaProvincia.it - News h24 e notizie di approfondimento<\/title>\n<meta name=\"description\" content=\"Il consigliere regionale del Pd, proprio in questi giorni, ha presentato\u00a0all&#039;XI Commissione la \u00a0proposta di legge sul contrasto a tale fenomeno\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2019\/10\/19\/revenge-porn-sara-battisti-regione-lazio-legge\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Revenge Porn, l&#039;iniziativa di Sara Battisti per contrastare il fenomeno\" \/>\n<meta property=\"og:description\" content=\"Il consigliere regionale del Pd, proprio in questi giorni, ha presentato\u00a0all&#039;XI Commissione la \u00a0proposta di legge sul contrasto a tale fenomeno\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2019\/10\/19\/revenge-porn-sara-battisti-regione-lazio-legge\/\" \/>\n<meta property=\"og:site_name\" content=\"IlCorriereDellaProvincia.it - News h24 e notizie di approfondimento\" \/>\n<meta property=\"article:author\" content=\"www.facebook.com\/tunews24\" \/>\n<meta property=\"article:published_time\" content=\"2019-10-19T06:26:03+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2019-10-19T12:42:32+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2019\/01\/sara-battisti.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"860\" \/>\n\t<meta property=\"og:image:height\" content=\"488\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Redazione\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"Redazione\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minuti\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2019\\\/10\\\/19\\\/revenge-porn-sara-battisti-regione-lazio-legge\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2019\\\/10\\\/19\\\/revenge-porn-sara-battisti-regione-lazio-legge\\\/\"},\"author\":{\"name\":\"Redazione\",\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/#\\\/schema\\\/person\\\/6d7f0a9120d0c03d0c552e9fdf49ed7d\"},\"headline\":\"Revenge Porn, l&#8217;iniziativa di Sara Battisti per contrastare il fenomeno\",\"datePublished\":\"2019-10-19T06:26:03+00:00\",\"dateModified\":\"2019-10-19T12:42:32+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2019\\\/10\\\/19\\\/revenge-porn-sara-battisti-regione-lazio-legge\\\/\"},\"wordCount\":454,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2019\\\/10\\\/19\\\/revenge-porn-sara-battisti-regione-lazio-legge\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2019\\\/01\\\/sara-battisti.jpg\",\"keywords\":[\"contrasto\",\"Frosinone\",\"legge\",\"regione lazio\",\"Revenge Porn\",\"Sara Battisti\"],\"articleSection\":[\"Evidenza\"],\"inLanguage\":\"it-IT\",\"copyrightYear\":\"2019\",\"copyrightHolder\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/#organization\"}},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2019\\\/10\\\/19\\\/revenge-porn-sara-battisti-regione-lazio-legge\\\/\",\"url\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2019\\\/10\\\/19\\\/revenge-porn-sara-battisti-regione-lazio-legge\\\/\",\"name\":\"Revenge Porn, l'iniziativa di Sara Battisti per contrastare il fenomeno - IlCorriereDellaProvincia.it - News h24 e notizie di approfondimento\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2019\\\/10\\\/19\\\/revenge-porn-sara-battisti-regione-lazio-legge\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2019\\\/10\\\/19\\\/revenge-porn-sara-battisti-regione-lazio-legge\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2019\\\/01\\\/sara-battisti.jpg\",\"datePublished\":\"2019-10-19T06:26:03+00:00\",\"dateModified\":\"2019-10-19T12:42:32+00:00\",\"description\":\"Il consigliere regionale del Pd, proprio in questi giorni, ha presentato\u00a0all'XI Commissione la \u00a0proposta di legge sul contrasto a tale fenomeno\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2019\\\/10\\\/19\\\/revenge-porn-sara-battisti-regione-lazio-legge\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2019\\\/10\\\/19\\\/revenge-porn-sara-battisti-regione-lazio-legge\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2019\\\/10\\\/19\\\/revenge-porn-sara-battisti-regione-lazio-legge\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2019\\\/01\\\/sara-battisti.jpg\",\"contentUrl\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2019\\\/01\\\/sara-battisti.jpg\",\"width\":860,\"height\":488,\"caption\":\"sara battisti il corriere della provincia regione lazio frosinone ciociaria\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2019\\\/10\\\/19\\\/revenge-porn-sara-battisti-regione-lazio-legge\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Revenge Porn, l&#8217;iniziativa di Sara Battisti per contrastare il fenomeno\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/#website\",\"url\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/\",\"name\":\"Il Corriere Delle Provincia\",\"description\":\"IlCorriereDellaProvincia.it, quotidiano web di politica, cronaca, inchiesta, lavoro, scuola, turismo, cultura e spettacolo, economia e finanza, salute e benessere. Approfondimenti e notizie aggiornate con foto e video della provincia di Frosinone ma anche news nazionali, dell\u2019Italia e del Mondo.\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":[\"Organization\",\"Place\"],\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/#organization\",\"name\":\"Globalpress s.r.l.\",\"url\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/\",\"logo\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2019\\\/10\\\/19\\\/revenge-porn-sara-battisti-regione-lazio-legge\\\/#local-main-organization-logo\"},\"image\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2019\\\/10\\\/19\\\/revenge-porn-sara-battisti-regione-lazio-legge\\\/#local-main-organization-logo\"},\"telephone\":[],\"openingHoursSpecification\":[{\"@type\":\"OpeningHoursSpecification\",\"dayOfWeek\":[\"Monday\",\"Tuesday\",\"Wednesday\",\"Thursday\",\"Friday\",\"Saturday\",\"Sunday\"],\"opens\":\"09:00\",\"closes\":\"17:00\"}]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/#\\\/schema\\\/person\\\/6d7f0a9120d0c03d0c552e9fdf49ed7d\",\"name\":\"Redazione\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/a40eeacccdcad861f831dde73317f63a542e738f0dc4b79b9f47062d3d4bd1d2?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/a40eeacccdcad861f831dde73317f63a542e738f0dc4b79b9f47062d3d4bd1d2?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/a40eeacccdcad861f831dde73317f63a542e738f0dc4b79b9f47062d3d4bd1d2?s=96&d=mm&r=g\",\"caption\":\"Redazione\"},\"description\":\"SEGUICI ANCHE SUI SOCIAL Facebook: TuNews24 e TuSport24 Instagram: TuNews24 e TuSport24 Youtube: TuNews24 Telegram: TuNews24 Puoi leggerci anche in formato cartaceo: il settimanale viene pubblicato e distribuito gratuitamente ogni venerd\u00ec in edicole, bar, centri commerciali e svariati esercizi. Ma \u00e8 possibile anche sfogliarlo comodamente online, cliccando su TU NEWS sfogliabile TU NEWS, PASSIONE PER L\u2019INFORMAZIONE\",\"sameAs\":[\"http:\\\/\\\/www.tunews24.it\",\"www.facebook.com\\\/tunews24\"],\"url\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/author\\\/senzafirma\\\/\"},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2019\\\/10\\\/19\\\/revenge-porn-sara-battisti-regione-lazio-legge\\\/#local-main-organization-logo\",\"url\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2022\\\/11\\\/cropped-il-corriere-della-provincia-testata-web-scontornata.png\",\"contentUrl\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2022\\\/11\\\/cropped-il-corriere-della-provincia-testata-web-scontornata.png\",\"width\":2911,\"height\":717,\"caption\":\"Globalpress s.r.l.\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Revenge Porn, l'iniziativa di Sara Battisti per contrastare il fenomeno - IlCorriereDellaProvincia.it - News h24 e notizie di approfondimento","description":"Il consigliere regionale del Pd, proprio in questi giorni, ha presentato\u00a0all'XI Commissione la \u00a0proposta di legge sul contrasto a tale fenomeno","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2019\/10\/19\/revenge-porn-sara-battisti-regione-lazio-legge\/","og_locale":"it_IT","og_type":"article","og_title":"Revenge Porn, l'iniziativa di Sara Battisti per contrastare il fenomeno","og_description":"Il consigliere regionale del Pd, proprio in questi giorni, ha presentato\u00a0all'XI Commissione la \u00a0proposta di legge sul contrasto a tale fenomeno","og_url":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2019\/10\/19\/revenge-porn-sara-battisti-regione-lazio-legge\/","og_site_name":"IlCorriereDellaProvincia.it - News h24 e notizie di approfondimento","article_author":"www.facebook.com\/tunews24","article_published_time":"2019-10-19T06:26:03+00:00","article_modified_time":"2019-10-19T12:42:32+00:00","og_image":[{"width":860,"height":488,"url":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2019\/01\/sara-battisti.jpg","type":"image\/jpeg"}],"author":"Redazione","twitter_card":"summary_large_image","twitter_misc":{"Scritto da":"Redazione","Tempo di lettura stimato":"2 minuti"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2019\/10\/19\/revenge-porn-sara-battisti-regione-lazio-legge\/#article","isPartOf":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2019\/10\/19\/revenge-porn-sara-battisti-regione-lazio-legge\/"},"author":{"name":"Redazione","@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/#\/schema\/person\/6d7f0a9120d0c03d0c552e9fdf49ed7d"},"headline":"Revenge Porn, l&#8217;iniziativa di Sara Battisti per contrastare il fenomeno","datePublished":"2019-10-19T06:26:03+00:00","dateModified":"2019-10-19T12:42:32+00:00","mainEntityOfPage":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2019\/10\/19\/revenge-porn-sara-battisti-regione-lazio-legge\/"},"wordCount":454,"commentCount":0,"publisher":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/#organization"},"image":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2019\/10\/19\/revenge-porn-sara-battisti-regione-lazio-legge\/#primaryimage"},"thumbnailUrl":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2019\/01\/sara-battisti.jpg","keywords":["contrasto","Frosinone","legge","regione lazio","Revenge Porn","Sara Battisti"],"articleSection":["Evidenza"],"inLanguage":"it-IT","copyrightYear":"2019","copyrightHolder":{"@id":"https:\/\/www.tunews24.it\/#organization"}},{"@type":"WebPage","@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2019\/10\/19\/revenge-porn-sara-battisti-regione-lazio-legge\/","url":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2019\/10\/19\/revenge-porn-sara-battisti-regione-lazio-legge\/","name":"Revenge Porn, l'iniziativa di Sara Battisti per contrastare il fenomeno - IlCorriereDellaProvincia.it - News h24 e notizie di approfondimento","isPartOf":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2019\/10\/19\/revenge-porn-sara-battisti-regione-lazio-legge\/#primaryimage"},"image":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2019\/10\/19\/revenge-porn-sara-battisti-regione-lazio-legge\/#primaryimage"},"thumbnailUrl":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2019\/01\/sara-battisti.jpg","datePublished":"2019-10-19T06:26:03+00:00","dateModified":"2019-10-19T12:42:32+00:00","description":"Il consigliere regionale del Pd, proprio in questi giorni, ha presentato\u00a0all'XI Commissione la \u00a0proposta di legge sul contrasto a tale fenomeno","breadcrumb":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2019\/10\/19\/revenge-porn-sara-battisti-regione-lazio-legge\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2019\/10\/19\/revenge-porn-sara-battisti-regione-lazio-legge\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2019\/10\/19\/revenge-porn-sara-battisti-regione-lazio-legge\/#primaryimage","url":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2019\/01\/sara-battisti.jpg","contentUrl":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2019\/01\/sara-battisti.jpg","width":860,"height":488,"caption":"sara battisti il corriere della provincia regione lazio frosinone ciociaria"},{"@type":"BreadcrumbList","@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2019\/10\/19\/revenge-porn-sara-battisti-regione-lazio-legge\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/"},{"@type":"ListItem","position":2,"name":"Revenge Porn, l&#8217;iniziativa di Sara Battisti per contrastare il fenomeno"}]},{"@type":"WebSite","@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/#website","url":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/","name":"Il Corriere Delle Provincia","description":"IlCorriereDellaProvincia.it, quotidiano web di politica, cronaca, inchiesta, lavoro, scuola, turismo, cultura e spettacolo, economia e finanza, salute e benessere. Approfondimenti e notizie aggiornate con foto e video della provincia di Frosinone ma anche news nazionali, dell\u2019Italia e del Mondo.","publisher":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":["Organization","Place"],"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/#organization","name":"Globalpress s.r.l.","url":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/","logo":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2019\/10\/19\/revenge-porn-sara-battisti-regione-lazio-legge\/#local-main-organization-logo"},"image":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2019\/10\/19\/revenge-porn-sara-battisti-regione-lazio-legge\/#local-main-organization-logo"},"telephone":[],"openingHoursSpecification":[{"@type":"OpeningHoursSpecification","dayOfWeek":["Monday","Tuesday","Wednesday","Thursday","Friday","Saturday","Sunday"],"opens":"09:00","closes":"17:00"}]},{"@type":"Person","@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/#\/schema\/person\/6d7f0a9120d0c03d0c552e9fdf49ed7d","name":"Redazione","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/secure.gravatar.com\/avatar\/a40eeacccdcad861f831dde73317f63a542e738f0dc4b79b9f47062d3d4bd1d2?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/a40eeacccdcad861f831dde73317f63a542e738f0dc4b79b9f47062d3d4bd1d2?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/a40eeacccdcad861f831dde73317f63a542e738f0dc4b79b9f47062d3d4bd1d2?s=96&d=mm&r=g","caption":"Redazione"},"description":"SEGUICI ANCHE SUI SOCIAL Facebook: TuNews24 e TuSport24 Instagram: TuNews24 e TuSport24 Youtube: TuNews24 Telegram: TuNews24 Puoi leggerci anche in formato cartaceo: il settimanale viene pubblicato e distribuito gratuitamente ogni venerd\u00ec in edicole, bar, centri commerciali e svariati esercizi. Ma \u00e8 possibile anche sfogliarlo comodamente online, cliccando su TU NEWS sfogliabile TU NEWS, PASSIONE PER L\u2019INFORMAZIONE","sameAs":["http:\/\/www.tunews24.it","www.facebook.com\/tunews24"],"url":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/author\/senzafirma\/"},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2019\/10\/19\/revenge-porn-sara-battisti-regione-lazio-legge\/#local-main-organization-logo","url":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2022\/11\/cropped-il-corriere-della-provincia-testata-web-scontornata.png","contentUrl":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2022\/11\/cropped-il-corriere-della-provincia-testata-web-scontornata.png","width":2911,"height":717,"caption":"Globalpress s.r.l."}]}},"_links":{"self":[{"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/posts\/20470","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/users\/18"}],"replies":[{"embeddable":true,"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/comments?post=20470"}],"version-history":[{"count":2,"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/posts\/20470\/revisions"}],"predecessor-version":[{"id":20472,"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/posts\/20470\/revisions\/20472"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/media\/5074"}],"wp:attachment":[{"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/media?parent=20470"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/categories?post=20470"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/tags?post=20470"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}