{"id":20249,"date":"2019-10-16T07:57:45","date_gmt":"2019-10-16T05:57:45","guid":{"rendered":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/?p=20249"},"modified":"2019-10-16T18:16:53","modified_gmt":"2019-10-16T16:16:53","slug":"frosinone-isole-pedonali-al-centro-storico-vertice-tra-comune-e-commercianti","status":"publish","type":"post","link":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2019\/10\/16\/frosinone-isole-pedonali-al-centro-storico-vertice-tra-comune-e-commercianti\/","title":{"rendered":"Frosinone, isole pedonali al centro storico: vertice tra Comune e commercianti"},"content":{"rendered":"<p><strong>Il sindaco Nicola Ottaviani e agli assessori Rossella Testa e Antonio Scaccia<\/strong>, hanno incontrato i commercianti del centro storico di Frosinone per verificare lo stato di attuazione sul programma delle isole pedonali nella parte alta della citt\u00e0.<\/p>\n<h2><\/h2>\n<h2>L&#8217;obiettivo<\/h2>\n<p>A seguito di quello che sar\u00e0 anche l&#8217;evento della Notte Bianca, prevista per sabato 19 ottobre, si apporteranno ulteriori soluzioni per conciliare le esigenze del miglioramento della qualit\u00e0 dell&#8217;aria con quelle connesse al commercio e alla disciplina della circolazione stradale. Contestualmente, i<strong> rappresentanti degli esercenti, insieme all&#8217;amministrazione comunale, hanno concertato una serie di iniziative<\/strong> per rendere ancora pi\u00f9 appetibile il passeggio e l&#8217;arredo urbano nel periodo natalizio, attraverso nuovi investimenti e accorgimenti concordati nella partnership tra pubblico e privato.<\/p>\n<p>Alla fine del mese di ottobre \u00e8 stata <strong>fissata la prossima tappa per la verifica della sperimentazion<\/strong>e attualmente in atto, sempre nell&#8217;ottica di migliorare ulteriormente la sostenibilit\u00e0 ecologica, ambientale e commerciale del centro storico del capoluogo, a vantaggio anche dei residenti e dei visitatori provenienti dal resto del territorio provinciale.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Il sindaco Nicola Ottaviani e agli assessori Rossella Testa e Antonio Scaccia, hanno incontrato i commercianti del centro storico di<\/p>\n","protected":false},"author":18,"featured_media":20250,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[4,2236],"tags":[1434,94,93,5733,639,4306],"class_list":["post-20249","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-primo-piano","category-attualita","tag-antonio-scaccia","tag-ciociaria","tag-frosinone","tag-isole-pedonali","tag-nicola-ottaviani","tag-rossella-testa"],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v27.8 (Yoast SEO v27.8) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Frosinone, isole pedonali al centro storico: vertice tra Comune e commercianti - IlCorriereDellaProvincia.it - News h24 e notizie di approfondimento<\/title>\n<meta name=\"description\" content=\"I rappresentanti degli esercenti, insieme all&#039;amministrazione comunale, hanno concertato una serie di iniziative per rendere pi\u00f9 appetibile il passeggio\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2019\/10\/16\/frosinone-isole-pedonali-al-centro-storico-vertice-tra-comune-e-commercianti\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Frosinone, isole pedonali al centro storico: vertice tra Comune e commercianti\" \/>\n<meta property=\"og:description\" content=\"I rappresentanti degli esercenti, insieme all&#039;amministrazione comunale, hanno concertato una serie di iniziative per rendere pi\u00f9 appetibile il passeggio\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2019\/10\/16\/frosinone-isole-pedonali-al-centro-storico-vertice-tra-comune-e-commercianti\/\" \/>\n<meta property=\"og:site_name\" content=\"IlCorriereDellaProvincia.it - News h24 e notizie di approfondimento\" \/>\n<meta property=\"article:author\" content=\"www.facebook.com\/tunews24\" \/>\n<meta property=\"article:published_time\" content=\"2019-10-16T05:57:45+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2019-10-16T16:16:53+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2019\/10\/frosinone-isola-pedonale-Corso-della-repubblica.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"800\" \/>\n\t<meta property=\"og:image:height\" content=\"537\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Redazione\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"Redazione\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2019\\\/10\\\/16\\\/frosinone-isole-pedonali-al-centro-storico-vertice-tra-comune-e-commercianti\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2019\\\/10\\\/16\\\/frosinone-isole-pedonali-al-centro-storico-vertice-tra-comune-e-commercianti\\\/\"},\"author\":{\"name\":\"Redazione\",\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/#\\\/schema\\\/person\\\/6d7f0a9120d0c03d0c552e9fdf49ed7d\"},\"headline\":\"Frosinone, isole pedonali al centro storico: vertice tra Comune e commercianti\",\"datePublished\":\"2019-10-16T05:57:45+00:00\",\"dateModified\":\"2019-10-16T16:16:53+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2019\\\/10\\\/16\\\/frosinone-isole-pedonali-al-centro-storico-vertice-tra-comune-e-commercianti\\\/\"},\"wordCount\":182,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2019\\\/10\\\/16\\\/frosinone-isole-pedonali-al-centro-storico-vertice-tra-comune-e-commercianti\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2019\\\/10\\\/frosinone-isola-pedonale-Corso-della-repubblica.jpg\",\"keywords\":[\"antonio scaccia\",\"Ciociaria\",\"Frosinone\",\"isole pedonali\",\"nicola ottaviani\",\"Rossella Testa\"],\"articleSection\":[\"*PRIMO PIANO*\",\"Attualit\u00e0\"],\"inLanguage\":\"it-IT\",\"copyrightYear\":\"2019\",\"copyrightHolder\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/#organization\"}},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2019\\\/10\\\/16\\\/frosinone-isole-pedonali-al-centro-storico-vertice-tra-comune-e-commercianti\\\/\",\"url\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2019\\\/10\\\/16\\\/frosinone-isole-pedonali-al-centro-storico-vertice-tra-comune-e-commercianti\\\/\",\"name\":\"Frosinone, isole pedonali al centro storico: vertice tra Comune e commercianti - IlCorriereDellaProvincia.it - News h24 e notizie di approfondimento\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2019\\\/10\\\/16\\\/frosinone-isole-pedonali-al-centro-storico-vertice-tra-comune-e-commercianti\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2019\\\/10\\\/16\\\/frosinone-isole-pedonali-al-centro-storico-vertice-tra-comune-e-commercianti\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2019\\\/10\\\/frosinone-isola-pedonale-Corso-della-repubblica.jpg\",\"datePublished\":\"2019-10-16T05:57:45+00:00\",\"dateModified\":\"2019-10-16T16:16:53+00:00\",\"description\":\"I rappresentanti degli esercenti, insieme all'amministrazione comunale, hanno concertato una serie di iniziative per rendere pi\u00f9 appetibile il passeggio\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2019\\\/10\\\/16\\\/frosinone-isole-pedonali-al-centro-storico-vertice-tra-comune-e-commercianti\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2019\\\/10\\\/16\\\/frosinone-isole-pedonali-al-centro-storico-vertice-tra-comune-e-commercianti\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2019\\\/10\\\/16\\\/frosinone-isole-pedonali-al-centro-storico-vertice-tra-comune-e-commercianti\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2019\\\/10\\\/frosinone-isola-pedonale-Corso-della-repubblica.jpg\",\"contentUrl\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2019\\\/10\\\/frosinone-isola-pedonale-Corso-della-repubblica.jpg\",\"width\":800,\"height\":537},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2019\\\/10\\\/16\\\/frosinone-isole-pedonali-al-centro-storico-vertice-tra-comune-e-commercianti\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Frosinone, isole pedonali al centro storico: vertice tra Comune e commercianti\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/#website\",\"url\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/\",\"name\":\"Il Corriere Delle Provincia\",\"description\":\"IlCorriereDellaProvincia.it, quotidiano web di politica, cronaca, inchiesta, lavoro, scuola, turismo, cultura e spettacolo, economia e finanza, salute e benessere. Approfondimenti e notizie aggiornate con foto e video della provincia di Frosinone ma anche news nazionali, dell\u2019Italia e del Mondo.\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":[\"Organization\",\"Place\"],\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/#organization\",\"name\":\"Globalpress s.r.l.\",\"url\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/\",\"logo\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2019\\\/10\\\/16\\\/frosinone-isole-pedonali-al-centro-storico-vertice-tra-comune-e-commercianti\\\/#local-main-organization-logo\"},\"image\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2019\\\/10\\\/16\\\/frosinone-isole-pedonali-al-centro-storico-vertice-tra-comune-e-commercianti\\\/#local-main-organization-logo\"},\"telephone\":[],\"openingHoursSpecification\":[{\"@type\":\"OpeningHoursSpecification\",\"dayOfWeek\":[\"Monday\",\"Tuesday\",\"Wednesday\",\"Thursday\",\"Friday\",\"Saturday\",\"Sunday\"],\"opens\":\"09:00\",\"closes\":\"17:00\"}]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/#\\\/schema\\\/person\\\/6d7f0a9120d0c03d0c552e9fdf49ed7d\",\"name\":\"Redazione\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/a40eeacccdcad861f831dde73317f63a542e738f0dc4b79b9f47062d3d4bd1d2?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/a40eeacccdcad861f831dde73317f63a542e738f0dc4b79b9f47062d3d4bd1d2?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/a40eeacccdcad861f831dde73317f63a542e738f0dc4b79b9f47062d3d4bd1d2?s=96&d=mm&r=g\",\"caption\":\"Redazione\"},\"description\":\"SEGUICI ANCHE SUI SOCIAL Facebook: TuNews24 e TuSport24 Instagram: TuNews24 e TuSport24 Youtube: TuNews24 Telegram: TuNews24 Puoi leggerci anche in formato cartaceo: il settimanale viene pubblicato e distribuito gratuitamente ogni venerd\u00ec in edicole, bar, centri commerciali e svariati esercizi. Ma \u00e8 possibile anche sfogliarlo comodamente online, cliccando su TU NEWS sfogliabile TU NEWS, PASSIONE PER L\u2019INFORMAZIONE\",\"sameAs\":[\"http:\\\/\\\/www.tunews24.it\",\"www.facebook.com\\\/tunews24\"],\"url\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/author\\\/senzafirma\\\/\"},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2019\\\/10\\\/16\\\/frosinone-isole-pedonali-al-centro-storico-vertice-tra-comune-e-commercianti\\\/#local-main-organization-logo\",\"url\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2022\\\/11\\\/cropped-il-corriere-della-provincia-testata-web-scontornata.png\",\"contentUrl\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2022\\\/11\\\/cropped-il-corriere-della-provincia-testata-web-scontornata.png\",\"width\":2911,\"height\":717,\"caption\":\"Globalpress s.r.l.\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Frosinone, isole pedonali al centro storico: vertice tra Comune e commercianti - IlCorriereDellaProvincia.it - News h24 e notizie di approfondimento","description":"I rappresentanti degli esercenti, insieme all'amministrazione comunale, hanno concertato una serie di iniziative per rendere pi\u00f9 appetibile il passeggio","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2019\/10\/16\/frosinone-isole-pedonali-al-centro-storico-vertice-tra-comune-e-commercianti\/","og_locale":"it_IT","og_type":"article","og_title":"Frosinone, isole pedonali al centro storico: vertice tra Comune e commercianti","og_description":"I rappresentanti degli esercenti, insieme all'amministrazione comunale, hanno concertato una serie di iniziative per rendere pi\u00f9 appetibile il passeggio","og_url":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2019\/10\/16\/frosinone-isole-pedonali-al-centro-storico-vertice-tra-comune-e-commercianti\/","og_site_name":"IlCorriereDellaProvincia.it - News h24 e notizie di approfondimento","article_author":"www.facebook.com\/tunews24","article_published_time":"2019-10-16T05:57:45+00:00","article_modified_time":"2019-10-16T16:16:53+00:00","og_image":[{"width":800,"height":537,"url":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2019\/10\/frosinone-isola-pedonale-Corso-della-repubblica.jpg","type":"image\/jpeg"}],"author":"Redazione","twitter_card":"summary_large_image","twitter_misc":{"Scritto da":"Redazione","Tempo di lettura stimato":"1 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2019\/10\/16\/frosinone-isole-pedonali-al-centro-storico-vertice-tra-comune-e-commercianti\/#article","isPartOf":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2019\/10\/16\/frosinone-isole-pedonali-al-centro-storico-vertice-tra-comune-e-commercianti\/"},"author":{"name":"Redazione","@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/#\/schema\/person\/6d7f0a9120d0c03d0c552e9fdf49ed7d"},"headline":"Frosinone, isole pedonali al centro storico: vertice tra Comune e commercianti","datePublished":"2019-10-16T05:57:45+00:00","dateModified":"2019-10-16T16:16:53+00:00","mainEntityOfPage":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2019\/10\/16\/frosinone-isole-pedonali-al-centro-storico-vertice-tra-comune-e-commercianti\/"},"wordCount":182,"commentCount":0,"publisher":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/#organization"},"image":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2019\/10\/16\/frosinone-isole-pedonali-al-centro-storico-vertice-tra-comune-e-commercianti\/#primaryimage"},"thumbnailUrl":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2019\/10\/frosinone-isola-pedonale-Corso-della-repubblica.jpg","keywords":["antonio scaccia","Ciociaria","Frosinone","isole pedonali","nicola ottaviani","Rossella Testa"],"articleSection":["*PRIMO PIANO*","Attualit\u00e0"],"inLanguage":"it-IT","copyrightYear":"2019","copyrightHolder":{"@id":"https:\/\/www.tunews24.it\/#organization"}},{"@type":"WebPage","@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2019\/10\/16\/frosinone-isole-pedonali-al-centro-storico-vertice-tra-comune-e-commercianti\/","url":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2019\/10\/16\/frosinone-isole-pedonali-al-centro-storico-vertice-tra-comune-e-commercianti\/","name":"Frosinone, isole pedonali al centro storico: vertice tra Comune e commercianti - IlCorriereDellaProvincia.it - News h24 e notizie di approfondimento","isPartOf":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2019\/10\/16\/frosinone-isole-pedonali-al-centro-storico-vertice-tra-comune-e-commercianti\/#primaryimage"},"image":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2019\/10\/16\/frosinone-isole-pedonali-al-centro-storico-vertice-tra-comune-e-commercianti\/#primaryimage"},"thumbnailUrl":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2019\/10\/frosinone-isola-pedonale-Corso-della-repubblica.jpg","datePublished":"2019-10-16T05:57:45+00:00","dateModified":"2019-10-16T16:16:53+00:00","description":"I rappresentanti degli esercenti, insieme all'amministrazione comunale, hanno concertato una serie di iniziative per rendere pi\u00f9 appetibile il passeggio","breadcrumb":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2019\/10\/16\/frosinone-isole-pedonali-al-centro-storico-vertice-tra-comune-e-commercianti\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2019\/10\/16\/frosinone-isole-pedonali-al-centro-storico-vertice-tra-comune-e-commercianti\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2019\/10\/16\/frosinone-isole-pedonali-al-centro-storico-vertice-tra-comune-e-commercianti\/#primaryimage","url":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2019\/10\/frosinone-isola-pedonale-Corso-della-repubblica.jpg","contentUrl":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2019\/10\/frosinone-isola-pedonale-Corso-della-repubblica.jpg","width":800,"height":537},{"@type":"BreadcrumbList","@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2019\/10\/16\/frosinone-isole-pedonali-al-centro-storico-vertice-tra-comune-e-commercianti\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/"},{"@type":"ListItem","position":2,"name":"Frosinone, isole pedonali al centro storico: vertice tra Comune e commercianti"}]},{"@type":"WebSite","@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/#website","url":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/","name":"Il Corriere Delle Provincia","description":"IlCorriereDellaProvincia.it, quotidiano web di politica, cronaca, inchiesta, lavoro, scuola, turismo, cultura e spettacolo, economia e finanza, salute e benessere. Approfondimenti e notizie aggiornate con foto e video della provincia di Frosinone ma anche news nazionali, dell\u2019Italia e del Mondo.","publisher":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":["Organization","Place"],"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/#organization","name":"Globalpress s.r.l.","url":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/","logo":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2019\/10\/16\/frosinone-isole-pedonali-al-centro-storico-vertice-tra-comune-e-commercianti\/#local-main-organization-logo"},"image":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2019\/10\/16\/frosinone-isole-pedonali-al-centro-storico-vertice-tra-comune-e-commercianti\/#local-main-organization-logo"},"telephone":[],"openingHoursSpecification":[{"@type":"OpeningHoursSpecification","dayOfWeek":["Monday","Tuesday","Wednesday","Thursday","Friday","Saturday","Sunday"],"opens":"09:00","closes":"17:00"}]},{"@type":"Person","@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/#\/schema\/person\/6d7f0a9120d0c03d0c552e9fdf49ed7d","name":"Redazione","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/secure.gravatar.com\/avatar\/a40eeacccdcad861f831dde73317f63a542e738f0dc4b79b9f47062d3d4bd1d2?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/a40eeacccdcad861f831dde73317f63a542e738f0dc4b79b9f47062d3d4bd1d2?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/a40eeacccdcad861f831dde73317f63a542e738f0dc4b79b9f47062d3d4bd1d2?s=96&d=mm&r=g","caption":"Redazione"},"description":"SEGUICI ANCHE SUI SOCIAL Facebook: TuNews24 e TuSport24 Instagram: TuNews24 e TuSport24 Youtube: TuNews24 Telegram: TuNews24 Puoi leggerci anche in formato cartaceo: il settimanale viene pubblicato e distribuito gratuitamente ogni venerd\u00ec in edicole, bar, centri commerciali e svariati esercizi. Ma \u00e8 possibile anche sfogliarlo comodamente online, cliccando su TU NEWS sfogliabile TU NEWS, PASSIONE PER L\u2019INFORMAZIONE","sameAs":["http:\/\/www.tunews24.it","www.facebook.com\/tunews24"],"url":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/author\/senzafirma\/"},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2019\/10\/16\/frosinone-isole-pedonali-al-centro-storico-vertice-tra-comune-e-commercianti\/#local-main-organization-logo","url":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2022\/11\/cropped-il-corriere-della-provincia-testata-web-scontornata.png","contentUrl":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2022\/11\/cropped-il-corriere-della-provincia-testata-web-scontornata.png","width":2911,"height":717,"caption":"Globalpress s.r.l."}]}},"_links":{"self":[{"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/posts\/20249","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/users\/18"}],"replies":[{"embeddable":true,"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/comments?post=20249"}],"version-history":[{"count":1,"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/posts\/20249\/revisions"}],"predecessor-version":[{"id":20251,"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/posts\/20249\/revisions\/20251"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/media\/20250"}],"wp:attachment":[{"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/media?parent=20249"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/categories?post=20249"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/tags?post=20249"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}