{"id":19819,"date":"2019-10-11T13:26:40","date_gmt":"2019-10-11T11:26:40","guid":{"rendered":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/?p=19819"},"modified":"2019-10-12T08:39:10","modified_gmt":"2019-10-12T06:39:10","slug":"ad-arpino-parte-il-servizio-per-lo-smaltimento-degli-olii-esausti","status":"publish","type":"post","link":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2019\/10\/11\/ad-arpino-parte-il-servizio-per-lo-smaltimento-degli-olii-esausti\/","title":{"rendered":"Ad Arpino parte il servizio per lo smaltimento degli olii esausti"},"content":{"rendered":"<p>Nella giornata di luned\u00ec scorso, ad Arpino, sono stati installati<strong> cinque nuovi contenitori per la raccolta degli olii vegetali esausti<\/strong>, come gli olii da frittura e di conservazione degli alimenti.<\/p>\n<h2>Posizionati in cinque punti<\/h2>\n<p>I raccoglitori sono stati posizionati in cinque localit\u00e0 strategiche: nel centro storico presso il <strong>parcheggio in via delle Volte<\/strong> e nelle zone periferiche in <strong>piazza San Sosio<\/strong>, in localit\u00e0 <strong>Vignepiane<\/strong>, in localit\u00e0 <strong>Vuotti<\/strong> (piazza Attio Tullio) e in localit\u00e0 <strong>Collecarino<\/strong>, in prossimit\u00e0 della Chiesa parrocchiale.<\/p>\n<p>&nbsp;<\/p>\n<figure id=\"attachment_19820\" aria-describedby=\"caption-attachment-19820\" style=\"width: 605px\" class=\"wp-caption aligncenter\"><img loading=\"lazy\" decoding=\"async\" class=\"wp-image-19820 size-full\" src=\"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2019\/10\/raccoglitore-olii-esausti.jpg\" alt=\"raccoglitori olio esausto il corriere della provincia\" width=\"605\" height=\"807\" srcset=\"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2019\/10\/raccoglitore-olii-esausti.jpg 605w, https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2019\/10\/raccoglitore-olii-esausti-225x300.jpg 225w, https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2019\/10\/raccoglitore-olii-esausti-500x667.jpg 500w\" sizes=\"auto, (max-width: 605px) 100vw, 605px\" \/><figcaption id=\"caption-attachment-19820\" class=\"wp-caption-text\">Uno dei cinque raccoglitori di olii esausti posizionati in diversi punti di Arpino<\/figcaption><\/figure>\n<p>&nbsp;<\/p>\n<p><strong>L\u2019assessore all\u2019Ambiente Maria Manuel<\/strong> commenta: &#8220;Gli olii da frittura vengono spesso erroneamente smaltiti nei lavandini e nei bagni delle nostre case diventando fonte di grave inquinamento. L&#8217;installazione di questi raccoglitori consentir\u00e0 ai cittadini di smaltire correttamente gli oli vegetali esausti&#8221;.<\/p>\n<p>&#8220;\u00c8 quindi molto importante osservare attentamente le norme di corretto deposito e riciclo. In particolare, gli oli devono essere depositati negli appositi raccoglitori all\u2019interno di contenitori in plastica ben chiusi. \u00c8 assolutamente vietata la raccolta di altre tipologie di olio (olii minerali, olii motore etc.)&#8221;.<\/p>\n<p>&nbsp;<\/p>\n<figure id=\"attachment_19821\" aria-describedby=\"caption-attachment-19821\" style=\"width: 632px\" class=\"wp-caption aligncenter\"><img loading=\"lazy\" decoding=\"async\" class=\"wp-image-19821 size-full\" src=\"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2019\/10\/renato-rea-arpino-e1570792328278.jpg\" alt=\"sindaco arpino il corriere della provincia\" width=\"632\" height=\"339\" \/><figcaption id=\"caption-attachment-19821\" class=\"wp-caption-text\">Il sindaco di Arpino Renato Rea<\/figcaption><\/figure>\n<p>&nbsp;<\/p>\n<p><strong>Il sindaco Renato Rea<\/strong> conclude: &#8220;Questa iniziativa testimonia l&#8217;attenzione dell&#8217;Amministrazione comunale alle tematiche ambientali. Sar\u00e0 nostra cura promuovere una campagna di sensibilizzazione che miri ad un maggior rispetto del nostro territorio&#8221;.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Nella giornata di luned\u00ec scorso, ad Arpino, sono stati installati cinque nuovi contenitori per la raccolta degli olii vegetali esausti,<\/p>\n","protected":false},"author":18,"featured_media":19822,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[2236],"tags":[520,254,94,149,93,6559,6558,4671,117],"class_list":["post-19819","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-attualita","tag-ambiente","tag-arpino","tag-ciociaria","tag-comune","tag-frosinone","tag-olii-esausti","tag-raccoglitori","tag-renato-rea","tag-sindaco"],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v27.8 (Yoast SEO v27.8) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Ad Arpino parte il servizio per lo smaltimento degli olii esausti - IlCorriereDellaProvincia.it - News h24 e notizie di approfondimento<\/title>\n<meta name=\"description\" content=\"Nella giornata di luned\u00ec, ad Arpino, sono stati installati 5 nuovi contenitori per la raccolta degli olii vegetali esausti in diversi punti del territorio\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2019\/10\/11\/ad-arpino-parte-il-servizio-per-lo-smaltimento-degli-olii-esausti\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Ad Arpino parte il servizio per lo smaltimento degli olii esausti\" \/>\n<meta property=\"og:description\" content=\"Nella giornata di luned\u00ec, ad Arpino, sono stati installati 5 nuovi contenitori per la raccolta degli olii vegetali esausti in diversi punti del territorio\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2019\/10\/11\/ad-arpino-parte-il-servizio-per-lo-smaltimento-degli-olii-esausti\/\" \/>\n<meta property=\"og:site_name\" content=\"IlCorriereDellaProvincia.it - News h24 e notizie di approfondimento\" \/>\n<meta property=\"article:author\" content=\"www.facebook.com\/tunews24\" \/>\n<meta property=\"article:published_time\" content=\"2019-10-11T11:26:40+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2019-10-12T06:39:10+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2019\/10\/Veduta-Arpino-e1570792930331.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"632\" \/>\n\t<meta property=\"og:image:height\" content=\"363\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Redazione\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"Redazione\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2019\\\/10\\\/11\\\/ad-arpino-parte-il-servizio-per-lo-smaltimento-degli-olii-esausti\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2019\\\/10\\\/11\\\/ad-arpino-parte-il-servizio-per-lo-smaltimento-degli-olii-esausti\\\/\"},\"author\":{\"name\":\"Redazione\",\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/#\\\/schema\\\/person\\\/6d7f0a9120d0c03d0c552e9fdf49ed7d\"},\"headline\":\"Ad Arpino parte il servizio per lo smaltimento degli olii esausti\",\"datePublished\":\"2019-10-11T11:26:40+00:00\",\"dateModified\":\"2019-10-12T06:39:10+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2019\\\/10\\\/11\\\/ad-arpino-parte-il-servizio-per-lo-smaltimento-degli-olii-esausti\\\/\"},\"wordCount\":247,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2019\\\/10\\\/11\\\/ad-arpino-parte-il-servizio-per-lo-smaltimento-degli-olii-esausti\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2019\\\/10\\\/Veduta-Arpino-e1570792930331.jpg\",\"keywords\":[\"ambiente\",\"arpino\",\"Ciociaria\",\"comune\",\"Frosinone\",\"olii esausti\",\"raccoglitori\",\"renato rea\",\"Sindaco\"],\"articleSection\":[\"Attualit\u00e0\"],\"inLanguage\":\"it-IT\",\"copyrightYear\":\"2019\",\"copyrightHolder\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/#organization\"}},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2019\\\/10\\\/11\\\/ad-arpino-parte-il-servizio-per-lo-smaltimento-degli-olii-esausti\\\/\",\"url\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2019\\\/10\\\/11\\\/ad-arpino-parte-il-servizio-per-lo-smaltimento-degli-olii-esausti\\\/\",\"name\":\"Ad Arpino parte il servizio per lo smaltimento degli olii esausti - IlCorriereDellaProvincia.it - News h24 e notizie di approfondimento\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2019\\\/10\\\/11\\\/ad-arpino-parte-il-servizio-per-lo-smaltimento-degli-olii-esausti\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2019\\\/10\\\/11\\\/ad-arpino-parte-il-servizio-per-lo-smaltimento-degli-olii-esausti\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2019\\\/10\\\/Veduta-Arpino-e1570792930331.jpg\",\"datePublished\":\"2019-10-11T11:26:40+00:00\",\"dateModified\":\"2019-10-12T06:39:10+00:00\",\"description\":\"Nella giornata di luned\u00ec, ad Arpino, sono stati installati 5 nuovi contenitori per la raccolta degli olii vegetali esausti in diversi punti del territorio\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2019\\\/10\\\/11\\\/ad-arpino-parte-il-servizio-per-lo-smaltimento-degli-olii-esausti\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2019\\\/10\\\/11\\\/ad-arpino-parte-il-servizio-per-lo-smaltimento-degli-olii-esausti\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2019\\\/10\\\/11\\\/ad-arpino-parte-il-servizio-per-lo-smaltimento-degli-olii-esausti\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2019\\\/10\\\/Veduta-Arpino-e1570792930331.jpg\",\"contentUrl\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2019\\\/10\\\/Veduta-Arpino-e1570792930331.jpg\",\"width\":632,\"height\":363,\"caption\":\"Una veduta panoramica di Arpino\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2019\\\/10\\\/11\\\/ad-arpino-parte-il-servizio-per-lo-smaltimento-degli-olii-esausti\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Ad Arpino parte il servizio per lo smaltimento degli olii esausti\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/#website\",\"url\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/\",\"name\":\"Il Corriere Delle Provincia\",\"description\":\"IlCorriereDellaProvincia.it, quotidiano web di politica, cronaca, inchiesta, lavoro, scuola, turismo, cultura e spettacolo, economia e finanza, salute e benessere. Approfondimenti e notizie aggiornate con foto e video della provincia di Frosinone ma anche news nazionali, dell\u2019Italia e del Mondo.\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":[\"Organization\",\"Place\"],\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/#organization\",\"name\":\"Globalpress s.r.l.\",\"url\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/\",\"logo\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2019\\\/10\\\/11\\\/ad-arpino-parte-il-servizio-per-lo-smaltimento-degli-olii-esausti\\\/#local-main-organization-logo\"},\"image\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2019\\\/10\\\/11\\\/ad-arpino-parte-il-servizio-per-lo-smaltimento-degli-olii-esausti\\\/#local-main-organization-logo\"},\"telephone\":[],\"openingHoursSpecification\":[{\"@type\":\"OpeningHoursSpecification\",\"dayOfWeek\":[\"Monday\",\"Tuesday\",\"Wednesday\",\"Thursday\",\"Friday\",\"Saturday\",\"Sunday\"],\"opens\":\"09:00\",\"closes\":\"17:00\"}]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/#\\\/schema\\\/person\\\/6d7f0a9120d0c03d0c552e9fdf49ed7d\",\"name\":\"Redazione\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/a40eeacccdcad861f831dde73317f63a542e738f0dc4b79b9f47062d3d4bd1d2?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/a40eeacccdcad861f831dde73317f63a542e738f0dc4b79b9f47062d3d4bd1d2?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/a40eeacccdcad861f831dde73317f63a542e738f0dc4b79b9f47062d3d4bd1d2?s=96&d=mm&r=g\",\"caption\":\"Redazione\"},\"description\":\"SEGUICI ANCHE SUI SOCIAL Facebook: TuNews24 e TuSport24 Instagram: TuNews24 e TuSport24 Youtube: TuNews24 Telegram: TuNews24 Puoi leggerci anche in formato cartaceo: il settimanale viene pubblicato e distribuito gratuitamente ogni venerd\u00ec in edicole, bar, centri commerciali e svariati esercizi. Ma \u00e8 possibile anche sfogliarlo comodamente online, cliccando su TU NEWS sfogliabile TU NEWS, PASSIONE PER L\u2019INFORMAZIONE\",\"sameAs\":[\"http:\\\/\\\/www.tunews24.it\",\"www.facebook.com\\\/tunews24\"],\"url\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/author\\\/senzafirma\\\/\"},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2019\\\/10\\\/11\\\/ad-arpino-parte-il-servizio-per-lo-smaltimento-degli-olii-esausti\\\/#local-main-organization-logo\",\"url\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2022\\\/11\\\/cropped-il-corriere-della-provincia-testata-web-scontornata.png\",\"contentUrl\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2022\\\/11\\\/cropped-il-corriere-della-provincia-testata-web-scontornata.png\",\"width\":2911,\"height\":717,\"caption\":\"Globalpress s.r.l.\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Ad Arpino parte il servizio per lo smaltimento degli olii esausti - IlCorriereDellaProvincia.it - News h24 e notizie di approfondimento","description":"Nella giornata di luned\u00ec, ad Arpino, sono stati installati 5 nuovi contenitori per la raccolta degli olii vegetali esausti in diversi punti del territorio","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2019\/10\/11\/ad-arpino-parte-il-servizio-per-lo-smaltimento-degli-olii-esausti\/","og_locale":"it_IT","og_type":"article","og_title":"Ad Arpino parte il servizio per lo smaltimento degli olii esausti","og_description":"Nella giornata di luned\u00ec, ad Arpino, sono stati installati 5 nuovi contenitori per la raccolta degli olii vegetali esausti in diversi punti del territorio","og_url":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2019\/10\/11\/ad-arpino-parte-il-servizio-per-lo-smaltimento-degli-olii-esausti\/","og_site_name":"IlCorriereDellaProvincia.it - News h24 e notizie di approfondimento","article_author":"www.facebook.com\/tunews24","article_published_time":"2019-10-11T11:26:40+00:00","article_modified_time":"2019-10-12T06:39:10+00:00","og_image":[{"width":632,"height":363,"url":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2019\/10\/Veduta-Arpino-e1570792930331.jpg","type":"image\/jpeg"}],"author":"Redazione","twitter_card":"summary_large_image","twitter_misc":{"Scritto da":"Redazione","Tempo di lettura stimato":"1 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2019\/10\/11\/ad-arpino-parte-il-servizio-per-lo-smaltimento-degli-olii-esausti\/#article","isPartOf":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2019\/10\/11\/ad-arpino-parte-il-servizio-per-lo-smaltimento-degli-olii-esausti\/"},"author":{"name":"Redazione","@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/#\/schema\/person\/6d7f0a9120d0c03d0c552e9fdf49ed7d"},"headline":"Ad Arpino parte il servizio per lo smaltimento degli olii esausti","datePublished":"2019-10-11T11:26:40+00:00","dateModified":"2019-10-12T06:39:10+00:00","mainEntityOfPage":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2019\/10\/11\/ad-arpino-parte-il-servizio-per-lo-smaltimento-degli-olii-esausti\/"},"wordCount":247,"commentCount":0,"publisher":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/#organization"},"image":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2019\/10\/11\/ad-arpino-parte-il-servizio-per-lo-smaltimento-degli-olii-esausti\/#primaryimage"},"thumbnailUrl":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2019\/10\/Veduta-Arpino-e1570792930331.jpg","keywords":["ambiente","arpino","Ciociaria","comune","Frosinone","olii esausti","raccoglitori","renato rea","Sindaco"],"articleSection":["Attualit\u00e0"],"inLanguage":"it-IT","copyrightYear":"2019","copyrightHolder":{"@id":"https:\/\/www.tunews24.it\/#organization"}},{"@type":"WebPage","@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2019\/10\/11\/ad-arpino-parte-il-servizio-per-lo-smaltimento-degli-olii-esausti\/","url":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2019\/10\/11\/ad-arpino-parte-il-servizio-per-lo-smaltimento-degli-olii-esausti\/","name":"Ad Arpino parte il servizio per lo smaltimento degli olii esausti - IlCorriereDellaProvincia.it - News h24 e notizie di approfondimento","isPartOf":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2019\/10\/11\/ad-arpino-parte-il-servizio-per-lo-smaltimento-degli-olii-esausti\/#primaryimage"},"image":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2019\/10\/11\/ad-arpino-parte-il-servizio-per-lo-smaltimento-degli-olii-esausti\/#primaryimage"},"thumbnailUrl":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2019\/10\/Veduta-Arpino-e1570792930331.jpg","datePublished":"2019-10-11T11:26:40+00:00","dateModified":"2019-10-12T06:39:10+00:00","description":"Nella giornata di luned\u00ec, ad Arpino, sono stati installati 5 nuovi contenitori per la raccolta degli olii vegetali esausti in diversi punti del territorio","breadcrumb":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2019\/10\/11\/ad-arpino-parte-il-servizio-per-lo-smaltimento-degli-olii-esausti\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2019\/10\/11\/ad-arpino-parte-il-servizio-per-lo-smaltimento-degli-olii-esausti\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2019\/10\/11\/ad-arpino-parte-il-servizio-per-lo-smaltimento-degli-olii-esausti\/#primaryimage","url":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2019\/10\/Veduta-Arpino-e1570792930331.jpg","contentUrl":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2019\/10\/Veduta-Arpino-e1570792930331.jpg","width":632,"height":363,"caption":"Una veduta panoramica di Arpino"},{"@type":"BreadcrumbList","@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2019\/10\/11\/ad-arpino-parte-il-servizio-per-lo-smaltimento-degli-olii-esausti\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/"},{"@type":"ListItem","position":2,"name":"Ad Arpino parte il servizio per lo smaltimento degli olii esausti"}]},{"@type":"WebSite","@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/#website","url":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/","name":"Il Corriere Delle Provincia","description":"IlCorriereDellaProvincia.it, quotidiano web di politica, cronaca, inchiesta, lavoro, scuola, turismo, cultura e spettacolo, economia e finanza, salute e benessere. Approfondimenti e notizie aggiornate con foto e video della provincia di Frosinone ma anche news nazionali, dell\u2019Italia e del Mondo.","publisher":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":["Organization","Place"],"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/#organization","name":"Globalpress s.r.l.","url":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/","logo":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2019\/10\/11\/ad-arpino-parte-il-servizio-per-lo-smaltimento-degli-olii-esausti\/#local-main-organization-logo"},"image":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2019\/10\/11\/ad-arpino-parte-il-servizio-per-lo-smaltimento-degli-olii-esausti\/#local-main-organization-logo"},"telephone":[],"openingHoursSpecification":[{"@type":"OpeningHoursSpecification","dayOfWeek":["Monday","Tuesday","Wednesday","Thursday","Friday","Saturday","Sunday"],"opens":"09:00","closes":"17:00"}]},{"@type":"Person","@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/#\/schema\/person\/6d7f0a9120d0c03d0c552e9fdf49ed7d","name":"Redazione","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/secure.gravatar.com\/avatar\/a40eeacccdcad861f831dde73317f63a542e738f0dc4b79b9f47062d3d4bd1d2?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/a40eeacccdcad861f831dde73317f63a542e738f0dc4b79b9f47062d3d4bd1d2?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/a40eeacccdcad861f831dde73317f63a542e738f0dc4b79b9f47062d3d4bd1d2?s=96&d=mm&r=g","caption":"Redazione"},"description":"SEGUICI ANCHE SUI SOCIAL Facebook: TuNews24 e TuSport24 Instagram: TuNews24 e TuSport24 Youtube: TuNews24 Telegram: TuNews24 Puoi leggerci anche in formato cartaceo: il settimanale viene pubblicato e distribuito gratuitamente ogni venerd\u00ec in edicole, bar, centri commerciali e svariati esercizi. Ma \u00e8 possibile anche sfogliarlo comodamente online, cliccando su TU NEWS sfogliabile TU NEWS, PASSIONE PER L\u2019INFORMAZIONE","sameAs":["http:\/\/www.tunews24.it","www.facebook.com\/tunews24"],"url":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/author\/senzafirma\/"},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2019\/10\/11\/ad-arpino-parte-il-servizio-per-lo-smaltimento-degli-olii-esausti\/#local-main-organization-logo","url":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2022\/11\/cropped-il-corriere-della-provincia-testata-web-scontornata.png","contentUrl":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2022\/11\/cropped-il-corriere-della-provincia-testata-web-scontornata.png","width":2911,"height":717,"caption":"Globalpress s.r.l."}]}},"_links":{"self":[{"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/posts\/19819","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/users\/18"}],"replies":[{"embeddable":true,"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/comments?post=19819"}],"version-history":[{"count":1,"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/posts\/19819\/revisions"}],"predecessor-version":[{"id":19823,"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/posts\/19819\/revisions\/19823"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/media\/19822"}],"wp:attachment":[{"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/media?parent=19819"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/categories?post=19819"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/tags?post=19819"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}