{"id":19166,"date":"2019-10-04T15:16:58","date_gmt":"2019-10-04T13:16:58","guid":{"rendered":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/?p=19166"},"modified":"2019-10-04T15:20:15","modified_gmt":"2019-10-04T13:20:15","slug":"isola-del-liri-una-giornata-tra-arte-gusto-e-turismo","status":"publish","type":"post","link":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2019\/10\/04\/isola-del-liri-una-giornata-tra-arte-gusto-e-turismo\/","title":{"rendered":"Isola del Liri: una giornata tra arte, gusto e turismo"},"content":{"rendered":"<p><strong>Si rinnova anche per il 2019 l<\/strong>a giornata dedicata all\u2019arte, al gusto ed al turismo che si svolger\u00e0 venerd\u00ec 11 ottobre 2019 ad \u00a0Isola del Liri. A darne notizia il sindaco della citt\u00e0 di Isola del Liri, Massimiliano Quadrini.<\/p>\n<p>&nbsp;<\/p>\n<figure id=\"attachment_9017\" aria-describedby=\"caption-attachment-9017\" style=\"width: 632px\" class=\"wp-caption aligncenter\"><img loading=\"lazy\" decoding=\"async\" class=\"size-full wp-image-9017\" src=\"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2019\/03\/massimiliano-quadrini-isola-e1554032372889.jpg\" alt=\"massimiliano quadrini isola del liri il corriere della provincia\" width=\"632\" height=\"418\" \/><figcaption id=\"caption-attachment-9017\" class=\"wp-caption-text\">Massimiliano Quadrini, sindaco di Isola del Liri<\/figcaption><\/figure>\n<h2><\/h2>\n<h2>L&#8217;intervento<\/h2>\n<p>&#8220;In programma ci sono numerosi momenti di incontro e spettacolo che si svolgeranno durante l\u2019intera giornata. L&#8217;invito \u00e8 a tutta la cittadinanza e a tutti gli amanti dell&#8217;arte e delle nostre tradizioni, anche culinarie. \u00c8 l&#8217;ennesimo evento che questa Amministrazione propone al territorio. Un impegno costante e quotidiano il nostro &#8211; ha aggiunto Massimiliano Quadrini &#8211; che si \u00e8 tradotto in tante manifestazioni di successo. Questo conferma l&#8217;ottimo lavoro che stiamo facendo. Ringrazio gli amministratori comunali e gli organizzatori che hanno allestito una giornata particolarmente interessante che, sono certo, vedr\u00e0 la partecipazione di molte persone. <strong>Ringrazio inoltre l\u2019onorevole Mauro Buschini<\/strong> per l\u2019immancabile sensibilit\u00e0 istituzionale e per il costante sostegno alle nostre iniziative, a garanzia \u00a0della crescita costante delle attivit\u00e0 poste in essere da questa amministrazione per lo sviluppo sociale e culturale del nostro territorio&#8221;.<\/p>\n<h2><\/h2>\n<h2>Il programma<\/h2>\n<p>La mattinata del prossimo 11 ottobre, inizier\u00e0 con un percorso turistico, accompagnato da esperti del territorio, che, <strong>dalle 10.30 inizier\u00e0 dalla ex-Cartiera<\/strong> \u201cLefevbre\u201d, per poi proseguire nel centro storico cittadino fino a raggiungere la \u201cGalleria Pisani\u201d e la Cascata Grande che potr\u00e0 essere ammirata da vicino Non mancher\u00e0 un momento di degustazione di prodotti tipici locali .<\/p>\n<h2><\/h2>\n<h2>Tra mostre e balletti<\/h2>\n<p>Alle ore 20.00, presso il Cinemateatro &#8216;Mangoni&#8217; sar\u00e0 allestita ed inaugurata la mostra fotografica realizzata per il corpo di ballo <strong>&#8216;Balletto di Chieti&#8217;<\/strong>, che si esibir\u00e0 la sera stessa alle 21.00. La mostra vedr\u00e0 l\u2019esposizione di immagini dei ballerini durante i loro spettacoli, nei backstage e nei momenti di pausa. Alle 20.30 avremo un interessante concerto con l\u2019esibizione di giovani artisti della locale &#8216;Accademia Musicale Isolana&#8217;, diretti dal Maestro Sandro Taglione.<\/p>\n<p>I ragazzi affronteranno un repertorio musicale che costituir\u00e0 il filo conduttore della giornata, in particolare, verranno eseguiti i brani dello spettacolo di ballo che concluder\u00e0 la giornata. Infatti, a conclusione dell\u2019evento, si potr\u00e0 assistere, alle ore 21.00, allo spettacolo dal titolo &#8216;<strong>Lirica in Danza&#8217;<\/strong>, magistralmente rappresentato dalla &#8216;Balletto di Chieti&#8217; con il Coreografo Tuccio Rigano.<\/p>\n<p>Per la seconda volta questa compagnia presenter\u00e0 un suggestivo spettacolo ad Citt\u00e0 di Isola del Liri in un contesto di attivit\u00e0 che mirano a valorizzare tutti gli aspetti peculiari della citt\u00e0: le arti, il turismo, il cibo. Isola del Liri si conferma \u201ccitt\u00e0 della Musica\u201d e rinnova uno spettacolo straordinario, ballerini professionisti si esibiranno dando valore alla musica ed al movimento, un connubio magico che coinvolger\u00e0 tutti i partecipanti. L\u2019ingresso al Cinemateatro \u00e8 libero e gratuito<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Si rinnova anche per il 2019 la giornata dedicata all\u2019arte, al gusto ed al turismo che si svolger\u00e0 venerd\u00ec 11<\/p>\n","protected":false},"author":18,"featured_media":19170,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[4,1],"tags":[6434,260,1775,1388,117],"class_list":["post-19166","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-primo-piano","category-news","tag-isola-del-gusto","tag-isola-del-liri","tag-massimiliano-quadrini","tag-mauro-buschini","tag-sindaco"],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v27.8 (Yoast SEO v27.8) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Isola del Liri: una giornata tra arte, gusto e turismo - IlCorriereDellaProvincia.it - News h24 e notizie di approfondimento<\/title>\n<meta name=\"description\" content=\"La mattinata dell&#039;11 ottobre, inizier\u00e0 con un percorso turistico, accompagnato da esperti del territorio, che, dalle 10.30 inizier\u00e0 dalla ex-Cartiera\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2019\/10\/04\/isola-del-liri-una-giornata-tra-arte-gusto-e-turismo\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Isola del Liri: una giornata tra arte, gusto e turismo\" \/>\n<meta property=\"og:description\" content=\"La mattinata dell&#039;11 ottobre, inizier\u00e0 con un percorso turistico, accompagnato da esperti del territorio, che, dalle 10.30 inizier\u00e0 dalla ex-Cartiera\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2019\/10\/04\/isola-del-liri-una-giornata-tra-arte-gusto-e-turismo\/\" \/>\n<meta property=\"og:site_name\" content=\"IlCorriereDellaProvincia.it - News h24 e notizie di approfondimento\" \/>\n<meta property=\"article:author\" content=\"www.facebook.com\/tunews24\" \/>\n<meta property=\"article:published_time\" content=\"2019-10-04T13:16:58+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2019-10-04T13:20:15+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2019\/10\/gusto-isola-del-liri.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"790\" \/>\n\t<meta property=\"og:image:height\" content=\"462\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Redazione\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"Redazione\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minuti\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2019\\\/10\\\/04\\\/isola-del-liri-una-giornata-tra-arte-gusto-e-turismo\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2019\\\/10\\\/04\\\/isola-del-liri-una-giornata-tra-arte-gusto-e-turismo\\\/\"},\"author\":{\"name\":\"Redazione\",\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/#\\\/schema\\\/person\\\/6d7f0a9120d0c03d0c552e9fdf49ed7d\"},\"headline\":\"Isola del Liri: una giornata tra arte, gusto e turismo\",\"datePublished\":\"2019-10-04T13:16:58+00:00\",\"dateModified\":\"2019-10-04T13:20:15+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2019\\\/10\\\/04\\\/isola-del-liri-una-giornata-tra-arte-gusto-e-turismo\\\/\"},\"wordCount\":463,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2019\\\/10\\\/04\\\/isola-del-liri-una-giornata-tra-arte-gusto-e-turismo\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2019\\\/10\\\/gusto-isola-del-liri.jpg\",\"keywords\":[\"isola del gusto\",\"isola del liri\",\"massimiliano quadrini\",\"mauro buschini\",\"Sindaco\"],\"articleSection\":[\"*PRIMO PIANO*\",\"News\"],\"inLanguage\":\"it-IT\",\"copyrightYear\":\"2019\",\"copyrightHolder\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/#organization\"}},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2019\\\/10\\\/04\\\/isola-del-liri-una-giornata-tra-arte-gusto-e-turismo\\\/\",\"url\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2019\\\/10\\\/04\\\/isola-del-liri-una-giornata-tra-arte-gusto-e-turismo\\\/\",\"name\":\"Isola del Liri: una giornata tra arte, gusto e turismo - IlCorriereDellaProvincia.it - News h24 e notizie di approfondimento\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2019\\\/10\\\/04\\\/isola-del-liri-una-giornata-tra-arte-gusto-e-turismo\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2019\\\/10\\\/04\\\/isola-del-liri-una-giornata-tra-arte-gusto-e-turismo\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2019\\\/10\\\/gusto-isola-del-liri.jpg\",\"datePublished\":\"2019-10-04T13:16:58+00:00\",\"dateModified\":\"2019-10-04T13:20:15+00:00\",\"description\":\"La mattinata dell'11 ottobre, inizier\u00e0 con un percorso turistico, accompagnato da esperti del territorio, che, dalle 10.30 inizier\u00e0 dalla ex-Cartiera\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2019\\\/10\\\/04\\\/isola-del-liri-una-giornata-tra-arte-gusto-e-turismo\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2019\\\/10\\\/04\\\/isola-del-liri-una-giornata-tra-arte-gusto-e-turismo\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2019\\\/10\\\/04\\\/isola-del-liri-una-giornata-tra-arte-gusto-e-turismo\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2019\\\/10\\\/gusto-isola-del-liri.jpg\",\"contentUrl\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2019\\\/10\\\/gusto-isola-del-liri.jpg\",\"width\":790,\"height\":462,\"caption\":\"gusto-isola-del-liri\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2019\\\/10\\\/04\\\/isola-del-liri-una-giornata-tra-arte-gusto-e-turismo\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Isola del Liri: una giornata tra arte, gusto e turismo\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/#website\",\"url\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/\",\"name\":\"Il Corriere Delle Provincia\",\"description\":\"IlCorriereDellaProvincia.it, quotidiano web di politica, cronaca, inchiesta, lavoro, scuola, turismo, cultura e spettacolo, economia e finanza, salute e benessere. Approfondimenti e notizie aggiornate con foto e video della provincia di Frosinone ma anche news nazionali, dell\u2019Italia e del Mondo.\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":[\"Organization\",\"Place\"],\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/#organization\",\"name\":\"Globalpress s.r.l.\",\"url\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/\",\"logo\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2019\\\/10\\\/04\\\/isola-del-liri-una-giornata-tra-arte-gusto-e-turismo\\\/#local-main-organization-logo\"},\"image\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2019\\\/10\\\/04\\\/isola-del-liri-una-giornata-tra-arte-gusto-e-turismo\\\/#local-main-organization-logo\"},\"telephone\":[],\"openingHoursSpecification\":[{\"@type\":\"OpeningHoursSpecification\",\"dayOfWeek\":[\"Monday\",\"Tuesday\",\"Wednesday\",\"Thursday\",\"Friday\",\"Saturday\",\"Sunday\"],\"opens\":\"09:00\",\"closes\":\"17:00\"}]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/#\\\/schema\\\/person\\\/6d7f0a9120d0c03d0c552e9fdf49ed7d\",\"name\":\"Redazione\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/a40eeacccdcad861f831dde73317f63a542e738f0dc4b79b9f47062d3d4bd1d2?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/a40eeacccdcad861f831dde73317f63a542e738f0dc4b79b9f47062d3d4bd1d2?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/a40eeacccdcad861f831dde73317f63a542e738f0dc4b79b9f47062d3d4bd1d2?s=96&d=mm&r=g\",\"caption\":\"Redazione\"},\"description\":\"SEGUICI ANCHE SUI SOCIAL Facebook: TuNews24 e TuSport24 Instagram: TuNews24 e TuSport24 Youtube: TuNews24 Telegram: TuNews24 Puoi leggerci anche in formato cartaceo: il settimanale viene pubblicato e distribuito gratuitamente ogni venerd\u00ec in edicole, bar, centri commerciali e svariati esercizi. Ma \u00e8 possibile anche sfogliarlo comodamente online, cliccando su TU NEWS sfogliabile TU NEWS, PASSIONE PER L\u2019INFORMAZIONE\",\"sameAs\":[\"http:\\\/\\\/www.tunews24.it\",\"www.facebook.com\\\/tunews24\"],\"url\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/author\\\/senzafirma\\\/\"},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2019\\\/10\\\/04\\\/isola-del-liri-una-giornata-tra-arte-gusto-e-turismo\\\/#local-main-organization-logo\",\"url\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2022\\\/11\\\/cropped-il-corriere-della-provincia-testata-web-scontornata.png\",\"contentUrl\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2022\\\/11\\\/cropped-il-corriere-della-provincia-testata-web-scontornata.png\",\"width\":2911,\"height\":717,\"caption\":\"Globalpress s.r.l.\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Isola del Liri: una giornata tra arte, gusto e turismo - IlCorriereDellaProvincia.it - News h24 e notizie di approfondimento","description":"La mattinata dell'11 ottobre, inizier\u00e0 con un percorso turistico, accompagnato da esperti del territorio, che, dalle 10.30 inizier\u00e0 dalla ex-Cartiera","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2019\/10\/04\/isola-del-liri-una-giornata-tra-arte-gusto-e-turismo\/","og_locale":"it_IT","og_type":"article","og_title":"Isola del Liri: una giornata tra arte, gusto e turismo","og_description":"La mattinata dell'11 ottobre, inizier\u00e0 con un percorso turistico, accompagnato da esperti del territorio, che, dalle 10.30 inizier\u00e0 dalla ex-Cartiera","og_url":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2019\/10\/04\/isola-del-liri-una-giornata-tra-arte-gusto-e-turismo\/","og_site_name":"IlCorriereDellaProvincia.it - News h24 e notizie di approfondimento","article_author":"www.facebook.com\/tunews24","article_published_time":"2019-10-04T13:16:58+00:00","article_modified_time":"2019-10-04T13:20:15+00:00","og_image":[{"width":790,"height":462,"url":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2019\/10\/gusto-isola-del-liri.jpg","type":"image\/jpeg"}],"author":"Redazione","twitter_card":"summary_large_image","twitter_misc":{"Scritto da":"Redazione","Tempo di lettura stimato":"2 minuti"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2019\/10\/04\/isola-del-liri-una-giornata-tra-arte-gusto-e-turismo\/#article","isPartOf":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2019\/10\/04\/isola-del-liri-una-giornata-tra-arte-gusto-e-turismo\/"},"author":{"name":"Redazione","@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/#\/schema\/person\/6d7f0a9120d0c03d0c552e9fdf49ed7d"},"headline":"Isola del Liri: una giornata tra arte, gusto e turismo","datePublished":"2019-10-04T13:16:58+00:00","dateModified":"2019-10-04T13:20:15+00:00","mainEntityOfPage":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2019\/10\/04\/isola-del-liri-una-giornata-tra-arte-gusto-e-turismo\/"},"wordCount":463,"commentCount":0,"publisher":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/#organization"},"image":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2019\/10\/04\/isola-del-liri-una-giornata-tra-arte-gusto-e-turismo\/#primaryimage"},"thumbnailUrl":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2019\/10\/gusto-isola-del-liri.jpg","keywords":["isola del gusto","isola del liri","massimiliano quadrini","mauro buschini","Sindaco"],"articleSection":["*PRIMO PIANO*","News"],"inLanguage":"it-IT","copyrightYear":"2019","copyrightHolder":{"@id":"https:\/\/www.tunews24.it\/#organization"}},{"@type":"WebPage","@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2019\/10\/04\/isola-del-liri-una-giornata-tra-arte-gusto-e-turismo\/","url":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2019\/10\/04\/isola-del-liri-una-giornata-tra-arte-gusto-e-turismo\/","name":"Isola del Liri: una giornata tra arte, gusto e turismo - IlCorriereDellaProvincia.it - News h24 e notizie di approfondimento","isPartOf":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2019\/10\/04\/isola-del-liri-una-giornata-tra-arte-gusto-e-turismo\/#primaryimage"},"image":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2019\/10\/04\/isola-del-liri-una-giornata-tra-arte-gusto-e-turismo\/#primaryimage"},"thumbnailUrl":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2019\/10\/gusto-isola-del-liri.jpg","datePublished":"2019-10-04T13:16:58+00:00","dateModified":"2019-10-04T13:20:15+00:00","description":"La mattinata dell'11 ottobre, inizier\u00e0 con un percorso turistico, accompagnato da esperti del territorio, che, dalle 10.30 inizier\u00e0 dalla ex-Cartiera","breadcrumb":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2019\/10\/04\/isola-del-liri-una-giornata-tra-arte-gusto-e-turismo\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2019\/10\/04\/isola-del-liri-una-giornata-tra-arte-gusto-e-turismo\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2019\/10\/04\/isola-del-liri-una-giornata-tra-arte-gusto-e-turismo\/#primaryimage","url":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2019\/10\/gusto-isola-del-liri.jpg","contentUrl":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2019\/10\/gusto-isola-del-liri.jpg","width":790,"height":462,"caption":"gusto-isola-del-liri"},{"@type":"BreadcrumbList","@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2019\/10\/04\/isola-del-liri-una-giornata-tra-arte-gusto-e-turismo\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/"},{"@type":"ListItem","position":2,"name":"Isola del Liri: una giornata tra arte, gusto e turismo"}]},{"@type":"WebSite","@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/#website","url":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/","name":"Il Corriere Delle Provincia","description":"IlCorriereDellaProvincia.it, quotidiano web di politica, cronaca, inchiesta, lavoro, scuola, turismo, cultura e spettacolo, economia e finanza, salute e benessere. Approfondimenti e notizie aggiornate con foto e video della provincia di Frosinone ma anche news nazionali, dell\u2019Italia e del Mondo.","publisher":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":["Organization","Place"],"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/#organization","name":"Globalpress s.r.l.","url":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/","logo":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2019\/10\/04\/isola-del-liri-una-giornata-tra-arte-gusto-e-turismo\/#local-main-organization-logo"},"image":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2019\/10\/04\/isola-del-liri-una-giornata-tra-arte-gusto-e-turismo\/#local-main-organization-logo"},"telephone":[],"openingHoursSpecification":[{"@type":"OpeningHoursSpecification","dayOfWeek":["Monday","Tuesday","Wednesday","Thursday","Friday","Saturday","Sunday"],"opens":"09:00","closes":"17:00"}]},{"@type":"Person","@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/#\/schema\/person\/6d7f0a9120d0c03d0c552e9fdf49ed7d","name":"Redazione","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/secure.gravatar.com\/avatar\/a40eeacccdcad861f831dde73317f63a542e738f0dc4b79b9f47062d3d4bd1d2?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/a40eeacccdcad861f831dde73317f63a542e738f0dc4b79b9f47062d3d4bd1d2?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/a40eeacccdcad861f831dde73317f63a542e738f0dc4b79b9f47062d3d4bd1d2?s=96&d=mm&r=g","caption":"Redazione"},"description":"SEGUICI ANCHE SUI SOCIAL Facebook: TuNews24 e TuSport24 Instagram: TuNews24 e TuSport24 Youtube: TuNews24 Telegram: TuNews24 Puoi leggerci anche in formato cartaceo: il settimanale viene pubblicato e distribuito gratuitamente ogni venerd\u00ec in edicole, bar, centri commerciali e svariati esercizi. Ma \u00e8 possibile anche sfogliarlo comodamente online, cliccando su TU NEWS sfogliabile TU NEWS, PASSIONE PER L\u2019INFORMAZIONE","sameAs":["http:\/\/www.tunews24.it","www.facebook.com\/tunews24"],"url":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/author\/senzafirma\/"},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2019\/10\/04\/isola-del-liri-una-giornata-tra-arte-gusto-e-turismo\/#local-main-organization-logo","url":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2022\/11\/cropped-il-corriere-della-provincia-testata-web-scontornata.png","contentUrl":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2022\/11\/cropped-il-corriere-della-provincia-testata-web-scontornata.png","width":2911,"height":717,"caption":"Globalpress s.r.l."}]}},"_links":{"self":[{"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/posts\/19166","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/users\/18"}],"replies":[{"embeddable":true,"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/comments?post=19166"}],"version-history":[{"count":2,"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/posts\/19166\/revisions"}],"predecessor-version":[{"id":19169,"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/posts\/19166\/revisions\/19169"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/media\/19170"}],"wp:attachment":[{"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/media?parent=19166"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/categories?post=19166"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/tags?post=19166"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}