{"id":17824,"date":"2019-09-10T17:52:58","date_gmt":"2019-09-10T15:52:58","guid":{"rendered":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/?p=17824"},"modified":"2019-09-11T13:16:42","modified_gmt":"2019-09-11T11:16:42","slug":"area-industriale-di-anagni-partono-i-lavori-de-angelis-manteniamo-gli-impegni","status":"publish","type":"post","link":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2019\/09\/10\/area-industriale-di-anagni-partono-i-lavori-de-angelis-manteniamo-gli-impegni\/","title":{"rendered":"Area industriale di Anagni, partono i lavori. De Angelis: manteniamo gli impegni"},"content":{"rendered":"<p><strong>L&#8217;area industriale di Anagni,<\/strong> finalmente, pronta a cambiare volto. Mercoled\u00ec, ad Anagni, alla presenza del Presidente dell\u2019ASI<strong> Francesco De Angelis e del Sindaco di Anagni Daniele Natalia<\/strong> \u00e8 avvenuta la consegna dei lavori che porteranno al rifacimento del manto stradale, e non solo, dell&#8217;asse viario di collegamento tra la strada provinciale Morolense con la strada comunale localit\u00e0 Paduni-Selciatella, per complessivi 899.988,46 euro.<\/p>\n<h2>L&#8217;obiettivo<\/h2>\n<p>La strada oggetto di intervento rappresenta il principale asse di collegamento autostradale utilizzato da tutte le aziende che insistono nell&#8217;area industriale dell\u2019Agglomerato di Anagni (Comuni di Anagni e Sgurgola) oltre a quelle insediate nell&#8217;Agglomerato di Frosinone (Comuni di Morolo e Ferentino nord). Si tratta di un intervento di straordinaria importanza che verr\u00e0 realizzato dal Consorzio per lo Sviluppo Industriale Frosinone per la sistemazione della viabilit\u00e0 nell\u2019Agglomerato industriale di Anagni.<\/p>\n<p>Nello specifico, i lavori riguarderanno: il rifacimento del manto stradale, della segnaletica verticale e orizzontale, la sistemazione della regimentazione delle acque e il consolidamento della struttura stradale in alcuni punti.<\/p>\n<p>Tutto questo \u00e8 stato fatto in meno di dodici mesi, a partire dalla richiesta di finanziamento e dalla progettazione dell\u2019intervento, fino all\u2019ottenimento del finanziamento, all\u2019espletamento della gara e l\u2019inizio dei lavori.<\/p>\n<h2>L&#8217;intervento del presidente<\/h2>\n<p>&#8220;Ringrazio \u2013<strong> ha dichiarato il presidente De Angelis<\/strong> \u2013 il Presidente della Regione Lazio Nicola Zingaretti, l\u2019Assessore Regionale Gian Paolo Manzella, il Presidente del Consiglio Regionale Mauro Buschini, la Giunta ed i Consiglieri Regionali Sara Battisti, Pasquale Ciacciarelli e Loreto Marcelli per il contributo dato alla realizzazione di questa importantissima opera. Ringrazio, inoltre, il Sindaco di Anagni Daniele Natalia, le Associazioni di categoria, i sindacati e la Camera di Commercio per la fattiva collaborazione&#8221;<\/p>\n<p>&#8220;Questo intervento \u2013 conclude De Angelis\u00a0 &#8211; \u00e8 la conferma di come la legge 46 sia uno strumento utile a sostegno delle imprese&#8221;. E ancora &#8220;La realizzazione di questa infrastruttura servir\u00e0 a restituire forza e competitivit\u00e0 alle aziende del nostro territorio al fine di favorire lo sviluppo economico e l\u2019occupazione&#8221;.<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>L&#8217;area industriale di Anagni, finalmente, pronta a cambiare volto. Mercoled\u00ec, ad Anagni, alla presenza del Presidente dell\u2019ASI Francesco De Angelis<\/p>\n","protected":false},"author":18,"featured_media":8263,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[41],"tags":[441,289,3124,969,93,227],"class_list":["post-17824","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-slide","tag-anagni","tag-asi","tag-daniele-natalia","tag-francesco-de-angelis","tag-frosinone","tag-lavori"],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v27.8 (Yoast SEO v27.8) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Area industriale di Anagni, partono i lavori. De Angelis: manteniamo gli impegni - IlCorriereDellaProvincia.it - News h24 e notizie di approfondimento<\/title>\n<meta name=\"description\" content=\"Mercoled\u00ec, ad Anagni, alla presenza del Presidente dell\u2019ASI Francesco De Angelis e del Sindaco di Anagni Daniele Natalia \u00e8 avvenuta la consegna\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2019\/09\/10\/area-industriale-di-anagni-partono-i-lavori-de-angelis-manteniamo-gli-impegni\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Area industriale di Anagni, partono i lavori. De Angelis: manteniamo gli impegni\" \/>\n<meta property=\"og:description\" content=\"Mercoled\u00ec, ad Anagni, alla presenza del Presidente dell\u2019ASI Francesco De Angelis e del Sindaco di Anagni Daniele Natalia \u00e8 avvenuta la consegna\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2019\/09\/10\/area-industriale-di-anagni-partono-i-lavori-de-angelis-manteniamo-gli-impegni\/\" \/>\n<meta property=\"og:site_name\" content=\"IlCorriereDellaProvincia.it - News h24 e notizie di approfondimento\" \/>\n<meta property=\"article:author\" content=\"www.facebook.com\/tunews24\" \/>\n<meta property=\"article:published_time\" content=\"2019-09-10T15:52:58+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2019-09-11T11:16:42+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2019\/03\/francesco-de-angelis-e1553000829638.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"632\" \/>\n\t<meta property=\"og:image:height\" content=\"379\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Redazione\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"Redazione\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minuti\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2019\\\/09\\\/10\\\/area-industriale-di-anagni-partono-i-lavori-de-angelis-manteniamo-gli-impegni\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2019\\\/09\\\/10\\\/area-industriale-di-anagni-partono-i-lavori-de-angelis-manteniamo-gli-impegni\\\/\"},\"author\":{\"name\":\"Redazione\",\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/#\\\/schema\\\/person\\\/6d7f0a9120d0c03d0c552e9fdf49ed7d\"},\"headline\":\"Area industriale di Anagni, partono i lavori. De Angelis: manteniamo gli impegni\",\"datePublished\":\"2019-09-10T15:52:58+00:00\",\"dateModified\":\"2019-09-11T11:16:42+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2019\\\/09\\\/10\\\/area-industriale-di-anagni-partono-i-lavori-de-angelis-manteniamo-gli-impegni\\\/\"},\"wordCount\":341,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2019\\\/09\\\/10\\\/area-industriale-di-anagni-partono-i-lavori-de-angelis-manteniamo-gli-impegni\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2019\\\/03\\\/francesco-de-angelis-e1553000829638.jpg\",\"keywords\":[\"anagni\",\"asi\",\"Daniele Natalia\",\"francesco de angelis\",\"Frosinone\",\"lavori\"],\"articleSection\":[\"*SLIDE*\"],\"inLanguage\":\"it-IT\",\"copyrightYear\":\"2019\",\"copyrightHolder\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/#organization\"}},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2019\\\/09\\\/10\\\/area-industriale-di-anagni-partono-i-lavori-de-angelis-manteniamo-gli-impegni\\\/\",\"url\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2019\\\/09\\\/10\\\/area-industriale-di-anagni-partono-i-lavori-de-angelis-manteniamo-gli-impegni\\\/\",\"name\":\"Area industriale di Anagni, partono i lavori. De Angelis: manteniamo gli impegni - IlCorriereDellaProvincia.it - News h24 e notizie di approfondimento\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2019\\\/09\\\/10\\\/area-industriale-di-anagni-partono-i-lavori-de-angelis-manteniamo-gli-impegni\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2019\\\/09\\\/10\\\/area-industriale-di-anagni-partono-i-lavori-de-angelis-manteniamo-gli-impegni\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2019\\\/03\\\/francesco-de-angelis-e1553000829638.jpg\",\"datePublished\":\"2019-09-10T15:52:58+00:00\",\"dateModified\":\"2019-09-11T11:16:42+00:00\",\"description\":\"Mercoled\u00ec, ad Anagni, alla presenza del Presidente dell\u2019ASI Francesco De Angelis e del Sindaco di Anagni Daniele Natalia \u00e8 avvenuta la consegna\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2019\\\/09\\\/10\\\/area-industriale-di-anagni-partono-i-lavori-de-angelis-manteniamo-gli-impegni\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2019\\\/09\\\/10\\\/area-industriale-di-anagni-partono-i-lavori-de-angelis-manteniamo-gli-impegni\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2019\\\/09\\\/10\\\/area-industriale-di-anagni-partono-i-lavori-de-angelis-manteniamo-gli-impegni\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2019\\\/03\\\/francesco-de-angelis-e1553000829638.jpg\",\"contentUrl\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2019\\\/03\\\/francesco-de-angelis-e1553000829638.jpg\",\"width\":632,\"height\":379,\"caption\":\"Francesco De Angelis\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2019\\\/09\\\/10\\\/area-industriale-di-anagni-partono-i-lavori-de-angelis-manteniamo-gli-impegni\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Area industriale di Anagni, partono i lavori. De Angelis: manteniamo gli impegni\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/#website\",\"url\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/\",\"name\":\"Il Corriere Delle Provincia\",\"description\":\"IlCorriereDellaProvincia.it, quotidiano web di politica, cronaca, inchiesta, lavoro, scuola, turismo, cultura e spettacolo, economia e finanza, salute e benessere. Approfondimenti e notizie aggiornate con foto e video della provincia di Frosinone ma anche news nazionali, dell\u2019Italia e del Mondo.\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":[\"Organization\",\"Place\"],\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/#organization\",\"name\":\"Globalpress s.r.l.\",\"url\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/\",\"logo\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2019\\\/09\\\/10\\\/area-industriale-di-anagni-partono-i-lavori-de-angelis-manteniamo-gli-impegni\\\/#local-main-organization-logo\"},\"image\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2019\\\/09\\\/10\\\/area-industriale-di-anagni-partono-i-lavori-de-angelis-manteniamo-gli-impegni\\\/#local-main-organization-logo\"},\"telephone\":[],\"openingHoursSpecification\":[{\"@type\":\"OpeningHoursSpecification\",\"dayOfWeek\":[\"Monday\",\"Tuesday\",\"Wednesday\",\"Thursday\",\"Friday\",\"Saturday\",\"Sunday\"],\"opens\":\"09:00\",\"closes\":\"17:00\"}]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/#\\\/schema\\\/person\\\/6d7f0a9120d0c03d0c552e9fdf49ed7d\",\"name\":\"Redazione\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/a40eeacccdcad861f831dde73317f63a542e738f0dc4b79b9f47062d3d4bd1d2?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/a40eeacccdcad861f831dde73317f63a542e738f0dc4b79b9f47062d3d4bd1d2?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/a40eeacccdcad861f831dde73317f63a542e738f0dc4b79b9f47062d3d4bd1d2?s=96&d=mm&r=g\",\"caption\":\"Redazione\"},\"description\":\"SEGUICI ANCHE SUI SOCIAL Facebook: TuNews24 e TuSport24 Instagram: TuNews24 e TuSport24 Youtube: TuNews24 Telegram: TuNews24 Puoi leggerci anche in formato cartaceo: il settimanale viene pubblicato e distribuito gratuitamente ogni venerd\u00ec in edicole, bar, centri commerciali e svariati esercizi. Ma \u00e8 possibile anche sfogliarlo comodamente online, cliccando su TU NEWS sfogliabile TU NEWS, PASSIONE PER L\u2019INFORMAZIONE\",\"sameAs\":[\"http:\\\/\\\/www.tunews24.it\",\"www.facebook.com\\\/tunews24\"],\"url\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/author\\\/senzafirma\\\/\"},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2019\\\/09\\\/10\\\/area-industriale-di-anagni-partono-i-lavori-de-angelis-manteniamo-gli-impegni\\\/#local-main-organization-logo\",\"url\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2022\\\/11\\\/cropped-il-corriere-della-provincia-testata-web-scontornata.png\",\"contentUrl\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2022\\\/11\\\/cropped-il-corriere-della-provincia-testata-web-scontornata.png\",\"width\":2911,\"height\":717,\"caption\":\"Globalpress s.r.l.\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Area industriale di Anagni, partono i lavori. De Angelis: manteniamo gli impegni - IlCorriereDellaProvincia.it - News h24 e notizie di approfondimento","description":"Mercoled\u00ec, ad Anagni, alla presenza del Presidente dell\u2019ASI Francesco De Angelis e del Sindaco di Anagni Daniele Natalia \u00e8 avvenuta la consegna","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2019\/09\/10\/area-industriale-di-anagni-partono-i-lavori-de-angelis-manteniamo-gli-impegni\/","og_locale":"it_IT","og_type":"article","og_title":"Area industriale di Anagni, partono i lavori. De Angelis: manteniamo gli impegni","og_description":"Mercoled\u00ec, ad Anagni, alla presenza del Presidente dell\u2019ASI Francesco De Angelis e del Sindaco di Anagni Daniele Natalia \u00e8 avvenuta la consegna","og_url":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2019\/09\/10\/area-industriale-di-anagni-partono-i-lavori-de-angelis-manteniamo-gli-impegni\/","og_site_name":"IlCorriereDellaProvincia.it - News h24 e notizie di approfondimento","article_author":"www.facebook.com\/tunews24","article_published_time":"2019-09-10T15:52:58+00:00","article_modified_time":"2019-09-11T11:16:42+00:00","og_image":[{"width":632,"height":379,"url":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2019\/03\/francesco-de-angelis-e1553000829638.jpg","type":"image\/jpeg"}],"author":"Redazione","twitter_card":"summary_large_image","twitter_misc":{"Scritto da":"Redazione","Tempo di lettura stimato":"2 minuti"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2019\/09\/10\/area-industriale-di-anagni-partono-i-lavori-de-angelis-manteniamo-gli-impegni\/#article","isPartOf":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2019\/09\/10\/area-industriale-di-anagni-partono-i-lavori-de-angelis-manteniamo-gli-impegni\/"},"author":{"name":"Redazione","@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/#\/schema\/person\/6d7f0a9120d0c03d0c552e9fdf49ed7d"},"headline":"Area industriale di Anagni, partono i lavori. De Angelis: manteniamo gli impegni","datePublished":"2019-09-10T15:52:58+00:00","dateModified":"2019-09-11T11:16:42+00:00","mainEntityOfPage":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2019\/09\/10\/area-industriale-di-anagni-partono-i-lavori-de-angelis-manteniamo-gli-impegni\/"},"wordCount":341,"commentCount":0,"publisher":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/#organization"},"image":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2019\/09\/10\/area-industriale-di-anagni-partono-i-lavori-de-angelis-manteniamo-gli-impegni\/#primaryimage"},"thumbnailUrl":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2019\/03\/francesco-de-angelis-e1553000829638.jpg","keywords":["anagni","asi","Daniele Natalia","francesco de angelis","Frosinone","lavori"],"articleSection":["*SLIDE*"],"inLanguage":"it-IT","copyrightYear":"2019","copyrightHolder":{"@id":"https:\/\/www.tunews24.it\/#organization"}},{"@type":"WebPage","@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2019\/09\/10\/area-industriale-di-anagni-partono-i-lavori-de-angelis-manteniamo-gli-impegni\/","url":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2019\/09\/10\/area-industriale-di-anagni-partono-i-lavori-de-angelis-manteniamo-gli-impegni\/","name":"Area industriale di Anagni, partono i lavori. De Angelis: manteniamo gli impegni - IlCorriereDellaProvincia.it - News h24 e notizie di approfondimento","isPartOf":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2019\/09\/10\/area-industriale-di-anagni-partono-i-lavori-de-angelis-manteniamo-gli-impegni\/#primaryimage"},"image":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2019\/09\/10\/area-industriale-di-anagni-partono-i-lavori-de-angelis-manteniamo-gli-impegni\/#primaryimage"},"thumbnailUrl":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2019\/03\/francesco-de-angelis-e1553000829638.jpg","datePublished":"2019-09-10T15:52:58+00:00","dateModified":"2019-09-11T11:16:42+00:00","description":"Mercoled\u00ec, ad Anagni, alla presenza del Presidente dell\u2019ASI Francesco De Angelis e del Sindaco di Anagni Daniele Natalia \u00e8 avvenuta la consegna","breadcrumb":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2019\/09\/10\/area-industriale-di-anagni-partono-i-lavori-de-angelis-manteniamo-gli-impegni\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2019\/09\/10\/area-industriale-di-anagni-partono-i-lavori-de-angelis-manteniamo-gli-impegni\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2019\/09\/10\/area-industriale-di-anagni-partono-i-lavori-de-angelis-manteniamo-gli-impegni\/#primaryimage","url":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2019\/03\/francesco-de-angelis-e1553000829638.jpg","contentUrl":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2019\/03\/francesco-de-angelis-e1553000829638.jpg","width":632,"height":379,"caption":"Francesco De Angelis"},{"@type":"BreadcrumbList","@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2019\/09\/10\/area-industriale-di-anagni-partono-i-lavori-de-angelis-manteniamo-gli-impegni\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/"},{"@type":"ListItem","position":2,"name":"Area industriale di Anagni, partono i lavori. De Angelis: manteniamo gli impegni"}]},{"@type":"WebSite","@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/#website","url":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/","name":"Il Corriere Delle Provincia","description":"IlCorriereDellaProvincia.it, quotidiano web di politica, cronaca, inchiesta, lavoro, scuola, turismo, cultura e spettacolo, economia e finanza, salute e benessere. Approfondimenti e notizie aggiornate con foto e video della provincia di Frosinone ma anche news nazionali, dell\u2019Italia e del Mondo.","publisher":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":["Organization","Place"],"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/#organization","name":"Globalpress s.r.l.","url":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/","logo":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2019\/09\/10\/area-industriale-di-anagni-partono-i-lavori-de-angelis-manteniamo-gli-impegni\/#local-main-organization-logo"},"image":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2019\/09\/10\/area-industriale-di-anagni-partono-i-lavori-de-angelis-manteniamo-gli-impegni\/#local-main-organization-logo"},"telephone":[],"openingHoursSpecification":[{"@type":"OpeningHoursSpecification","dayOfWeek":["Monday","Tuesday","Wednesday","Thursday","Friday","Saturday","Sunday"],"opens":"09:00","closes":"17:00"}]},{"@type":"Person","@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/#\/schema\/person\/6d7f0a9120d0c03d0c552e9fdf49ed7d","name":"Redazione","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/secure.gravatar.com\/avatar\/a40eeacccdcad861f831dde73317f63a542e738f0dc4b79b9f47062d3d4bd1d2?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/a40eeacccdcad861f831dde73317f63a542e738f0dc4b79b9f47062d3d4bd1d2?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/a40eeacccdcad861f831dde73317f63a542e738f0dc4b79b9f47062d3d4bd1d2?s=96&d=mm&r=g","caption":"Redazione"},"description":"SEGUICI ANCHE SUI SOCIAL Facebook: TuNews24 e TuSport24 Instagram: TuNews24 e TuSport24 Youtube: TuNews24 Telegram: TuNews24 Puoi leggerci anche in formato cartaceo: il settimanale viene pubblicato e distribuito gratuitamente ogni venerd\u00ec in edicole, bar, centri commerciali e svariati esercizi. Ma \u00e8 possibile anche sfogliarlo comodamente online, cliccando su TU NEWS sfogliabile TU NEWS, PASSIONE PER L\u2019INFORMAZIONE","sameAs":["http:\/\/www.tunews24.it","www.facebook.com\/tunews24"],"url":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/author\/senzafirma\/"},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2019\/09\/10\/area-industriale-di-anagni-partono-i-lavori-de-angelis-manteniamo-gli-impegni\/#local-main-organization-logo","url":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2022\/11\/cropped-il-corriere-della-provincia-testata-web-scontornata.png","contentUrl":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2022\/11\/cropped-il-corriere-della-provincia-testata-web-scontornata.png","width":2911,"height":717,"caption":"Globalpress s.r.l."}]}},"_links":{"self":[{"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/posts\/17824","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/users\/18"}],"replies":[{"embeddable":true,"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/comments?post=17824"}],"version-history":[{"count":1,"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/posts\/17824\/revisions"}],"predecessor-version":[{"id":17825,"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/posts\/17824\/revisions\/17825"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/media\/8263"}],"wp:attachment":[{"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/media?parent=17824"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/categories?post=17824"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/tags?post=17824"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}