{"id":17664,"date":"2019-09-07T16:30:20","date_gmt":"2019-09-07T14:30:20","guid":{"rendered":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/?p=17664"},"modified":"2019-09-09T14:38:29","modified_gmt":"2019-09-09T12:38:29","slug":"fondi-per-dissesto-idrogeologico-magliocchetti-spinge-per-la-ciociaria","status":"publish","type":"post","link":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2019\/09\/07\/fondi-per-dissesto-idrogeologico-magliocchetti-spinge-per-la-ciociaria\/","title":{"rendered":"Fondi per dissesto idrogeologico, Magliocchetti &#8216;spinge&#8217; per la Ciociaria"},"content":{"rendered":"<p>La firma del ministro dell&#8217;Ambiente, Sergio Costa, sul decreto attuativo che trasferisce alle Regioni i <strong>fondi del Piano Stralcio da 315 milioni di euro<\/strong> destinati ai <strong>progetti esecutivi di tutela del territorio<\/strong> dal dissesto idrogeologico, ha sollecitato il <strong>consigliere comunale di Frosinone<\/strong>, <strong>Danilo Magliocchetti<\/strong>, a intervenire.<\/p>\n<p>In particolare, quale delegato del Consiglio nazionale dell&#8217;Anci, Magliocchetti ha scritto all&#8217;assessore regionale ai Lavori Pubblici, Tutela del Territorio e Ambiente, <strong>Mauro Alessandri<\/strong>, affinch\u00e9 <strong>si provveda celermente a trasferire i fondi<\/strong> ai Comuni della provincia di Frosinone.<\/p>\n<h2>I Comuni destinatari<\/h2>\n<p>In particolare, si tratta di: Acuto, Alatri, Anagni, Castrocielo, Frosinone, Sant\u2019Ambrogio sul Garigliano, Vallerotonda e Veroli, che rientrano nei <strong>35 interventi del Lazio<\/strong> per<strong> un totale di 22.735.582 euro<\/strong>.<\/p>\n<p>Si tratta di tutti interventi urgenti ed indifferibili e, sottolinea Magliocchetti, soprattutto se si parla dei lavori straordinari di <strong>manutenzione dell\u2019alveo del fiume Cosa<\/strong>, per un importo dei lavori di <strong>580.000 euro<\/strong>.<\/p>\n<h2>La richiesta nella lettera<\/h2>\n<p>&#8220;Nell\u2019ambito degli 8 interventi previsti per la Provincia di Frosinone \u2013 scrive l&#8217;ex forzista all&#8217;onorevole Alessandri &#8211; quello dell\u2019alveo del fiume Cosa, riveste una importanza strategica, non solo per i Comuni interessati, ma per l\u2019intero bacino, atteso che con l\u2019approssimarsi dell&#8217;imminente periodo autunnale e conseguentemente delle piogge, il rischio idrogeologico aumenta notevolmente e notoriamente&#8221;.<\/p>\n<p>&nbsp;<\/p>\n<figure id=\"attachment_11210\" aria-describedby=\"caption-attachment-11210\" style=\"width: 632px\" class=\"wp-caption aligncenter\"><img loading=\"lazy\" decoding=\"async\" class=\"wp-image-11210 size-full\" src=\"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2019\/05\/danilo-magliocchetti-e1557916293585.jpg\" alt=\"danilo magliocchetti frosinone il corriere della provincia\" width=\"632\" height=\"505\" \/><figcaption id=\"caption-attachment-11210\" class=\"wp-caption-text\">Il consigliere comunale di Frosinone Danilo Magliocchetti<\/figcaption><\/figure>\n<p>&nbsp;<\/p>\n<p>&#8220;Peraltro, su un territorio a particolare pericolo idrogeologico generale, come certificato dal recente Rapporto Ispra, laddove la provincia di Frosinone primeggia, in negativo, sulle altre del Lazio, per 4 indicatori su 6. <strong>Si tratta di aree a pericolosit\u00e0 da frana<\/strong>; popolazione a rischio frana; famiglie a rischio in aree a pericolosit\u00e0 da frana; edifici a rischio in aree a pericolosit\u00e0 da frana&#8221;.<\/p>\n<p>&#8220;Per questi motivi \u2013 conclude Magliocchetti &#8211; visto il provvedimento del Ministero dell\u2019Ambiente, la prego di provvedere subito, senza alcun indugio, al trasferimento, appena disponibili, delle risorse finanziarie previste per gli 8 Comuni della provincia di Frosinone, allo scopo di iniziare subito i lavori necessari, di prevenzione idrogeologica, previsti da ciascuna Amministrazione, con particolare riferimento per i lavori del fiume Cosa&#8221;.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>La firma del ministro dell&#8217;Ambiente, Sergio Costa, sul decreto attuativo che trasferisce alle Regioni i fondi del Piano Stralcio da<\/p>\n","protected":false},"author":18,"featured_media":17666,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[41,2236],"tags":[858,2129,565,464,4615,6055,6054,562,6056,2811],"class_list":["post-17664","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-slide","category-attualita","tag-danilo-magliocchetti","tag-dissesto-idrogeologico","tag-fondi","tag-manutenzione","tag-mauro-alessandri","tag-ministero-dellambiente","tag-piano-stralcio","tag-regione-lazio","tag-rischio-idrogeologico","tag-sergio-costa"],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v27.8 (Yoast SEO v27.8) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Fondi per dissesto idrogeologico, Magliocchetti &#039;spinge&#039; per la Ciociaria - IlCorriereDellaProvincia.it - News h24 e notizie di approfondimento<\/title>\n<meta name=\"description\" content=\"Il consigliere comunale di Frosinone Danilo Magliocchetti scrive all&#039;assessore regionale Alessandri per sollecitare l&#039;invio di fondi per il dissesto\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2019\/09\/07\/fondi-per-dissesto-idrogeologico-magliocchetti-spinge-per-la-ciociaria\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Fondi per dissesto idrogeologico, Magliocchetti &#039;spinge&#039; per la Ciociaria\" \/>\n<meta property=\"og:description\" content=\"Il consigliere comunale di Frosinone Danilo Magliocchetti scrive all&#039;assessore regionale Alessandri per sollecitare l&#039;invio di fondi per il dissesto\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2019\/09\/07\/fondi-per-dissesto-idrogeologico-magliocchetti-spinge-per-la-ciociaria\/\" \/>\n<meta property=\"og:site_name\" content=\"IlCorriereDellaProvincia.it - News h24 e notizie di approfondimento\" \/>\n<meta property=\"article:author\" content=\"www.facebook.com\/tunews24\" \/>\n<meta property=\"article:published_time\" content=\"2019-09-07T14:30:20+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2019-09-09T12:38:29+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2019\/09\/fiume-cosa-e1567866584135.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"632\" \/>\n\t<meta property=\"og:image:height\" content=\"375\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Redazione\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"Redazione\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minuti\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2019\\\/09\\\/07\\\/fondi-per-dissesto-idrogeologico-magliocchetti-spinge-per-la-ciociaria\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2019\\\/09\\\/07\\\/fondi-per-dissesto-idrogeologico-magliocchetti-spinge-per-la-ciociaria\\\/\"},\"author\":{\"name\":\"Redazione\",\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/#\\\/schema\\\/person\\\/6d7f0a9120d0c03d0c552e9fdf49ed7d\"},\"headline\":\"Fondi per dissesto idrogeologico, Magliocchetti &#8216;spinge&#8217; per la Ciociaria\",\"datePublished\":\"2019-09-07T14:30:20+00:00\",\"dateModified\":\"2019-09-09T12:38:29+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2019\\\/09\\\/07\\\/fondi-per-dissesto-idrogeologico-magliocchetti-spinge-per-la-ciociaria\\\/\"},\"wordCount\":356,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2019\\\/09\\\/07\\\/fondi-per-dissesto-idrogeologico-magliocchetti-spinge-per-la-ciociaria\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2019\\\/09\\\/fiume-cosa-e1567866584135.jpg\",\"keywords\":[\"danilo magliocchetti\",\"dissesto idrogeologico\",\"fondi\",\"manutenzione\",\"Mauro Alessandri\",\"ministero dell'ambiente\",\"piano stralcio\",\"regione lazio\",\"rischio idrogeologico\",\"sergio costa\"],\"articleSection\":[\"*SLIDE*\",\"Attualit\u00e0\"],\"inLanguage\":\"it-IT\",\"copyrightYear\":\"2019\",\"copyrightHolder\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/#organization\"}},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2019\\\/09\\\/07\\\/fondi-per-dissesto-idrogeologico-magliocchetti-spinge-per-la-ciociaria\\\/\",\"url\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2019\\\/09\\\/07\\\/fondi-per-dissesto-idrogeologico-magliocchetti-spinge-per-la-ciociaria\\\/\",\"name\":\"Fondi per dissesto idrogeologico, Magliocchetti 'spinge' per la Ciociaria - IlCorriereDellaProvincia.it - News h24 e notizie di approfondimento\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2019\\\/09\\\/07\\\/fondi-per-dissesto-idrogeologico-magliocchetti-spinge-per-la-ciociaria\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2019\\\/09\\\/07\\\/fondi-per-dissesto-idrogeologico-magliocchetti-spinge-per-la-ciociaria\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2019\\\/09\\\/fiume-cosa-e1567866584135.jpg\",\"datePublished\":\"2019-09-07T14:30:20+00:00\",\"dateModified\":\"2019-09-09T12:38:29+00:00\",\"description\":\"Il consigliere comunale di Frosinone Danilo Magliocchetti scrive all'assessore regionale Alessandri per sollecitare l'invio di fondi per il dissesto\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2019\\\/09\\\/07\\\/fondi-per-dissesto-idrogeologico-magliocchetti-spinge-per-la-ciociaria\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2019\\\/09\\\/07\\\/fondi-per-dissesto-idrogeologico-magliocchetti-spinge-per-la-ciociaria\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2019\\\/09\\\/07\\\/fondi-per-dissesto-idrogeologico-magliocchetti-spinge-per-la-ciociaria\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2019\\\/09\\\/fiume-cosa-e1567866584135.jpg\",\"contentUrl\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2019\\\/09\\\/fiume-cosa-e1567866584135.jpg\",\"width\":632,\"height\":375,\"caption\":\"Un tratto del fiume Cosa\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2019\\\/09\\\/07\\\/fondi-per-dissesto-idrogeologico-magliocchetti-spinge-per-la-ciociaria\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Fondi per dissesto idrogeologico, Magliocchetti &#8216;spinge&#8217; per la Ciociaria\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/#website\",\"url\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/\",\"name\":\"Il Corriere Delle Provincia\",\"description\":\"IlCorriereDellaProvincia.it, quotidiano web di politica, cronaca, inchiesta, lavoro, scuola, turismo, cultura e spettacolo, economia e finanza, salute e benessere. Approfondimenti e notizie aggiornate con foto e video della provincia di Frosinone ma anche news nazionali, dell\u2019Italia e del Mondo.\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":[\"Organization\",\"Place\"],\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/#organization\",\"name\":\"Globalpress s.r.l.\",\"url\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/\",\"logo\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2019\\\/09\\\/07\\\/fondi-per-dissesto-idrogeologico-magliocchetti-spinge-per-la-ciociaria\\\/#local-main-organization-logo\"},\"image\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2019\\\/09\\\/07\\\/fondi-per-dissesto-idrogeologico-magliocchetti-spinge-per-la-ciociaria\\\/#local-main-organization-logo\"},\"telephone\":[],\"openingHoursSpecification\":[{\"@type\":\"OpeningHoursSpecification\",\"dayOfWeek\":[\"Monday\",\"Tuesday\",\"Wednesday\",\"Thursday\",\"Friday\",\"Saturday\",\"Sunday\"],\"opens\":\"09:00\",\"closes\":\"17:00\"}]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/#\\\/schema\\\/person\\\/6d7f0a9120d0c03d0c552e9fdf49ed7d\",\"name\":\"Redazione\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/a40eeacccdcad861f831dde73317f63a542e738f0dc4b79b9f47062d3d4bd1d2?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/a40eeacccdcad861f831dde73317f63a542e738f0dc4b79b9f47062d3d4bd1d2?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/a40eeacccdcad861f831dde73317f63a542e738f0dc4b79b9f47062d3d4bd1d2?s=96&d=mm&r=g\",\"caption\":\"Redazione\"},\"description\":\"SEGUICI ANCHE SUI SOCIAL Facebook: TuNews24 e TuSport24 Instagram: TuNews24 e TuSport24 Youtube: TuNews24 Telegram: TuNews24 Puoi leggerci anche in formato cartaceo: il settimanale viene pubblicato e distribuito gratuitamente ogni venerd\u00ec in edicole, bar, centri commerciali e svariati esercizi. Ma \u00e8 possibile anche sfogliarlo comodamente online, cliccando su TU NEWS sfogliabile TU NEWS, PASSIONE PER L\u2019INFORMAZIONE\",\"sameAs\":[\"http:\\\/\\\/www.tunews24.it\",\"www.facebook.com\\\/tunews24\"],\"url\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/author\\\/senzafirma\\\/\"},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2019\\\/09\\\/07\\\/fondi-per-dissesto-idrogeologico-magliocchetti-spinge-per-la-ciociaria\\\/#local-main-organization-logo\",\"url\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2022\\\/11\\\/cropped-il-corriere-della-provincia-testata-web-scontornata.png\",\"contentUrl\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2022\\\/11\\\/cropped-il-corriere-della-provincia-testata-web-scontornata.png\",\"width\":2911,\"height\":717,\"caption\":\"Globalpress s.r.l.\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Fondi per dissesto idrogeologico, Magliocchetti 'spinge' per la Ciociaria - IlCorriereDellaProvincia.it - News h24 e notizie di approfondimento","description":"Il consigliere comunale di Frosinone Danilo Magliocchetti scrive all'assessore regionale Alessandri per sollecitare l'invio di fondi per il dissesto","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2019\/09\/07\/fondi-per-dissesto-idrogeologico-magliocchetti-spinge-per-la-ciociaria\/","og_locale":"it_IT","og_type":"article","og_title":"Fondi per dissesto idrogeologico, Magliocchetti 'spinge' per la Ciociaria","og_description":"Il consigliere comunale di Frosinone Danilo Magliocchetti scrive all'assessore regionale Alessandri per sollecitare l'invio di fondi per il dissesto","og_url":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2019\/09\/07\/fondi-per-dissesto-idrogeologico-magliocchetti-spinge-per-la-ciociaria\/","og_site_name":"IlCorriereDellaProvincia.it - News h24 e notizie di approfondimento","article_author":"www.facebook.com\/tunews24","article_published_time":"2019-09-07T14:30:20+00:00","article_modified_time":"2019-09-09T12:38:29+00:00","og_image":[{"width":632,"height":375,"url":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2019\/09\/fiume-cosa-e1567866584135.jpg","type":"image\/jpeg"}],"author":"Redazione","twitter_card":"summary_large_image","twitter_misc":{"Scritto da":"Redazione","Tempo di lettura stimato":"2 minuti"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2019\/09\/07\/fondi-per-dissesto-idrogeologico-magliocchetti-spinge-per-la-ciociaria\/#article","isPartOf":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2019\/09\/07\/fondi-per-dissesto-idrogeologico-magliocchetti-spinge-per-la-ciociaria\/"},"author":{"name":"Redazione","@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/#\/schema\/person\/6d7f0a9120d0c03d0c552e9fdf49ed7d"},"headline":"Fondi per dissesto idrogeologico, Magliocchetti &#8216;spinge&#8217; per la Ciociaria","datePublished":"2019-09-07T14:30:20+00:00","dateModified":"2019-09-09T12:38:29+00:00","mainEntityOfPage":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2019\/09\/07\/fondi-per-dissesto-idrogeologico-magliocchetti-spinge-per-la-ciociaria\/"},"wordCount":356,"commentCount":0,"publisher":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/#organization"},"image":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2019\/09\/07\/fondi-per-dissesto-idrogeologico-magliocchetti-spinge-per-la-ciociaria\/#primaryimage"},"thumbnailUrl":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2019\/09\/fiume-cosa-e1567866584135.jpg","keywords":["danilo magliocchetti","dissesto idrogeologico","fondi","manutenzione","Mauro Alessandri","ministero dell'ambiente","piano stralcio","regione lazio","rischio idrogeologico","sergio costa"],"articleSection":["*SLIDE*","Attualit\u00e0"],"inLanguage":"it-IT","copyrightYear":"2019","copyrightHolder":{"@id":"https:\/\/www.tunews24.it\/#organization"}},{"@type":"WebPage","@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2019\/09\/07\/fondi-per-dissesto-idrogeologico-magliocchetti-spinge-per-la-ciociaria\/","url":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2019\/09\/07\/fondi-per-dissesto-idrogeologico-magliocchetti-spinge-per-la-ciociaria\/","name":"Fondi per dissesto idrogeologico, Magliocchetti 'spinge' per la Ciociaria - IlCorriereDellaProvincia.it - News h24 e notizie di approfondimento","isPartOf":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2019\/09\/07\/fondi-per-dissesto-idrogeologico-magliocchetti-spinge-per-la-ciociaria\/#primaryimage"},"image":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2019\/09\/07\/fondi-per-dissesto-idrogeologico-magliocchetti-spinge-per-la-ciociaria\/#primaryimage"},"thumbnailUrl":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2019\/09\/fiume-cosa-e1567866584135.jpg","datePublished":"2019-09-07T14:30:20+00:00","dateModified":"2019-09-09T12:38:29+00:00","description":"Il consigliere comunale di Frosinone Danilo Magliocchetti scrive all'assessore regionale Alessandri per sollecitare l'invio di fondi per il dissesto","breadcrumb":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2019\/09\/07\/fondi-per-dissesto-idrogeologico-magliocchetti-spinge-per-la-ciociaria\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2019\/09\/07\/fondi-per-dissesto-idrogeologico-magliocchetti-spinge-per-la-ciociaria\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2019\/09\/07\/fondi-per-dissesto-idrogeologico-magliocchetti-spinge-per-la-ciociaria\/#primaryimage","url":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2019\/09\/fiume-cosa-e1567866584135.jpg","contentUrl":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2019\/09\/fiume-cosa-e1567866584135.jpg","width":632,"height":375,"caption":"Un tratto del fiume Cosa"},{"@type":"BreadcrumbList","@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2019\/09\/07\/fondi-per-dissesto-idrogeologico-magliocchetti-spinge-per-la-ciociaria\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/"},{"@type":"ListItem","position":2,"name":"Fondi per dissesto idrogeologico, Magliocchetti &#8216;spinge&#8217; per la Ciociaria"}]},{"@type":"WebSite","@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/#website","url":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/","name":"Il Corriere Delle Provincia","description":"IlCorriereDellaProvincia.it, quotidiano web di politica, cronaca, inchiesta, lavoro, scuola, turismo, cultura e spettacolo, economia e finanza, salute e benessere. Approfondimenti e notizie aggiornate con foto e video della provincia di Frosinone ma anche news nazionali, dell\u2019Italia e del Mondo.","publisher":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":["Organization","Place"],"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/#organization","name":"Globalpress s.r.l.","url":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/","logo":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2019\/09\/07\/fondi-per-dissesto-idrogeologico-magliocchetti-spinge-per-la-ciociaria\/#local-main-organization-logo"},"image":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2019\/09\/07\/fondi-per-dissesto-idrogeologico-magliocchetti-spinge-per-la-ciociaria\/#local-main-organization-logo"},"telephone":[],"openingHoursSpecification":[{"@type":"OpeningHoursSpecification","dayOfWeek":["Monday","Tuesday","Wednesday","Thursday","Friday","Saturday","Sunday"],"opens":"09:00","closes":"17:00"}]},{"@type":"Person","@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/#\/schema\/person\/6d7f0a9120d0c03d0c552e9fdf49ed7d","name":"Redazione","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/secure.gravatar.com\/avatar\/a40eeacccdcad861f831dde73317f63a542e738f0dc4b79b9f47062d3d4bd1d2?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/a40eeacccdcad861f831dde73317f63a542e738f0dc4b79b9f47062d3d4bd1d2?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/a40eeacccdcad861f831dde73317f63a542e738f0dc4b79b9f47062d3d4bd1d2?s=96&d=mm&r=g","caption":"Redazione"},"description":"SEGUICI ANCHE SUI SOCIAL Facebook: TuNews24 e TuSport24 Instagram: TuNews24 e TuSport24 Youtube: TuNews24 Telegram: TuNews24 Puoi leggerci anche in formato cartaceo: il settimanale viene pubblicato e distribuito gratuitamente ogni venerd\u00ec in edicole, bar, centri commerciali e svariati esercizi. Ma \u00e8 possibile anche sfogliarlo comodamente online, cliccando su TU NEWS sfogliabile TU NEWS, PASSIONE PER L\u2019INFORMAZIONE","sameAs":["http:\/\/www.tunews24.it","www.facebook.com\/tunews24"],"url":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/author\/senzafirma\/"},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2019\/09\/07\/fondi-per-dissesto-idrogeologico-magliocchetti-spinge-per-la-ciociaria\/#local-main-organization-logo","url":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2022\/11\/cropped-il-corriere-della-provincia-testata-web-scontornata.png","contentUrl":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2022\/11\/cropped-il-corriere-della-provincia-testata-web-scontornata.png","width":2911,"height":717,"caption":"Globalpress s.r.l."}]}},"_links":{"self":[{"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/posts\/17664","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/users\/18"}],"replies":[{"embeddable":true,"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/comments?post=17664"}],"version-history":[{"count":1,"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/posts\/17664\/revisions"}],"predecessor-version":[{"id":17667,"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/posts\/17664\/revisions\/17667"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/media\/17666"}],"wp:attachment":[{"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/media?parent=17664"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/categories?post=17664"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/tags?post=17664"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}