{"id":17513,"date":"2019-09-04T14:58:02","date_gmt":"2019-09-04T12:58:02","guid":{"rendered":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/?p=17513"},"modified":"2019-09-04T14:58:02","modified_gmt":"2019-09-04T12:58:02","slug":"arce-gelateria-e-pizzeria-nel-mirino-del-nas","status":"publish","type":"post","link":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2019\/09\/04\/arce-gelateria-e-pizzeria-nel-mirino-del-nas\/","title":{"rendered":"Arce, gelateria e pizzeria nel mirino del Nas"},"content":{"rendered":"<p><strong>I carabinieri della Stazione di Arce<\/strong>, unitamente a personale del Nucleo Carabinieri Antisofisticazioni e Sanit\u00e0 di Latina, nell\u2019ambito di un servizio finalizzato alla repressione di reati in materia di sicurezza alimentare, hanno segnalato alle competenti autorit\u00e0 amministrative un 37enne residente ad Arce, gestore di un <em>bar \u2013 gelateria<\/em> ed una 56enne residente ad Arce gestrice di un <em>ristorante \u2013 pizzeria<\/em>, entrambi incensurati.<\/p>\n<h2>L&#8217;indagine<\/h2>\n<p>Nel corso degli accertamenti svolti presso le due attivit\u00e0 commerciali<strong>, i carabinieri hanno rilevato gravi carenze igienico sanitarie degli ambienti,<\/strong> in particolare delle celle frigorifere adibite alla conservazione degli alimenti, nonch\u00e9 variazioni strutturali non autorizzate. Pertanto, nei confronti dei rispettivi titolari sono state contestate sanzioni amministrative per\u00a0 7.000 euro.\u00a0 Sono in corso ulteriori accertamenti con i competenti uffici dell\u2019Asl per verificare ulteriori eventuali irregolarit\u00e0 amministrative.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>I carabinieri della Stazione di Arce, unitamente a personale del Nucleo Carabinieri Antisofisticazioni e Sanit\u00e0 di Latina, nell\u2019ambito di un<\/p>\n","protected":false},"author":18,"featured_media":8100,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[41],"tags":[411,90,6001,1854,6002,4556],"class_list":["post-17513","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-slide","tag-arce","tag-carabinieri","tag-geleteria","tag-nas","tag-pizzeria","tag-ristorante"],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v27.8 (Yoast SEO v27.8) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Arce, gelateria e pizzeria nel mirino del Nas - IlCorriereDellaProvincia.it - News h24 e notizie di approfondimento<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2019\/09\/04\/arce-gelateria-e-pizzeria-nel-mirino-del-nas\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Arce, gelateria e pizzeria nel mirino del Nas\" \/>\n<meta property=\"og:description\" content=\"I carabinieri della Stazione di Arce, unitamente a personale del Nucleo Carabinieri Antisofisticazioni e Sanit\u00e0 di Latina, nell\u2019ambito di un\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2019\/09\/04\/arce-gelateria-e-pizzeria-nel-mirino-del-nas\/\" \/>\n<meta property=\"og:site_name\" content=\"IlCorriereDellaProvincia.it - News h24 e notizie di approfondimento\" \/>\n<meta property=\"article:author\" content=\"www.facebook.com\/tunews24\" \/>\n<meta property=\"article:published_time\" content=\"2019-09-04T12:58:02+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2019\/03\/nas.png\" \/>\n\t<meta property=\"og:image:width\" content=\"661\" \/>\n\t<meta property=\"og:image:height\" content=\"460\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"Redazione\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"Redazione\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2019\\\/09\\\/04\\\/arce-gelateria-e-pizzeria-nel-mirino-del-nas\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2019\\\/09\\\/04\\\/arce-gelateria-e-pizzeria-nel-mirino-del-nas\\\/\"},\"author\":{\"name\":\"Redazione\",\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/#\\\/schema\\\/person\\\/6d7f0a9120d0c03d0c552e9fdf49ed7d\"},\"headline\":\"Arce, gelateria e pizzeria nel mirino del Nas\",\"datePublished\":\"2019-09-04T12:58:02+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2019\\\/09\\\/04\\\/arce-gelateria-e-pizzeria-nel-mirino-del-nas\\\/\"},\"wordCount\":136,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2019\\\/09\\\/04\\\/arce-gelateria-e-pizzeria-nel-mirino-del-nas\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2019\\\/03\\\/nas.png\",\"keywords\":[\"Arce\",\"carabinieri\",\"geleteria\",\"nas\",\"pizzeria\",\"ristorante\"],\"articleSection\":[\"*SLIDE*\"],\"inLanguage\":\"it-IT\",\"copyrightYear\":\"2019\",\"copyrightHolder\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/#organization\"}},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2019\\\/09\\\/04\\\/arce-gelateria-e-pizzeria-nel-mirino-del-nas\\\/\",\"url\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2019\\\/09\\\/04\\\/arce-gelateria-e-pizzeria-nel-mirino-del-nas\\\/\",\"name\":\"Arce, gelateria e pizzeria nel mirino del Nas - IlCorriereDellaProvincia.it - News h24 e notizie di approfondimento\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2019\\\/09\\\/04\\\/arce-gelateria-e-pizzeria-nel-mirino-del-nas\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2019\\\/09\\\/04\\\/arce-gelateria-e-pizzeria-nel-mirino-del-nas\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2019\\\/03\\\/nas.png\",\"datePublished\":\"2019-09-04T12:58:02+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2019\\\/09\\\/04\\\/arce-gelateria-e-pizzeria-nel-mirino-del-nas\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2019\\\/09\\\/04\\\/arce-gelateria-e-pizzeria-nel-mirino-del-nas\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2019\\\/09\\\/04\\\/arce-gelateria-e-pizzeria-nel-mirino-del-nas\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2019\\\/03\\\/nas.png\",\"contentUrl\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2019\\\/03\\\/nas.png\",\"width\":661,\"height\":460,\"caption\":\"carabinieri nas il corriere della provincia ciociaria frosinone\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2019\\\/09\\\/04\\\/arce-gelateria-e-pizzeria-nel-mirino-del-nas\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Arce, gelateria e pizzeria nel mirino del Nas\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/#website\",\"url\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/\",\"name\":\"Il Corriere Delle Provincia\",\"description\":\"IlCorriereDellaProvincia.it, quotidiano web di politica, cronaca, inchiesta, lavoro, scuola, turismo, cultura e spettacolo, economia e finanza, salute e benessere. Approfondimenti e notizie aggiornate con foto e video della provincia di Frosinone ma anche news nazionali, dell\u2019Italia e del Mondo.\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":[\"Organization\",\"Place\"],\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/#organization\",\"name\":\"Globalpress s.r.l.\",\"url\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/\",\"logo\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2019\\\/09\\\/04\\\/arce-gelateria-e-pizzeria-nel-mirino-del-nas\\\/#local-main-organization-logo\"},\"image\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2019\\\/09\\\/04\\\/arce-gelateria-e-pizzeria-nel-mirino-del-nas\\\/#local-main-organization-logo\"},\"telephone\":[],\"openingHoursSpecification\":[{\"@type\":\"OpeningHoursSpecification\",\"dayOfWeek\":[\"Monday\",\"Tuesday\",\"Wednesday\",\"Thursday\",\"Friday\",\"Saturday\",\"Sunday\"],\"opens\":\"09:00\",\"closes\":\"17:00\"}]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/#\\\/schema\\\/person\\\/6d7f0a9120d0c03d0c552e9fdf49ed7d\",\"name\":\"Redazione\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/a40eeacccdcad861f831dde73317f63a542e738f0dc4b79b9f47062d3d4bd1d2?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/a40eeacccdcad861f831dde73317f63a542e738f0dc4b79b9f47062d3d4bd1d2?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/a40eeacccdcad861f831dde73317f63a542e738f0dc4b79b9f47062d3d4bd1d2?s=96&d=mm&r=g\",\"caption\":\"Redazione\"},\"description\":\"SEGUICI ANCHE SUI SOCIAL Facebook: TuNews24 e TuSport24 Instagram: TuNews24 e TuSport24 Youtube: TuNews24 Telegram: TuNews24 Puoi leggerci anche in formato cartaceo: il settimanale viene pubblicato e distribuito gratuitamente ogni venerd\u00ec in edicole, bar, centri commerciali e svariati esercizi. Ma \u00e8 possibile anche sfogliarlo comodamente online, cliccando su TU NEWS sfogliabile TU NEWS, PASSIONE PER L\u2019INFORMAZIONE\",\"sameAs\":[\"http:\\\/\\\/www.tunews24.it\",\"www.facebook.com\\\/tunews24\"],\"url\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/author\\\/senzafirma\\\/\"},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2019\\\/09\\\/04\\\/arce-gelateria-e-pizzeria-nel-mirino-del-nas\\\/#local-main-organization-logo\",\"url\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2022\\\/11\\\/cropped-il-corriere-della-provincia-testata-web-scontornata.png\",\"contentUrl\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2022\\\/11\\\/cropped-il-corriere-della-provincia-testata-web-scontornata.png\",\"width\":2911,\"height\":717,\"caption\":\"Globalpress s.r.l.\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Arce, gelateria e pizzeria nel mirino del Nas - IlCorriereDellaProvincia.it - News h24 e notizie di approfondimento","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2019\/09\/04\/arce-gelateria-e-pizzeria-nel-mirino-del-nas\/","og_locale":"it_IT","og_type":"article","og_title":"Arce, gelateria e pizzeria nel mirino del Nas","og_description":"I carabinieri della Stazione di Arce, unitamente a personale del Nucleo Carabinieri Antisofisticazioni e Sanit\u00e0 di Latina, nell\u2019ambito di un","og_url":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2019\/09\/04\/arce-gelateria-e-pizzeria-nel-mirino-del-nas\/","og_site_name":"IlCorriereDellaProvincia.it - News h24 e notizie di approfondimento","article_author":"www.facebook.com\/tunews24","article_published_time":"2019-09-04T12:58:02+00:00","og_image":[{"width":661,"height":460,"url":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2019\/03\/nas.png","type":"image\/png"}],"author":"Redazione","twitter_card":"summary_large_image","twitter_misc":{"Scritto da":"Redazione","Tempo di lettura stimato":"1 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2019\/09\/04\/arce-gelateria-e-pizzeria-nel-mirino-del-nas\/#article","isPartOf":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2019\/09\/04\/arce-gelateria-e-pizzeria-nel-mirino-del-nas\/"},"author":{"name":"Redazione","@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/#\/schema\/person\/6d7f0a9120d0c03d0c552e9fdf49ed7d"},"headline":"Arce, gelateria e pizzeria nel mirino del Nas","datePublished":"2019-09-04T12:58:02+00:00","mainEntityOfPage":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2019\/09\/04\/arce-gelateria-e-pizzeria-nel-mirino-del-nas\/"},"wordCount":136,"commentCount":0,"publisher":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/#organization"},"image":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2019\/09\/04\/arce-gelateria-e-pizzeria-nel-mirino-del-nas\/#primaryimage"},"thumbnailUrl":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2019\/03\/nas.png","keywords":["Arce","carabinieri","geleteria","nas","pizzeria","ristorante"],"articleSection":["*SLIDE*"],"inLanguage":"it-IT","copyrightYear":"2019","copyrightHolder":{"@id":"https:\/\/www.tunews24.it\/#organization"}},{"@type":"WebPage","@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2019\/09\/04\/arce-gelateria-e-pizzeria-nel-mirino-del-nas\/","url":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2019\/09\/04\/arce-gelateria-e-pizzeria-nel-mirino-del-nas\/","name":"Arce, gelateria e pizzeria nel mirino del Nas - IlCorriereDellaProvincia.it - News h24 e notizie di approfondimento","isPartOf":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2019\/09\/04\/arce-gelateria-e-pizzeria-nel-mirino-del-nas\/#primaryimage"},"image":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2019\/09\/04\/arce-gelateria-e-pizzeria-nel-mirino-del-nas\/#primaryimage"},"thumbnailUrl":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2019\/03\/nas.png","datePublished":"2019-09-04T12:58:02+00:00","breadcrumb":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2019\/09\/04\/arce-gelateria-e-pizzeria-nel-mirino-del-nas\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2019\/09\/04\/arce-gelateria-e-pizzeria-nel-mirino-del-nas\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2019\/09\/04\/arce-gelateria-e-pizzeria-nel-mirino-del-nas\/#primaryimage","url":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2019\/03\/nas.png","contentUrl":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2019\/03\/nas.png","width":661,"height":460,"caption":"carabinieri nas il corriere della provincia ciociaria frosinone"},{"@type":"BreadcrumbList","@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2019\/09\/04\/arce-gelateria-e-pizzeria-nel-mirino-del-nas\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/"},{"@type":"ListItem","position":2,"name":"Arce, gelateria e pizzeria nel mirino del Nas"}]},{"@type":"WebSite","@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/#website","url":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/","name":"Il Corriere Delle Provincia","description":"IlCorriereDellaProvincia.it, quotidiano web di politica, cronaca, inchiesta, lavoro, scuola, turismo, cultura e spettacolo, economia e finanza, salute e benessere. Approfondimenti e notizie aggiornate con foto e video della provincia di Frosinone ma anche news nazionali, dell\u2019Italia e del Mondo.","publisher":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":["Organization","Place"],"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/#organization","name":"Globalpress s.r.l.","url":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/","logo":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2019\/09\/04\/arce-gelateria-e-pizzeria-nel-mirino-del-nas\/#local-main-organization-logo"},"image":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2019\/09\/04\/arce-gelateria-e-pizzeria-nel-mirino-del-nas\/#local-main-organization-logo"},"telephone":[],"openingHoursSpecification":[{"@type":"OpeningHoursSpecification","dayOfWeek":["Monday","Tuesday","Wednesday","Thursday","Friday","Saturday","Sunday"],"opens":"09:00","closes":"17:00"}]},{"@type":"Person","@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/#\/schema\/person\/6d7f0a9120d0c03d0c552e9fdf49ed7d","name":"Redazione","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/secure.gravatar.com\/avatar\/a40eeacccdcad861f831dde73317f63a542e738f0dc4b79b9f47062d3d4bd1d2?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/a40eeacccdcad861f831dde73317f63a542e738f0dc4b79b9f47062d3d4bd1d2?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/a40eeacccdcad861f831dde73317f63a542e738f0dc4b79b9f47062d3d4bd1d2?s=96&d=mm&r=g","caption":"Redazione"},"description":"SEGUICI ANCHE SUI SOCIAL Facebook: TuNews24 e TuSport24 Instagram: TuNews24 e TuSport24 Youtube: TuNews24 Telegram: TuNews24 Puoi leggerci anche in formato cartaceo: il settimanale viene pubblicato e distribuito gratuitamente ogni venerd\u00ec in edicole, bar, centri commerciali e svariati esercizi. Ma \u00e8 possibile anche sfogliarlo comodamente online, cliccando su TU NEWS sfogliabile TU NEWS, PASSIONE PER L\u2019INFORMAZIONE","sameAs":["http:\/\/www.tunews24.it","www.facebook.com\/tunews24"],"url":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/author\/senzafirma\/"},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2019\/09\/04\/arce-gelateria-e-pizzeria-nel-mirino-del-nas\/#local-main-organization-logo","url":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2022\/11\/cropped-il-corriere-della-provincia-testata-web-scontornata.png","contentUrl":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2022\/11\/cropped-il-corriere-della-provincia-testata-web-scontornata.png","width":2911,"height":717,"caption":"Globalpress s.r.l."}]}},"_links":{"self":[{"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/posts\/17513","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/users\/18"}],"replies":[{"embeddable":true,"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/comments?post=17513"}],"version-history":[{"count":1,"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/posts\/17513\/revisions"}],"predecessor-version":[{"id":17514,"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/posts\/17513\/revisions\/17514"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/media\/8100"}],"wp:attachment":[{"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/media?parent=17513"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/categories?post=17513"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/tags?post=17513"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}