{"id":17163,"date":"2019-08-27T14:04:07","date_gmt":"2019-08-27T12:04:07","guid":{"rendered":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/?p=17163"},"modified":"2019-08-28T10:51:05","modified_gmt":"2019-08-28T08:51:05","slug":"la-minaccia-si-fa-consegnare-il-portafogli-e-fugge-denunciato-per-rapina","status":"publish","type":"post","link":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2019\/08\/27\/la-minaccia-si-fa-consegnare-il-portafogli-e-fugge-denunciato-per-rapina\/","title":{"rendered":"La minaccia, si fa consegnare il portafogli e fugge: denunciato per rapina"},"content":{"rendered":"<p>Avvicina una <strong>trentaduenne di Sora<\/strong> e, minacciandola, si fa consegnare il portafogli. Poi fugge ma viene <strong>identificato e rintracciato dai carabinieri<\/strong> che lo denunciano per rapina.<\/p>\n<p>\u00c8 accaduto <strong>ieri pomeriggio a Frosinone<\/strong> quando i militari della stazione, a conclusione di un\u2019attivit\u00e0 d\u2019indagine, hanno denunciato in stato di libert\u00e0 per rapina, un trentanovenne residente nel capoluogo, gi\u00e0 censito per reati in materia di stupefacenti e gi\u00e0 sottoposto alla misura di prevenzione dell\u2019avviso orale.<\/p>\n<p>Ieri mattina l\u2019uomo ha avvicinato<strong> una ragazza residente a Sora<\/strong> e, dietro minacce verbali, si \u00e8 fatto consegnare il portafogli contenente denaro contante. Poi si \u00e8 dato alla fuga nelle vie limitrofe. I carabinieri, acquisite le necessarie informazioni e la descrizione sommaria del trentanovenne, sono riusciti a identificarlo e denunciarlo. Sar\u00e0 anche proposto per l\u2019applicazione della sorveglianza speciale.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Avvicina una trentaduenne di Sora e, minacciandola, si fa consegnare il portafogli. Poi fugge ma viene identificato e rintracciato dai<\/p>\n","protected":false},"author":18,"featured_media":17165,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[41,2],"tags":[90,245,93,1337,338,161,5901],"class_list":["post-17163","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-slide","category-cronaca","tag-carabinieri","tag-denuncia","tag-frosinone","tag-portafogli","tag-rapina","tag-sora","tag-trentaduenne"],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v27.8 (Yoast SEO v27.8) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>La minaccia, si fa consegnare il portafogli e fugge: denunciato per rapina - IlCorriereDellaProvincia.it - News h24 e notizie di approfondimento<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2019\/08\/27\/la-minaccia-si-fa-consegnare-il-portafogli-e-fugge-denunciato-per-rapina\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"La minaccia, si fa consegnare il portafogli e fugge: denunciato per rapina\" \/>\n<meta property=\"og:description\" content=\"Avvicina una trentaduenne di Sora e, minacciandola, si fa consegnare il portafogli. Poi fugge ma viene identificato e rintracciato dai\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2019\/08\/27\/la-minaccia-si-fa-consegnare-il-portafogli-e-fugge-denunciato-per-rapina\/\" \/>\n<meta property=\"og:site_name\" content=\"IlCorriereDellaProvincia.it - News h24 e notizie di approfondimento\" \/>\n<meta property=\"article:author\" content=\"www.facebook.com\/tunews24\" \/>\n<meta property=\"article:published_time\" content=\"2019-08-27T12:04:07+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2019-08-28T08:51:05+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2019\/08\/rapina-frosinone-e1566907408892.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"632\" \/>\n\t<meta property=\"og:image:height\" content=\"349\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Redazione\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"Redazione\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2019\\\/08\\\/27\\\/la-minaccia-si-fa-consegnare-il-portafogli-e-fugge-denunciato-per-rapina\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2019\\\/08\\\/27\\\/la-minaccia-si-fa-consegnare-il-portafogli-e-fugge-denunciato-per-rapina\\\/\"},\"author\":{\"name\":\"Redazione\",\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/#\\\/schema\\\/person\\\/6d7f0a9120d0c03d0c552e9fdf49ed7d\"},\"headline\":\"La minaccia, si fa consegnare il portafogli e fugge: denunciato per rapina\",\"datePublished\":\"2019-08-27T12:04:07+00:00\",\"dateModified\":\"2019-08-28T08:51:05+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2019\\\/08\\\/27\\\/la-minaccia-si-fa-consegnare-il-portafogli-e-fugge-denunciato-per-rapina\\\/\"},\"wordCount\":144,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2019\\\/08\\\/27\\\/la-minaccia-si-fa-consegnare-il-portafogli-e-fugge-denunciato-per-rapina\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2019\\\/08\\\/rapina-frosinone-e1566907408892.jpg\",\"keywords\":[\"carabinieri\",\"denuncia\",\"Frosinone\",\"portafogli\",\"rapina\",\"sora\",\"trentaduenne\"],\"articleSection\":[\"*SLIDE*\",\"Cronaca\"],\"inLanguage\":\"it-IT\",\"copyrightYear\":\"2019\",\"copyrightHolder\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/#organization\"}},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2019\\\/08\\\/27\\\/la-minaccia-si-fa-consegnare-il-portafogli-e-fugge-denunciato-per-rapina\\\/\",\"url\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2019\\\/08\\\/27\\\/la-minaccia-si-fa-consegnare-il-portafogli-e-fugge-denunciato-per-rapina\\\/\",\"name\":\"La minaccia, si fa consegnare il portafogli e fugge: denunciato per rapina - IlCorriereDellaProvincia.it - News h24 e notizie di approfondimento\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2019\\\/08\\\/27\\\/la-minaccia-si-fa-consegnare-il-portafogli-e-fugge-denunciato-per-rapina\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2019\\\/08\\\/27\\\/la-minaccia-si-fa-consegnare-il-portafogli-e-fugge-denunciato-per-rapina\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2019\\\/08\\\/rapina-frosinone-e1566907408892.jpg\",\"datePublished\":\"2019-08-27T12:04:07+00:00\",\"dateModified\":\"2019-08-28T08:51:05+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2019\\\/08\\\/27\\\/la-minaccia-si-fa-consegnare-il-portafogli-e-fugge-denunciato-per-rapina\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2019\\\/08\\\/27\\\/la-minaccia-si-fa-consegnare-il-portafogli-e-fugge-denunciato-per-rapina\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2019\\\/08\\\/27\\\/la-minaccia-si-fa-consegnare-il-portafogli-e-fugge-denunciato-per-rapina\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2019\\\/08\\\/rapina-frosinone-e1566907408892.jpg\",\"contentUrl\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2019\\\/08\\\/rapina-frosinone-e1566907408892.jpg\",\"width\":632,\"height\":349,\"caption\":\"Denunciato per rapina a una donna\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2019\\\/08\\\/27\\\/la-minaccia-si-fa-consegnare-il-portafogli-e-fugge-denunciato-per-rapina\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"La minaccia, si fa consegnare il portafogli e fugge: denunciato per rapina\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/#website\",\"url\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/\",\"name\":\"Il Corriere Delle Provincia\",\"description\":\"IlCorriereDellaProvincia.it, quotidiano web di politica, cronaca, inchiesta, lavoro, scuola, turismo, cultura e spettacolo, economia e finanza, salute e benessere. Approfondimenti e notizie aggiornate con foto e video della provincia di Frosinone ma anche news nazionali, dell\u2019Italia e del Mondo.\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":[\"Organization\",\"Place\"],\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/#organization\",\"name\":\"Globalpress s.r.l.\",\"url\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/\",\"logo\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2019\\\/08\\\/27\\\/la-minaccia-si-fa-consegnare-il-portafogli-e-fugge-denunciato-per-rapina\\\/#local-main-organization-logo\"},\"image\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2019\\\/08\\\/27\\\/la-minaccia-si-fa-consegnare-il-portafogli-e-fugge-denunciato-per-rapina\\\/#local-main-organization-logo\"},\"telephone\":[],\"openingHoursSpecification\":[{\"@type\":\"OpeningHoursSpecification\",\"dayOfWeek\":[\"Monday\",\"Tuesday\",\"Wednesday\",\"Thursday\",\"Friday\",\"Saturday\",\"Sunday\"],\"opens\":\"09:00\",\"closes\":\"17:00\"}]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/#\\\/schema\\\/person\\\/6d7f0a9120d0c03d0c552e9fdf49ed7d\",\"name\":\"Redazione\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/a40eeacccdcad861f831dde73317f63a542e738f0dc4b79b9f47062d3d4bd1d2?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/a40eeacccdcad861f831dde73317f63a542e738f0dc4b79b9f47062d3d4bd1d2?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/a40eeacccdcad861f831dde73317f63a542e738f0dc4b79b9f47062d3d4bd1d2?s=96&d=mm&r=g\",\"caption\":\"Redazione\"},\"description\":\"SEGUICI ANCHE SUI SOCIAL Facebook: TuNews24 e TuSport24 Instagram: TuNews24 e TuSport24 Youtube: TuNews24 Telegram: TuNews24 Puoi leggerci anche in formato cartaceo: il settimanale viene pubblicato e distribuito gratuitamente ogni venerd\u00ec in edicole, bar, centri commerciali e svariati esercizi. Ma \u00e8 possibile anche sfogliarlo comodamente online, cliccando su TU NEWS sfogliabile TU NEWS, PASSIONE PER L\u2019INFORMAZIONE\",\"sameAs\":[\"http:\\\/\\\/www.tunews24.it\",\"www.facebook.com\\\/tunews24\"],\"url\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/author\\\/senzafirma\\\/\"},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2019\\\/08\\\/27\\\/la-minaccia-si-fa-consegnare-il-portafogli-e-fugge-denunciato-per-rapina\\\/#local-main-organization-logo\",\"url\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2022\\\/11\\\/cropped-il-corriere-della-provincia-testata-web-scontornata.png\",\"contentUrl\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2022\\\/11\\\/cropped-il-corriere-della-provincia-testata-web-scontornata.png\",\"width\":2911,\"height\":717,\"caption\":\"Globalpress s.r.l.\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"La minaccia, si fa consegnare il portafogli e fugge: denunciato per rapina - IlCorriereDellaProvincia.it - News h24 e notizie di approfondimento","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2019\/08\/27\/la-minaccia-si-fa-consegnare-il-portafogli-e-fugge-denunciato-per-rapina\/","og_locale":"it_IT","og_type":"article","og_title":"La minaccia, si fa consegnare il portafogli e fugge: denunciato per rapina","og_description":"Avvicina una trentaduenne di Sora e, minacciandola, si fa consegnare il portafogli. Poi fugge ma viene identificato e rintracciato dai","og_url":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2019\/08\/27\/la-minaccia-si-fa-consegnare-il-portafogli-e-fugge-denunciato-per-rapina\/","og_site_name":"IlCorriereDellaProvincia.it - News h24 e notizie di approfondimento","article_author":"www.facebook.com\/tunews24","article_published_time":"2019-08-27T12:04:07+00:00","article_modified_time":"2019-08-28T08:51:05+00:00","og_image":[{"width":632,"height":349,"url":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2019\/08\/rapina-frosinone-e1566907408892.jpg","type":"image\/jpeg"}],"author":"Redazione","twitter_card":"summary_large_image","twitter_misc":{"Scritto da":"Redazione","Tempo di lettura stimato":"1 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2019\/08\/27\/la-minaccia-si-fa-consegnare-il-portafogli-e-fugge-denunciato-per-rapina\/#article","isPartOf":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2019\/08\/27\/la-minaccia-si-fa-consegnare-il-portafogli-e-fugge-denunciato-per-rapina\/"},"author":{"name":"Redazione","@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/#\/schema\/person\/6d7f0a9120d0c03d0c552e9fdf49ed7d"},"headline":"La minaccia, si fa consegnare il portafogli e fugge: denunciato per rapina","datePublished":"2019-08-27T12:04:07+00:00","dateModified":"2019-08-28T08:51:05+00:00","mainEntityOfPage":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2019\/08\/27\/la-minaccia-si-fa-consegnare-il-portafogli-e-fugge-denunciato-per-rapina\/"},"wordCount":144,"commentCount":0,"publisher":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/#organization"},"image":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2019\/08\/27\/la-minaccia-si-fa-consegnare-il-portafogli-e-fugge-denunciato-per-rapina\/#primaryimage"},"thumbnailUrl":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2019\/08\/rapina-frosinone-e1566907408892.jpg","keywords":["carabinieri","denuncia","Frosinone","portafogli","rapina","sora","trentaduenne"],"articleSection":["*SLIDE*","Cronaca"],"inLanguage":"it-IT","copyrightYear":"2019","copyrightHolder":{"@id":"https:\/\/www.tunews24.it\/#organization"}},{"@type":"WebPage","@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2019\/08\/27\/la-minaccia-si-fa-consegnare-il-portafogli-e-fugge-denunciato-per-rapina\/","url":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2019\/08\/27\/la-minaccia-si-fa-consegnare-il-portafogli-e-fugge-denunciato-per-rapina\/","name":"La minaccia, si fa consegnare il portafogli e fugge: denunciato per rapina - IlCorriereDellaProvincia.it - News h24 e notizie di approfondimento","isPartOf":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2019\/08\/27\/la-minaccia-si-fa-consegnare-il-portafogli-e-fugge-denunciato-per-rapina\/#primaryimage"},"image":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2019\/08\/27\/la-minaccia-si-fa-consegnare-il-portafogli-e-fugge-denunciato-per-rapina\/#primaryimage"},"thumbnailUrl":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2019\/08\/rapina-frosinone-e1566907408892.jpg","datePublished":"2019-08-27T12:04:07+00:00","dateModified":"2019-08-28T08:51:05+00:00","breadcrumb":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2019\/08\/27\/la-minaccia-si-fa-consegnare-il-portafogli-e-fugge-denunciato-per-rapina\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2019\/08\/27\/la-minaccia-si-fa-consegnare-il-portafogli-e-fugge-denunciato-per-rapina\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2019\/08\/27\/la-minaccia-si-fa-consegnare-il-portafogli-e-fugge-denunciato-per-rapina\/#primaryimage","url":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2019\/08\/rapina-frosinone-e1566907408892.jpg","contentUrl":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2019\/08\/rapina-frosinone-e1566907408892.jpg","width":632,"height":349,"caption":"Denunciato per rapina a una donna"},{"@type":"BreadcrumbList","@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2019\/08\/27\/la-minaccia-si-fa-consegnare-il-portafogli-e-fugge-denunciato-per-rapina\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/"},{"@type":"ListItem","position":2,"name":"La minaccia, si fa consegnare il portafogli e fugge: denunciato per rapina"}]},{"@type":"WebSite","@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/#website","url":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/","name":"Il Corriere Delle Provincia","description":"IlCorriereDellaProvincia.it, quotidiano web di politica, cronaca, inchiesta, lavoro, scuola, turismo, cultura e spettacolo, economia e finanza, salute e benessere. Approfondimenti e notizie aggiornate con foto e video della provincia di Frosinone ma anche news nazionali, dell\u2019Italia e del Mondo.","publisher":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":["Organization","Place"],"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/#organization","name":"Globalpress s.r.l.","url":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/","logo":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2019\/08\/27\/la-minaccia-si-fa-consegnare-il-portafogli-e-fugge-denunciato-per-rapina\/#local-main-organization-logo"},"image":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2019\/08\/27\/la-minaccia-si-fa-consegnare-il-portafogli-e-fugge-denunciato-per-rapina\/#local-main-organization-logo"},"telephone":[],"openingHoursSpecification":[{"@type":"OpeningHoursSpecification","dayOfWeek":["Monday","Tuesday","Wednesday","Thursday","Friday","Saturday","Sunday"],"opens":"09:00","closes":"17:00"}]},{"@type":"Person","@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/#\/schema\/person\/6d7f0a9120d0c03d0c552e9fdf49ed7d","name":"Redazione","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/secure.gravatar.com\/avatar\/a40eeacccdcad861f831dde73317f63a542e738f0dc4b79b9f47062d3d4bd1d2?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/a40eeacccdcad861f831dde73317f63a542e738f0dc4b79b9f47062d3d4bd1d2?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/a40eeacccdcad861f831dde73317f63a542e738f0dc4b79b9f47062d3d4bd1d2?s=96&d=mm&r=g","caption":"Redazione"},"description":"SEGUICI ANCHE SUI SOCIAL Facebook: TuNews24 e TuSport24 Instagram: TuNews24 e TuSport24 Youtube: TuNews24 Telegram: TuNews24 Puoi leggerci anche in formato cartaceo: il settimanale viene pubblicato e distribuito gratuitamente ogni venerd\u00ec in edicole, bar, centri commerciali e svariati esercizi. Ma \u00e8 possibile anche sfogliarlo comodamente online, cliccando su TU NEWS sfogliabile TU NEWS, PASSIONE PER L\u2019INFORMAZIONE","sameAs":["http:\/\/www.tunews24.it","www.facebook.com\/tunews24"],"url":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/author\/senzafirma\/"},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2019\/08\/27\/la-minaccia-si-fa-consegnare-il-portafogli-e-fugge-denunciato-per-rapina\/#local-main-organization-logo","url":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2022\/11\/cropped-il-corriere-della-provincia-testata-web-scontornata.png","contentUrl":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2022\/11\/cropped-il-corriere-della-provincia-testata-web-scontornata.png","width":2911,"height":717,"caption":"Globalpress s.r.l."}]}},"_links":{"self":[{"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/posts\/17163","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/users\/18"}],"replies":[{"embeddable":true,"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/comments?post=17163"}],"version-history":[{"count":1,"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/posts\/17163\/revisions"}],"predecessor-version":[{"id":17164,"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/posts\/17163\/revisions\/17164"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/media\/17165"}],"wp:attachment":[{"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/media?parent=17163"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/categories?post=17163"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/tags?post=17163"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}