{"id":17132,"date":"2019-08-26T17:27:21","date_gmt":"2019-08-26T15:27:21","guid":{"rendered":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/?p=17132"},"modified":"2019-08-26T17:41:59","modified_gmt":"2019-08-26T15:41:59","slug":"al-festival-delle-storie-lo-sport-epico-di-piero-trellini-carlo-pernat-e-massimo-calandri","status":"publish","type":"post","link":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2019\/08\/26\/al-festival-delle-storie-lo-sport-epico-di-piero-trellini-carlo-pernat-e-massimo-calandri\/","title":{"rendered":"Al Festival delle Storie lo sport epico di Piero Trellini, Carlo Pernat e Massimo Calandri"},"content":{"rendered":"<p><strong>Dieci anni di Festival delle Storie e un\u2019atmosfera che resta incantata<\/strong>, magica, incredibilmente straordinaria. Dal sogno di Vittorio Macioce e Rachele Brancatisano a una realt\u00e0 che oggi conta oltre centoventi ospiti.<\/p>\n<p>&nbsp;<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"wp-image-17135 aligncenter\" src=\"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2019\/08\/festival-storie-uno.jpg\" alt=\"\" width=\"632\" height=\"420\" srcset=\"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2019\/08\/festival-storie-uno.jpg 720w, https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2019\/08\/festival-storie-uno-300x200.jpg 300w, https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2019\/08\/festival-storie-uno-500x333.jpg 500w, https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2019\/08\/festival-storie-uno-272x182.jpg 272w\" sizes=\"auto, (max-width: 632px) 100vw, 632px\" \/><\/p>\n<h2><\/h2>\n<h2>Il programma<\/h2>\n<p>Un avvio a Broccostella e Gallinaro nel primo giorno di rassegna e grande partecipazione di pubblico ad ogni appuntamento, per qualsiasi evento.<strong> Dal giornalista Marino Bartoletti a Maurizio Piccirilli<\/strong>, l\u2019autore della storica foto del corpo di Aldo Moro ritrovato in via Caetani; da Andrea Cuomo ad Anna Muzio, che hanno parlato di caff\u00e8, a Simone Dolcemascolo e ai suoi straordinari dolci.<\/p>\n<p>Oggi, 26 agosto, la carovana del Festival si ferma ad Alvito. Dolcissimo, in mattinata, il ricordo dello scrittore e traduttore Sergio Claudio Perroni, con sua moglie Cettina Cali\u00f2, lo scrittore Amleto de Silva, il cantautore Edoardo Inglese e Vittorio Macioce.<\/p>\n<h2>I presenti<\/h2>\n<p>A partire dalle 18, nel vecchio convento di San Nicola, lo scrittore Mauro Garofalo, il regista e attore Luca Mauceri, lo scrittore Gioachino Lanotte, l\u2019ex parlamentare Nunzia De Girolamo, lo scrittore Renato Cantore, l\u2019astrofisica Emma Gatti, la scrittrice Giada Trebeschi, il giornalista Massimo Veronese, il pianista Nazzareno Caruso e lo scrittore Davide Toffoli. Gran finale parlando della luna con Vittorio Macioce, Marino Bartoletti, Amleto de Silva, Edoardo Inglese e David Duszynski.<\/p>\n<p>&nbsp;<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"wp-image-17136 aligncenter\" src=\"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2019\/08\/festiva-storie-due.jpg\" alt=\"\" width=\"632\" height=\"421\" srcset=\"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2019\/08\/festiva-storie-due.jpg 1600w, https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2019\/08\/festiva-storie-due-300x200.jpg 300w, https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2019\/08\/festiva-storie-due-768x512.jpg 768w, https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2019\/08\/festiva-storie-due-1024x682.jpg 1024w, https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2019\/08\/festiva-storie-due-500x333.jpg 500w, https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2019\/08\/festiva-storie-due-272x182.jpg 272w\" sizes=\"auto, (max-width: 632px) 100vw, 632px\" \/><\/p>\n<p>&nbsp;<\/p>\n<h2>Domani si arriva a San Donato Val di Comino<\/h2>\n<p>Si comincia alle 18 con \u201cBelli e dannati\u201d, con Marina Mander, Paolo Marati e Mattia Signorini.<\/p>\n<p>La vita \u00e8 il pi\u00f9 bastardo romanzo di formazione. Per raccontarla negli anni pi\u00f9 inquieti ci vuole talento ed empatia. \u00c8 un viaggio nell\u2019adolescenza, quella eterna, che si ripete in tutte le generazioni. Marina Mander lo fa con &#8216;L\u2019et\u00e0 straniera&#8217;, Mattia Signorini con \u201cStelle minori\u201d e Paolo Marati con &#8216;Il giorno in cui Lorenzo mor\u00ec&#8217;.<\/p>\n<p>Alle 20.30 si parla di epopea del calcio con Piero Trellini e la sua \u201cItalia-Brasile 3 a 2\u201d.\u00a0Trellini aveva dodici anni in quel caldo pomeriggio del 5 luglio 1982 in cui l\u2019Italia e il Brasile si sfidavano all\u2019Estadio de Sarri\u00e1 di Barcellona. Dodici anni sono sufficienti per capire che si sta assistendo alla \u201cpartita pi\u00f9 bella della storia del calcio\u201d. E vederla a dodici anni \u00e8 un\u2019esperienza unica perch\u00e9 hai gli occhi pieni di sogni e un\u2019infinita voglia di fare il tifo per il futuro. Lui la racconta nel libro \u201cLa partita\u201d.<\/p>\n<p>Ancora sport alle 21.30 con Carlo Pernat e Massimo Calandri, che insieme hanno scritto\u00a0\u201cBel\u00ecn che paddock\u201d. Calandri \u00e8 un giornalista di Repubblica e il primo \u00e8 un manager del mondo dei motori. Ha scoperto e lanciato pluricampioni del mondo e vinto 20 titoli iridati. Ha messo d\u2019accordo sponsor e motori, contribuendo alla crescita planetaria della MotoGP come nessun altro.<\/p>\n<p>Si chiude alle 22.30 con \u201cOrsitudine\u201d, a cura del Teatro Lanciavicchio. Si tratta di uno spettacolo nato per raccontare l\u2019orso: proprio \u201cquello marsicano\u201d, di cui conosciamo davvero poco. Una\u00a0narrazione drammaturgica originale, nella quale sono confluiti dati scientifici e anche storie e leggende recuperate dalla tradizione italiana e mondiale.<\/p>\n<p>&nbsp;<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"size-full wp-image-17137 aligncenter\" src=\"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2019\/08\/festival-macioce.jpg\" alt=\"\" width=\"600\" height=\"450\" srcset=\"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2019\/08\/festival-macioce.jpg 600w, https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2019\/08\/festival-macioce-300x225.jpg 300w, https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2019\/08\/festival-macioce-500x375.jpg 500w\" sizes=\"auto, (max-width: 600px) 100vw, 600px\" \/><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Dieci anni di Festival delle Storie e un\u2019atmosfera che resta incantata, magica, incredibilmente straordinaria. Dal sogno di Vittorio Macioce e<\/p>\n","protected":false},"author":18,"featured_media":17134,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[4,14,1],"tags":[5891,5540,955,5791],"class_list":["post-17132","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-primo-piano","category-cultura","category-news","tag-festival-delle-storie","tag-san-donato-val-di-comino","tag-val-di-comino","tag-vittorio-macioce"],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v27.8 (Yoast SEO v27.8) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Al Festival delle Storie lo sport epico di Piero Trellini, Carlo Pernat e Massimo Calandri - IlCorriereDellaProvincia.it - News h24 e notizie di approfondimento<\/title>\n<meta name=\"description\" content=\"Un avvio a Broccostella e Gallinaro nel primo giorno di rassegna e grande partecipazione di pubblico ad ogni appuntamento, per qualsiasi evento\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2019\/08\/26\/al-festival-delle-storie-lo-sport-epico-di-piero-trellini-carlo-pernat-e-massimo-calandri\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Al Festival delle Storie lo sport epico di Piero Trellini, Carlo Pernat e Massimo Calandri\" \/>\n<meta property=\"og:description\" content=\"Un avvio a Broccostella e Gallinaro nel primo giorno di rassegna e grande partecipazione di pubblico ad ogni appuntamento, per qualsiasi evento\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2019\/08\/26\/al-festival-delle-storie-lo-sport-epico-di-piero-trellini-carlo-pernat-e-massimo-calandri\/\" \/>\n<meta property=\"og:site_name\" content=\"IlCorriereDellaProvincia.it - News h24 e notizie di approfondimento\" \/>\n<meta property=\"article:author\" content=\"www.facebook.com\/tunews24\" \/>\n<meta property=\"article:published_time\" content=\"2019-08-26T15:27:21+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2019-08-26T15:41:59+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2019\/08\/festival-storie.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"720\" \/>\n\t<meta property=\"og:image:height\" content=\"479\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Redazione\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"Redazione\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minuti\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2019\\\/08\\\/26\\\/al-festival-delle-storie-lo-sport-epico-di-piero-trellini-carlo-pernat-e-massimo-calandri\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2019\\\/08\\\/26\\\/al-festival-delle-storie-lo-sport-epico-di-piero-trellini-carlo-pernat-e-massimo-calandri\\\/\"},\"author\":{\"name\":\"Redazione\",\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/#\\\/schema\\\/person\\\/6d7f0a9120d0c03d0c552e9fdf49ed7d\"},\"headline\":\"Al Festival delle Storie lo sport epico di Piero Trellini, Carlo Pernat e Massimo Calandri\",\"datePublished\":\"2019-08-26T15:27:21+00:00\",\"dateModified\":\"2019-08-26T15:41:59+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2019\\\/08\\\/26\\\/al-festival-delle-storie-lo-sport-epico-di-piero-trellini-carlo-pernat-e-massimo-calandri\\\/\"},\"wordCount\":505,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2019\\\/08\\\/26\\\/al-festival-delle-storie-lo-sport-epico-di-piero-trellini-carlo-pernat-e-massimo-calandri\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2019\\\/08\\\/festival-storie.jpg\",\"keywords\":[\"festival delle storie\",\"san donato val di comino\",\"Val di Comino\",\"vittorio macioce\"],\"articleSection\":[\"*PRIMO PIANO*\",\"Cultura e Spettacolo\",\"News\"],\"inLanguage\":\"it-IT\",\"copyrightYear\":\"2019\",\"copyrightHolder\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/#organization\"}},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2019\\\/08\\\/26\\\/al-festival-delle-storie-lo-sport-epico-di-piero-trellini-carlo-pernat-e-massimo-calandri\\\/\",\"url\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2019\\\/08\\\/26\\\/al-festival-delle-storie-lo-sport-epico-di-piero-trellini-carlo-pernat-e-massimo-calandri\\\/\",\"name\":\"Al Festival delle Storie lo sport epico di Piero Trellini, Carlo Pernat e Massimo Calandri - IlCorriereDellaProvincia.it - News h24 e notizie di approfondimento\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2019\\\/08\\\/26\\\/al-festival-delle-storie-lo-sport-epico-di-piero-trellini-carlo-pernat-e-massimo-calandri\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2019\\\/08\\\/26\\\/al-festival-delle-storie-lo-sport-epico-di-piero-trellini-carlo-pernat-e-massimo-calandri\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2019\\\/08\\\/festival-storie.jpg\",\"datePublished\":\"2019-08-26T15:27:21+00:00\",\"dateModified\":\"2019-08-26T15:41:59+00:00\",\"description\":\"Un avvio a Broccostella e Gallinaro nel primo giorno di rassegna e grande partecipazione di pubblico ad ogni appuntamento, per qualsiasi evento\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2019\\\/08\\\/26\\\/al-festival-delle-storie-lo-sport-epico-di-piero-trellini-carlo-pernat-e-massimo-calandri\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2019\\\/08\\\/26\\\/al-festival-delle-storie-lo-sport-epico-di-piero-trellini-carlo-pernat-e-massimo-calandri\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2019\\\/08\\\/26\\\/al-festival-delle-storie-lo-sport-epico-di-piero-trellini-carlo-pernat-e-massimo-calandri\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2019\\\/08\\\/festival-storie.jpg\",\"contentUrl\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2019\\\/08\\\/festival-storie.jpg\",\"width\":720,\"height\":479,\"caption\":\"festival storie il corriere della provincia\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2019\\\/08\\\/26\\\/al-festival-delle-storie-lo-sport-epico-di-piero-trellini-carlo-pernat-e-massimo-calandri\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Al Festival delle Storie lo sport epico di Piero Trellini, Carlo Pernat e Massimo Calandri\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/#website\",\"url\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/\",\"name\":\"Il Corriere Delle Provincia\",\"description\":\"IlCorriereDellaProvincia.it, quotidiano web di politica, cronaca, inchiesta, lavoro, scuola, turismo, cultura e spettacolo, economia e finanza, salute e benessere. Approfondimenti e notizie aggiornate con foto e video della provincia di Frosinone ma anche news nazionali, dell\u2019Italia e del Mondo.\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":[\"Organization\",\"Place\"],\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/#organization\",\"name\":\"Globalpress s.r.l.\",\"url\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/\",\"logo\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2019\\\/08\\\/26\\\/al-festival-delle-storie-lo-sport-epico-di-piero-trellini-carlo-pernat-e-massimo-calandri\\\/#local-main-organization-logo\"},\"image\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2019\\\/08\\\/26\\\/al-festival-delle-storie-lo-sport-epico-di-piero-trellini-carlo-pernat-e-massimo-calandri\\\/#local-main-organization-logo\"},\"telephone\":[],\"openingHoursSpecification\":[{\"@type\":\"OpeningHoursSpecification\",\"dayOfWeek\":[\"Monday\",\"Tuesday\",\"Wednesday\",\"Thursday\",\"Friday\",\"Saturday\",\"Sunday\"],\"opens\":\"09:00\",\"closes\":\"17:00\"}]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/#\\\/schema\\\/person\\\/6d7f0a9120d0c03d0c552e9fdf49ed7d\",\"name\":\"Redazione\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/a40eeacccdcad861f831dde73317f63a542e738f0dc4b79b9f47062d3d4bd1d2?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/a40eeacccdcad861f831dde73317f63a542e738f0dc4b79b9f47062d3d4bd1d2?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/a40eeacccdcad861f831dde73317f63a542e738f0dc4b79b9f47062d3d4bd1d2?s=96&d=mm&r=g\",\"caption\":\"Redazione\"},\"description\":\"SEGUICI ANCHE SUI SOCIAL Facebook: TuNews24 e TuSport24 Instagram: TuNews24 e TuSport24 Youtube: TuNews24 Telegram: TuNews24 Puoi leggerci anche in formato cartaceo: il settimanale viene pubblicato e distribuito gratuitamente ogni venerd\u00ec in edicole, bar, centri commerciali e svariati esercizi. Ma \u00e8 possibile anche sfogliarlo comodamente online, cliccando su TU NEWS sfogliabile TU NEWS, PASSIONE PER L\u2019INFORMAZIONE\",\"sameAs\":[\"http:\\\/\\\/www.tunews24.it\",\"www.facebook.com\\\/tunews24\"],\"url\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/author\\\/senzafirma\\\/\"},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2019\\\/08\\\/26\\\/al-festival-delle-storie-lo-sport-epico-di-piero-trellini-carlo-pernat-e-massimo-calandri\\\/#local-main-organization-logo\",\"url\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2022\\\/11\\\/cropped-il-corriere-della-provincia-testata-web-scontornata.png\",\"contentUrl\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2022\\\/11\\\/cropped-il-corriere-della-provincia-testata-web-scontornata.png\",\"width\":2911,\"height\":717,\"caption\":\"Globalpress s.r.l.\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Al Festival delle Storie lo sport epico di Piero Trellini, Carlo Pernat e Massimo Calandri - IlCorriereDellaProvincia.it - News h24 e notizie di approfondimento","description":"Un avvio a Broccostella e Gallinaro nel primo giorno di rassegna e grande partecipazione di pubblico ad ogni appuntamento, per qualsiasi evento","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2019\/08\/26\/al-festival-delle-storie-lo-sport-epico-di-piero-trellini-carlo-pernat-e-massimo-calandri\/","og_locale":"it_IT","og_type":"article","og_title":"Al Festival delle Storie lo sport epico di Piero Trellini, Carlo Pernat e Massimo Calandri","og_description":"Un avvio a Broccostella e Gallinaro nel primo giorno di rassegna e grande partecipazione di pubblico ad ogni appuntamento, per qualsiasi evento","og_url":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2019\/08\/26\/al-festival-delle-storie-lo-sport-epico-di-piero-trellini-carlo-pernat-e-massimo-calandri\/","og_site_name":"IlCorriereDellaProvincia.it - News h24 e notizie di approfondimento","article_author":"www.facebook.com\/tunews24","article_published_time":"2019-08-26T15:27:21+00:00","article_modified_time":"2019-08-26T15:41:59+00:00","og_image":[{"width":720,"height":479,"url":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2019\/08\/festival-storie.jpg","type":"image\/jpeg"}],"author":"Redazione","twitter_card":"summary_large_image","twitter_misc":{"Scritto da":"Redazione","Tempo di lettura stimato":"2 minuti"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2019\/08\/26\/al-festival-delle-storie-lo-sport-epico-di-piero-trellini-carlo-pernat-e-massimo-calandri\/#article","isPartOf":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2019\/08\/26\/al-festival-delle-storie-lo-sport-epico-di-piero-trellini-carlo-pernat-e-massimo-calandri\/"},"author":{"name":"Redazione","@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/#\/schema\/person\/6d7f0a9120d0c03d0c552e9fdf49ed7d"},"headline":"Al Festival delle Storie lo sport epico di Piero Trellini, Carlo Pernat e Massimo Calandri","datePublished":"2019-08-26T15:27:21+00:00","dateModified":"2019-08-26T15:41:59+00:00","mainEntityOfPage":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2019\/08\/26\/al-festival-delle-storie-lo-sport-epico-di-piero-trellini-carlo-pernat-e-massimo-calandri\/"},"wordCount":505,"commentCount":0,"publisher":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/#organization"},"image":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2019\/08\/26\/al-festival-delle-storie-lo-sport-epico-di-piero-trellini-carlo-pernat-e-massimo-calandri\/#primaryimage"},"thumbnailUrl":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2019\/08\/festival-storie.jpg","keywords":["festival delle storie","san donato val di comino","Val di Comino","vittorio macioce"],"articleSection":["*PRIMO PIANO*","Cultura e Spettacolo","News"],"inLanguage":"it-IT","copyrightYear":"2019","copyrightHolder":{"@id":"https:\/\/www.tunews24.it\/#organization"}},{"@type":"WebPage","@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2019\/08\/26\/al-festival-delle-storie-lo-sport-epico-di-piero-trellini-carlo-pernat-e-massimo-calandri\/","url":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2019\/08\/26\/al-festival-delle-storie-lo-sport-epico-di-piero-trellini-carlo-pernat-e-massimo-calandri\/","name":"Al Festival delle Storie lo sport epico di Piero Trellini, Carlo Pernat e Massimo Calandri - IlCorriereDellaProvincia.it - News h24 e notizie di approfondimento","isPartOf":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2019\/08\/26\/al-festival-delle-storie-lo-sport-epico-di-piero-trellini-carlo-pernat-e-massimo-calandri\/#primaryimage"},"image":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2019\/08\/26\/al-festival-delle-storie-lo-sport-epico-di-piero-trellini-carlo-pernat-e-massimo-calandri\/#primaryimage"},"thumbnailUrl":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2019\/08\/festival-storie.jpg","datePublished":"2019-08-26T15:27:21+00:00","dateModified":"2019-08-26T15:41:59+00:00","description":"Un avvio a Broccostella e Gallinaro nel primo giorno di rassegna e grande partecipazione di pubblico ad ogni appuntamento, per qualsiasi evento","breadcrumb":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2019\/08\/26\/al-festival-delle-storie-lo-sport-epico-di-piero-trellini-carlo-pernat-e-massimo-calandri\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2019\/08\/26\/al-festival-delle-storie-lo-sport-epico-di-piero-trellini-carlo-pernat-e-massimo-calandri\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2019\/08\/26\/al-festival-delle-storie-lo-sport-epico-di-piero-trellini-carlo-pernat-e-massimo-calandri\/#primaryimage","url":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2019\/08\/festival-storie.jpg","contentUrl":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2019\/08\/festival-storie.jpg","width":720,"height":479,"caption":"festival storie il corriere della provincia"},{"@type":"BreadcrumbList","@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2019\/08\/26\/al-festival-delle-storie-lo-sport-epico-di-piero-trellini-carlo-pernat-e-massimo-calandri\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/"},{"@type":"ListItem","position":2,"name":"Al Festival delle Storie lo sport epico di Piero Trellini, Carlo Pernat e Massimo Calandri"}]},{"@type":"WebSite","@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/#website","url":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/","name":"Il Corriere Delle Provincia","description":"IlCorriereDellaProvincia.it, quotidiano web di politica, cronaca, inchiesta, lavoro, scuola, turismo, cultura e spettacolo, economia e finanza, salute e benessere. Approfondimenti e notizie aggiornate con foto e video della provincia di Frosinone ma anche news nazionali, dell\u2019Italia e del Mondo.","publisher":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":["Organization","Place"],"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/#organization","name":"Globalpress s.r.l.","url":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/","logo":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2019\/08\/26\/al-festival-delle-storie-lo-sport-epico-di-piero-trellini-carlo-pernat-e-massimo-calandri\/#local-main-organization-logo"},"image":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2019\/08\/26\/al-festival-delle-storie-lo-sport-epico-di-piero-trellini-carlo-pernat-e-massimo-calandri\/#local-main-organization-logo"},"telephone":[],"openingHoursSpecification":[{"@type":"OpeningHoursSpecification","dayOfWeek":["Monday","Tuesday","Wednesday","Thursday","Friday","Saturday","Sunday"],"opens":"09:00","closes":"17:00"}]},{"@type":"Person","@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/#\/schema\/person\/6d7f0a9120d0c03d0c552e9fdf49ed7d","name":"Redazione","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/secure.gravatar.com\/avatar\/a40eeacccdcad861f831dde73317f63a542e738f0dc4b79b9f47062d3d4bd1d2?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/a40eeacccdcad861f831dde73317f63a542e738f0dc4b79b9f47062d3d4bd1d2?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/a40eeacccdcad861f831dde73317f63a542e738f0dc4b79b9f47062d3d4bd1d2?s=96&d=mm&r=g","caption":"Redazione"},"description":"SEGUICI ANCHE SUI SOCIAL Facebook: TuNews24 e TuSport24 Instagram: TuNews24 e TuSport24 Youtube: TuNews24 Telegram: TuNews24 Puoi leggerci anche in formato cartaceo: il settimanale viene pubblicato e distribuito gratuitamente ogni venerd\u00ec in edicole, bar, centri commerciali e svariati esercizi. Ma \u00e8 possibile anche sfogliarlo comodamente online, cliccando su TU NEWS sfogliabile TU NEWS, PASSIONE PER L\u2019INFORMAZIONE","sameAs":["http:\/\/www.tunews24.it","www.facebook.com\/tunews24"],"url":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/author\/senzafirma\/"},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2019\/08\/26\/al-festival-delle-storie-lo-sport-epico-di-piero-trellini-carlo-pernat-e-massimo-calandri\/#local-main-organization-logo","url":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2022\/11\/cropped-il-corriere-della-provincia-testata-web-scontornata.png","contentUrl":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2022\/11\/cropped-il-corriere-della-provincia-testata-web-scontornata.png","width":2911,"height":717,"caption":"Globalpress s.r.l."}]}},"_links":{"self":[{"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/posts\/17132","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/users\/18"}],"replies":[{"embeddable":true,"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/comments?post=17132"}],"version-history":[{"count":4,"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/posts\/17132\/revisions"}],"predecessor-version":[{"id":17140,"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/posts\/17132\/revisions\/17140"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/media\/17134"}],"wp:attachment":[{"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/media?parent=17132"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/categories?post=17132"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/tags?post=17132"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}