{"id":16762,"date":"2019-08-14T15:38:47","date_gmt":"2019-08-14T13:38:47","guid":{"rendered":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/?p=16762"},"modified":"2019-08-15T08:59:19","modified_gmt":"2019-08-15T06:59:19","slug":"aggredita-dallex-convivente-che-voleva-sottrarle-le-chiavi-di-casa","status":"publish","type":"post","link":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2019\/08\/14\/aggredita-dallex-convivente-che-voleva-sottrarle-le-chiavi-di-casa\/","title":{"rendered":"Aggredita dall&#8217;ex convivente per le chiavi di casa"},"content":{"rendered":"<p>Una storia di violenza che arriva da<strong> Piglio<\/strong>, dove un <strong>cinquantunenne<\/strong> \u00e8 stato denunciato per aver <strong>aggredito la sua ex convivente<\/strong> alla quale aveva strappato la borsa.<\/p>\n<p>A intervenire, questa mattina, sono stati i carabinieri della stazione di Piglio che, a conclusione di un&#8217;indagine scaturita dalla <strong>denuncia-querela di una donna albanese di 51 anni<\/strong>, ne hanno denunciato l&#8217;ex convivente.<\/p>\n<p>Secondo le accuse della donna, poi verificate dai militari, l&#8217;uomo si \u00e8 reso responsabile dei reati di violenza privata e lesioni personali. Il 12 agosto scorso, mentre <strong>la donna si trovava all\u2019interno dell\u2019abitazione popolare<\/strong> assegnata a figli di entrambi, \u00e8 stata aggredita dall\u2019ex convivente, che le aveva sottratto la borsa per impossessarsi delle chiavi di casa.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Una storia di violenza che arriva da Piglio, dove un cinquantunenne \u00e8 stato denunciato per aver aggredito la sua ex<\/p>\n","protected":false},"author":18,"featured_media":10511,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[4,2],"tags":[1576,814,90,5787,5786,298,494,598],"class_list":["post-16762","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-primo-piano","category-cronaca","tag-aggressione","tag-alloggio-popolare","tag-carabinieri","tag-chiavi","tag-ex-convivente","tag-lesioni","tag-piglio","tag-violenza"],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v27.8 (Yoast SEO v27.8) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Aggredita dall&#039;ex convivente per le chiavi di casa - IlCorriereDellaProvincia.it - News h24 e notizie di approfondimento<\/title>\n<meta name=\"description\" content=\"Un cinquantunenne \u00e8 stato denunciato dopo che la sua ex convivente ha raccontato ai carabinieri di essere stata aggredita per un mazzo di chiavi\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2019\/08\/14\/aggredita-dallex-convivente-che-voleva-sottrarle-le-chiavi-di-casa\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Aggredita dall&#039;ex convivente per le chiavi di casa\" \/>\n<meta property=\"og:description\" content=\"Un cinquantunenne \u00e8 stato denunciato dopo che la sua ex convivente ha raccontato ai carabinieri di essere stata aggredita per un mazzo di chiavi\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2019\/08\/14\/aggredita-dallex-convivente-che-voleva-sottrarle-le-chiavi-di-casa\/\" \/>\n<meta property=\"og:site_name\" content=\"IlCorriereDellaProvincia.it - News h24 e notizie di approfondimento\" \/>\n<meta property=\"article:author\" content=\"www.facebook.com\/tunews24\" \/>\n<meta property=\"article:published_time\" content=\"2019-08-14T13:38:47+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2019-08-15T06:59:19+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2019\/04\/violenza-donna-e1556276413914.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"632\" \/>\n\t<meta property=\"og:image:height\" content=\"347\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Redazione\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"Redazione\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2019\\\/08\\\/14\\\/aggredita-dallex-convivente-che-voleva-sottrarle-le-chiavi-di-casa\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2019\\\/08\\\/14\\\/aggredita-dallex-convivente-che-voleva-sottrarle-le-chiavi-di-casa\\\/\"},\"author\":{\"name\":\"Redazione\",\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/#\\\/schema\\\/person\\\/6d7f0a9120d0c03d0c552e9fdf49ed7d\"},\"headline\":\"Aggredita dall&#8217;ex convivente per le chiavi di casa\",\"datePublished\":\"2019-08-14T13:38:47+00:00\",\"dateModified\":\"2019-08-15T06:59:19+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2019\\\/08\\\/14\\\/aggredita-dallex-convivente-che-voleva-sottrarle-le-chiavi-di-casa\\\/\"},\"wordCount\":125,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2019\\\/08\\\/14\\\/aggredita-dallex-convivente-che-voleva-sottrarle-le-chiavi-di-casa\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2019\\\/04\\\/violenza-donna-e1556276413914.jpg\",\"keywords\":[\"aggressione\",\"alloggio popolare\",\"carabinieri\",\"chiavi\",\"ex convivente\",\"lesioni\",\"piglio\",\"violenza\"],\"articleSection\":[\"*PRIMO PIANO*\",\"Cronaca\"],\"inLanguage\":\"it-IT\",\"copyrightYear\":\"2019\",\"copyrightHolder\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/#organization\"}},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2019\\\/08\\\/14\\\/aggredita-dallex-convivente-che-voleva-sottrarle-le-chiavi-di-casa\\\/\",\"url\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2019\\\/08\\\/14\\\/aggredita-dallex-convivente-che-voleva-sottrarle-le-chiavi-di-casa\\\/\",\"name\":\"Aggredita dall'ex convivente per le chiavi di casa - IlCorriereDellaProvincia.it - News h24 e notizie di approfondimento\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2019\\\/08\\\/14\\\/aggredita-dallex-convivente-che-voleva-sottrarle-le-chiavi-di-casa\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2019\\\/08\\\/14\\\/aggredita-dallex-convivente-che-voleva-sottrarle-le-chiavi-di-casa\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2019\\\/04\\\/violenza-donna-e1556276413914.jpg\",\"datePublished\":\"2019-08-14T13:38:47+00:00\",\"dateModified\":\"2019-08-15T06:59:19+00:00\",\"description\":\"Un cinquantunenne \u00e8 stato denunciato dopo che la sua ex convivente ha raccontato ai carabinieri di essere stata aggredita per un mazzo di chiavi\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2019\\\/08\\\/14\\\/aggredita-dallex-convivente-che-voleva-sottrarle-le-chiavi-di-casa\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2019\\\/08\\\/14\\\/aggredita-dallex-convivente-che-voleva-sottrarle-le-chiavi-di-casa\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2019\\\/08\\\/14\\\/aggredita-dallex-convivente-che-voleva-sottrarle-le-chiavi-di-casa\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2019\\\/04\\\/violenza-donna-e1556276413914.jpg\",\"contentUrl\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2019\\\/04\\\/violenza-donna-e1556276413914.jpg\",\"width\":632,\"height\":347,\"caption\":\"Violenza sulla donna\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2019\\\/08\\\/14\\\/aggredita-dallex-convivente-che-voleva-sottrarle-le-chiavi-di-casa\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Aggredita dall&#8217;ex convivente per le chiavi di casa\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/#website\",\"url\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/\",\"name\":\"Il Corriere Delle Provincia\",\"description\":\"IlCorriereDellaProvincia.it, quotidiano web di politica, cronaca, inchiesta, lavoro, scuola, turismo, cultura e spettacolo, economia e finanza, salute e benessere. Approfondimenti e notizie aggiornate con foto e video della provincia di Frosinone ma anche news nazionali, dell\u2019Italia e del Mondo.\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":[\"Organization\",\"Place\"],\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/#organization\",\"name\":\"Globalpress s.r.l.\",\"url\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/\",\"logo\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2019\\\/08\\\/14\\\/aggredita-dallex-convivente-che-voleva-sottrarle-le-chiavi-di-casa\\\/#local-main-organization-logo\"},\"image\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2019\\\/08\\\/14\\\/aggredita-dallex-convivente-che-voleva-sottrarle-le-chiavi-di-casa\\\/#local-main-organization-logo\"},\"telephone\":[],\"openingHoursSpecification\":[{\"@type\":\"OpeningHoursSpecification\",\"dayOfWeek\":[\"Monday\",\"Tuesday\",\"Wednesday\",\"Thursday\",\"Friday\",\"Saturday\",\"Sunday\"],\"opens\":\"09:00\",\"closes\":\"17:00\"}]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/#\\\/schema\\\/person\\\/6d7f0a9120d0c03d0c552e9fdf49ed7d\",\"name\":\"Redazione\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/a40eeacccdcad861f831dde73317f63a542e738f0dc4b79b9f47062d3d4bd1d2?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/a40eeacccdcad861f831dde73317f63a542e738f0dc4b79b9f47062d3d4bd1d2?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/a40eeacccdcad861f831dde73317f63a542e738f0dc4b79b9f47062d3d4bd1d2?s=96&d=mm&r=g\",\"caption\":\"Redazione\"},\"description\":\"SEGUICI ANCHE SUI SOCIAL Facebook: TuNews24 e TuSport24 Instagram: TuNews24 e TuSport24 Youtube: TuNews24 Telegram: TuNews24 Puoi leggerci anche in formato cartaceo: il settimanale viene pubblicato e distribuito gratuitamente ogni venerd\u00ec in edicole, bar, centri commerciali e svariati esercizi. Ma \u00e8 possibile anche sfogliarlo comodamente online, cliccando su TU NEWS sfogliabile TU NEWS, PASSIONE PER L\u2019INFORMAZIONE\",\"sameAs\":[\"http:\\\/\\\/www.tunews24.it\",\"www.facebook.com\\\/tunews24\"],\"url\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/author\\\/senzafirma\\\/\"},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2019\\\/08\\\/14\\\/aggredita-dallex-convivente-che-voleva-sottrarle-le-chiavi-di-casa\\\/#local-main-organization-logo\",\"url\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2022\\\/11\\\/cropped-il-corriere-della-provincia-testata-web-scontornata.png\",\"contentUrl\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2022\\\/11\\\/cropped-il-corriere-della-provincia-testata-web-scontornata.png\",\"width\":2911,\"height\":717,\"caption\":\"Globalpress s.r.l.\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Aggredita dall'ex convivente per le chiavi di casa - IlCorriereDellaProvincia.it - News h24 e notizie di approfondimento","description":"Un cinquantunenne \u00e8 stato denunciato dopo che la sua ex convivente ha raccontato ai carabinieri di essere stata aggredita per un mazzo di chiavi","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2019\/08\/14\/aggredita-dallex-convivente-che-voleva-sottrarle-le-chiavi-di-casa\/","og_locale":"it_IT","og_type":"article","og_title":"Aggredita dall'ex convivente per le chiavi di casa","og_description":"Un cinquantunenne \u00e8 stato denunciato dopo che la sua ex convivente ha raccontato ai carabinieri di essere stata aggredita per un mazzo di chiavi","og_url":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2019\/08\/14\/aggredita-dallex-convivente-che-voleva-sottrarle-le-chiavi-di-casa\/","og_site_name":"IlCorriereDellaProvincia.it - News h24 e notizie di approfondimento","article_author":"www.facebook.com\/tunews24","article_published_time":"2019-08-14T13:38:47+00:00","article_modified_time":"2019-08-15T06:59:19+00:00","og_image":[{"width":632,"height":347,"url":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2019\/04\/violenza-donna-e1556276413914.jpg","type":"image\/jpeg"}],"author":"Redazione","twitter_card":"summary_large_image","twitter_misc":{"Scritto da":"Redazione","Tempo di lettura stimato":"1 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2019\/08\/14\/aggredita-dallex-convivente-che-voleva-sottrarle-le-chiavi-di-casa\/#article","isPartOf":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2019\/08\/14\/aggredita-dallex-convivente-che-voleva-sottrarle-le-chiavi-di-casa\/"},"author":{"name":"Redazione","@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/#\/schema\/person\/6d7f0a9120d0c03d0c552e9fdf49ed7d"},"headline":"Aggredita dall&#8217;ex convivente per le chiavi di casa","datePublished":"2019-08-14T13:38:47+00:00","dateModified":"2019-08-15T06:59:19+00:00","mainEntityOfPage":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2019\/08\/14\/aggredita-dallex-convivente-che-voleva-sottrarle-le-chiavi-di-casa\/"},"wordCount":125,"commentCount":0,"publisher":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/#organization"},"image":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2019\/08\/14\/aggredita-dallex-convivente-che-voleva-sottrarle-le-chiavi-di-casa\/#primaryimage"},"thumbnailUrl":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2019\/04\/violenza-donna-e1556276413914.jpg","keywords":["aggressione","alloggio popolare","carabinieri","chiavi","ex convivente","lesioni","piglio","violenza"],"articleSection":["*PRIMO PIANO*","Cronaca"],"inLanguage":"it-IT","copyrightYear":"2019","copyrightHolder":{"@id":"https:\/\/www.tunews24.it\/#organization"}},{"@type":"WebPage","@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2019\/08\/14\/aggredita-dallex-convivente-che-voleva-sottrarle-le-chiavi-di-casa\/","url":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2019\/08\/14\/aggredita-dallex-convivente-che-voleva-sottrarle-le-chiavi-di-casa\/","name":"Aggredita dall'ex convivente per le chiavi di casa - IlCorriereDellaProvincia.it - News h24 e notizie di approfondimento","isPartOf":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2019\/08\/14\/aggredita-dallex-convivente-che-voleva-sottrarle-le-chiavi-di-casa\/#primaryimage"},"image":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2019\/08\/14\/aggredita-dallex-convivente-che-voleva-sottrarle-le-chiavi-di-casa\/#primaryimage"},"thumbnailUrl":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2019\/04\/violenza-donna-e1556276413914.jpg","datePublished":"2019-08-14T13:38:47+00:00","dateModified":"2019-08-15T06:59:19+00:00","description":"Un cinquantunenne \u00e8 stato denunciato dopo che la sua ex convivente ha raccontato ai carabinieri di essere stata aggredita per un mazzo di chiavi","breadcrumb":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2019\/08\/14\/aggredita-dallex-convivente-che-voleva-sottrarle-le-chiavi-di-casa\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2019\/08\/14\/aggredita-dallex-convivente-che-voleva-sottrarle-le-chiavi-di-casa\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2019\/08\/14\/aggredita-dallex-convivente-che-voleva-sottrarle-le-chiavi-di-casa\/#primaryimage","url":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2019\/04\/violenza-donna-e1556276413914.jpg","contentUrl":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2019\/04\/violenza-donna-e1556276413914.jpg","width":632,"height":347,"caption":"Violenza sulla donna"},{"@type":"BreadcrumbList","@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2019\/08\/14\/aggredita-dallex-convivente-che-voleva-sottrarle-le-chiavi-di-casa\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/"},{"@type":"ListItem","position":2,"name":"Aggredita dall&#8217;ex convivente per le chiavi di casa"}]},{"@type":"WebSite","@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/#website","url":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/","name":"Il Corriere Delle Provincia","description":"IlCorriereDellaProvincia.it, quotidiano web di politica, cronaca, inchiesta, lavoro, scuola, turismo, cultura e spettacolo, economia e finanza, salute e benessere. Approfondimenti e notizie aggiornate con foto e video della provincia di Frosinone ma anche news nazionali, dell\u2019Italia e del Mondo.","publisher":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":["Organization","Place"],"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/#organization","name":"Globalpress s.r.l.","url":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/","logo":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2019\/08\/14\/aggredita-dallex-convivente-che-voleva-sottrarle-le-chiavi-di-casa\/#local-main-organization-logo"},"image":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2019\/08\/14\/aggredita-dallex-convivente-che-voleva-sottrarle-le-chiavi-di-casa\/#local-main-organization-logo"},"telephone":[],"openingHoursSpecification":[{"@type":"OpeningHoursSpecification","dayOfWeek":["Monday","Tuesday","Wednesday","Thursday","Friday","Saturday","Sunday"],"opens":"09:00","closes":"17:00"}]},{"@type":"Person","@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/#\/schema\/person\/6d7f0a9120d0c03d0c552e9fdf49ed7d","name":"Redazione","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/secure.gravatar.com\/avatar\/a40eeacccdcad861f831dde73317f63a542e738f0dc4b79b9f47062d3d4bd1d2?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/a40eeacccdcad861f831dde73317f63a542e738f0dc4b79b9f47062d3d4bd1d2?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/a40eeacccdcad861f831dde73317f63a542e738f0dc4b79b9f47062d3d4bd1d2?s=96&d=mm&r=g","caption":"Redazione"},"description":"SEGUICI ANCHE SUI SOCIAL Facebook: TuNews24 e TuSport24 Instagram: TuNews24 e TuSport24 Youtube: TuNews24 Telegram: TuNews24 Puoi leggerci anche in formato cartaceo: il settimanale viene pubblicato e distribuito gratuitamente ogni venerd\u00ec in edicole, bar, centri commerciali e svariati esercizi. Ma \u00e8 possibile anche sfogliarlo comodamente online, cliccando su TU NEWS sfogliabile TU NEWS, PASSIONE PER L\u2019INFORMAZIONE","sameAs":["http:\/\/www.tunews24.it","www.facebook.com\/tunews24"],"url":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/author\/senzafirma\/"},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2019\/08\/14\/aggredita-dallex-convivente-che-voleva-sottrarle-le-chiavi-di-casa\/#local-main-organization-logo","url":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2022\/11\/cropped-il-corriere-della-provincia-testata-web-scontornata.png","contentUrl":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2022\/11\/cropped-il-corriere-della-provincia-testata-web-scontornata.png","width":2911,"height":717,"caption":"Globalpress s.r.l."}]}},"_links":{"self":[{"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/posts\/16762","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/users\/18"}],"replies":[{"embeddable":true,"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/comments?post=16762"}],"version-history":[{"count":3,"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/posts\/16762\/revisions"}],"predecessor-version":[{"id":16765,"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/posts\/16762\/revisions\/16765"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/media\/10511"}],"wp:attachment":[{"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/media?parent=16762"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/categories?post=16762"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/tags?post=16762"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}