{"id":16034,"date":"2019-07-29T09:00:34","date_gmt":"2019-07-29T07:00:34","guid":{"rendered":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/?p=16034"},"modified":"2019-07-28T22:42:16","modified_gmt":"2019-07-28T20:42:16","slug":"fontana-liri-ca-2019-con-le-stelle-maria-luigia-borsi-e-petra-conti","status":"publish","type":"post","link":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2019\/07\/29\/fontana-liri-ca-2019-con-le-stelle-maria-luigia-borsi-e-petra-conti\/","title":{"rendered":"Fontana Liri&#8230;Ca 2019 con le stelle Maria Luigia Borsi e Petra Conti"},"content":{"rendered":"<p>Torna il <strong>prossimo 31 luglio<\/strong> l&#8217;evento estivo di <strong>Fontana Liri&#8230;Ca &#8211; Note verso il cielo 2019<\/strong>, giunto ormai alla XIII edizione ed eccezionalmente inserito quest&#8217;anno nelle serate dei festeggiamenti di Maria SS di Loreto.<\/p>\n<p>La suggestiva piazzetta di Fontana Liri Superiore &#8211; ormai familiare a molti melomani e appassionati della bella musica e del bel canto grazie al formidabile intuito e alla passione che anima il <strong>direttore artistico dell&#8217;evento Moreno Bianchi<\/strong> &#8211; si trasformer\u00e0 per una sera in un prestigioso palcoscenico dove torneranno ad esibirsi alcuni artisti del gotha della musica internazionale.<\/p>\n<h2>I protagonisti<\/h2>\n<p>Oltre all&#8217;inconfondibile voce del <strong>soprano Maria Luigia Borsi<\/strong>, presente dalla prima edizione e perno attorno a cui \u00e8 costruito l&#8217;evento, potremo ascoltare il <strong>celebre tenore Salvatore Cordella<\/strong> che, al pari di Maria Luigia, si \u00e8 esibito per le pi\u00f9 grandi istituzioni musicali del mondo.<\/p>\n<p>&nbsp;<\/p>\n<figure id=\"attachment_16035\" aria-describedby=\"caption-attachment-16035\" style=\"width: 400px\" class=\"wp-caption aligncenter\"><img loading=\"lazy\" decoding=\"async\" class=\"wp-image-16035 size-full\" src=\"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2019\/07\/maria-luigia-borsi.jpg\" alt=\"soprano maria luigia borsi il corriere della provincia\" width=\"400\" height=\"400\" srcset=\"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2019\/07\/maria-luigia-borsi.jpg 400w, https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2019\/07\/maria-luigia-borsi-150x150.jpg 150w, https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2019\/07\/maria-luigia-borsi-300x300.jpg 300w\" sizes=\"auto, (max-width: 400px) 100vw, 400px\" \/><figcaption id=\"caption-attachment-16035\" class=\"wp-caption-text\">Il soprano Maria Luigia Borsi<\/figcaption><\/figure>\n<p>&nbsp;<\/p>\n<p>Questa edizione riserva un&#8217;eccezionale sorpresa: ospite della serata sar\u00e0 <strong>l&#8217;\u00e9toile della danza Petra Conti<\/strong>. Dal 2014 ambasciatrice della danza italiana nel mondo, Petra ha danzato in tutti i pi\u00f9 importanti teatri del globo.<\/p>\n<p>La nota ballerina di origini ciociare e residente a Los Angeles &#8211; in questi giorni a Verona per la stagione estiva dell&#8217;Arena, impegnata nei ballabili delle due opere verdiane di punta del 2019, Aida e La Traviata &#8211; volentieri ha accettato l&#8217;invito del Direttore Artistico per avere la soddisfazione di esibirsi nella sua terra natale.<\/p>\n<p>&nbsp;<\/p>\n<figure id=\"attachment_16036\" aria-describedby=\"caption-attachment-16036\" style=\"width: 416px\" class=\"wp-caption aligncenter\"><img loading=\"lazy\" decoding=\"async\" class=\"wp-image-16036 size-full\" src=\"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2019\/07\/petra-conti.jpg\" alt=\"petra conti fontana liri il corriere della provincia\" width=\"416\" height=\"400\" srcset=\"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2019\/07\/petra-conti.jpg 416w, https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2019\/07\/petra-conti-300x288.jpg 300w\" sizes=\"auto, (max-width: 416px) 100vw, 416px\" \/><figcaption id=\"caption-attachment-16036\" class=\"wp-caption-text\">L&#8217;etoile Petra Conti<\/figcaption><\/figure>\n<p>&nbsp;<\/p>\n<h2>Tanti gli ospiti in cartellone<\/h2>\n<p>Non mancher\u00e0 il <strong>Duo Baldo &#8211; il violinista Brad Repp e il pianista Aldo Gentileschi<\/strong> &#8211; la virtuosissima coppia musicale capace di catturare l&#8217;attenzione di tutto il pubblico con il loro approccio &#8216;divertito e divertente&#8217; alla musica. Interverranno, inoltre, due giovani promesse della lirica, il <strong>soprano Miriam Cicotti<\/strong> e il <strong>tenore Paride Cataldo<\/strong>. Direttamente da Rai Due, ospite fisso della trasmissione &#8216;Detto Fatto&#8217;, con un&#8217;incursione nel repertorio della musica napoletana, salir\u00e0 sul sagrato-palco del festival il pizzaiolo-cantante <strong>Gianfranco Iervolino<\/strong>.<\/p>\n<p>Il programma prevede, infine, il contributo del Coro polifonico Collegium Musicum Vox Angeli, diretto dal <strong>maestro Fabio Pantanella<\/strong>, alla terza collaborazione con Fontana Liri&#8230;Ca.<\/p>\n<p>Il maestro accompagnatore dei cantanti sar\u00e0 il pianista\/compositore <strong>Stefano Teani<\/strong>, tra l&#8217;altro maestro collaboratore del maestro Riccardo Muti.<\/p>\n<p>Una serata di grande musica con grandi artisti per un appuntamento da non perdere.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Torna il prossimo 31 luglio l&#8217;evento estivo di Fontana Liri&#8230;Ca &#8211; Note verso il cielo 2019, giunto ormai alla XIII<\/p>\n","protected":false},"author":18,"featured_media":16037,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[4,14],"tags":[823,1487,1394,5609,1393,5608],"class_list":["post-16034","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-primo-piano","category-cultura","tag-fontana-liri","tag-lirica","tag-maria-luigia-borsi","tag-petra-conti","tag-soprano","tag-tenore"],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v27.8 (Yoast SEO v27.8) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Fontana Liri...Ca 2019 con le stelle Maria Luigia Borsi e Petra Conti - IlCorriereDellaProvincia.it - News h24 e notizie di approfondimento<\/title>\n<meta name=\"description\" content=\"Torna il prossimo 31 luglio l&#039;evento estivo di Fontana Liri...Ca - Note verso il cielo 2019, giunto ormai alla XIII edizione. Tanti i protagonisti\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2019\/07\/29\/fontana-liri-ca-2019-con-le-stelle-maria-luigia-borsi-e-petra-conti\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Fontana Liri...Ca 2019 con le stelle Maria Luigia Borsi e Petra Conti\" \/>\n<meta property=\"og:description\" content=\"Torna il prossimo 31 luglio l&#039;evento estivo di Fontana Liri...Ca - Note verso il cielo 2019, giunto ormai alla XIII edizione. Tanti i protagonisti\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2019\/07\/29\/fontana-liri-ca-2019-con-le-stelle-maria-luigia-borsi-e-petra-conti\/\" \/>\n<meta property=\"og:site_name\" content=\"IlCorriereDellaProvincia.it - News h24 e notizie di approfondimento\" \/>\n<meta property=\"article:author\" content=\"www.facebook.com\/tunews24\" \/>\n<meta property=\"article:published_time\" content=\"2019-07-29T07:00:34+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2019\/07\/maria-luigia-borsi-1-e1564346470555.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"632\" \/>\n\t<meta property=\"og:image:height\" content=\"399\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Redazione\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"Redazione\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minuti\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2019\\\/07\\\/29\\\/fontana-liri-ca-2019-con-le-stelle-maria-luigia-borsi-e-petra-conti\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2019\\\/07\\\/29\\\/fontana-liri-ca-2019-con-le-stelle-maria-luigia-borsi-e-petra-conti\\\/\"},\"author\":{\"name\":\"Redazione\",\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/#\\\/schema\\\/person\\\/6d7f0a9120d0c03d0c552e9fdf49ed7d\"},\"headline\":\"Fontana Liri&#8230;Ca 2019 con le stelle Maria Luigia Borsi e Petra Conti\",\"datePublished\":\"2019-07-29T07:00:34+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2019\\\/07\\\/29\\\/fontana-liri-ca-2019-con-le-stelle-maria-luigia-borsi-e-petra-conti\\\/\"},\"wordCount\":414,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2019\\\/07\\\/29\\\/fontana-liri-ca-2019-con-le-stelle-maria-luigia-borsi-e-petra-conti\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2019\\\/07\\\/maria-luigia-borsi-1-e1564346470555.jpg\",\"keywords\":[\"Fontana Liri\",\"lirica\",\"maria luigia borsi\",\"petra conti\",\"soprano\",\"tenore\"],\"articleSection\":[\"*PRIMO PIANO*\",\"Cultura e Spettacolo\"],\"inLanguage\":\"it-IT\",\"copyrightYear\":\"2019\",\"copyrightHolder\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/#organization\"}},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2019\\\/07\\\/29\\\/fontana-liri-ca-2019-con-le-stelle-maria-luigia-borsi-e-petra-conti\\\/\",\"url\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2019\\\/07\\\/29\\\/fontana-liri-ca-2019-con-le-stelle-maria-luigia-borsi-e-petra-conti\\\/\",\"name\":\"Fontana Liri...Ca 2019 con le stelle Maria Luigia Borsi e Petra Conti - IlCorriereDellaProvincia.it - News h24 e notizie di approfondimento\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2019\\\/07\\\/29\\\/fontana-liri-ca-2019-con-le-stelle-maria-luigia-borsi-e-petra-conti\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2019\\\/07\\\/29\\\/fontana-liri-ca-2019-con-le-stelle-maria-luigia-borsi-e-petra-conti\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2019\\\/07\\\/maria-luigia-borsi-1-e1564346470555.jpg\",\"datePublished\":\"2019-07-29T07:00:34+00:00\",\"description\":\"Torna il prossimo 31 luglio l'evento estivo di Fontana Liri...Ca - Note verso il cielo 2019, giunto ormai alla XIII edizione. Tanti i protagonisti\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2019\\\/07\\\/29\\\/fontana-liri-ca-2019-con-le-stelle-maria-luigia-borsi-e-petra-conti\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2019\\\/07\\\/29\\\/fontana-liri-ca-2019-con-le-stelle-maria-luigia-borsi-e-petra-conti\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2019\\\/07\\\/29\\\/fontana-liri-ca-2019-con-le-stelle-maria-luigia-borsi-e-petra-conti\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2019\\\/07\\\/maria-luigia-borsi-1-e1564346470555.jpg\",\"contentUrl\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2019\\\/07\\\/maria-luigia-borsi-1-e1564346470555.jpg\",\"width\":632,\"height\":399,\"caption\":\"Il soprano Maria Luigia Borsi\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2019\\\/07\\\/29\\\/fontana-liri-ca-2019-con-le-stelle-maria-luigia-borsi-e-petra-conti\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Fontana Liri&#8230;Ca 2019 con le stelle Maria Luigia Borsi e Petra Conti\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/#website\",\"url\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/\",\"name\":\"Il Corriere Delle Provincia\",\"description\":\"IlCorriereDellaProvincia.it, quotidiano web di politica, cronaca, inchiesta, lavoro, scuola, turismo, cultura e spettacolo, economia e finanza, salute e benessere. Approfondimenti e notizie aggiornate con foto e video della provincia di Frosinone ma anche news nazionali, dell\u2019Italia e del Mondo.\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":[\"Organization\",\"Place\"],\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/#organization\",\"name\":\"Globalpress s.r.l.\",\"url\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/\",\"logo\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2019\\\/07\\\/29\\\/fontana-liri-ca-2019-con-le-stelle-maria-luigia-borsi-e-petra-conti\\\/#local-main-organization-logo\"},\"image\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2019\\\/07\\\/29\\\/fontana-liri-ca-2019-con-le-stelle-maria-luigia-borsi-e-petra-conti\\\/#local-main-organization-logo\"},\"telephone\":[],\"openingHoursSpecification\":[{\"@type\":\"OpeningHoursSpecification\",\"dayOfWeek\":[\"Monday\",\"Tuesday\",\"Wednesday\",\"Thursday\",\"Friday\",\"Saturday\",\"Sunday\"],\"opens\":\"09:00\",\"closes\":\"17:00\"}]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/#\\\/schema\\\/person\\\/6d7f0a9120d0c03d0c552e9fdf49ed7d\",\"name\":\"Redazione\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/a40eeacccdcad861f831dde73317f63a542e738f0dc4b79b9f47062d3d4bd1d2?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/a40eeacccdcad861f831dde73317f63a542e738f0dc4b79b9f47062d3d4bd1d2?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/a40eeacccdcad861f831dde73317f63a542e738f0dc4b79b9f47062d3d4bd1d2?s=96&d=mm&r=g\",\"caption\":\"Redazione\"},\"description\":\"SEGUICI ANCHE SUI SOCIAL Facebook: TuNews24 e TuSport24 Instagram: TuNews24 e TuSport24 Youtube: TuNews24 Telegram: TuNews24 Puoi leggerci anche in formato cartaceo: il settimanale viene pubblicato e distribuito gratuitamente ogni venerd\u00ec in edicole, bar, centri commerciali e svariati esercizi. Ma \u00e8 possibile anche sfogliarlo comodamente online, cliccando su TU NEWS sfogliabile TU NEWS, PASSIONE PER L\u2019INFORMAZIONE\",\"sameAs\":[\"http:\\\/\\\/www.tunews24.it\",\"www.facebook.com\\\/tunews24\"],\"url\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/author\\\/senzafirma\\\/\"},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2019\\\/07\\\/29\\\/fontana-liri-ca-2019-con-le-stelle-maria-luigia-borsi-e-petra-conti\\\/#local-main-organization-logo\",\"url\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2022\\\/11\\\/cropped-il-corriere-della-provincia-testata-web-scontornata.png\",\"contentUrl\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2022\\\/11\\\/cropped-il-corriere-della-provincia-testata-web-scontornata.png\",\"width\":2911,\"height\":717,\"caption\":\"Globalpress s.r.l.\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Fontana Liri...Ca 2019 con le stelle Maria Luigia Borsi e Petra Conti - IlCorriereDellaProvincia.it - News h24 e notizie di approfondimento","description":"Torna il prossimo 31 luglio l'evento estivo di Fontana Liri...Ca - Note verso il cielo 2019, giunto ormai alla XIII edizione. Tanti i protagonisti","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2019\/07\/29\/fontana-liri-ca-2019-con-le-stelle-maria-luigia-borsi-e-petra-conti\/","og_locale":"it_IT","og_type":"article","og_title":"Fontana Liri...Ca 2019 con le stelle Maria Luigia Borsi e Petra Conti","og_description":"Torna il prossimo 31 luglio l'evento estivo di Fontana Liri...Ca - Note verso il cielo 2019, giunto ormai alla XIII edizione. Tanti i protagonisti","og_url":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2019\/07\/29\/fontana-liri-ca-2019-con-le-stelle-maria-luigia-borsi-e-petra-conti\/","og_site_name":"IlCorriereDellaProvincia.it - News h24 e notizie di approfondimento","article_author":"www.facebook.com\/tunews24","article_published_time":"2019-07-29T07:00:34+00:00","og_image":[{"width":632,"height":399,"url":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2019\/07\/maria-luigia-borsi-1-e1564346470555.jpg","type":"image\/jpeg"}],"author":"Redazione","twitter_card":"summary_large_image","twitter_misc":{"Scritto da":"Redazione","Tempo di lettura stimato":"2 minuti"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2019\/07\/29\/fontana-liri-ca-2019-con-le-stelle-maria-luigia-borsi-e-petra-conti\/#article","isPartOf":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2019\/07\/29\/fontana-liri-ca-2019-con-le-stelle-maria-luigia-borsi-e-petra-conti\/"},"author":{"name":"Redazione","@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/#\/schema\/person\/6d7f0a9120d0c03d0c552e9fdf49ed7d"},"headline":"Fontana Liri&#8230;Ca 2019 con le stelle Maria Luigia Borsi e Petra Conti","datePublished":"2019-07-29T07:00:34+00:00","mainEntityOfPage":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2019\/07\/29\/fontana-liri-ca-2019-con-le-stelle-maria-luigia-borsi-e-petra-conti\/"},"wordCount":414,"commentCount":0,"publisher":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/#organization"},"image":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2019\/07\/29\/fontana-liri-ca-2019-con-le-stelle-maria-luigia-borsi-e-petra-conti\/#primaryimage"},"thumbnailUrl":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2019\/07\/maria-luigia-borsi-1-e1564346470555.jpg","keywords":["Fontana Liri","lirica","maria luigia borsi","petra conti","soprano","tenore"],"articleSection":["*PRIMO PIANO*","Cultura e Spettacolo"],"inLanguage":"it-IT","copyrightYear":"2019","copyrightHolder":{"@id":"https:\/\/www.tunews24.it\/#organization"}},{"@type":"WebPage","@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2019\/07\/29\/fontana-liri-ca-2019-con-le-stelle-maria-luigia-borsi-e-petra-conti\/","url":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2019\/07\/29\/fontana-liri-ca-2019-con-le-stelle-maria-luigia-borsi-e-petra-conti\/","name":"Fontana Liri...Ca 2019 con le stelle Maria Luigia Borsi e Petra Conti - IlCorriereDellaProvincia.it - News h24 e notizie di approfondimento","isPartOf":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2019\/07\/29\/fontana-liri-ca-2019-con-le-stelle-maria-luigia-borsi-e-petra-conti\/#primaryimage"},"image":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2019\/07\/29\/fontana-liri-ca-2019-con-le-stelle-maria-luigia-borsi-e-petra-conti\/#primaryimage"},"thumbnailUrl":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2019\/07\/maria-luigia-borsi-1-e1564346470555.jpg","datePublished":"2019-07-29T07:00:34+00:00","description":"Torna il prossimo 31 luglio l'evento estivo di Fontana Liri...Ca - Note verso il cielo 2019, giunto ormai alla XIII edizione. Tanti i protagonisti","breadcrumb":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2019\/07\/29\/fontana-liri-ca-2019-con-le-stelle-maria-luigia-borsi-e-petra-conti\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2019\/07\/29\/fontana-liri-ca-2019-con-le-stelle-maria-luigia-borsi-e-petra-conti\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2019\/07\/29\/fontana-liri-ca-2019-con-le-stelle-maria-luigia-borsi-e-petra-conti\/#primaryimage","url":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2019\/07\/maria-luigia-borsi-1-e1564346470555.jpg","contentUrl":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2019\/07\/maria-luigia-borsi-1-e1564346470555.jpg","width":632,"height":399,"caption":"Il soprano Maria Luigia Borsi"},{"@type":"BreadcrumbList","@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2019\/07\/29\/fontana-liri-ca-2019-con-le-stelle-maria-luigia-borsi-e-petra-conti\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/"},{"@type":"ListItem","position":2,"name":"Fontana Liri&#8230;Ca 2019 con le stelle Maria Luigia Borsi e Petra Conti"}]},{"@type":"WebSite","@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/#website","url":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/","name":"Il Corriere Delle Provincia","description":"IlCorriereDellaProvincia.it, quotidiano web di politica, cronaca, inchiesta, lavoro, scuola, turismo, cultura e spettacolo, economia e finanza, salute e benessere. Approfondimenti e notizie aggiornate con foto e video della provincia di Frosinone ma anche news nazionali, dell\u2019Italia e del Mondo.","publisher":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":["Organization","Place"],"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/#organization","name":"Globalpress s.r.l.","url":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/","logo":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2019\/07\/29\/fontana-liri-ca-2019-con-le-stelle-maria-luigia-borsi-e-petra-conti\/#local-main-organization-logo"},"image":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2019\/07\/29\/fontana-liri-ca-2019-con-le-stelle-maria-luigia-borsi-e-petra-conti\/#local-main-organization-logo"},"telephone":[],"openingHoursSpecification":[{"@type":"OpeningHoursSpecification","dayOfWeek":["Monday","Tuesday","Wednesday","Thursday","Friday","Saturday","Sunday"],"opens":"09:00","closes":"17:00"}]},{"@type":"Person","@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/#\/schema\/person\/6d7f0a9120d0c03d0c552e9fdf49ed7d","name":"Redazione","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/secure.gravatar.com\/avatar\/a40eeacccdcad861f831dde73317f63a542e738f0dc4b79b9f47062d3d4bd1d2?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/a40eeacccdcad861f831dde73317f63a542e738f0dc4b79b9f47062d3d4bd1d2?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/a40eeacccdcad861f831dde73317f63a542e738f0dc4b79b9f47062d3d4bd1d2?s=96&d=mm&r=g","caption":"Redazione"},"description":"SEGUICI ANCHE SUI SOCIAL Facebook: TuNews24 e TuSport24 Instagram: TuNews24 e TuSport24 Youtube: TuNews24 Telegram: TuNews24 Puoi leggerci anche in formato cartaceo: il settimanale viene pubblicato e distribuito gratuitamente ogni venerd\u00ec in edicole, bar, centri commerciali e svariati esercizi. Ma \u00e8 possibile anche sfogliarlo comodamente online, cliccando su TU NEWS sfogliabile TU NEWS, PASSIONE PER L\u2019INFORMAZIONE","sameAs":["http:\/\/www.tunews24.it","www.facebook.com\/tunews24"],"url":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/author\/senzafirma\/"},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2019\/07\/29\/fontana-liri-ca-2019-con-le-stelle-maria-luigia-borsi-e-petra-conti\/#local-main-organization-logo","url":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2022\/11\/cropped-il-corriere-della-provincia-testata-web-scontornata.png","contentUrl":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2022\/11\/cropped-il-corriere-della-provincia-testata-web-scontornata.png","width":2911,"height":717,"caption":"Globalpress s.r.l."}]}},"_links":{"self":[{"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/posts\/16034","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/users\/18"}],"replies":[{"embeddable":true,"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/comments?post=16034"}],"version-history":[{"count":1,"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/posts\/16034\/revisions"}],"predecessor-version":[{"id":16038,"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/posts\/16034\/revisions\/16038"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/media\/16037"}],"wp:attachment":[{"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/media?parent=16034"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/categories?post=16034"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/tags?post=16034"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}