{"id":15896,"date":"2019-07-26T14:59:02","date_gmt":"2019-07-26T12:59:02","guid":{"rendered":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/?p=15896"},"modified":"2019-07-26T15:00:15","modified_gmt":"2019-07-26T13:00:15","slug":"nomine-dirigenti-asl-ciaccarelli-pessimo-segnale-politico-e-sanitario-dalla-giunta-zingaretti","status":"publish","type":"post","link":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2019\/07\/26\/nomine-dirigenti-asl-ciaccarelli-pessimo-segnale-politico-e-sanitario-dalla-giunta-zingaretti\/","title":{"rendered":"Nomine dirigenti Asl, Ciacciarelli: pessimo segnale politico e sanitario dalla giunta Zingaretti"},"content":{"rendered":"<p><strong>\u201cSulle nomine dei nuovi dirigenti delle Aziende Sanitarie Ospedaliere del Lazio<\/strong>, tra cui quella di Frosinone, il centrosinistra ha dimostrato, ancora una volta, di non riuscire ad assicurare l\u2019assistenza sanitaria sui territori&#8221;.<strong> Cos\u00ec il consigliere regionale del Lazio Pasquale Ciacciarelli<\/strong>, Forza Italia\/Laboratorio Lazio per il Cambiamento.<\/p>\n<h2>L&#8217;affondo<\/h2>\n<p>&#8220;In Commissione Sanit\u00e0 &#8211; fa notare &#8211;<strong> la Giunta Zingaretti \u00e8 andata sotto<\/strong>, confermando di essere una maggioranza senza numeri, un\u2019anatra zoppa. Mi chiedo come si possa pensare a risolvere i problemi della gente con un presidente ormai da mesi latitante, in giro per l\u2019Italia per fare campagna elettorale da segretario del Partito Democratico, ed una maggioranza che sulla carta e nei fatti non esiste&#8221;.<\/p>\n<h2>Situazione critica<\/h2>\n<p>&#8220;Sulle nomine dei manager Asl la Giunta Zingaretti ha lanciato<strong> un segnale bruttissimo<\/strong>, e da un punto di vista politico che sanitario.\u00a0 Sulla sanit\u00e0, in particolare, questo governo regionale ha dimostrato di non aver avuto a cuore le esigenze dei cittadini. E poco importa se il centrosinistra si riempie la bocca con l\u2019uscita dal commissariamento, la situazione in tutta la Regione Lazio resta critica, ed a pagare sono sempre i poveri cittadini, che quotidianamente vivono disagi nei pronto soccorso. Da questi ultimi mi arrivano molto spesso segnalazioni sulle inefficienze del sistema sanitario, in particolare in provincia di Frosinone. Non possono pagare loro per l\u2019incapacit\u00e0 di un\u2019amministrazione regionale!\u201d<\/p>\n","protected":false},"excerpt":{"rendered":"<p>\u201cSulle nomine dei nuovi dirigenti delle Aziende Sanitarie Ospedaliere del Lazio, tra cui quella di Frosinone, il centrosinistra ha dimostrato,<\/p>\n","protected":false},"author":18,"featured_media":15899,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[4,11],"tags":[93,5572,562,107],"class_list":["post-15896","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-primo-piano","category-salute","tag-frosinone","tag-pasquale-ciaciarelli","tag-regione-lazio","tag-sanita"],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v27.8 (Yoast SEO v27.8) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Nomine dirigenti Asl, Ciacciarelli: pessimo segnale politico e sanitario dalla giunta Zingaretti - IlCorriereDellaProvincia.it - News h24 e notizie di approfondimento<\/title>\n<meta name=\"description\" content=\"Il consigliere regionale di Forza Italia critica pesanetemente il governo regionale in tema di sanit\u00e0. Tante le criticit\u00e0 anche nel Frusinate\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2019\/07\/26\/nomine-dirigenti-asl-ciaccarelli-pessimo-segnale-politico-e-sanitario-dalla-giunta-zingaretti\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Nomine dirigenti Asl, Ciacciarelli: pessimo segnale politico e sanitario dalla giunta Zingaretti\" \/>\n<meta property=\"og:description\" content=\"Il consigliere regionale di Forza Italia critica pesanetemente il governo regionale in tema di sanit\u00e0. Tante le criticit\u00e0 anche nel Frusinate\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2019\/07\/26\/nomine-dirigenti-asl-ciaccarelli-pessimo-segnale-politico-e-sanitario-dalla-giunta-zingaretti\/\" \/>\n<meta property=\"og:site_name\" content=\"IlCorriereDellaProvincia.it - News h24 e notizie di approfondimento\" \/>\n<meta property=\"article:author\" content=\"www.facebook.com\/tunews24\" \/>\n<meta property=\"article:published_time\" content=\"2019-07-26T12:59:02+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2019-07-26T13:00:15+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2019\/07\/pasquale-ciacciarelli-consigliere-regionale-il-corriere-della-provincia-e1566288502603.jpeg\" \/>\n\t<meta property=\"og:image:width\" content=\"632\" \/>\n\t<meta property=\"og:image:height\" content=\"414\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Redazione\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"Redazione\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2019\\\/07\\\/26\\\/nomine-dirigenti-asl-ciaccarelli-pessimo-segnale-politico-e-sanitario-dalla-giunta-zingaretti\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2019\\\/07\\\/26\\\/nomine-dirigenti-asl-ciaccarelli-pessimo-segnale-politico-e-sanitario-dalla-giunta-zingaretti\\\/\"},\"author\":{\"name\":\"Redazione\",\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/#\\\/schema\\\/person\\\/6d7f0a9120d0c03d0c552e9fdf49ed7d\"},\"headline\":\"Nomine dirigenti Asl, Ciacciarelli: pessimo segnale politico e sanitario dalla giunta Zingaretti\",\"datePublished\":\"2019-07-26T12:59:02+00:00\",\"dateModified\":\"2019-07-26T13:00:15+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2019\\\/07\\\/26\\\/nomine-dirigenti-asl-ciaccarelli-pessimo-segnale-politico-e-sanitario-dalla-giunta-zingaretti\\\/\"},\"wordCount\":240,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2019\\\/07\\\/26\\\/nomine-dirigenti-asl-ciaccarelli-pessimo-segnale-politico-e-sanitario-dalla-giunta-zingaretti\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2019\\\/07\\\/pasquale-ciacciarelli-consigliere-regionale-il-corriere-della-provincia-e1566288502603.jpeg\",\"keywords\":[\"Frosinone\",\"Pasquale Ciaciarelli\",\"regione lazio\",\"Sanit\u00e0\"],\"articleSection\":[\"*PRIMO PIANO*\",\"Salute e Benessere\"],\"inLanguage\":\"it-IT\",\"copyrightYear\":\"2019\",\"copyrightHolder\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/#organization\"}},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2019\\\/07\\\/26\\\/nomine-dirigenti-asl-ciaccarelli-pessimo-segnale-politico-e-sanitario-dalla-giunta-zingaretti\\\/\",\"url\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2019\\\/07\\\/26\\\/nomine-dirigenti-asl-ciaccarelli-pessimo-segnale-politico-e-sanitario-dalla-giunta-zingaretti\\\/\",\"name\":\"Nomine dirigenti Asl, Ciacciarelli: pessimo segnale politico e sanitario dalla giunta Zingaretti - IlCorriereDellaProvincia.it - News h24 e notizie di approfondimento\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2019\\\/07\\\/26\\\/nomine-dirigenti-asl-ciaccarelli-pessimo-segnale-politico-e-sanitario-dalla-giunta-zingaretti\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2019\\\/07\\\/26\\\/nomine-dirigenti-asl-ciaccarelli-pessimo-segnale-politico-e-sanitario-dalla-giunta-zingaretti\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2019\\\/07\\\/pasquale-ciacciarelli-consigliere-regionale-il-corriere-della-provincia-e1566288502603.jpeg\",\"datePublished\":\"2019-07-26T12:59:02+00:00\",\"dateModified\":\"2019-07-26T13:00:15+00:00\",\"description\":\"Il consigliere regionale di Forza Italia critica pesanetemente il governo regionale in tema di sanit\u00e0. Tante le criticit\u00e0 anche nel Frusinate\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2019\\\/07\\\/26\\\/nomine-dirigenti-asl-ciaccarelli-pessimo-segnale-politico-e-sanitario-dalla-giunta-zingaretti\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2019\\\/07\\\/26\\\/nomine-dirigenti-asl-ciaccarelli-pessimo-segnale-politico-e-sanitario-dalla-giunta-zingaretti\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2019\\\/07\\\/26\\\/nomine-dirigenti-asl-ciaccarelli-pessimo-segnale-politico-e-sanitario-dalla-giunta-zingaretti\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2019\\\/07\\\/pasquale-ciacciarelli-consigliere-regionale-il-corriere-della-provincia-e1566288502603.jpeg\",\"contentUrl\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2019\\\/07\\\/pasquale-ciacciarelli-consigliere-regionale-il-corriere-della-provincia-e1566288502603.jpeg\",\"width\":632,\"height\":414,\"caption\":\"Il consigliere regionale Pasquale Ciacciarelli\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2019\\\/07\\\/26\\\/nomine-dirigenti-asl-ciaccarelli-pessimo-segnale-politico-e-sanitario-dalla-giunta-zingaretti\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Nomine dirigenti Asl, Ciacciarelli: pessimo segnale politico e sanitario dalla giunta Zingaretti\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/#website\",\"url\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/\",\"name\":\"Il Corriere Delle Provincia\",\"description\":\"IlCorriereDellaProvincia.it, quotidiano web di politica, cronaca, inchiesta, lavoro, scuola, turismo, cultura e spettacolo, economia e finanza, salute e benessere. Approfondimenti e notizie aggiornate con foto e video della provincia di Frosinone ma anche news nazionali, dell\u2019Italia e del Mondo.\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":[\"Organization\",\"Place\"],\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/#organization\",\"name\":\"Globalpress s.r.l.\",\"url\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/\",\"logo\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2019\\\/07\\\/26\\\/nomine-dirigenti-asl-ciaccarelli-pessimo-segnale-politico-e-sanitario-dalla-giunta-zingaretti\\\/#local-main-organization-logo\"},\"image\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2019\\\/07\\\/26\\\/nomine-dirigenti-asl-ciaccarelli-pessimo-segnale-politico-e-sanitario-dalla-giunta-zingaretti\\\/#local-main-organization-logo\"},\"telephone\":[],\"openingHoursSpecification\":[{\"@type\":\"OpeningHoursSpecification\",\"dayOfWeek\":[\"Monday\",\"Tuesday\",\"Wednesday\",\"Thursday\",\"Friday\",\"Saturday\",\"Sunday\"],\"opens\":\"09:00\",\"closes\":\"17:00\"}]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/#\\\/schema\\\/person\\\/6d7f0a9120d0c03d0c552e9fdf49ed7d\",\"name\":\"Redazione\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/a40eeacccdcad861f831dde73317f63a542e738f0dc4b79b9f47062d3d4bd1d2?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/a40eeacccdcad861f831dde73317f63a542e738f0dc4b79b9f47062d3d4bd1d2?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/a40eeacccdcad861f831dde73317f63a542e738f0dc4b79b9f47062d3d4bd1d2?s=96&d=mm&r=g\",\"caption\":\"Redazione\"},\"description\":\"SEGUICI ANCHE SUI SOCIAL Facebook: TuNews24 e TuSport24 Instagram: TuNews24 e TuSport24 Youtube: TuNews24 Telegram: TuNews24 Puoi leggerci anche in formato cartaceo: il settimanale viene pubblicato e distribuito gratuitamente ogni venerd\u00ec in edicole, bar, centri commerciali e svariati esercizi. Ma \u00e8 possibile anche sfogliarlo comodamente online, cliccando su TU NEWS sfogliabile TU NEWS, PASSIONE PER L\u2019INFORMAZIONE\",\"sameAs\":[\"http:\\\/\\\/www.tunews24.it\",\"www.facebook.com\\\/tunews24\"],\"url\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/author\\\/senzafirma\\\/\"},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2019\\\/07\\\/26\\\/nomine-dirigenti-asl-ciaccarelli-pessimo-segnale-politico-e-sanitario-dalla-giunta-zingaretti\\\/#local-main-organization-logo\",\"url\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2022\\\/11\\\/cropped-il-corriere-della-provincia-testata-web-scontornata.png\",\"contentUrl\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2022\\\/11\\\/cropped-il-corriere-della-provincia-testata-web-scontornata.png\",\"width\":2911,\"height\":717,\"caption\":\"Globalpress s.r.l.\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Nomine dirigenti Asl, Ciacciarelli: pessimo segnale politico e sanitario dalla giunta Zingaretti - IlCorriereDellaProvincia.it - News h24 e notizie di approfondimento","description":"Il consigliere regionale di Forza Italia critica pesanetemente il governo regionale in tema di sanit\u00e0. Tante le criticit\u00e0 anche nel Frusinate","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2019\/07\/26\/nomine-dirigenti-asl-ciaccarelli-pessimo-segnale-politico-e-sanitario-dalla-giunta-zingaretti\/","og_locale":"it_IT","og_type":"article","og_title":"Nomine dirigenti Asl, Ciacciarelli: pessimo segnale politico e sanitario dalla giunta Zingaretti","og_description":"Il consigliere regionale di Forza Italia critica pesanetemente il governo regionale in tema di sanit\u00e0. Tante le criticit\u00e0 anche nel Frusinate","og_url":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2019\/07\/26\/nomine-dirigenti-asl-ciaccarelli-pessimo-segnale-politico-e-sanitario-dalla-giunta-zingaretti\/","og_site_name":"IlCorriereDellaProvincia.it - News h24 e notizie di approfondimento","article_author":"www.facebook.com\/tunews24","article_published_time":"2019-07-26T12:59:02+00:00","article_modified_time":"2019-07-26T13:00:15+00:00","og_image":[{"width":632,"height":414,"url":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2019\/07\/pasquale-ciacciarelli-consigliere-regionale-il-corriere-della-provincia-e1566288502603.jpeg","type":"image\/jpeg"}],"author":"Redazione","twitter_card":"summary_large_image","twitter_misc":{"Scritto da":"Redazione","Tempo di lettura stimato":"1 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2019\/07\/26\/nomine-dirigenti-asl-ciaccarelli-pessimo-segnale-politico-e-sanitario-dalla-giunta-zingaretti\/#article","isPartOf":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2019\/07\/26\/nomine-dirigenti-asl-ciaccarelli-pessimo-segnale-politico-e-sanitario-dalla-giunta-zingaretti\/"},"author":{"name":"Redazione","@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/#\/schema\/person\/6d7f0a9120d0c03d0c552e9fdf49ed7d"},"headline":"Nomine dirigenti Asl, Ciacciarelli: pessimo segnale politico e sanitario dalla giunta Zingaretti","datePublished":"2019-07-26T12:59:02+00:00","dateModified":"2019-07-26T13:00:15+00:00","mainEntityOfPage":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2019\/07\/26\/nomine-dirigenti-asl-ciaccarelli-pessimo-segnale-politico-e-sanitario-dalla-giunta-zingaretti\/"},"wordCount":240,"commentCount":0,"publisher":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/#organization"},"image":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2019\/07\/26\/nomine-dirigenti-asl-ciaccarelli-pessimo-segnale-politico-e-sanitario-dalla-giunta-zingaretti\/#primaryimage"},"thumbnailUrl":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2019\/07\/pasquale-ciacciarelli-consigliere-regionale-il-corriere-della-provincia-e1566288502603.jpeg","keywords":["Frosinone","Pasquale Ciaciarelli","regione lazio","Sanit\u00e0"],"articleSection":["*PRIMO PIANO*","Salute e Benessere"],"inLanguage":"it-IT","copyrightYear":"2019","copyrightHolder":{"@id":"https:\/\/www.tunews24.it\/#organization"}},{"@type":"WebPage","@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2019\/07\/26\/nomine-dirigenti-asl-ciaccarelli-pessimo-segnale-politico-e-sanitario-dalla-giunta-zingaretti\/","url":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2019\/07\/26\/nomine-dirigenti-asl-ciaccarelli-pessimo-segnale-politico-e-sanitario-dalla-giunta-zingaretti\/","name":"Nomine dirigenti Asl, Ciacciarelli: pessimo segnale politico e sanitario dalla giunta Zingaretti - IlCorriereDellaProvincia.it - News h24 e notizie di approfondimento","isPartOf":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2019\/07\/26\/nomine-dirigenti-asl-ciaccarelli-pessimo-segnale-politico-e-sanitario-dalla-giunta-zingaretti\/#primaryimage"},"image":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2019\/07\/26\/nomine-dirigenti-asl-ciaccarelli-pessimo-segnale-politico-e-sanitario-dalla-giunta-zingaretti\/#primaryimage"},"thumbnailUrl":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2019\/07\/pasquale-ciacciarelli-consigliere-regionale-il-corriere-della-provincia-e1566288502603.jpeg","datePublished":"2019-07-26T12:59:02+00:00","dateModified":"2019-07-26T13:00:15+00:00","description":"Il consigliere regionale di Forza Italia critica pesanetemente il governo regionale in tema di sanit\u00e0. Tante le criticit\u00e0 anche nel Frusinate","breadcrumb":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2019\/07\/26\/nomine-dirigenti-asl-ciaccarelli-pessimo-segnale-politico-e-sanitario-dalla-giunta-zingaretti\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2019\/07\/26\/nomine-dirigenti-asl-ciaccarelli-pessimo-segnale-politico-e-sanitario-dalla-giunta-zingaretti\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2019\/07\/26\/nomine-dirigenti-asl-ciaccarelli-pessimo-segnale-politico-e-sanitario-dalla-giunta-zingaretti\/#primaryimage","url":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2019\/07\/pasquale-ciacciarelli-consigliere-regionale-il-corriere-della-provincia-e1566288502603.jpeg","contentUrl":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2019\/07\/pasquale-ciacciarelli-consigliere-regionale-il-corriere-della-provincia-e1566288502603.jpeg","width":632,"height":414,"caption":"Il consigliere regionale Pasquale Ciacciarelli"},{"@type":"BreadcrumbList","@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2019\/07\/26\/nomine-dirigenti-asl-ciaccarelli-pessimo-segnale-politico-e-sanitario-dalla-giunta-zingaretti\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/"},{"@type":"ListItem","position":2,"name":"Nomine dirigenti Asl, Ciacciarelli: pessimo segnale politico e sanitario dalla giunta Zingaretti"}]},{"@type":"WebSite","@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/#website","url":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/","name":"Il Corriere Delle Provincia","description":"IlCorriereDellaProvincia.it, quotidiano web di politica, cronaca, inchiesta, lavoro, scuola, turismo, cultura e spettacolo, economia e finanza, salute e benessere. Approfondimenti e notizie aggiornate con foto e video della provincia di Frosinone ma anche news nazionali, dell\u2019Italia e del Mondo.","publisher":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":["Organization","Place"],"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/#organization","name":"Globalpress s.r.l.","url":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/","logo":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2019\/07\/26\/nomine-dirigenti-asl-ciaccarelli-pessimo-segnale-politico-e-sanitario-dalla-giunta-zingaretti\/#local-main-organization-logo"},"image":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2019\/07\/26\/nomine-dirigenti-asl-ciaccarelli-pessimo-segnale-politico-e-sanitario-dalla-giunta-zingaretti\/#local-main-organization-logo"},"telephone":[],"openingHoursSpecification":[{"@type":"OpeningHoursSpecification","dayOfWeek":["Monday","Tuesday","Wednesday","Thursday","Friday","Saturday","Sunday"],"opens":"09:00","closes":"17:00"}]},{"@type":"Person","@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/#\/schema\/person\/6d7f0a9120d0c03d0c552e9fdf49ed7d","name":"Redazione","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/secure.gravatar.com\/avatar\/a40eeacccdcad861f831dde73317f63a542e738f0dc4b79b9f47062d3d4bd1d2?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/a40eeacccdcad861f831dde73317f63a542e738f0dc4b79b9f47062d3d4bd1d2?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/a40eeacccdcad861f831dde73317f63a542e738f0dc4b79b9f47062d3d4bd1d2?s=96&d=mm&r=g","caption":"Redazione"},"description":"SEGUICI ANCHE SUI SOCIAL Facebook: TuNews24 e TuSport24 Instagram: TuNews24 e TuSport24 Youtube: TuNews24 Telegram: TuNews24 Puoi leggerci anche in formato cartaceo: il settimanale viene pubblicato e distribuito gratuitamente ogni venerd\u00ec in edicole, bar, centri commerciali e svariati esercizi. Ma \u00e8 possibile anche sfogliarlo comodamente online, cliccando su TU NEWS sfogliabile TU NEWS, PASSIONE PER L\u2019INFORMAZIONE","sameAs":["http:\/\/www.tunews24.it","www.facebook.com\/tunews24"],"url":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/author\/senzafirma\/"},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2019\/07\/26\/nomine-dirigenti-asl-ciaccarelli-pessimo-segnale-politico-e-sanitario-dalla-giunta-zingaretti\/#local-main-organization-logo","url":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2022\/11\/cropped-il-corriere-della-provincia-testata-web-scontornata.png","contentUrl":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2022\/11\/cropped-il-corriere-della-provincia-testata-web-scontornata.png","width":2911,"height":717,"caption":"Globalpress s.r.l."}]}},"_links":{"self":[{"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/posts\/15896","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/users\/18"}],"replies":[{"embeddable":true,"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/comments?post=15896"}],"version-history":[{"count":2,"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/posts\/15896\/revisions"}],"predecessor-version":[{"id":15902,"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/posts\/15896\/revisions\/15902"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/media\/15899"}],"wp:attachment":[{"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/media?parent=15896"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/categories?post=15896"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/tags?post=15896"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}