{"id":1554,"date":"2018-11-16T10:40:15","date_gmt":"2018-11-16T09:40:15","guid":{"rendered":"http:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/?p=1554"},"modified":"2018-11-16T10:42:00","modified_gmt":"2018-11-16T09:42:00","slug":"famiglia-di-orsi-annegata-in-una-vasca-di-raccolta-delle-acque","status":"publish","type":"post","link":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2018\/11\/16\/famiglia-di-orsi-annegata-in-una-vasca-di-raccolta-delle-acque\/","title":{"rendered":"Tre orsi annegati in una vasca di raccolta delle acque"},"content":{"rendered":"<p>Morti altri tre orsi. Li ha trovati il personale del <strong>Parco nazionale d&#8217;Abruzzo<\/strong>, insieme ai Carabinieri forestali, in una vasca per la raccolta dell&#8217;acqua in localit\u00e0 <strong>&#8216;Le fossette&#8217;<\/strong>, tra i Comuni di Balsorano e Villavallelonga, nella<strong> zona di protezione esterna del parco<\/strong>.<\/p>\n<p>Si tratta di una <strong>femmina di circa 10 anni<\/strong>, con <strong>2 cuccioli<\/strong> dell&#8217;anno, un maschio e una femmina, che sono presumibilmente annegati cadendo nella vasca per la raccolta delle acque dalla quale non sono riusciti a risalire.<\/p>\n<figure id=\"attachment_1557\" aria-describedby=\"caption-attachment-1557\" style=\"width: 684px\" class=\"wp-caption aligncenter\"><img loading=\"lazy\" decoding=\"async\" class=\"wp-image-1557 size-large\" src=\"http:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2018\/11\/orsi-morti-parco.jpg-684x1024.jpg\" alt=\"orsi annegati parco abruzzo \" width=\"684\" height=\"1024\" \/><figcaption id=\"caption-attachment-1557\" class=\"wp-caption-text\">La vasca di raccolta delle acque dove sono annegati i tre orsi marsicani<\/figcaption><\/figure>\n<h2>Le operazioni di recupero<\/h2>\n<p>La segnalazione della presenza di animali nella vasca \u00e8 giunta al servizio di sorveglianza nel tardo pomeriggio di mercoled\u00ec da parte di un <strong>escursionista di Balsorano<\/strong> e ieri mattina all&#8217;alba il personale del Parco ha raggiunto la localit\u00e0. Per il recupero dei plantigradi \u00e8 stato necessario l&#8217;intervento di un <strong>elicottero<\/strong>, messo a disposizione dai carabinieri forestali, in quanto la localit\u00e0 si trova<strong> in alta quota<\/strong> ed \u00e8 raggiungibile solo a piedi. Le carcasse sono state trasportate a <strong>Pescasseroli<\/strong> e saranno sottoposte ad esame necroscopico per accertare o escludere che non ci siano altre cause di morte.<br \/>\nNel frattempo, il servizio di sorveglianza, in raccordo con la <strong>Procura di Avezzano<\/strong>, ha adottato tutti gli atti di polizia giudiziaria in relazione alla morte degli orsi.<\/p>\n<figure id=\"attachment_1560\" aria-describedby=\"caption-attachment-1560\" style=\"width: 800px\" class=\"wp-caption aligncenter\"><img loading=\"lazy\" decoding=\"async\" class=\"wp-image-1560 size-large\" src=\"http:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2018\/11\/orsi-parco-abruzzo2.jpg-1024x509.jpg\" alt=\"orsi marsicani morti parco abruzzo\" width=\"800\" height=\"398\" \/><figcaption id=\"caption-attachment-1560\" class=\"wp-caption-text\">Gli orsi marsicani recuperati dal personale del Parco insieme ai carabinieri forestali<\/figcaption><\/figure>\n<h2>Il precedente nel 2010<\/h2>\n<p>La vasca, nella quale erano gi\u00e0 morti altri 2 orsi nel 2010, si trova su una <strong>propriet\u00e0 privata<\/strong> e gli interventi di messa in sicurezza realizzati dai proprietari, con il supporto del Corpo Forestale dello Stato nel 2012, non erano pi\u00f9 adeguati a garantire la sicurezza di uomini e animali.<br \/>\nSu segnalazione dell&#8217;<strong>Associazione Salviamo l&#8217;orso<\/strong> il servizio di sorveglianza del Parco ha provveduto a verificare la situazione e l&#8217;Ente, pur trattandosi di una propriet\u00e0 privata fuori dai confini del Parco, nelle scorse settimane ha intimato ai proprietari di realizzare <strong>adeguate misure di protezione<\/strong> per garantire l&#8217;incolumit\u00e0 di persone e animali, fornendo anche la consulenza tecnica per una soluzione efficace e definitiva del problema. Purtroppo, a tutt&#8217;oggi, non \u00e8 stato realizzato alcun intervento.<\/p>\n<figure id=\"attachment_1558\" aria-describedby=\"caption-attachment-1558\" style=\"width: 800px\" class=\"wp-caption aligncenter\"><img loading=\"lazy\" decoding=\"async\" class=\"wp-image-1558 size-large\" src=\"http:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2018\/11\/orsi-parco-abruzzo-1-1024x450.jpg\" alt=\"orsi annegati parco abruzzo\" width=\"800\" height=\"352\" \/><figcaption id=\"caption-attachment-1558\" class=\"wp-caption-text\">L&#8217;area della zona di protezione speciale del parco dove sono stati ritrovati gli orsi annegati<\/figcaption><\/figure>\n<h2><strong>Le parole del presidente Carrara<br \/>\n<\/strong><\/h2>\n<p>&#8220;Siamo di fronte a una<strong> perdita gravissima<\/strong> per l&#8217;esigua popolazione di orsi marsicani \u2013 dichiara il Presidente del Parco, Antonio Carrara &#8211; che rischia di vanificare i tanti sforzi compiuti quotidianamente per ridurre la mortalit\u00e0 e per avere un numero di femmine riproduttive pi\u00f9 alto. L&#8217;episodio ripropone la necessit\u00e0 di interventi pi\u00f9 incisi per garantire la <strong>conservazione dell&#8217;orso marsicano<\/strong>, soprattutto fuori dal territorio del Parco, dove l&#8217;autorit\u00e0 e la funzione dell&#8217;Ente sono normativamente meno incisivi ed efficaci&#8221;.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Morti altri tre orsi. Li ha trovati il personale del Parco nazionale d&#8217;Abruzzo, insieme ai Carabinieri forestali, in una vasca<\/p>\n","protected":false},"author":7,"featured_media":1559,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[41,2],"tags":[592,593,94,595,594,93,590,589,591,161,596],"class_list":["post-1554","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-slide","category-cronaca","tag-abruzzo","tag-balsorano","tag-ciociaria","tag-elicottero","tag-forestale","tag-frosinone","tag-marsicani","tag-orsi","tag-parco-nazionale","tag-sora","tag-zps"],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v27.8 (Yoast SEO v27.8) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Tre orsi annegati in una vasca di raccolta delle acque - IlCorriereDellaProvincia.it - News h24 e notizie di approfondimento<\/title>\n<meta name=\"description\" content=\"Tre orsi marsicani, una mamma e due suoi cuccioli, sono stati trovati morti nel parco nazionale d&#039;Abruzzo: annegati in una vasca di raccolta delle acque\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2018\/11\/16\/famiglia-di-orsi-annegata-in-una-vasca-di-raccolta-delle-acque\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Tre orsi annegati in una vasca di raccolta delle acque\" \/>\n<meta property=\"og:description\" content=\"Tre orsi marsicani, una mamma e due suoi cuccioli, sono stati trovati morti nel parco nazionale d&#039;Abruzzo: annegati in una vasca di raccolta delle acque\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2018\/11\/16\/famiglia-di-orsi-annegata-in-una-vasca-di-raccolta-delle-acque\/\" \/>\n<meta property=\"og:site_name\" content=\"IlCorriereDellaProvincia.it - News h24 e notizie di approfondimento\" \/>\n<meta property=\"article:author\" content=\"http:\/\/www.facebook.com\/tunews24\" \/>\n<meta property=\"article:published_time\" content=\"2018-11-16T09:40:15+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2018-11-16T09:42:00+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2018\/11\/orsi-parco-abruzzo-2-e1542361058708.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"632\" \/>\n\t<meta property=\"og:image:height\" content=\"422\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Giulia Abbruzzese\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"Giulia Abbruzzese\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minuti\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2018\\\/11\\\/16\\\/famiglia-di-orsi-annegata-in-una-vasca-di-raccolta-delle-acque\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2018\\\/11\\\/16\\\/famiglia-di-orsi-annegata-in-una-vasca-di-raccolta-delle-acque\\\/\"},\"author\":{\"name\":\"Giulia Abbruzzese\",\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/#\\\/schema\\\/person\\\/58bf90a6d70d54d2f0db83bc3d580351\"},\"headline\":\"Tre orsi annegati in una vasca di raccolta delle acque\",\"datePublished\":\"2018-11-16T09:40:15+00:00\",\"dateModified\":\"2018-11-16T09:42:00+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2018\\\/11\\\/16\\\/famiglia-di-orsi-annegata-in-una-vasca-di-raccolta-delle-acque\\\/\"},\"wordCount\":490,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2018\\\/11\\\/16\\\/famiglia-di-orsi-annegata-in-una-vasca-di-raccolta-delle-acque\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2018\\\/11\\\/orsi-parco-abruzzo-2-e1542361058708.jpg\",\"keywords\":[\"abruzzo\",\"balsorano\",\"Ciociaria\",\"elicottero\",\"forestale\",\"Frosinone\",\"marsicani\",\"orsi\",\"parco nazionale\",\"sora\",\"zps\"],\"articleSection\":[\"*SLIDE*\",\"Cronaca\"],\"inLanguage\":\"it-IT\",\"copyrightYear\":\"2018\",\"copyrightHolder\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/#organization\"}},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2018\\\/11\\\/16\\\/famiglia-di-orsi-annegata-in-una-vasca-di-raccolta-delle-acque\\\/\",\"url\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2018\\\/11\\\/16\\\/famiglia-di-orsi-annegata-in-una-vasca-di-raccolta-delle-acque\\\/\",\"name\":\"Tre orsi annegati in una vasca di raccolta delle acque - IlCorriereDellaProvincia.it - News h24 e notizie di approfondimento\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2018\\\/11\\\/16\\\/famiglia-di-orsi-annegata-in-una-vasca-di-raccolta-delle-acque\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2018\\\/11\\\/16\\\/famiglia-di-orsi-annegata-in-una-vasca-di-raccolta-delle-acque\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2018\\\/11\\\/orsi-parco-abruzzo-2-e1542361058708.jpg\",\"datePublished\":\"2018-11-16T09:40:15+00:00\",\"dateModified\":\"2018-11-16T09:42:00+00:00\",\"description\":\"Tre orsi marsicani, una mamma e due suoi cuccioli, sono stati trovati morti nel parco nazionale d'Abruzzo: annegati in una vasca di raccolta delle acque\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2018\\\/11\\\/16\\\/famiglia-di-orsi-annegata-in-una-vasca-di-raccolta-delle-acque\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2018\\\/11\\\/16\\\/famiglia-di-orsi-annegata-in-una-vasca-di-raccolta-delle-acque\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2018\\\/11\\\/16\\\/famiglia-di-orsi-annegata-in-una-vasca-di-raccolta-delle-acque\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2018\\\/11\\\/orsi-parco-abruzzo-2-e1542361058708.jpg\",\"contentUrl\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2018\\\/11\\\/orsi-parco-abruzzo-2-e1542361058708.jpg\",\"width\":632,\"height\":422,\"caption\":\"Tre orsi annegati in una vasca di raccolta delle acque nella zona di protezione speciale del Parco nazionale d'Abruzzo\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2018\\\/11\\\/16\\\/famiglia-di-orsi-annegata-in-una-vasca-di-raccolta-delle-acque\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Tre orsi annegati in una vasca di raccolta delle acque\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/#website\",\"url\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/\",\"name\":\"Il Corriere Delle Provincia\",\"description\":\"IlCorriereDellaProvincia.it, quotidiano web di politica, cronaca, inchiesta, lavoro, scuola, turismo, cultura e spettacolo, economia e finanza, salute e benessere. Approfondimenti e notizie aggiornate con foto e video della provincia di Frosinone ma anche news nazionali, dell\u2019Italia e del Mondo.\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":[\"Organization\",\"Place\"],\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/#organization\",\"name\":\"Globalpress s.r.l.\",\"url\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/\",\"logo\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2018\\\/11\\\/16\\\/famiglia-di-orsi-annegata-in-una-vasca-di-raccolta-delle-acque\\\/#local-main-organization-logo\"},\"image\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2018\\\/11\\\/16\\\/famiglia-di-orsi-annegata-in-una-vasca-di-raccolta-delle-acque\\\/#local-main-organization-logo\"},\"telephone\":[],\"openingHoursSpecification\":[{\"@type\":\"OpeningHoursSpecification\",\"dayOfWeek\":[\"Monday\",\"Tuesday\",\"Wednesday\",\"Thursday\",\"Friday\",\"Saturday\",\"Sunday\"],\"opens\":\"09:00\",\"closes\":\"17:00\"}]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/#\\\/schema\\\/person\\\/58bf90a6d70d54d2f0db83bc3d580351\",\"name\":\"Giulia Abbruzzese\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/ff9b2f7c2c6d1751e3de0056e95b7af4a6c366bf539cdd639aac86cd1908507f?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/ff9b2f7c2c6d1751e3de0056e95b7af4a6c366bf539cdd639aac86cd1908507f?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/ff9b2f7c2c6d1751e3de0056e95b7af4a6c366bf539cdd639aac86cd1908507f?s=96&d=mm&r=g\",\"caption\":\"Giulia Abbruzzese\"},\"description\":\"Giornalista dei quotidiani online \\\"Il Corriere della Provincia\\\" e \\\"TuNews24.it\\\" e del settimanale \\\"Tu News\\\", ha collaborato anche con il mensile \\\"Qui Magazine\\\" oltre che con il settimanale \\\"Qui Sette\\\"; \u00e8 stata inoltre Caposervizio del quotidiano \\\"\u2018Ciociaria Oggi\\\" e Caporedattore de \\\"Il quotidiano della Ciociaria\\\". Collabora con la rivista \\\"Chic Style\\\".\",\"sameAs\":[\"http:\\\/\\\/www.tunews24.it\",\"http:\\\/\\\/www.facebook.com\\\/tunews24\"],\"url\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/author\\\/giulia-abbruzzese\\\/\"},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2018\\\/11\\\/16\\\/famiglia-di-orsi-annegata-in-una-vasca-di-raccolta-delle-acque\\\/#local-main-organization-logo\",\"url\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2022\\\/11\\\/cropped-il-corriere-della-provincia-testata-web-scontornata.png\",\"contentUrl\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2022\\\/11\\\/cropped-il-corriere-della-provincia-testata-web-scontornata.png\",\"width\":2911,\"height\":717,\"caption\":\"Globalpress s.r.l.\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Tre orsi annegati in una vasca di raccolta delle acque - IlCorriereDellaProvincia.it - News h24 e notizie di approfondimento","description":"Tre orsi marsicani, una mamma e due suoi cuccioli, sono stati trovati morti nel parco nazionale d'Abruzzo: annegati in una vasca di raccolta delle acque","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2018\/11\/16\/famiglia-di-orsi-annegata-in-una-vasca-di-raccolta-delle-acque\/","og_locale":"it_IT","og_type":"article","og_title":"Tre orsi annegati in una vasca di raccolta delle acque","og_description":"Tre orsi marsicani, una mamma e due suoi cuccioli, sono stati trovati morti nel parco nazionale d'Abruzzo: annegati in una vasca di raccolta delle acque","og_url":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2018\/11\/16\/famiglia-di-orsi-annegata-in-una-vasca-di-raccolta-delle-acque\/","og_site_name":"IlCorriereDellaProvincia.it - News h24 e notizie di approfondimento","article_author":"http:\/\/www.facebook.com\/tunews24","article_published_time":"2018-11-16T09:40:15+00:00","article_modified_time":"2018-11-16T09:42:00+00:00","og_image":[{"width":632,"height":422,"url":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2018\/11\/orsi-parco-abruzzo-2-e1542361058708.jpg","type":"image\/jpeg"}],"author":"Giulia Abbruzzese","twitter_card":"summary_large_image","twitter_misc":{"Scritto da":"Giulia Abbruzzese","Tempo di lettura stimato":"2 minuti"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2018\/11\/16\/famiglia-di-orsi-annegata-in-una-vasca-di-raccolta-delle-acque\/#article","isPartOf":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2018\/11\/16\/famiglia-di-orsi-annegata-in-una-vasca-di-raccolta-delle-acque\/"},"author":{"name":"Giulia Abbruzzese","@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/#\/schema\/person\/58bf90a6d70d54d2f0db83bc3d580351"},"headline":"Tre orsi annegati in una vasca di raccolta delle acque","datePublished":"2018-11-16T09:40:15+00:00","dateModified":"2018-11-16T09:42:00+00:00","mainEntityOfPage":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2018\/11\/16\/famiglia-di-orsi-annegata-in-una-vasca-di-raccolta-delle-acque\/"},"wordCount":490,"commentCount":0,"publisher":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/#organization"},"image":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2018\/11\/16\/famiglia-di-orsi-annegata-in-una-vasca-di-raccolta-delle-acque\/#primaryimage"},"thumbnailUrl":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2018\/11\/orsi-parco-abruzzo-2-e1542361058708.jpg","keywords":["abruzzo","balsorano","Ciociaria","elicottero","forestale","Frosinone","marsicani","orsi","parco nazionale","sora","zps"],"articleSection":["*SLIDE*","Cronaca"],"inLanguage":"it-IT","copyrightYear":"2018","copyrightHolder":{"@id":"https:\/\/www.tunews24.it\/#organization"}},{"@type":"WebPage","@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2018\/11\/16\/famiglia-di-orsi-annegata-in-una-vasca-di-raccolta-delle-acque\/","url":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2018\/11\/16\/famiglia-di-orsi-annegata-in-una-vasca-di-raccolta-delle-acque\/","name":"Tre orsi annegati in una vasca di raccolta delle acque - IlCorriereDellaProvincia.it - News h24 e notizie di approfondimento","isPartOf":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2018\/11\/16\/famiglia-di-orsi-annegata-in-una-vasca-di-raccolta-delle-acque\/#primaryimage"},"image":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2018\/11\/16\/famiglia-di-orsi-annegata-in-una-vasca-di-raccolta-delle-acque\/#primaryimage"},"thumbnailUrl":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2018\/11\/orsi-parco-abruzzo-2-e1542361058708.jpg","datePublished":"2018-11-16T09:40:15+00:00","dateModified":"2018-11-16T09:42:00+00:00","description":"Tre orsi marsicani, una mamma e due suoi cuccioli, sono stati trovati morti nel parco nazionale d'Abruzzo: annegati in una vasca di raccolta delle acque","breadcrumb":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2018\/11\/16\/famiglia-di-orsi-annegata-in-una-vasca-di-raccolta-delle-acque\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2018\/11\/16\/famiglia-di-orsi-annegata-in-una-vasca-di-raccolta-delle-acque\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2018\/11\/16\/famiglia-di-orsi-annegata-in-una-vasca-di-raccolta-delle-acque\/#primaryimage","url":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2018\/11\/orsi-parco-abruzzo-2-e1542361058708.jpg","contentUrl":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2018\/11\/orsi-parco-abruzzo-2-e1542361058708.jpg","width":632,"height":422,"caption":"Tre orsi annegati in una vasca di raccolta delle acque nella zona di protezione speciale del Parco nazionale d'Abruzzo"},{"@type":"BreadcrumbList","@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2018\/11\/16\/famiglia-di-orsi-annegata-in-una-vasca-di-raccolta-delle-acque\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/"},{"@type":"ListItem","position":2,"name":"Tre orsi annegati in una vasca di raccolta delle acque"}]},{"@type":"WebSite","@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/#website","url":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/","name":"Il Corriere Delle Provincia","description":"IlCorriereDellaProvincia.it, quotidiano web di politica, cronaca, inchiesta, lavoro, scuola, turismo, cultura e spettacolo, economia e finanza, salute e benessere. Approfondimenti e notizie aggiornate con foto e video della provincia di Frosinone ma anche news nazionali, dell\u2019Italia e del Mondo.","publisher":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":["Organization","Place"],"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/#organization","name":"Globalpress s.r.l.","url":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/","logo":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2018\/11\/16\/famiglia-di-orsi-annegata-in-una-vasca-di-raccolta-delle-acque\/#local-main-organization-logo"},"image":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2018\/11\/16\/famiglia-di-orsi-annegata-in-una-vasca-di-raccolta-delle-acque\/#local-main-organization-logo"},"telephone":[],"openingHoursSpecification":[{"@type":"OpeningHoursSpecification","dayOfWeek":["Monday","Tuesday","Wednesday","Thursday","Friday","Saturday","Sunday"],"opens":"09:00","closes":"17:00"}]},{"@type":"Person","@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/#\/schema\/person\/58bf90a6d70d54d2f0db83bc3d580351","name":"Giulia Abbruzzese","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/secure.gravatar.com\/avatar\/ff9b2f7c2c6d1751e3de0056e95b7af4a6c366bf539cdd639aac86cd1908507f?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/ff9b2f7c2c6d1751e3de0056e95b7af4a6c366bf539cdd639aac86cd1908507f?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/ff9b2f7c2c6d1751e3de0056e95b7af4a6c366bf539cdd639aac86cd1908507f?s=96&d=mm&r=g","caption":"Giulia Abbruzzese"},"description":"Giornalista dei quotidiani online \"Il Corriere della Provincia\" e \"TuNews24.it\" e del settimanale \"Tu News\", ha collaborato anche con il mensile \"Qui Magazine\" oltre che con il settimanale \"Qui Sette\"; \u00e8 stata inoltre Caposervizio del quotidiano \"\u2018Ciociaria Oggi\" e Caporedattore de \"Il quotidiano della Ciociaria\". Collabora con la rivista \"Chic Style\".","sameAs":["http:\/\/www.tunews24.it","http:\/\/www.facebook.com\/tunews24"],"url":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/author\/giulia-abbruzzese\/"},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2018\/11\/16\/famiglia-di-orsi-annegata-in-una-vasca-di-raccolta-delle-acque\/#local-main-organization-logo","url":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2022\/11\/cropped-il-corriere-della-provincia-testata-web-scontornata.png","contentUrl":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2022\/11\/cropped-il-corriere-della-provincia-testata-web-scontornata.png","width":2911,"height":717,"caption":"Globalpress s.r.l."}]}},"_links":{"self":[{"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/posts\/1554","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/users\/7"}],"replies":[{"embeddable":true,"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/comments?post=1554"}],"version-history":[{"count":2,"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/posts\/1554\/revisions"}],"predecessor-version":[{"id":1568,"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/posts\/1554\/revisions\/1568"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/media\/1559"}],"wp:attachment":[{"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/media?parent=1554"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/categories?post=1554"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/tags?post=1554"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}