{"id":15441,"date":"2019-07-22T18:35:36","date_gmt":"2019-07-22T16:35:36","guid":{"rendered":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/?p=15441"},"modified":"2019-07-22T18:35:36","modified_gmt":"2019-07-22T16:35:36","slug":"crisi-fca-ciacciarelli-sollecita-un-tavolo-ministeriale","status":"publish","type":"post","link":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2019\/07\/22\/crisi-fca-ciacciarelli-sollecita-un-tavolo-ministeriale\/","title":{"rendered":"Crisi Fca, Ciacciarelli sollecita un tavolo ministeriale"},"content":{"rendered":"<p>\u201cA<strong>l trand negativo annunciato dal rapporto del Ministero dei Trasporti<\/strong> per le vendite FCA vanno a sommarsi previsioni future tutt\u2019altro che rosee.\u00a0 Da gennaio a giugno c\u2019 \u00e8 stato un calo del 47,2% per i modelli del marchio Alfa Romeo prodotti a Cassino. Cos\u00ec il consigliere regionale del Lazio <strong>Pasquale Ciacciarelli<\/strong> (FI).<\/p>\n<h2>L&#8217;analisi<\/h2>\n<p>&#8220;Fca ha registrato un calo delle vendite a giugno del 13,5% in Europa, con la quota di mercato che scende al 6,1%. E&#8217; l&#8217;allarme lanciato dal sindacato Fiom-Cgil.\u00a0<strong> La situazione \u00e8 estremamente drammatica per il settore dell\u2019automotive in Italia, in particolar modo \u00a0per lo stabilimento FCA di Piedimonte San Germano<\/strong>, e non fa altro che alimentare un clima di incertezza sul futuro dello stabilimento e dei lavoratori. La cassa integrazione per 3000 di questi, inoltre, \u00e8 quasi terminata,e poi \u00a0non ci saranno pi\u00f9 altri ammortizzatori sociali&#8221;.<\/p>\n<h2>L&#8217;appello<\/h2>\n<p>&#8220;Si prospetta, dunque, un dramma nel dramma. Il lavoro \u00e8 una questione cruciale, soprattutto in un territorio martoriato dalla disoccupazione e dalla crisi, come il nostro, pertanto \u00e8 necessario tenere alta l\u2019attenzione sullo stabilimento Fiat Chrysler di Piedimonte San Germano\/Cassino. Settimane fa \u00e8 stata approvata in Consiglio Regionale la \u00a0mozione, di cui sono firmatario, insieme ad altri colleghi, che impegna \u00a0il presidente Zingaretti e la Giunta ad istituire<strong> un tavolo ministeriale permanente per monitorare la situazione<\/strong> relativa allo stabilimento FCA di Piedimonte San Germano di cui facciano parte i rappresentanti del Gruppo FCA ed i sindaci dei Comuni interessati, al fine di elaborare adeguate politiche di contrasto alla crisi e sostegno al territorio. Non si pu\u00f2 pi\u00f9 aspettare oltre. Non capisco Zingaretti, cosa aspetta? Io dico che dalle carte bisogna passare ai fatti e dare risposte concrete ai lavoratori sul loro futuro.\u201d<\/p>\n<p>&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>\u201cAl trand negativo annunciato dal rapporto del Ministero dei Trasporti per le vendite FCA vanno a sommarsi previsioni future tutt\u2019altro<\/p>\n","protected":false},"author":18,"featured_media":1303,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[28],"tags":[3730,216,155,554,279,1336,619,562],"class_list":["post-15441","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-politica","tag-alfa-romeo","tag-cassino","tag-crisi","tag-fca","tag-lavoro","tag-pasquale-ciacciarelli","tag-piedimonte","tag-regione-lazio"],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v27.8 (Yoast SEO v27.8) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Crisi Fca, Ciacciarelli sollecita un tavolo ministeriale - IlCorriereDellaProvincia.it - News h24 e notizie di approfondimento<\/title>\n<meta name=\"description\" content=\"Da gennaio a giugno c\u2019 \u00e8 stato un calo del 47,2% per i modelli del marchio Alfa Romeo prodotti a Cassino. Il consigliere regionale chiede interventi.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2019\/07\/22\/crisi-fca-ciacciarelli-sollecita-un-tavolo-ministeriale\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Crisi Fca, Ciacciarelli sollecita un tavolo ministeriale\" \/>\n<meta property=\"og:description\" content=\"Da gennaio a giugno c\u2019 \u00e8 stato un calo del 47,2% per i modelli del marchio Alfa Romeo prodotti a Cassino. Il consigliere regionale chiede interventi.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2019\/07\/22\/crisi-fca-ciacciarelli-sollecita-un-tavolo-ministeriale\/\" \/>\n<meta property=\"og:site_name\" content=\"IlCorriereDellaProvincia.it - News h24 e notizie di approfondimento\" \/>\n<meta property=\"article:author\" content=\"www.facebook.com\/tunews24\" \/>\n<meta property=\"article:published_time\" content=\"2019-07-22T16:35:36+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2018\/11\/pasquale-cicciarelli-e1546167085557.jpeg\" \/>\n\t<meta property=\"og:image:width\" content=\"632\" \/>\n\t<meta property=\"og:image:height\" content=\"421\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Redazione\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"Redazione\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2019\\\/07\\\/22\\\/crisi-fca-ciacciarelli-sollecita-un-tavolo-ministeriale\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2019\\\/07\\\/22\\\/crisi-fca-ciacciarelli-sollecita-un-tavolo-ministeriale\\\/\"},\"author\":{\"name\":\"Redazione\",\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/#\\\/schema\\\/person\\\/6d7f0a9120d0c03d0c552e9fdf49ed7d\"},\"headline\":\"Crisi Fca, Ciacciarelli sollecita un tavolo ministeriale\",\"datePublished\":\"2019-07-22T16:35:36+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2019\\\/07\\\/22\\\/crisi-fca-ciacciarelli-sollecita-un-tavolo-ministeriale\\\/\"},\"wordCount\":288,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2019\\\/07\\\/22\\\/crisi-fca-ciacciarelli-sollecita-un-tavolo-ministeriale\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2018\\\/11\\\/pasquale-cicciarelli-e1546167085557.jpeg\",\"keywords\":[\"Alfa Romeo\",\"Cassino\",\"crisi\",\"Fca\",\"lavoro\",\"pasquale ciacciarelli\",\"piedimonte\",\"regione lazio\"],\"articleSection\":[\"Evidenza\"],\"inLanguage\":\"it-IT\",\"copyrightYear\":\"2019\",\"copyrightHolder\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/#organization\"}},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2019\\\/07\\\/22\\\/crisi-fca-ciacciarelli-sollecita-un-tavolo-ministeriale\\\/\",\"url\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2019\\\/07\\\/22\\\/crisi-fca-ciacciarelli-sollecita-un-tavolo-ministeriale\\\/\",\"name\":\"Crisi Fca, Ciacciarelli sollecita un tavolo ministeriale - IlCorriereDellaProvincia.it - News h24 e notizie di approfondimento\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2019\\\/07\\\/22\\\/crisi-fca-ciacciarelli-sollecita-un-tavolo-ministeriale\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2019\\\/07\\\/22\\\/crisi-fca-ciacciarelli-sollecita-un-tavolo-ministeriale\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2018\\\/11\\\/pasquale-cicciarelli-e1546167085557.jpeg\",\"datePublished\":\"2019-07-22T16:35:36+00:00\",\"description\":\"Da gennaio a giugno c\u2019 \u00e8 stato un calo del 47,2% per i modelli del marchio Alfa Romeo prodotti a Cassino. Il consigliere regionale chiede interventi.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2019\\\/07\\\/22\\\/crisi-fca-ciacciarelli-sollecita-un-tavolo-ministeriale\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2019\\\/07\\\/22\\\/crisi-fca-ciacciarelli-sollecita-un-tavolo-ministeriale\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2019\\\/07\\\/22\\\/crisi-fca-ciacciarelli-sollecita-un-tavolo-ministeriale\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2018\\\/11\\\/pasquale-cicciarelli-e1546167085557.jpeg\",\"contentUrl\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2018\\\/11\\\/pasquale-cicciarelli-e1546167085557.jpeg\",\"width\":632,\"height\":421,\"caption\":\"Il consigliere regionale di Forza Italia Pasquale Ciacciarelli\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2019\\\/07\\\/22\\\/crisi-fca-ciacciarelli-sollecita-un-tavolo-ministeriale\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Crisi Fca, Ciacciarelli sollecita un tavolo ministeriale\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/#website\",\"url\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/\",\"name\":\"Il Corriere Delle Provincia\",\"description\":\"IlCorriereDellaProvincia.it, quotidiano web di politica, cronaca, inchiesta, lavoro, scuola, turismo, cultura e spettacolo, economia e finanza, salute e benessere. Approfondimenti e notizie aggiornate con foto e video della provincia di Frosinone ma anche news nazionali, dell\u2019Italia e del Mondo.\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":[\"Organization\",\"Place\"],\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/#organization\",\"name\":\"Globalpress s.r.l.\",\"url\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/\",\"logo\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2019\\\/07\\\/22\\\/crisi-fca-ciacciarelli-sollecita-un-tavolo-ministeriale\\\/#local-main-organization-logo\"},\"image\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2019\\\/07\\\/22\\\/crisi-fca-ciacciarelli-sollecita-un-tavolo-ministeriale\\\/#local-main-organization-logo\"},\"telephone\":[],\"openingHoursSpecification\":[{\"@type\":\"OpeningHoursSpecification\",\"dayOfWeek\":[\"Monday\",\"Tuesday\",\"Wednesday\",\"Thursday\",\"Friday\",\"Saturday\",\"Sunday\"],\"opens\":\"09:00\",\"closes\":\"17:00\"}]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/#\\\/schema\\\/person\\\/6d7f0a9120d0c03d0c552e9fdf49ed7d\",\"name\":\"Redazione\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/a40eeacccdcad861f831dde73317f63a542e738f0dc4b79b9f47062d3d4bd1d2?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/a40eeacccdcad861f831dde73317f63a542e738f0dc4b79b9f47062d3d4bd1d2?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/a40eeacccdcad861f831dde73317f63a542e738f0dc4b79b9f47062d3d4bd1d2?s=96&d=mm&r=g\",\"caption\":\"Redazione\"},\"description\":\"SEGUICI ANCHE SUI SOCIAL Facebook: TuNews24 e TuSport24 Instagram: TuNews24 e TuSport24 Youtube: TuNews24 Telegram: TuNews24 Puoi leggerci anche in formato cartaceo: il settimanale viene pubblicato e distribuito gratuitamente ogni venerd\u00ec in edicole, bar, centri commerciali e svariati esercizi. Ma \u00e8 possibile anche sfogliarlo comodamente online, cliccando su TU NEWS sfogliabile TU NEWS, PASSIONE PER L\u2019INFORMAZIONE\",\"sameAs\":[\"http:\\\/\\\/www.tunews24.it\",\"www.facebook.com\\\/tunews24\"],\"url\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/author\\\/senzafirma\\\/\"},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2019\\\/07\\\/22\\\/crisi-fca-ciacciarelli-sollecita-un-tavolo-ministeriale\\\/#local-main-organization-logo\",\"url\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2022\\\/11\\\/cropped-il-corriere-della-provincia-testata-web-scontornata.png\",\"contentUrl\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2022\\\/11\\\/cropped-il-corriere-della-provincia-testata-web-scontornata.png\",\"width\":2911,\"height\":717,\"caption\":\"Globalpress s.r.l.\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Crisi Fca, Ciacciarelli sollecita un tavolo ministeriale - IlCorriereDellaProvincia.it - News h24 e notizie di approfondimento","description":"Da gennaio a giugno c\u2019 \u00e8 stato un calo del 47,2% per i modelli del marchio Alfa Romeo prodotti a Cassino. Il consigliere regionale chiede interventi.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2019\/07\/22\/crisi-fca-ciacciarelli-sollecita-un-tavolo-ministeriale\/","og_locale":"it_IT","og_type":"article","og_title":"Crisi Fca, Ciacciarelli sollecita un tavolo ministeriale","og_description":"Da gennaio a giugno c\u2019 \u00e8 stato un calo del 47,2% per i modelli del marchio Alfa Romeo prodotti a Cassino. Il consigliere regionale chiede interventi.","og_url":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2019\/07\/22\/crisi-fca-ciacciarelli-sollecita-un-tavolo-ministeriale\/","og_site_name":"IlCorriereDellaProvincia.it - News h24 e notizie di approfondimento","article_author":"www.facebook.com\/tunews24","article_published_time":"2019-07-22T16:35:36+00:00","og_image":[{"width":632,"height":421,"url":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2018\/11\/pasquale-cicciarelli-e1546167085557.jpeg","type":"image\/jpeg"}],"author":"Redazione","twitter_card":"summary_large_image","twitter_misc":{"Scritto da":"Redazione","Tempo di lettura stimato":"1 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2019\/07\/22\/crisi-fca-ciacciarelli-sollecita-un-tavolo-ministeriale\/#article","isPartOf":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2019\/07\/22\/crisi-fca-ciacciarelli-sollecita-un-tavolo-ministeriale\/"},"author":{"name":"Redazione","@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/#\/schema\/person\/6d7f0a9120d0c03d0c552e9fdf49ed7d"},"headline":"Crisi Fca, Ciacciarelli sollecita un tavolo ministeriale","datePublished":"2019-07-22T16:35:36+00:00","mainEntityOfPage":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2019\/07\/22\/crisi-fca-ciacciarelli-sollecita-un-tavolo-ministeriale\/"},"wordCount":288,"commentCount":0,"publisher":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/#organization"},"image":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2019\/07\/22\/crisi-fca-ciacciarelli-sollecita-un-tavolo-ministeriale\/#primaryimage"},"thumbnailUrl":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2018\/11\/pasquale-cicciarelli-e1546167085557.jpeg","keywords":["Alfa Romeo","Cassino","crisi","Fca","lavoro","pasquale ciacciarelli","piedimonte","regione lazio"],"articleSection":["Evidenza"],"inLanguage":"it-IT","copyrightYear":"2019","copyrightHolder":{"@id":"https:\/\/www.tunews24.it\/#organization"}},{"@type":"WebPage","@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2019\/07\/22\/crisi-fca-ciacciarelli-sollecita-un-tavolo-ministeriale\/","url":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2019\/07\/22\/crisi-fca-ciacciarelli-sollecita-un-tavolo-ministeriale\/","name":"Crisi Fca, Ciacciarelli sollecita un tavolo ministeriale - IlCorriereDellaProvincia.it - News h24 e notizie di approfondimento","isPartOf":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2019\/07\/22\/crisi-fca-ciacciarelli-sollecita-un-tavolo-ministeriale\/#primaryimage"},"image":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2019\/07\/22\/crisi-fca-ciacciarelli-sollecita-un-tavolo-ministeriale\/#primaryimage"},"thumbnailUrl":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2018\/11\/pasquale-cicciarelli-e1546167085557.jpeg","datePublished":"2019-07-22T16:35:36+00:00","description":"Da gennaio a giugno c\u2019 \u00e8 stato un calo del 47,2% per i modelli del marchio Alfa Romeo prodotti a Cassino. Il consigliere regionale chiede interventi.","breadcrumb":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2019\/07\/22\/crisi-fca-ciacciarelli-sollecita-un-tavolo-ministeriale\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2019\/07\/22\/crisi-fca-ciacciarelli-sollecita-un-tavolo-ministeriale\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2019\/07\/22\/crisi-fca-ciacciarelli-sollecita-un-tavolo-ministeriale\/#primaryimage","url":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2018\/11\/pasquale-cicciarelli-e1546167085557.jpeg","contentUrl":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2018\/11\/pasquale-cicciarelli-e1546167085557.jpeg","width":632,"height":421,"caption":"Il consigliere regionale di Forza Italia Pasquale Ciacciarelli"},{"@type":"BreadcrumbList","@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2019\/07\/22\/crisi-fca-ciacciarelli-sollecita-un-tavolo-ministeriale\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/"},{"@type":"ListItem","position":2,"name":"Crisi Fca, Ciacciarelli sollecita un tavolo ministeriale"}]},{"@type":"WebSite","@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/#website","url":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/","name":"Il Corriere Delle Provincia","description":"IlCorriereDellaProvincia.it, quotidiano web di politica, cronaca, inchiesta, lavoro, scuola, turismo, cultura e spettacolo, economia e finanza, salute e benessere. Approfondimenti e notizie aggiornate con foto e video della provincia di Frosinone ma anche news nazionali, dell\u2019Italia e del Mondo.","publisher":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":["Organization","Place"],"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/#organization","name":"Globalpress s.r.l.","url":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/","logo":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2019\/07\/22\/crisi-fca-ciacciarelli-sollecita-un-tavolo-ministeriale\/#local-main-organization-logo"},"image":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2019\/07\/22\/crisi-fca-ciacciarelli-sollecita-un-tavolo-ministeriale\/#local-main-organization-logo"},"telephone":[],"openingHoursSpecification":[{"@type":"OpeningHoursSpecification","dayOfWeek":["Monday","Tuesday","Wednesday","Thursday","Friday","Saturday","Sunday"],"opens":"09:00","closes":"17:00"}]},{"@type":"Person","@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/#\/schema\/person\/6d7f0a9120d0c03d0c552e9fdf49ed7d","name":"Redazione","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/secure.gravatar.com\/avatar\/a40eeacccdcad861f831dde73317f63a542e738f0dc4b79b9f47062d3d4bd1d2?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/a40eeacccdcad861f831dde73317f63a542e738f0dc4b79b9f47062d3d4bd1d2?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/a40eeacccdcad861f831dde73317f63a542e738f0dc4b79b9f47062d3d4bd1d2?s=96&d=mm&r=g","caption":"Redazione"},"description":"SEGUICI ANCHE SUI SOCIAL Facebook: TuNews24 e TuSport24 Instagram: TuNews24 e TuSport24 Youtube: TuNews24 Telegram: TuNews24 Puoi leggerci anche in formato cartaceo: il settimanale viene pubblicato e distribuito gratuitamente ogni venerd\u00ec in edicole, bar, centri commerciali e svariati esercizi. Ma \u00e8 possibile anche sfogliarlo comodamente online, cliccando su TU NEWS sfogliabile TU NEWS, PASSIONE PER L\u2019INFORMAZIONE","sameAs":["http:\/\/www.tunews24.it","www.facebook.com\/tunews24"],"url":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/author\/senzafirma\/"},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2019\/07\/22\/crisi-fca-ciacciarelli-sollecita-un-tavolo-ministeriale\/#local-main-organization-logo","url":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2022\/11\/cropped-il-corriere-della-provincia-testata-web-scontornata.png","contentUrl":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2022\/11\/cropped-il-corriere-della-provincia-testata-web-scontornata.png","width":2911,"height":717,"caption":"Globalpress s.r.l."}]}},"_links":{"self":[{"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/posts\/15441","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/users\/18"}],"replies":[{"embeddable":true,"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/comments?post=15441"}],"version-history":[{"count":1,"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/posts\/15441\/revisions"}],"predecessor-version":[{"id":15442,"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/posts\/15441\/revisions\/15442"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/media\/1303"}],"wp:attachment":[{"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/media?parent=15441"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/categories?post=15441"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/tags?post=15441"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}