{"id":15038,"date":"2019-07-17T08:40:57","date_gmt":"2019-07-17T06:40:57","guid":{"rendered":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/?p=15038"},"modified":"2019-07-18T11:23:04","modified_gmt":"2019-07-18T09:23:04","slug":"cassino-i-furbetti-dellacqua-su-2-500-utenze-verificate-oltre-700-sono-abusive","status":"publish","type":"post","link":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2019\/07\/17\/cassino-i-furbetti-dellacqua-su-2-500-utenze-verificate-oltre-700-sono-abusive\/","title":{"rendered":"Cassino, I furbetti dell\u2019acqua: su 2.500 utenze verificate oltre 700 sono abusive"},"content":{"rendered":"<p dir=\"ltr\"><strong>Quasi un\u2019utenza ogni tre \u00e8 abusiva<\/strong>. Le verifiche condotte da Acea Ato 5 sulle forniture idriche del centro di Cassino hanno dato riscontri clamorosi: su 2.500 posizioni verificate \u00e8 emerso che oltre 700 sono risultate sostanzialmente abusive. Abitazioni, negozi o attivit\u00e0 che hanno l\u2019acqua completamente gratis e da sempre.<\/p>\n<h2>Utenze non censite<\/h2>\n<p dir=\"ltr\">Tali utenze, infatti, pur se dotate di contatore dei consumi, non risultano censite<strong> n\u00e9 negli elenchi del Comune di Cassino, che fino a due anni fa gestiva il servizio acquedotto, n\u00e9 tra quelli dell\u2019attuale gestore Acea Ato 5<\/strong>; utenze che non hanno mai ricevuto fatture, n\u00e9 dal Municipio in precedenza, n\u00e9 ora dal gestore unico.<\/p>\n<figure id=\"attachment_8467\" aria-describedby=\"caption-attachment-8467\" style=\"width: 632px\" class=\"wp-caption aligncenter\"><img loading=\"lazy\" decoding=\"async\" class=\"size-full wp-image-8467\" src=\"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2019\/03\/stefano-magini-acea-e1553269171909.jpg\" alt=\"presidente acea il corriere della provincia\" width=\"632\" height=\"361\" \/><figcaption id=\"caption-attachment-8467\" class=\"wp-caption-text\">Il presidente di Acea Stefano Magini<\/figcaption><\/figure>\n<h2>Acea segnala il caso a sindaco e prefetto<\/h2>\n<p dir=\"ltr\">Una situazione di diffusa illegalit\u00e0 che ha costretto il presidente di Acea Ato 5,<strong> Stefano Magini,<\/strong> a segnalare il caso alla nuova amministrazione comunale della Citt\u00e0 martire, guidata dal sindaco<strong> Enzo Salera<\/strong>, e alla Prefettura di Frosinone a cui \u00e8 stato chiesto supporto al fine di convocare un incontro tra gestore e Comune.<\/p>\n<p dir=\"ltr\">Nella missiva, Acea rappresenta di aver acquisito la gestione del servizio idrico nel centro di Cassino dal 1\u00b0 luglio 2017, ereditando una serie di criticit\u00e0 gestionali sia sul profilo della manutenzione che prettamente amministrativo. Ha quindi avviato un\u2019attivit\u00e0 di approfondita verifica del database comunale delle utenze trasferite, riscontrando fin da subito numerosi allacci attivi ma non censiti e quindi non contrattualizzati.<\/p>\n<h2>Rischi pesanti<\/h2>\n<p dir=\"ltr\">Una situazione di assoluta gravit\u00e0, come denuncia la societ\u00e0 di gestione, suscettibile anche di profili penalmente rilevanti.\u00a0 Nella segnalazione fatta anche al prefetto Ignazio Portelli, si evidenzia come tale stato di cose si differenzi dal caso in cui l\u2019utente si allaccia abusivamente alla rete pubblica, poich\u00e9, nelle situazioni fin qui riscontrate, <strong>le utenze risultano provviste di misuratore a suo tempo<\/strong> evidentemente installato dal Comune, senza tuttavia che a ci\u00f2 siano seguiti la contrattualizzazione dell\u2019utenza, l\u2019invio delle fatture e i pagamenti. Insomma, in questo caso si potrebbero prefigurare responsabilit\u00e0 dirette anche dell\u2019ente comunale e dei responsabili che in passato si sono occupati del servizio idrico.<\/p>\n<h2>Il gestore idrico sollecita un confronto<\/h2>\n<p dir=\"ltr\">Per questo Acea Ato 5 chiede un confronto c<strong>on il Comune al fine di definire tempi e modi per contrastare il fenomeno descritto,<\/strong> nella consapevolezza che, vista la mole di utenze interessate &#8211; a regime potrebbero superare le 3-4.000 &#8211; e visto il contesto territoriale di accentuata ostilit\u00e0 nei confronti del gestore (e forse se ne capisce ora meglio anche il perch\u00e9!), non appare percorribile la strada dei distacchi massivi e della conseguente obbligatoria segnalazione alla Procura della repubblica (che finirebbe inondata di denunce), con il rischio, inoltre, di problemi d&#8217;ordine pubblico e di sicurezza per gli operatori Acea.<\/p>\n<p dir=\"ltr\">D\u2019altro canto<strong>, lo stesso presidente Magini ha auspicato<\/strong> l&#8217;instaurazione &#8211; a differenza del passato &#8211; di forme di collaborazione con il Comune cos\u00ec da favorire la migliore e pi\u00f9 efficace gestione del servizio, a garanzia degli stessi utenti.<\/p>\n<p>&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Quasi un\u2019utenza ogni tre \u00e8 abusiva. Le verifiche condotte da Acea Ato 5 sulle forniture idriche del centro di Cassino<\/p>\n","protected":false},"author":18,"featured_media":15039,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[41,2236],"tags":[1329,216,3273,2659,5380],"class_list":["post-15038","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-slide","category-attualita","tag-acea-ato-5","tag-cassino","tag-enzo-salera","tag-stefano-magini","tag-utenze-abiusive"],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v27.8 (Yoast SEO v27.8) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Cassino, I furbetti dell\u2019acqua: su 2.500 utenze verificate oltre 700 sono abusive - IlCorriereDellaProvincia.it - News h24 e notizie di approfondimento<\/title>\n<meta name=\"description\" content=\"Acea rappresenta di aver acquisito la gestione del servizio idrico nel centro di Cassino dal 1\u00b0 luglio 2017, ereditando una serie di criticit\u00e0 gestionali\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2019\/07\/17\/cassino-i-furbetti-dellacqua-su-2-500-utenze-verificate-oltre-700-sono-abusive\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Cassino, I furbetti dell\u2019acqua: su 2.500 utenze verificate oltre 700 sono abusive\" \/>\n<meta property=\"og:description\" content=\"Acea rappresenta di aver acquisito la gestione del servizio idrico nel centro di Cassino dal 1\u00b0 luglio 2017, ereditando una serie di criticit\u00e0 gestionali\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2019\/07\/17\/cassino-i-furbetti-dellacqua-su-2-500-utenze-verificate-oltre-700-sono-abusive\/\" \/>\n<meta property=\"og:site_name\" content=\"IlCorriereDellaProvincia.it - News h24 e notizie di approfondimento\" \/>\n<meta property=\"article:author\" content=\"www.facebook.com\/tunews24\" \/>\n<meta property=\"article:published_time\" content=\"2019-07-17T06:40:57+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2019-07-18T09:23:04+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2019\/07\/contatori-acqua.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"560\" \/>\n\t<meta property=\"og:image:height\" content=\"315\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Redazione\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"Redazione\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minuti\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2019\\\/07\\\/17\\\/cassino-i-furbetti-dellacqua-su-2-500-utenze-verificate-oltre-700-sono-abusive\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2019\\\/07\\\/17\\\/cassino-i-furbetti-dellacqua-su-2-500-utenze-verificate-oltre-700-sono-abusive\\\/\"},\"author\":{\"name\":\"Redazione\",\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/#\\\/schema\\\/person\\\/6d7f0a9120d0c03d0c552e9fdf49ed7d\"},\"headline\":\"Cassino, I furbetti dell\u2019acqua: su 2.500 utenze verificate oltre 700 sono abusive\",\"datePublished\":\"2019-07-17T06:40:57+00:00\",\"dateModified\":\"2019-07-18T09:23:04+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2019\\\/07\\\/17\\\/cassino-i-furbetti-dellacqua-su-2-500-utenze-verificate-oltre-700-sono-abusive\\\/\"},\"wordCount\":503,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2019\\\/07\\\/17\\\/cassino-i-furbetti-dellacqua-su-2-500-utenze-verificate-oltre-700-sono-abusive\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2019\\\/07\\\/contatori-acqua.jpg\",\"keywords\":[\"acea ato 5\",\"Cassino\",\"enzo salera\",\"Stefano Magini\",\"utenze abiusive\"],\"articleSection\":[\"*SLIDE*\",\"Attualit\u00e0\"],\"inLanguage\":\"it-IT\",\"copyrightYear\":\"2019\",\"copyrightHolder\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/#organization\"}},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2019\\\/07\\\/17\\\/cassino-i-furbetti-dellacqua-su-2-500-utenze-verificate-oltre-700-sono-abusive\\\/\",\"url\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2019\\\/07\\\/17\\\/cassino-i-furbetti-dellacqua-su-2-500-utenze-verificate-oltre-700-sono-abusive\\\/\",\"name\":\"Cassino, I furbetti dell\u2019acqua: su 2.500 utenze verificate oltre 700 sono abusive - IlCorriereDellaProvincia.it - News h24 e notizie di approfondimento\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2019\\\/07\\\/17\\\/cassino-i-furbetti-dellacqua-su-2-500-utenze-verificate-oltre-700-sono-abusive\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2019\\\/07\\\/17\\\/cassino-i-furbetti-dellacqua-su-2-500-utenze-verificate-oltre-700-sono-abusive\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2019\\\/07\\\/contatori-acqua.jpg\",\"datePublished\":\"2019-07-17T06:40:57+00:00\",\"dateModified\":\"2019-07-18T09:23:04+00:00\",\"description\":\"Acea rappresenta di aver acquisito la gestione del servizio idrico nel centro di Cassino dal 1\u00b0 luglio 2017, ereditando una serie di criticit\u00e0 gestionali\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2019\\\/07\\\/17\\\/cassino-i-furbetti-dellacqua-su-2-500-utenze-verificate-oltre-700-sono-abusive\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2019\\\/07\\\/17\\\/cassino-i-furbetti-dellacqua-su-2-500-utenze-verificate-oltre-700-sono-abusive\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2019\\\/07\\\/17\\\/cassino-i-furbetti-dellacqua-su-2-500-utenze-verificate-oltre-700-sono-abusive\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2019\\\/07\\\/contatori-acqua.jpg\",\"contentUrl\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2019\\\/07\\\/contatori-acqua.jpg\",\"width\":560,\"height\":315},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2019\\\/07\\\/17\\\/cassino-i-furbetti-dellacqua-su-2-500-utenze-verificate-oltre-700-sono-abusive\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Cassino, I furbetti dell\u2019acqua: su 2.500 utenze verificate oltre 700 sono abusive\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/#website\",\"url\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/\",\"name\":\"Il Corriere Delle Provincia\",\"description\":\"IlCorriereDellaProvincia.it, quotidiano web di politica, cronaca, inchiesta, lavoro, scuola, turismo, cultura e spettacolo, economia e finanza, salute e benessere. Approfondimenti e notizie aggiornate con foto e video della provincia di Frosinone ma anche news nazionali, dell\u2019Italia e del Mondo.\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":[\"Organization\",\"Place\"],\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/#organization\",\"name\":\"Globalpress s.r.l.\",\"url\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/\",\"logo\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2019\\\/07\\\/17\\\/cassino-i-furbetti-dellacqua-su-2-500-utenze-verificate-oltre-700-sono-abusive\\\/#local-main-organization-logo\"},\"image\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2019\\\/07\\\/17\\\/cassino-i-furbetti-dellacqua-su-2-500-utenze-verificate-oltre-700-sono-abusive\\\/#local-main-organization-logo\"},\"telephone\":[],\"openingHoursSpecification\":[{\"@type\":\"OpeningHoursSpecification\",\"dayOfWeek\":[\"Monday\",\"Tuesday\",\"Wednesday\",\"Thursday\",\"Friday\",\"Saturday\",\"Sunday\"],\"opens\":\"09:00\",\"closes\":\"17:00\"}]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/#\\\/schema\\\/person\\\/6d7f0a9120d0c03d0c552e9fdf49ed7d\",\"name\":\"Redazione\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/a40eeacccdcad861f831dde73317f63a542e738f0dc4b79b9f47062d3d4bd1d2?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/a40eeacccdcad861f831dde73317f63a542e738f0dc4b79b9f47062d3d4bd1d2?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/a40eeacccdcad861f831dde73317f63a542e738f0dc4b79b9f47062d3d4bd1d2?s=96&d=mm&r=g\",\"caption\":\"Redazione\"},\"description\":\"SEGUICI ANCHE SUI SOCIAL Facebook: TuNews24 e TuSport24 Instagram: TuNews24 e TuSport24 Youtube: TuNews24 Telegram: TuNews24 Puoi leggerci anche in formato cartaceo: il settimanale viene pubblicato e distribuito gratuitamente ogni venerd\u00ec in edicole, bar, centri commerciali e svariati esercizi. Ma \u00e8 possibile anche sfogliarlo comodamente online, cliccando su TU NEWS sfogliabile TU NEWS, PASSIONE PER L\u2019INFORMAZIONE\",\"sameAs\":[\"http:\\\/\\\/www.tunews24.it\",\"www.facebook.com\\\/tunews24\"],\"url\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/author\\\/senzafirma\\\/\"},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2019\\\/07\\\/17\\\/cassino-i-furbetti-dellacqua-su-2-500-utenze-verificate-oltre-700-sono-abusive\\\/#local-main-organization-logo\",\"url\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2022\\\/11\\\/cropped-il-corriere-della-provincia-testata-web-scontornata.png\",\"contentUrl\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2022\\\/11\\\/cropped-il-corriere-della-provincia-testata-web-scontornata.png\",\"width\":2911,\"height\":717,\"caption\":\"Globalpress s.r.l.\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Cassino, I furbetti dell\u2019acqua: su 2.500 utenze verificate oltre 700 sono abusive - IlCorriereDellaProvincia.it - News h24 e notizie di approfondimento","description":"Acea rappresenta di aver acquisito la gestione del servizio idrico nel centro di Cassino dal 1\u00b0 luglio 2017, ereditando una serie di criticit\u00e0 gestionali","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2019\/07\/17\/cassino-i-furbetti-dellacqua-su-2-500-utenze-verificate-oltre-700-sono-abusive\/","og_locale":"it_IT","og_type":"article","og_title":"Cassino, I furbetti dell\u2019acqua: su 2.500 utenze verificate oltre 700 sono abusive","og_description":"Acea rappresenta di aver acquisito la gestione del servizio idrico nel centro di Cassino dal 1\u00b0 luglio 2017, ereditando una serie di criticit\u00e0 gestionali","og_url":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2019\/07\/17\/cassino-i-furbetti-dellacqua-su-2-500-utenze-verificate-oltre-700-sono-abusive\/","og_site_name":"IlCorriereDellaProvincia.it - News h24 e notizie di approfondimento","article_author":"www.facebook.com\/tunews24","article_published_time":"2019-07-17T06:40:57+00:00","article_modified_time":"2019-07-18T09:23:04+00:00","og_image":[{"width":560,"height":315,"url":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2019\/07\/contatori-acqua.jpg","type":"image\/jpeg"}],"author":"Redazione","twitter_card":"summary_large_image","twitter_misc":{"Scritto da":"Redazione","Tempo di lettura stimato":"2 minuti"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2019\/07\/17\/cassino-i-furbetti-dellacqua-su-2-500-utenze-verificate-oltre-700-sono-abusive\/#article","isPartOf":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2019\/07\/17\/cassino-i-furbetti-dellacqua-su-2-500-utenze-verificate-oltre-700-sono-abusive\/"},"author":{"name":"Redazione","@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/#\/schema\/person\/6d7f0a9120d0c03d0c552e9fdf49ed7d"},"headline":"Cassino, I furbetti dell\u2019acqua: su 2.500 utenze verificate oltre 700 sono abusive","datePublished":"2019-07-17T06:40:57+00:00","dateModified":"2019-07-18T09:23:04+00:00","mainEntityOfPage":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2019\/07\/17\/cassino-i-furbetti-dellacqua-su-2-500-utenze-verificate-oltre-700-sono-abusive\/"},"wordCount":503,"commentCount":0,"publisher":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/#organization"},"image":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2019\/07\/17\/cassino-i-furbetti-dellacqua-su-2-500-utenze-verificate-oltre-700-sono-abusive\/#primaryimage"},"thumbnailUrl":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2019\/07\/contatori-acqua.jpg","keywords":["acea ato 5","Cassino","enzo salera","Stefano Magini","utenze abiusive"],"articleSection":["*SLIDE*","Attualit\u00e0"],"inLanguage":"it-IT","copyrightYear":"2019","copyrightHolder":{"@id":"https:\/\/www.tunews24.it\/#organization"}},{"@type":"WebPage","@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2019\/07\/17\/cassino-i-furbetti-dellacqua-su-2-500-utenze-verificate-oltre-700-sono-abusive\/","url":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2019\/07\/17\/cassino-i-furbetti-dellacqua-su-2-500-utenze-verificate-oltre-700-sono-abusive\/","name":"Cassino, I furbetti dell\u2019acqua: su 2.500 utenze verificate oltre 700 sono abusive - IlCorriereDellaProvincia.it - News h24 e notizie di approfondimento","isPartOf":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2019\/07\/17\/cassino-i-furbetti-dellacqua-su-2-500-utenze-verificate-oltre-700-sono-abusive\/#primaryimage"},"image":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2019\/07\/17\/cassino-i-furbetti-dellacqua-su-2-500-utenze-verificate-oltre-700-sono-abusive\/#primaryimage"},"thumbnailUrl":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2019\/07\/contatori-acqua.jpg","datePublished":"2019-07-17T06:40:57+00:00","dateModified":"2019-07-18T09:23:04+00:00","description":"Acea rappresenta di aver acquisito la gestione del servizio idrico nel centro di Cassino dal 1\u00b0 luglio 2017, ereditando una serie di criticit\u00e0 gestionali","breadcrumb":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2019\/07\/17\/cassino-i-furbetti-dellacqua-su-2-500-utenze-verificate-oltre-700-sono-abusive\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2019\/07\/17\/cassino-i-furbetti-dellacqua-su-2-500-utenze-verificate-oltre-700-sono-abusive\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2019\/07\/17\/cassino-i-furbetti-dellacqua-su-2-500-utenze-verificate-oltre-700-sono-abusive\/#primaryimage","url":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2019\/07\/contatori-acqua.jpg","contentUrl":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2019\/07\/contatori-acqua.jpg","width":560,"height":315},{"@type":"BreadcrumbList","@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2019\/07\/17\/cassino-i-furbetti-dellacqua-su-2-500-utenze-verificate-oltre-700-sono-abusive\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/"},{"@type":"ListItem","position":2,"name":"Cassino, I furbetti dell\u2019acqua: su 2.500 utenze verificate oltre 700 sono abusive"}]},{"@type":"WebSite","@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/#website","url":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/","name":"Il Corriere Delle Provincia","description":"IlCorriereDellaProvincia.it, quotidiano web di politica, cronaca, inchiesta, lavoro, scuola, turismo, cultura e spettacolo, economia e finanza, salute e benessere. Approfondimenti e notizie aggiornate con foto e video della provincia di Frosinone ma anche news nazionali, dell\u2019Italia e del Mondo.","publisher":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":["Organization","Place"],"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/#organization","name":"Globalpress s.r.l.","url":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/","logo":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2019\/07\/17\/cassino-i-furbetti-dellacqua-su-2-500-utenze-verificate-oltre-700-sono-abusive\/#local-main-organization-logo"},"image":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2019\/07\/17\/cassino-i-furbetti-dellacqua-su-2-500-utenze-verificate-oltre-700-sono-abusive\/#local-main-organization-logo"},"telephone":[],"openingHoursSpecification":[{"@type":"OpeningHoursSpecification","dayOfWeek":["Monday","Tuesday","Wednesday","Thursday","Friday","Saturday","Sunday"],"opens":"09:00","closes":"17:00"}]},{"@type":"Person","@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/#\/schema\/person\/6d7f0a9120d0c03d0c552e9fdf49ed7d","name":"Redazione","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/secure.gravatar.com\/avatar\/a40eeacccdcad861f831dde73317f63a542e738f0dc4b79b9f47062d3d4bd1d2?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/a40eeacccdcad861f831dde73317f63a542e738f0dc4b79b9f47062d3d4bd1d2?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/a40eeacccdcad861f831dde73317f63a542e738f0dc4b79b9f47062d3d4bd1d2?s=96&d=mm&r=g","caption":"Redazione"},"description":"SEGUICI ANCHE SUI SOCIAL Facebook: TuNews24 e TuSport24 Instagram: TuNews24 e TuSport24 Youtube: TuNews24 Telegram: TuNews24 Puoi leggerci anche in formato cartaceo: il settimanale viene pubblicato e distribuito gratuitamente ogni venerd\u00ec in edicole, bar, centri commerciali e svariati esercizi. Ma \u00e8 possibile anche sfogliarlo comodamente online, cliccando su TU NEWS sfogliabile TU NEWS, PASSIONE PER L\u2019INFORMAZIONE","sameAs":["http:\/\/www.tunews24.it","www.facebook.com\/tunews24"],"url":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/author\/senzafirma\/"},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2019\/07\/17\/cassino-i-furbetti-dellacqua-su-2-500-utenze-verificate-oltre-700-sono-abusive\/#local-main-organization-logo","url":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2022\/11\/cropped-il-corriere-della-provincia-testata-web-scontornata.png","contentUrl":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2022\/11\/cropped-il-corriere-della-provincia-testata-web-scontornata.png","width":2911,"height":717,"caption":"Globalpress s.r.l."}]}},"_links":{"self":[{"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/posts\/15038","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/users\/18"}],"replies":[{"embeddable":true,"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/comments?post=15038"}],"version-history":[{"count":2,"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/posts\/15038\/revisions"}],"predecessor-version":[{"id":15041,"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/posts\/15038\/revisions\/15041"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/media\/15039"}],"wp:attachment":[{"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/media?parent=15038"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/categories?post=15038"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/tags?post=15038"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}