{"id":14952,"date":"2019-07-15T19:39:35","date_gmt":"2019-07-15T17:39:35","guid":{"rendered":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/?p=14952"},"modified":"2019-07-16T15:30:17","modified_gmt":"2019-07-16T13:30:17","slug":"trasporto-pubblico-a-cassino-salera-porta-risultati-dalla-regione","status":"publish","type":"post","link":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2019\/07\/15\/trasporto-pubblico-a-cassino-salera-porta-risultati-dalla-regione\/","title":{"rendered":"Trasporto pubblico a Cassino: Salera porta risultati dalla Regione"},"content":{"rendered":"<p>Trasporto pubblico locale e pendolarismo: il <strong>sindaco di Cassino, Enzo Salera<\/strong>, \u00e8 stato ricevuto questa mattina dall&#8217;<strong>assessore alla mobilit\u00e0 Mauro Alessandri<\/strong> negli uffici di via Cristoforo Colombo. Come ha sottolineato lostesso sindaco sono state affrontate sia le tematiche relative al trasporto pubblico locale che le tematiche relative al pendolarismo.<\/p>\n<p>&#8220;Sono stato particolarmente soddisfatto \u2013 ha detto Salera &#8211; della disponibilit\u00e0 riscontrata dall\u2019assessore e dal suo staff per risolvere le annose problematiche che il Comune ha, nonostante l\u2019ottimo lavoro svolto dalla ditta Magni, nella nostra citt\u00e0 ormai da anni&#8221;.<\/p>\n<h2>Il collegamento per la sede universitaria<\/h2>\n<p>&#8220;La nostra attenzione, in particolare, \u00e8 rivolta nei confronti del collegamento tra la stazione e l\u2019Universit\u00e0 in via Folcara. Gi\u00e0 oggi c\u2019\u00e8 una corsa ogni mezzora ma \u00e8 nostra intenzione, con la collaborazione della Regione e di Magni implementare ancora di pi\u00f9 questo servizio. Riuscire a collegare la zona della Folcara con la stazione e il centro di Cassino, significa offrire concretamente un servizio a tutti coloro che studiano e lavorano all\u2019Universit\u00e0 di Cassino e del Lazio Meridionale, e significa anche decongestionare il traffico cittadino, in particolare nel collegamento viario che come tutti sappiamo non \u00e8 eccelso. Solo attraverso un trasporto migliore e pi\u00f9 strutturato, Cassino pu\u00f2 divenire davvero citt\u00e0 universitaria&#8221;.<\/p>\n<p>&nbsp;<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"wp-image-14953 size-full\" src=\"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2019\/07\/universit\u00e0-cassino-e1563211873157.jpg\" alt=\"universit\u00e0 folcara cassino il corriere della provincia\" width=\"632\" height=\"474\" \/><\/p>\n<p>&nbsp;<\/p>\n<p><strong>Salera ha anche riferito dei nuovi criteri che la Regione Lazio utilizzer\u00e0 prossimamente per l\u2019assegnazione dei fondi del Tpl<\/strong>, illustrati dall&#8217;assessore Alessandri, i quali &#8220;andranno a ricadere pienamente gli elementi che oggi abbiamo posto sul tavolo tra cui emerge un numero alto di utenza per singola corsa, visto che Cassino \u00e8 una citt\u00e0 universitaria ed ha notevole richiesta soprattutto da parte di ragazzi. E stiamo parlando di oltre 3.000 persone che ogni giorno usufruiscono del servizio&#8221;.<\/p>\n<h2>Semaforo verde per la corsa bis Cassino-Anagnina<\/h2>\n<p>&#8220;L\u2019altra importante notizia di giornata \u2013 ha fatto sapere il sindaco &#8211; \u00e8 l\u2019ok ufficiale alla corsa bis di Cotral, collegamento diretto Cassino \u2013 Anagnina via autostrada con partenza alle ore 6, per il mese di agosto, come d\u2019altronde avevamo richiesto in campagna elettorale&#8221;.<\/p>\n<p>&#8220;Tale collegamento diretto sar\u00e0 effettuato su autobus bipiano e si andr\u00e0 ad aggiungere alle corse abituali di Cotral. <strong>Tale richiesta era stata effettuata in quanto nel mese di agosto la linea Cassino-Roma sar\u00e0 interessata da lavori sulla linea tra Colleferro e Ciampino<\/strong> con il blocco della circolazione ferroviaria. Questo autobus sostitutivo, come richiesto dall\u2019associazione dei pendolari, sar\u00e0 un servizio ulteriore rispetto al servizio sostitutivo tra Colleferro e Ciampino che Trenitalia ha predisposto per tutto il mese ed \u00e8 un servizio molto pi\u00f9 comodo e veloce con la capitale&#8221;.<\/p>\n<h2>Il commento dell&#8217;assessore<\/h2>\n<p>&#8220;Cominciano a vedersi i risultati concreti del nostro lavoro \u2013 spiega <strong>l\u2019assessore al commercio e trasporti del Comune di Cassino Chiara Delli Colli<\/strong> &#8211; Dopo aver risolto la questione relativa al collegamento con gli uffici dell\u2019Inps, altre due importanti notizie per tutti coloro che sia nella citt\u00e0 di Cassino, che all\u2019interno della nostra Regione si muovono con i mezzi pubblici sia per studio o per lavoro&#8221;.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Trasporto pubblico locale e pendolarismo: il sindaco di Cassino, Enzo Salera, \u00e8 stato ricevuto questa mattina dall&#8217;assessore alla mobilit\u00e0 Mauro<\/p>\n","protected":false},"author":18,"featured_media":14955,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[4,2236],"tags":[3378,216,5069,377,375,3273,405,4615,1695,562,5276,5351],"class_list":["post-14952","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-primo-piano","category-attualita","tag-assessore-regionale","tag-cassino","tag-collegamento","tag-corse","tag-cotral","tag-enzo-salera","tag-incontro","tag-mauro-alessandri","tag-mobilita","tag-regione-lazio","tag-trasporto","tag-trasporto-pubblico-locale"],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v27.8 (Yoast SEO v27.8) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Trasporto pubblico a Cassino: Salera porta risultati dalla Regione - IlCorriereDellaProvincia.it - News h24 e notizie di approfondimento<\/title>\n<meta name=\"description\" content=\"Il sindaco di Cassino Enzo Salera \u00e8 stato ricevuto oggi dall&#039;assessore regionale alla mobilit\u00e0 Mauro Alessandri e ha ottenuto molte rassicurazioni\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2019\/07\/15\/trasporto-pubblico-a-cassino-salera-porta-risultati-dalla-regione\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Trasporto pubblico a Cassino: Salera porta risultati dalla Regione\" \/>\n<meta property=\"og:description\" content=\"Il sindaco di Cassino Enzo Salera \u00e8 stato ricevuto oggi dall&#039;assessore regionale alla mobilit\u00e0 Mauro Alessandri e ha ottenuto molte rassicurazioni\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2019\/07\/15\/trasporto-pubblico-a-cassino-salera-porta-risultati-dalla-regione\/\" \/>\n<meta property=\"og:site_name\" content=\"IlCorriereDellaProvincia.it - News h24 e notizie di approfondimento\" \/>\n<meta property=\"article:author\" content=\"www.facebook.com\/tunews24\" \/>\n<meta property=\"article:published_time\" content=\"2019-07-15T17:39:35+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2019-07-16T13:30:17+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2019\/07\/salera-regione-lazio-e1563212206883.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"632\" \/>\n\t<meta property=\"og:image:height\" content=\"407\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Redazione\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"Redazione\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minuti\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2019\\\/07\\\/15\\\/trasporto-pubblico-a-cassino-salera-porta-risultati-dalla-regione\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2019\\\/07\\\/15\\\/trasporto-pubblico-a-cassino-salera-porta-risultati-dalla-regione\\\/\"},\"author\":{\"name\":\"Redazione\",\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/#\\\/schema\\\/person\\\/6d7f0a9120d0c03d0c552e9fdf49ed7d\"},\"headline\":\"Trasporto pubblico a Cassino: Salera porta risultati dalla Regione\",\"datePublished\":\"2019-07-15T17:39:35+00:00\",\"dateModified\":\"2019-07-16T13:30:17+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2019\\\/07\\\/15\\\/trasporto-pubblico-a-cassino-salera-porta-risultati-dalla-regione\\\/\"},\"wordCount\":502,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2019\\\/07\\\/15\\\/trasporto-pubblico-a-cassino-salera-porta-risultati-dalla-regione\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2019\\\/07\\\/salera-regione-lazio-e1563212206883.jpg\",\"keywords\":[\"assessore regionale\",\"Cassino\",\"collegamento\",\"corse\",\"cotral\",\"enzo salera\",\"incontro\",\"Mauro Alessandri\",\"mobilit\u00e0\",\"regione lazio\",\"trasporto\",\"trasporto pubblico locale\"],\"articleSection\":[\"*PRIMO PIANO*\",\"Attualit\u00e0\"],\"inLanguage\":\"it-IT\",\"copyrightYear\":\"2019\",\"copyrightHolder\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/#organization\"}},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2019\\\/07\\\/15\\\/trasporto-pubblico-a-cassino-salera-porta-risultati-dalla-regione\\\/\",\"url\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2019\\\/07\\\/15\\\/trasporto-pubblico-a-cassino-salera-porta-risultati-dalla-regione\\\/\",\"name\":\"Trasporto pubblico a Cassino: Salera porta risultati dalla Regione - IlCorriereDellaProvincia.it - News h24 e notizie di approfondimento\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2019\\\/07\\\/15\\\/trasporto-pubblico-a-cassino-salera-porta-risultati-dalla-regione\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2019\\\/07\\\/15\\\/trasporto-pubblico-a-cassino-salera-porta-risultati-dalla-regione\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2019\\\/07\\\/salera-regione-lazio-e1563212206883.jpg\",\"datePublished\":\"2019-07-15T17:39:35+00:00\",\"dateModified\":\"2019-07-16T13:30:17+00:00\",\"description\":\"Il sindaco di Cassino Enzo Salera \u00e8 stato ricevuto oggi dall'assessore regionale alla mobilit\u00e0 Mauro Alessandri e ha ottenuto molte rassicurazioni\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2019\\\/07\\\/15\\\/trasporto-pubblico-a-cassino-salera-porta-risultati-dalla-regione\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2019\\\/07\\\/15\\\/trasporto-pubblico-a-cassino-salera-porta-risultati-dalla-regione\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2019\\\/07\\\/15\\\/trasporto-pubblico-a-cassino-salera-porta-risultati-dalla-regione\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2019\\\/07\\\/salera-regione-lazio-e1563212206883.jpg\",\"contentUrl\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2019\\\/07\\\/salera-regione-lazio-e1563212206883.jpg\",\"width\":632,\"height\":407,\"caption\":\"Il sindaco di Cassino Enzo Salera con l'assessore regionale Mauro Alessandri\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2019\\\/07\\\/15\\\/trasporto-pubblico-a-cassino-salera-porta-risultati-dalla-regione\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Trasporto pubblico a Cassino: Salera porta risultati dalla Regione\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/#website\",\"url\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/\",\"name\":\"Il Corriere Delle Provincia\",\"description\":\"IlCorriereDellaProvincia.it, quotidiano web di politica, cronaca, inchiesta, lavoro, scuola, turismo, cultura e spettacolo, economia e finanza, salute e benessere. Approfondimenti e notizie aggiornate con foto e video della provincia di Frosinone ma anche news nazionali, dell\u2019Italia e del Mondo.\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":[\"Organization\",\"Place\"],\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/#organization\",\"name\":\"Globalpress s.r.l.\",\"url\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/\",\"logo\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2019\\\/07\\\/15\\\/trasporto-pubblico-a-cassino-salera-porta-risultati-dalla-regione\\\/#local-main-organization-logo\"},\"image\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2019\\\/07\\\/15\\\/trasporto-pubblico-a-cassino-salera-porta-risultati-dalla-regione\\\/#local-main-organization-logo\"},\"telephone\":[],\"openingHoursSpecification\":[{\"@type\":\"OpeningHoursSpecification\",\"dayOfWeek\":[\"Monday\",\"Tuesday\",\"Wednesday\",\"Thursday\",\"Friday\",\"Saturday\",\"Sunday\"],\"opens\":\"09:00\",\"closes\":\"17:00\"}]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/#\\\/schema\\\/person\\\/6d7f0a9120d0c03d0c552e9fdf49ed7d\",\"name\":\"Redazione\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/a40eeacccdcad861f831dde73317f63a542e738f0dc4b79b9f47062d3d4bd1d2?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/a40eeacccdcad861f831dde73317f63a542e738f0dc4b79b9f47062d3d4bd1d2?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/a40eeacccdcad861f831dde73317f63a542e738f0dc4b79b9f47062d3d4bd1d2?s=96&d=mm&r=g\",\"caption\":\"Redazione\"},\"description\":\"SEGUICI ANCHE SUI SOCIAL Facebook: TuNews24 e TuSport24 Instagram: TuNews24 e TuSport24 Youtube: TuNews24 Telegram: TuNews24 Puoi leggerci anche in formato cartaceo: il settimanale viene pubblicato e distribuito gratuitamente ogni venerd\u00ec in edicole, bar, centri commerciali e svariati esercizi. Ma \u00e8 possibile anche sfogliarlo comodamente online, cliccando su TU NEWS sfogliabile TU NEWS, PASSIONE PER L\u2019INFORMAZIONE\",\"sameAs\":[\"http:\\\/\\\/www.tunews24.it\",\"www.facebook.com\\\/tunews24\"],\"url\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/author\\\/senzafirma\\\/\"},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2019\\\/07\\\/15\\\/trasporto-pubblico-a-cassino-salera-porta-risultati-dalla-regione\\\/#local-main-organization-logo\",\"url\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2022\\\/11\\\/cropped-il-corriere-della-provincia-testata-web-scontornata.png\",\"contentUrl\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2022\\\/11\\\/cropped-il-corriere-della-provincia-testata-web-scontornata.png\",\"width\":2911,\"height\":717,\"caption\":\"Globalpress s.r.l.\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Trasporto pubblico a Cassino: Salera porta risultati dalla Regione - IlCorriereDellaProvincia.it - News h24 e notizie di approfondimento","description":"Il sindaco di Cassino Enzo Salera \u00e8 stato ricevuto oggi dall'assessore regionale alla mobilit\u00e0 Mauro Alessandri e ha ottenuto molte rassicurazioni","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2019\/07\/15\/trasporto-pubblico-a-cassino-salera-porta-risultati-dalla-regione\/","og_locale":"it_IT","og_type":"article","og_title":"Trasporto pubblico a Cassino: Salera porta risultati dalla Regione","og_description":"Il sindaco di Cassino Enzo Salera \u00e8 stato ricevuto oggi dall'assessore regionale alla mobilit\u00e0 Mauro Alessandri e ha ottenuto molte rassicurazioni","og_url":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2019\/07\/15\/trasporto-pubblico-a-cassino-salera-porta-risultati-dalla-regione\/","og_site_name":"IlCorriereDellaProvincia.it - News h24 e notizie di approfondimento","article_author":"www.facebook.com\/tunews24","article_published_time":"2019-07-15T17:39:35+00:00","article_modified_time":"2019-07-16T13:30:17+00:00","og_image":[{"width":632,"height":407,"url":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2019\/07\/salera-regione-lazio-e1563212206883.jpg","type":"image\/jpeg"}],"author":"Redazione","twitter_card":"summary_large_image","twitter_misc":{"Scritto da":"Redazione","Tempo di lettura stimato":"2 minuti"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2019\/07\/15\/trasporto-pubblico-a-cassino-salera-porta-risultati-dalla-regione\/#article","isPartOf":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2019\/07\/15\/trasporto-pubblico-a-cassino-salera-porta-risultati-dalla-regione\/"},"author":{"name":"Redazione","@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/#\/schema\/person\/6d7f0a9120d0c03d0c552e9fdf49ed7d"},"headline":"Trasporto pubblico a Cassino: Salera porta risultati dalla Regione","datePublished":"2019-07-15T17:39:35+00:00","dateModified":"2019-07-16T13:30:17+00:00","mainEntityOfPage":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2019\/07\/15\/trasporto-pubblico-a-cassino-salera-porta-risultati-dalla-regione\/"},"wordCount":502,"commentCount":0,"publisher":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/#organization"},"image":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2019\/07\/15\/trasporto-pubblico-a-cassino-salera-porta-risultati-dalla-regione\/#primaryimage"},"thumbnailUrl":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2019\/07\/salera-regione-lazio-e1563212206883.jpg","keywords":["assessore regionale","Cassino","collegamento","corse","cotral","enzo salera","incontro","Mauro Alessandri","mobilit\u00e0","regione lazio","trasporto","trasporto pubblico locale"],"articleSection":["*PRIMO PIANO*","Attualit\u00e0"],"inLanguage":"it-IT","copyrightYear":"2019","copyrightHolder":{"@id":"https:\/\/www.tunews24.it\/#organization"}},{"@type":"WebPage","@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2019\/07\/15\/trasporto-pubblico-a-cassino-salera-porta-risultati-dalla-regione\/","url":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2019\/07\/15\/trasporto-pubblico-a-cassino-salera-porta-risultati-dalla-regione\/","name":"Trasporto pubblico a Cassino: Salera porta risultati dalla Regione - IlCorriereDellaProvincia.it - News h24 e notizie di approfondimento","isPartOf":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2019\/07\/15\/trasporto-pubblico-a-cassino-salera-porta-risultati-dalla-regione\/#primaryimage"},"image":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2019\/07\/15\/trasporto-pubblico-a-cassino-salera-porta-risultati-dalla-regione\/#primaryimage"},"thumbnailUrl":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2019\/07\/salera-regione-lazio-e1563212206883.jpg","datePublished":"2019-07-15T17:39:35+00:00","dateModified":"2019-07-16T13:30:17+00:00","description":"Il sindaco di Cassino Enzo Salera \u00e8 stato ricevuto oggi dall'assessore regionale alla mobilit\u00e0 Mauro Alessandri e ha ottenuto molte rassicurazioni","breadcrumb":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2019\/07\/15\/trasporto-pubblico-a-cassino-salera-porta-risultati-dalla-regione\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2019\/07\/15\/trasporto-pubblico-a-cassino-salera-porta-risultati-dalla-regione\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2019\/07\/15\/trasporto-pubblico-a-cassino-salera-porta-risultati-dalla-regione\/#primaryimage","url":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2019\/07\/salera-regione-lazio-e1563212206883.jpg","contentUrl":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2019\/07\/salera-regione-lazio-e1563212206883.jpg","width":632,"height":407,"caption":"Il sindaco di Cassino Enzo Salera con l'assessore regionale Mauro Alessandri"},{"@type":"BreadcrumbList","@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2019\/07\/15\/trasporto-pubblico-a-cassino-salera-porta-risultati-dalla-regione\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/"},{"@type":"ListItem","position":2,"name":"Trasporto pubblico a Cassino: Salera porta risultati dalla Regione"}]},{"@type":"WebSite","@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/#website","url":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/","name":"Il Corriere Delle Provincia","description":"IlCorriereDellaProvincia.it, quotidiano web di politica, cronaca, inchiesta, lavoro, scuola, turismo, cultura e spettacolo, economia e finanza, salute e benessere. Approfondimenti e notizie aggiornate con foto e video della provincia di Frosinone ma anche news nazionali, dell\u2019Italia e del Mondo.","publisher":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":["Organization","Place"],"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/#organization","name":"Globalpress s.r.l.","url":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/","logo":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2019\/07\/15\/trasporto-pubblico-a-cassino-salera-porta-risultati-dalla-regione\/#local-main-organization-logo"},"image":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2019\/07\/15\/trasporto-pubblico-a-cassino-salera-porta-risultati-dalla-regione\/#local-main-organization-logo"},"telephone":[],"openingHoursSpecification":[{"@type":"OpeningHoursSpecification","dayOfWeek":["Monday","Tuesday","Wednesday","Thursday","Friday","Saturday","Sunday"],"opens":"09:00","closes":"17:00"}]},{"@type":"Person","@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/#\/schema\/person\/6d7f0a9120d0c03d0c552e9fdf49ed7d","name":"Redazione","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/secure.gravatar.com\/avatar\/a40eeacccdcad861f831dde73317f63a542e738f0dc4b79b9f47062d3d4bd1d2?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/a40eeacccdcad861f831dde73317f63a542e738f0dc4b79b9f47062d3d4bd1d2?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/a40eeacccdcad861f831dde73317f63a542e738f0dc4b79b9f47062d3d4bd1d2?s=96&d=mm&r=g","caption":"Redazione"},"description":"SEGUICI ANCHE SUI SOCIAL Facebook: TuNews24 e TuSport24 Instagram: TuNews24 e TuSport24 Youtube: TuNews24 Telegram: TuNews24 Puoi leggerci anche in formato cartaceo: il settimanale viene pubblicato e distribuito gratuitamente ogni venerd\u00ec in edicole, bar, centri commerciali e svariati esercizi. Ma \u00e8 possibile anche sfogliarlo comodamente online, cliccando su TU NEWS sfogliabile TU NEWS, PASSIONE PER L\u2019INFORMAZIONE","sameAs":["http:\/\/www.tunews24.it","www.facebook.com\/tunews24"],"url":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/author\/senzafirma\/"},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2019\/07\/15\/trasporto-pubblico-a-cassino-salera-porta-risultati-dalla-regione\/#local-main-organization-logo","url":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2022\/11\/cropped-il-corriere-della-provincia-testata-web-scontornata.png","contentUrl":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2022\/11\/cropped-il-corriere-della-provincia-testata-web-scontornata.png","width":2911,"height":717,"caption":"Globalpress s.r.l."}]}},"_links":{"self":[{"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/posts\/14952","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/users\/18"}],"replies":[{"embeddable":true,"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/comments?post=14952"}],"version-history":[{"count":1,"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/posts\/14952\/revisions"}],"predecessor-version":[{"id":14957,"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/posts\/14952\/revisions\/14957"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/media\/14955"}],"wp:attachment":[{"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/media?parent=14952"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/categories?post=14952"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/tags?post=14952"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}